{"id":32800,"date":"2026-04-13T04:00:11","date_gmt":"2026-04-13T07:00:11","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=32800"},"modified":"2025-12-31T19:15:52","modified_gmt":"2025-12-31T22:15:52","slug":"13-de-abril-devocional-diario-charles-spurgeon","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/","title":{"rendered":"13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_raw_html]<\/p>\n<p>JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuc3ByZWFrZXIuY29tJTJGZW1iZWQlMkZwbGF5ZXIlMkZzdGFuZGFyZCUzRmVwaXNvZGVfaWQlM0Q4MjMzODExJTI2YXV0b3BsYXklM0RmYWxzZSUyMiUyMHN0eWxlJTNEJTIyd2lkdGglM0ElMjAxMDAlMjUlM0IlMjBoZWlnaHQlM0ElMjAxMzFweCUzQiUyMiUyMGZyYW1lYm9yZGVyJTNEJTIyMCUyMiUyMHNjcm9sbGluZyUzRCUyMm5vJTIyJTNFJTNDJTJGaWZyYW1lJTNF<\/p>\n<p>[\/vc_raw_html][vc_video link=&#8221;https:\/\/youtu.be\/WOA7Z0nA2AM&#8221;]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Vers\u00edculo do Dia: <\/strong>&#8220;O meu amado \u00e9 para mim um saquitel de mirra.&#8221; (C\u00e2ntico dos C\u00e2nticos 1.13)<\/p>\n<p style=\"text-align: justify;\">A mirra pode muito bem ter sido escolhida como uma figura do Senhor Jesus por causa de sua preciosidade, seu perfume, sua agradabilidade, suas capacidades de cura, preserva\u00e7\u00e3o e desinfec\u00e7\u00e3o, bem como sua liga\u00e7\u00e3o com os sacrif\u00edcios. Ent\u00e3o, por que o Senhor Jesus \u00e9 comparado a um &#8220;saquitel&#8221; de mirra? Primeiramente, por causa da plenitude. O Senhor Jesus n\u00e3o \u00e9 uma pequena quantidade de mirra; \u00e9 uma arca repleta desse tesouro. Ele n\u00e3o \u00e9 um ramo ou uma flor de mirra, e sim todo um feixe de mirra. Em Cristo, existe o suficiente para todas as minhas necessidades; que eu n\u00e3o seja lento para valer-me dele. Nosso amado \u00e9 comparado a um feixe, tamb\u00e9m por conta de sua variedade: pois em Cristo h\u00e1 n\u00e3o somente uma coisa necess\u00e1ria, mas &#8220;Nele, habita, corporalmente, toda a plenitude da Divindade&#8221; (Colossenses 2.9). Tudo o que \u00e9 necess\u00e1rio se encontra em Jesus. Considere os diferentes aspectos do car\u00e1ter de Jesus e voc\u00ea perceber\u00e1 uma diversidade maravilhosa &#8211; Profeta, Sacerdote, Rei, Esposo, Amigo, Pastor. Considere a vida dele, sua morte, ressurrei\u00e7\u00e3o, ascens\u00e3o e segundo advento. Veja-O em suas virtudes &#8211; gentileza, coragem, ren\u00fancia, amor, fidelidade, verdade, justi\u00e7a. Tudo isso \u00e9 saquitel de mirra.<\/p>\n<p style=\"text-align: justify;\">O Senhor Jesus tamb\u00e9m \u00e9 &#8220;um saquitel de mirra&#8221; por causa da preserva\u00e7\u00e3o. Ele n\u00e3o \u00e9 mirra desperdi\u00e7ada, esparramada pelo ch\u00e3o, para ser pisoteada; \u00e9 mirra atada em feixes, para ser guardada em uma arca de tesouro. Temos de valorizar o Senhor Jesus como o nosso melhor tesouro. Devemos manter os pensamentos sobre Ele e o conhecimento dele guardados &#8220;a sete chaves&#8221; para que o diabo n\u00e3o nos roube.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m disso, o Senhor Jesus \u00e9 um saquitel de mirra por causa da especialidade. A figura da mirra sugere uma gra\u00e7a que discrimina e distingue. Desde antes da funda\u00e7\u00e3o do mundo, o Senhor Jesus foi separado para seu povo. Exala o seu perfume somente para aqueles que sabem como ter comunh\u00e3o com Ele e desfrutar de um relacionamento \u00edntimo com Ele. Feliz \u00e9 aquele que pode dizer: &#8220;O meu amado \u00e9 para mim um saquitel de mirra&#8221;.<\/p>\n<p>[\/vc_column_text]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_column_text css=&#8221;.vc_custom_1460401625074{padding-top: 30px !important;padding-right: 30px !important;padding-bottom: 30px !important;padding-left: 30px !important;background-color: #0058af !important;}&#8221;]<\/p>\n<h2 class=\"wpb_heading\" style=\"text-align: left;\"><span style=\"color: #ffffff;\">Assine o Devocional Di\u00e1rio CHARLES SPURGEON<\/span><\/h2>\n<p class=\"wpb_heading\" style=\"text-align: left;\"><span style=\"color: #ffffff;\">Preencha seu\u00a0e-mail abaixo e receba uma notifica\u00e7\u00e3o a cada novo devocional<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<form accept-charset=\"utf-8\" action=\"http:\/\/informativo.ministeriofiel.com.br\/subscribe\" method=\"POST\"><input id=\"email\" style=\"padding: 10px; border: solid 1px #fff; box-shadow: inset 1px 1px 2px 0 #707070; transition: box-shadow 0.3s; font-size: 25px;\" name=\"email\" type=\"text\" \/><input name=\"list\" type=\"hidden\" value=\"Mf892nZkZc5xMpsjOkPU3763uQ\" \/> \u00a0 \u00a0 \u00a0 <input id=\"submit\" style=\"font-size: 15px; padding: 5px 15px; background: #ccc; border: 0 none; cursor: pointer; -webkit-border-radius: 5px; border-radius: 5px;\" name=\"submit\" type=\"submit\" \/><\/form>\n<p>[\/vc_column_text]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_message color=&#8221;alert-danger&#8221; style=&#8221;square_outlined&#8221; el_class=&#8221;creditos_box&#8221;]<\/p>\n<p style=\"text-align: left;\"><strong>Por:<\/strong>\u00a0Charles Spurgeon.\u00a0\u00a9 2016 Minist\u00e9rio Fiel.\u00a0Todos os direitos reservados.<\/p>\n<p>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vers\u00edculo do Dia: &#8220;O meu amado \u00e9 para mim um saquitel de mirra.&#8221; (C\u00e2ntico dos C\u00e2nticos 1.13)<\/p>\n","protected":false},"author":52,"featured_media":31053,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[1],"tags":[374],"class_list":["post-32800","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-sem-categoria","tag-devocional-diario-charles-spurgeon","tema-devocional","tema-devocional-diario-charles-spurgeon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho\" \/>\n<meta property=\"og:description\" content=\"Vers\u00edculo do Dia: &quot;O meu amado \u00e9 para mim um saquitel de mirra.&quot; (C\u00e2ntico dos C\u00e2nticos 1.13)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/13-de-abril-devocional-diario-charles-spurgeon\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/13-de-abril-devocional-diario-charles-spurgeon\\\/\",\"name\":\"13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/13-de-abril-devocional-diario-charles-spurgeon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/13-de-abril-devocional-diario-charles-spurgeon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2026-04-13T07:00:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/13-de-abril-devocional-diario-charles-spurgeon\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/13-de-abril-devocional-diario-charles-spurgeon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/13-de-abril-devocional-diario-charles-spurgeon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/13-de-abril-devocional-diario-charles-spurgeon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/","og_locale":"pt_BR","og_type":"article","og_title":"13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","og_description":"Vers\u00edculo do Dia: \"O meu amado \u00e9 para mim um saquitel de mirra.\" (C\u00e2ntico dos C\u00e2nticos 1.13)","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/","name":"13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","datePublished":"2026-04-13T07:00:11+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/13-de-abril-devocional-diario-charles-spurgeon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"13 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/32800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=32800"}],"version-history":[{"count":1,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/32800\/revisions"}],"predecessor-version":[{"id":62576,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/32800\/revisions\/62576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/31053"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=32800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=32800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=32800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}