{"id":32997,"date":"2026-04-23T04:00:02","date_gmt":"2026-04-23T07:00:02","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=32997"},"modified":"2025-12-31T19:20:26","modified_gmt":"2025-12-31T22:20:26","slug":"23-de-abril-devocional-diario-charles-spurgeon","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/","title":{"rendered":"23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<\/p>\n<div class=\"wpb_wrapper\"><iframe loading=\"lazy\" style=\"width: 100%; height: 131px;\" src=\"https:\/\/www.spreaker.com\/embed\/player\/standard?episode_id=8304827&amp;autoplay=false\" width=\"300\" height=\"150\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/div>\n<p>[vc_video link=&#8221;http:\/\/www.youtube.com\/watch?v=oZXe6CtYDbc&#8221;]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Vers\u00edculo do Dia:<\/strong>&#8220;Em todas estas coisas, por\u00e9m, somos mais que vencedores, por meio daquele que nos amou.&#8221; (Romanos 8.37)<\/p>\n<p style=\"text-align: justify;\">Vamos a Cristo para receber perd\u00e3o e depois, com muita frequ\u00eancia, olhamos para n\u00f3s mesmos em busca de poder para lutarmos contra nossos pecados. Paulo falou as seguintes palavras de repreens\u00e3o: &#8220;\u00d3 g\u00e1latas insensatos! Quem vos fascinou a v\u00f3s outros, ante cujos olhos foi Jesus Cristo exposto como crucificado? Quero apenas saber isto de v\u00f3s: recebeste o Esp\u00edrito pelas obras da lei ou pela prega\u00e7\u00e3o da f\u00e9? Sois assim insensatos que, tendo come\u00e7ado no Esp\u00edrito, estejais, agora, vos aperfei\u00e7oando na carne?&#8221; (G\u00e1latas 3.1-3).<\/p>\n<p style=\"text-align: justify;\">Traga os seus pecados \u00e0 cruz de Cristo, pois somente ali o velho homem pode ser aniquilado (ver Romanos 6.6). Estamos crucificados com Cristo. A \u00fanica arma com a qual lutaremos contra o pecado \u00e9 lan\u00e7a que penetrou o lado de Jesus. Por exemplo, como voc\u00ea pode vencer seu mau g\u00eanio? Talvez voc\u00ea nunca experimentou a solu\u00e7\u00e3o correta de traz\u00ea-lo ao Senhor Jesus. Como foi que obtive a salva\u00e7\u00e3o? Vim a Jesus como eu estava e confiei nEle para salvar-me. \u00c9 deste mesmo modo que eu tenho de mortificar meu temperamento descontrolado; \u00e9 a \u00fanica maneira pela qual eu posso faz\u00ea-lo morrer. Tenho de lev\u00e1-lo \u00e0 cruz e clamar: &#8220;Senhor Jesus, creio que Tu podes me livrar deste temperamento explosivo&#8221;. Esta \u00e9 a \u00fanica maneira de golpear fatalmente esse temperamento. Voc\u00ea \u00e9 cobi\u00e7oso? Sente que o mundo est\u00e1 enla\u00e7ando-o? Voc\u00ea pode lutar contra este mal o quanto desejar, mas voc\u00ea nunca ser\u00e1 liberto dele, exceto pelo sangue de Jesus. Entregue-se a Ele. Diga-Lhe: &#8220;Senhor, eu tenho confiado em Ti, teu nome \u00e9 Jesus pois Tu salvas teu povo dos pecados deles. Senhor, este \u00e9 um de meus pecados; salva-me dele!&#8221; A Lei \u00e9 nada sem Cristo, no que se refere a acabar com o pecado. Seu arrependimento, suas ora\u00e7\u00f5es e l\u00e1grimas &#8211; todos juntos &#8211; nada valem sem Jesus. Ningu\u00e9m, exceto Jesus, pode transformar pecadores ou os santos desamparados em homens bons. Se voc\u00ea quer ser um vencedor, isso tem de acontecer por interm\u00e9dio do Senhor Jesus.<\/p>\n<p>[\/vc_column_text]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_column_text css=&#8221;.vc_custom_1460401292600{padding-top: 30px !important;padding-right: 30px !important;padding-bottom: 30px !important;padding-left: 30px !important;background-color: #0058af !important;}&#8221;]<\/p>\n<h2 class=\"wpb_heading\" style=\"text-align: left;\"><span style=\"color: #ffffff;\">Assine o Devocional Di\u00e1rio CHARLES SPURGEON<\/span><\/h2>\n<p class=\"wpb_heading\" style=\"text-align: left;\"><span style=\"color: #ffffff;\">Preencha seu\u00a0e-mail abaixo e receba uma notifica\u00e7\u00e3o a cada novo devocional<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<form accept-charset=\"utf-8\" action=\"http:\/\/informativo.ministeriofiel.com.br\/subscribe\" method=\"POST\"><input id=\"email\" style=\"padding: 10px; border: solid 1px #fff; box-shadow: inset 1px 1px 2px 0 #707070; transition: box-shadow 0.3s; font-size: 25px;\" name=\"email\" type=\"text\" \/><input name=\"list\" type=\"hidden\" value=\"Mf892nZkZc5xMpsjOkPU3763uQ\" \/> \u00a0 \u00a0 \u00a0 <input id=\"submit\" style=\"font-size: 15px; padding: 5px 15px; background: #ccc; border: 0 none; cursor: pointer; -webkit-border-radius: 5px; border-radius: 5px;\" name=\"submit\" type=\"submit\" \/><\/form>\n<p>[\/vc_column_text]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_message color=&#8221;alert-danger&#8221; style=&#8221;square_outlined&#8221; el_class=&#8221;creditos_box&#8221;]<\/p>\n<p style=\"text-align: left;\"><strong>Por:<\/strong>\u00a0Charles Spurgeon.\u00a0\u00a9 2016 Minist\u00e9rio Fiel.\u00a0Todos os direitos reservados.<\/p>\n<p>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vers\u00edculo do Dia: &#8220;Em todas estas coisas, por\u00e9m, somos mais que vencedores, por meio daquele que nos amou.&#8221; (Romanos 8.37)<\/p>\n","protected":false},"author":52,"featured_media":31053,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[1],"tags":[374],"class_list":["post-32997","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-sem-categoria","tag-devocional-diario-charles-spurgeon","tema-devocional","tema-devocional-diario-charles-spurgeon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho\" \/>\n<meta property=\"og:description\" content=\"Vers\u00edculo do Dia: &quot;Em todas estas coisas, por\u00e9m, somos mais que vencedores, por meio daquele que nos amou.&quot; (Romanos 8.37)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/23-de-abril-devocional-diario-charles-spurgeon\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/23-de-abril-devocional-diario-charles-spurgeon\\\/\",\"name\":\"23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/23-de-abril-devocional-diario-charles-spurgeon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/23-de-abril-devocional-diario-charles-spurgeon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2026-04-23T07:00:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/23-de-abril-devocional-diario-charles-spurgeon\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/23-de-abril-devocional-diario-charles-spurgeon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/23-de-abril-devocional-diario-charles-spurgeon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/23-de-abril-devocional-diario-charles-spurgeon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/","og_locale":"pt_BR","og_type":"article","og_title":"23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","og_description":"Vers\u00edculo do Dia: \"Em todas estas coisas, por\u00e9m, somos mais que vencedores, por meio daquele que nos amou.\" (Romanos 8.37)","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/","name":"23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","datePublished":"2026-04-23T07:00:02+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/23-de-abril-devocional-diario-charles-spurgeon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"23 de Abril \u2013 Devocional Di\u00e1rio CHARLES SPURGEON"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/32997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=32997"}],"version-history":[{"count":1,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/32997\/revisions"}],"predecessor-version":[{"id":62565,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/32997\/revisions\/62565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/31053"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=32997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=32997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=32997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}