{"id":33428,"date":"2026-05-27T04:00:22","date_gmt":"2026-05-27T07:00:22","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=33428"},"modified":"2025-12-31T19:35:53","modified_gmt":"2025-12-31T22:35:53","slug":"27-de-maio-devocional-diario-charles-spurgeon","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/","title":{"rendered":"27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuc3ByZWFrZXIuY29tJTJGZW1iZWQlMkZwbGF5ZXIlMkZzdGFuZGFyZCUzRmVwaXNvZGVfaWQlM0Q4NTg3MzM5JTI2YXV0b3BsYXklM0RmYWxzZSUyMiUyMHN0eWxlJTNEJTIyd2lkdGglM0ElMjAxMDAlMjUlM0IlMjBoZWlnaHQlM0ElMjAxMzFweCUzQiUyMiUyMGZyYW1lYm9yZGVyJTNEJTIyMCUyMiUyMHNjcm9sbGluZyUzRCUyMm5vJTIyJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][vc_video link=&#8221;https:\/\/youtu.be\/By99q-t0_34&#8243;][vc_empty_space height=&#8221;30px&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Vers\u00edculo do Dia:<\/strong> &#8220;Morava Mefibosete em Jerusal\u00e9m, porquanto comia sempre \u00e0 mesa do rei. Ele era coxo de ambos os p\u00e9s.&#8221; (2 Samuel 9.13)<\/p>\n<p style=\"text-align: justify;\">Mefibosete n\u00e3o era um belo ornamento para a mesa de um rei; apesar disso, ele tinha lugar permanente nas refei\u00e7\u00f5es de Davi, porque este podia ver no rosto de Mefibosete os tra\u00e7os do amado J\u00f4natas. Assim como Mefibosete, podemos clamar ao Rei da Gl\u00f3ria: &#8220;Quem \u00e9 teu servo, para teres olhado para um c\u00e3o morto tal como eu?&#8221; (2 Samuel 9.8). Mas Deus nos favorece proporcionando-nos a comunh\u00e3o consigo mesmo, porque v\u00ea em n\u00f3s a semelhan\u00e7a de seu mui amado Jesus. O povo do Senhor \u00e9 querido por causa de Outro. Esse \u00e9 o amor que o Pai tem para com o seu Filho unig\u00eanito.<\/p>\n<p style=\"text-align: justify;\">Por amor a Jesus, Deus exalta os humildes irm\u00e3os dele, retirando-os da insignific\u00e2ncia para o companheirismo celestial, outorgando-lhes suprimento real e posi\u00e7\u00e3o de nobreza. A imperfei\u00e7\u00e3o deles n\u00e3o os impedir\u00e1 de desfrutarem seus privil\u00e9gios. O aleijado \u00e9 herdeiro, do mesmo modo como se pudesse correr \u00e0 semelhan\u00e7a de Asael &#8220;era ligeiro de p\u00e9s, como gazela selvagem&#8221; (2 Samuel 2.18). Nossa justi\u00e7a n\u00e3o manca, embora nossa for\u00e7a possa mancar. A mesa de um rei \u00e9 um esconderijo nobre para pernas coxas, e no banquete do evangelho aprendemos a nos alegrar nas enfermidades porque o poder de Cristo repousa sobre n\u00f3s. Entretanto, defeitos graves podem manchar a personalidade dos mais amados santos de Deus. Os santos cuja f\u00e9 \u00e9 fraca e cujo conhecimento \u00e9 escasso s\u00e3o grandes perdedores. Est\u00e3o expostos a muitos inimigos e n\u00e3o podem seguir o Rei aonde quer que v\u00e1.<\/p>\n<p style=\"text-align: justify;\">Esta enfermidade frequentemente surge a partir de quedas. A m\u00e1 nutri\u00e7\u00e3o no in\u00edcio da vida crist\u00e3 geralmente faz com que os novos convertidos caiam em um tipo de des\u00e2nimo do qual nunca se recuperar\u00e3o, e pecados, em outros casos, faz com que ossos sejam quebrados. Senhor, ajuda o manco a saltar como um veado e satisfaz todo o teu povo com o p\u00e3o da tua mesa.<\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1464870209524{padding-top: 30px !important;padding-right: 30px !important;padding-bottom: 30px !important;padding-left: 30px !important;background-color: #0058af !important;}&#8221;]<\/p>\n<h2 class=\"wpb_heading\" style=\"text-align: left;\"><span style=\"color: #ffffff;\">Assine o Devocional Di\u00e1rio CHARLES SPURGEON<\/span><\/h2>\n<p class=\"wpb_heading\" style=\"text-align: left;\"><span style=\"color: #ffffff;\">Preencha seu\u00a0e-mail abaixo e receba uma notifica\u00e7\u00e3o a cada novo devocional<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<form accept-charset=\"utf-8\" action=\"http:\/\/informativo.ministeriofiel.com.br\/subscribe\" method=\"POST\"><input id=\"email\" style=\"padding: 10px; border: solid 1px #fff; box-shadow: inset 1px 1px 2px 0 #707070; transition: box-shadow 0.3s; font-size: 25px;\" name=\"email\" type=\"text\" \/><input name=\"list\" type=\"hidden\" value=\"Mf892nZkZc5xMpsjOkPU3763uQ\" \/> \u00a0 \u00a0 \u00a0 <input id=\"submit\" style=\"font-size: 15px; padding: 5px 15px; background: #ccc; border: 0 none; cursor: pointer; -webkit-border-radius: 5px; border-radius: 5px;\" name=\"submit\" type=\"submit\" \/><\/form>\n<p>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; el_class=&#8221;creditos_box&#8221;]<\/p>\n<p style=\"text-align: left;\"><strong>Por:<\/strong>\u00a0Charles Spurgeon.\u00a0\u00a9 2016 Minist\u00e9rio Fiel.\u00a0Todos os direitos reservados.<\/p>\n<p>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vers\u00edculo do Dia: &#8220;Morava Mefibosete em Jerusal\u00e9m, porquanto comia sempre \u00e0 mesa do rei. Ele era coxo de ambos os p\u00e9s.&#8221; (2 Samuel 9.13)<\/p>\n","protected":false},"author":52,"featured_media":31053,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[1],"tags":[374],"class_list":["post-33428","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-sem-categoria","tag-devocional-diario-charles-spurgeon","tema-devocional","tema-devocional-diario-charles-spurgeon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho\" \/>\n<meta property=\"og:description\" content=\"Vers\u00edculo do Dia: &quot;Morava Mefibosete em Jerusal\u00e9m, porquanto comia sempre \u00e0 mesa do rei. Ele era coxo de ambos os p\u00e9s.&quot; (2 Samuel 9.13)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/27-de-maio-devocional-diario-charles-spurgeon\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/27-de-maio-devocional-diario-charles-spurgeon\\\/\",\"name\":\"27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/27-de-maio-devocional-diario-charles-spurgeon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/27-de-maio-devocional-diario-charles-spurgeon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2026-05-27T07:00:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/27-de-maio-devocional-diario-charles-spurgeon\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/27-de-maio-devocional-diario-charles-spurgeon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/27-de-maio-devocional-diario-charles-spurgeon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/VE-header.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/27-de-maio-devocional-diario-charles-spurgeon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/","og_locale":"pt_BR","og_type":"article","og_title":"27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","og_description":"Vers\u00edculo do Dia: \"Morava Mefibosete em Jerusal\u00e9m, porquanto comia sempre \u00e0 mesa do rei. Ele era coxo de ambos os p\u00e9s.\" (2 Samuel 9.13)","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/","name":"27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON - Voltemos Ao Evangelho","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","datePublished":"2026-05-27T07:00:22+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/12\/VE-header.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/27-de-maio-devocional-diario-charles-spurgeon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"27 de Maio \u2013 Devocional Di\u00e1rio CHARLES SPURGEON"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/33428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=33428"}],"version-history":[{"count":1,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/33428\/revisions"}],"predecessor-version":[{"id":62531,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/33428\/revisions\/62531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/31053"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=33428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=33428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=33428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}