{"id":53923,"date":"2026-06-04T04:00:45","date_gmt":"2026-06-04T07:00:45","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=53923"},"modified":"2026-01-01T05:34:24","modified_gmt":"2026-01-01T08:34:24","slug":"4-de-junho-devocional-promessas-preciosas","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/","title":{"rendered":"4 de junho &#8211; Excessivamente Precioso"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3aWRnZXQuc3ByZWFrZXIuY29tJTJGcGxheWVyJTNGZXBpc29kZV9pZCUzRDI4ODE4NDc1JTI2dGhlbWUlM0RsaWdodCUyNnBsYXlsaXN0JTNEZmFsc2UlMjZwbGF5bGlzdC1jb250aW51b3VzJTNEZmFsc2UlMjZhdXRvcGxheSUzRGZhbHNlJTI2bGl2ZS1hdXRvcGxheSUzRGZhbHNlJTI2Y2hhcHRlcnMtaW1hZ2UlM0R0cnVlJTI2ZXBpc29kZV9pbWFnZV9wb3NpdGlvbiUzRHJpZ2h0JTI2aGlkZS1sb2dvJTNEdHJ1ZSUyNmhpZGUtbGlrZXMlM0R0cnVlJTI2aGlkZS1jb21tZW50cyUzRHRydWUlMjZoaWRlLXNoYXJpbmclM0R0cnVlJTI2aGlkZS1kb3dubG9hZCUzRHRydWUlMjIlMjB3aWR0aCUzRCUyMjEwMCUyNSUyMiUyMGhlaWdodCUzRCUyMjIwMHB4JTIyJTIwZnJhbWVib3JkZXIlM0QlMjIwJTIyJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_btn title=&#8221;Spotify&#8221; style=&#8221;classic&#8221; shape=&#8221;square&#8221; size=&#8221;sm&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fab fa-spotify&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffiel.in%2Fspotifypromessas||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_btn title=&#8221;Apple&#8221; style=&#8221;classic&#8221; shape=&#8221;square&#8221; size=&#8221;sm&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-podcast&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffiel.in%2Fitunespromessas||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_btn title=&#8221;Google&#8221; style=&#8221;classic&#8221; shape=&#8221;square&#8221; size=&#8221;sm&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fab fa-google&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffiel.in%2Fspotifypromessas||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_btn title=&#8221;Youtube&#8221; style=&#8221;classic&#8221; shape=&#8221;square&#8221; size=&#8221;sm&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fab fa-youtube&#8221; add_icon=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffiel.in%2Fyoutubepromessas||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;30px&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: left;\"><strong>Vers\u00edculo do dia:\u00a0<\/strong><em>Eles ser\u00e3o para mim particular tesouro, naquele dia que prepararei, diz o SENHOR dos Ex\u00e9rcitos. (Malaquias 3.17)<\/em><\/p>\n<p>Est\u00e1 chegando o dia em que ser\u00e3o contadas as j\u00f3ias da coroa de nosso grande Rei, para que seja verificado se elas correspondem ao invent\u00e1rio que o Pai deu ao Filho. \u00d3 minha alma, tu estar\u00e1s entre as j\u00f3ias preciosas de Jesus? Es preciosa para Ele, se Ele \u00e9 precioso para ti; e tu ser\u00e1s dEle, &#8220;naquele dia&#8221;, se hoje Ele te pertence.<\/p>\n<p>Nos dias de Malaquias, os eleitos do Senhor estavam t\u00e3o acostumados a conversar uns com os outros, que o Senhor ouvia suas conversas. Ele apreciava tanto essas conversas, que as registrou em um livro, sim Ele fez um livro dessas conversas e guardou-o em seu escrit\u00f3rio de recorda\u00e7\u00f5es. Estando satisfeito com as conversas dos eleitos, o Senhor tamb\u00e9m sentiu satisfa\u00e7\u00e3o neles. \u00d3 minha alma, p\u00e1ra e pergunta a ti mesma: Se Jesus ouvisse tua conversa, Ele ficaria satisfeito? Tua conversa glorifica-O e edifica os irm\u00e3os em Cristo? Responde, \u00f3 minha alma, e tem certeza de estar respondendo com a verdade.<\/p>\n<p>Que grande honra ser\u00e1 para n\u00f3s, criaturas infelizes, o sermos reputados pelo Senhor como as j\u00f3ias de sua coroa! Dessa honra desfrutar\u00e3o todos os verdadeiros crentes. Jesus n\u00e3o est\u00e1 apenas dizendo: &#8220;Eles s\u00e3o meus&#8221;, mas tamb\u00e9m: &#8220;Eles ser\u00e3o meus&#8221;. Jesus nos comprou, nos buscou, nos trouxe at\u00e9 Ele e nos tem transformado de tal maneira \u00e0 sua imagem, que continuar\u00e1 lutando em nosso favor, com todo o seu poder.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]<strong>Por:<\/strong> Charles Spurgeon. \u00a9 2020 Minist\u00e9rio Fiel. Todos os direitos reservados.<\/p>\n<p><strong>Promova<\/strong> a Promessas Preciosas em seu blog\/site. <a href=\"https:\/\/fiel.in\/promessaspreciosas\">Clique aqui e pegue o c\u00f3digo<\/a>.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vers\u00edculo do dia: Eles ser\u00e3o para mim particular tesouro, naquele dia que prepararei, diz o SENHOR dos Ex\u00e9rcitos. (Malaquias 3.17)<\/p>\n","protected":false},"author":52,"featured_media":52154,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[1],"tags":[2510],"class_list":["post-53923","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-sem-categoria","tag-devocional-promessas-preciosas","tema-devocional","tema-devocional-promessas-preciosas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 de junho - Excessivamente Precioso - Voltemos Ao Evangelho<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 de junho - Excessivamente Precioso - Voltemos Ao Evangelho\" \/>\n<meta property=\"og:description\" content=\"Vers\u00edculo do dia: Eles ser\u00e3o para mim particular tesouro, naquele dia que prepararei, diz o SENHOR dos Ex\u00e9rcitos. (Malaquias 3.17)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Identidade-PromessasPreciosas-e1660313872391.jpg?fit=856%2C365&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/4-de-junho-devocional-promessas-preciosas\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/4-de-junho-devocional-promessas-preciosas\\\/\",\"name\":\"4 de junho - Excessivamente Precioso - Voltemos Ao Evangelho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/4-de-junho-devocional-promessas-preciosas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/4-de-junho-devocional-promessas-preciosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Identidade-PromessasPreciosas-e1660313872391.jpg?fit=856%2C365&ssl=1\",\"datePublished\":\"2026-06-04T07:00:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/4-de-junho-devocional-promessas-preciosas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/4-de-junho-devocional-promessas-preciosas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/4-de-junho-devocional-promessas-preciosas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Identidade-PromessasPreciosas-e1660313872391.jpg?fit=856%2C365&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Identidade-PromessasPreciosas-e1660313872391.jpg?fit=856%2C365&ssl=1\",\"width\":856,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/4-de-junho-devocional-promessas-preciosas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4 de junho &#8211; Excessivamente Precioso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 de junho - Excessivamente Precioso - Voltemos Ao Evangelho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/","og_locale":"pt_BR","og_type":"article","og_title":"4 de junho - Excessivamente Precioso - Voltemos Ao Evangelho","og_description":"Vers\u00edculo do dia: Eles ser\u00e3o para mim particular tesouro, naquele dia que prepararei, diz o SENHOR dos Ex\u00e9rcitos. (Malaquias 3.17)","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":856,"height":365,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Identidade-PromessasPreciosas-e1660313872391.jpg?fit=856%2C365&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/","name":"4 de junho - Excessivamente Precioso - Voltemos Ao Evangelho","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Identidade-PromessasPreciosas-e1660313872391.jpg?fit=856%2C365&ssl=1","datePublished":"2026-06-04T07:00:45+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Identidade-PromessasPreciosas-e1660313872391.jpg?fit=856%2C365&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Identidade-PromessasPreciosas-e1660313872391.jpg?fit=856%2C365&ssl=1","width":856,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/4-de-junho-devocional-promessas-preciosas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"4 de junho &#8211; Excessivamente Precioso"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/53923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=53923"}],"version-history":[{"count":1,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/53923\/revisions"}],"predecessor-version":[{"id":53924,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/53923\/revisions\/53924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/52154"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=53923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=53923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=53923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}