{"id":67576,"date":"2026-03-28T05:00:38","date_gmt":"2026-03-28T08:00:38","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?post_type=devocionais&#038;p=67576"},"modified":"2026-01-01T14:52:42","modified_gmt":"2026-01-01T17:52:42","slug":"uma-dieta-solida-hebreus-5-11-14","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/","title":{"rendered":"Uma dieta s\u00f3lida (Hebreus 5.11-14)"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/Vm8Eof9ut2I?si=9WSdgEXbHRqV-OVl\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: center;\"><a href=\"#_ftn1\" name=\"_ftnref1\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>Porquanto vos tendes tornado tardios em ouvir. [\u2026] Tendes, novamente, necessidade de algu\u00e9m que vos ensine, de novo, quais s\u00e3o os princ\u00edpios elementares dos or\u00e1culos de Deus; assim, vos tornastes como necessitados de leite e n\u00e3o de alimento s\u00f3lido. Ora, todo aquele que se alimenta de leite \u00e9 inexperiente na palavra da justi\u00e7a, porque \u00e9 crian\u00e7a. Mas o alimento s\u00f3lido \u00e9 para os adultos.<\/em> (Hebreus 5.11-14)<\/p>\n<p>&nbsp;<\/p>\n<p>Imagine visitar seu restaurante favorito e perceber que todos os clientes est\u00e3o sentados \u00e0 mesa bebendo leite em mamadeiras gigantes. Que cena bizarra seria! Ainda assim, essa \u00e9 a imagem que o autor de Hebreus ilustrou quando ele exortou os judeus crist\u00e3os de sua \u00e9poca a permanecerem famintos por uma semelhan\u00e7a cada vez maior com Cristo. Ele sabia que muitos j\u00e1 estavam se tornando complacentes em sua f\u00e9. Aqueles que j\u00e1 deveriam ter se tornado mestres precisavam, antes, revisar o maternal da f\u00e9 todo de novo.<\/p>\n<p>A dificuldade para esses crentes em entender os princ\u00edpios b\u00edblicos n\u00e3o resultou de nenhum assunto complexo nem de inabilidade do autor de explicar com clareza. Em vez disso, eles eram deliberadamente tardios em aprender. Quando o autor escreve que eles eram \u201ctardios em ouvir\u201d, a palavra \u201ctardio\u201d \u00e9 a mesma que ele usa posteriormente quando os alerta a n\u00e3o serem \u201cindolentes\u201d (Hb 6.12).<a href=\"#_ftn1\" name=\"_ftnref1\"><sup>[1]<\/sup><\/a> Ali ele exorta seus leitores, em vez de tolerar tal atitude indolente, a serem \u201cimitadores daqueles que, pela f\u00e9 e pela longanimidade, herdam as promessas\u201d.<\/p>\n<p>Se esses crist\u00e3os primitivos tivessem sido almas disciplinadas que estivessem ouvindo cuidadosamente e tentando entender os conceitos b\u00edblicos e simplesmente tendo dificuldade nisso, o autor provavelmente n\u00e3o teria sido t\u00e3o duro com eles. Mas esse n\u00e3o era o caso. Ele teve de repreender membros da igreja que deveriam estar recebendo ardentemente a verdade, mas que haviam se tornado ap\u00e1ticos. Seu entusiasmo diminuiu. Eles pararam de prestar aten\u00e7\u00e3o. Como resultado, eles n\u00e3o entendiam o que os impedia de serem ainda mais transformados pela verdade de Deus.<\/p>\n<p>Se n\u00e3o formos vigilantes, o mesmo pode acontecer conosco. N\u00e3o podemos nos sustentar com uma dieta de cereal de flocos de arroz, torradas e leite. N\u00e3o h\u00e1 problema em gostar de leite. Est\u00e1 tudo bem em t\u00ea-lo como parte de nossa dieta. Mas n\u00e3o est\u00e1 nada bem bebermos leite como a totalidade da nossa alimenta\u00e7\u00e3o. Isso \u00e9 algo para os beb\u00eas, e n\u00f3s n\u00e3o devemos permanecer como beb\u00eas. Precisamos aprender a comer alimentos mais nutritivos e expandir nosso paladar.<\/p>\n<p>Torne seu objetivo continuamente \u201c[crescer] na gra\u00e7a e no conhecimento de nosso Senhor\u201d (2Pe 3.18), a fim de que voc\u00ea possa lidar com as implica\u00e7\u00f5es da genu\u00edna experi\u00eancia crist\u00e3. N\u00e3o se torne algu\u00e9m que ouve as Boas Novas do Evangelho sendo proclamadas e diz em sua mente: \u201cAh, eu j\u00e1 sei isso. Posso parar de ouvir agora.\u201d N\u00e3o se torne algu\u00e9m que considera o serm\u00e3o da manh\u00e3 de domingo um alimento espiritual suficiente para durar a semana inteira. N\u00e3o se torne algu\u00e9m que fica chapinhando no raso e nunca faz um esfor\u00e7o para mergulhar bem fundo nas riquezas da Palavra de Deus. Seja algu\u00e9m que ama o Evangelho e que, pela gra\u00e7a de Deus, nunca se cansa de ouvi-lo; e algu\u00e9m que ama a Palavra de Deus \u2014 ama beber dela, mastig\u00e1-la e \u00e9 impulsionado pela sua verdade vez ap\u00f3s vez, \u00e0 medida que voc\u00ea se torna mais e mais como seu grandioso assunto, nosso Senhor e Salvador.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Aprofunde sua devo\u00e7\u00e3o a Deus em <a href=\"http:\/\/fiel.in\/devocional\">fiel.in\/devocional<\/a><\/p>\n<hr \/>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><sup>[1]<\/sup><\/a> N.T.: Do grego <em>n\u014dthroi<\/em>.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devocional Verdade para a vida para 28 de mar\u00e7o<\/p>\n","protected":false},"author":25,"featured_media":66220,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[3773],"tags":[3715,3843],"class_list":["post-67576","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-devocional-diario","tag-devocional-verdade-para-a-vida","tag-truth-for-life","tema-devocional-verdade-para-a-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uma dieta s\u00f3lida (Hebreus 5.11-14) - Devocional Verdade para vida<\/title>\n<meta name=\"description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Hebreus 5.11-14.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uma dieta s\u00f3lida (Hebreus 5.11-14) - Devocional Verdade para vida\" \/>\n<meta property=\"og:description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Hebreus 5.11-14.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/uma-dieta-solida-hebreus-5-11-14\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/uma-dieta-solida-hebreus-5-11-14\\\/\",\"name\":\"Uma dieta s\u00f3lida (Hebreus 5.11-14) - Devocional Verdade para vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/uma-dieta-solida-hebreus-5-11-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/uma-dieta-solida-hebreus-5-11-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2026-03-28T08:00:38+00:00\",\"description\":\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Hebreus 5.11-14.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/uma-dieta-solida-hebreus-5-11-14\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/uma-dieta-solida-hebreus-5-11-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/uma-dieta-solida-hebreus-5-11-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/uma-dieta-solida-hebreus-5-11-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Uma dieta s\u00f3lida (Hebreus 5.11-14)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uma dieta s\u00f3lida (Hebreus 5.11-14) - Devocional Verdade para vida","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Hebreus 5.11-14.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/","og_locale":"pt_BR","og_type":"article","og_title":"Uma dieta s\u00f3lida (Hebreus 5.11-14) - Devocional Verdade para vida","og_description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Hebreus 5.11-14.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":837,"height":470,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/","name":"Uma dieta s\u00f3lida (Hebreus 5.11-14) - Devocional Verdade para vida","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","datePublished":"2026-03-28T08:00:38+00:00","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Hebreus 5.11-14.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","width":837,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/uma-dieta-solida-hebreus-5-11-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"Uma dieta s\u00f3lida (Hebreus 5.11-14)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/67576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=67576"}],"version-history":[{"count":1,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/67576\/revisions"}],"predecessor-version":[{"id":67577,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/67576\/revisions\/67577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/66220"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=67576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=67576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=67576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}