{"id":68039,"date":"2026-05-19T04:30:53","date_gmt":"2026-05-19T07:30:53","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?post_type=devocionais&#038;p=68039"},"modified":"2026-01-01T18:14:43","modified_gmt":"2026-01-01T21:14:43","slug":"recebido-a-sua-mesa-rute-2-14","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/","title":{"rendered":"Recebido \u00e0 sua mesa (Rute 2.14)"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/Whq9wZq5yn4?si=J1MYiUo_FDGF5FAD\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: center;\"><em>\u00c0 hora de comer, Boaz lhe disse: Achega-te para aqui, e come do p\u00e3o, e molha no vinho o teu bocado. Ela se assentou ao lado dos segadores, e ele lhe deu gr\u00e3os tostados de cereais; ela comeu e se fartou, e ainda lhe sobejou.<\/em> (Rt 2.14)<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Voc\u00ea e eu somos chamados a ser pontes que atravessam a fenda entre a experi\u00eancia de isolamento e uma vida de aceita\u00e7\u00e3o divina.<\/p>\n<p style=\"text-align: justify;\">Para Rute, Boaz era essa ponte. No meio de um longo dia de labuta, Boaz convidou seus colegas de trabalho para desfrutar de uma refei\u00e7\u00e3o. Ele tamb\u00e9m convidou Rute para comer entre os ceifeiros. \u00c9 f\u00e1cil n\u00e3o entender o significado disso. Rute era uma estranha, uma estrangeira e uma mulher. As a\u00e7\u00f5es de Boaz foram inesperadas e culturalmente contraintuitivas. Elas se assemelhavam \u00e0s de Cristo.<\/p>\n<p style=\"text-align: justify;\">Boaz \u00e9 um exemplo de algu\u00e9m cujas a\u00e7\u00f5es foram a ponte entre o isolamento e a aceita\u00e7\u00e3o que Deus oferece. Como moabita, Rute teria parecido e agido de maneira diferente das de Bel\u00e9m. Al\u00e9m disso, o status de vi\u00fava de Rute e Noemi as teria isolado em muitos c\u00edrculos sociais. Contudo, porque o amor de Deus havia enchido seu cora\u00e7\u00e3o, Boaz desconsiderou qualquer ind\u00edcio de preconceito que pudesse ter tido e acolheu Rute \u00e0 sua mesa.<\/p>\n<p style=\"text-align: justify;\">Boaz n\u00e3o parou ao garantir que Rute se sentisse confort\u00e1vel apenas com suas a\u00e7\u00f5es. N\u00e3o; ele tamb\u00e9m se certificou de que os outros trabalhadores tratassem Rute com aceita\u00e7\u00e3o e bondade, e n\u00e3o a deixou passar dificuldade enquanto ela aprendia as habilidades de seu novo of\u00edcio (Rt 2.15-16). Ele foi muito al\u00e9m para prover e cuidar dela.<\/p>\n<p style=\"text-align: justify;\">Fazemos o mesmo com descrentes, novos crentes ou visitantes de nossas igrejas? Um crist\u00e3o \u00e9, por defini\u00e7\u00e3o, um destinat\u00e1rio do amor pactual de Deus. Portanto, um crist\u00e3o deve ser o primeiro a incluir o p\u00e1ria \u2014 o crist\u00e3o \u00e9 o primeiro a dizer: \u201cVoc\u00ea \u00e9 bem-vindo aqui! Que bom que voc\u00ea est\u00e1 aqui. Por favor, participe! Quer se juntar a mim?\u201d Somos chamados a enfrentar a mar\u00e9 muito comum da exclusividade ego\u00edsta e o h\u00e1bito igualmente pernicioso de passar tempo apenas com aqueles que s\u00e3o como n\u00f3s e dar boas-vindas apenas a estes.<\/p>\n<p style=\"text-align: justify;\">Encontramos a bravura necess\u00e1ria para ser uma ponte e n\u00e3o uma barreira quando olhamos para nossa pr\u00f3pria aceita\u00e7\u00e3o por Deus em Cristo. A inclus\u00e3o de Rute por Boaz \u2014 apesar de sua ra\u00e7a, posi\u00e7\u00e3o social e falta de experi\u00eancia de trabalho \u2014 aponta para a hist\u00f3ria eterna do maior acolhimento de Deus. O Deus santo chamou atrav\u00e9s das divis\u00f5es entre judeus e gentios, escravizados e livres, dizendo aos pecadores: \u201cOlhai para mim e sereis salvos, v\u00f3s, todos os confins da terra\u201d (Is 45.22). Devemos voltar nosso olhar novamente para a cruz, pois l\u00e1 aprendemos o que significa ser amado e acolhido por Deus. S\u00f3 ent\u00e3o seremos capazes de amar e acolher verdadeiramente os outros.<\/p>\n<p style=\"text-align: justify;\">Ent\u00e3o, veja como Deus em Cristo recebe voc\u00ea \u00e0 sua mesa e, em seguida, pergunte a si mesmo: \u201cComo o Esp\u00edrito de Deus est\u00e1 me levando a superar uma barreira? Quem ele est\u00e1 me chamando a receber \u00e0 minha mesa?\u201d<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><strong><em>Tenha uma experi\u00eancia ainda mais enriquecedora em sua vida adquirindo este devocional em formato de livro\u00a0 \u2014\u00a0<a class=\"external\" href=\"https:\/\/www.editorafiel.com.br\/alistair-begg\/devocional-verdade-para-a-vida\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI<\/a>\u00a0e adquira j\u00e1 o seu!<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure class=\"wp-caption aligncenter\" style=\"width: 298px;\"><a class=\"external\" href=\"https:\/\/www.editorafiel.com.br\/alistair-begg\/devocional-verdade-para-a-vida\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/i0.wp.com\/images.tcdn.com.br\/img\/img_prod\/1221753\/devocional_verdade_para_a_vida_1227_2_f97ddd6144f4a8aff564562ab4a574d2.png?resize=412%2C648&amp;ssl=1\" alt=\"\" width=\"298\" height=\"469\" \/><\/a><\/figure>\n<hr \/>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devocional Verdade para a vida para 19 de maio<\/p>\n","protected":false},"author":25,"featured_media":66220,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[3773],"tags":[3715,3843],"class_list":["post-68039","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-devocional-diario","tag-devocional-verdade-para-a-vida","tag-truth-for-life","tema-devocional-verdade-para-a-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recebido \u00e0 sua mesa (Rute 2.14) - Devocional Verdade para vida<\/title>\n<meta name=\"description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Rute 2.14.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recebido \u00e0 sua mesa (Rute 2.14) - Devocional Verdade para vida\" \/>\n<meta property=\"og:description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Rute 2.14.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/recebido-a-sua-mesa-rute-2-14\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/recebido-a-sua-mesa-rute-2-14\\\/\",\"name\":\"Recebido \u00e0 sua mesa (Rute 2.14) - Devocional Verdade para vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/recebido-a-sua-mesa-rute-2-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/recebido-a-sua-mesa-rute-2-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2026-05-19T07:30:53+00:00\",\"description\":\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Rute 2.14.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/recebido-a-sua-mesa-rute-2-14\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/recebido-a-sua-mesa-rute-2-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/recebido-a-sua-mesa-rute-2-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/recebido-a-sua-mesa-rute-2-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recebido \u00e0 sua mesa (Rute 2.14)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recebido \u00e0 sua mesa (Rute 2.14) - Devocional Verdade para vida","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Rute 2.14.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/","og_locale":"pt_BR","og_type":"article","og_title":"Recebido \u00e0 sua mesa (Rute 2.14) - Devocional Verdade para vida","og_description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Rute 2.14.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":837,"height":470,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/","name":"Recebido \u00e0 sua mesa (Rute 2.14) - Devocional Verdade para vida","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","datePublished":"2026-05-19T07:30:53+00:00","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Rute 2.14.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","width":837,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/recebido-a-sua-mesa-rute-2-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"Recebido \u00e0 sua mesa (Rute 2.14)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=68039"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68039\/revisions"}],"predecessor-version":[{"id":68141,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68039\/revisions\/68141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/66220"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=68039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=68039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=68039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}