{"id":68091,"date":"2026-05-24T04:30:11","date_gmt":"2026-05-24T07:30:11","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?post_type=devocionais&#038;p=68091"},"modified":"2026-01-01T18:17:05","modified_gmt":"2026-01-01T21:17:05","slug":"lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/","title":{"rendered":"Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7)"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/ZetjHfOoOl0?si=CBR7du87-EV8F9ro\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>Humilhai-vos, portanto, sob a poderosa m\u00e3o de Deus, para que ele, em tempo oportuno, vos exalte, lan\u00e7ando sobre ele toda a vossa ansiedade, porque ele tem cuidado de v\u00f3s.<\/em> (1Pe 5.6-7)<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">A ansiedade pode aumentar \u00e0s vezes, quando menos esperamos, e rapidamente nos sobrecarregar. Ou pode ocupar uma resid\u00eancia indesejada e aparentemente permanente em nossa vida. Poucas pessoas n\u00e3o a experimentam; pode assumir rostos diferentes e pode ser impelida por circunst\u00e2ncias diferentes, mas o problema em si \u00e9 notavelmente comum.<\/p>\n<p style=\"text-align: justify;\">Quando enfrentamos a ansiedade, muitas vezes tentamos ignor\u00e1-la distraindo a mente: \u201cDeixe-me ouvir m\u00fasica. Deixe-me dar uma volta. Deixe-me correr alguns quil\u00f4metros. Deixe-me fazer <em>alguma coisa\u2026<\/em> Apenas me deixe fugir!\u201d<\/p>\n<p style=\"text-align: justify;\">Observe, por\u00e9m, que, neste vers\u00edculo, Pedro n\u00e3o diz que devemos negar, ignorar ou fugir da ansiedade. Em vez disso, devemos \u201c[<em>lan\u00e7ar<\/em>] sobre ele toda a [nossa] ansiedade\u201d. A palavra grega para \u201clan\u00e7ar\u201d aqui \u00e9 uma palavra de a\u00e7\u00e3o decisiva e en\u00e9rgica. Pode ser usada para descrever o descarte de um saco de lixo. N\u00e3o nos esfor\u00e7amos muito para mov\u00ea-lo; simplesmente o pegamos e jogamos na lixeira. De igual forma, em vez de passar por nossos dias pressionados pelo fardo da ansiedade, devemos lan\u00e7\u00e1-lo, arremess\u00e1-lo, sobre o Senhor.<\/p>\n<p style=\"text-align: justify;\">Fazer isso exige que desistamos de nosso orgulho \u2014 nosso desejo de controlar e triunfar sobre as circunst\u00e2ncias. Ser humilde \u00e9 o que nos permite entregar nossas preocupa\u00e7\u00f5es a Deus: a presen\u00e7a da humildade leva \u00e0 aus\u00eancia da ansiedade. Quando tentamos lidar com as coisas em nossas pr\u00f3prias m\u00e3os atrav\u00e9s de muita preocupa\u00e7\u00e3o, indicamos uma aus\u00eancia de humildade; estamos mais preocupados com n\u00f3s mesmos do que com nosso Pai celestial, ou estamos mais determinados a navegar nosso pr\u00f3prio curso do que a deixar isso com ele.<\/p>\n<p style=\"text-align: justify;\">Sempre haver\u00e1 uma circunst\u00e2ncia que pode nos deixar ansiosos. Pedro n\u00e3o se refere a nenhuma circunst\u00e2ncia espec\u00edfica; em vez disso, ele aborda a ansiedade produzida pelas circunst\u00e2ncias. Nossa ansiedade em si \u00e9 o que lan\u00e7amos sobre o Senhor, fazendo exatamente o que a B\u00edblia manda fazer: humilhar-nos sob a m\u00e3o de Deus, dizendo \u201cMeu Pai sabe o que \u00e9 melhor. Ele cuida de mim melhor do que eu posso cuidar de mim mesmo.\u201d Quando as preocupa\u00e7\u00f5es nos sobrecarregam, podemos nos recusar a ser sobrecarregados por elas, lembrando-nos da disposi\u00e7\u00e3o do Senhor de ajudar.<\/p>\n<p style=\"text-align: justify;\">Voc\u00ea pode estar passando por dificuldades hoje, imaginando como chegar\u00e1 ao dia seguinte. Talvez tenha passado muito tempo desde que voc\u00ea se ajoelhou ao lado de sua cama e realmente lan\u00e7ou seu fardo sobre o \u00fanico que \u00e9 capaz de carreg\u00e1-lo, dizendo: \u201cDeus, n\u00e3o posso viver minha vida com esse fardo nas costas. Toma-o. \u00c9 teu.\u201d<\/p>\n<p style=\"text-align: justify;\">Se essa pessoa \u00e9 voc\u00ea, n\u00e3o hesite mais. Lance suas preocupa\u00e7\u00f5es nos bra\u00e7os amorosos de seu Pai celestial e experimente a liberdade e a paz que somente ele pode prover.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftn1\" name=\"_ftnref1\"><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><strong><em>Tenha uma experi\u00eancia ainda mais enriquecedora em sua vida adquirindo este devocional em formato de livro\u00a0 \u2014\u00a0<a class=\"external\" href=\"https:\/\/www.editorafiel.com.br\/alistair-begg\/devocional-verdade-para-a-vida\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI<\/a>\u00a0e adquira j\u00e1 o seu!<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure class=\"wp-caption aligncenter\" style=\"width: 298px;\"><a class=\"external\" href=\"https:\/\/www.editorafiel.com.br\/alistair-begg\/devocional-verdade-para-a-vida\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/i0.wp.com\/images.tcdn.com.br\/img\/img_prod\/1221753\/devocional_verdade_para_a_vida_1227_2_f97ddd6144f4a8aff564562ab4a574d2.png?resize=412%2C648&amp;ssl=1\" alt=\"\" width=\"298\" height=\"469\" \/><\/a><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devocional Verdade para a vida para 24 de maio<\/p>\n","protected":false},"author":25,"featured_media":66220,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[3773],"tags":[3715,3843],"class_list":["post-68091","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-devocional-diario","tag-devocional-verdade-para-a-vida","tag-truth-for-life","tema-devocional-verdade-para-a-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7) - Devocional Verdade para vida<\/title>\n<meta name=\"description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em 1 Pedro 5.6-7.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7) - Devocional Verdade para vida\" \/>\n<meta property=\"og:description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em 1 Pedro 5.6-7.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\\\/\",\"name\":\"Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7) - Devocional Verdade para vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2026-05-24T07:30:11+00:00\",\"description\":\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em 1 Pedro 5.6-7.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7) - Devocional Verdade para vida","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em 1 Pedro 5.6-7.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/","og_locale":"pt_BR","og_type":"article","og_title":"Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7) - Devocional Verdade para vida","og_description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em 1 Pedro 5.6-7.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":837,"height":470,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/","name":"Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7) - Devocional Verdade para vida","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","datePublished":"2026-05-24T07:30:11+00:00","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em 1 Pedro 5.6-7.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","width":837,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/lancando-todas-as-suas-preocupacoes-1-pedro-5-6-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"Lan\u00e7ando todas as suas preocupa\u00e7\u00f5es (1 Pedro 5.6-7)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=68091"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68091\/revisions"}],"predecessor-version":[{"id":68136,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68091\/revisions\/68136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/66220"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=68091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=68091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=68091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}