{"id":68267,"date":"2026-06-15T04:30:30","date_gmt":"2026-06-15T07:30:30","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?post_type=devocionais&#038;p=68267"},"modified":"2026-01-01T18:27:23","modified_gmt":"2026-01-01T21:27:23","slug":"a-cidade-do-homem-apocalipse-18-4-5","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/","title":{"rendered":"A cidade do homem (Apocalipse 18.4-5)"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/xjCuzLS9HKk?si=bVc-aMC4A18GO5A-\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">Retirai-vos dela,\u00a0povo meu, para n\u00e3o serdes c\u00famplices em seus pecados e para n\u00e3o participardes dos seus flagelos;\u00a0porque os seus pecados se acumularam at\u00e9 ao c\u00e9u, e Deus se lembrou dos atos in\u00edquos que ela praticou.<\/span><\/i><span style=\"font-weight: 400;\"> (Ap 18.4-5)<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">N\u00e3o devemos ficar surpresos ou alarmados quando os crist\u00e3os enfrentam oposi\u00e7\u00e3o cont\u00ednua. A disposi\u00e7\u00e3o natural da humanidade \u00e9 de desafio orgulhoso a Deus e, portanto, contra o seu povo. O homem, sobre o fundamento inst\u00e1vel de seu orgulho, \u201cedifica uma cidade\u201d (para usar a linguagem pict\u00f3rica do Apocalipse) e arquiteta um estilo de vida que se op\u00f5e aos caminhos de Deus.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A humanidade tem feito isso desde a Queda. O primeiro projeto de constru\u00e7\u00e3o sem Deus foi na plan\u00edcie de Sinar, em um lugar chamado Babel (Gn 11.1-9) \u2014 o lugar que mais tarde recebeu o nome de Babil\u00f4nia e para o qual o povo de Deus foi exilado. Apocalipse 18, portanto, refere-se \u00e0 cidade do homem, constru\u00edda em desafio a Deus, como a Babil\u00f4nia; e a Babil\u00f4nia \u00e9 ent\u00e3o personificada como uma prostituta, seduzindo as pessoas a cometer adult\u00e9rio espiritual. Atraente e sedutora, a cidade do homem \u00e9 eficaz em afastar muitos de Deus. \u00c9 \u201ca grande cidade que domina sobre os reis da terra\u201d (17.18), e sua influ\u00eancia \u00e9 significativa e destrutiva.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Como, ent\u00e3o, os cidad\u00e3os da cidade de Deus devem responder a esse rival mundano? Devemos estar no mundo, mas n\u00e3o ser do mundo. Em outras palavras, devemos ser sal, que tem um sabor distinto e uma qualidade conservadora; e devemos ser luz, que exp\u00f5e o que as trevas encobrem, mas que tamb\u00e9m guia os outros ao longo do caminho para a seguran\u00e7a (Mt 5.13-16). Devemos viver na tens\u00e3o de ser membros deste mundo, mas n\u00e3o pertencer aqui: residir aqui, mas tamb\u00e9m estarmos separados daqueles cujos cora\u00e7\u00f5es e mentes est\u00e3o contra Deus. Os pecados da cidade do homem n\u00e3o devem caracterizar o crente, diz Jo\u00e3o, para n\u00e3o \u201c[participarmos] dos seus flagelos\u201d. Se nos rendermos \u00e0 sedu\u00e7\u00e3o da Babil\u00f4nia, provaremos que nossa identidade nunca foi verdadeiramente a de um cidad\u00e3o do Reino de Deus.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Aqueles que seguem a Cristo devem estar comprometidos com a verdade da B\u00edblia. O cristianismo \u00e9 mais do que um c\u00f3digo moral. \u00c9 mais do que uma estrutura para viver ou um m\u00e9todo para melhorar a vida de algu\u00e9m. Onde est\u00e1 a cruz nisso? O cristianismo \u00e9 distinto de todas as outras religi\u00f5es, pois nos apegamos \u00e0 morte de Jesus na cruz como nosso meio de reconcilia\u00e7\u00e3o com Deus. J\u00e1 estivemos mortos em nossos pecados, merecedores da ira e do julgamento de Deus \u2014 por\u00e9m ele nos redimiu por meio da vida perfeita de Cristo, de sua morte expiat\u00f3ria e ressurrei\u00e7\u00e3o vitoriosa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Por enquanto, o mundo continua como sempre foi. Mas um dia Cristo voltar\u00e1 e silenciar\u00e1 todos os falsos profetas, todos os cidad\u00e3os da Babil\u00f4nia e at\u00e9 mesmo o pr\u00f3prio diabo. Podemos ver a igreja pressionada, ridicularizada, contrariada por meio de legisla\u00e7\u00e3o e perseguida. O mundo nos ver\u00e1 como fracos, do lado errado da hist\u00f3ria, e indignos de respeito ou aceita\u00e7\u00e3o. Contudo, temos esperan\u00e7a nesta afirma\u00e7\u00e3o triunfante: nem as portas da Babil\u00f4nia nem as portas do inferno prevalecer\u00e3o, porque Cristo edificar\u00e1 e guardar\u00e1 sua igreja (Mt 16.18). Ent\u00e3o, por ora, enquanto voc\u00ea vive na Babil\u00f4nia, qual de seus pecados voc\u00ea acha mais atraente? De que maneira voc\u00ea est\u00e1 mais tentado a viver como se esta cidade fosse tudo o que existe? E que oportunidades voc\u00ea recebeu para ser sal e luz para aqueles ao seu redor? Certifique-se de resistir \u00e0 cidade do homem e de chamar outros para a cidade de Deus.<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftn1\" name=\"_ftnref1\"><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><strong><em>Tenha uma experi\u00eancia ainda mais enriquecedora em sua vida adquirindo este devocional em formato de livro\u00a0 \u2014\u00a0<a class=\"external\" href=\"https:\/\/www.editorafiel.com.br\/alistair-begg\/devocional-verdade-para-a-vida\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI<\/a>\u00a0e adquira j\u00e1 o seu!<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure class=\"wp-caption aligncenter\" style=\"width: 298px;\"><a class=\"external\" href=\"https:\/\/www.editorafiel.com.br\/alistair-begg\/devocional-verdade-para-a-vida\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/i0.wp.com\/images.tcdn.com.br\/img\/img_prod\/1221753\/devocional_verdade_para_a_vida_1227_2_f97ddd6144f4a8aff564562ab4a574d2.png?resize=412%2C648&amp;ssl=1\" alt=\"\" width=\"298\" height=\"469\" \/><\/a><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devocional Verdade para a vida para 15 de junho<\/p>\n","protected":false},"author":25,"featured_media":66220,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[3773],"tags":[3715,3843],"class_list":["post-68267","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-devocional-diario","tag-devocional-verdade-para-a-vida","tag-truth-for-life","tema-devocional-verdade-para-a-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A cidade do homem (Apocalipse 18.4-5) - Devocional Verdade para vida<\/title>\n<meta name=\"description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Apocalipse 18.4-5.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A cidade do homem (Apocalipse 18.4-5) - Devocional Verdade para vida\" \/>\n<meta property=\"og:description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Apocalipse 18.4-5.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/a-cidade-do-homem-apocalipse-18-4-5\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/a-cidade-do-homem-apocalipse-18-4-5\\\/\",\"name\":\"A cidade do homem (Apocalipse 18.4-5) - Devocional Verdade para vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/a-cidade-do-homem-apocalipse-18-4-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/a-cidade-do-homem-apocalipse-18-4-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2026-06-15T07:30:30+00:00\",\"description\":\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Apocalipse 18.4-5.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/a-cidade-do-homem-apocalipse-18-4-5\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/a-cidade-do-homem-apocalipse-18-4-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/a-cidade-do-homem-apocalipse-18-4-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/a-cidade-do-homem-apocalipse-18-4-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A cidade do homem (Apocalipse 18.4-5)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A cidade do homem (Apocalipse 18.4-5) - Devocional Verdade para vida","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Apocalipse 18.4-5.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/","og_locale":"pt_BR","og_type":"article","og_title":"A cidade do homem (Apocalipse 18.4-5) - Devocional Verdade para vida","og_description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Apocalipse 18.4-5.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":837,"height":470,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/","name":"A cidade do homem (Apocalipse 18.4-5) - Devocional Verdade para vida","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","datePublished":"2026-06-15T07:30:30+00:00","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Apocalipse 18.4-5.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","width":837,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/a-cidade-do-homem-apocalipse-18-4-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"A cidade do homem (Apocalipse 18.4-5)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=68267"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68267\/revisions"}],"predecessor-version":[{"id":68383,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68267\/revisions\/68383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/66220"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=68267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=68267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=68267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}