{"id":68390,"date":"2026-06-30T04:30:31","date_gmt":"2026-06-30T07:30:31","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?post_type=devocionais&#038;p=68390"},"modified":"2026-01-01T18:31:28","modified_gmt":"2026-01-01T21:31:28","slug":"vencendo-o-mal-romanos-12-21","status":"publish","type":"devocionais","link":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/","title":{"rendered":"Vencendo o mal (Romanos 12.21)"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/zPtjVNCfxXU?si=7XuhKdi3H8gWfobD\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>N\u00e3o te deixes vencer do mal, mas vence o mal com o bem.<\/em> (Rm 12.21)<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Enquanto estudava na Universidade de Cambridge na d\u00e9cada de 40, uma jovem se tornou secret\u00e1ria do Partido Comunista. O inverno de 1946\u201347 foi fenomenalmente severo, fazendo com que os canos de \u00e1gua congelassem parcialmente e, portanto, resultando em escassez de \u00e1gua. As alunas estavam limitadas a um banho por semana e, enquanto esperavam na longa fila, havia muita murmura\u00e7\u00e3o e disputas por posi\u00e7\u00e3o \u2014 inclusive por parte da Secret\u00e1ria do Partido Comunista.<\/p>\n<p style=\"text-align: justify;\">Uma das garotas que tinha acesso mais direto ao banheiro era crist\u00e3. A estudante comunista notou, com o tempo, que essa garota nunca reivindicava seus direitos e respondia gentilmente ao ego\u00edsmo dos outros. A crist\u00e3 estava praticando e vivendo o que a jovem comunista afirmava acreditar, mas n\u00e3o fazia. Essa observa\u00e7\u00e3o levou a uma conversa, uma convers\u00e3o \u2014 e, enfim, a uma nova mission\u00e1ria no Extremo Oriente.<\/p>\n<p style=\"text-align: justify;\">Sempre que tentamos derrotar o mal por nossas pr\u00f3prias palavras e a\u00e7\u00f5es malignas, somos consumidos. O mal n\u00e3o pode ser superado por uma for\u00e7a igualmente maligna. O mal \u00e9 duplicado em vez de anulado. Se perdermos o controle de n\u00f3s mesmos ao nos envolvermos com um inimigo, ent\u00e3o fomos derrotados n\u00e3o por essa pessoa, mas pelo Maligno. Somos n\u00f3s que fomos vencidos e perdemos a oportunidade de fazer o que \u00e9 certo aos olhos de Deus.<\/p>\n<p style=\"text-align: justify;\">Vencer o mal \u00e9 uma no\u00e7\u00e3o popular em nossa cultura. Ouvimos isso em m\u00fasicas e lemas motivacionais. Muitas vezes, a ideia \u00e9 que, se pudermos ao menos \u201cficar juntos\u201d, teremos sucesso em derrotar os males que nos atormentam. \u00c9 uma ideia nobre, mas n\u00e3o tem o poder necess\u00e1rio. <em>N\u00e3o podemos<\/em> vencer o mal por conta pr\u00f3pria; simplesmente n\u00e3o funcionar\u00e1. \u201cSomos mais que vencedores\u201d <em>apenas<\/em> \u201cpor meio daquele que nos amou\u201d (Rm 8.37). O poder de Deus por seu Esp\u00edrito e sua Palavra nos d\u00e1 tanto o \u00edmpeto quanto a for\u00e7a de que precisamos para triunfar.<\/p>\n<p style=\"text-align: justify;\">Este \u00e9 o caminho que Jesus tomou. Ele n\u00e3o executou vingan\u00e7a com suas pr\u00f3prias m\u00e3os, mas se confiou \u00e0s m\u00e3os do Pai. Cristo foi para a cruz, onde o amor triunfou sobre o mal. Ao escolhermos ser gentis, fazer o bem e andar no caminho da cruz, experimentaremos o poder de Deus operando em n\u00f3s para vencer o mal com a bondade de seu amor.<\/p>\n<p style=\"text-align: justify;\">O escritor de hinos Charles Tindley nos lembrou dessa verdade quando escreveu:<\/p>\n<p style=\"text-align: center;\"><em>Com a Palavra de Deus como uma espada minha,<\/em><\/p>\n<p style=\"text-align: center;\"><em>Eu vencerei um dia [\u2026]<\/em><\/p>\n<p style=\"text-align: center;\"><em>Se Jesus for meu l\u00edder,<\/em><\/p>\n<p style=\"text-align: center;\"><em>Eu vencerei um dia.<\/em><a href=\"#_ftn1\" name=\"_ftnref1\"><sup>[1]<\/sup><\/a><\/p>\n<p style=\"text-align: justify;\">Pela gra\u00e7a dele, voc\u00ea vencer\u00e1 todos os desafios e injusti\u00e7as deste mundo algum dia. E, \u00e0 medida que voc\u00ea responde o errado com o certo, o desprezo com a bondade, e a negatividade com a b\u00ean\u00e7\u00e3o, pela gra\u00e7a dele voc\u00ea vencer\u00e1 o mal com o bem hoje.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><strong><em>Tenha uma experi\u00eancia ainda mais enriquecedora em sua vida adquirindo este devocional em formato de livro\u00a0 \u2014 <a class=\"external\" href=\"https:\/\/www.editorafiel.com.br\/alistair-begg\/devocional-verdade-para-a-vida\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI<\/a>\u00a0e adquira j\u00e1 o seu!<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure class=\"wp-caption aligncenter\" style=\"width: 298px;\"><a class=\"external\" href=\"https:\/\/www.editorafiel.com.br\/alistair-begg\/devocional-verdade-para-a-vida\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/i0.wp.com\/images.tcdn.com.br\/img\/img_prod\/1221753\/devocional_verdade_para_a_vida_1227_2_f97ddd6144f4a8aff564562ab4a574d2.png?resize=412%2C648&amp;ssl=1\" alt=\"\" width=\"298\" height=\"469\" \/><\/a><\/figure>\n<hr \/>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><sup>[1]<\/sup><\/a> Charles Albert Tindley, \u201cI\u2019ll Overcome Some Day\u201d (1900).<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devocional Verdade para a vida para 30 de junho<\/p>\n","protected":false},"author":25,"featured_media":66220,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[3773],"tags":[3715,3843],"class_list":["post-68390","devocionais","type-devocionais","status-publish","has-post-thumbnail","hentry","category-devocional-diario","tag-devocional-verdade-para-a-vida","tag-truth-for-life","tema-devocional-verdade-para-a-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vencendo o mal (Romanos 12.21) - Devocional Verdade para vida<\/title>\n<meta name=\"description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Romanos 12.21.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vencendo o mal (Romanos 12.21) - Devocional Verdade para vida\" \/>\n<meta property=\"og:description\" content=\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Romanos 12.21.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/vencendo-o-mal-romanos-12-21\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/vencendo-o-mal-romanos-12-21\\\/\",\"name\":\"Vencendo o mal (Romanos 12.21) - Devocional Verdade para vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/vencendo-o-mal-romanos-12-21\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/vencendo-o-mal-romanos-12-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2026-06-30T07:30:31+00:00\",\"description\":\"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Romanos 12.21.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/vencendo-o-mal-romanos-12-21\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/vencendo-o-mal-romanos-12-21\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/vencendo-o-mal-romanos-12-21\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/vencendo-o-mal-romanos-12-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devocionais\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/devocionais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vencendo o mal (Romanos 12.21)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vencendo o mal (Romanos 12.21) - Devocional Verdade para vida","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Romanos 12.21.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/","og_locale":"pt_BR","og_type":"article","og_title":"Vencendo o mal (Romanos 12.21) - Devocional Verdade para vida","og_description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Romanos 12.21.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","og_image":[{"width":837,"height":470,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/","name":"Vencendo o mal (Romanos 12.21) - Devocional Verdade para vida","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","datePublished":"2026-06-30T07:30:31+00:00","description":"Tenha um encontro di\u00e1rio com a Palavra de Deus. Leia este devocional Verdade para vida de Alistair Begg em Romanos 12.21.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/Header-Devocional-TFL-VE.png?fit=837%2C470&ssl=1","width":837,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/vencendo-o-mal-romanos-12-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Devocionais","item":"https:\/\/voltemosaoevangelho.com\/blog\/devocionais\/"},{"@type":"ListItem","position":3,"name":"Vencendo o mal (Romanos 12.21)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/devocionais"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=68390"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68390\/revisions"}],"predecessor-version":[{"id":68500,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/devocionais\/68390\/revisions\/68500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/66220"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=68390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=68390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=68390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}