{"id":72742,"date":"2026-02-03T11:37:51","date_gmt":"2026-02-03T14:37:51","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?post_type=o-que-a-biblia-diz&#038;p=72742"},"modified":"2026-02-04T18:09:36","modified_gmt":"2026-02-04T21:09:36","slug":"qual-a-importancia-da-biblia-em-nossas-vidas","status":"publish","type":"o-que-a-biblia-diz","link":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/","title":{"rendered":"Qual a import\u00e2ncia da B\u00edblia em nossas vidas?"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #808080;\"><em><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Resumo:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> Este artigo aborda por que a leitura di\u00e1ria da B\u00edblia \u00e9 vital para glorificar a Deus em Cristo. O texto \u00e9 um compilado organizado por Tony Reinke, jornalista que atua como professor e editor de Desiring God, contendo cita\u00e7\u00f5es diretas e respostas b\u00edblicas de John Piper, PhD em Novo Testamento pela Universidade de Munique, fundador do de Desiring God e chanceler do Bethlehem College &amp; Seminary, com mais de 30 anos de experi\u00eancia como pastor e autor de mais de 50 livros sobre assuntos teol\u00f3gicos, exeg\u00e9ticos e de vida crist\u00e3.<\/span><\/span><\/em><\/span><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Priorizamos a leitura di\u00e1ria da B\u00edblia porque, sem ela, n\u00e3o conseguimos alcan\u00e7ar o grande prop\u00f3sito da vida: \u201cexaltar a Deus como magn\u00edfico em Cristo \u2014 isto \u00e9, demonstrar como ele \u00e9 precioso e valioso, demonstr\u00e1-lo como um tesouro supremo\u201d (Fp 1.20). Ainda assim, \u201ctemos uma enorme tend\u00eancia em pensar, sentir e agir de maneiras que <em>n\u00e3o<\/em> fazem Cristo parecer grandioso\u201d. Para cumprirmos o nosso grande prop\u00f3sito, precisamos enxergar a gl\u00f3ria. \u201cSe n\u00e3o desejarmos, valorizarmos, desfrutarmos, provarmos e estimarmos a Cristo, n\u00e3o o apresentaremos como magn\u00edfico no que sentimos, dizemos e fazemos. Cristo \u00e9 mais exaltado em n\u00f3s quando estamos mais satisfeitos nele, e n\u00e3o podemos ficar satisfeitos sem contempl\u00e1-lo e sem <em>usufruir<\/em> de sua presen\u00e7a.\u201d Isso \u201cs\u00f3 acontecer\u00e1\u201d por meio de uma \u201cmedita\u00e7\u00e3o constante na Palavra de Deus, a B\u00edblia.\u201d Nas Escrituras, contemplamos a gl\u00f3ria de Cristo, e essa gl\u00f3ria nos transforma de dentro para fora (2Co 3.18; 4.4).<\/p>\n<p style=\"text-align: justify;\">A leitura b\u00edblica adequada \u00e9 motivada por um desespero na busca de ver a Deus. \u201cA raz\u00e3o pela qual leio a B\u00edblia \u00e9 porque estou completamente morto sem Cristo e sua Palavra. Mas eu quero que toda a minha vida, cada parte dela, seja gloriosa. Quero que a vida seja bela. Quero que a vida seja muito mais do que \u00e9 se eu tentar viv\u00ea-la sozinho. Quero ver qu\u00e3o surpreendente \u00e9 a realidade a cada momento \u2014 cada pessoa, cada pedra, cada \u00e1rvore, cada animal, cada obra de salva\u00e7\u00e3o. Sei que, largado \u00e0 pr\u00f3pria sorte, sou um fracasso absoluto. Estou vazio, sem profundidade, sem emo\u00e7\u00f5es significativas, sem intensidade, sem beleza, sem valor, sem do\u00e7ura ou maravilha \u2014 apenas tomado por uma sensa\u00e7\u00e3o de estar oco, sem vida, estagnado, passando de uma preocupa\u00e7\u00e3o mundana para outra.\u201d<\/p>\n<p style=\"text-align: justify;\">H\u00e1 \u201cuma esperan\u00e7a para o John Piper: que eu tenha olhos para ver a magnific\u00eancia de tudo que \u00e9 encantador em Deus \u2014 ou seja, que Deus se agrade em minha leitura b\u00edblica para me fazer ver a gl\u00f3ria que realmente se encontra nela\u201d. Devemos contemplar e saborear a gl\u00f3ria que nos transforma em pecadores redimidos, glorificando a Deus ao encontrarmos satisfa\u00e7\u00e3o nele. Nesse contexto, a leitura da B\u00edblia \u00e9 realmente uma \u201cexplora\u00e7\u00e3o fascinante\u201d.<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><\/p>\n<p style=\"text-align: justify;\">Este artigo \u00e9 um trecho do livro <strong>John Piper Responde<\/strong>: <em>respostas b\u00edblicas sobre os dilemas da vida<\/em>, escrito por Tony Reinke (em breve pela Editora Fiel).<\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> JPR 1140: \u201cA New Year, A New Bible Reading Plan\u201d (1 de janeiro de 2018). [Dispon\u00edvel em portugu\u00eas em VoltemosAoEvangelho.com sob o t\u00edtulo <em>Ano Novo \u2013 Oportunidade para ler a B\u00edblia toda<\/em>]<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A leitura da B\u00edblia revela a gl\u00f3ria de Cristo, transforma cora\u00e7\u00e3o, sustenta a f\u00e9, produz satisfa\u00e7\u00e3o em Deus e capacita crentes a viverem para gl\u00f3ria.<\/p>\n","protected":false},"author":490,"featured_media":72784,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[3547],"class_list":["post-72742","o-que-a-biblia-diz","type-o-que-a-biblia-diz","status-publish","has-post-thumbnail","hentry","tag-o-que-a-biblia-diz-sobre","tema-sobre-ler-negligenciar-e-memorizar-a-biblia","livro-john-piper-responde-respostas-biblicas-sobre-os-dilemas-da-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qual a import\u00e2ncia da B\u00edblia em nossas vidas? - Voltemos Ao Evangelho<\/title>\n<meta name=\"description\" content=\"A leitura da B\u00edblia revela a gl\u00f3ria de Cristo, transforma cora\u00e7\u00e3o, sustenta a f\u00e9, produz satisfa\u00e7\u00e3o em Deus e capacita crentes a viverem para gl\u00f3ria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a import\u00e2ncia da B\u00edblia em nossas vidas? - Voltemos Ao Evangelho\" \/>\n<meta property=\"og:description\" content=\"A leitura da B\u00edblia revela a gl\u00f3ria de Cristo, transforma cora\u00e7\u00e3o, sustenta a f\u00e9, produz satisfa\u00e7\u00e3o em Deus e capacita crentes a viverem para gl\u00f3ria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T21:09:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2026\/02\/O-QUE-A-BIBLIA-DIZ.png\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/qual-a-importancia-da-biblia-em-nossas-vidas\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/qual-a-importancia-da-biblia-em-nossas-vidas\\\/\",\"name\":\"Qual a import\u00e2ncia da B\u00edblia em nossas vidas? - Voltemos Ao Evangelho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/qual-a-importancia-da-biblia-em-nossas-vidas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/qual-a-importancia-da-biblia-em-nossas-vidas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/O-QUE-A-BIBLIA-DIZ.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2026-02-03T14:37:51+00:00\",\"dateModified\":\"2026-02-04T21:09:36+00:00\",\"description\":\"A leitura da B\u00edblia revela a gl\u00f3ria de Cristo, transforma cora\u00e7\u00e3o, sustenta a f\u00e9, produz satisfa\u00e7\u00e3o em Deus e capacita crentes a viverem para gl\u00f3ria.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/qual-a-importancia-da-biblia-em-nossas-vidas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/qual-a-importancia-da-biblia-em-nossas-vidas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/qual-a-importancia-da-biblia-em-nossas-vidas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/O-QUE-A-BIBLIA-DIZ.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/O-QUE-A-BIBLIA-DIZ.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/qual-a-importancia-da-biblia-em-nossas-vidas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que a B\u00edblia diz\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/o-que-a-biblia-diz\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qual a import\u00e2ncia da B\u00edblia em nossas vidas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual a import\u00e2ncia da B\u00edblia em nossas vidas? - Voltemos Ao Evangelho","description":"A leitura da B\u00edblia revela a gl\u00f3ria de Cristo, transforma cora\u00e7\u00e3o, sustenta a f\u00e9, produz satisfa\u00e7\u00e3o em Deus e capacita crentes a viverem para gl\u00f3ria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a import\u00e2ncia da B\u00edblia em nossas vidas? - Voltemos Ao Evangelho","og_description":"A leitura da B\u00edblia revela a gl\u00f3ria de Cristo, transforma cora\u00e7\u00e3o, sustenta a f\u00e9, produz satisfa\u00e7\u00e3o em Deus e capacita crentes a viverem para gl\u00f3ria.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_modified_time":"2026-02-04T21:09:36+00:00","og_image":[{"width":837,"height":470,"url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2026\/02\/O-QUE-A-BIBLIA-DIZ.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@voltemos","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/","name":"Qual a import\u00e2ncia da B\u00edblia em nossas vidas? - Voltemos Ao Evangelho","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2026\/02\/O-QUE-A-BIBLIA-DIZ.png?fit=837%2C470&ssl=1","datePublished":"2026-02-03T14:37:51+00:00","dateModified":"2026-02-04T21:09:36+00:00","description":"A leitura da B\u00edblia revela a gl\u00f3ria de Cristo, transforma cora\u00e7\u00e3o, sustenta a f\u00e9, produz satisfa\u00e7\u00e3o em Deus e capacita crentes a viverem para gl\u00f3ria.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2026\/02\/O-QUE-A-BIBLIA-DIZ.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2026\/02\/O-QUE-A-BIBLIA-DIZ.png?fit=837%2C470&ssl=1","width":837,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/qual-a-importancia-da-biblia-em-nossas-vidas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"O que a B\u00edblia diz","item":"https:\/\/voltemosaoevangelho.com\/blog\/o-que-a-biblia-diz\/"},{"@type":"ListItem","position":3,"name":"Qual a import\u00e2ncia da B\u00edblia em nossas vidas?"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/o-que-a-biblia-diz\/72742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/o-que-a-biblia-diz"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/o-que-a-biblia-diz"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/490"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=72742"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/o-que-a-biblia-diz\/72742\/revisions"}],"predecessor-version":[{"id":72770,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/o-que-a-biblia-diz\/72742\/revisions\/72770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/72784"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=72742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=72742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=72742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}