{"id":10598,"date":"2012-11-14T03:04:55","date_gmt":"2012-11-14T05:04:55","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=10598"},"modified":"2015-10-30T12:21:21","modified_gmt":"2015-10-30T14:21:21","slug":"r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/","title":{"rendered":"R. C. Sproul &#8211; Toda a terra est\u00e1 cheia da Sua gl\u00f3ria"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<blockquote><\/p>\n<p style=\"text-align: justify;\">Santo, santo, santo \u00e9 o SENHOR dos Ex\u00e9rcitos; toda a terra est\u00e1 cheia da sua gl\u00f3ria. \u00a0(Is 6:3)<\/p>\n<p><\/blockquote>[vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Neste v\u00eddeo (4 min.), R. C. Sproul reflete sobre a onipresen\u00e7a da gl\u00f3ria de Deus na cria\u00e7\u00e3o, baseado em Isa\u00edas 6:1-3.<\/p>\n<p>[\/vc_column_text][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=8L6Mal6lm4c&#8221;]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_column_text]<\/p>\n<h3 style=\"text-align: justify;\">Transcri\u00e7\u00e3o<\/h3>\n<p style=\"text-align: justify;\">Em Isa\u00edas 6, quando ele teve aquela vis\u00e3o na ocasi\u00e3o do seu chamado para ser um profeta, recordamos do can\u00e7\u00e3o dos anjos na presen\u00e7a de Deus que cantavam: \u201cSanto, santo, santo \u00e9 o SENHOR dos Ex\u00e9rcitos.\u201d Mas o que mais a m\u00fasica cont\u00e9m? \u201cToda a terra est\u00e1 cheia da sua gl\u00f3ria.\u201d Ent\u00e3o, voc\u00ea v\u00ea a ant\u00edtese? Voc\u00ea v\u00ea a colis\u00e3o entre o secularismo radical de pessoas como Jean-Paul Sartre e o ensino da Escritura? O ensino das Escrituras n\u00e3o \u00e9 que o santo e sagrado est\u00e3o em algum \u00e2mbito escondido, alguma esfera esot\u00e9rica, onde apenas os mais brilhantes pensadores da elite podem penetrar para encontrar um vislumbre ligeiro do santo.<\/p>\n<p style=\"text-align: justify;\">Pelo contr\u00e1rio, toda a terra est\u00e1 cheia da gl\u00f3ria de Deus. Ent\u00e3o, por que temos essa sensa\u00e7\u00e3o do profano? Bem, Calvino respondeu a essa pergunta dizendo que \u201ctoda a cria\u00e7\u00e3o \u00e9 um teatro glorioso, como se estivesse gritando, manifestando claramente a santidade de Deus, mas n\u00f3s estamos cegos a isso.\u201d Mas a cegueira \u00e9 uma cegueira volunt\u00e1ria. N\u00f3s somos como seres humanos que transitam neste teatro glorioso com os olhos vendados. Vendas que colocamos em nossos pr\u00f3prios olhos para n\u00e3o ver o santo e sagrado, porque n\u00e3o h\u00e1 nada mais terr\u00edvel para criaturas pecadoras do que ser exposto ao santo.<\/p>\n<p style=\"text-align: justify;\">\u00c9 isso o que vemos nesta hist\u00f3ria. Mois\u00e9s v\u00ea a sar\u00e7a ardente que n\u00e3o \u00e9 consumida; e nos \u00e9 dito na narrativa que ele se vira para o lado para observ\u00e1-la. Enquanto ele se vira, olhando na dire\u00e7\u00e3o da sar\u00e7a, ele n\u00e3o est\u00e1 satisfeito em observ\u00e1-la \u00e0 dist\u00e2ncia; ele come\u00e7a a caminhar em dire\u00e7\u00e3o \u00e0 sar\u00e7a. Ele come\u00e7a a se aproximar dela, e ao se aproximar, de repente, a voz sai da sar\u00e7a, chamando-o pelo nome, dizendo: \u201cMois\u00e9s, Mois\u00e9s, pare a\u00ed mesmo! N\u00e3o se achegue, n\u00e3o se aproxime. Em vez disso, tire seu cal\u00e7ado, tire as sand\u00e1lias dos p\u00e9s, pois o lugar em que voc\u00ea est\u00e1 \u00e9 terra santa.\u201d<\/p>\n<p>[\/vc_column_text]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_message color=&#8221;alert-danger&#8221; style=&#8221;square_outlined&#8221; el_class=&#8221;creditos_box&#8221;]<strong>Por:<\/strong> R. C. Sproul. Extra\u00eddo do site\u00a0<a href=\"http:\/\/fiel.in\/1JmySBE\" target=\"_blank\">ligonier.org<\/a>.\u00a0\u00a9 2012 Ligonier Ministries. Original:\u00a0<a href=\"http:\/\/fiel.in\/1ipXvUx\" target=\"_blank\">R.C.\u00a0Sproul on the Ubiquity of God\u2019s Glory in\u00a0Creation<\/a><\/p>\n<p><strong>Tradu\u00e7\u00e3o:<\/strong> Vin\u00edcius Musselman Pimentel \u2013 Editora Fiel \u00a9 Todos os direitos reservados[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Neste v\u00eddeo (4 min.), R. C. Sproul reflete sobre a onipresen\u00e7a da gl\u00f3ria de Deus na cria\u00e7\u00e3o, baseado em Isa\u00edas 6:1-3.<\/p>\n","protected":false},"author":284,"featured_media":10599,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-10598","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","post_format-post-format-video","tema-atributos-de-deus","categoria-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R. C. Sproul - Toda a terra est\u00e1 cheia da Sua gl\u00f3ria<\/title>\n<meta name=\"description\" content=\"Neste v\u00eddeo (4 min.), R. C. Sproul reflete sobre a onipresen\u00e7a da gl\u00f3ria de Deus na cria\u00e7\u00e3o, baseado em Isa\u00edas 6:1-3.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R. C. Sproul - Toda a terra est\u00e1 cheia da Sua gl\u00f3ria\" \/>\n<meta property=\"og:description\" content=\"Neste v\u00eddeo (4 min.), R. C. Sproul reflete sobre a onipresen\u00e7a da gl\u00f3ria de Deus na cria\u00e7\u00e3o, baseado em Isa\u00edas 6:1-3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-14T05:04:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-30T14:21:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2012\/11\/sproul-gloria.jpg?fit=700%2C300&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R. C. Sproul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"R. C. Sproul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/\"},\"author\":{\"name\":\"R. C. Sproul\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/e4716c5afbd274fd32535531c2cfca98\"},\"headline\":\"R. C. Sproul &#8211; Toda a terra est\u00e1 cheia da Sua gl\u00f3ria\",\"datePublished\":\"2012-11-14T05:04:55+00:00\",\"dateModified\":\"2015-10-30T14:21:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/\"},\"wordCount\":517,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/sproul-gloria.jpg?fit=700%2C300&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/\",\"name\":\"R. C. Sproul - Toda a terra est\u00e1 cheia da Sua gl\u00f3ria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/sproul-gloria.jpg?fit=700%2C300&ssl=1\",\"datePublished\":\"2012-11-14T05:04:55+00:00\",\"dateModified\":\"2015-10-30T14:21:21+00:00\",\"description\":\"Neste v\u00eddeo (4 min.), R. C. Sproul reflete sobre a onipresen\u00e7a da gl\u00f3ria de Deus na cria\u00e7\u00e3o, baseado em Isa\u00edas 6:1-3.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/sproul-gloria.jpg?fit=700%2C300&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/sproul-gloria.jpg?fit=700%2C300&ssl=1\",\"width\":\"700\",\"height\":\"300\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2012\\\/11\\\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R. C. Sproul &#8211; Toda a terra est\u00e1 cheia da Sua gl\u00f3ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/e4716c5afbd274fd32535531c2cfca98\",\"name\":\"R. C. Sproul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"caption\":\"R. C. Sproul\"},\"description\":\"R. C. Sproul nasceu em 1939, no estado da Pensilv\u00e2nia. Foi ministro presbiteriano, pastor da igreja St. Andrews Chapel, na Fl\u00f3rida. Foi fundador e presidente do minist\u00e9rio Ligonier, professor e palestrante em semin\u00e1rios e confer\u00eancias, autor de mais de sessenta livros, v\u00e1rios deles publicados em portugu\u00eas, e editor geral da Reformation Study Bible.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/r-c-sproul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R. C. Sproul - Toda a terra est\u00e1 cheia da Sua gl\u00f3ria","description":"Neste v\u00eddeo (4 min.), R. C. Sproul reflete sobre a onipresen\u00e7a da gl\u00f3ria de Deus na cria\u00e7\u00e3o, baseado em Isa\u00edas 6:1-3.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/","og_locale":"pt_BR","og_type":"article","og_title":"R. C. Sproul - Toda a terra est\u00e1 cheia da Sua gl\u00f3ria","og_description":"Neste v\u00eddeo (4 min.), R. C. Sproul reflete sobre a onipresen\u00e7a da gl\u00f3ria de Deus na cria\u00e7\u00e3o, baseado em Isa\u00edas 6:1-3.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2012-11-14T05:04:55+00:00","article_modified_time":"2015-10-30T14:21:21+00:00","og_image":[{"width":700,"height":300,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2012\/11\/sproul-gloria.jpg?fit=700%2C300&ssl=1","type":"image\/jpeg"}],"author":"R. C. Sproul","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"R. C. Sproul","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/"},"author":{"name":"R. C. Sproul","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/e4716c5afbd274fd32535531c2cfca98"},"headline":"R. C. Sproul &#8211; Toda a terra est\u00e1 cheia da Sua gl\u00f3ria","datePublished":"2012-11-14T05:04:55+00:00","dateModified":"2015-10-30T14:21:21+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/"},"wordCount":517,"commentCount":7,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2012\/11\/sproul-gloria.jpg?fit=700%2C300&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/","name":"R. C. Sproul - Toda a terra est\u00e1 cheia da Sua gl\u00f3ria","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2012\/11\/sproul-gloria.jpg?fit=700%2C300&ssl=1","datePublished":"2012-11-14T05:04:55+00:00","dateModified":"2015-10-30T14:21:21+00:00","description":"Neste v\u00eddeo (4 min.), R. C. Sproul reflete sobre a onipresen\u00e7a da gl\u00f3ria de Deus na cria\u00e7\u00e3o, baseado em Isa\u00edas 6:1-3.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2012\/11\/sproul-gloria.jpg?fit=700%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2012\/11\/sproul-gloria.jpg?fit=700%2C300&ssl=1","width":"700","height":"300"},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2012\/11\/r-c-sproul-toda-a-terra-esta-cheia-da-sua-gloria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"R. C. Sproul &#8211; Toda a terra est\u00e1 cheia da Sua gl\u00f3ria"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/e4716c5afbd274fd32535531c2cfca98","name":"R. C. Sproul","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","caption":"R. C. Sproul"},"description":"R. C. Sproul nasceu em 1939, no estado da Pensilv\u00e2nia. Foi ministro presbiteriano, pastor da igreja St. Andrews Chapel, na Fl\u00f3rida. Foi fundador e presidente do minist\u00e9rio Ligonier, professor e palestrante em semin\u00e1rios e confer\u00eancias, autor de mais de sessenta livros, v\u00e1rios deles publicados em portugu\u00eas, e editor geral da Reformation Study Bible.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/r-c-sproul\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-2KW","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2012\/11\/sproul-gloria.jpg?fit=700%2C300&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/10598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/284"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=10598"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/10598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/10599"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=10598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=10598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=10598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}