{"id":12437,"date":"2013-05-08T00:05:12","date_gmt":"2013-05-08T03:05:12","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=12437"},"modified":"2015-07-07T16:09:37","modified_gmt":"2015-07-07T19:09:37","slug":"uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/","title":{"rendered":"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\/4]"},"content":{"rendered":"<p style=\"text-align: center;\"><a class=\"btn btn-default btn-sm btn-shortcode\" href=\"http:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/\" target=\"\" style=\"color:#silver !important;\"> Parte 1<\/a>\u00a0<a class=\"btn btn-default btn-sm btn-shortcode\" href=\"&#8221;http:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-24\/&#8221;\" target=\"\" style=\"color:#&#8221;silver&#8221; !important;\"> Parte 2<\/a>\u00a0<a class=\"btn btn-default btn-sm btn-shortcode\" href=\"&#8221;http:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-34\/&#8221;\" target=\"\" style=\"color:#&#8221;silver&#8221; !important;\"> Parte 3<\/a>\u00a0<a class=\"btn btn-default btn-sm btn-shortcode\" href=\"&#8221;http:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-44\/&#8221;\" target=\"\" style=\"color:#&#8221;silver&#8221; !important;\"> Parte 4<\/a><\/p>\n<div>\n<h2 style=\"text-align: justify;\">Diagn\u00f3stico &#8211; O Problema com Grande Parte da Prega\u00e7\u00e3o de Hoje<\/h2>\n<p style=\"text-align: justify;\">Na associa\u00e7\u00e3o de igrejas \u00e0 qual eu perten\u00e7o &#8211; a <i>Southern Baptist Convention <\/i>[Conven\u00e7\u00e3o Batista do Sul] -, a batalha pela inerr\u00e2ncia da Escritura pode ter sido ganha. Entretanto, nem n\u00f3s nem outras denomina\u00e7\u00f5es ou igrejas evang\u00e9licas que ganharam batalhas semelhantes dever\u00edamos nos congratular t\u00e3o rapidamente. Isso porque muitas igrejas conservadoras podem abra\u00e7ar a inerr\u00e2ncia da Escritura, mas, ainda assim, negar na pr\u00e1tica <i>a sufici\u00eancia <\/i>da Palavra de Deus. N\u00f3s podemos dizer que a Escritura \u00e9 a palavra inerrante de Deus, mas, ainda assim, falhar em proclam\u00e1-la seriamente de nossos p\u00falpitos.<\/p>\n<p style=\"text-align: justify;\">Existe, na verdade, uma fome pela palavra de Deus em muitas igrejas evang\u00e9licas hoje. Algumas s\u00e9ries de serm\u00f5es fazem, em seus t\u00edtulos, refer\u00eancias a programas de TV tais como <i>Gilligan\u2019s Island<\/i>, <i>Bonanza<\/i> e <i>Mary Tyler Moore<\/i>. A prega\u00e7\u00e3o, com frequ\u00eancia, foca em passos para um casamento bem-sucedido ou em como criar filhos em nossa cultura. Serm\u00f5es sobre quest\u00f5es familiares, obviamente, s\u00e3o adequados e necess\u00e1rios, mas dois problemas frequentemente aparecem. Primeiro, o que as Escrituras de fato ensinam acerca desses assuntos \u00e9 frequentemente negligenciado. Quantos serm\u00f5es sobre casamento apresentam com fidelidade e urg\u00eancia o que Paulo de fato ensina sobre os papeis do homem e da mulher (Ef 5.22-23)? Ou acaso n\u00f3s estamos constrangidos pelo que as Escrituras ensinam?<\/p>\n<p style=\"text-align: justify;\">Segundo, e talvez mais s\u00e9rio, tais serm\u00f5es s\u00e3o quase sempre pregados no n\u00edvel horizontal. Eles se tornam o centro da vida semanal da congrega\u00e7\u00e3o, e a cosmovis\u00e3o teol\u00f3gica que permeia a Palavra de Deus e prov\u00ea o fundamento para toda a vida \u00e9 simplesmente ignorada. Nossos pastores se tornam moralistas como Dear Abby, dando conselhos sobre como viver uma vida feliz semana ap\u00f3s semana.<\/p>\n<p style=\"text-align: justify;\">Muitas congrega\u00e7\u00f5es n\u00e3o percebem o que est\u00e1 acontecendo porque a vida moral que tal prega\u00e7\u00e3o promove est\u00e1 de acordo, ao menos em parte, com a Escritura. Ela vai ao encontro das necessidades sentidas tanto por crentes como por incr\u00e9dulos.<\/p>\n<p style=\"text-align: justify;\">Pastores tamb\u00e9m creem que devem preencher seus serm\u00f5es com hist\u00f3rias e ilustra\u00e7\u00f5es, de modo que as anedotas enfatizem o ensino moral apresentado. Todo bom pregador usar\u00e1 ilustra\u00e7\u00f5es. Todavia, serm\u00f5es podem se tornar t\u00e3o repletos de hist\u00f3rias que acabam desprovidos de qualquer teologia.<\/p>\n<p style=\"text-align: justify;\">Eu tenho ouvido evang\u00e9licos afirmarem com certa frequ\u00eancia que as igrejas evang\u00e9licas est\u00e3o indo bem em teologia porque as congrega\u00e7\u00f5es n\u00e3o est\u00e3o reclamando daquilo que lhes \u00e9 ensinado. Tal coment\u00e1rio \u00e9 completamente assustador. N\u00f3s, como pastores, temos a responsabilidade de proclamar &#8220;todo o des\u00edgnio de Deus&#8221; (At 20.27). N\u00f3s n\u00e3o podemos p\u00f4r a nossa confian\u00e7a em pesquisas de opini\u00e3o congregacionais para determinar se n\u00f3s estamos cumprindo o nosso chamado. N\u00f3s devemos p\u00f4r a nossa confian\u00e7a naquilo que as Escrituras exigem. Pode ser que uma congrega\u00e7\u00e3o jamais tenha sido seriamente ensinada na Palavra de Deus, de modo que os crentes n\u00e3o percebem onde n\u00f3s estamos falhando como pastores.<\/p>\n<p style=\"text-align: justify;\">Paulo nos alerta que &#8220;entre v\u00f3s penetrar\u00e3o lobos vorazes, que n\u00e3o poupar\u00e3o o rebanho&#8221; (At 20.29). E, em outro lugar, ele afirma que &#8220;haver\u00e1 tempo em que n\u00e3o suportar\u00e3o a s\u00e3 doutrina; pelo contr\u00e1rio, cercar-se-\u00e3o de mestres segundo as suas pr\u00f3prias cobi\u00e7as, como que sentindo coceira nos ouvidos; e se recusar\u00e3o a dar ouvidos \u00e0 verdade, entregando-se \u00e0s f\u00e1bulas&#8221; (2Tm 4.3-4). Se n\u00f3s avaliamos nossa prega\u00e7\u00e3o pelo que as congrega\u00e7\u00f5es desejam, n\u00f3s podemos estar dando espa\u00e7o para as heresias. Eu n\u00e3o estou dizendo que nossas congrega\u00e7\u00f5es s\u00e3o her\u00e9ticas, mas apenas que o teste para a fidelidade \u00e9 a Palavra de Deus, e n\u00e3o a opini\u00e3o popular. O chamado dos pastores \u00e9 para alimentar o rebanho com a Palavra de Deus, n\u00e3o para agradar as pessoas com o que elas desejam ouvir.<\/p>\n<p style=\"text-align: justify;\">Muito frequentemente, nossas congrega\u00e7\u00f5es s\u00e3o treinadas de modo pobre por aqueles de n\u00f3s que pregam. Considere o que acontece quando alimentamos uma congrega\u00e7\u00e3o com uma dieta constante de prega\u00e7\u00e3o moralista. Eles podem aprender a ser gentis, perdoadores, amorosos, bons maridos ou esposas (tudo isso \u00e9 bom, obviamente!). Os seus cora\u00e7\u00f5es podem ser aquecidos e at\u00e9 edificados. Mas, \u00e0 medida que o fundamento teol\u00f3gico \u00e9 negligenciado, o lobo da heresia passa a espreitar cada vez mais de perto. Como? N\u00e3o que o pr\u00f3prio pastor seja um herege. Ele pode ser completamente ortodoxo e fiel em sua pr\u00f3pria teologia. No entanto, ele <i>presume<\/i> a teologia em toda a sua prega\u00e7\u00e3o e, assim, torna-se negligente em pregar ao seu povo o enredo e a teologia da B\u00edblia. Em uma ou duas gera\u00e7\u00f5es, portanto, a congrega\u00e7\u00e3o pode, desavisadamente e por ignor\u00e2ncia, chamar um pastor mais liberal. Esse novo pastor tamb\u00e9m pregar\u00e1 que as pessoas devem ser boas, gentis e amorosas. Ele tamb\u00e9m enfatizar\u00e1 a import\u00e2ncia de bons casamentos e relacionamentos din\u00e2micos. As pessoas nos bancos podem nem sequer discernir a diferen\u00e7a, uma vez que a teologia parece exatamente igual \u00e0 do pastor conservador que o precedeu. E, em um sentido, ela o \u00e9, pois o pastor conservador nunca proclamou ou pregou a sua teologia. O pastor conservador cria na inerr\u00e2ncia da Escritura, mas n\u00e3o em sua sufici\u00eancia, pois ele deixou de proclamar tudo o que as Escrituras ensinam \u00e0 sua congrega\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Nossa ignor\u00e2ncia acerca da teologia constantemente se evidencia. N\u00e3o saem da minha mente duas ocasi\u00f5es nos \u00faltimos dez anos (uma em um grande est\u00e1dio, por um pregador cujo nome n\u00e3o lembro) em que um pregador convidava as pessoas para virem \u00e0 frente. O serm\u00e3o no est\u00e1dio pretendia ser um serm\u00e3o evangel\u00edstico, mas eu posso honestamente dizer que o evangelho n\u00e3o foi pregado de modo algum. Nada foi dito acerca de Cristo crucificado e ressurreto, ou <i>por que<\/i> ele foi crucificado e ressurreto. Nada foi dito sobre por que a f\u00e9 salva, e n\u00e3o as obras. Milhares vieram \u00e0 frente e foram, sem d\u00favida, contados como salvos. Mas eu co\u00e7ava minha cabe\u00e7a e indagava o que de fato estava acontecendo. Eu orei para que ao menos alguns fossem verdadeiramente convertidos, talvez porque eles j\u00e1 conhecessem o conte\u00fado do evangelho de ouvi-lo em outras ocasi\u00f5es. O mesmo aconteceu no culto de uma igreja que eu visitava. O pregador prolongou-se em um inspirado convite para que os ouvintes &#8220;viessem \u00e0 frente&#8221; e &#8220;fossem salvos&#8221;, mas ele n\u00e3o deu qualquer explica\u00e7\u00e3o acerca do evangelho!<\/p>\n<p style=\"text-align: justify;\">Tal prega\u00e7\u00e3o pode encher nossas igrejas de pessoas n\u00e3o convertidas, as quais s\u00e3o duplamente perigosas: elas foram asseguradas por seus pastores de que s\u00e3o convertidas e de que nunca podem perder a sua salva\u00e7\u00e3o, mas ainda est\u00e3o perdidas. Ent\u00e3o, daquele dia em diante, essas mesmas pessoas s\u00e3o exortadas, semana ap\u00f3s semana, com o nosso novo evangelho para esses tempos p\u00f3s-modernos: sejam legais.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<blockquote>\n<p style=\"text-align: justify;\">Por Thomas R. Schreiner. Extra\u00eddo do site <a href=\"http:\/\/9marks.org\/\">www.9marks.org<\/a>. Copyright \u00a9 2013 9Marks. Usado com Permiss\u00e3o. Original:\u00a0<a href=\"http:\/\/www.9marks.org\/journal\/preaching-and-biblical-theology-101-pbt-101\">Preaching and Biblical Theology 101<\/a><\/p>\n<p style=\"text-align: justify;\">Tradu\u00e7\u00e3o: Vin\u00edcius Silva Pimentel \u2013 Minist\u00e9rio Fiel \u00a9 Todos os direitos reservados. Website: <a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\">www.MinisterioFiel.com.br<\/a> \/ <a href=\"http:\/\/voltemosaoevangelho.com\/blog\/\" target=\"_blank\">www.VoltemosAoEvangelho.com<\/a>. Original:\u00a0<a href=\"http:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/\" target=\"_blank\">Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner)<\/a><\/p>\n<p style=\"text-align: justify;\">Permiss\u00f5es: Voc\u00ea est\u00e1 autorizado e incentivado a reproduzir e distribuir este material em qualquer formato, desde que informe o autor, seu minist\u00e9rio e o tradutor, n\u00e3o altere o conte\u00fado original e n\u00e3o o utilize para fins comerciais.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/pt.9marks.org\/\" target=\"_blank\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/05\/9marks-logo2-300x83.png?resize=180%2C50\" alt=\"9marks-logo2\" width=\"180\" height=\"50\" \/><\/a><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Muitas igrejas conservadoras podem abra\u00e7ar a inerr\u00e2ncia da Escritura, mas, ainda assim, negar na pr\u00e1tica a sufici\u00eancia da Palavra de Deus. N\u00f3s podemos dizer que a Escritura \u00e9 a palavra inerrante de Deus, mas, ainda assim, falhar em proclam\u00e1-la seriamente de nossos p\u00falpitos.<\/p>\n","protected":false},"author":324,"featured_media":12440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[237],"class_list":["post-12437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-teologia-biblica","tema-9-marcas","tema-a-leitura-biblica","tema-ministerio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\/4]<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\/4]\" \/>\n<meta property=\"og:description\" content=\"Muitas igrejas conservadoras podem abra\u00e7ar a inerr\u00e2ncia da Escritura, mas, ainda assim, negar na pr\u00e1tica a sufici\u00eancia da Palavra de Deus. N\u00f3s podemos dizer que a Escritura \u00e9 a palavra inerrante de Deus, mas, ainda assim, falhar em proclam\u00e1-la seriamente de nossos p\u00falpitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-08T03:05:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-07T19:09:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/05\/9marks-teologia.jpg?fit=700%2C300&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas R. Schreiner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas R. Schreiner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/\"},\"author\":{\"name\":\"Thomas R. Schreiner\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/5e803f88aa999e155a28c393d6688828\"},\"headline\":\"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\\\/4]\",\"datePublished\":\"2013-05-08T03:05:12+00:00\",\"dateModified\":\"2015-07-07T19:09:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/\"},\"wordCount\":1376,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/9marks-teologia.jpg?fit=700%2C300&ssl=1\",\"keywords\":[\"Teologia B\u00edblica\"],\"articleSection\":[\"...\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/\",\"name\":\"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\\\/4]\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/9marks-teologia.jpg?fit=700%2C300&ssl=1\",\"datePublished\":\"2013-05-08T03:05:12+00:00\",\"dateModified\":\"2015-07-07T19:09:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/9marks-teologia.jpg?fit=700%2C300&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/9marks-teologia.jpg?fit=700%2C300&ssl=1\",\"width\":700,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/05\\\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\\\/4]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/5e803f88aa999e155a28c393d6688828\",\"name\":\"Thomas R. Schreiner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g\",\"caption\":\"Thomas R. Schreiner\"},\"description\":\"Thomas R. Schreiner serve como pastor de prega\u00e7\u00e3o na Clifton Baptist Church em Louisville, Kentucky. Ele \u00e9 tamb\u00e9m professor de Novo Testamento no Southern Baptist Theological Seminary e escreveu Romans (Baker, 1998) e Paul, Apostle of God\u2019s Glory in Christ: A Pauline Theology (InterVarsity, 2001), entre muitos outros t\u00edtulos.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/thomas-r-schreiner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\/4]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/","og_locale":"pt_BR","og_type":"article","og_title":"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\/4]","og_description":"Muitas igrejas conservadoras podem abra\u00e7ar a inerr\u00e2ncia da Escritura, mas, ainda assim, negar na pr\u00e1tica a sufici\u00eancia da Palavra de Deus. N\u00f3s podemos dizer que a Escritura \u00e9 a palavra inerrante de Deus, mas, ainda assim, falhar em proclam\u00e1-la seriamente de nossos p\u00falpitos.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2013-05-08T03:05:12+00:00","article_modified_time":"2015-07-07T19:09:37+00:00","og_image":[{"width":700,"height":300,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/05\/9marks-teologia.jpg?fit=700%2C300&ssl=1","type":"image\/jpeg"}],"author":"Thomas R. Schreiner","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Thomas R. Schreiner","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/"},"author":{"name":"Thomas R. Schreiner","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/5e803f88aa999e155a28c393d6688828"},"headline":"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\/4]","datePublished":"2013-05-08T03:05:12+00:00","dateModified":"2015-07-07T19:09:37+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/"},"wordCount":1376,"commentCount":5,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/05\/9marks-teologia.jpg?fit=700%2C300&ssl=1","keywords":["Teologia B\u00edblica"],"articleSection":["..."],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/","name":"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\/4]","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/05\/9marks-teologia.jpg?fit=700%2C300&ssl=1","datePublished":"2013-05-08T03:05:12+00:00","dateModified":"2015-07-07T19:09:37+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/05\/9marks-teologia.jpg?fit=700%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/05\/9marks-teologia.jpg?fit=700%2C300&ssl=1","width":700,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/05\/uma-introducao-a-pregacao-e-a-teologia-biblica-thomas-r-schreiner-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Uma introdu\u00e7\u00e3o \u00e0 Prega\u00e7\u00e3o e \u00e0 Teologia B\u00edblica (Thomas R. Schreiner) [1\/4]"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/5e803f88aa999e155a28c393d6688828","name":"Thomas R. Schreiner","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g","caption":"Thomas R. Schreiner"},"description":"Thomas R. Schreiner serve como pastor de prega\u00e7\u00e3o na Clifton Baptist Church em Louisville, Kentucky. Ele \u00e9 tamb\u00e9m professor de Novo Testamento no Southern Baptist Theological Seminary e escreveu Romans (Baker, 1998) e Paul, Apostle of God\u2019s Glory in Christ: A Pauline Theology (InterVarsity, 2001), entre muitos outros t\u00edtulos.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/thomas-r-schreiner\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/05\/9marks-teologia.jpg?fit=700%2C300&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-3eB","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/12437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/324"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=12437"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/12437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/12440"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=12437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=12437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=12437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}