{"id":13816,"date":"2013-08-13T03:02:05","date_gmt":"2013-08-13T06:02:05","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=13816"},"modified":"2018-11-13T14:59:44","modified_gmt":"2018-11-13T16:59:44","slug":"voce-foi-salvo-de-que-r-c-sproul","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/","title":{"rendered":"Voc\u00ea foi salvo de qu\u00ea? &#8211; R. C. Sproul"},"content":{"rendered":"<p style=\"text-align: justify;\">Certa vez, fui confrontando por um jovem na Filad\u00e9lfia que me perguntou: \u201cVoc\u00ea est\u00e1 salvo?\u201d Minha resposta para ele foi: \u201cSalvo de qu\u00ea?\u201d. Ele foi pego de surpresa com a minha pergunta. Obviamente, ele n\u00e3o tinha pensado muito sobre o significado da quest\u00e3o que estava perguntando. Certamente eu n\u00e3o estava salvo de ser interrompido na rua e abordado com a pergunta \u201cVoc\u00ea est\u00e1 salvo?\u201d.<\/p>\n<p style=\"text-align: justify;\">A quest\u00e3o de ser salvo \u00e9 a quest\u00e3o suprema da B\u00edblia. O assunto das Sagradas Escrituras \u00e9 o tema da salva\u00e7\u00e3o. Jesus, em sua concep\u00e7\u00e3o no ventre de Maria, \u00e9 anunciado como o Salvador. Salvador e salva\u00e7\u00e3o caminham juntos. O papel do Salvador \u00e9 salvar.<\/p>\n<p style=\"text-align: justify;\">Perguntamos novamente: Salvo de qu\u00ea? O significado b\u00edblico de salva\u00e7\u00e3o \u00e9 amplo e variado. Na forma mais simples, o verbo\u00a0<em>salvar\u00a0<\/em>significa \u201cresgatar de uma situa\u00e7\u00e3o perigosa ou amea\u00e7adora\u201d. Quando Israel escapa da derrota nas m\u00e3os de seus inimigos no campo de batalha, ele se diz salvo. Quando as pessoas se recuperam de uma doen\u00e7a com risco de vida, elas experimentam salva\u00e7\u00e3o. Quando a colheita \u00e9 resgatada de praga ou seca, o resultado \u00e9 a salva\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Usamos a palavra\u00a0<em>salva\u00e7\u00e3o<\/em>\u00a0de uma maneira similar. Diz-se que um boxeador foi \u00a0\u201dsalvo pelo gongo\u201d se o\u00a0<em>round<\/em>\u00a0termina antes do \u00e1rbitro iniciar a contagem. Salva\u00e7\u00e3o significa ser resgatado de alguma calamidade. No entanto, a B\u00edblia usa o termo\u00a0<em>salva\u00e7\u00e3o<\/em>\u00a0em um sentido espec\u00edfico para se referir \u00e0 nossa reden\u00e7\u00e3o definitiva do pecado e \u00e0 reconcilia\u00e7\u00e3o com Deus. Neste sentido, a salva\u00e7\u00e3o \u00e9 da calamidade final \u2013 o ju\u00edzo de Deus. A salva\u00e7\u00e3o final \u00e9 realizada por Cristo, \u201cque nos livra da ira vindoura\u201d (1Ts 1.10).<\/p>\n<p style=\"text-align: justify;\">A B\u00edblia anuncia claramente que haver\u00e1 um dia de julgamento, em que todos os seres humanos ser\u00e3o responsabilizados diante do tribunal de Deus. Para muitos, esse \u201cdia do Senhor\u201d ser\u00e1 um dia de trevas, sem luz. Esse ser\u00e1 o dia em que Deus vai derramar sua ira contra os \u00edmpios e impenitentes. Ser\u00e1 o holocausto final, a hora mais escura, a pior calamidade da hist\u00f3ria humana.\u00a0 Ser liberto da ira de Deus, que muito certamente vir\u00e1 sobre o mundo, \u00e9 a salva\u00e7\u00e3o definitiva. Esta \u00e9 a opera\u00e7\u00e3o de resgate que Cristo executa para o seu povo, como seu salvador.<\/p>\n<p style=\"text-align: justify;\">A B\u00edblia usa o termo\u00a0<em>salva\u00e7\u00e3o<\/em>\u00a0n\u00e3o s\u00f3 em muitos sentidos, mas em muitos tempos. O verbo\u00a0<em>salvar<\/em>\u00a0aparece em praticamente todos os poss\u00edveis tempos da l\u00edngua grega. H\u00e1 o sentido de que\u00a0<em>fomos salvos<\/em>\u00a0(desde a funda\u00e7\u00e3o do mundo); est\u00e1vamos\u00a0<em>sendo salvos<\/em>\u00a0(pela obra de Deus na hist\u00f3ria);\u00a0<em>somos salvos<\/em>\u00a0(por estar em um estado justificado); estamos\u00a0<em>sendo salvos<\/em>\u00a0(por estarmos sendo santificados ou tornado santos) e\u00a0<em>seremos salvos<\/em>\u00a0(por experimentar a consuma\u00e7\u00e3o da nossa reden\u00e7\u00e3o no c\u00e9u). A B\u00edblia fala da salva\u00e7\u00e3o em termos de passado, presente e futuro.<\/p>\n<p style=\"text-align: justify;\">\u00c0s vezes, n\u00f3s igualamos a nossa salva\u00e7\u00e3o presente com a nossa justifica\u00e7\u00e3o. Em outros momentos, vemos a justifica\u00e7\u00e3o como um passo espec\u00edfico na ordem total ou plano de salva\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Por fim, \u00e9 importante notar outro aspecto central do conceito b\u00edblico de salva\u00e7\u00e3o. A salva\u00e7\u00e3o \u00e9 do Senhor. Salva\u00e7\u00e3o n\u00e3o \u00e9 uma iniciativa humana. Os seres humanos n\u00e3o podem se salvar. A salva\u00e7\u00e3o \u00e9 uma obra divina, que \u00e9 realizada e aplicada por Deus. \u00a0Somos salvos\u00a0<em>pelo Senhor<\/em>\u00a0e\u00a0<em>do Senhor<\/em>. \u00c9 ele quem nos salva da sua pr\u00f3pria ira.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>Traduzido por Annelise Schulz | <a href=\"http:\/\/iprodigo.com\/traducoes\/salvo-do-que.html\" target=\"_blank\">iPr\u00f3digo.com<\/a> | Original\u00a0<a title=\"Texto original aqui\" href=\"http:\/\/www.opc.org\/nh.html?article_id=78\" target=\"_blank\">aqui<\/a><\/em><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>A quest\u00e3o de ser salvo \u00e9 a quest\u00e3o suprema da B\u00edblia. O assunto das Sagradas Escrituras \u00e9 o tema da salva\u00e7\u00e3o.<\/p>\n","protected":false},"author":284,"featured_media":13818,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[480],"class_list":["post-13816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-ligonier","tema-a-expiacaoressurreicao","tema-a-glorificacaocondenacao","tema-ligonier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voc\u00ea foi salvo de qu\u00ea? - R. C. Sproul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voc\u00ea foi salvo de qu\u00ea? - R. C. Sproul\" \/>\n<meta property=\"og:description\" content=\"A quest\u00e3o de ser salvo \u00e9 a quest\u00e3o suprema da B\u00edblia. O assunto das Sagradas Escrituras \u00e9 o tema da salva\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-13T06:02:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-13T16:59:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/08\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R. C. Sproul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"R. C. Sproul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/\"},\"author\":{\"name\":\"R. C. Sproul\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/e4716c5afbd274fd32535531c2cfca98\"},\"headline\":\"Voc\u00ea foi salvo de qu\u00ea? &#8211; R. C. Sproul\",\"datePublished\":\"2013-08-13T06:02:05+00:00\",\"dateModified\":\"2018-11-13T16:59:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/\"},\"wordCount\":608,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1\",\"keywords\":[\"Minist\u00e9rio Ligonier\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/\",\"name\":\"Voc\u00ea foi salvo de qu\u00ea? - R. C. Sproul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1\",\"datePublished\":\"2013-08-13T06:02:05+00:00\",\"dateModified\":\"2018-11-13T16:59:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1\",\"width\":700,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2013\\\/08\\\/voce-foi-salvo-de-que-r-c-sproul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voc\u00ea foi salvo de qu\u00ea? &#8211; R. C. Sproul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/e4716c5afbd274fd32535531c2cfca98\",\"name\":\"R. C. Sproul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"caption\":\"R. C. Sproul\"},\"description\":\"R. C. Sproul nasceu em 1939, no estado da Pensilv\u00e2nia. Foi ministro presbiteriano, pastor da igreja St. Andrews Chapel, na Fl\u00f3rida. Foi fundador e presidente do minist\u00e9rio Ligonier, professor e palestrante em semin\u00e1rios e confer\u00eancias, autor de mais de sessenta livros, v\u00e1rios deles publicados em portugu\u00eas, e editor geral da Reformation Study Bible.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/r-c-sproul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voc\u00ea foi salvo de qu\u00ea? - R. C. Sproul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/","og_locale":"pt_BR","og_type":"article","og_title":"Voc\u00ea foi salvo de qu\u00ea? - R. C. Sproul","og_description":"A quest\u00e3o de ser salvo \u00e9 a quest\u00e3o suprema da B\u00edblia. O assunto das Sagradas Escrituras \u00e9 o tema da salva\u00e7\u00e3o.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2013-08-13T06:02:05+00:00","article_modified_time":"2018-11-13T16:59:44+00:00","og_image":[{"width":700,"height":300,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/08\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1","type":"image\/jpeg"}],"author":"R. C. Sproul","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"R. C. Sproul","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/"},"author":{"name":"R. C. Sproul","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/e4716c5afbd274fd32535531c2cfca98"},"headline":"Voc\u00ea foi salvo de qu\u00ea? &#8211; R. C. Sproul","datePublished":"2013-08-13T06:02:05+00:00","dateModified":"2018-11-13T16:59:44+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/"},"wordCount":608,"commentCount":12,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/08\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1","keywords":["Minist\u00e9rio Ligonier"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/","name":"Voc\u00ea foi salvo de qu\u00ea? - R. C. Sproul","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/08\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1","datePublished":"2013-08-13T06:02:05+00:00","dateModified":"2018-11-13T16:59:44+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/08\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/08\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1","width":700,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2013\/08\/voce-foi-salvo-de-que-r-c-sproul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Voc\u00ea foi salvo de qu\u00ea? &#8211; R. C. Sproul"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/e4716c5afbd274fd32535531c2cfca98","name":"R. C. Sproul","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","caption":"R. C. Sproul"},"description":"R. C. Sproul nasceu em 1939, no estado da Pensilv\u00e2nia. Foi ministro presbiteriano, pastor da igreja St. Andrews Chapel, na Fl\u00f3rida. Foi fundador e presidente do minist\u00e9rio Ligonier, professor e palestrante em semin\u00e1rios e confer\u00eancias, autor de mais de sessenta livros, v\u00e1rios deles publicados em portugu\u00eas, e editor geral da Reformation Study Bible.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/r-c-sproul\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-3AQ","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/08\/sproul-salvo-que.jpg?fit=700%2C300&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/13816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/284"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=13816"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/13816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/13818"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=13816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=13816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=13816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}