{"id":14700,"date":"2014-01-14T00:01:46","date_gmt":"2014-01-14T02:01:46","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=14700"},"modified":"2015-07-07T16:02:51","modified_gmt":"2015-07-07T19:02:51","slug":"uma-paixao-por-santidade-john-piper","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/","title":{"rendered":"Uma Paix\u00e3o por Santidade &#8211; John Piper"},"content":{"rendered":"<p style=\"text-align: justify;\">Tr\u00eas dos seis primeiros oradores principais na Confer\u00eancia de Bethlehem para Pastores disseram que o escritor mais influente em suas vidas (depois dos escritores da B\u00edblia) foi John Owen. JI Packer, Roger Nicole e Sinclair Ferguson colocaram Owen mesmo acima de Jonathan Edwards \u2014 imagine voc\u00ea!<\/p>\n<p style=\"text-align: justify;\">John Owen nasceu em 1616. Ele foi provavelmente o maior pastor-te\u00f3logo entre os puritanos. Como J. I Packer diria, ele foi o mais alto entre as sequ\u00f3ias Puritanas. Seus vinte e tr\u00eas grossos volumes ainda est\u00e3o impressos, formando e alimentando pastores de hoje (como eu).<\/p>\n<p style=\"text-align: justify;\">Ele era um homem de incr\u00edvel atividade\u2014<em>politicamente<\/em>\u00a0(como capel\u00e3o de Oliver Cromwell e orador freq\u00fcente do Parlamento),\u00a0<em>&#8220;denominacionalmente&#8221;<\/em>\u00a0(como o homem chave para todas as controv\u00e9rsias entre puritanos congregacionais e puritanos presbiterianos),<em>teologicamente<\/em>\u00a0(como o principal puritano defensor da verdade calvinista) ,<em>academicamente<\/em>\u00a0(como reitor e vice-chanceler da Universidade de Oxford) ,\u00a0<em>pastoralmente<\/em>(servindo as igrejas e em torno de Londres quase toda a sua vida adulta, mesmo quando era ilegal reunir-se) e\u00a0<em>pessoalmente<\/em>\u00a0(com uma fam\u00edlia de 11 crian\u00e7as, 10 das quais morreram enquanto jovens, seguido pela 11\u00aa, quando ela era uma jovem adulta).<\/p>\n<p style=\"text-align: justify;\">O que me surpreendeu sobre este homem \u00e9 que no meio de toda essa atividade, a sua paix\u00e3o n\u00e3o era atua\u00e7\u00e3o p\u00fablica, mas a santidade pessoal. Ele disse,<\/p>\n<blockquote><p>O desejo do meu cora\u00e7\u00e3o para com Deus e o prop\u00f3sito principal da minha vida&#8230; s\u00e3o que&#8230; a santidade universal possa ser promovida no meu pr\u00f3prio e nos cora\u00e7\u00f5es e caminhos de outros.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Eu preciso de her\u00f3is como este. N\u00e3o muitos l\u00edderes hoje declaram as metas de suas vidas em termos de santidade. E mais e mais l\u00edderes abertamente confessam que sua santidade pessoal n\u00e3o tem significado para a sua atua\u00e7\u00e3o p\u00fablica. Por exemplo, o presidente dos Estados Unidos comunicou claramente que ele n\u00e3o acredita que sua pureza pessoal foi um fator significativo em sua lideran\u00e7a desta na\u00e7\u00e3o. Da mesma forma lemos recentemente: &#8220;Pr\u00edncipe Charles declaradamente j\u00e1 teria acabado de terminar um prolongado caso de adult\u00e9rio com Camilla Parker-Bowles a fim de remover qualquer obst\u00e1culo \u00e0 sua sucess\u00e3o ao trono.&#8221; Ent\u00e3o, em ambos os lados do Atl\u00e2ntico, nossos estadistas dizem com suas vidas: santidade pessoal n\u00e3o \u00e9 grande neg\u00f3cio \u2014 atua\u00e7\u00e3o p\u00fablica e pureza pessoal n\u00e3o est\u00e3o relacionadas.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o \u00e9 assim com Owen. A maravilha, o poder e a beleza de sua vida p\u00fablica foi a const\u00e2ncia de sua comunh\u00e3o pessoal com Deus em pureza e alegria. Um de seus bi\u00f3grafos descreveu assim:<\/p>\n<blockquote><p>Em meio ao barulho da controv\u00e9rsia teol\u00f3gica, as atividades cativantes e desconcertantes de um posto p\u00fablico de alta posi\u00e7\u00e3o, e os des\u00e2nimos depressivos de uma universidade,\u00a0<em>ele ainda estava vivendo perto de Deus<\/em>, e como Jac\u00f3 no meio das pedras da deserto, [ele estava]\u00a0<em>mantendo rela\u00e7\u00f5es secretas com o eterno e invis\u00edvel<\/em>.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Em suas pr\u00f3prias palavras ele deu o segredo para a sua santidade pessoal em meio a todas as press\u00f5es e as dores da vida:<\/p>\n<blockquote><p>Que melhor prepara\u00e7\u00e3o pode haver para o [nosso futuro gozo da gl\u00f3ria de Cristo] do que em uma contempla\u00e7\u00e3o anterior constante desta gl\u00f3ria na revela\u00e7\u00e3o que \u00e9 feita no Evangelho.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">L\u00e1 est\u00e1 a chave para a pureza e santidade, e a chave para a efic\u00e1cia duradoura de toda a vida:\u00a0<em>constante contempla\u00e7\u00e3o da gl\u00f3ria de Cristo<\/em>.<\/p>\n<p style=\"text-align: justify;\">Vindo (a cada hora) para a Pedra Viva,<\/p>\n<p style=\"text-align: justify;\">Pastor John<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>Por<\/strong>\u00a0John Piper \u00a9 Desiring God Foundation. Usado com permiss\u00e3o. Site em ingl\u00eas:\u00a0desiringGod.org\u00a0| Portugu\u00eas:\u00a0<a href=\"http:\/\/www.satisfacaoemdeus.org\/\">satisfacaoemDeus.org<\/a>\u00a0|. Original:\u00a0<a href=\"http:\/\/pt.desiringgod.org\/resource-library\/taste-see-articles\/a-passion-for-holiness\" target=\"_blank\">Uma Paix\u00e3o por Santidade<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Tradu\u00e7\u00e3o<\/strong>:\u00a0<a href=\"http:\/\/voltemosaoevangelho.com\/blog\/\" target=\"_blank\">www.VoltemosAoEvangelho.com<\/a>. Original:\u00a0<a href=\"http:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/\" target=\"_blank\">Uma Paix\u00e3o por Santidade &#8211; John Piper<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Permiss\u00f5es:<\/strong>\u00a0Voc\u00ea est\u00e1 autorizado e incentivado a reproduzir e distribuir este material em qualquer formato, desde que informe o autor, seu minist\u00e9rio e o tradutor, n\u00e3o altere o conte\u00fado original e n\u00e3o o utilize para fins comerciais.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>L\u00e1 est\u00e1 a chave para a pureza e santidade, e a chave para a efic\u00e1cia duradoura de toda a vida: constante contempla\u00e7\u00e3o da gl\u00f3ria de Cristo.<\/p>\n","protected":false},"author":16,"featured_media":14703,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-14700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tema-desiring-god","tema-perseveranca-dos-santos","tema-santificacao-e-crescimento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uma Paix\u00e3o por Santidade - John Piper<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uma Paix\u00e3o por Santidade - John Piper\" \/>\n<meta property=\"og:description\" content=\"L\u00e1 est\u00e1 a chave para a pureza e santidade, e a chave para a efic\u00e1cia duradoura de toda a vida: constante contempla\u00e7\u00e3o da gl\u00f3ria de Cristo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-14T02:01:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-07T19:02:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/12\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John Piper\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Piper\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/\"},\"author\":{\"name\":\"John Piper\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/eccd77fc9d095509088ce03ddc4fe98b\"},\"headline\":\"Uma Paix\u00e3o por Santidade &#8211; John Piper\",\"datePublished\":\"2014-01-14T02:01:46+00:00\",\"dateModified\":\"2015-07-07T19:02:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/\"},\"wordCount\":693,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/\",\"name\":\"Uma Paix\u00e3o por Santidade - John Piper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1\",\"datePublished\":\"2014-01-14T02:01:46+00:00\",\"dateModified\":\"2015-07-07T19:02:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1\",\"width\":700,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/01\\\/uma-paixao-por-santidade-john-piper\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uma Paix\u00e3o por Santidade &#8211; John Piper\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/eccd77fc9d095509088ce03ddc4fe98b\",\"name\":\"John Piper\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g\",\"caption\":\"John Piper\"},\"description\":\"John Piper \u00e9 o fundador e professor do desiringGod.org e chanceler do Bethlehem College &amp; Seminary. Por 33 anos, serviu como pastor da igreja Bethlehem Baptist Church, em Mine\u00e1polis, Minessota. Ele \u00e9 autor de mais de 50 livros, incluindo Em busca de Deus: Medita\u00e7\u00f5es de um hedonista crist\u00e3o e o mais recente Provid\u00eancia.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/john-piper\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uma Paix\u00e3o por Santidade - John Piper","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/","og_locale":"pt_BR","og_type":"article","og_title":"Uma Paix\u00e3o por Santidade - John Piper","og_description":"L\u00e1 est\u00e1 a chave para a pureza e santidade, e a chave para a efic\u00e1cia duradoura de toda a vida: constante contempla\u00e7\u00e3o da gl\u00f3ria de Cristo.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2014-01-14T02:01:46+00:00","article_modified_time":"2015-07-07T19:02:51+00:00","og_image":[{"width":700,"height":300,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/12\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1","type":"image\/jpeg"}],"author":"John Piper","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"John Piper","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/"},"author":{"name":"John Piper","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/eccd77fc9d095509088ce03ddc4fe98b"},"headline":"Uma Paix\u00e3o por Santidade &#8211; John Piper","datePublished":"2014-01-14T02:01:46+00:00","dateModified":"2015-07-07T19:02:51+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/"},"wordCount":693,"commentCount":12,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/12\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/","name":"Uma Paix\u00e3o por Santidade - John Piper","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/12\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1","datePublished":"2014-01-14T02:01:46+00:00","dateModified":"2015-07-07T19:02:51+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/12\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/12\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1","width":700,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/01\/uma-paixao-por-santidade-john-piper\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Uma Paix\u00e3o por Santidade &#8211; John Piper"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/eccd77fc9d095509088ce03ddc4fe98b","name":"John Piper","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g","caption":"John Piper"},"description":"John Piper \u00e9 o fundador e professor do desiringGod.org e chanceler do Bethlehem College &amp; Seminary. Por 33 anos, serviu como pastor da igreja Bethlehem Baptist Church, em Mine\u00e1polis, Minessota. Ele \u00e9 autor de mais de 50 livros, incluindo Em busca de Deus: Medita\u00e7\u00f5es de um hedonista crist\u00e3o e o mais recente Provid\u00eancia.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/john-piper\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-3P6","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2013\/12\/UmaPaixaoPorSantidade.jpg?fit=700%2C300&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/14700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=14700"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/14700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/14703"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=14700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=14700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=14700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}