{"id":16909,"date":"2014-07-14T00:01:23","date_gmt":"2014-07-14T03:01:23","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=16909"},"modified":"2018-11-13T17:43:53","modified_gmt":"2018-11-13T19:43:53","slug":"cristo-e-relevante-para-todo-o-mundo","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/","title":{"rendered":"Cristo \u00e9 Relevante para Todo o Mundo"},"content":{"rendered":"<p>Cristo tem uma miss\u00e3o para n\u00f3s enquanto estamos aqui. Em Jo\u00e3o 17.15 diz &#8220;N\u00e3o pe\u00e7o que os tires do mundo, e sim que os guardes do mal&#8221;. Aprenda mais sobre esse prop\u00f3sito lendo o artigo de R. C. Sproul:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Tenho ficado fascinado com aqueles momentos na vida de Jesus em que o v\u00e9u de sua carne humana deu espa\u00e7o \u00e0 vis\u00e3o de sua gl\u00f3ria refulgente como o Filho de Deus. Como deve ter sido ser um de seus disc\u00edpulos e t\u00ea-lo conhecido como um homem, e ent\u00e3o ver com clareza sua deidade em um encontro de luz ofuscante? O mais espetacular desses encontros foi a sua transfigura\u00e7\u00e3o, aquele momento em que o seu esplendor transcendente paralisou Pedro, Tiago e Jo\u00e3o com temor (Mt 17.1-13). Tudo o que eles queriam naquele momento era se banhar na gl\u00f3ria de Jesus para sempre \u2014 ent\u00e3o foi isso o que eles pediram.<\/p>\n<p style=\"text-align: justify;\">Sempre me chocou o fato de Jesus ter dito n\u00e3o para aquele pedido. Em vez disso, Jesus desceu do Monte da Transfigura\u00e7\u00e3o com seus disc\u00edpulos e voltou para o mundo. A volta de Jesus para o mundo tem servido de modelo para o minist\u00e9rio da igreja at\u00e9 os dias de hoje. Quando Cristo chama pessoas para o seu reino, ele n\u00e3o as tira do mundo para sempre. Ele as envia de volta com o evangelho.<\/p>\n<p style=\"text-align: justify;\">Jesus fez isso com os Ap\u00f3stolos logo ap\u00f3s a sua ressurrei\u00e7\u00e3o. Ele chegou ao cen\u00e1culo, onde eles estavam se escondendo temerosos, e disse que eles deveriam esperar que o Esp\u00edrito fosse derramado. Mas quando isso acontecesse, n\u00e3o deveria haver mais espera. Uma vez que viesse o Esp\u00edrito, eles tinham que sair para o mundo (Lc 24.36-49). E foi isso o que eles fizeram. Os Ap\u00f3stolos chegaram at\u00e9 a pra\u00e7a com a autoridade de Cristo e transtornaram o mundo.<\/p>\n<p style=\"text-align: justify;\">Paulo \u00e9 um modelo de compromisso com o mundo.<\/p>\n<p style=\"text-align: justify;\">[&#8230;] Martinho Lutero pregou que a igreja tinha que se mudar do templo celestial para dentro do mundo.<\/p>\n<p style=\"text-align: justify;\">[&#8230;]\u00a0Ao longo da hist\u00f3ria da igreja, muitos t\u00eam ensinado a ideia do que podemos chamar de \u201csalva\u00e7\u00e3o por separa\u00e7\u00e3o\u201d, crendo que alcan\u00e7aremos a santidade ao evitar contato com pecadores. Contudo, essa doutrina precede o cristianismo, tendo sido inventada pelos fariseus, que se escandalizavam com o minist\u00e9rio de Jesus aos cobradores de impostos, prostitutas e leprosos&#8230;<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Veja o desenvolvimento completo do texto, sobre o modelo de Paulo e Lutero e sobre a mentira que tem sido dita por muitos nas igrejas lendo o artigo completo:<\/p>\n<p style=\"text-align: center;\"><a class=\"btn btn-default btn-sm btn-shortcode\" href=\"http:\/\/fiel.in\/1mNwWcx\" target=\"\" style=\"color:#silver !important;\"> Leia ao artigo completo<\/a><\/p>\n<blockquote><p><span style=\"text-align: justify; line-height: 1.5em;\"><strong><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-16911 alignleft\" src=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/Janeiro2014.jpg?resize=119%2C180\" alt=\"\" width=\"119\" height=\"180\" srcset=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/Janeiro2014.jpg?w=204&amp;ssl=1 204w, https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/Janeiro2014.jpg?resize=198%2C300&amp;ssl=1 198w\" sizes=\"auto, (max-width: 119px) 100vw, 119px\" \/>Por:<\/strong>\u00a0R. C. Sproul.\u00a0Extra\u00eddo do site\u00a0<\/span><a style=\"text-align: justify; line-height: 1.5em;\" href=\"http:\/\/www.ligonier.org\/\" target=\"_blank\">www.ligonier.org<\/a><span style=\"text-align: justify; line-height: 1.5em;\">. \u00a9 2013 Ligonier Ministries. Original:\u00a0<a href=\"http:\/\/www.ligonier.org\/learn\/articles\/world\/\" target=\"_blank\">Into the World<\/a><\/span><\/p>\n<p style=\"text-align: justify;\">Este artigo faz parte da edi\u00e7\u00e3o de Janeiro\u00a0de 2014 da revista\u00a0<a href=\"http:\/\/www.ligonier.org\/tabletalk\/\" target=\"_blank\">Tabletalk<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Tradu\u00e7\u00e3o<\/strong>: Alan Cristie. Revis\u00e3o: Renata do Esp\u00edrito Santo \u2013 \u00a9 Minist\u00e9rio Fiel. Todos os direitos reservados. Website:\u00a0<a href=\"http:\/\/www.ministeriofiel.com.br\" target=\"_blank\">www.MinisterioFiel.com.br<\/a>. Original:\u00a0<a href=\"http:\/\/www.ministeriofiel.com.br\/artigos\/detalhes\/706\/Cristo_e_Relevante_para_Todo_o_Mundo\" target=\"_blank\">Cristo \u00e9 Relevante para Todo o Mundo<\/a><a href=\"http:\/\/www.ministeriofiel.com.br\/artigos\/detalhes\/673\/Fe_ou_Arrependimento_o_que_vem_primeiro\" target=\"_blank\"><br \/>\n<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Permiss\u00f5es<\/strong>: Voc\u00ea est\u00e1 autorizado e incentivado a reproduzir e distribuir este material em qualquer formato, desde que informe o autor, seu minist\u00e9rio e o tradutor, n\u00e3o altere o conte\u00fado original e n\u00e3o o utilize para fins comerciais.<\/p>\n<p style=\"text-align: justify;\"><a class=\"btn btn-default btn-sm btn-shortcode\" href=\"http:\/\/voltemosaoevangelho.com\/blog\/category\/series\/tabletalk\/\" target=\"\" style=\"color:#silver !important;\"> Veja mais artigos desta revista<\/a><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Cristo tem uma miss\u00e3o para n\u00f3s enquanto estamos aqui. Em Jo\u00e3o 17.15 diz &#8220;N\u00e3o pe\u00e7o que os tires do mundo, e sim que os guardes do mal&#8221;. Aprenda mais sobre esse prop\u00f3sito lendo o artigo de R. C. Sproul<\/p>\n","protected":false},"author":284,"featured_media":16910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[480,224],"class_list":["post-16909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-ligonier","tag-tabletalk","tema-evangelizacao-e-missoes","tema-igreja","tema-ligonier","tema-ministerio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cristo \u00e9 Relevante para Todo o Mundo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cristo \u00e9 Relevante para Todo o Mundo\" \/>\n<meta property=\"og:description\" content=\"Cristo tem uma miss\u00e3o para n\u00f3s enquanto estamos aqui. Em Jo\u00e3o 17.15 diz &quot;N\u00e3o pe\u00e7o que os tires do mundo, e sim que os guardes do mal&quot;. Aprenda mais sobre esse prop\u00f3sito lendo o artigo de R. C. Sproul\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-14T03:01:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-13T19:43:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R. C. Sproul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"R. C. Sproul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/\"},\"author\":{\"name\":\"R. C. Sproul\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/e4716c5afbd274fd32535531c2cfca98\"},\"headline\":\"Cristo \u00e9 Relevante para Todo o Mundo\",\"datePublished\":\"2014-07-14T03:01:23+00:00\",\"dateModified\":\"2018-11-13T19:43:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/\"},\"wordCount\":588,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1\",\"keywords\":[\"Minist\u00e9rio Ligonier\",\"Tabletalk\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/\",\"name\":\"Cristo \u00e9 Relevante para Todo o Mundo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1\",\"datePublished\":\"2014-07-14T03:01:23+00:00\",\"dateModified\":\"2018-11-13T19:43:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1\",\"width\":700,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2014\\\/07\\\/cristo-e-relevante-para-todo-o-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cristo \u00e9 Relevante para Todo o Mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/e4716c5afbd274fd32535531c2cfca98\",\"name\":\"R. C. Sproul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/R.-C.-Sproul_avatar_1534174398-96x96.png\",\"caption\":\"R. C. Sproul\"},\"description\":\"R. C. Sproul nasceu em 1939, no estado da Pensilv\u00e2nia. Foi ministro presbiteriano, pastor da igreja St. Andrews Chapel, na Fl\u00f3rida. Foi fundador e presidente do minist\u00e9rio Ligonier, professor e palestrante em semin\u00e1rios e confer\u00eancias, autor de mais de sessenta livros, v\u00e1rios deles publicados em portugu\u00eas, e editor geral da Reformation Study Bible.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/r-c-sproul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cristo \u00e9 Relevante para Todo o Mundo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/","og_locale":"pt_BR","og_type":"article","og_title":"Cristo \u00e9 Relevante para Todo o Mundo","og_description":"Cristo tem uma miss\u00e3o para n\u00f3s enquanto estamos aqui. Em Jo\u00e3o 17.15 diz \"N\u00e3o pe\u00e7o que os tires do mundo, e sim que os guardes do mal\". Aprenda mais sobre esse prop\u00f3sito lendo o artigo de R. C. Sproul","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2014-07-14T03:01:23+00:00","article_modified_time":"2018-11-13T19:43:53+00:00","og_image":[{"width":700,"height":300,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1","type":"image\/jpeg"}],"author":"R. C. Sproul","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"R. C. Sproul","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/"},"author":{"name":"R. C. Sproul","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/e4716c5afbd274fd32535531c2cfca98"},"headline":"Cristo \u00e9 Relevante para Todo o Mundo","datePublished":"2014-07-14T03:01:23+00:00","dateModified":"2018-11-13T19:43:53+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/"},"wordCount":588,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1","keywords":["Minist\u00e9rio Ligonier","Tabletalk"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/","name":"Cristo \u00e9 Relevante para Todo o Mundo","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1","datePublished":"2014-07-14T03:01:23+00:00","dateModified":"2018-11-13T19:43:53+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1","width":700,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2014\/07\/cristo-e-relevante-para-todo-o-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cristo \u00e9 Relevante para Todo o Mundo"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/e4716c5afbd274fd32535531c2cfca98","name":"R. C. Sproul","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/08\/R.-C.-Sproul_avatar_1534174398-96x96.png","caption":"R. C. Sproul"},"description":"R. C. Sproul nasceu em 1939, no estado da Pensilv\u00e2nia. Foi ministro presbiteriano, pastor da igreja St. Andrews Chapel, na Fl\u00f3rida. Foi fundador e presidente do minist\u00e9rio Ligonier, professor e palestrante em semin\u00e1rios e confer\u00eancias, autor de mais de sessenta livros, v\u00e1rios deles publicados em portugu\u00eas, e editor geral da Reformation Study Bible.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/r-c-sproul\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-4oJ","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/07\/CristoERelevanteParaTodoOMundo.jpg?fit=700%2C300&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/16909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/284"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=16909"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/16909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/16910"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=16909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=16909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=16909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}