{"id":1945,"date":"2010-12-23T08:00:00","date_gmt":"2010-12-23T08:00:00","guid":{"rendered":"http:\/\/174.120.239.194\/~volte089\/blog\/?p=1945"},"modified":"2015-07-06T17:46:43","modified_gmt":"2015-07-06T20:46:43","slug":"c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/","title":{"rendered":"C.H.Spurgeon &#8211; A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1973\" title=\"natal\" src=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?resize=500%2C125\" alt=\"\" width=\"500\" height=\"125\" srcset=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?resize=300%2C75&amp;ssl=1 300w, https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?resize=470%2C117&amp;ssl=1 470w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n<div style=\"text-align: justify;\">III. Isso nos leva ao terceiro ponto: PARA QUE VEIO JESUS? Ele veio para ser &#8220;governador em Israel.&#8221; \u00c9 algo muito singular que se dissera de Jesus Cristo que era &#8220;nascido o rei dos judeus.&#8221; Poucos alguma vez &#8220;nasceram reis.&#8221; Alguns homens nascem como pr\u00edncipes, mas \u00e9 coisa rara nascerem como reis. N\u00e3o creio que se encontre algum caso na hist\u00f3ria onde um menino tenha nascido rei. Nasceu como Pr\u00edncipe de Gales, talvez, e teve que esperar anos, at\u00e9 que seu pai morresse, e ent\u00e3o fizessem do herdeiro rei, pondo uma coroa na sua cabe\u00e7a, e uma crisma sagrada, e outras estranhas coisas desse tipo; mas n\u00e3o nasceu rei. N\u00e3o recordo de ningu\u00e9m que tenha nascido rei, exceto Jesus \u2013 e existe um significado enf\u00e1tico nesse verso que cantamos:<\/div>\n<div style=\"text-align: center;\">&#8220;Nascido para libertar Teu povo;<\/div>\n<div style=\"text-align: center;\">Nascido menino, mas, no entanto, rei&#8221;<\/div>\n<div style=\"text-align: justify;\">No instante que veio \u00e0 terra Ele era um rei. N\u00e3o teve que esperar sua maioridade para poder assumir Seu imp\u00e9rio \u2013 mas t\u00e3o pronto como Seu olho saudou a luz do sol, era rei \u2013 desde o instante que Sua pequeninas m\u00e3os tomaram alguma coisa, tomaram um cetro; logo que seu pulso pulsou, e Seu sangue come\u00e7ou a fluir, seu cora\u00e7\u00e3o bradou com batidas reais, e seu pulso pulsou com uma medida imperial, e seu sangue fluiu em uma corrente de realeza. Ele nasceu rei. Veio para &#8220;governar em Israel.&#8221; &#8220;Ah!&#8221; dir\u00e1 algu\u00e9m, &#8220;ent\u00e3o veio em v\u00e3o, pois exerceu muito pouco seu governo, pois &#8216;Veio para o que era seu, e os seus n\u00e3o o receberam,'(Jo\u00e3o 1:11) veio a Israel mas n\u00e3o foi seu Rei, antes foi mais bem &#8216;desprezado, e o mais rejeitado entre os homens&#8217; ( Isaias 53:3) rejeitado por todos eles, e abandonado por Israel, por quem veio.&#8221;<\/div>\n<div style=\"text-align: justify;\">Ai, mas &#8220;nem todos os que s\u00e3o de Israel s\u00e3o israelitas;&#8221; (Romanos 9:6), nem tampouco porque sejam da semente de Abra\u00e3o s\u00e3o todos tamb\u00e9m chamados. Ah, n\u00e3o! Ele n\u00e3o \u00e9 Senhor de Israel segundo a carne, antes que, \u00e9 Senhor de Israel segundo o esp\u00edrito. Muitos lhe obedeceram em seu car\u00e1ter de Senhor. Por acaso os ap\u00f3stolos n\u00e3o se inclinaram diante Ele, e lhe reconheceram como rei? E agora, Israel n\u00e3o o sa\u00fada como seu Senhor? Acaso toda a semente de Abra\u00e3o segundo o esp\u00edrito, todos os crentes, pois ele \u00e9 o &#8220;pai dos crentes,&#8221; n\u00e3o reconhecem que a Cristo pertencem os escudos dos poderosos, pois Ele \u00e9 o Rei de toda a terra? N\u00e3o governa em Israel? Ai sim, Ele verdadeiramente reina; e aqueles que n\u00e3o s\u00e3o governados por Cristo n\u00e3o s\u00e3o de Israel. Ele veio para ser Senhor de Israel.<\/div>\n<div style=\"text-align: justify;\">Meu irm\u00e3o, j\u00e1 se submeteu ao governo de Jesus? \u00c9 Senhor de seu cora\u00e7\u00e3o, ou n\u00e3o? Podemos conhecer a Israel por isso: Cristo veio a seus cora\u00e7\u00f5es, para ser Senhor deles. &#8220;Oh&#8221; dir\u00e1 algu\u00e9m, &#8220;fa\u00e7o o que me d\u00e1 na telha, nunca estive debaixo da servid\u00e3o de ningu\u00e9m.&#8221; Ah! Ent\u00e3o voc\u00ea odeia ao senhorio de Cristo. &#8220;Oh&#8221;, dir\u00e1 outro, &#8220;me submeto a meu ministro, a meu cl\u00e9rigo, a meu sacerdote, e penso que o que me diz \u00e9 suficiente, pois ele \u00e9 meu senhor.&#8221; \u00c9 assim? Ah! Pobre escravo, n\u00e3o conhece sua dignidade; pois ningu\u00e9m \u00e9 seu senhor legal sen\u00e3o o Senhor Jesus Cristo. &#8220;Ai,&#8221; diz outro, &#8220;professei Sua religi\u00e3o, e sou Seu seguidor.&#8221; Mas, governa Ele em seu cora\u00e7\u00e3o? Tem Ele o comando de seu cora\u00e7\u00e3o? Ele guia seu ju\u00edzo? Voc\u00ea busca em Sua m\u00e3o o conselho quando prova dificuldades? Est\u00e1 desejoso de honra-Lhe, e colocar coroas sobre Sua cabe\u00e7a? Ele \u00e9 seu Senhor? Se for assim, ent\u00e3o voc\u00ea \u00e9 um dos de Israel; pois est\u00e1 escrito: &#8220;governar\u00e1 em Israel.&#8221;<\/div>\n<div style=\"text-align: justify;\">Bendito Senhor Jesus! Tu \u00e9s Senhor nos cora\u00e7\u00f5es dos que s\u00e3o Teu povo, e sempre o ser\u00e1s; n\u00e3o queremos outro senhor, salvo a Ti, e n\u00e3o nos submetemos a ningu\u00e9m mais, alem de Ti. Somos livres, posto que somos servos de Cristo; estamos em liberdade, j\u00e1 que Ele \u00e9 nosso Senhor, e n\u00e3o conhecemos nenhuma servid\u00e3o nem alguma escravid\u00e3o, porque somente Jesus Cristo \u00e9 o monarca de nossos cora\u00e7\u00f5es. Ele veio para ser &#8220;Senhor em Israel;&#8221; e atente bem, essa Sua miss\u00e3o n\u00e3o est\u00e1, todavia, terminada, e n\u00e3o o estar\u00e1 at\u00e9 as gl\u00f3rias futuras. Dentre de pouco ver\u00e3o Cristo vir de novo, para ser Senhor sobre Seu povo Israel, e governar sobre eles, n\u00e3o somente como o Israel espiritual, mas tamb\u00e9m como o Israel natural, pois os judeus ser\u00e3o restaurados a sua terra, e as tribos de Jac\u00f3 cantar\u00e3o nas naves de seu templo; a Deus ser\u00e3o oferecidos novamente hinos hebreus de louvor, e o cora\u00e7\u00e3o do judeu incr\u00e9dulo ser\u00e1 derretido aos p\u00e9s do verdadeiro Messias.<\/div>\n<div style=\"text-align: justify;\">Em breve, Aquele que em Seu nascimento foi saudado como rei dos judeus por certos orientais, e de Quem em Sua morte um ocidental escreveu &#8220;Rei dos Judeus&#8221;, ser\u00e1 chamado rei dos judeus em todas as partes; sim, Rei dos judeus e tamb\u00e9m dos gentios; nessa monarquia universal, cujo dom\u00ednio se estender\u00e1 por todo o globo da Terra, e cuja dura\u00e7\u00e3o ser\u00e1 sem tempo. Ele veio para ser Senhor em Israel, e com toda certeza ser\u00e1 Senhor, quando reine gloriosamente em Seu povo, com todos seus antepassados.<\/div>\n<blockquote><p><strong>Por<\/strong> C.H.Spurgeon. <strong>Tradu\u00e7\u00e3o: <\/strong><a href=\"http:\/\/www.projetospurgeon.com.br\/\">projetoSpurgeon.com.br<\/a><br \/>\n<strong>Permiss\u00f5es:<\/strong> Voc\u00ea est\u00e1 autorizado e incentivado a reproduzir e distribuir este material em qualquer formato, desde que adicione as informa\u00e7\u00f5es supracitadas, n\u00e3o altere o conte\u00fado original e n\u00e3o o utilize para fins comerciais.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>III. Isso nos leva ao terceiro ponto: PARA QUE VEIO JESUS? Ele veio para ser &#8220;governador em Israel.&#8221; \u00c9 algo muito singular que se dissera de Jesus Cristo que era &#8220;nascido o rei dos judeus.&#8221; Poucos alguma vez &#8220;nasceram reis.&#8221; Alguns homens nascem como pr\u00edncipes, mas \u00e9 coisa rara nascerem como reis. N\u00e3o creio que [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":1973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tema-a-outros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C.H.Spurgeon - A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C.H.Spurgeon - A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)\" \/>\n<meta property=\"og:description\" content=\"III. Isso nos leva ao terceiro ponto: PARA QUE VEIO JESUS? Ele veio para ser &#8220;governador em Israel.&#8221; \u00c9 algo muito singular que se dissera de Jesus Cristo que era &#8220;nascido o rei dos judeus.&#8221; Poucos alguma vez &#8220;nasceram reis.&#8221; Alguns homens nascem como pr\u00edncipes, mas \u00e9 coisa rara nascerem como reis. N\u00e3o creio que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-23T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-06T20:46:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?fit=500%2C125&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charles H. Spurgeon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles H. Spurgeon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/\"},\"author\":{\"name\":\"Charles H. Spurgeon\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/d75643a609cec5a1afc8b3ba61ab2dd4\"},\"headline\":\"C.H.Spurgeon &#8211; A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)\",\"datePublished\":\"2010-12-23T08:00:00+00:00\",\"dateModified\":\"2015-07-06T20:46:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/\"},\"wordCount\":985,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/natal.jpg?fit=500%2C125&ssl=1\",\"articleSection\":[\"...\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/\",\"name\":\"C.H.Spurgeon - A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/natal.jpg?fit=500%2C125&ssl=1\",\"datePublished\":\"2010-12-23T08:00:00+00:00\",\"dateModified\":\"2015-07-06T20:46:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/natal.jpg?fit=500%2C125&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/natal.jpg?fit=500%2C125&ssl=1\",\"width\":\"500\",\"height\":\"125\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2010\\\/12\\\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C.H.Spurgeon &#8211; A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/d75643a609cec5a1afc8b3ba61ab2dd4\",\"name\":\"Charles H. Spurgeon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Charles-H.-Spurgeon_avatar_1410794045-96x96.jpg\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Charles-H.-Spurgeon_avatar_1410794045-96x96.jpg\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Charles-H.-Spurgeon_avatar_1410794045-96x96.jpg\",\"caption\":\"Charles H. Spurgeon\"},\"description\":\"C. H. Spurgeon (1834-1892) era pregador, autor e editor brit\u00e2nico. Foi pastor do Tabern\u00e1culo Batista Metropolitano, em Londres, desde 1861 at\u00e9 a data de sua morte. Fundou um semin\u00e1rio, um orfanato e editou uma revista mensal chamada \u201cSword and Trowel\u201d. Conhecido como \u201cPr\u00edncipe dos Pregadores\u201d, Spurgeon escreveu muitos livros e artigos, particularmente na \u00e1rea devocional.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/charles-h-spurgeon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C.H.Spurgeon - A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/","og_locale":"pt_BR","og_type":"article","og_title":"C.H.Spurgeon - A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)","og_description":"III. Isso nos leva ao terceiro ponto: PARA QUE VEIO JESUS? Ele veio para ser &#8220;governador em Israel.&#8221; \u00c9 algo muito singular que se dissera de Jesus Cristo que era &#8220;nascido o rei dos judeus.&#8221; Poucos alguma vez &#8220;nasceram reis.&#8221; Alguns homens nascem como pr\u00edncipes, mas \u00e9 coisa rara nascerem como reis. N\u00e3o creio que [&hellip;]","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2010-12-23T08:00:00+00:00","article_modified_time":"2015-07-06T20:46:43+00:00","og_image":[{"width":500,"height":125,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?fit=500%2C125&ssl=1","type":"image\/jpeg"}],"author":"Charles H. Spurgeon","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Charles H. Spurgeon","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/"},"author":{"name":"Charles H. Spurgeon","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/d75643a609cec5a1afc8b3ba61ab2dd4"},"headline":"C.H.Spurgeon &#8211; A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)","datePublished":"2010-12-23T08:00:00+00:00","dateModified":"2015-07-06T20:46:43+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/"},"wordCount":985,"commentCount":1,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?fit=500%2C125&ssl=1","articleSection":["..."],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/","name":"C.H.Spurgeon - A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?fit=500%2C125&ssl=1","datePublished":"2010-12-23T08:00:00+00:00","dateModified":"2015-07-06T20:46:43+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?fit=500%2C125&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?fit=500%2C125&ssl=1","width":"500","height":"125"},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2010\/12\/c-h-spurgeon-a-encarnacao-e-o-nascimento-de-cristo-parte-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"C.H.Spurgeon &#8211; A Encarna\u00e7\u00e3o e o Nascimento de Cristo (parte 3)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/d75643a609cec5a1afc8b3ba61ab2dd4","name":"Charles H. Spurgeon","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Charles-H.-Spurgeon_avatar_1410794045-96x96.jpg","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Charles-H.-Spurgeon_avatar_1410794045-96x96.jpg","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Charles-H.-Spurgeon_avatar_1410794045-96x96.jpg","caption":"Charles H. Spurgeon"},"description":"C. H. Spurgeon (1834-1892) era pregador, autor e editor brit\u00e2nico. Foi pastor do Tabern\u00e1culo Batista Metropolitano, em Londres, desde 1861 at\u00e9 a data de sua morte. Fundou um semin\u00e1rio, um orfanato e editou uma revista mensal chamada \u201cSword and Trowel\u201d. Conhecido como \u201cPr\u00edncipe dos Pregadores\u201d, Spurgeon escreveu muitos livros e artigos, particularmente na \u00e1rea devocional.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/charles-h-spurgeon\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2010\/12\/natal.jpg?fit=500%2C125&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-vn","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/1945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=1945"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/1945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/1973"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=1945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=1945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=1945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}