{"id":31555,"date":"2016-01-25T16:11:50","date_gmt":"2016-01-25T18:11:50","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=31555"},"modified":"2020-02-27T08:47:37","modified_gmt":"2020-02-27T11:47:37","slug":"7-recomendacoes-para-ler-a-biblia-melhor-parte-12","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/","title":{"rendered":"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\/2)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Todos desejamos ler a B\u00edblia melhor. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel. Existem, no entanto, algumas armadilhas e ciladas a serem evitadas, e passaremos nesta s\u00e9ria de dois artigos algumas dicas bem b\u00e1sicas. Ent\u00e3o, o que devemos ter em mente enquanto pensamos em ler a B\u00edblia melhor?<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">A B\u00edblia \u00e9 um livro grande. Para muitas das pessoas com quem trabalhamos na periferia \u00e9 um livro muito grande. Em suas p\u00e1ginas, encontramos muitos tipos diferentes de literatura: poesia, profecia, hist\u00f3ria, narrativa, ep\u00edstolas e escritos apocal\u00edpticos. \u00c9 pesado. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel. N\u00e3o precisamos estudar em um semin\u00e1rio para abrir a B\u00edblia e entend\u00ea-la. Uma B\u00edblia aberta, na m\u00e3o de um leitor \u00e1vido e cheio do Esp\u00edrito, \u00e9 algo poderoso.<\/p>\n<p style=\"text-align: justify;\">Existem, no entanto, algumas armadilhas e ciladas a serem evitadas, e esta s\u00e9ria de dois artigos ir\u00e1 nos passar algumas dicas bem b\u00e1sicas. Ent\u00e3o, o que devemos ter em mente enquanto pensamos em ler e ensinar a B\u00edblia em nossa periferia ou comunidade carente?<\/p>\n<p style=\"text-align: justify;\"><strong>Evite ser superficial.<\/strong> N\u00f3s n\u00e3o podemos simplesmente ler o texto b\u00edblico e pular direto para o que ele significa para n\u00f3s. Precisamos fazer o trabalho duro de interpreta\u00e7\u00e3o. A \u00e9poca e a cultura mudam e precisamos, ent\u00e3o, entender o sentido original do texto ou podemos criar um grande problema. Imagine sua esposa se arrumando pela manh\u00e3 e come\u00e7a aquele t\u00edpico papo de uma hora no banheiro, metade desse tempo arrumando o cabelo. \u201cComo est\u00e1?\u201d \u2013 ela pergunta. Voc\u00ea responde: \u201cBem, minha querida est\u00e1 um pouco parecido com Cantares 4.1: \u2018Os teus cabelos s\u00e3o como o rebanho de cabras\u2019.\u201d N\u00e3o pare a\u00ed. O que voc\u00ea acha de Cantares 7.4b? \u201cO teu nariz, como a torre do L\u00edbano, que olha para Damasco\u201d. Nenhum destes coment\u00e1rios vai receber muito amor. Mas, na cultura do Oriente M\u00e9dio, quanto maior o nariz, maior a beleza e ser comparada com algo t\u00e3o valioso como cabras era um enorme elogio! N\u00f3s temos que ter cuidado para n\u00e3o ler a B\u00edblia superficialmente ou podemos causar (s\u00e9rios) problemas.<\/p>\n<p style=\"text-align: justify;\"><strong>N\u00e3o super-espiritualize a B\u00edblia. <\/strong>1 Samuel 17 \u00e9 o maior exemplo. Todos n\u00f3s conhecemos a hist\u00f3ria. Enquanto o rei Saul e seu ex\u00e9rcito se acovardavam pelo medo, Davi entendeu o desafio de Golias como uma ofensa a Deus e seu povo. Armado com uma funda e cinco pedras lisas, Davi derrubou o gigante e o decapitou, selando seu destino como rei de Israel. Qual foi a aplica\u00e7\u00e3o que ouvi in\u00fameras vezes? Todos n\u00f3s enfrentamos gigantes como Golias em nossas vidas. Quais s\u00e3o alguns dos nossos gigantes? Drogas, div\u00f3rcio, dificuldades, morte e etc. Como podemos \u201cderrotar esses gigantes como Davi fez?\u201d E as cinco pedras lisas? O que elas representam? Que tal, nosso passado (vit\u00f3rias passadas?), ora\u00e7\u00e3o, prioridades (a reputa\u00e7\u00e3o\/gl\u00f3ria de Deus), paix\u00e3o e persist\u00eancia? Apliquemos estes em nossas vidas e venceremos nossos pr\u00f3prios gigantes.<\/p>\n<p style=\"text-align: justify;\">Qual \u00e9 o problema com essa interpreta\u00e7\u00e3o e aplica\u00e7\u00e3o? Bem, para come\u00e7ar, ela nos coloca no lugar de Davi. Ela nos coloca no centro da hist\u00f3ria. Ela nos transforma no her\u00f3i. Mas n\u00f3s n\u00e3o somos o her\u00f3i. Davi \u00e9 o her\u00f3i. Se estiv\u00e9ssemos em algum lugar nessa hist\u00f3ria, estar\u00edamos com o rei Saul e os israelitas acovardados pelo medo de Golias. Na verdade, somos n\u00f3s que precisamos de um her\u00f3i, um campe\u00e3o, um Salvador. Ent\u00e3o, Jesus \u00e9 o verdadeiro her\u00f3i nesse texto. Ele \u00e9 o Filho de Davi, o herdeiro do trono de Davi (\u201cLivro da genealogia de Jesus Cristo, filho de Davi, filho de Abra\u00e3o.\u201d \u2013 \u00a0Mateus 1.1. \u201cEste ser\u00e1 grande e ser\u00e1 chamado Filho do Alt\u00edssimo; Deus, o \u00a0Senhor, lhe dar\u00e1 o trono de Davi, seu pai;\u201d \u2013 Lucas 1.32). Logo, o que temos aqui \u00e9 na realidade uma sombra de Jesus, aquele que derrotou o verdadeiro gigante, a morte, quando enfrentou Satan\u00e1s e morreu na cruz, a fim de que n\u00e3o mais viv\u00eassemos em temor. Esse texto \u00e9 sobre Jesus, n\u00e3o sobre n\u00f3s. Tenha cuidado para n\u00e3o mega-espiritualizar a B\u00edblia em pequenos pontos sobre como devemos viver. A B\u00edblia n\u00e3o \u00e9 sempre, nem em \u00faltima inst\u00e2ncia, um livro sobre n\u00f3s. Ela \u00e9 um livro sobre Ele.<\/p>\n<p style=\"text-align: justify;\"><strong>Tenha cuidado com a linguagem. <\/strong>Palavras mudam de significado. A palavra arm\u00e1rio \u00e9 um bom exemplo. Originalmente significava um lugar onde se guardava armas. Imaginem, ent\u00e3o, quantas palavras variaram ou mudaram de significado em um livro que tem milhares de anos? 1 Cor\u00edntios 4.1, por exemplo, traz a tradu\u00e7\u00e3o \u201cdespenseiros\u201d ou ministros em algumas tradu\u00e7\u00f5es da B\u00edblias, mas o significado literal \u00e9 \u201cescravo\u201d. Paulo queria que seu legado fosse visto como nada mais do que o de um escravo. Isso \u00e9 um pensamento (e uma tradu\u00e7\u00e3o) muito mais forte que meramente um despenseiro ou um ministro quando pensamos no que essas palavras significam hoje.<\/p>\n<p style=\"text-align: justify;\"><strong>Hist\u00f3ria.<\/strong> Por que Pilatos permitiu que o judeus matassem Jesus quando sabia que ele era inocente? Ele certamente n\u00e3o era amigo do povo judeu? A hist\u00f3ria pode nos ajudar aqui. Est\u00e1 bem documentado que Pilatos odiava ter sido designado para Israel. N\u00f3s lemos em livros de hist\u00f3ria que, quando Pilatos chegou a seu posto, ele tentou for\u00e7ar os judeus a adorar divindades pag\u00e3s. Mas ele acabou se vendo com uma grande revolta em suas m\u00e3os. Muitas pessoas perderam suas vidas antes que a ordem fosse restaurada. Seu chefe, o imperador, ficou com tanta raiva dele que amea\u00e7ou tir\u00e1-lo da fun\u00e7\u00e3o caso n\u00e3o conseguisse manter a paz. Ent\u00e3o Pilatos fazia o que podia para manter os l\u00edderes judeus felizes e para impedir que ele perdesse seu emprego e seu status na sociedade.<\/p>\n<\/blockquote>\n<p>[\/vc_column_text]<div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_call_to_action wpb_content_element vc_cta_btn_pos_right vc_cta_blue vc_cta_square_outlined vc_txt_align_center\"><\/p>\n<h2 style=\"text-align: left;\">Leia o Artigo Completo<\/h2>\n<p style=\"text-align: left;\">Veja a conclus\u00e3o do texto lendo o artigo completo<\/p>\n<p><a class=\"btn btn-default btn-md btn-red\" style=\"color: #fff; background-color:red\" href=\"http:\/\/bit.ly\/1RJ1CuH\" target=\"_blank\">Clique aqui e leia o artigo completo<\/a><\/div><div class=\"vc_empty_space\" style=\"line-height: 30px; height: 30px;\"><span class=\"vc_empty_space_inner\"><\/span><\/div>[vc_message color=&#8221;alert-danger&#8221; style=&#8221;square_outlined&#8221; el_class=&#8221;creditos_box&#8221;]<\/p>\n<p style=\"text-align: left;\"><strong>Por:<\/strong> Mez McConnell.\u00a0\u00a9 2015 20schemes. Original:\u00a0<a href=\"http:\/\/bit.ly\/1OK7QXB\" target=\"_blank\" rel=\"noopener noreferrer\">Can We Read &amp; Understand The Bible If We\u2019re Not Experts? (1)<\/a>.<\/p>\n<p style=\"text-align: left;\"><strong>Tradu\u00e7\u00e3o<\/strong>: Fabio Luciano. <strong>Revis\u00e3o:<\/strong> Vin\u00edcius Musselman Pimentel. \u00a9 2014\u00a0Minist\u00e9rio Fiel. Todos os direitos reservados. Website:\u00a0<a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">MinisterioFiel.com.br<\/a>. Original: <a href=\"http:\/\/bit.ly\/1RJ1CuH\" target=\"_blank\" rel=\"noopener noreferrer\">Podemos Compreender a B\u00edblia se n\u00e3o Somos Experts? (parte 1\/2)<\/a>.<\/p>\n<p>[\/vc_message][vc_column_text]<\/p>\n<p><a href=\"http:\/\/bit.ly\/1ZNNGyW\" target=\"_blank\" rel=\"attachment noopener wp-att-31560 noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-31560\" src=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/20Schemes-footer-ve.jpg?resize=890%2C116\" alt=\"20Schemes-footer-ve\" width=\"890\" height=\"116\" srcset=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/20Schemes-footer-ve.jpg?w=890&amp;ssl=1 890w, https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/20Schemes-footer-ve.jpg?resize=300%2C39&amp;ssl=1 300w, https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/20Schemes-footer-ve.jpg?resize=768%2C100&amp;ssl=1 768w, https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/20Schemes-footer-ve.jpg?resize=610%2C80&amp;ssl=1 610w\" sizes=\"auto, (max-width: 890px) 100vw, 890px\" \/><\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Todos desejamos ler a B\u00edblia melhor. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel.<\/p>\n","protected":false},"author":422,"featured_media":31557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[897],"class_list":["post-31555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-igreja-para-a-periferia-20schemes","tema-20schemes","tema-a-leitura-biblica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\/2)<\/title>\n<meta name=\"description\" content=\"Todos desejamos ler a B\u00edblia melhor. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\/2)\" \/>\n<meta property=\"og:description\" content=\"Todos desejamos ler a B\u00edblia melhor. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-25T18:11:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-27T11:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mez McConnell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mez McConnell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/\"},\"author\":{\"name\":\"Mez McConnell\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/16ed25e9425ec13faec54df31da35da1\"},\"headline\":\"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\\\/2)\",\"datePublished\":\"2016-01-25T18:11:50+00:00\",\"dateModified\":\"2020-02-27T11:47:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/\"},\"wordCount\":1166,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1\",\"keywords\":[\"Igreja para a Periferia - 20schemes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/\",\"name\":\"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\\\/2)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2016-01-25T18:11:50+00:00\",\"dateModified\":\"2020-02-27T11:47:37+00:00\",\"description\":\"Todos desejamos ler a B\u00edblia melhor. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2016\\\/01\\\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\\\/2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/16ed25e9425ec13faec54df31da35da1\",\"name\":\"Mez McConnell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"caption\":\"Mez McConnell\"},\"description\":\"\u00c9 pastor s\u00eanior da Niddrie Community Church, Edimburgo, Esc\u00f3cia. \u00c9 fundador do 20schemes, um minist\u00e9rio voltado para planta\u00e7\u00e3o de igrejas nos lugares mais dif\u00edceis da Esc\u00f3cia. Desde 1999, McConnell tem se envolvido com o minist\u00e9rio pastoral, tanto em planta\u00e7\u00e3o quanto revitaliza\u00e7\u00e3o.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/mez-mcconnell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\/2)","description":"Todos desejamos ler a B\u00edblia melhor. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/","og_locale":"pt_BR","og_type":"article","og_title":"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\/2)","og_description":"Todos desejamos ler a B\u00edblia melhor. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2016-01-25T18:11:50+00:00","article_modified_time":"2020-02-27T11:47:37+00:00","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"author":"Mez McConnell","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Mez McConnell","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/"},"author":{"name":"Mez McConnell","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/16ed25e9425ec13faec54df31da35da1"},"headline":"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\/2)","datePublished":"2016-01-25T18:11:50+00:00","dateModified":"2020-02-27T11:47:37+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/"},"wordCount":1166,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1","keywords":["Igreja para a Periferia - 20schemes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/","name":"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\/2)","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1","datePublished":"2016-01-25T18:11:50+00:00","dateModified":"2020-02-27T11:47:37+00:00","description":"Todos desejamos ler a B\u00edblia melhor. Entend\u00ea-la corretamente n\u00e3o \u00e9 f\u00e1cil, mas certamente n\u00e3o \u00e9 imposs\u00edvel.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2016\/01\/7-recomendacoes-para-ler-a-biblia-melhor-parte-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"7 recomenda\u00e7\u00f5es para ler a B\u00edblia melhor (parte 1\/2)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/16ed25e9425ec13faec54df31da35da1","name":"Mez McConnell","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","caption":"Mez McConnell"},"description":"\u00c9 pastor s\u00eanior da Niddrie Community Church, Edimburgo, Esc\u00f3cia. \u00c9 fundador do 20schemes, um minist\u00e9rio voltado para planta\u00e7\u00e3o de igrejas nos lugares mais dif\u00edceis da Esc\u00f3cia. Desde 1999, McConnell tem se envolvido com o minist\u00e9rio pastoral, tanto em planta\u00e7\u00e3o quanto revitaliza\u00e7\u00e3o.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/mez-mcconnell\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2016\/01\/7-recomendacoes-para-ler-a-biblia.jpg?fit=890%2C381&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-8cX","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/31555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/422"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=31555"}],"version-history":[{"count":1,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/31555\/revisions"}],"predecessor-version":[{"id":52598,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/31555\/revisions\/52598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/31557"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=31555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=31555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=31555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}