{"id":41668,"date":"2018-01-11T00:05:54","date_gmt":"2018-01-11T02:05:54","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=41668"},"modified":"2020-08-18T20:12:16","modified_gmt":"2020-08-18T23:12:16","slug":"quando-alguem-amado-vai-para-jesus","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/","title":{"rendered":"Quando algu\u00e9m amado vai para Jesus"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Mais cedo ou mais tarde todos teremos que enfrentar a morte de algu\u00e9m querido. Crist\u00e3os se deparam com essa realidade mais do que os outros porque pertencemos a uma fam\u00edlia maior: a igreja. No corpo de Cristo, Deus nos aben\u00e7oa com muitos irm\u00e3os, irm\u00e3s, pais e m\u00e3es \u2013 todos queridos e amados cujo v\u00ednculo espiritual conosco nunca ser\u00e1 cortado (Marcos 3.31-35).<\/p>\n<p>Todos n\u00f3s temos que contar com a morte. Algum dia todos vamos confrontar nosso pr\u00f3prio fim, mas ao longo do caminho vamos tamb\u00e9m testemunhar amigos amados e fam\u00edlia partirem desta vida para a pr\u00f3xima. A morte \u00e9 um inimigo real \u2013 um inimigo aterrador. \u201cO \u00faltimo inimigo a ser destru\u00eddo \u00e9 a morte.\u201d (1 Cor\u00edntios 15.26).<\/p>\n<p>Eu vi pessoas morrerem na minha frente. Eu perdi amigos, jovens e velhos. A morte \u00e9 sempre feia. A morte sempre traz sofrimento. E n\u00e3o h\u00e1 nada de errado em entristecer-se diante da morte. O pr\u00f3prio Jesus chorou diante da morte de seu amigo L\u00e1zaro (Jo\u00e3o 11.35). Deus nos criou de tal forma que a morte \u00e9 antinatural para n\u00f3s. Fomos feitos para viver.<\/p>\n<p>Mas quando perdemos algu\u00e9m amado que \u00e9 um crente, precisamos nos lembrar de uma verdade importante que ir\u00e1 nos ajudar a lidar com a perda. A tristeza certamente vai nos atingir, mas pela gra\u00e7a de Deus, o sofrimento n\u00e3o vai nos derrotar. Esta verdade vai ao cora\u00e7\u00e3o da f\u00e9 crist\u00e3 e nos oferece discernimento quanto \u00e0 pessoa de Cristo, o Deus-homem.<\/p>\n<h3>Jesus quer voc\u00ea<\/h3>\n<p>Em Jo\u00e3o 17.24, lemos palavras que, em uma reflex\u00e3o cuidadosa e cheia de ora\u00e7\u00e3o, deveriam estar em nossos cora\u00e7\u00f5es quando algu\u00e9m amado morre. Considere cuidadosamente a linguagem:<\/p>\n<p><i>Pai, a minha vontade \u00e9 que onde eu estou, estejam tamb\u00e9m comigo os que me deste, para que vejam a minha gl\u00f3ria que me conferiste, porque me amaste antes da funda\u00e7\u00e3o do mundo.<\/i><\/p>\n<p>Como um homem, Jesus tem certos desejos. Ele tinha desejos na terra, e ele ainda tem desejos no c\u00e9u. Aqui, Jesus tem um desejo que ele faz conhecido ao Pai. Ele fala, como ele frequentemente fez antes, daqueles que o Pai lhe deu (veja Jo\u00e3o 6.37, 39; 10.29; 17.6,9). Aqueles que o Pai deu a Cristo s\u00e3o as pr\u00f3prias ovelhas por quem o Bom Pastor d\u00e1 a vida (Jo\u00e3o 10.11). Jesus ora ao Pai por suas amadas ovelhas na Ora\u00e7\u00e3o Sacerdotal de Jo\u00e3o 17, e ele continua a interceder por elas at\u00e9 o dia de hoje (Romanos 8.34).<\/p>\n<p>E o que Jesus deseja?<\/p>\n<p>Ele deseja que o seu povo esteja com ele. Jesus \u00e9 completamente feliz e satisfeito reinando do c\u00e9u, mas de acordo com sua ora\u00e7\u00e3o em Jo\u00e3o 17, ele ainda tem um certo desejo n\u00e3o atendido: que seu povo esteja com ele no lar que ele j\u00e1 preparou para eles (Jo\u00e3o 14.2-4).<\/p>\n<h3>N\u00f3s podemos perder, mas Jesus ganha<\/h3>\n<p>Quando um irm\u00e3o ou irm\u00e3 no Senhor morre, devemos lembrar primeiro e principalmente que o Pai respondeu a ora\u00e7\u00e3o de Jesus. Deus \u00e9 soberano sobre as mortes de nossos amados, e ele tem prop\u00f3sitos que n\u00f3s podemos nunca compreender (Deuteron\u00f4mio 32.39, Tiago 4.15), mas podemos nos agarrar \u00e0 verdade de que Jesus orou ao seu Pai para trazer seu povo para casa. Quando um crente morre, o Pai est\u00e1 atendendo o pedido que seu Filho fez quando orou, mais ou menos dois mil anos atr\u00e1s, na noite anterior \u00e0 entrega de sua vida por seu povo.<\/p>\n<p>Podemos pelo menos dizer isso:\u00a0<i>Quando algu\u00e9m amado se vai, Jesus ganha muito mais do que n\u00f3s perdemos.<\/i><\/p>\n<p>Sim, n\u00f3s perdemos. N\u00f3s nunca mais vamos compartilhar daquela doce comunh\u00e3o com nosso irm\u00e3o ou irm\u00e3 nesta vida. A magnitude da perda facilmente frustra nossas palavras. Mas a perda nunca vai al\u00e9m das palavras de Jesus: \u201cPai, eu desejo que eles tamb\u00e9m, os que tu me deste, estejam comigo para que vejam a minha gl\u00f3ria\u2026\u201d.<\/p>\n<h3>Alegria eterna al\u00e9m do t\u00famulo<\/h3>\n<p>Jesus sabe que tem uma gl\u00f3ria que vai muito al\u00e9m do que qualquer coisa que esse mundo possa oferecer. Ele sabe que um verdadeiro vislumbre dele vale mais do que milh\u00f5es de mundos. Ele sabe que a vis\u00e3o de sua gl\u00f3ria n\u00e3o vai deixar ningu\u00e9m insatisfeito. Jesus quer que seus preciosos santos entre na verdadeira e eterna felicidade com ele.<\/p>\n<p>N\u00f3s certamente experimentamos muitas alegrias nesta vida, mas nada pode ser comparado ao puro deleite da comunh\u00e3o sem barreiras com Jesus. Somos destinados a uma alegria indiz\u00edvel em sua presen\u00e7a.<\/p>\n<h3>Uma resposta \u00e0 ora\u00e7\u00e3o<\/h3>\n<p>Quando voc\u00ea perde algu\u00e9m amado no Senhor para o Senhor, voc\u00ea realmente perde \u2013 pelo menos por enquanto. Mas aquele irm\u00e3o ou irm\u00e3 ganha, assim como Jesus (Filipenses 2.20-23). N\u00f3s podemos derramar l\u00e1grimas o suficiente para encher baldes, mas a corrente de l\u00e1grimas correndo por nossas bochechas v\u00e3o reluzir de alegria quanto percebermos que a morte de nossos amados n\u00e3o \u00e9 nada menos do que uma resposta \u00e0 ora\u00e7\u00e3o de Jesus.<\/p>\n<p>A morte de algu\u00e9m amado no Senhor pode trazer um dos maiores testes \u00e0 nossa f\u00e9. Mas podemos confiar que nosso amado est\u00e1 melhor l\u00e1 com o Amado? Vamos crer que o Filho de Deus est\u00e1 colhendo os frutos de seu trabalho pelos pecadores? Se cremos, ent\u00e3o nossa tristeza \u00e9 uma tristeza piedosa, e Jesus vai converter nossa tristeza em alegria (Jo\u00e3o 16.20).<\/p>\n<p>\u201cPreciosa \u00e9 aos olhos do SENHOR a morte dos seus santos.\u201d (Salmo 116.15), e pode ser preciosa para n\u00f3s tamb\u00e9m quando nos agarramos \u00e0 esperan\u00e7a de que a morte nunca ir\u00e1 vencer (1 Cor\u00edntios 15.54-55). Jesus se entristeceu para que n\u00f3s nunca tiv\u00e9ssemos que enfrentar uma tristeza sem esperan\u00e7a em face da morte.<\/p>\n<p>No final, a morte \u00e9 apenas uma resposta \u00e0 ora\u00e7\u00e3o de Jesus.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por:\u00a0Mark Jones.\u00a0\u00a9 Desiring God. Website: <a href=\"https:\/\/www.desiringgod.org\" target=\"_blank\" rel=\"noopener noreferrer\">desiringgod.org<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/www.desiringgod.org\/articles\/when-a-loved-one-goes-home-to-jesus\" target=\"_blank\" rel=\"noopener noreferrer\">When a Loved One Goes Home to Jesus<\/a>.<\/p>\n<p>Original: <a href=\"http:\/\/reforma21.org\/artigos\/quando-alguem-amado-vai-para-jesus.html\" target=\"_blank\" rel=\"noopener noreferrer\">Quando algu\u00e9m amado vai para Jesus<\/a>. \u00a9 Minist\u00e9rio Fiel. Website: <a href=\"https:\/\/www.ministeriofiel.com.br\" target=\"_blank\" rel=\"noopener noreferrer\">ministeriofiel.com.br<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Daniel TC.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Quando um irm\u00e3o ou irm\u00e3 no Senhor morre, devemos lembrar primeiro e principalmente que o Pai respondeu a ora\u00e7\u00e3o de Jesus.<\/p>\n","protected":false},"author":432,"featured_media":54000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[592],"class_list":["post-41668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-desiring-god","tema-esperanca","tema-esperanca-dup","tema-luto","tema-morte","tema-morte-dup","tema-a-oracao","tema-oracao","tema-sofrimento","tema-sofrimento-dup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quando algu\u00e9m amado vai para Jesus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando algu\u00e9m amado vai para Jesus\" \/>\n<meta property=\"og:description\" content=\"Quando um irm\u00e3o ou irm\u00e3 no Senhor morre, devemos lembrar primeiro e principalmente que o Pai respondeu a ora\u00e7\u00e3o de Jesus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-11T02:05:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-18T23:12:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/01\/Quando-algue\u0301m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mark Jones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mark Jones\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/\"},\"author\":{\"name\":\"Mark Jones\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/798107cac82eb1bf8861845c878eb6fa\"},\"headline\":\"Quando algu\u00e9m amado vai para Jesus\",\"datePublished\":\"2018-01-11T02:05:54+00:00\",\"dateModified\":\"2020-08-18T23:12:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/\"},\"wordCount\":1081,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"Desiring God Portugu\u00eas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/\",\"name\":\"Quando algu\u00e9m amado vai para Jesus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2018-01-11T02:05:54+00:00\",\"dateModified\":\"2020-08-18T23:12:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/01\\\/quando-alguem-amado-vai-para-jesus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quando algu\u00e9m amado vai para Jesus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/798107cac82eb1bf8861845c878eb6fa\",\"name\":\"Mark Jones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Mark-Jones_avatar_1521634784-96x96.jpg\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Mark-Jones_avatar_1521634784-96x96.jpg\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Mark-Jones_avatar_1521634784-96x96.jpg\",\"caption\":\"Mark Jones\"},\"description\":\"\u00c9 ministro na igreja Faith Presbyterian Church, em Vancouver, British Columbia, Canad\u00e1, igreja afiliada \u00e0 Presbyterian Church of America (PCA). \u00c9 tamb\u00e9m pesquisador adjunto da Faculty of Theology da University of the Free State, em Bloemfontein, na \u00c1frica do Sul.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/mark-jones\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando algu\u00e9m amado vai para Jesus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/","og_locale":"pt_BR","og_type":"article","og_title":"Quando algu\u00e9m amado vai para Jesus","og_description":"Quando um irm\u00e3o ou irm\u00e3 no Senhor morre, devemos lembrar primeiro e principalmente que o Pai respondeu a ora\u00e7\u00e3o de Jesus.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2018-01-11T02:05:54+00:00","article_modified_time":"2020-08-18T23:12:16+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/01\/Quando-algue\u0301m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Mark Jones","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Mark Jones","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/"},"author":{"name":"Mark Jones","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/798107cac82eb1bf8861845c878eb6fa"},"headline":"Quando algu\u00e9m amado vai para Jesus","datePublished":"2018-01-11T02:05:54+00:00","dateModified":"2020-08-18T23:12:16+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/"},"wordCount":1081,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/01\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1","keywords":["Desiring God Portugu\u00eas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/","name":"Quando algu\u00e9m amado vai para Jesus","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/01\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1","datePublished":"2018-01-11T02:05:54+00:00","dateModified":"2020-08-18T23:12:16+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/01\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/01\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/01\/quando-alguem-amado-vai-para-jesus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quando algu\u00e9m amado vai para Jesus"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/798107cac82eb1bf8861845c878eb6fa","name":"Mark Jones","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/Mark-Jones_avatar_1521634784-96x96.jpg","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/Mark-Jones_avatar_1521634784-96x96.jpg","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/Mark-Jones_avatar_1521634784-96x96.jpg","caption":"Mark Jones"},"description":"\u00c9 ministro na igreja Faith Presbyterian Church, em Vancouver, British Columbia, Canad\u00e1, igreja afiliada \u00e0 Presbyterian Church of America (PCA). \u00c9 tamb\u00e9m pesquisador adjunto da Faculty of Theology da University of the Free State, em Bloemfontein, na \u00c1frica do Sul.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/mark-jones\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-aQ4","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/01\/Quando-algue%CC%81m-amado-vai-para-Jesus.jpg?fit=750%2C395&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/41668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/432"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=41668"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/41668\/revisions"}],"predecessor-version":[{"id":54017,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/41668\/revisions\/54017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/54000"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=41668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=41668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=41668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}