{"id":42722,"date":"2018-03-23T00:10:09","date_gmt":"2018-03-23T03:10:09","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=42722"},"modified":"2025-12-17T17:18:58","modified_gmt":"2025-12-17T20:18:58","slug":"o-nome-de-deus-uma-animacao","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/","title":{"rendered":"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Agora, n\u00f3s do Voltemos ao Evangelho estamos em parceria com o Full of Eyes, um projeto que existe pra proclamar em forma visual a gl\u00f3ria de Deus em Cristo como ensinado nas Escrituras. Atrav\u00e9s do blog\u00a0<span class=\"highlightNode\">Voltemos ao Evangelho<\/span>, voc\u00ea poder\u00e1 encontrar os recursos do\u00a0<span class=\"highlightNode\">Full\u00a0<\/span><span class=\"highlightNode\">of\u00a0<\/span><span class=\"highlightNode\">Eyes<\/span>, como imagens, artigo\u00a0<span class=\"highlightNode\">e<\/span>\u00a0v\u00eddeos, que ser\u00e3o disponibilizados em portugu\u00eas por n\u00f3s.<\/p>\n<p>Mais um recurso \u00e0 servi\u00e7o da igreja de fala portuguesa![\/vc_column_text][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=B_VmsD8z8MM&#8221; title=&#8221;Assista ao v\u00eddeo:&#8221;][vc_empty_space height=&#8221;30px&#8221;][vc_column_text]<\/p>\n<h2>Mostra-me a tua gl\u00f3ria<\/h2>\n<p>Em \u00caxodo 33.18, Mois\u00e9s pede para ver a gl\u00f3ria de Deus e ele responde dizendo que revelar\u00e1 a Mois\u00e9s o seu nome. Nas escrituras, um nome \u00e9 muito mais do que um modo de se referir a algu\u00e9m. Antes, um nome tem a inten\u00e7\u00e3o de expressar algo essencial sobre o seu detentor, como um resumo da identidade de algu\u00e9m. Assim, quando Deus proclama o seu nome no cap\u00edtulo seguinte (34.6-7), ele est\u00e1 de fato revelando o seu car\u00e1ter a Mois\u00e9s (e a n\u00f3s), ele est\u00e1 apresentando a sua identidade, ele est\u00e1 mostrando ao seu povo quem ele \u00e9. \u00c9 impressionante que esta seja a resposta de Deus ao pedido para ver a sua gl\u00f3ria. O que \u00e9 a gl\u00f3ria de Deus? Segundo \u00caxodo 33-34 \u00e9 a proclama\u00e7\u00e3o do nome de Deus, a revela\u00e7\u00e3o de sua identidade, sua beleza interior comunicada exteriormente, \u00e9 Deus feito conhecido.<\/p>\n<p>Mas enquanto ele proclamava a sua identidade a Mois\u00e9s, o pr\u00f3prio YHWH passaria, e o esplendor de sua presen\u00e7a teria destru\u00eddo Mois\u00e9s (Ex.20). Assim, para que Mois\u00e9s pudesse se regozijar em vez de ser destru\u00eddo pela gl\u00f3ria de Deus, YHWH coloca Mois\u00e9s na \u201cfenda da penha\u201d e cobre o profeta com a m\u00e3o (v. 22). Bem, isso \u00e9 significativo por pelo menos quatro raz\u00f5es.<\/p>\n<h2>Quatro coisas a serem observadas<\/h2>\n<p>Em primeiro lugar, Deus \u00e9 frequentemente referido nas escrituras como a rocha e ref\u00fagio do seu povo (Dt. 32.4,15,18; Sl. 18.2, 57.1, 61.2-3, etc.). Nenhuma palavra ou situa\u00e7\u00e3o na B\u00edblia \u00e9 sem prop\u00f3sito, e por isso n\u00e3o devemos pensar que \u00e9 uma coincid\u00eancia que Mois\u00e9s se refugie em uma rocha. N\u00e3o creio que possamos ler este relato \u00e0 luz de toda a escritura, sem lembrarmos que o pr\u00f3prio Deus \u00e9 t\u00e3o frequentemente a rocha do nosso ref\u00fagio.<\/p>\n<p>Em segundo lugar, deve ser observado que uma \u201cfenda\u201d em uma rocha \u00e9 algo como uma fissura, rachadura ou greta. Mois\u00e9s \u00e9 escondido em uma rocha que foi quebrada; trata-se de uma rocha ferida. E mais que isso, ele \u00e9 escondido na fenda da rocha. Aqui vemos Mois\u00e9s se refugiando da presen\u00e7a destruidora de Deus na ferida de uma rocha&#8230; ecos do Calv\u00e1rio devem come\u00e7ar a preencher as nossas mentes.<\/p>\n<p>Em terceiro lugar, h\u00e1 pelo menos alguma raz\u00e3o para crer que a rocha em que Mois\u00e9s est\u00e1 escondido \u00e9, na verdade, a rocha que foi ferida e da qual fluiu \u00e1gua em \u00caxodo 17. Antes de prosseguir, preciso ressaltar que devo ao meu colega seminarista John Supica a maioria das ideias a seguir.<\/p>\n<p>Em \u00caxodo 17.6 lemos que a rocha que Mois\u00e9s feriu estava \u201cem Horebe\u201d, e muitos creem que Horebe \u00e9 outro nome para o Sinai. Sabemos que quando a rocha foi ferida, ela se abriu para que \u00e1gua jorrasse como um rio (Sl. 105.41, Is. 48.21), o que significa que deve ter havido pelo menos algum tipo de fissura nela. N\u00e3o poderia ser esta mesma fenda \u2014 a mesma \u201cferida\u201d \u2014 em que Mois\u00e9s \u00e9 colocado por Deus para que n\u00e3o pere\u00e7a? Se este for o caso, ent\u00e3o temos a garantia de ver figuras cristol\u00f3gicas neste evento por duas raz\u00f5es. Primeiramente, Paulo nos diz que a rocha ferida no deserto era um tipo de Cristo (1 Cor.10.4). E, em segundo lugar, a hist\u00f3ria da ferida da rocha em \u00caxodo 17 \u00e9 apresentada de forma muito intencional como um ato de entrega substitutiva do pr\u00f3prio YHWH (a explica\u00e7\u00e3o completa desse evento, no entanto, \u00e9 tema para outro artigo \u2014 talvez pelo pr\u00f3prio John Supica). Sem d\u00favida, \u00caxodo 17 prenuncia a obra de Cristo na cruz; e, como eu j\u00e1 disse, h\u00e1 evid\u00eancias para crer que a rocha de \u00caxodo 17 \u00e9 a mesma em cuja ferida Mois\u00e9s se refugia em \u00caxodo 33.<\/p>\n<p>Em quarto lugar, observe que YHWH cobre Mois\u00e9s com a sua m\u00e3o. \u00c9 claro que esta \u00e9 uma linguagem antropom\u00f3rfica j\u00e1 que antes da encarna\u00e7\u00e3o do Filho na hist\u00f3ria humana, Deus n\u00e3o tinha corpo. Contudo, o uso de figuras referentes a \u201cm\u00e3o\u201d n\u00e3o \u00e9 insignificante. Muitas vezes, a \u201cm\u00e3o\u201d de Deus \u00e9 sin\u00f4nimo de sua for\u00e7a salvadora e preservadora em rela\u00e7\u00e3o ao seu povo (Ex.15.6; Sl.17.7, 60.5, 63.8; Is.41.10). Esta figura atinge o seu cl\u00edmax na cruz, onde a m\u00e3o de YHWH encarnado, Deus o Filho, \u00e9 estendida e erguida no supremo ato de reden\u00e7\u00e3o. N\u00e3o acho que podemos ler um texto sobre a m\u00e3o de Deus operando para salvar aqueles que lhe pertencem (ou, neste caso, cobri-los da destrui\u00e7\u00e3o) sem ver \u2014 como Tom\u00e9 \u2014 as m\u00e3os de nosso Senhor e nosso Deus \u2014 feridas para salvar o seu povo.<\/p>\n<p>Deus coloca Mois\u00e9s na ferida de uma rocha doadora de vida e cobre-o com a sua m\u00e3o, para que o profeta desfrute da gl\u00f3ria de Deus e n\u00e3o seja destru\u00eddo por ela. A prepara\u00e7\u00e3o de Deus para declarar a sua gl\u00f3ria a Mois\u00e9s \u00e9 rica em figuras cristol\u00f3gicas. E devemos ter isso em mente quando nos voltamos para o cap\u00edtulo 34 e vemos YHWH fazer a proclama\u00e7\u00e3o definitiva do Antigo Testamento a respeito de sua identidade \u2014 seu nome \u2014 a Mois\u00e9s.<\/p>\n<h2>O nome declarado no Sinai<\/h2>\n<p>\u201cYHWH, YHWH, Deus compassivo, clemente e long\u00e2nimo e grande em miseric\u00f3rdia e fidelidade; que guarda a miseric\u00f3rdia em mil gera\u00e7\u00f5es, que perdoa a iniquidade, a transgress\u00e3o e o pecado, ainda que n\u00e3o inocenta o culpado&#8230;\u201d. (Ex. 34.6-7)<\/p>\n<p>O nome de Deus proclamado em \u00caxodo 34.6-7 \u00e9 paradigm\u00e1tico de como o povo de Deus o percebe em todo o restante das escrituras. Embora muito \u2014 na verdade, infinito \u2014 pudesse ser dito sobre isso, neste artigo eu simplesmente desejo observar a descri\u00e7\u00e3o da caracter\u00edstica central: \u201c&#8230; grande em miseric\u00f3rdia e fidelidade\u201d.<\/p>\n<p>\u00c0 medida que a hist\u00f3ria da reden\u00e7\u00e3o revelat\u00f3ria de Deus continua, essas duas palavras parecem formar uma esp\u00e9cie de refer\u00eancia \u201cabreviada\u201d que remente \u00e0 revela\u00e7\u00e3o da identidade de Deus no Sinai. Elas frequentemente aparecem em contextos onde o pacto da gra\u00e7a de Deus \u00e9 estabelecido ou revelado, e tendem a ser expressivas do amor misericordioso, inexor\u00e1vel e perdoador de Deus por seu povo da alian\u00e7a (Sl. 40.11, 57.1-3, 69.13-14; 85.4-10, 89.23-26 &#8211; palavra variante usada para fidelidade -, 108.3-5, 115.1; Os. 4.1). Ningu\u00e9m que confia totalmente no nome de Deus, como revelado no Sinai, ser\u00e1 envergonhado\u2026<\/p>\n<p>No entanto, h\u00e1 uma tens\u00e3o presente quando um pecador apela para a clem\u00eancia de um Deus cujo nome \u00e9 \u201cgrande em miseric\u00f3rdia e fidelidade\u201d. Embora ele seja cheio de amor infal\u00edvel e perdoador, a sua fidelidade \u00e0 sua alian\u00e7a parece exigir a destrui\u00e7\u00e3o daqueles que se op\u00f5em a ele. Essa tens\u00e3o na ess\u00eancia do nome de YHWH permanecer\u00e1 sem solu\u00e7\u00e3o at\u00e9 chegarmos ao Novo Testamento. Por agora, \u00e9 suficiente reconhecermos que a express\u00e3o \u201cmiseric\u00f3rdia e fidelidade\u201d a) pode ser usada como uma abrevia\u00e7\u00e3o para todo o nome de Deus revelado no Sinai e b) aponta especialmente para o amor soberano, perdoador e redentor do Senhor.<\/p>\n<h2>O verbo se fez carne<\/h2>\n<p>\u201cE o Verbo se fez carne e habitou entre n\u00f3s, cheio de gra\u00e7a e de verdade, e vimos a sua gl\u00f3ria, gl\u00f3ria como do unig\u00eanito do Pai\u201d. (Jo 1.14)<\/p>\n<p>O verbo \u2014 a auto-revela\u00e7\u00e3o eternamente existente de Deus \u2014 se fez carne e foi vista por testemunhas oculares na terra. E Jo\u00e3o diz que a gl\u00f3ria que viu na encarna\u00e7\u00e3o do Filho era cheia \u201cde gra\u00e7a e verdade\u201d.<\/p>\n<p>Isso \u00e9 impressionante porque as duas palavras para \u201cgra\u00e7a e verdade\u201d s\u00e3o amplamente reconhecidas como os equivalentes gregos \u00e0s palavras hebraicas \u201cmiseric\u00f3rdia e fidelidade\u201d. Ao aplicar uma das descri\u00e7\u00f5es de identidade de YHWH favoritas da B\u00edblia hebraica ao homem Jesus Cristo, Jo\u00e3o est\u00e1 fazendo uma declara\u00e7\u00e3o teol\u00f3gica ousada e revolucion\u00e1ria. Ele essencialmente est\u00e1 afirmando que a gl\u00f3ria de YHWH revelada no Sinai agora foi encarnada na pessoa de Jesus Cristo. Jo\u00e3o nos diz que esse homem \u00e9 a resposta final \u00e0 s\u00faplica de Mois\u00e9s para ver a gl\u00f3ria de Deus. Jesus n\u00e3o apenas ensina de modo correto sobre o nome de Deus, ele \u00e9 o nome de Deus encarnado.<\/p>\n<p>Jo\u00e3o 1.1-18 \u00e9 a maior introdu\u00e7\u00e3o a um livro j\u00e1 escrito. Nessa introdu\u00e7\u00e3o, Jo\u00e3o faz a surpreendente afirma\u00e7\u00e3o de que Deus, o Filho, que \u00e9 o eterno e n\u00e3o criado Verbo de Deus, entrou na hist\u00f3ria humana como Jesus de Nazar\u00e9. E que esse homem \u2014 em sua vida e minist\u00e9rio humanos \u2014 revelou o nome, a identidade e a gl\u00f3ria de Deus YHWH. Jo\u00e3o nos diz que \u201cNingu\u00e9m jamais viu a Deus\u201d (uma alus\u00e3o intencional a \u00caxodo 33 e a Mois\u00e9s ser escondido na rocha), mas o homem de carne e sangue, Jesus Cristo, que \u00e9 Ele mesmo Deus, ele tornou o Deus todo-poderoso conhecido a n\u00f3s.<\/p>\n<p>Absolutamente surpreendente. Jo\u00e3o nos enche de antecipa\u00e7\u00e3o quando come\u00e7amos a ler o seu evangelho: \u201cComo Jesus nos mostrar\u00e1 YHWH?\u201d, \u201cComo a sua gl\u00f3ria se manifestar\u00e1?\u201d, \u201cO que YHWH far\u00e1 para mostrar de modo culminante a sua \u201cmiseric\u00f3rdia e fidelidade\u201d, a sua \u201cgra\u00e7a e verdade\u201d? Por causa da \u00eanfase do pr\u00f3logo no papel de Jesus como exegeta de Deus, tudo o que ele diz e faz no evangelho de Jo\u00e3o \u00e9 carregado de peso revelat\u00f3rio. N\u00e3o se trata apenas da vida de um profeta, esta \u00e9 a vida de Deus conosco, e ver algo verdadeiro sobre Jesus \u00e9 ver algo verdadeiro sobre Deus.<\/p>\n<h2>O nome declarado no Calv\u00e1rio<\/h2>\n<p>Ent\u00e3o, que maravilha, que mist\u00e9rio, que esplendor e gl\u00f3ria \u00e9 percebermos que esta vida \u2014 a vida de Deus feita conhecida \u2014 culmina com a morte. Mais do que qualquer outro autor evang\u00e9lico, Jo\u00e3o enfatiza que a crucifica\u00e7\u00e3o de Jesus foi em si o ato supremo da reden\u00e7\u00e3o auto-reveladora de Deus e, portanto, a comunica\u00e7\u00e3o suprema da gl\u00f3ria de Deus \u2014 a gl\u00f3ria falada no Sinai (como um coment\u00e1rio adicional, eu n\u00e3o creio que seja coincid\u00eancia que Jo\u00e3o fale tanto do amor e da gl\u00f3ria da cruz de Cristo e tamb\u00e9m foi \u2014 at\u00e9 onde sabemos \u2014 o \u00fanico escritor evang\u00e9lico fisicamente presente na crucifica\u00e7\u00e3o).<\/p>\n<p>Quando Jesus est\u00e1 \u00e0 beira do Calv\u00e1rio, ele volta o seu cora\u00e7\u00e3o para o Pai e diz: \u201c&#8230; Mas precisamente com este prop\u00f3sito vim para esta hora.\u00a0Pai, glorifica o teu nome\u201d (Jo. 12.27-28). O prop\u00f3sito da cruz \u00e9 o Pai glorificado (e lembre-se do que dissemos acima, a gl\u00f3ria de Deus \u00e9 Ele mesmo feito conhecido). Ou novamente, depois que Judas possu\u00eddo por satan\u00e1s sai para trair Cristo, Jesus proclama: \u201cAgora, foi glorificado o Filho do Homem, e Deus foi glorificado nele; se Deus foi glorificado nele, tamb\u00e9m Deus o glorificar\u00e1 nele mesmo; e glorific\u00e1-lo-\u00e1 imediatamente\u201d. E ent\u00e3o, quando ele est\u00e1 a apenas alguns minutos da pris\u00e3o e a algumas horas da cruz, o Filho ergue a sua voz e roga ao Pai: \u201ce, agora, glorifica-me, \u00f3 Pai, contigo mesmo, com a gl\u00f3ria que eu tive junto de ti, antes que houvesse mundo\u201d (Jo. 17.5).<\/p>\n<p>Gl\u00f3ria, gl\u00f3ria, gl\u00f3ria&#8230; no evangelho de Jo\u00e3o a cruz est\u00e1 repleta de gl\u00f3ria. Por qu\u00ea? Porque a \u201cgl\u00f3ria\u201d de Deus \u00e9 a revela\u00e7\u00e3o de sua identidade, sua beleza interior, seu Nome e \u2014 como Jo\u00e3o 1.14-18 deixou claro \u2014 \u00e9 isso que Jesus veio fazer. Toda a vida de Jesus foi uma revela\u00e7\u00e3o do nome de Deus, mas essa obra de comunica\u00e7\u00e3o do nome culmina em sua morte voluntariamente escolhida na cruz.<\/p>\n<p>Quando vista sob a luz radiante da ressurrei\u00e7\u00e3o, a cruz de Cristo se torna o ato definitivo da reden\u00e7\u00e3o revelat\u00f3ria de Deus. \u00c9 na cruz, na natureza humana fr\u00e1gil e sangrenta que Jesus soberanamente uniu a si mesmo, que Deus YHWH se proclama de modo definitivo \u00e0 sua cria\u00e7\u00e3o. \u00c9 oferecendo a sua humanidade para ser amaldi\u00e7oada pelas assola\u00e7\u00f5es da lei divina, em lugar de seu povo, que YHWH se mostra fiel tanto para punir como para salvar. \u00c9 por tecer a mortalidade na tape\u00e7aria de sua pr\u00f3pria vida infinita, para que ele possa dar essa vida totalmente na morte do seu amado que nosso Senhor e Deus revela toda a extens\u00e3o da sua miseric\u00f3rdia. \u00c9 casando a vida de Deus com 5 litros de sangue humano derramado sob a\u00e7oites romanos em terra judaica que YHWH se mostra verdadeiramente como aquele que perdoa a iniquidade, a transgress\u00e3o e o pecado. E \u00e9 se tornando a pedra de moinho da culpa do pecado de seu povo e se afogando sob os golpes da ira torrencial de Deus, que o todo-poderoso Senhor do Sinai se proclama como aquele que n\u00e3o inocenta o culpado. O nome sussurrado em palavras no Sinai \u00e9 proclamado em alta voz em carne, osso, l\u00e1grimas e amor encarnado no G\u00f3lgota. Ah, incompreens\u00edvel Senhor, a ti seja a gl\u00f3ria!<\/p>\n<h2>A imagem explicada<\/h2>\n<p>O nome de Deus \u00e9 comunicado de modo culminante e com definitiva clareza na pessoa de Jesus Cristo e, mais especialmente, naquele ato supremo de reden\u00e7\u00e3o revelat\u00f3ria: a crucifica\u00e7\u00e3o e a ressurrei\u00e7\u00e3o. Isso \u00e9 o que eu estava tentando comunicar tanto nesta imagem quanto na anima\u00e7\u00e3o da qual ela foi extra\u00edda, <em>O Nome de Deus<\/em>. A princ\u00edpio, a imagem acima \u00e9 uma representa\u00e7\u00e3o da cena de \u00caxodo 34.6-7, onde YHWH passa por diante de Mois\u00e9s e proclama o seu nome. As letras s\u00e3o o \u201ctetragrama\u201d das consoantes hebraicas que formam o nome do Deus \u00fanico e verdadeiro. Como j\u00e1 falamos acima, este evento e este nome fazem muito mais do que nos lembrar do que Deus \u00e9 chamado; antes, este \u00e9 um momento em que Deus revela quem ele \u00e9.<\/p>\n<p>Por causa disso, voc\u00ea observar\u00e1 que eu chamei a aten\u00e7\u00e3o para a pessoa e a obra de Cristo, em quem o nome aqui proclamado encontrar\u00e1 a sua express\u00e3o culminante. A fenda na qual Mois\u00e9s est\u00e1 escondido \u00e9 vermelho-carmesim e se alinha com a m\u00e3o coberta de YHWH, de modo a evocar a imagem da m\u00e3o ferida de Cristo. Isto \u00e9 apropriado j\u00e1 que as feridas de Cristo representam o ato redentivo final da miseric\u00f3rdia e fidelidade de YHWH em favor do seu povo, e porque \u00e9 \u2014 metaforicamente \u2014 \u201cnas\u201d feridas de Cristo que eles se refugiam da tempestade da ira de Deus. Assim como Mois\u00e9s foi coberto por YHWH na fenda da rocha, tamb\u00e9m todo o povo de Deus que confia em Cristo \u00e9 coberto pela m\u00e3o do Deus encarnado. Estamos cobertos para que nos regozijemos em vez de sermos destru\u00eddos pela gl\u00f3ria de nosso Deus \u2014 gl\u00f3ria que vemos com maior clareza neste mesmo ato de reden\u00e7\u00e3o pelo qual fomos cobertos: a morte e a ressurrei\u00e7\u00e3o de Deus, o Filho.<\/p>\n<p>Desse modo, oro para que tanto esta imagem quanto a anima\u00e7\u00e3o <em>O Nome de Deus<\/em> ajudem voc\u00ea a contemplar com admira\u00e7\u00e3o e olhos cheios de alegria que Deus \u00e9 definitivamente feito conhecido na pessoa e obra revelat\u00f3ria e redentora de seu Filho. Seria blasf\u00eamia afirm\u00e1-lo se o pr\u00f3prio Deus n\u00e3o nos tivesse ensinado a diz\u00ea-lo&#8230; e esta \u00e9 a verdade mais doce que a mente humana pode conceber&#8230; se desejamos conhecer a Deus: olhemos para o Jesus crucificado e ressurreto.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por:\u00a0Chris Powers.\u00a0\u00a9 Full of Eyes. Website: <a href=\"http:\/\/www.fullofeyes.com\/\" target=\"_blank\" rel=\"noopener\">fullofeyes.com<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"http:\/\/www.fullofeyes.com\/project\/the-name-of-god-an-animation\/\" target=\"_blank\" rel=\"noopener\">The Name of God \u2013 An Animation<\/a>.<\/p>\n<p>Original: O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o.\u00a0\u00a9 Voltemos ao Evangelho. Website:\u00a0<a href=\"http:\/\/voltemosaoevangelho.com\/\" target=\"_blank\" rel=\"noopener\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Camila Rebeca Teixeira. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>O nome de Deus \u00e9 comunicado de modo culminante e com definitiva clareza na pessoa de Jesus Cristo e, mais especialmente, naquele ato supremo de reden\u00e7\u00e3o revelat\u00f3ria: a crucifica\u00e7\u00e3o e a ressurrei\u00e7\u00e3o. Assista a anima\u00e7\u00e3o.<\/p>\n","protected":false},"author":596,"featured_media":42723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[1924],"class_list":["post-42722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-full-of-eyes","tema-deus","tema-full-of-eyes","tema-justica-de-deus","tema-misericoridia-de-deus","tema-natureza-de-deus","tema-nome-de-deus","tema-teontologia-doutrina-de-deus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O nome de Deus \u00e9 comunicado de modo culminante e com definitiva clareza na pessoa de Jesus Cristo e, mais especialmente, naquele ato supremo de reden\u00e7\u00e3o revelat\u00f3ria: a crucifica\u00e7\u00e3o e a ressurrei\u00e7\u00e3o. Assista a anima\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-23T03:10:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T20:18:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/o-nome-de-deus-animacao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chris Powers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris Powers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/\"},\"author\":{\"name\":\"Chris Powers\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/8a695e03ada0d2039a5de673e059f879\"},\"headline\":\"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o\",\"datePublished\":\"2018-03-23T03:10:09+00:00\",\"dateModified\":\"2025-12-17T20:18:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/\"},\"wordCount\":2811,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1\",\"keywords\":[\"Full of Eyes\"],\"articleSection\":[\"...\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/\",\"name\":\"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2018-03-23T03:10:09+00:00\",\"dateModified\":\"2025-12-17T20:18:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/o-nome-de-deus-uma-animacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/8a695e03ada0d2039a5de673e059f879\",\"name\":\"Chris Powers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Chris-Powers_avatar_1529345965-96x96.png\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Chris-Powers_avatar_1529345965-96x96.png\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Chris-Powers_avatar_1529345965-96x96.png\",\"caption\":\"Chris Powers\"},\"description\":\"Chris Powers \u00e9 fundador e desenhista do Full of Eyes, novo parceiro do Voltemos ao Evangelho.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/chris-powers\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/","og_locale":"pt_BR","og_type":"article","og_title":"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o","og_description":"O nome de Deus \u00e9 comunicado de modo culminante e com definitiva clareza na pessoa de Jesus Cristo e, mais especialmente, naquele ato supremo de reden\u00e7\u00e3o revelat\u00f3ria: a crucifica\u00e7\u00e3o e a ressurrei\u00e7\u00e3o. Assista a anima\u00e7\u00e3o.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2018-03-23T03:10:09+00:00","article_modified_time":"2025-12-17T20:18:58+00:00","og_image":[{"width":890,"height":381,"url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/o-nome-de-deus-animacao.jpg","type":"image\/jpeg"}],"author":"Chris Powers","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Chris Powers","Est. tempo de leitura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/"},"author":{"name":"Chris Powers","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/8a695e03ada0d2039a5de673e059f879"},"headline":"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o","datePublished":"2018-03-23T03:10:09+00:00","dateModified":"2025-12-17T20:18:58+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/"},"wordCount":2811,"commentCount":2,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1","keywords":["Full of Eyes"],"articleSection":["..."],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/","name":"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1","datePublished":"2018-03-23T03:10:09+00:00","dateModified":"2025-12-17T20:18:58+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/o-nome-de-deus-uma-animacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"O Nome de Deus \u2013 Uma Anima\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/8a695e03ada0d2039a5de673e059f879","name":"Chris Powers","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/06\/Chris-Powers_avatar_1529345965-96x96.png","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/06\/Chris-Powers_avatar_1529345965-96x96.png","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/06\/Chris-Powers_avatar_1529345965-96x96.png","caption":"Chris Powers"},"description":"Chris Powers \u00e9 fundador e desenhista do Full of Eyes, novo parceiro do Voltemos ao Evangelho.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/chris-powers\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/o-nome-de-deus-animacao.jpg?fit=890%2C381&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-b74","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/42722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/596"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=42722"}],"version-history":[{"count":1,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/42722\/revisions"}],"predecessor-version":[{"id":72511,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/42722\/revisions\/72511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/42723"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=42722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=42722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=42722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}