{"id":42757,"date":"2018-03-27T00:10:18","date_gmt":"2018-03-27T03:10:18","guid":{"rendered":"http:\/\/voltemosaoevangelho.com\/blog\/?p=42757"},"modified":"2018-03-27T12:14:33","modified_gmt":"2018-03-27T15:14:33","slug":"terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/","title":{"rendered":"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Existe uma m\u00e1xima que diz \u201cenvie seus filhos \u00e0 C\u00e9sar e eles voltar\u00e3o romanos\u201d.<\/p>\n<p>Diariamente me pego a pensar na carreira que Deus prop\u00f4s a n\u00f3s mulheres, como m\u00e3es. Uma fun\u00e7\u00e3o de incompar\u00e1vel valor e digo isso com imenso temor! A n\u00f3s foi dado a ben\u00e7\u00e3o de gerar e guiarmos nossos filhos nos caminhos do Senhor.<\/p>\n<p>A fam\u00edlia \u00e9 uma d\u00e1diva do Senhor e atrav\u00e9s dela impactamos e influenciamos a vida de nossos filhos e de toda a sociedade. Os pais s\u00e3o respons\u00e1veis por ensinar as crian\u00e7as, moldando seu car\u00e1ter de acordo com princ\u00edpios e valores crist\u00e3os. Mas sobretudo, da m\u00e3e prov\u00e9m a maior responsabilidade, pois \u00e9 ela quem diariamente educa e direciona a crian\u00e7a nos anos iniciais.<\/p>\n<p>Mas o que \u00e9 educa\u00e7\u00e3o? Vai muito al\u00e9m de se portar bem, racioc\u00ednio l\u00f3gico e boas argumenta\u00e7\u00f5es. A educa\u00e7\u00e3o abrange tamb\u00e9m o cora\u00e7\u00e3o da crian\u00e7a. N\u00f3s somos educados por nossas amizades e por coisas que amamos. As crian\u00e7as s\u00e3o educadas e inspiradas atrav\u00e9s do amor e tamb\u00e9m pelo exemplo.<\/p>\n<p><em>\u201cQuando crian\u00e7as s\u00e3o guiadas a buscar algo para se pensar sobre durante sua vida, elas continuar\u00e3o este h\u00e1bito ao longo de suas vidas\u201d (Karen Andreola)<\/em><\/p>\n<p>Se n\u00f3s n\u00e3o as ensinarmos a amar a Deus, ningu\u00e9m mais far\u00e1. \u00c9 no lar que se aprende a amar a Deus. Quando nos sentimos satisfeitos apenas com a educa\u00e7\u00e3o da mente, no sentido aprendizado de conte\u00fado, n\u00f3s estamos negligenciando o prop\u00f3sito maior da educa\u00e7\u00e3o que \u00e9 glorificar e amar \u00e0 Deus.<\/p>\n<p>\u00c9 muito mais c\u00f4modo para n\u00f3s delegarmos esta fun\u00e7\u00e3o \u00e0 terceiros, faz parte da natureza humana optarmos pelo que seja mais f\u00e1cil. Mesmo que optamos delegar parte da educa\u00e7\u00e3o dos nossos filhos, temos a responsabilidade de avaliar o conte\u00fado e a qualidade deste ensino pelo crivo b\u00edblico. Creio que Deus espera de n\u00f3s muito mais. Todo dom de conhecimento e discernimento vem do Senhor. E o \u00e1pice de toda educa\u00e7\u00e3o \u00e9 o constante conhecimento e intimidade com Deus, pois Ele \u00e9 nosso educador supremo, o criador de todas as coisas.<\/p>\n<p>Como no poema:<\/p>\n<p><em>\u201cBuscamos por verdade no mundo.<br \/>\n<\/em><em>Selecionamos o bom, o verdadeiro, o belo,<br \/>\n<\/em><em>Das gravuras nas pedras e pergaminhos escritos,<br \/>\n<\/em><em>E todos os antigos campos floridos da alma;<br \/>\n<\/em><em>E quando ca\u00e7adores do melhor,<br \/>\n<\/em><em>Voltamos carregados da nossa busca,<br \/>\n<\/em><em>Apenas para descobrir que tudo dito pelos s\u00e1bios<br \/>\n<\/em><em>Est\u00e1 no livro que nossas m\u00e3es leram.\u201d <\/em><\/p>\n<p><em>\u2013 John Greenleaf Whittier<\/em><\/p>\n<p>Trago \u00e0 sua aten\u00e7\u00e3o o \u00faltimo verso do poema: \u201cEst\u00e1 no livro que nossas m\u00e3es leram\u201d, vejam a import\u00e2ncia.\u00a0 Deus em sua palavra nos diz:<\/p>\n<p><em>\u201cOs mandamentos que hoje te dou ser\u00e3o gravados no teu cora\u00e7\u00e3o.<\/em><em><br \/>\nTu os inculcar\u00e1s a teus filhos, e deles falar\u00e1s, seja sentado em tua casa, seja andando pelo caminho, ao te deitares e ao te levantares.<br \/>\nAt\u00e1-los-\u00e1s \u00e0 tua m\u00e3o como sinal, e os levar\u00e1s como uma faixa frontal diante dos teus olhos.<br \/>\nTu os escrever\u00e1s nos umbrais e nas portas de tua casa.\u201d (<\/em><a href=\"https:\/\/www.bibliaonline.com.br\/vc\/dt\/6\/6-9\"><em>Deuteron\u00f4mio 6:6-9<\/em><\/a><em>)<\/em><\/p>\n<p>\u00c9 uma tarefa sem igual. Gravar a palavra de Deus nos cora\u00e7\u00f5es de nossos filhos. Inculcar na mente de nossos filhos. Ensinar a todo momento e o tempo todo.<\/p>\n<p>Ent\u00e3o vos pergunto, vale a pena terceirizar nossos filhos a ponto de perder seus cora\u00e7\u00f5es? Se nossos filhos n\u00e3o aprenderem a amar a Deus de nada ter\u00e1 valido.[\/vc_column_text][vc_empty_space height=&#8221;30px&#8221;][vc_cta h2=&#8221;Vislumbres da Gra\u00e7a&#8221; h4=&#8221;Valorizando o evangelho na rotina do lar&#8221;]<b><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-42762 alignleft\" src=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/vislumbres-da-graca-1-200x300.jpg?resize=200%2C300\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/vislumbres-da-graca-1.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/vislumbres-da-graca-1.jpg?w=426&amp;ssl=1 426w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Deus se importa com as pequenas coisas do seu dia a dia?<\/b><\/p>\n<p>\u00c0s vezes, a vida parece um fardo. S\u00e3o sempre as mesmas tarefas e obriga\u00e7\u00f5es, desafios e desencorajamentos, ansiedades e responsabilidades. Todas as mulheres j\u00e1 experimentaram essa sensa\u00e7\u00e3o, seja uma m\u00e3e, dona de casa ou uma mulher que trabalha fora, dividindo tempo entre o trabalho e o lar. Por\u00e9m, este livro ir\u00e1 encorajar suas leitoras a enxergar a realidade da gra\u00e7a de Deus naquelas \u00e1reas do dia a dia que parecem entediantes e sem import\u00e2ncia. Atrav\u00e9s de exemplos pessoais e hist\u00f3rias cativantes, a autora apresenta reflex\u00f5es ricamente b\u00edblicas que ir\u00e3o ajudar a leitora a experimentar o poder extraordin\u00e1rio do evangelho em sua vida cotidiana.<\/p>\n<p><a class=\"btn btn-default btn-lg\" style=\"color: #fff;\" href=\"http:\/\/fiel.in\/2Bi4l9Q\" target=\"_blank\">CONFIRA<\/a>[\/vc_cta][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Rachel Haswell.\u00a0\u00a9 Voltemos ao Evangelho. Website: <a href=\"http:\/\/voltemosaoevangelho.com\/\" target=\"_blank\" rel=\"noopener\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Revis\u00e3o: Renata Gandolfo. Original: <a href=\"http:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/\" target=\"_blank\" rel=\"noopener\">A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?<\/a>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Rachel Haswell: Se n\u00f3s n\u00e3o ensinarmos nossos filhos a amarem a Deus, ningu\u00e9m mais far\u00e1. \u00c9 no lar que se aprende a amar a Deus.<\/p>\n","protected":false},"author":598,"featured_media":42759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3065,624],"tags":[1861],"class_list":["post-42757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casamento-e-familia","category-mulheres","tag-vida-de-ovelha","tema-criacao-de-filhos","tema-filhos","tema-mulheres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?\" \/>\n<meta property=\"og:description\" content=\"Rachel Haswell: Se n\u00f3s n\u00e3o ensinarmos nossos filhos a amarem a Deus, ningu\u00e9m mais far\u00e1. \u00c9 no lar que se aprende a amar a Deus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-27T03:10:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-27T15:14:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rachel Haswell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rachel Haswell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/\"},\"author\":{\"name\":\"Rachel Haswell\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/1fc3c35711dca7689d246a315440967f\"},\"headline\":\"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?\",\"datePublished\":\"2018-03-27T03:10:18+00:00\",\"dateModified\":\"2018-03-27T15:14:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/\"},\"wordCount\":870,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1\",\"keywords\":[\"Vida de Ovelha\"],\"articleSection\":[\"Casamento e fam\u00edlia\",\"Mulheres\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/\",\"name\":\"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2018-03-27T03:10:18+00:00\",\"dateModified\":\"2018-03-27T15:14:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/03\\\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/1fc3c35711dca7689d246a315440967f\",\"name\":\"Rachel Haswell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Rachel-Haswell_avatar_1522162886-96x96.png\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Rachel-Haswell_avatar_1522162886-96x96.png\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Rachel-Haswell_avatar_1522162886-96x96.png\",\"caption\":\"Rachel Haswell\"},\"description\":\"Rachel Haswell, \u00e9 casada com Daniel Haswell, presb\u00edtero da Igreja Presbiteriana de Sapiranga, no Rio Grande do Sul, onde o casal congrega. Eles tem 3 filhas, Helena (4), Isabel (2) e Olivia (5 meses). Rachel \u00e9 M\u00e3e Homeschooler, Bi\u00f3loga, Especialista em biotecnologia, Mestre em gen\u00e9tica e melhoramento. \u00c9 autora do Blog: Family Has Tools.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/rachel-haswell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/","og_locale":"pt_BR","og_type":"article","og_title":"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?","og_description":"Rachel Haswell: Se n\u00f3s n\u00e3o ensinarmos nossos filhos a amarem a Deus, ningu\u00e9m mais far\u00e1. \u00c9 no lar que se aprende a amar a Deus.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2018-03-27T03:10:18+00:00","article_modified_time":"2018-03-27T15:14:33+00:00","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"author":"Rachel Haswell","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Rachel Haswell","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/"},"author":{"name":"Rachel Haswell","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/1fc3c35711dca7689d246a315440967f"},"headline":"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?","datePublished":"2018-03-27T03:10:18+00:00","dateModified":"2018-03-27T15:14:33+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/"},"wordCount":870,"commentCount":1,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1","keywords":["Vida de Ovelha"],"articleSection":["Casamento e fam\u00edlia","Mulheres"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/","name":"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1","datePublished":"2018-03-27T03:10:18+00:00","dateModified":"2018-03-27T15:14:33+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/03\/terceirizacao-de-nossos-filhos-proxima-geracao-sera-de-fato-de-cristaos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"A terceiriza\u00e7\u00e3o de nossos filhos \u2013 a pr\u00f3xima gera\u00e7\u00e3o ser\u00e1 de fato de crist\u00e3os?"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/1fc3c35711dca7689d246a315440967f","name":"Rachel Haswell","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/Rachel-Haswell_avatar_1522162886-96x96.png","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/Rachel-Haswell_avatar_1522162886-96x96.png","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/Rachel-Haswell_avatar_1522162886-96x96.png","caption":"Rachel Haswell"},"description":"Rachel Haswell, \u00e9 casada com Daniel Haswell, presb\u00edtero da Igreja Presbiteriana de Sapiranga, no Rio Grande do Sul, onde o casal congrega. Eles tem 3 filhas, Helena (4), Isabel (2) e Olivia (5 meses). Rachel \u00e9 M\u00e3e Homeschooler, Bi\u00f3loga, Especialista em biotecnologia, Mestre em gen\u00e9tica e melhoramento. \u00c9 autora do Blog: Family Has Tools.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/rachel-haswell\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/03\/a-terceirizacao-de-nossos-filhos.jpg?fit=890%2C381&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-b7D","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/42757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/598"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=42757"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/42757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/42759"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=42757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=42757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=42757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}