{"id":46491,"date":"2018-12-14T10:59:01","date_gmt":"2018-12-14T12:59:01","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=46491"},"modified":"2018-12-14T10:59:01","modified_gmt":"2018-12-14T12:59:01","slug":"a-restauracao-de-deus","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/","title":{"rendered":"A restaura\u00e7\u00e3o de Deus"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_btn title=&#8221;S\u00e9rie &#8220;Aprendendo com os Salmos de romagem &#8211; c\u00e2nticos dos degraus&#8220; | Clique e veja o sum\u00e1rio&#8221; size=&#8221;sm&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffiel.in%2FSerieSalmosDeRomagem||target:%20_blank|&#8221;][vc_column_text]Nem sempre estamos onde queremos ou temos o que desejamos. A vida \u00e9 cheia de altos e baixos. Nossos dias depois da queda s\u00e3o de \u201ccanseira\u201d e \u201cenfado\u201d. Sim, temos for\u00e7a, virilidade, alegria, mas elas nunca perduram o tempo todo. Precisamos ter as energias renovadas para encarar o mundo debaixo do sol.<\/p>\n<p>O hin\u00e1rio dos peregrinos \u00e9 o hin\u00e1rio dos altos e baixos da vida. Ele fala do cansa\u00e7o, do medo, da ang\u00fastia, e, ao mesmo passo convida o peregrino a subir mais um degrau, cravando os olhos na miseric\u00f3rdia do Eterno.<\/p>\n<p>Por assim dizer, a m\u00e9trica do Salmo 126 reflete a restaura\u00e7\u00e3o das for\u00e7as em Deus. Este salmo \u00e9 a poesia do sorriso de uma ponta a outra. N\u00e3o existe lei que nos pro\u00edba de ter deleite em Deus. Vejamos que li\u00e7\u00f5es o texto sagrado nos ensina:<\/p>\n<h2>Ficamos como sonha<\/h2>\n<p>Os peregrinos, no primeiro momento, olharam para os grandes feitos de Deus no passado e encontraram raz\u00f5es para alegria (1). Houve um tempo de restaura\u00e7\u00e3o em Si\u00e3o, talvez o per\u00edodo da liberta\u00e7\u00e3o do cativeiro babil\u00f4nico. Seja como for, depois de um tempo dif\u00edcil, o Senhor mudou a sorte do seu povo e a alegria foi renovada. Gosto da express\u00e3o do puritano M. Henry quando ele diz: <em>a provid\u00eancia assobiou para eles, e eles estavam dan\u00e7ando.<\/em> Parecia um sonho! Era um momento de grande fasc\u00ednio!<\/p>\n<p>As na\u00e7\u00f5es n\u00e3o falavam em outra coisa, sen\u00e3o sobre o que aconteceu com o povo de Deus (2). N\u00e3o apenas Israel, mas o cen\u00e1rio internacional foi impactado com atos de Deus na hist\u00f3ria da reden\u00e7\u00e3o do seu povo. Nesse ponto vemos uma antecipa\u00e7\u00e3o do interesse do Senhor por todos os povos, aleluia!<\/p>\n<p>Note ainda que os peregrinos n\u00e3o estavam alegres por causa das coisas que eles podiam realizar. Eles estavam alegres por causa dos feitos de Deus (3). Era como se estivessem dizendo para o mundo e uns para os outros: <em>cantem com for\u00e7a, renovem suas for\u00e7as em Deus, ele j\u00e1 nos libertou no passado! Temos motivos de sobra para cantar!<\/em><\/p>\n<h2>Restaura Senhor<\/h2>\n<p>Parece que no tempo presente o salmista passava por um momento dif\u00edcil, por isso, mais uma vez ele clamou: restaura Senhor. A f\u00e9 de ontem n\u00e3o substitu\u00eda a necessidade de continuar acreditando no Deus do pacto! Por vezes, o povo de Deus atravessa momentos de aridez espiritual, mas a verdadeira f\u00e9 perdura e clama por restaura\u00e7\u00e3o.<\/p>\n<p>De alguma forma o salmista se sentia seco, tal como os <em>u\u00e1dis<\/em> da regi\u00e3o sul de Israel. Durante a maior parte do tempo essas terras ficavam secas ou apresentavam uma pequena l\u00e2mina de \u00e1gua. Por\u00e9m quando a chuva caia rapidamente o cen\u00e1rio mudava e a vida se renovava. Isto posto, creio que o salmista estava fazendo o seguinte pedido: <em>enche minha vida novamente Senhor, assim como foi feito no passado! Derrama um poderoso avivamento sobre o teu povo!<\/em><\/p>\n<h2>Quem sai andando<\/h2>\n<p>Nos versos 5 e 6 os olhos do salmista se movem na dire\u00e7\u00e3o do futuro de Deus. Os olhos cheios de l\u00e1grimas se encheram de esperan\u00e7a. O cora\u00e7\u00e3o nost\u00e1lgico se encheu de expectativas. O peregrino come\u00e7a a andar em dire\u00e7\u00e3o as promessas de Deus!<\/p>\n<p>Enquanto anda o peregrino, mesmo chorando, deve semear. O peregrino deve espalhar, mesmo nas horas dif\u00edceis, o temor do Senhor, mesmo que ele n\u00e3o veja os frutos da colheita. Os peregrinos j\u00e1 sentiram a alegria (Salmo 122), mas existem situa\u00e7\u00e3o em que a peregrina\u00e7\u00e3o \u00e9 feita com os olhos cheio de l\u00e1grimas.<\/p>\n<p>Com os olhos da esperan\u00e7a o salmista tem certeza em Deus dos frutos que sobrevir\u00e3o. Os olhos marejados n\u00e3o lhe impedem de ver a ceifa certa e garantida pelas promessas do pacto! A esperan\u00e7a em Deus \u00e9 o motor do peregrino em tempo de sequid\u00e3o espiritual.<\/p>\n<h2>Cristo \u00e9 a nossa esperan\u00e7a<\/h2>\n<p>\u00c9ramos escravos do pecado, por\u00e9m, na cruz, o Senhor rasgou o escrito de d\u00edvida que constava em nosso desfavor. Jesus \u00e9 a nossa passagem para Deus! Ele \u00e9 a nossa P\u00e1scoa e por ele somos declarados justos e perdoados diante do Senhor.<\/p>\n<p>Ainda que tenhamos tamanha certeza do que Cristo fez por n\u00f3s, alguns experimentar\u00e3o momentos de sequid\u00e3o espiritual. Molhamos a B\u00edblia com l\u00e1grimas, participamos do servi\u00e7o de adora\u00e7\u00e3o com sentimentos de tristeza insepultos. Voc\u00ea se sente assim?<\/p>\n<p>O Salmo 126 deve ser lido com a luz do Evangelho: Cristo nos arrancou do cativeiro do pecado. No final de todos as coisas ele vir\u00e1 e enxugar\u00e1 dos nossos olhos todas l\u00e1grimas. Continue caminhando pela f\u00e9, n\u00e3o pelos sentimentos. Se cremos em Cristo semearemos em tempos de alegria e tristeza. Lembre-se: o Senhor vai enxugar dos nossos olhos toda l\u00e1grima e nos dar\u00e1 eterno descanso.<\/p>\n<p>Continuemos nossa peregrina\u00e7\u00e3o! Deus nos dar\u00e1 alegria plena! Deus vai mudar nossa sorte de uma vez por todas! Ore para que o Senhor derrame seu poderoso avivamento! Uma gota da sua miseric\u00f3rdia \u00e9 o suficiente para encher nosso cora\u00e7\u00e3o de alegria e renovar nossas for\u00e7as![\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Francisco Macena.\u00a0\u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\" target=\"_blank\" rel=\"noopener\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/\" target=\"_blank\" rel=\"noopener\">A restaura\u00e7\u00e3o de Deus<\/a>.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Francisco Macena: A esperan\u00e7a em Deus \u00e9 o motor do peregrino em tempo de sequid\u00e3o espiritual.<\/p>\n","protected":false},"author":580,"featured_media":46494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[700,435],"tags":[2136,2090],"class_list":["post-46491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudos-biblicos","category-teologia","tag-aprendendo-com-os-salmos-de-romagem-canticos-dos-degraus","tag-teobrasil","tema-estudos-biblicos","tema-salmos","tema-salmos-de-romagem","tema-teologia","categoria-artigo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A restaura\u00e7\u00e3o de Deus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A restaura\u00e7\u00e3o de Deus\" \/>\n<meta property=\"og:description\" content=\"Francisco Macena: A esperan\u00e7a em Deus \u00e9 o motor do peregrino em tempo de sequid\u00e3o espiritual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-14T12:59:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/12\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Macena da Costa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Macena da Costa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/\"},\"author\":{\"name\":\"Francisco Macena da Costa\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/3c134dd3ea92d4be0e6f68d8f12bdbc4\"},\"headline\":\"A restaura\u00e7\u00e3o de Deus\",\"datePublished\":\"2018-12-14T12:59:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/\"},\"wordCount\":981,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1\",\"keywords\":[\"Aprendendo com os Salmos de romagem - c\u00e2nticos dos degraus\",\"TeoBrasil\"],\"articleSection\":[\"Estudos B\u00edblicos\",\"Teologia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/\",\"name\":\"A restaura\u00e7\u00e3o de Deus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2018-12-14T12:59:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2018\\\/12\\\/a-restauracao-de-deus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A restaura\u00e7\u00e3o de Deus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/3c134dd3ea92d4be0e6f68d8f12bdbc4\",\"name\":\"Francisco Macena da Costa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a0759fd56a38272a69a4bc3559acbd7c85d840061dcb125570269eb101ef942?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a0759fd56a38272a69a4bc3559acbd7c85d840061dcb125570269eb101ef942?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a0759fd56a38272a69a4bc3559acbd7c85d840061dcb125570269eb101ef942?s=96&d=mm&r=g\",\"caption\":\"Francisco Macena da Costa\"},\"description\":\"Francisco Macena da Costa pastoreia a Igreja Presbiteriana do Cambeba em Fortaleza, Cear\u00e1. \u00c9 Mestre em Teologia Sistem\u00e1tica pelo Centro Presbiteriano de P\u00f3s-gradua\u00e7\u00e3o Andrew Jumper (CPAJ) e Professor de teologia na Escola Teol\u00f3gica Charles Spurgeon. \u00c9 casado com Danielle Costa, com quem tem 3 filhos, Sarah, Samantha e Samuel.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/francisco-macena-da-costa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A restaura\u00e7\u00e3o de Deus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/","og_locale":"pt_BR","og_type":"article","og_title":"A restaura\u00e7\u00e3o de Deus","og_description":"Francisco Macena: A esperan\u00e7a em Deus \u00e9 o motor do peregrino em tempo de sequid\u00e3o espiritual.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2018-12-14T12:59:01+00:00","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/12\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"author":"Francisco Macena da Costa","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Francisco Macena da Costa","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/"},"author":{"name":"Francisco Macena da Costa","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/3c134dd3ea92d4be0e6f68d8f12bdbc4"},"headline":"A restaura\u00e7\u00e3o de Deus","datePublished":"2018-12-14T12:59:01+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/"},"wordCount":981,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/12\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1","keywords":["Aprendendo com os Salmos de romagem - c\u00e2nticos dos degraus","TeoBrasil"],"articleSection":["Estudos B\u00edblicos","Teologia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/","name":"A restaura\u00e7\u00e3o de Deus","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/12\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1","datePublished":"2018-12-14T12:59:01+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/12\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/12\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2018\/12\/a-restauracao-de-deus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"A restaura\u00e7\u00e3o de Deus"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/3c134dd3ea92d4be0e6f68d8f12bdbc4","name":"Francisco Macena da Costa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2a0759fd56a38272a69a4bc3559acbd7c85d840061dcb125570269eb101ef942?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a0759fd56a38272a69a4bc3559acbd7c85d840061dcb125570269eb101ef942?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a0759fd56a38272a69a4bc3559acbd7c85d840061dcb125570269eb101ef942?s=96&d=mm&r=g","caption":"Francisco Macena da Costa"},"description":"Francisco Macena da Costa pastoreia a Igreja Presbiteriana do Cambeba em Fortaleza, Cear\u00e1. \u00c9 Mestre em Teologia Sistem\u00e1tica pelo Centro Presbiteriano de P\u00f3s-gradua\u00e7\u00e3o Andrew Jumper (CPAJ) e Professor de teologia na Escola Teol\u00f3gica Charles Spurgeon. \u00c9 casado com Danielle Costa, com quem tem 3 filhos, Sarah, Samantha e Samuel.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/francisco-macena-da-costa\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-c5R","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/12\/A-restauracao-de-Deus.jpg?fit=890%2C381&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/46491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/580"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=46491"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/46491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/46494"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=46491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=46491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=46491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}