{"id":47582,"date":"2019-02-25T14:47:45","date_gmt":"2019-02-25T17:47:45","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=47582"},"modified":"2019-02-26T10:22:00","modified_gmt":"2019-02-26T13:22:00","slug":"nossa-atitude-em-relacao-ao-fariseu","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/","title":{"rendered":"Nossa atitude em rela\u00e7\u00e3o ao Fariseu"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Navegar por um percurso entre a rocha Scylla do antinomianismo, de um lado, e o turbilh\u00e3o Car\u00edbdis do legalismo, do outro, \u00e9 uma incessante responsabilidade da vida crist\u00e3. A dificuldade \u00e9 agravada pelo fato de que a maioria de n\u00f3s se v\u00ea atra\u00edda mais pelas rochas de um lado do que do outro. Talvez isso seja uma rea\u00e7\u00e3o \u00e0 nossa educa\u00e7\u00e3o, ou \u00e0 prega\u00e7\u00e3o desequilibrada que uma vez dominou nossas igrejas, ou ainda a uma fase anterior de nossa pr\u00f3pria caminhada crist\u00e3, quando nos voltamos para a condescend\u00eancia pr\u00f3pria ou auto-justifica\u00e7\u00e3o. E enquanto nunca devemos nos desvencilhar da luta para permanecer no curso e evitar os recifes perigosos que sempre se escondem logo abaixo da superf\u00edcie, devemos lembrar que existem outras pessoas que est\u00e3o fazendo a jornada tamb\u00e9m, e que nossas rea\u00e7\u00f5es, \u00e0 medida que as vemos tra\u00e7ar um curso inseguro, podem ser moldadas tanto por nossa pr\u00f3pria hist\u00f3ria de nossos erros quanto por seus erros presentes.<\/p>\n<p>Aqueles de n\u00f3s, de origem fundamentalista, que vieram a conhecer a Cristo, podem encontrar-se no meio de uma rea\u00e7\u00e3o ao legalismo. Exig\u00eancias excessivamente restritivas acrescentaram cargas desnecess\u00e1rias \u00e0 luz e ao jugo suave de Cristo. Mas em algum momento, na bondosa provid\u00eancia de Deus, redescobrimos as riquezas da gra\u00e7a soberana. Entendemos que tendo sido justificados livremente, \u00e0 parte de nossas obras, fomos revestidos da justi\u00e7a de Cristo, total e imut\u00e1velmente perdoados, aceitos e amados. Chegamos a nos apegar com gratid\u00e3o \u00e0 maravilhosa verdade de nossa ado\u00e7\u00e3o. Em Cristo, n\u00f3s que outrora \u00e9ramos inimigos de Deus somos agora seus filhos, herdeiros de Deus e co-herdeiros com Cristo.<\/p>\n<p><em>\u201cO pr\u00f3prio Esp\u00edrito testifica com o nosso esp\u00edrito que somos filhos de Deus. \u00a0Ora, se somos filhos, somos tamb\u00e9m herdeiros, herdeiros de Deus e coerdeiros com Cristo; se com ele sofremos, tamb\u00e9m com ele seremos glorificados\u201d. <\/em><em>(<a href=\"https:\/\/www.esv.org\/Rom.+8.16\u201317\">Rm 8.16, 17<\/a>).<\/em><\/p>\n<p>A vergonha que uma vez sentimos, quando deixamos de cumprir as exig\u00eancias legalistas colocadas sobre n\u00f3s, se dissipou \u00e0 medida que nos apropriamos de nossa liberdade como filhos do Rei. Sabemos agora que n\u00e3o precisamos tentar ganhar um lugar para n\u00f3s mesmos na casa de Deus por nossos pr\u00f3prios esfor\u00e7os, uma vez que fomos adotados para sempre em sua fam\u00edlia.<\/p>\n<p>Mas, tendo redescoberto as alegrias dessas preciosas verdades do evangelho, ainda assim estamos em perigo. Misericordiosamente, o primeiro perigo \u00e9 bem conhecido e, embora seja pernicioso, a maioria de n\u00f3s est\u00e1 em guarda contra ele. \u00c9 o perigo da rea\u00e7\u00e3o exagerada. Sabemos que n\u00e3o devemos ouvir, nas fortes garantias da rica gra\u00e7a de Deus, uma nega\u00e7\u00e3o das exig\u00eancias igualmente fortes da santa lei de Deus. Sabemos que pelas obras da lei ningu\u00e9m ser\u00e1 justificado (Gl 2.16), todavia, n\u00e3o estamos fora da lei de Deus, mas vivemos sob a lei de Cristo (1Co 9.21). A lei, despojada de seu poder de condena\u00e7\u00e3o, tornou-se nossa amiga. Para continuar a met\u00e1fora do mar, a lei se torna para um crist\u00e3o como o piloto de um navio, conduzindo a embarca\u00e7\u00e3o por \u00e1guas trai\u00e7oeiras e tra\u00e7ando um curso seguro.<\/p>\n<p>O segundo perigo, no entanto, \u00e9 facilmente esquecido. Tra\u00e7ar um curso seguro para n\u00f3s mesmos \u00e9 uma coisa, mas a paci\u00eancia com os companheiros crist\u00e3os que podem estar desviando desse curso \u00e9 bem outra. Como legalistas em recupera\u00e7\u00e3o, precisamos reconhecer a rapidez com que nossa paci\u00eancia com os outros pode falhar quando eles ainda n\u00e3o conseguem ver as imensas rochas do legalismo, das quais sempre temos o cuidado de nos desviar. N\u00f3s nos perguntamos como eles podem ser t\u00e3o cegos a ponto de se perderem completamente nas pedras afiadas da auto-justi\u00e7a e nos recifes escondidos da vergonha. Como estamos felizes por n\u00e3o mais cometermos seus erros. Qu\u00e3o ing\u00eanuos s\u00e3o aqueles que n\u00e3o conseguem ver o caminho da verdadeira liberdade do evangelho.<\/p>\n<p>Mas o legalismo assume uma variedade de formas, e uma de suas mais sutis \u00e9 exposta em nossa ostenta\u00e7\u00e3o de orgulho que, ao contr\u00e1rio de nossos pobres irm\u00e3os legalistas, sabemos melhor. E assim, enquanto nos congratulamos pela nossa sabedoria em navegar com seguran\u00e7a longe dos perigos da limita\u00e7\u00e3o excessiva e das restri\u00e7\u00f5es pesadas e constru\u00eddas pelo homem, acabamos encalhados nas pr\u00f3prias rochas das quais pens\u00e1vamos ter escapado. J. Gresham Machen, refletindo sobre a par\u00e1bola do fariseu e do publicano em Lucas 18.11, certa vez apontou esse perigo em seu livro What Is Faith? (O que \u00e9 f\u00e9?).<\/p>\n<p><em>Sem d\u00favida, achamos que podemos evitar o erro do fariseu. Deus n\u00e3o era para ele, dizemos, porque ele estava desdenhoso em rela\u00e7\u00e3o ao publicano; seremos ternos com o publicano, como Jesus nos ensinou a ser, e ent\u00e3o Deus ser\u00e1 por n\u00f3s. \u00c9 sem d\u00favida uma boa ideia; \u00e9 bom que estejamos sens\u00edveis ao publicano. Mas qual \u00e9 a nossa atitude para com o fariseu? Infelizmente, n\u00f3s o desprezamos de uma maneira verdadeiramente farisaica. Subimos ao templo para orar; n\u00f3s nos levantamos e oramos assim para n\u00f3s mesmos: \u201cDeus, eu te agrade\u00e7o porque n\u00e3o sou como os outros homens, orgulhoso de minha pr\u00f3pria justi\u00e7a e sem amor para com os publicanos, ou at\u00e9 mesmo como este \u2014 fariseu\u201d.<\/em><\/p>\n<p>Se esperamos salvar os outros das rochas, n\u00e3o o poderemos fazer se tamb\u00e9m nos encalharmos. A pr\u00e1tica da paci\u00eancia \u00e9 a melhor defesa contra se tornar um legalista sobre o legalismo e farisaico em rela\u00e7\u00e3o aos fariseus.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: David Strain. \u00a9 Ligonier Ministries. Website: <a href=\"http:\/\/www.ligonier.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">ligonier.org<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/tabletalkmagazine.com\/article\/2016\/06\/our-attitude-toward-pharisee\/\" target=\"_blank\" rel=\"noopener noreferrer\">Our Attitude toward the Pharisee<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nossa atitude em rela\u00e7\u00e3o ao Fariseu<\/a>.\u00a0\u00a9 Voltemos ao Evangelho. Website:\u00a0<a href=\"https:\/\/voltemosaoevangelho.com\" target=\"_blank\" rel=\"noopener noreferrer\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados.\u00a0Tradu\u00e7\u00e3o: Paulo Reiss Junior.\u00a0Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>David Strain: O legalismo assume uma variedade de formas, e uma de suas mais sutis \u00e9 exposta em nossa ostenta\u00e7\u00e3o de orgulho que, ao contr\u00e1rio de nossos pobres irm\u00e3os legalistas, sabemos melhor.<\/p>\n","protected":false},"author":671,"featured_media":47586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[2169,480],"class_list":["post-47582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-legalismo-vs-religiao-evangelica","tag-ligonier","tema-evangelho","tema-evangelho-dup","tema-legalismo","tema-ligonier","tema-religiao","tema-religiao-dup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nossa atitude em rela\u00e7\u00e3o ao Fariseu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nossa atitude em rela\u00e7\u00e3o ao Fariseu\" \/>\n<meta property=\"og:description\" content=\"David Strain: O legalismo assume uma variedade de formas, e uma de suas mais sutis \u00e9 exposta em nossa ostenta\u00e7\u00e3o de orgulho que, ao contr\u00e1rio de nossos pobres irm\u00e3os legalistas, sabemos melhor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-25T17:47:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-26T13:22:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Strain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Strain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/\"},\"author\":{\"name\":\"David Strain\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/3d4851417571ffd135a8dfafc1a1f9f6\"},\"headline\":\"Nossa atitude em rela\u00e7\u00e3o ao Fariseu\",\"datePublished\":\"2019-02-25T17:47:45+00:00\",\"dateModified\":\"2019-02-26T13:22:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/\"},\"wordCount\":1039,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1\",\"keywords\":[\"Legalismo vs. Religi\u00e3o Evang\u00e9lica\",\"Minist\u00e9rio Ligonier\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/\",\"name\":\"Nossa atitude em rela\u00e7\u00e3o ao Fariseu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2019-02-25T17:47:45+00:00\",\"dateModified\":\"2019-02-26T13:22:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/02\\\/nossa-atitude-em-relacao-ao-fariseu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nossa atitude em rela\u00e7\u00e3o ao Fariseu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/3d4851417571ffd135a8dfafc1a1f9f6\",\"name\":\"David Strain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/David-Strain-96x96.png\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/David-Strain-96x96.png\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/David-Strain-96x96.png\",\"caption\":\"David Strain\"},\"description\":\"Dr. David Strain \u00e9 Pastor da First Presbyterian Church em Jackson, Mississippi, e presidente do \u201cBoard of Christian Witness to Israel\u201d (Am\u00e9rica do Norte).\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/david-strain\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nossa atitude em rela\u00e7\u00e3o ao Fariseu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/","og_locale":"pt_BR","og_type":"article","og_title":"Nossa atitude em rela\u00e7\u00e3o ao Fariseu","og_description":"David Strain: O legalismo assume uma variedade de formas, e uma de suas mais sutis \u00e9 exposta em nossa ostenta\u00e7\u00e3o de orgulho que, ao contr\u00e1rio de nossos pobres irm\u00e3os legalistas, sabemos melhor.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2019-02-25T17:47:45+00:00","article_modified_time":"2019-02-26T13:22:00+00:00","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"author":"David Strain","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"David Strain","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/"},"author":{"name":"David Strain","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/3d4851417571ffd135a8dfafc1a1f9f6"},"headline":"Nossa atitude em rela\u00e7\u00e3o ao Fariseu","datePublished":"2019-02-25T17:47:45+00:00","dateModified":"2019-02-26T13:22:00+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/"},"wordCount":1039,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1","keywords":["Legalismo vs. Religi\u00e3o Evang\u00e9lica","Minist\u00e9rio Ligonier"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/","name":"Nossa atitude em rela\u00e7\u00e3o ao Fariseu","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1","datePublished":"2019-02-25T17:47:45+00:00","dateModified":"2019-02-26T13:22:00+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nossa atitude em rela\u00e7\u00e3o ao Fariseu"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/3d4851417571ffd135a8dfafc1a1f9f6","name":"David Strain","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/David-Strain-96x96.png","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/David-Strain-96x96.png","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/David-Strain-96x96.png","caption":"David Strain"},"description":"Dr. David Strain \u00e9 Pastor da First Presbyterian Church em Jackson, Mississippi, e presidente do \u201cBoard of Christian Witness to Israel\u201d (Am\u00e9rica do Norte).","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/david-strain\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/02\/nossa-atitude-em-relacao-ao-fariseu.jpg?fit=890%2C381&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-cns","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/47582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/671"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=47582"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/47582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/47586"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=47582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=47582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=47582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}