{"id":49272,"date":"2019-06-13T10:00:33","date_gmt":"2019-06-13T13:00:33","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=49272"},"modified":"2020-02-11T15:56:32","modified_gmt":"2020-02-11T18:56:32","slug":"noivas-vamos-falar-das-financas-para-o-casamento","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/","title":{"rendered":"Noivas, vamos falar das finan\u00e7as para o casamento?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]J\u00e1 se passaram 18 anos desde o dia do sim que eu e meu marido demos um ao outro. Enfim, tinha chegado o grande dia! Ufa! Quanta prepara\u00e7\u00e3o, foram 8 meses do noivado at\u00e9 o casamento. N\u00f3s literalmente colocamos a m\u00e3o na massa, pois minha sogra fazia salgadinhos maravilhosos e n\u00f3s fomos ajud\u00e1-la a moldar coxinha, bolinha, rissoles e todas as del\u00edcias pelas quais, depois, receber\u00edamos muitos elogios dos convidados.<\/p>\n<p>O bolo n\u00f3s ganhamos dos nossos tios, os refrigerantes foram pura ostenta\u00e7\u00e3o, porque compramos garrafas de 600 ml para colocar nas mesas, uau!<\/p>\n<p>Por causa das amizades que meu sogro tinha, os gar\u00e7ons trabalharam como cortesia. As donas de um <em>Buffet<\/em> nos emprestaram toalhas, capas de cadeiras e lou\u00e7as. Nas flores ganhamos um bom desconto porque a dona da floricultura era de nossa igreja. Nessa altura do campeonato voc\u00ea j\u00e1 deve estar pensando que foi um casamento brega, com tantas coisas emprestadas, ganhadas e confeccionadas com nossas pr\u00f3prias m\u00e3os, pois bem, te digo que n\u00e3o foi: foi bonito, alegre, est\u00e1vamos radiantes de termos convidados todos das duas igrejas que eu e ele frequent\u00e1vamos, todos os amigos das duas empresas onde trabalh\u00e1vamos, todas pessoas de nossas fam\u00edlias. Sim, os convites foram para os murais das igrejas, publicados em seus boletins e lidos de p\u00falpitos. Quer\u00edamos celebrar com o povo de Deus, com nossas fam\u00edlias e com nossos amigos.<\/p>\n<p>Comecei com essa hist\u00f3ria n\u00e3o para exaltar o quanto fomos exemplares no modo como fizemos nosso casamento, erramos muito em muitas coisas, mas para colocar uma frase que meu marido sempre fala quando estamos conversando sobre os casamentos e as festas de hoje: ainda bem que casamos h\u00e1 tanto tempo, que n\u00e3o tinha nada disso, da ind\u00fastria que se criou por traz dos casamentos. Assim como em um filme, chegamos ao que realmente interessa nesse artigo, ao seu \u00e1pice, ao que nos faz pensar: <span style=\"font-weight: normal !msorm;\"><strong>como est\u00e3o as finan\u00e7as do seu casamento, noivinha?<\/strong><\/span> Est\u00e3o dentro do padr\u00e3o b\u00edblico? Est\u00e3o seguindo uma ordem de planejamento b\u00edblico?<\/p>\n<p>Darei algumas dicas para o planejamento, desde os preparativos at\u00e9 o pr\u00f3prio dia do casamento (ah, e estou levando em considera\u00e7\u00e3o que voc\u00ea est\u00e1 casando com um rapaz que professa a mesma f\u00e9 que voc\u00ea, sen\u00e3o, procure seu pastor e tenha uma boa conversa com ele antes):<\/p>\n<p><span style=\"font-weight: normal !msorm;\"><strong>1<\/strong><\/span><span style=\"font-weight: normal !msorm;\"><strong><u><sup>o<\/sup><\/u><\/strong><\/span><span style=\"font-weight: normal !msorm;\"><strong> Passo:<\/strong><\/span> J\u00e1 dizia o ditado, <span style=\"font-weight: normal !msorm;\"><strong>quem casa quer casa.<\/strong><\/span> Mas mais profundo do que isso \u00e9 a ordenan\u00e7a b\u00edblica de Gn 2:24 \u201c&#8230;deixa o homem pai e m\u00e3e e se une a sua mulher&#8230;\u201d. Duas quest\u00f5es s\u00e3o levantadas aqui, uma seria mesmo a quest\u00e3o de terem uma casa s\u00f3 para si, construindo um novo lar, unidos em uma s\u00f3 carne, se conhecendo no dia a dia, f\u00edsica, emocional e espiritualmente, sem ter a interfer\u00eancia de terceiros. Outro ponto que \u00e9 muito relevante \u00e9 que o novo casal deixe de ter o financiamento dos pais assim que casar (salvo se s\u00e3o mission\u00e1rios e os pais s\u00e3o uns dos mantenedores do minist\u00e9rio). O sustento do lar vem do Senhor por meio do trabalho do esposo e n\u00e3o do pai do esposo ou do sogro do esposo. Se n\u00e3o houver um bom planejamento durante os preparativos do casamento, voc\u00eas j\u00e1 v\u00e3o entrar no casamento cheios de d\u00edvidas e, talvez, j\u00e1 entrem para a estat\u00edstica dos div\u00f3rcios que acontecem por problemas financeiros. Ali\u00e1s o div\u00f3rcio n\u00e3o deve nem ser considerado por n\u00f3s crist\u00e3os, no entanto pela dureza dos nossos cora\u00e7\u00f5es (Mt 19.8) constuma-se ouvir por a\u00ed essa frase: \u201c\u2014 Se n\u00e3o der certo, separa!\u201dA qual n\u00e3o deve nem ser pensada por n\u00f3s!<\/p>\n<p>Voltando \u00e0 quest\u00e3o da casa, muitos tem d\u00favida entre comprar ou alugar e isso depende muito do quanto reservado voc\u00eas t\u00eam para investir na parcela de entrada no im\u00f3vel. Se voc\u00eas optarem por alugar e investir o dinheiro que t\u00eam da parcela de entrada e mensalmente aplicarem mais (tendo disciplina para isso) \u00e9 uma \u00f3tima op\u00e7\u00e3o, pois voc\u00eas v\u00e3o fazer o seu dinheiro trabalhar para voc\u00eas e n\u00e3o pagar\u00e3o juros para parcelar o valor do im\u00f3vel. Mas se voc\u00eas n\u00e3o s\u00e3o o tipo de casal com disciplina, o melhor seria fazer um financiamento. Mas comece pequeno, reservem o valor m\u00e1ximo para a parcela de entrada que conseguirem, assim as presta\u00e7\u00f5es ficar\u00e3o com valor mais baixo. E n\u00e3o confiem deliberadamente nos agentes banc\u00e1rios, pois eles trabalham para fazer o banco lucrar, procurem pessoas da \u00e1rea financeira para serem aconselhados. Lembrem-se tamb\u00e9m de analisar as dist\u00e2ncias entre o im\u00f3vel desejado e os locais que mais frequentam: trabalho, escola\/cursos, igreja, para que n\u00e3o gastem muito com combust\u00edvel ou transporte.<\/p>\n<p><span style=\"font-weight: normal !msorm;\"><strong>2<\/strong><\/span><span style=\"font-weight: normal !msorm;\"><strong><u><sup>o<\/sup><\/u><\/strong><\/span><span style=\"font-weight: normal !msorm;\"><strong> Passo:<\/strong><\/span> <span style=\"font-weight: normal !msorm;\"><strong>Planejamento financeiro<\/strong><\/span>. Sabe aquele casal da igreja que voc\u00eas os consideram exemplo? Que vivem uma vida modesta, equilibrada, que \u00e9 percept\u00edvel que h\u00e1 um bom planejamento financeiro na vida do casal (de prefer\u00eancia que ainda n\u00e3o tenham filhos)? Pois bem, se acheguem a eles, pe\u00e7am que os ajudem a informar os valores que gastam por m\u00eas dos itens necess\u00e1rios para se viver: mercado, \u00e1gua, luz, internet, g\u00e1s, IPTU. Esses valores variam de cidade para cidade, de acordo com o custo de vida. Com esses valores em mente, j\u00e1 \u00e9 poss\u00edvel ter uma ideia do que voc\u00eas precisar\u00e3o separar por m\u00eas no or\u00e7amento de custos que voc\u00eas possivelmente n\u00e3o tenham hoje como solteiros. Lucas 14.28 nos diz que devemos fazer planejamentos, mas n\u00e3o devemos andar ansiosos com isso (Mt 6.25). Tenho visto a m\u00e3o do Senhor operar na vida de noivos que andam com os passos firmes na presen\u00e7a do Senhor e com o cora\u00e7\u00e3o pronto a glorific\u00e1-lo com seus casamentos. \u00c9 assim que o Senhor cuida dos seus.<\/p>\n<p><span style=\"font-weight: normal !msorm;\"><strong>3<u><sup>o<\/sup><\/u> Passo:<\/strong><\/span> <strong>O culto do casamento<\/strong>. Voc\u00ea e seu noivo devem pensar em como vai ser o culto de louvor e gratid\u00e3o a Deus, rogando a Ele as b\u00ean\u00e7\u00e3os para essa nova fam\u00edlia e tamb\u00e9m ser\u00e1 uma \u00f3tima oportunidade de amigos e familiares serem evangelizados.<\/p>\n<p>Particularmente eu penso que os casamentos devem ser nas igrejas mesmo, pois h\u00e1 uma maior rever\u00eancia e aten\u00e7\u00e3o ao que est\u00e1 sendo pregado.<\/p>\n<p>Sei que muitas vezes as noivinhas optam por fazer a cerim\u00f4nia do casamento no local da festa para economizar com decora\u00e7\u00e3o e deslocamento dos convidados, mas, sinceramente, nesse dia, <span style=\"font-weight: normal !msorm;\"><strong>Cristo tem que ser o centro<\/strong><\/span> e seus convidados tem que ver isso na vida de voc\u00eas dois. Pensem em como voc\u00eas v\u00e3o honrar e glorificar mais a Deus e como seus convidados poder\u00e3o dar mais aten\u00e7\u00e3o a ele.<\/p>\n<p>As flores da esta\u00e7\u00e3o podem ser uma op\u00e7\u00e3o mais econ\u00f4mica. Sei que muitas vezes sonhamos com uma ou outra flor, mas hoje em dia a uni\u00e3o da beleza das flores que o Pai nos d\u00e1 com a criatividade que deu aos homens t\u00eam feito enfeites maravilhosos. Caso queira contratar uma ornamentadora que n\u00e3o vai caber no or\u00e7amento de voc\u00eas (e n\u00e3o tem problema se n\u00e3o couber) pe\u00e7a ajuda para aquela irm\u00e3 da igreja que voc\u00ea sabe que tem habilidade para fazer decora\u00e7\u00e3o, a internet est\u00e1 a\u00ed com milh\u00f5es de ideias criativas e com valores muito em conta. Lembrando, novamente, Cristo deve ser o centro desse dia!<\/p>\n<p><span style=\"font-weight: normal !msorm;\"><strong>4<u><sup>o<\/sup><\/u> passo:<\/strong><\/span> <span style=\"font-weight: normal !msorm;\"><strong>O <\/strong><\/span><span style=\"font-weight: normal !msorm;\"><strong>vestido<\/strong><\/span>. Ah! O vestido. Sonhamos tanto com esse vestido. O meu foi o mais rodado poss\u00edvel, me senti t\u00e3o linda! E meu noivo tamb\u00e9m achou, porque era o que ele mais dizia quando me viu! Noivinha querida, sonhe com seu vestido! Sonhe com voc\u00ea entrando na nave da igreja e seu lindo noivo te esperando sorridente! Mas olhe, seu vestido n\u00e3o precisa ser o de primeiro aluguel, n\u00e3o precisa ser bordado com cristais Swarovisk, n\u00e3o precisa ter a renda que veio de Paris. Ele precisa ser do jeito que sonhou, que se adeque a seu tipo de corpo, sem extravag\u00e2ncia, decotes e transpar\u00eancias. H\u00e1 dezenas e dezenas de lojas, experimente muitos, tenha paci\u00eancia, aproveite esse momento, que ser\u00e1 \u00fanico, at\u00e9 achar aquele que caia no seu gosto e no padr\u00e3o de mod\u00e9stia de uma mulher crist\u00e3 (1Tm 2.9). E, muito, muito importante, que caiba no bolso! Muitas vezes a m\u00e3e da noiva faz quest\u00e3o de pagar o t\u00e3o sonhado vestido da filha, ou o pai, ou uma tia, ou at\u00e9 voc\u00ea mesma juntou durante um bom tempo um dinheirinho para voc\u00ea estar exuberante. E esteja, mas n\u00e3o alugue naquela loja chique s\u00f3 para ostentar, v\u00e1 at\u00e9 aquela loja que voc\u00ea n\u00e3o d\u00e1 nada para ela e voc\u00ea pode achar um do seu gosto e que n\u00e3o vai esfolar ningu\u00e9m para pagar um pre\u00e7o exorbitante em um aluguel. E tem mais, as lojas normalmente j\u00e1 t\u00eam o v\u00e9u e o acess\u00f3rio de cabelo para emprestar, procure ali at\u00e9 achar um do seu gosto, n\u00e3o gaste mais com isso. Pechinchar no pre\u00e7o tamb\u00e9m \u00e9 uma boa, porque \u00e9 cultura do brasileiro deixar uma \u201cgordurinha\u201d no valor para a negocia\u00e7\u00e3o.<\/p>\n<p><span style=\"font-weight: normal !msorm;\"><strong>5<u><sup>o<\/sup><\/u> passo:<\/strong><\/span> <strong>Equipando a<\/strong> <strong>casa<span style=\"font-weight: normal !msorm;\">.<\/span><\/strong> Ore ao Senhor para que voc\u00eas tenham na casa de voc\u00eas os itens b\u00e1sicos e guardem o dinheiro para isso: Cama, guarda-roupa, arm\u00e1rios de cozinha, fog\u00e3o, geladeira, m\u00e1quina de lavar roupa, televis\u00e3o e rack. Fa\u00e7am um levantamento de pre\u00e7os dos itens novos e guardem o dinheiro. N\u00e3o se apressem a comprar, pois as pessoas tendem a presentear at\u00e9 mesmo com esses itens, mas n\u00e3o \u00e9 isso que deve estar no cora\u00e7\u00e3o ao convidar padrinhos, por exemplo, o que deve estar no cora\u00e7\u00e3o de voc\u00eas \u00e9 o vers\u00edculo 14 de Prov\u00e9rbios 11, ou seja, pessoas mais maduras na f\u00e9 que voc\u00eas, que tenham liberdade de darem conselhos a voc\u00eas durante a caminhada matrimonial. Se elas v\u00e3o ter dinheiro para presente, ou n\u00e3o, nem deve passar pela cabe\u00e7a dos noivos. Ultimamente cresceu o n\u00famero de pessoas usando os desapegos e vejo itens muito bons sendo negociados. Se voc\u00ea sente vergonha ou fica embara\u00e7ada em falar para as pessoas com medo do que elas v\u00e3o pensar de voc\u00ea, \u00e9 sinal de que existe um \u00eddolo no seu cora\u00e7\u00e3o, o desejo de agradar a homens. Pe\u00e7a ao Senhor para quebrar esse \u00eddolo e te dar for\u00e7as para vencer esse pecado.<\/p>\n<p><span style=\"font-weight: normal !msorm;\"><strong>6<u><sup>o<\/sup><\/u> passo:<\/strong><\/span> <span style=\"font-weight: normal !msorm;\"><strong>A F<\/strong><\/span><span style=\"font-weight: normal !msorm;\"><strong>esta.<\/strong><\/span> Voc\u00ea tem vontade de fazer uma festa? Eu j\u00e1 fui a casamentos que n\u00e3o tiveram festa, mas o culto foi t\u00e3o voltado ao louvor ao Senhor que n\u00e3o fez falta. Tamb\u00e9m j\u00e1 fui a casamentos que foi servido bolo e guaran\u00e1 pelos pr\u00f3prios di\u00e1conos da igreja e era vis\u00edvel a alegria deles em ajudar a servir no casamento de irm\u00e3os queridos. Tamb\u00e9m j\u00e1 fui a casamentos que toda a igreja se manifestou para ajudar. Meu cora\u00e7\u00e3o pulsa com isso, pois meu pensamento vai logo l\u00e1 para o Sl 133.1 <span style=\"font-style: normal !msorm;\"><em>\u201cOh! Como \u00e9 bom e agrad\u00e1vel viverem unidos os irm\u00e3os\u201d<\/em><\/span>, para mim \u00e9 uma das express\u00f5es de comunh\u00e3o da igreja, onde todos se juntam em servi\u00e7o ao pr\u00f3ximo. Mas tamb\u00e9m j\u00e1 fui em festa daquelas super festas que n\u00e3o pareciam casamento de crentes, s\u00f3 porque os noivos n\u00e3o queriam desagradar alguns convidados e acabaram se moldando aos padr\u00f5es deles (Cl 2.8) e n\u00e3o queriam que o casamento fosse mal falado ou porque queria seguir a moda, porque os casamentos de hoje TEM QUE TER os itens x, y e z. Precisa mesmo? Tem mesmo que ter? Ou o casamento pode ter a cara, o jeito dos noivos e o padr\u00e3o que eles vivem, segundo Cristo. Me lembro de um amigo que foi convidado para dar uma palavra em uma festa, a primeira coisa que ele falou: \u201cvoc\u00eas acham que Deus est\u00e1 aqui? Voc\u00eas acham que Deus est\u00e1 se agradando do que est\u00e1 vendo aqui?\u201d Ouvimos o sil\u00eancio, ouvimos a intrepidez desse irm\u00e3o e a sinceridade dele em exortar, o que n\u00e3o abalou em nada a amizade com os outros irm\u00e3os, pelo contr\u00e1rio, fortaleceu. Se voc\u00ea quer dar uma festa para seus convidados, n\u00e3o h\u00e1 pecado. Noivinha, se voc\u00ea quer oferecer um momento de festejar com aqueles que foram prestigiar esse momento \u00fanico, que se arrumaram, que estiveram presentes, fa\u00e7a! Desde que voc\u00ea use 2 par\u00e2metros: Deus est\u00e1 sendo glorificado em cada detalhe dessa festa? Tenho dinheiro em m\u00e3os para pagar por esses itens?<\/p>\n<p><span style=\"font-weight: normal !msorm;\"><strong>7<u><sup>o<\/sup><\/u> passo:<\/strong><\/span> <strong>A<\/strong> <span style=\"font-weight: normal !msorm;\"><strong>Lua de Mel<\/strong><\/span><strong>.<\/strong> Outro ponto bem complicado, porque nesse item p\u00f4de-se parcelar em tantas vezes que pode at\u00e9 passar para depois do casamento as presta\u00e7\u00f5es, j\u00e1 come\u00e7ando a vida a dois com d\u00edvida. Voc\u00eas dois precisam decidir que tipo de viagem gostam: praia, montanha, aventura. A quest\u00e3o de que falam de ser mais barato viajar para o exterior do que dentro do Brasil \u00e9 relativo e sazonal. Ir para algum lugar s\u00f3 para postar nas redes sociais \u00e9 ostenta\u00e7\u00e3o, querer mostrar para o outro o que voc\u00ea tem e o outro n\u00e3o \u00e9 incitar inveja e ci\u00fames nas pessoas. N\u00e3o que seja errado postarmos as fotos que mais gostamos, estou dizendo pela <span style=\"font-weight: normal !msorm;\"><strong>motiva\u00e7\u00e3o do nosso cora\u00e7\u00e3o<\/strong><\/span>, a real raz\u00e3o que nos leva a fazer isso ou aquilo. Ent\u00e3o, se a sua op\u00e7\u00e3o de escolha do local de lua de mel for para ostentar, est\u00e1 errado! A esccolha deve ser de comum acordo com seu noivo, afinal, ele tem que desfrutar tamb\u00e9m. Acompanhem as promo\u00e7\u00f5es dos sites, sempre aparecem coisas boas e adequem ao dinheiro que voc\u00eas t\u00eam separado para isso. O foco da lua de mel s\u00e3o os primeiros momentos a dois, o local \u00e9 secund\u00e1rio.<\/p>\n<h2>O seu cora\u00e7\u00e3o<\/h2>\n<p><span style=\"font-weight: normal !msorm;\"><strong>Pe\u00e7a ao Esp\u00edrito Santo que sonde seu cora\u00e7\u00e3o<\/strong><\/span> (Sl 139.23). Ore sobre cada quest\u00e3o, espere no Senhor, tenha calma em resolver cada item, procure algu\u00e9m para te ajudar nessa caminhada que n\u00e3o foque no seu \u201ceu\u201d, naquilo que \u201cvoc\u00ea merece\u201d &#8211; lembrando que n\u00e3o merecemos nada, \u00e9 Deus que nos alcan\u00e7a com sua gra\u00e7a e miseric\u00f3rdia &#8211; d\u00ea a ela liberdade de te exortar quando voc\u00ea estiver trilhando caminhos longe da Palavra de Deus, permita que ela aponte a cruz de Cristo para voc\u00ea. N\u00e3o esque\u00e7a do seu noivo, ele deve ser o primeiro a ser consultado em cada item, j\u00e1 v\u00e1 exercendo o cuidado e o pastoreio dele com voc\u00ea, assim como Cristo e sua igreja, n\u00e3o decida nada sem que os dois estejam em comum acordo.<\/p>\n<p>Oro por cada noivinha que ler esse artigo, para que seu casamento tenha o foco de glorificar ao Pai, desde os preparativos e at\u00e9 que a morte os separe.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Michelle Almeida. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\" target=\"_blank\" rel=\"noopener noreferrer\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/\" target=\"_blank\" rel=\"noopener noreferrer\">Noivas, vamos falar das finan\u00e7as para o casamento?<\/a>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Michelle Almeida: As finan\u00e7as para sua cerim\u00f4nia de casamento est\u00e3o seguindo uma ordem de planejamento b\u00edblico?<\/p>\n","protected":false},"author":641,"featured_media":49275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3065,624,409],"tags":[],"class_list":["post-49272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casamento-e-familia","category-mulheres","category-vida-crista","tema-dinheiro","tema-dinheiro-dup","tema-financas","tema-financas-dup","tema-mulheres","tema-vida-crista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noivas, vamos falar das finan\u00e7as para o casamento?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noivas, vamos falar das finan\u00e7as para o casamento?\" \/>\n<meta property=\"og:description\" content=\"Michelle Almeida: As finan\u00e7as para sua cerim\u00f4nia de casamento est\u00e3o seguindo uma ordem de planejamento b\u00edblico?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-13T13:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-11T18:56:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/06\/Noivas-vamos-falar-das-financ\u0327as-para-o-casamento-.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michelle Almeida\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michelle Almeida\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/\"},\"author\":{\"name\":\"Michelle Almeida\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/38b84d9f7639c5bf93f77875ec8c0a0c\"},\"headline\":\"Noivas, vamos falar das finan\u00e7as para o casamento?\",\"datePublished\":\"2019-06-13T13:00:33+00:00\",\"dateModified\":\"2020-02-11T18:56:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/\"},\"wordCount\":2644,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1\",\"articleSection\":[\"Casamento e fam\u00edlia\",\"Mulheres\",\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/\",\"name\":\"Noivas, vamos falar das finan\u00e7as para o casamento?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2019-06-13T13:00:33+00:00\",\"dateModified\":\"2020-02-11T18:56:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/06\\\/noivas-vamos-falar-das-financas-para-o-casamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noivas, vamos falar das finan\u00e7as para o casamento?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/38b84d9f7639c5bf93f77875ec8c0a0c\",\"name\":\"Michelle Almeida\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48d3993863412d65e75072d08ed9251e9eabd69e2cfad5cc441cc360cfa6cc3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48d3993863412d65e75072d08ed9251e9eabd69e2cfad5cc441cc360cfa6cc3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b48d3993863412d65e75072d08ed9251e9eabd69e2cfad5cc441cc360cfa6cc3?s=96&d=mm&r=g\",\"caption\":\"Michelle Almeida\"},\"description\":\"Michelle Almeida \u00e9 membro da Igreja Presbiteriana no Jardim Sul (IPB) em S\u00e3o Jos\u00e9 dos Campos, SP. Esposa do M\u00e1rcio e m\u00e3e da Clarissa e da Melissa. Formada em Administra\u00e7\u00e3o pela UNIP, cursa P\u00f3s-gradua\u00e7\u00e3o em Aconselhamento B\u00edblico pelo Cetevap e participa, desde 2018, das Confer\u00eancias de Treinamento em Aconselhamento B\u00edblico da ABCB (Associa\u00e7\u00e3o Brasileira de Conselheiros B\u00edblico). Exerceu o cargo de tesoureira em sua igreja durante 8 anos e ministra cursos sobre administra\u00e7\u00e3o financeira com enfoque b\u00edblico. \u00c9 tamb\u00e9m criadora do perfil @economiasegundoabiblia no Instagram.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/michelle-almeida\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noivas, vamos falar das finan\u00e7as para o casamento?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/","og_locale":"pt_BR","og_type":"article","og_title":"Noivas, vamos falar das finan\u00e7as para o casamento?","og_description":"Michelle Almeida: As finan\u00e7as para sua cerim\u00f4nia de casamento est\u00e3o seguindo uma ordem de planejamento b\u00edblico?","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2019-06-13T13:00:33+00:00","article_modified_time":"2020-02-11T18:56:32+00:00","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/06\/Noivas-vamos-falar-das-financ\u0327as-para-o-casamento-.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"author":"Michelle Almeida","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Michelle Almeida","Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/"},"author":{"name":"Michelle Almeida","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/38b84d9f7639c5bf93f77875ec8c0a0c"},"headline":"Noivas, vamos falar das finan\u00e7as para o casamento?","datePublished":"2019-06-13T13:00:33+00:00","dateModified":"2020-02-11T18:56:32+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/"},"wordCount":2644,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/06\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1","articleSection":["Casamento e fam\u00edlia","Mulheres","Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/","name":"Noivas, vamos falar das finan\u00e7as para o casamento?","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/06\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1","datePublished":"2019-06-13T13:00:33+00:00","dateModified":"2020-02-11T18:56:32+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/06\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/06\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/06\/noivas-vamos-falar-das-financas-para-o-casamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Noivas, vamos falar das finan\u00e7as para o casamento?"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/38b84d9f7639c5bf93f77875ec8c0a0c","name":"Michelle Almeida","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b48d3993863412d65e75072d08ed9251e9eabd69e2cfad5cc441cc360cfa6cc3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b48d3993863412d65e75072d08ed9251e9eabd69e2cfad5cc441cc360cfa6cc3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b48d3993863412d65e75072d08ed9251e9eabd69e2cfad5cc441cc360cfa6cc3?s=96&d=mm&r=g","caption":"Michelle Almeida"},"description":"Michelle Almeida \u00e9 membro da Igreja Presbiteriana no Jardim Sul (IPB) em S\u00e3o Jos\u00e9 dos Campos, SP. Esposa do M\u00e1rcio e m\u00e3e da Clarissa e da Melissa. Formada em Administra\u00e7\u00e3o pela UNIP, cursa P\u00f3s-gradua\u00e7\u00e3o em Aconselhamento B\u00edblico pelo Cetevap e participa, desde 2018, das Confer\u00eancias de Treinamento em Aconselhamento B\u00edblico da ABCB (Associa\u00e7\u00e3o Brasileira de Conselheiros B\u00edblico). Exerceu o cargo de tesoureira em sua igreja durante 8 anos e ministra cursos sobre administra\u00e7\u00e3o financeira com enfoque b\u00edblico. \u00c9 tamb\u00e9m criadora do perfil @economiasegundoabiblia no Instagram.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/michelle-almeida\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/06\/Noivas-vamos-falar-das-financ%CC%A7as-para-o-casamento-.jpg?fit=890%2C381&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-cOI","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/49272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/641"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=49272"}],"version-history":[{"count":1,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/49272\/revisions"}],"predecessor-version":[{"id":52382,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/49272\/revisions\/52382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/49275"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=49272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=49272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=49272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}