{"id":49622,"date":"2019-07-17T09:09:00","date_gmt":"2019-07-17T12:09:00","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=49622"},"modified":"2019-07-18T08:37:54","modified_gmt":"2019-07-18T11:37:54","slug":"ele-alimentou-dez-mil-orfaos-com-oracao-george-muller","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/","title":{"rendered":"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_btn title=&#8221;S\u00e9rie &#8220;Servos da Alegria Soberana&#8220; | Clique aqui para ler os outros artigos&#8221; size=&#8221;sm&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffiel.in%2F2FbDtf8||target:%20_blank|&#8221;][vc_column_text]George M\u00fcller construiu cinco grandes orfanatos e cuidou de 10.024 \u00f3rf\u00e3os durante sua vida. Quando ele come\u00e7ou em 1834, havia acomoda\u00e7\u00f5es para 3.600 \u00f3rf\u00e3os em toda a Inglaterra, e o dobro de crian\u00e7as com menos de oito anos estavam na pris\u00e3o. Um dos grandes efeitos do minist\u00e9rio de M\u00fcller foi inspirar os outros para que, de acordo com o bi\u00f3grafo A.T. Pierson, \u201ccinquenta anos depois que M\u00fcller come\u00e7ou seu trabalho, pelo menos cem mil \u00f3rf\u00e3os eram atendidos somente na Inglaterra\u201d <em>(George M\u00fcller de Bristol, 274).<\/em><\/p>\n<p>Ele orou por milh\u00f5es de d\u00f3lares (na moeda atual) para os \u00f3rf\u00e3os e nunca pediu dinheiro diretamente a ningu\u00e9m. Ele nunca recebeu um sal\u00e1rio nos \u00faltimos sessenta e oito anos de seu minist\u00e9rio, mas confiou em Deus para colocar no cora\u00e7\u00e3o das pessoas que lhe enviassem o que ele precisava. Ele nunca pegou um empr\u00e9stimo ou se endividou. E nem ele nem os \u00f3rf\u00e3os passaram fome.<\/p>\n<h2>Ativo at\u00e9 o fim<\/h2>\n<p>Ele fez tudo isso enquanto pregava tr\u00eas vezes por semana de 1830 a 1898, pelo menos dez mil vezes. E quando completou setenta anos, ele realizou o sonho de um longo trabalho mission\u00e1rio pelos dezessete anos seguintes, at\u00e9 os 87 anos. Ele viajou para 42 pa\u00edses, pregando em m\u00e9dia uma vez por dia e dirigindo-se a cerca de tr\u00eas milh\u00f5es de pessoas.<\/p>\n<p>Desde o final de suas viagens em 1892 (quando ele tinha 87 anos) at\u00e9 sua morte em mar\u00e7o de 1898, ele pregou em sua igreja e trabalhou para a <em>Scripture Knowledge Institution<\/em>. Ele conduziu uma reuni\u00e3o de ora\u00e7\u00e3o em sua igreja na noite de quarta-feira, 9 de mar\u00e7o de 1898. No dia seguinte, uma x\u00edcara de ch\u00e1 foi levada at\u00e9 ele \u00e0s sete da manh\u00e3, mas nenhuma resposta veio \u00e0 batida na porta. Ele foi encontrado morto no ch\u00e3o ao lado de sua cama.<\/p>\n<p>O funeral foi realizado na segunda-feira seguinte em Bristol, onde serviu por 66 anos. \u201cDezenas de milhares de pessoas reverentemente se posicionaram ao longo da rota da simples prociss\u00e3o; homens deixavam suas oficinas e escrit\u00f3rios, mulheres deixavam suas casas elegantes ou humildes cozinhas, todas procurando prestar um \u00faltimo sinal de respeito\u201d. Mil crian\u00e7as se reuniram para um culto na <em>Orphan House No. 3<\/em>. Eles haviam agora \u201cpela segunda vez perdido um \u2018pai\u2019\u201d. <em>(George M\u00fcller de Bristol, 285-86).<\/em><\/p>\n<h2>Mary e Susannah<\/h2>\n<p>M\u00fcller havia se casado duas vezes: com Mary Groves quando ele tinha vinte e cinco anos e com Susannah Sangar quando ele tinha 66 anos. Mary lhe deu quatro filhos. Dois eram natimortos. Um filho, Elias, morreu quando tinha um ano de idade. A filha de M\u00fcller, Lydia, casou-se com James Wright, que o sucedeu como chefe da institui\u00e7\u00e3o. Mas Lydia morreu em 1890 aos 57 anos. Cinco anos depois, M\u00fcller perdeu sua segunda esposa, apenas tr\u00eas anos antes de morrer. E assim ele sobreviveu \u00e0 sua fam\u00edlia e foi deixado sozinho com seu Salvador, sua igreja e dois mil filhos.<\/p>\n<p>Quando M\u00fcller recebeu o diagn\u00f3stico da febre reum\u00e1tica Mary, disse \u201cmeu cora\u00e7\u00e3o est\u00e1 prestes a ser quebrado por causa da profundidade do meu afeto\u201d <em>(A Narrative of Some of the Lord\u2019s Dealings with George M\u00fcller, 2:398). <\/em>Aquele que viu Deus responder dez mil ora\u00e7\u00f5es pelo apoio aos \u00f3rf\u00e3os n\u00e3o recebeu o que pediu desta vez. Ou recebeu?<\/p>\n<h2>\u201cEu estava satisfeito\u201d<\/h2>\n<p>Vinte minutos depois das quatro horas, no Dia do Senhor, 6 de fevereiro de 1870, Mary faleceu. \u201cCa\u00ed de joelhos e agradeci a Deus por sua liberta\u00e7\u00e3o e por t\u00ea-la levado para si e pedi ao Senhor que nos ajudasse e nos apoiasse\u201d <em>(A Narrative, 2: 400).<\/em> Ele lembrou mais tarde como ele se fortaleceu durante essas horas com o Salmo 84. 11: \u201cPorque o SENHOR Deus \u00e9 sol e escudo; o SENHOR d\u00e1 gra\u00e7a e gl\u00f3ria; nenhum bem sonega aos que andam retamente\u201d. E aqui n\u00f3s podemos ver a chave para sua vida:<\/p>\n<p><em>\u201cEu sou em mim mesmo um pobre pecador sem valor, mas fui salvo pelo sangue de Cristo; e eu n\u00e3o vivo no pecado; Eu ando em retid\u00e3o diante de Deus. Portanto, se for realmente bom para mim, minha querida esposa ser\u00e1 ressuscitada, ainda que esteja doente como est\u00e1. Deus a restaurar\u00e1 novamente. Mas se ela n\u00e3o for restaurada, ent\u00e3o n\u00e3o seria uma coisa boa para mim. E ent\u00e3o meu cora\u00e7\u00e3o est\u00e1 em repouso. Eu estou satisfeito com Deus. E tudo isso brota, como eu j\u00e1 disse antes, de aceitar a palavra de Deus, acreditando no que ele diz\u201d. (A Narrative, 2: 745)<\/em><\/p>\n<p>Aqui est\u00e1 o conjunto de convic\u00e7\u00f5es e experi\u00eancias inabal\u00e1veis \u200b\u200bque s\u00e3o a chave para a vida not\u00e1vel de M\u00fcller.<\/p>\n<ul>\n<li>\u201cEu sou em mim mesmo um pobre pecador sem valor\u201d.<\/li>\n<li>\u201cEu fui salvo pelo sangue de Cristo.\u201d<\/li>\n<li>\u201cEu n\u00e3o vivo em pecado.\u201d<\/li>\n<li>\u201cDeus \u00e9 soberano sobre a vida e a morte. Se for bom para ela e para mim, ela ser\u00e1 restaurada novamente. Se n\u00e3o for, ela n\u00e3o ser\u00e1\u201d.<\/li>\n<li>\u201cMeu cora\u00e7\u00e3o est\u00e1 em repouso\u201d.<\/li>\n<li>\u201cEstou satisfeito com Deus\u201d.<\/li>\n<\/ul>\n<p>Tudo isso vem de tomar Deus em sua palavra. Ali voc\u00ea v\u00ea o ser mais \u00edntimo de George M\u00fcller e a chave de sua vida &#8211; a palavra de Deus, revelando seu pecado, revelando seu Salvador, revelando a soberania de Deus, revelando a bondade de Deus, revelando a promessa de Deus, despertando sua f\u00e9, satisfazendo sua alma. \u201cEu estou satisfeito com Deus\u201d.<\/p>\n<h2>F\u00e9: Dom ou Gra\u00e7a?<\/h2>\n<p>Ent\u00e3o, suas ora\u00e7\u00f5es por Mary foram respondidas? Para entender como o pr\u00f3prio M\u00fcller responderia a essa pergunta, temos que ver a maneira como ele distinguiu o <em>dom<\/em> extraordin\u00e1rio da f\u00e9 e a <em>gra\u00e7a<\/em> comum da f\u00e9. Ele insistia constantemente, quando as pessoas o colocavam em um pedestal, que ele n\u00e3o tinha o dom da f\u00e9 s\u00f3 porque orava por suas pr\u00f3prias necessidades e pelas necessidades dos \u00f3rf\u00e3os, e o dinheiro chegava de maneira not\u00e1vel.<\/p>\n<p>A raz\u00e3o pela qual ele \u00e9 t\u00e3o inflex\u00edvel sobre isso \u00e9 que toda a sua vida &#8211; especialmente no modo como ele sustentou os \u00f3rf\u00e3os pela f\u00e9 e ora\u00e7\u00e3o sem pedir dinheiro a ningu\u00e9m al\u00e9m de Deus &#8211; foi conscientemente planejado para encorajar os crist\u00e3os em rela\u00e7\u00e3o a que que Deus \u00e9 realmente confi\u00e1vel para atender suas necessidades. Nunca entenderemos a paix\u00e3o de M\u00fcller pelo minist\u00e9rio dos \u00f3rf\u00e3o se n\u00e3o vermos que o bem dos \u00f3rf\u00e3os ficava em segundo lugar.<\/p>\n<p><em>\u201cAs tr\u00eas principais raz\u00f5es para o estabelecimento de uma Casa dos \u00d3rf\u00e3os s\u00e3o: 1) Que Deus seja glorificado, caso ele tenha prazer em me fornecer os meios, em vista de que n\u00e3o \u00e9 algo v\u00e3o confiar nele; e assim a f\u00e9 de seus filhos pode ser fortalecida. 2) O bem-estar espiritual de filhos sem pai e sem m\u00e3e. 3) Seu bem-estar temporal\u201d. (A Narrative, 1: 103)<\/em><\/p>\n<p>Essa foi a principal paix\u00e3o e objetivo unificador do minist\u00e9rio de M\u00fcller: <em>viver uma vida e liderar um minist\u00e9rio de forma a provar que Deus \u00e9 real, que Deus \u00e9 digno de confian\u00e7a e que Deus responde \u00e0 ora\u00e7\u00e3o. <\/em>Ele construiu orfanatos da maneira que ele fez para ajudar os crist\u00e3os a confiar em Deus. Ele repete isso de novo e de novo.<\/p>\n<h2>Tomando Deus em Sua Palavra<\/h2>\n<p>Agora vemos por que ele era t\u00e3o inflex\u00edvel em rela\u00e7\u00e3o a que sua f\u00e9 n\u00e3o era o dom da f\u00e9 mencionado em 1Cor\u00edntios 12. 9, que somente algumas pessoas t\u00eam, mas era a gra\u00e7a da f\u00e9 que todos os crist\u00e3os deveriam ter. Se os crist\u00e3os simplesmente disserem: \u201cM\u00fcller est\u00e1 em uma classe exclusiva; ele tem o dom da f\u00e9\u201d, ent\u00e3o estamos todos fora dessa conex\u00e3o e ele n\u00e3o pode mais ser um est\u00edmulo, prova e inspira\u00e7\u00e3o em rela\u00e7\u00e3o a como devemos viver. Aqui est\u00e1 o que ele diz:<\/p>\n<p><em>\u201cA diferen\u00e7a entre o dom e a gra\u00e7a da f\u00e9 parece-me isto. De acordo com o <\/em>dom<em> da f\u00e9, eu posso fazer alguma coisa, ou crer que uma coisa acontecer\u00e1, o n\u00e3o fazer, ou o n\u00e3o acreditar nessa coisa n\u00e3o seria pecado; j\u00e1 de acordo com a <\/em>gra\u00e7a<em> da f\u00e9, eu posso fazer alguma coisa, ou crer que uma coisa acontecer\u00e1, considerando que eu tenho a palavra de Deus como a base sobre a qual devo descansar, e, portanto, o n\u00e3o faz\u00ea-la, ou o n\u00e3o acreditar seria pecado.<\/em><\/p>\n<p><em>Por exemplo, o dom da f\u00e9 seria necess\u00e1rio, para acreditar que uma pessoa doente deveria ser restaurada novamente, embora n\u00e3o haja probabilidade humana: pois n\u00e3o h\u00e1 promessa para esse efeito; a gra\u00e7a da f\u00e9 \u00e9 necess\u00e1ria para acreditar que o Senhor me dar\u00e1 as necessidades da vida, se eu buscar primeiro o reino de Deus e Sua justi\u00e7a: pois h\u00e1 uma promessa nesse sentido (Mateus 6.33). (A Narrativa, 1:65)<\/em><\/p>\n<p>M\u00fcller n\u00e3o achou que tivesse algum fundamento b\u00edblico para ter certeza de que Deus pouparia sua esposa Mary. Ele admite que algumas vezes em sua vida ele tivesse recebido \u201calgo como o dom (n\u00e3o a gra\u00e7a) da f\u00e9 para que incondicionalmente pudesse pedir e procurar uma resposta\u201d, mas ele n\u00e3o tinha esse raro dom no caso de Mary (Uma Narrativa). 1:65). E ent\u00e3o ele orou por sua cura condicionalmente &#8211; a saber, se isso fosse bom para eles e para a gl\u00f3ria de Deus.<\/p>\n<p>Mas mais profundamente ele orou para que eles estivessem satisfeitos em Deus, seja o que quer que Deus fizesse. E Deus respondeu a essa ora\u00e7\u00e3o, ajudando M\u00fcller a crer no Salmo 84.11: \u201cnenhum bem sonega\u201d. Deus n\u00e3o reteve nada de bom para ele e ele ficou satisfeito com a vontade soberana de Deus. Tudo isso, diz ele, <em>\u201cbrota. . . de aceitar a palavra de Deus, acreditando no que ele diz\u201d. (A Narrative, 2: 745).<\/em><\/p>\n<h2>Oh, como ele ama<\/h2>\n<p>O objetivo da vida de George M\u00fcller era glorificar a Deus ajudando as pessoas a aceitarem a palavra de Deus. Para esse fim, ele saturou sua alma com a palavra de Deus. A certa altura, ele disse que havia lido a B\u00edblia de cinco a dez vezes mais do que qualquer outro livro. Seu objetivo era ver Deus em Jesus Cristo crucificado e ressuscitado dos mortos para que ele pudesse manter a felicidade de sua alma em Deus. Por esta profunda satisfa\u00e7\u00e3o em Deus, M\u00fcller foi libertado dos medos e lux\u00farias do mundo.<\/p>\n<p>E nessa liberdade de amor, ele escolheu uma estrat\u00e9gia de minist\u00e9rio e estilo de vida que colocava em evid\u00eancia a realidade, a confiabilidade e a beleza de Deus. Para usar suas pr\u00f3prias palavras, sua vida se tornou uma <em>\u201cprova vis\u00edvel da fidelidade imut\u00e1vel do Senhor\u201d (A Narrative, 1: 105).<\/em><\/p>\n<p>M\u00fcller foi sustentado nessa vida extraordin\u00e1ria por suas profundas convic\u00e7\u00f5es de que Deus \u00e9 soberano sobre o cora\u00e7\u00e3o humano e pode lev\u00e1-lo aonde desejar em resposta \u00e0 ora\u00e7\u00e3o; que Deus \u00e9 soberano sobre a vida e a morte; e que Deus \u00e9 bom em sua soberania e n\u00e3o ret\u00e9m as coisa boas para com aqueles que andam em retid\u00e3o. Ele se fortaleceu continuamente na etapa final da doen\u00e7a de sua esposa com as palavras de um hino:<\/p>\n<p><em>\u201cO melhor das b\u00ean\u00e7\u00e3os ele nos dar\u00e1<br \/>\n<\/em><em>Nada al\u00e9m do bem nos vai acontecer,<br \/>\n<\/em><em>Seguros para a gl\u00f3ria ele nos guiar\u00e1<br \/>\n<\/em><em>Oh, como ele ama\u201d! (A Narrative, 2:399)<\/em><\/p>\n<h2>Voc\u00ea n\u00e3o vai tentar desta maneira?<\/h2>\n<p>Deixarei M\u00fcller ter a palavra final de exorta\u00e7\u00e3o, pedindo que nos unamos a ele no caminho da f\u00e9 alegre e radical:<\/p>\n<p><em>\u201cMeu querido leitor crist\u00e3o, voc\u00ea n\u00e3o tentar\u00e1 dessa maneira? Voc\u00ea n\u00e3o vai conhecer por si mesmo. . . a preciosidade e a felicidade dessa forma de lan\u00e7ar todos os seus cuidados, encargos e necessidades sobre Deus? Este caminho est\u00e1 t\u00e3o aberto para voc\u00ea quanto para mim. . . Cada um \u00e9 convidado e ordenado a confiar no Senhor, a confiar nele com todo o seu cora\u00e7\u00e3o, lan\u00e7ar seu fardo sobre ele e invoc\u00e1-Lo no dia da ang\u00fastia. Voc\u00ea n\u00e3o vai fazer isso, meu querido irm\u00e3o em Cristo? Eu espero que voc\u00ea fa\u00e7a. Desejo que voc\u00ea prove a do\u00e7ura desse estado da alma, no qual, embora cercado por dificuldades e necessidades, ainda possa estar em paz, porque sabe que o Deus vivo, seu Pai Celestial, cuida de voc\u00ea\u201d. (A Narrativa, 1: 521).<\/em>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: John Piper. \u00a9 Desiring God Foundation. Website: desiringGod.org. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/www.desiringgod.org\/articles\/he-fed-ten-thousand-orphans-with-prayer\" target=\"_blank\" rel=\"noopener noreferrer\">He Fed Ten Thousand Orphans with Prayer<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/\">Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)<\/a>. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\" target=\"_blank\" rel=\"noopener noreferrer\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Paulo Reiss Junior. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>John Piper: M\u00fcller foi sustentado nessa vida extraordin\u00e1ria por suas profundas convic\u00e7\u00f5es de que Deus \u00e9 soberano sobre o cora\u00e7\u00e3o humano e pode lev\u00e1-lo aonde desejar em resposta \u00e0 ora\u00e7\u00e3o.<\/p>\n","protected":false},"author":16,"featured_media":49623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[507],"tags":[592,2424],"class_list":["post-49622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-da-igreja","tag-desiring-god","tag-servos-da-alegria-soberana","tema-biografia-crista","tema-historia-e-biografia","tema-a-oracao","tema-oracao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)\" \/>\n<meta property=\"og:description\" content=\"John Piper: M\u00fcller foi sustentado nessa vida extraordin\u00e1ria por suas profundas convic\u00e7\u00f5es de que Deus \u00e9 soberano sobre o cora\u00e7\u00e3o humano e pode lev\u00e1-lo aonde desejar em resposta \u00e0 ora\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-17T12:09:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-18T11:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/07\/Ele-alimentou-dez-mil-o\u0301rfa\u0303os-com-orac\u0327a\u0303o-George-Mu\u0308ller.jpg?fit=890%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John Piper\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Piper\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/\"},\"author\":{\"name\":\"John Piper\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/eccd77fc9d095509088ce03ddc4fe98b\"},\"headline\":\"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)\",\"datePublished\":\"2019-07-17T12:09:00+00:00\",\"dateModified\":\"2019-07-18T11:37:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/\"},\"wordCount\":2261,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1\",\"keywords\":[\"Desiring God Portugu\u00eas\",\"Servos da Alegria Soberana\"],\"articleSection\":[\"Hist\u00f3ria da Igreja\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/\",\"name\":\"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1\",\"datePublished\":\"2019-07-17T12:09:00+00:00\",\"dateModified\":\"2019-07-18T11:37:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1\",\"width\":890,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/07\\\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/eccd77fc9d095509088ce03ddc4fe98b\",\"name\":\"John Piper\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g\",\"caption\":\"John Piper\"},\"description\":\"John Piper \u00e9 o fundador e professor do desiringGod.org e chanceler do Bethlehem College &amp; Seminary. Por 33 anos, serviu como pastor da igreja Bethlehem Baptist Church, em Mine\u00e1polis, Minessota. Ele \u00e9 autor de mais de 50 livros, incluindo Em busca de Deus: Medita\u00e7\u00f5es de um hedonista crist\u00e3o e o mais recente Provid\u00eancia.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/john-piper\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/","og_locale":"pt_BR","og_type":"article","og_title":"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)","og_description":"John Piper: M\u00fcller foi sustentado nessa vida extraordin\u00e1ria por suas profundas convic\u00e7\u00f5es de que Deus \u00e9 soberano sobre o cora\u00e7\u00e3o humano e pode lev\u00e1-lo aonde desejar em resposta \u00e0 ora\u00e7\u00e3o.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2019-07-17T12:09:00+00:00","article_modified_time":"2019-07-18T11:37:54+00:00","og_image":[{"width":890,"height":381,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/07\/Ele-alimentou-dez-mil-o\u0301rfa\u0303os-com-orac\u0327a\u0303o-George-Mu\u0308ller.jpg?fit=890%2C381&ssl=1","type":"image\/jpeg"}],"author":"John Piper","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"John Piper","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/"},"author":{"name":"John Piper","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/eccd77fc9d095509088ce03ddc4fe98b"},"headline":"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)","datePublished":"2019-07-17T12:09:00+00:00","dateModified":"2019-07-18T11:37:54+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/"},"wordCount":2261,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/07\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1","keywords":["Desiring God Portugu\u00eas","Servos da Alegria Soberana"],"articleSection":["Hist\u00f3ria da Igreja"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/","name":"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/07\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1","datePublished":"2019-07-17T12:09:00+00:00","dateModified":"2019-07-18T11:37:54+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/07\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/07\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1","width":890,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/07\/ele-alimentou-dez-mil-orfaos-com-oracao-george-muller\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ele alimentou dez mil \u00f3rf\u00e3os com ora\u00e7\u00e3o (George M\u00fcller)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/eccd77fc9d095509088ce03ddc4fe98b","name":"John Piper","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5dcc1adfa38a525945a8a85865b303a2396fe586bc29eeef942060b9adc34fd?s=96&d=mm&r=g","caption":"John Piper"},"description":"John Piper \u00e9 o fundador e professor do desiringGod.org e chanceler do Bethlehem College &amp; Seminary. Por 33 anos, serviu como pastor da igreja Bethlehem Baptist Church, em Mine\u00e1polis, Minessota. Ele \u00e9 autor de mais de 50 livros, incluindo Em busca de Deus: Medita\u00e7\u00f5es de um hedonista crist\u00e3o e o mais recente Provid\u00eancia.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/john-piper\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/07\/Ele-alimentou-dez-mil-o%CC%81rfa%CC%83os-com-orac%CC%A7a%CC%83o-George-Mu%CC%88ller.jpg?fit=890%2C381&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-cUm","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/49622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=49622"}],"version-history":[{"count":0,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/49622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/49623"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=49622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=49622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=49622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}