{"id":50152,"date":"2019-08-24T18:00:43","date_gmt":"2019-08-24T21:00:43","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=50152"},"modified":"2019-08-27T11:24:05","modified_gmt":"2019-08-27T14:24:05","slug":"confissoes-de-um-viciado-em-louvor","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/","title":{"rendered":"Confiss\u00f5es de um viciado em louvor"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]A cena continua viva na minha mem\u00f3ria, embora j\u00e1 se tenham passados quase 20 anos.<\/p>\n<p>Estou sentado no meu quarto ao lado de nossa grande e velha casa da fazenda, um adolescente, ap\u00e1tico naquela hora da noite quando qualquer coisa \u00e9 melhor que dever de casa. \u00c9 uma noite quente de ver\u00e3o e as cigarras cantam seu coro como um ex\u00e9rcito de manifestantes com assobios. No meu pequeno toca-fitas Sanyo, coloco uma fita emprestada de um amigo. Keith Green, O mais recente cantor e compositor crist\u00e3o &#8211; bem, \u201co mais recente\u201d se comparado ao u\u00edsque Lismore 12 anos.<\/p>\n<p>Repito uma m\u00fasica v\u00e1rias vezes. O refr\u00e3o d\u00e1 um acorde profundo: \u201cQuando ou\u00e7o os louvores come\u00e7ar, n\u00e3o vejo nenhuma mancha em voc\u00ea, porque voc\u00ea \u00e9 meu filho e voc\u00ea me conhece. Para mim voc\u00ea \u00e9 apenas santo, nada do que voc\u00ea tenha feito permanece apenas o que voc\u00ea faz por mim\u201d.<\/p>\n<p>Eu escuto atentamente. \u201cQuando ou\u00e7o os louvores come\u00e7ar, n\u00e3o vejo mancha em voc\u00ea\u201d. Eu pondero como eu poderia louvar a Deus dessa maneira, para que ele olhasse para mim t\u00e3o favoravelmente. O fato de que essa \u201csalva\u00e7\u00e3o-pelo-louvor\u201d seja um tanto desonesta teologicamente n\u00e3o entra na minha cabe\u00e7a. Tudo em que estou interessado \u00e9 em como come\u00e7ar. Talvez eu deva ir \u00e0 noite de \u201cora\u00e7\u00e3o e louvor\u201d \u00e0s quartas-feiras na igreja e ver como isso \u00e9 feito &#8230;<\/p>\n<p>Assim come\u00e7ou, para um crist\u00e3o adolescente um pouco confuso, uma preocupa\u00e7\u00e3o com o \u201clouvor\u201d como um aspecto fundamental da vida crist\u00e3. Como a maioria das preocupa\u00e7\u00f5es adolescentes, se manteve intensa por alguns meses at\u00e9 que alguma outra coisa ocupasse seu lugar. Enquanto durou, eu fui obedientemente \u00e0 noite de ora\u00e7\u00e3o e louvor, onde eu descobri que a parte do \u201clouvor\u201d consistia em cantar refr\u00f5es devocionais, geralmente com os olhos fechados e bra\u00e7os erguidos. Li os livros de Merlin Carruthers, Prison to Praise e The Power of Praise, que me encorajaram a repetidamente dizer \u201cAleluia\u201d em rela\u00e7\u00e3o aos problemas da minha vida, a fim de faz\u00ea-los desaparecer. Tamb\u00e9m tentei isso no meu irm\u00e3ozinho com sucesso limitado.<\/p>\n<p>Uma coisa que eu nunca compreendi, como um adolescente fervoroso, era o que exatamente significava \u201clouvor\u201d. Por muito tempo presumi que voc\u00ea louvava ao Senhor dizendo \u201cAleluia\u201d, at\u00e9 que algu\u00e9m me informou que \u201cAleluia\u201d era apenas a palavra hebraica para \u201cLouvado seja o Senhor\u201d. Isso n\u00e3o me ajudou muito, porque significava que todos n\u00f3s est\u00e1vamos dizendo uns aos outros para \u201cLouvar ao Senhor\u201d o tempo todo (j\u00e1 que obviamente n\u00e3o est\u00e1vamos pedindo a Deus para que ele \u00a0\u201cLouvasse ao Senhor\u201d), mas n\u00f3s n\u00e3o est\u00e1vamos, na verdade, continuando com o \u201clouvor\u201d \u2013 seja l\u00e1 o que quer que ele fosse.<\/p>\n<p>Comecei ent\u00e3o a pensar que talvez o \u201clouvor\u201d fosse apenas outra maneira de dizer \u201ccantar\u201d, j\u00e1 que era o que sempre faz\u00edamos quando o ministro ou l\u00edder nos convidava para \u201clouvar a Deus\u201d. Talvez louvar fosse isso \u2013 era cantar uma can\u00e7\u00e3o a Deus. Eu ainda n\u00e3o tinha certeza disso.<\/p>\n<p>Embora todos parecessem concordar que o louvor era uma parte vital da vida crist\u00e3, e que isso tinha algo a ver com a ora\u00e7\u00e3o, e que provavelmente deveria ser cantado, ningu\u00e9m nunca me disse realmente como faz\u00ea-lo. Minhas experi\u00eancias nos vinte anos que se sucederam tamb\u00e9m n\u00e3o fizeram nada para aliviar minha confus\u00e3o.<\/p>\n<p>E ent\u00e3o, para o prop\u00f3sito deste artigo. O que exatamente \u00e9 \u201clouvor\u201d? E como se faz isso?<\/p>\n<p>Ao responder a essas perguntas, examinaremos principalmente esse livro em que mais da metade de todas as refer\u00eancias b\u00edblicas a \u201clouvor\u201d ocorrem &#8211; os Salmos. (Em nossa pr\u00f3xima edi\u00e7\u00e3o, continuaremos esta an\u00e1lise dos Salmos para ver como o louvor se relaciona com a ora\u00e7\u00e3o e como os salmos podem nos ajudar em nossas ora\u00e7\u00f5es.)<\/p>\n<h2>A import\u00e2ncia da \u201cpublicidade\u201d.<\/h2>\n<p>O t\u00edtulo hebraico para os Salmos (tehillim) significa simplesmente \u201clouvores\u201d, e certamente n\u00e3o podemos ler muitos salmos sem encontrar o chamado familiar para louvar (\u201cLouvai ao Senhor\u201d) ou alguma outra express\u00e3o de louvor (\u201ceu te louvarei, \u00f3 SENHOR\u201d).<\/p>\n<p>Em seu contexto original, os Salmos eram provavelmente algo como o hin\u00e1rio de Israel. Muitos, se n\u00e3o todos, eram acompanhados de m\u00fasica, e parece prov\u00e1vel que o templo fosse o lugar habitual onde eram cantados.<\/p>\n<p>Mas, se \u00e9 claro que a m\u00fasica esteve frequentemente envolvida no louvor de Israel, \u00e9 igualmente claro que era o acompanhamento para louvar, n\u00e3o o louvor em si. O canto era muitas vezes o modo de express\u00e3o, e os instrumentos musicais eram o acompanhamento (\u201cEu te louvarei com a lira e a harpa\u201d), mas o que estava sendo expresso e acompanhado? Quando soou o chamado para \u201cLouvar ao o Senhor\u201d, o que os israelitas na congrega\u00e7\u00e3o esperavam que acontecesse a seguir? O que era o \u201clouvor\u201d?<\/p>\n<h2>O que \u00e9 louvor?<\/h2>\n<p>Para muitos crist\u00e3os modernos, \u201clouvor\u201d \u00e9 um encontro pessoal com Deus, geralmente com um tom fortemente emocional, no qual falamos ou cantamos para ele e lhe dizemos o quanto o amamos e o honramos. \u201cN\u00f3s te louvamos Senhor. N\u00f3s te honramos, te glorificamos, exaltamos o teu grande e glorioso nome; louvamos-te Jesus\u201d, e assim por diante. O louvor \u00e9 geralmente visto como uma pr\u00e1tica religiosa especial, normalmente a ser realizada nas reuni\u00f5es da igreja.<\/p>\n<p>Gra\u00e7as, em grande parte ao movimento carism\u00e1tico, \u00e9 aqui que \u201clouvor\u201d est\u00e1 frequentemente localizado na consci\u00eancia crist\u00e3 moderna. Geralmente \u00e9 proferido ao mesmo tempo que \u201cadora\u00e7\u00e3o\u201d &#8211; como nos onipresentes \u00e1lbuns de \u201clouvor e adora\u00e7\u00e3o\u201d que inundam livrarias crist\u00e3s e m\u00eddias de m\u00fasica dos carros. \u00c9 uma experi\u00eancia de comunh\u00e3o com Deus, onde a presen\u00e7a de Deus \u00e9 especialmente encontrada.<\/p>\n<p>No entanto, como tantas vezes acontece com as palavras e ideias b\u00edblicas, a palavra hebraica traduzida como \u201clouvor\u201d descreve uma atividade muito mais comum e secular. Suponhamos que vemos um amigo fazendo algo excelente ou percebemos uma boa qualidade ou atributo em seu car\u00e1ter. \u201cLouvor\u201d acontece quando, tendo observado essa excel\u00eancia, falamos a outras pessoas sobre isso. Podemos ficar de p\u00e9 com nosso amigo diante de seus colegas e dizer a todos, bem na frente dele, o que ele fez e como \u00e9 excelente. N\u00f3s o elogiamos. Descrevemos qu\u00e3o nobre \u00e9 seu car\u00e1ter ou qu\u00e3o extraordin\u00e1rias s\u00e3o suas realiza\u00e7\u00f5es.<\/p>\n<p>Louvor \u00e9 essa proclama\u00e7\u00e3o de qu\u00e3o bom algu\u00e9m \u00e9. \u00c9 \u201cpublicidade\u201d. Nos Salmos, \u00e9 publicidade sobre Deus. Consiste em contar o mais alto e amplamente poss\u00edvel as excel\u00eancias do Deus de Israel, para que todos possam honr\u00e1-lo.<\/p>\n<p>Assim, quando h\u00e1 uma exorta\u00e7\u00e3o para louvar a Deus nos Salmos, ele \u00e9 invariavelmente seguido pelo pr\u00f3prio louvor &#8211; a declara\u00e7\u00e3o de seu car\u00e1ter e feitos poderosos para o indiv\u00edduo ou a na\u00e7\u00e3o. O salmo 96 \u00e9 um exemplo cl\u00e1ssico:<\/p>\n<p><em>\u201cCantai ao SENHOR um c\u00e2ntico novo, cantai ao SENHOR, todas as terras.\u00a0Cantai ao SENHOR, bendizei o seu nome; proclamai a sua salva\u00e7\u00e3o, dia ap\u00f3s dia. Anunciai entre as na\u00e7\u00f5es a sua gl\u00f3ria, entre todos os povos, as suas maravilhas. Porque grande \u00e9 o SENHOR e mui digno de ser louvado, tem\u00edvel mais que todos os deuses. Porque todos os deuses dos povos n\u00e3o passam de \u00eddolos; o SENHOR, por\u00e9m, fez os c\u00e9us. Gl\u00f3ria e majestade est\u00e3o diante dele, for\u00e7a e formosura, no seu santu\u00e1rio\u201d. (Salmo 96. 1-6).<\/em><\/p>\n<p>Essa proclama\u00e7\u00e3o p\u00fablica da grandeza de Deus nos Salmos abrange toda a gama do car\u00e1ter e das realiza\u00e7\u00f5es de Deus. Ele \u00e9 aclamado por ser o todo-poderoso Criador e sustentador de todas as coisas (Sl 74; 104), o Juiz da Terra (Sl 33. 6-9,13-15; 11), que governa com justi\u00e7a (Sl 9. 8) e age com firme e infal\u00edvel amor (Sl 136). Os Salmos ressoam com a maravilha de que esse Deus bom, justo e bom entrou em alian\u00e7a com Israel, que ele baixou das alturas para am\u00e1-los em suas profundezas. Ele \u00e9 o Redentor de Israel, ambos corporativamente (Sl 105; 136; 89) e individualmente (Sl 22; 30; 32).<\/p>\n<p>O louvor, ent\u00e3o, \u00e9 essencialmente publicidade, por mais odiosa que essa compara\u00e7\u00e3o possa parecer. De fato, para provocar ainda mais a compara\u00e7\u00e3o, \u00e9 como anunciar de tr\u00eas maneiras.<\/p>\n<h2>Louvor e m\u00fasica.<\/h2>\n<p>Como a publicidade, o louvor pode ser acompanhado pela m\u00fasica, embora a m\u00fasica n\u00e3o seja a ess\u00eancia dele. M\u00fasica \u00e9 louvar como o jingle \u00e9 publicidade. Pode torn\u00e1-lo eficaz, memor\u00e1vel, at\u00e9 mesmo grandioso, mas a menos que o produto seja realmente descrito e promovido, a m\u00fasica \u00e9 de pouca utilidade.<\/p>\n<p>No caso do louvor a Deus, \u00e9 mais apropriado fazer um som &#8211; como no Salmo 150, onde uma verdadeira orquestra \u00e9 montada para acompanhar o louvor. \u00c9 apropriado n\u00e3o apenas por causa da alegria e celebra\u00e7\u00e3o que naturalmente se desenvolvem no povo de Deus, por ele se recordar de todas as miseric\u00f3rdias de Deus, mas tamb\u00e9m porque torna a publicidade mais eficaz. A m\u00fasica n\u00e3o \u00e9 para o benef\u00edcio de Deus, como se ele gostasse de uma boa m\u00fasica, ou como se Baal precisasse acordar com um barulho alto. \u00c9 mais para aqueles que ouvem, de modo que, no contexto do templo, a proclama\u00e7\u00e3o da grandeza de Deus possa ter um grande efeito.<\/p>\n<p>Talvez um salmista moderno escreveria: \u201cLouvai a Deus com um poderoso sistema de PA, e com o som regulado em 11\u201d.<\/p>\n<h2>Formas diferentes.<\/h2>\n<p>Como publicidade, o louvor pode assumir diferentes formas. Muitas vezes, nos Salmos, \u00e9 na terceira pessoa &#8211; isto \u00e9, \u00e9 falado ou cantado sobre Deus, sendo dirigido \u00e0queles que ouvem e n\u00e3o ao pr\u00f3prio Deus. Isso ocorre na presen\u00e7a de Deus, sem d\u00favidas, mas \u00e9 dirigido \u00e0queles que est\u00e3o ouvindo:<\/p>\n<p><em>\u201cDo nascimento do sol at\u00e9 ao ocaso, louvado seja o nome do SENHOR. Excelso \u00e9 o SENHOR, acima de todas as na\u00e7\u00f5es, e a sua gl\u00f3ria, acima dos c\u00e9us. Quem h\u00e1 semelhante ao SENHOR, nosso Deus, cujo trono est\u00e1 nas alturas, que se inclina para ver o que se passa no c\u00e9u e sobre a terra? Ele ergue do p\u00f3 o desvalido e do monturo, o necessitado, para o assentar ao lado dos pr\u00edncipes, sim, com os pr\u00edncipes do seu povo. Faz que a mulher est\u00e9ril viva em fam\u00edlia e seja alegre m\u00e3e de filhos. Aleluia\u201d! (Sl 113. 3-9).<\/em><\/p>\n<p>\u00c0s vezes \u00e9 na forma de um testemunho pessoal:<\/p>\n<p><em>\u201cEsperei confiantemente pelo SENHOR; ele se inclinou para mim e me ouviu quando clamei por socorro.\u00a0Tirou-me de um po\u00e7o de perdi\u00e7\u00e3o, de um tremedal de lama; colocou-me os p\u00e9s sobre uma rocha e me firmou os passos.\u00a0E me p\u00f4s nos l\u00e1bios um novo c\u00e2ntico, um hino de louvor ao nosso Deus; muitos ver\u00e3o essas coisas, temer\u00e3o e confiar\u00e3o no SENHOR\u201d. (Sl 40.1-3).<\/em><\/p>\n<p>E \u00e0s vezes \u00e9 endere\u00e7ado diretamente ao pr\u00f3prio Deus:<\/p>\n<p><em>\u201cRender-te-ei gra\u00e7as, SENHOR, de todo o meu cora\u00e7\u00e3o; na presen\u00e7a dos poderosos te cantarei louvores. Prostrar-me-ei para o teu santo templo e louvarei o teu nome, por causa da tua miseric\u00f3rdia e da tua verdade, pois magnificaste acima de tudo o teu nome e a tua palavra. No dia em que eu clamei, tu me acudiste e alentaste a for\u00e7a de minha alma. Render-te-\u00e3o gra\u00e7as, \u00f3 SENHOR, todos os reis da terra, quando ouvirem as palavras da tua boca\u201d, (Sl 138. 1-4).<\/em><\/p>\n<p>No entanto, mesmo quando o louvor \u00e9 dirigido a Deus, ele tem o car\u00e1ter de proclama\u00e7\u00e3o. O salmista fala ou canta a Deus sobre todas as coisas que Deus \u00e9 e fez, mas est\u00e1 fazendo isso na frente dos outros. Deus \u00e9 \u201clouvado\u201d quando os outros ouvem falar das coisas maravilhosas que ele fez. O que nos leva \u00e0 terceira considera\u00e7\u00e3o de como \u00e9 como louvor \u00e9 publicidade.<\/p>\n<h2>Louvor \u00e9 p\u00fablico.<\/h2>\n<p>Assim como n\u00e3o se pode conduzir uma campanha publicit\u00e1ria em particular, ningu\u00e9m pode \u201clouvar\u201d em particular. A natureza b\u00e1sica do louvor \u00e9 a proclama\u00e7\u00e3o p\u00fablica, reconhecimento e aclama\u00e7\u00e3o de Deus. Observe como o salmista expressa isso no Salmo 40:<\/p>\n<p><em>\u201cProclamei as boas-novas de justi\u00e7a na grande congrega\u00e7\u00e3o; jamais cerrei os l\u00e1bios, tu o sabes, SENHOR. N\u00e3o ocultei no cora\u00e7\u00e3o a tua justi\u00e7a; proclamei a tua fidelidade e a tua salva\u00e7\u00e3o; n\u00e3o escondi da grande congrega\u00e7\u00e3o a tua gra\u00e7a e a tua verdade\u201d. (Sl 40. 9-10).<\/em><\/p>\n<p>\u00c9 como se o ato de resgate ou liberta\u00e7\u00e3o n\u00e3o fosse apenas para o salmista. \u00c9 dado a ele para que ele possa proclam\u00e1-lo para toda a comunidade. Escond\u00ea-lo ou mant\u00ea-lo para si mesmo \u00e9 impens\u00e1vel. Ele deve testificar na grande assembleia (Sl 35.18).<\/p>\n<p>Isso, \u00e9 claro, n\u00e3o quer dizer que em nossas ora\u00e7\u00f5es particulares n\u00e3o damos gra\u00e7as a Deus por quem ele \u00e9 e pelo que ele faz. Expressamos nossa adora\u00e7\u00e3o por seu car\u00e1ter e obras gloriosas. No entanto, se vamos usar palavras b\u00edblicas, devemos us\u00e1-las de maneira b\u00edblica. Essa a\u00e7\u00e3o de gra\u00e7as pessoal e privada n\u00e3o \u00e9 \u201clouvor\u201d no sentido b\u00edblico. Louvor sempre tem o car\u00e1ter de proclama\u00e7\u00e3o p\u00fablica.<\/p>\n<h2>Publicidade e n\u00f3s.<\/h2>\n<p>No NT, o louvor tem a mesma forma b\u00e1sica que no AT. Como Hebreus 13.15 diz:<\/p>\n<p><em>\u201cPor meio de Jesus, pois, ofere\u00e7amos a Deus, sempre, sacrif\u00edcio de louvor, que \u00e9 o fruto de l\u00e1bios que confessam o seu nome\u201d.<\/em><\/p>\n<p>Ou como Pedro expressa:<\/p>\n<p><em>\u201cV\u00f3s, por\u00e9m, sois ra\u00e7a eleita, sacerd\u00f3cio real, na\u00e7\u00e3o santa, povo de propriedade exclusiva de Deus, a fim de proclamardes as virtudes daquele que vos chamou das trevas para a sua maravilhosa luz; v\u00f3s, sim, que, antes, n\u00e3o \u00e9reis povo, mas, agora, sois povo de Deus, que n\u00e3o t\u00ednheis alcan\u00e7ado miseric\u00f3rdia, mas, agora, alcan\u00e7astes miseric\u00f3rdia\u201d. (1Pe 2. 9-10).<\/em><\/p>\n<p>O louvor \u00e9 uma confiss\u00e3o, um testemunho, uma declara\u00e7\u00e3o do que Deus faz. Naturalmente, para n\u00f3s, a quem chegou o fim dos s\u00e9culos, o louvor n\u00e3o mais se concentra no templo f\u00edsico de Jerusal\u00e9m e em sua adora\u00e7\u00e3o. Atrav\u00e9s de Jesus, somos todos templos do Esp\u00edrito Santo, e assim o louvor acontece n\u00e3o no contexto c\u00faltico de uma reuni\u00e3o no templo, mas sempre e onde quer que \u201cconfessemos seu nome\u201d. Quando declaramos sua grandeza para os outros, contando como ele nos mostrou miseric\u00f3rdia e nos chamou para ser seu pr\u00f3prio povo, ent\u00e3o estamos louvando a Deus.<\/p>\n<p>No Novo Testamento, ent\u00e3o, o louvor \u00e9 um pouco semelhante ao evangelismo. \u00c9 a publicidade dos poderosos feitos salv\u00edficos de Deus. Por causa do que Deus fez por n\u00f3s, testificamos. N\u00e3o \u00e9 algo que s\u00f3 fazemos na igreja, mais do que apenas proclamamos o evangelho quando nos reunimos. N\u00e3o \u00e9 algo que \u00e9 definido somente como m\u00fasica.<\/p>\n<p>Essa democratiza\u00e7\u00e3o ou expans\u00e3o do louvor no NT espelha a forma como muitas categorias do AT s\u00e3o transformadas em Cristo &#8211; \u201ctemplo\u201d, \u201cadora\u00e7\u00e3o\u201d, \u201csacerdote\u201d, \u201csacrif\u00edcio\u201d e assim por diante. De fato, muitos dos erros e problemas que enfrentamos na vida da igreja prov\u00eam de uma falha em reconhecer essa transforma\u00e7\u00e3o.<\/p>\n<p>No caso do louvor, muitas igrejas n\u00e3o conseguem libertar-se de um modo de pensar do AT \/ templo sobre como o louvor deve acontecer. O louvor \u00e9 visto como uma atividade ou experi\u00eancia religiosa, cultual, preparada para a m\u00fasica, a ser conduzida na igreja. Assim como Deus foi visto especialmente presente no templo do AT, sua presen\u00e7a especial era manifestada quando can\u00e7\u00f5es de louvor eram cantadas e uma atmosfera particular era criada.<\/p>\n<p>Mas em Cristo, o Pai vem e faz sua habita\u00e7\u00e3o dentro de cada um de n\u00f3s atrav\u00e9s do seu Esp\u00edrito. Ele est\u00e1 constantemente presente. Nossa adora\u00e7\u00e3o espiritual \u00e9 o sacrif\u00edcio de toda a nossa vida para ele (Rm 12. 1-2), e nosso louvor, da mesma forma, \u00e9 a confiss\u00e3o ao longo da vida e em toda a nossa vida, diante do mundo, do que ele fez por n\u00f3s.<\/p>\n<p>Tamb\u00e9m deve ser dito que muitas igrejas hoje n\u00e3o reconhecem a natureza b\u00e1sica do louvor, nos Salmos e no NT. Louvor n\u00e3o \u00e9 fazer m\u00fasica bonita para Deus. N\u00e3o \u00e9 um encontro pessoal e m\u00edstico com Deus. Nem louvamos a Deus dizendo: \u201cN\u00f3s te louvamos, Deus, obrigado Jesus, Aleluia\u201d.<\/p>\n<p>Louvor \u00e9 publicidade. \u00c9 lembrar e declarar quem \u00e9 Deus e o que ele fez. Acontece pelo ouvir, \u00e9 feito contando aos outros. \u00c9 exaltar a Deus, falar bem dele, transmitindo suas virtudes e excel\u00eancia. Louvor brota da salva\u00e7\u00e3o, do que ele fez por n\u00f3s. Louvor \u00e9 o testemunho dos redimidos.<\/p>\n<p>E nesse sentido, suponho, Keith Green estava no caminho errado. Ele deveria ter cantado: \u201cPorque n\u00e3o h\u00e1 mancha em voc\u00ea, eu quero ouvir o louvor come\u00e7ar\u201d.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Tony Payne. \u00a9 Matthias Media. Website: <a href=\"https:\/\/matthiasmedia.com\" target=\"_blank\" rel=\"noopener noreferrer\">matthiasmedia.com<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/matthiasmedia.com\/briefing\/1996\/02\/confessions-of-a-teenage-praise-junkie\/\" target=\"_blank\" rel=\"noopener noreferrer\">Confessions of a teenage praise junkie<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/\" target=\"_blank\" rel=\"noopener noreferrer\">Confiss\u00f5es de um viciado em louvor<\/a>. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\" target=\"_blank\" rel=\"noopener noreferrer\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Paulo Reiss Junior. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Louvor \u00e9 publicidade. \u00c9 lembrar e declarar quem \u00e9 Deus e o que ele fez.<\/p>\n","protected":false},"author":728,"featured_media":50232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2948],"tags":[],"class_list":["post-50152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culto-louvor-adoracao","tema-louvor-e-adoracao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confiss\u00f5es de um viciado em louvor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confiss\u00f5es de um viciado em louvor\" \/>\n<meta property=\"og:description\" content=\"Louvor \u00e9 publicidade. \u00c9 lembrar e declarar quem \u00e9 Deus e o que ele fez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-24T21:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-27T14:24:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Confisso\u0303es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tony Payne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tony Payne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/\"},\"author\":{\"name\":\"Tony Payne\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/8225c8434ce9fb9f9163698ea345060c\"},\"headline\":\"Confiss\u00f5es de um viciado em louvor\",\"datePublished\":\"2019-08-24T21:00:43+00:00\",\"dateModified\":\"2019-08-27T14:24:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/\"},\"wordCount\":2950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1\",\"articleSection\":[\"Culto, louvor e adora\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/\",\"name\":\"Confiss\u00f5es de um viciado em louvor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2019-08-24T21:00:43+00:00\",\"dateModified\":\"2019-08-27T14:24:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/confissoes-de-um-viciado-em-louvor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confiss\u00f5es de um viciado em louvor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/8225c8434ce9fb9f9163698ea345060c\",\"name\":\"Tony Payne\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9060dad55ed0e17781db3d5163257e08b35d531b2be9f160f08b3a3bd27dc041?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9060dad55ed0e17781db3d5163257e08b35d531b2be9f160f08b3a3bd27dc041?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9060dad55ed0e17781db3d5163257e08b35d531b2be9f160f08b3a3bd27dc041?s=96&d=mm&r=g\",\"caption\":\"Tony Payne\"},\"description\":\"Tony Payne \u00e9 graduado em teologia pela universidade Moore; \u00e9 editor do minist\u00e9rio Mathias Media, na Austr\u00e1lia, desde 1988. \u00c9 autor e coautor de diversas obras na \u00e1rea de minist\u00e9rio e discipulado. \u00c9 casado com Allison, com quem tem 5 filhos.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/tony-payne\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confiss\u00f5es de um viciado em louvor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/","og_locale":"pt_BR","og_type":"article","og_title":"Confiss\u00f5es de um viciado em louvor","og_description":"Louvor \u00e9 publicidade. \u00c9 lembrar e declarar quem \u00e9 Deus e o que ele fez.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2019-08-24T21:00:43+00:00","article_modified_time":"2019-08-27T14:24:05+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Confisso\u0303es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Tony Payne","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Tony Payne","Est. tempo de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/"},"author":{"name":"Tony Payne","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/8225c8434ce9fb9f9163698ea345060c"},"headline":"Confiss\u00f5es de um viciado em louvor","datePublished":"2019-08-24T21:00:43+00:00","dateModified":"2019-08-27T14:24:05+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/"},"wordCount":2950,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1","articleSection":["Culto, louvor e adora\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/","name":"Confiss\u00f5es de um viciado em louvor","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1","datePublished":"2019-08-24T21:00:43+00:00","dateModified":"2019-08-27T14:24:05+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/confissoes-de-um-viciado-em-louvor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Confiss\u00f5es de um viciado em louvor"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/8225c8434ce9fb9f9163698ea345060c","name":"Tony Payne","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9060dad55ed0e17781db3d5163257e08b35d531b2be9f160f08b3a3bd27dc041?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9060dad55ed0e17781db3d5163257e08b35d531b2be9f160f08b3a3bd27dc041?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9060dad55ed0e17781db3d5163257e08b35d531b2be9f160f08b3a3bd27dc041?s=96&d=mm&r=g","caption":"Tony Payne"},"description":"Tony Payne \u00e9 graduado em teologia pela universidade Moore; \u00e9 editor do minist\u00e9rio Mathias Media, na Austr\u00e1lia, desde 1988. \u00c9 autor e coautor de diversas obras na \u00e1rea de minist\u00e9rio e discipulado. \u00c9 casado com Allison, com quem tem 5 filhos.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/tony-payne\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-d2U","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Confisso%CC%83es-de-um-viciado-em-louvor.jpg?fit=856%2C394&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/728"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=50152"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50152\/revisions"}],"predecessor-version":[{"id":50236,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50152\/revisions\/50236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/50232"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=50152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=50152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=50152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}