{"id":50277,"date":"2019-08-29T09:44:09","date_gmt":"2019-08-29T12:44:09","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=50277"},"modified":"2025-12-17T17:35:25","modified_gmt":"2025-12-17T20:35:25","slug":"ira-e-choro-exegese-visual","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/","title":{"rendered":"Ira e Choro (Exegese Visual)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=&#8221;50282&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][vc_column_text]<em>\u201cEu fiz cessar o eia dos pisadores. Pelo que por Moabe vibra como harpa o meu \u00edntimo, e o meu cora\u00e7\u00e3o, por Quir-Heres\u201d. Isa\u00edas 16.10,11<\/em><\/p>\n<p><strong>\u201cEu fiz cessar o eia dos pisadores\u201d<\/strong>, aqui se refere ao julgamento do Senhor sobre Moabe e como ele silenciou os gritos de colheita que eram ouvidos em seus campos. O que sempre me intriga com esse vers\u00edculo (e os semelhantes em 16.9 e 15.5, assim como Jeremias 48.3-32, 35-36) \u00e9 como o Senhor &#8211; que \u00e9 totalmente livre para fazer o que quiser &#8211; ordena e executa julgamentos que entristecem o seu pr\u00f3prio \u201c\u00edntimo\u201d. Como pode ser isso? A \u00fanica coisa semelhante que temos para isso em nossa experi\u00eancia \u00e9 quando algu\u00e9m \u00e9 obrigado, por certas circunst\u00e2ncias a fazer algo que sabe que ser\u00e1 doloroso para ela (por exemplo, uma gravidez em que a m\u00e3e ou o beb\u00ea ou ambos morrer\u00e3o &#8230; o que fazer?). Mas isso n\u00e3o pode ser o caso de Deus. Ele n\u00e3o est\u00e1 preso a nada, sua vontade &#8211; Seu livre arb\u00edtrio soberano &#8211; \u00e9 a lei (Sl 115.3). E ainda assim, o vemos fazendo algo que faz com que se lamente nas profundezas de sua alma, que faz com que ele encharque com suas l\u00e1grimas aqueles que ele mesmo julgou (v.9). Esta \u00e9 uma linguagem chocante; o que vamos fazer com isso?<\/p>\n<p><strong>No m\u00ednimo<\/strong>, podemos dizer que a vida afetiva de Deus n\u00e3o \u00e9 como a nossa. Em absoluta liberdade irrestrita e soberana, ele escolhe chorar com genu\u00edno lamento e compaix\u00e3o por aqueles a quem ele despeda\u00e7a na sua ira sagrada. Nem seu choro nem sua destrui\u00e7\u00e3o s\u00e3o fingidos, nem s\u00e3o falsos, nem s\u00e3o um exibi\u00e7\u00e3o &#8230; ambos fluem de seu \u201c\u00edntimo\u201d, ambos mostram a beleza de seu car\u00e1ter. Isto \u00e9 um mist\u00e9rio &#8230;, mas aquele que abre seu cora\u00e7\u00e3o para n\u00f3s no Calv\u00e1rio. Sim, porque na cruz vemos o Pai esmagar seus inimigos no corpo de seu Amado, vemos o Filho voluntariamente levar nosso pecado e oferecer-se para ser esmagado, e vemos o Esp\u00edrito como o meio deste esmagamento. E simultaneamente, na cruz, vemos o Filho ensopar a terra com suas l\u00e1grimas e sangue, assim como o Pai &#8211; podemos supor &#8211; encharca o Filho (e n\u00f3s nele) com l\u00e1grimas de amor no Esp\u00edrito. Sim, a ira sagrada e o choro de compaix\u00e3o de Deus n\u00e3o est\u00e3o em desacordo, n\u00e3o s\u00e3o paix\u00f5es conflitantes, e sabemos disso porque elas cantam em harmonia no Calv\u00e1rio.<\/p>\n<p><strong>O que significa ter um Deus que chora?<\/strong> Um Deus que chora, n\u00e3o por fraqueza ou incapacidade, mas por uma vontade soberana que escolhe chorar sinceramente por e com suas criaturas? O que as l\u00e1grimas de Deus significam? Ele est\u00e1 chorando agora pelas na\u00e7\u00f5es? Ele est\u00e1 chorando agora por aqueles que se op\u00f5em a ele? Ele est\u00e1 chorando agora sobre aqueles sobre quem derrama a sua ira? Ou todo o seu choro pela humanidade foi alcan\u00e7ado na cruz? Todos os seus choros foram resumidos nas agonias do Filho Amado quando ele se tornou as na\u00e7\u00f5es pag\u00e3s, quando ele se tornou o pecador, como o amor que chorou quando ele derramou ira tornou-se aquele que chorou sob a ira derramada?<\/p>\n<p>Que possamos nos curvar diante do peso e maravilha do choro de Deus &#8211; santificado seja o Seu Nome.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Chris Powers. \u00a9 Full of Eyes. Website: <a href=\"https:\/\/www.fullofeyes.com\" target=\"_blank\" rel=\"noopener noreferrer\">fullofeyes.com<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/www.fullofeyes.com\/wrath-and-weeping\/\" target=\"_blank\" rel=\"noopener noreferrer\">Wrath and Weeping<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ira e Choro (Exegese Visual)<\/a>. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\" target=\"_blank\" rel=\"noopener noreferrer\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Paulo Reiss Junior. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cEu fiz cessar o eia dos pisadores. Pelo que por Moabe vibra como harpa o meu \u00edntimo, e o meu cora\u00e7\u00e3o, por Quir-Heres\u201d. Isa\u00edas 16.10,11<\/p>\n","protected":false},"author":596,"featured_media":50279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[1924],"class_list":["post-50277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-full-of-eyes","tema-deus","tema-exegese-visual","tema-full-of-eyes","tema-ira","tema-ira-de-deus","tema-jesus-cristo","tema-pessoa-de-cristo","tema-teontologia-doutrina-de-deus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ira e Choro (Exegese Visual)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ira e Choro (Exegese Visual)\" \/>\n<meta property=\"og:description\" content=\"\u201cEu fiz cessar o eia dos pisadores. Pelo que por Moabe vibra como harpa o meu \u00edntimo, e o meu cora\u00e7\u00e3o, por Quir-Heres\u201d. Isa\u00edas 16.10,11\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-29T12:44:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T20:35:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Ira-e-Choro-Exegese-Visual.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chris Powers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris Powers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/\"},\"author\":{\"name\":\"Chris Powers\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/8a695e03ada0d2039a5de673e059f879\"},\"headline\":\"Ira e Choro (Exegese Visual)\",\"datePublished\":\"2019-08-29T12:44:09+00:00\",\"dateModified\":\"2025-12-17T20:35:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/\"},\"wordCount\":677,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1\",\"keywords\":[\"Full of Eyes\"],\"articleSection\":[\"...\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/\",\"name\":\"Ira e Choro (Exegese Visual)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2019-08-29T12:44:09+00:00\",\"dateModified\":\"2025-12-17T20:35:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/08\\\/ira-e-choro-exegese-visual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ira e Choro (Exegese Visual)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/8a695e03ada0d2039a5de673e059f879\",\"name\":\"Chris Powers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Chris-Powers_avatar_1529345965-96x96.png\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Chris-Powers_avatar_1529345965-96x96.png\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Chris-Powers_avatar_1529345965-96x96.png\",\"caption\":\"Chris Powers\"},\"description\":\"Chris Powers \u00e9 fundador e desenhista do Full of Eyes, novo parceiro do Voltemos ao Evangelho.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/chris-powers\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ira e Choro (Exegese Visual)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/","og_locale":"pt_BR","og_type":"article","og_title":"Ira e Choro (Exegese Visual)","og_description":"\u201cEu fiz cessar o eia dos pisadores. Pelo que por Moabe vibra como harpa o meu \u00edntimo, e o meu cora\u00e7\u00e3o, por Quir-Heres\u201d. Isa\u00edas 16.10,11","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2019-08-29T12:44:09+00:00","article_modified_time":"2025-12-17T20:35:25+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Ira-e-Choro-Exegese-Visual.jpg","type":"image\/jpeg"}],"author":"Chris Powers","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Chris Powers","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/"},"author":{"name":"Chris Powers","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/8a695e03ada0d2039a5de673e059f879"},"headline":"Ira e Choro (Exegese Visual)","datePublished":"2019-08-29T12:44:09+00:00","dateModified":"2025-12-17T20:35:25+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/"},"wordCount":677,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1","keywords":["Full of Eyes"],"articleSection":["..."],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/","name":"Ira e Choro (Exegese Visual)","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1","datePublished":"2019-08-29T12:44:09+00:00","dateModified":"2025-12-17T20:35:25+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/08\/ira-e-choro-exegese-visual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ira e Choro (Exegese Visual)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/8a695e03ada0d2039a5de673e059f879","name":"Chris Powers","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/06\/Chris-Powers_avatar_1529345965-96x96.png","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/06\/Chris-Powers_avatar_1529345965-96x96.png","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/06\/Chris-Powers_avatar_1529345965-96x96.png","caption":"Chris Powers"},"description":"Chris Powers \u00e9 fundador e desenhista do Full of Eyes, novo parceiro do Voltemos ao Evangelho.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/chris-powers\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/08\/Ira-e-Choro-Exegese-Visual.jpg?fit=856%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-d4V","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/596"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=50277"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50277\/revisions"}],"predecessor-version":[{"id":50284,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50277\/revisions\/50284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/50279"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=50277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=50277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=50277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}