{"id":50399,"date":"2019-09-10T16:24:40","date_gmt":"2019-09-10T19:24:40","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=50399"},"modified":"2020-02-11T15:52:40","modified_gmt":"2020-02-11T18:52:40","slug":"helen-roseveare-medica-missionaria-e-serva-fiel","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/","title":{"rendered":"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<em>O trecho abaixo foi retirado com permiss\u00e3o do livro <a href=\"https:\/\/fiel.in\/2ENbPDY\" target=\"_blank\" rel=\"noopener noreferrer\">Mulheres Fi\u00e9is e seu Deus Maravilhoso<\/a>, de N\u00f6el Piper, Editora Fiel.<\/em><\/p>\n<p>Helen tamb\u00e9m havia sido designada para come\u00e7ar um programa de treinamento para trabalhadores na \u00e1rea m\u00e9dica. Os primeiros alunos come\u00e7aram a chegar para aprender enfermagem. Suas idades variavam de dezoito a vinte e quatro anos, e sua base educacional era o equivalente \u00e0 do Ensino Fundamental. Entre os alunos da primeira classe estava John Mangadima, que passaria a ser um amigo e colega durante os anos que Helen passou no Congo.<\/p>\n<p>Helen n\u00e3o foi treinada como professora ou enfermeira. N\u00e3o havia um curr\u00edculo pronto. Todo o ensino era em franc\u00eas e em sua\u00edli. Nenhuma dessas l\u00ednguas era a l\u00edngua nativa de Helen ou de qualquer dos alunos.<\/p>\n<p><strong>Deus me ensinou a ensinar conforme a necessidade que surgisse<\/strong>&#8230; Um paciente vinha ardendo em febre, ent\u00e3o pass\u00e1vamos a uma palestra sobre como usar, ler e entender um term\u00f4metro&#8230; Um beb\u00ea era trazido com broncopneumonia, e eu demonstrava o uso do estetosc\u00f3pio e como chegar a um diagn\u00f3stico. Um fluxo intermin\u00e1vel de pacientes, com um ilimitado conjunto de sintomas abdominais, nos proporcionava material para descobrir o uso do microsc\u00f3pio e aprender a reconhecer todas as esp\u00e9cies poss\u00edveis de parasitas.<\/p>\n<p>Servir de mentora aos alunos de enfermagem significava separar um tempo adicional para cada procedimento m\u00e9dico. Isso teve de se encaixar nos dias que j\u00e1 eram muito curtos.<\/p>\n<p>O excesso de trabalho e a consequente impossibilidade de ter uma noite de folga, ou de sair no fim de semana, trouxe-me uma certa irritabilidade e falta de paci\u00eancia que sempre me causavam uma consider\u00e1vel perda de sono. Eu sempre tive um temperamento impetuoso, mas que a maioria das vezes estava sob controle&#8230; desde a minha convers\u00e3o a Cristo. Agora a palavra irada e furiosa escaparia novamente, antes que eu pudesse control\u00e1-la, para minha vergonha. Pacientes que vinham at\u00e9 a janela da sala de jantar, enquanto est\u00e1vamos fazendo a refei\u00e7\u00e3o do meio-dia recebiam uma palavra afiada de minha parte: \u201cV\u00e1 ao dispens\u00e1rio, e n\u00e3o traga seus germes para a nossa casa\u201d \u2013 e um olhar triste surgiu nos rostos dos mission\u00e1rios mais antigos, que tratavam cada visitante em sua casa com gentileza e respeito.<\/p>\n<p>O evangelista Danga&#8230; me deu uma li\u00e7\u00e3o por causa desse comportamento anticrist\u00e3o. \u201cN\u00e3o desculpe a si mesma. Chame pecado de pecado e c\u00f3lera de c\u00f3lera. Ent\u00e3o, encare o fato de que sua pele branca n\u00e3o faz de voc\u00ea algu\u00e9m melhor do que n\u00f3s. Voc\u00ea precisa da purifica\u00e7\u00e3o de Deus e de seu perd\u00e3o, de ser preenchida e habitada por Ele, d\u00e1 mesma forma que n\u00f3s precisamos. Se voc\u00ea pode nos mostrar apenas a Doutora Helen, \u00e9 melhor voltar para casa: as pessoas precisam ver a Jesus.\u201d<\/p>\n<p>Ap\u00f3s dezoito meses em Ibambi, a diretoria da miss\u00e3o a transferiu para Nebobongo, porque era necess\u00e1rio que ela tomasse a frente do trabalho m\u00e9dico l\u00e1. Ent\u00e3o, os alunos de enfermagem e o programa de treinamento foram com Helen para Nebobongo, a onze quil\u00f4metros de Ibambi.<\/p>\n<p>Ela permaneceu em Nebobongo por dez anos, supervisionando o lepros\u00e1rio e o orfanato. Ela fundou quarenta e oito postos de sa\u00fade rurais, nas imedia\u00e7\u00f5es pr\u00f3ximas, um centro de treinamento para a forma\u00e7\u00e3o de param\u00e9dicos e um hospital com cem leitos e uma maternidade. O hospital e o centro de treinamento foram constru\u00eddos literalmente do ch\u00e3o, e as \u00fanicas pessoas que puderam fazer isso foram Helen e sua colega europeia Florence Stebbing, juntamente com os alunos.<\/p>\n<p>Aprendemos a fazer tijolos&#8230; aprendemos a lidar com a complexidade do forno de olaria&#8230; como utilizar o n\u00edvel de bolha, e a mistura certa de cimento e areia para fazer o concreto&#8230; como serrar as vigas de um tronco&#8230; como medir e erguer essas vigas, para montar o telhado&#8230; e transportar as onduladas telhas de amianto&#8230;<\/p>\n<p>Quando a tarefa parecia-lhes muito grande, Deus providenciava solu\u00e7\u00f5es inesperadas. Por exemplo, uma viga era pesada e perigosa para ser erguida pelos alunos e por Helen, novatos naquela fun\u00e7\u00e3o. <strong>Eles oraram por um construtor de telhados<\/strong> que fosse experiente. Naquele momento, uma mission\u00e1ria foi trazida para que ficasse de repouso at\u00e9 o final de sua gravidez de risco. Inesperadamente, Helen perguntou ao marido dela: \u201cVoc\u00ea faz telhados?\u201d Sim, ele fazia.<\/p>\n<p>A constru\u00e7\u00e3o n\u00e3o era o \u00fanico desafio. Cada necessidade tinha suas pr\u00f3prias dificuldades.<\/p>\n<p>Aprendemos mec\u00e2nica de autom\u00f3vel&#8230; em fun\u00e7\u00e3o da necessidade&#8230; Precis\u00e1vamos de um ve\u00edculo que funcionasse como ambul\u00e2ncia&#8230; caminh\u00e3o para a constru\u00e7\u00e3o&#8230; e caminhonete para carregar comida&#8230; O \u00fanico modo de fazer consertos era entrar debaixo ou dentro daquele carro junto com um colega africano e, em meio a tentativas e erros, trabalhar at\u00e9 que tiv\u00e9ssemos algum sucesso.<\/p>\n<p>Aprendemos sua\u00edli e franc\u00eas e alguma no\u00e7\u00e3o de bangala e kibudu; e ent\u00e3o assumimos a tarefa de expressar verdades m\u00e9dicas sem um jarg\u00e3o cient\u00edfico&#8230; <strong>Escrevemos nosso primeiro livro-texto em sua\u00edli<\/strong>&#8230; Fizemos matrizes, e logo cem c\u00f3pias foram reproduzidas em uma m\u00e1quina duplicadora antiga, na qual as p\u00e1ginas eram friccionadas individualmente e colocadas para secar. Hist\u00f3rias desagrad\u00e1veis poderiam ser contadas dos dias em que o vento entrava pelas venezianas e espalhava as p\u00e1ginas, numa avalanche desastrosa!<\/p>\n<p>Escrever livros-texto deve ter sido um trabalho de tempo integral, assim como a constru\u00e7\u00e3o do hospital e do centro de treinamento m\u00e9dico. E a demanda m\u00e9dica ia, em si mesma, al\u00e9m do tempo integral. <strong>Helen n\u00e3o podia esquecer que sentia o chamado para miss\u00e3o m\u00e9dica<\/strong>, mas os v\u00e1rios outros pap\u00e9is continuavam a pressionar, competindo pela prioridade nas limitadas horas do dia.<\/p>\n<p>Uma manh\u00e3, por exemplo, ela estava no forno da olaria, suas m\u00e3os \u00e1speras e cortadas pelo trabalho, quando foi chamada para ir ao hospital fazer uma cirurgia de emerg\u00eancia.<\/p>\n<p>Comecei a esfregar minhas m\u00e3os e os bra\u00e7os: minhas m\u00e3os do\u00edam intensamente debaixo da escova. Estendi minhas m\u00e3os para que a enfermeira colocasse \u00e1lcool antiss\u00e9ptico. Segurei minha respira\u00e7\u00e3o com for\u00e7a ao sentir a dor aguda. E comecei a murmurar em minha mente.<\/p>\n<p>Por que Deus n\u00e3o chamou outro mission\u00e1rio&#8230; para ficar encarregado da constru\u00e7\u00e3o&#8230; e assim eu poderia ficar livre para dar \u00e0s pessoas o melhor tratamento m\u00e9dico do qual creio ser capaz?&#8230;<\/p>\n<p>Na quarta-feira seguinte, contei tudo isto ao conselho da igreja e pedi que orassem, para que eu n\u00e3o ficasse ressentida. Um homem piedoso, depois de conduzir o grupo em ora\u00e7\u00e3o, sorriu para mim e me repreendeu gentilmente.<\/p>\n<p>\u201cDoutora\u201d, ele disse, \u201cquando voc\u00ea \u00e9 a m\u00e9dica, em seu uniforme branco, o estetosc\u00f3pio ao redor de seu pesco\u00e7o, falando franc\u00eas, voc\u00ea est\u00e1 a quil\u00f4metros de dist\u00e2ncia de n\u00f3s. N\u00f3s a tememos e lhe dizemos: \u201cSim, sim\u201d, mesmo quase n\u00e3o ouvindo o que voc\u00ea disse. Mas quando voc\u00ea est\u00e1 na olaria conosco, e suas m\u00e3os est\u00e3o \u00e1speras como as nossas&#8230; quando voc\u00ea est\u00e1 nos mercados, falando e cometendo seus erros na linguagem, n\u00f3s todos rimos com voc\u00ea: \u00e9 a\u00ed que n\u00f3s te amamos, confiamos em voc\u00ea e ouvimos o que voc\u00ea nos fala de Deus e de seus caminhos\u201d.<\/p>\n<p>Dentro de um ano a constru\u00e7\u00e3o do hospital foi conclu\u00edda. Agora <strong>n\u00e3o havia mais constru\u00e7\u00e3o para tomar o tempo e a energia de Helen.<\/strong> Era isto que ela esperava, mas, infelizmente, ainda n\u00e3o estava satisfeita.<\/p>\n<p>Minha reclama\u00e7\u00e3o foi invertida. O hospital estava pronto e funcionando, e a not\u00edcia estava se espalhando&#8230; E come\u00e7ou um fluxo de pacientes&#8230; Eu n\u00e3o tinha tempo para mais nada, a n\u00e3o ser para medicina, medicina, medicina&#8230; N\u00e3o tinha como cessar&#8230; n\u00e3o havia folga. Eu esperava ser uma boa mission\u00e1ria, e poder&#8230; sentar ao lado de pessoas acamadas&#8230; para falar das boas-novas da salva\u00e7\u00e3o. Mas n\u00e3o havia tempo para nada, sen\u00e3o para a medicina&#8230;<\/p>\n<p>Felizmente, outra vez, levei meu problema aos anci\u00e3os da igreja, pedindo suas ora\u00e7\u00f5es. E novamente eles n\u00e3o s\u00f3 oraram e me consolaram, como tamb\u00e9m, graciosamente, me repreenderam. \u201cDoutora, quantos pacientes v\u00eam ao hospital diariamente?\u201d&#8230;<\/p>\n<p>\u201cCerca de duzentos, duzentos e cinq\u00fcenta\u201d&#8230;<\/p>\n<p>\u201cCertamente eles v\u00eam porque voc\u00ea est\u00e1 l\u00e1! Eles n\u00e3o viriam, se n\u00e3o houvesse m\u00e9dico l\u00e1. E o que estamos fazendo?&#8230; O dia todo, a cada dia, onde voc\u00ea vai, n\u00f3s vamos&#8230; Doutora, voc\u00ea percebe que estamos tendo alegria&#8230; de levar cinco, dez, \u00e0s vezes at\u00e9 mais de dez pessoas ao Senhor a cada semana? Se voc\u00ea n\u00e3o estivesse aqui eles n\u00e3o viriam!\u201d&#8230;<\/p>\n<p>Deus teve de me ensinar a estar disposta a ser parte de um time.<\/p>\n<p><strong>Tamb\u00e9m havia li\u00e7\u00f5es a serem aprendidas a respeito da ora\u00e7\u00e3o<\/strong>. Algumas delas eram sobre algumas ora\u00e7\u00f5es que pareciam imposs\u00edveis e que foram respondidas.<\/p>\n<p>Uma mulher morreu ao dar \u00e0 luz, deixando um rec\u00e9m-nascido prematuro e uma menina de dois anos. N\u00e3o t\u00ednhamos incubadoras, porque n\u00e3o havia energia, e uma bolsa de \u00e1gua quente era a maneira de manter um beb\u00ea t\u00e3o pequenino aquecido durante as noites de ventos frios. Mas nas regi\u00f5es tropicais e \u00famidas, a borracha deteriora facilmente. Portanto, quando a \u00faltima bolsa de \u00e1gua foi enchida para o beb\u00ea, ela rompeu. Uma enfermeira foi incumbida de segurar aquele beb\u00ea e mant\u00ea-lo aquecido com o pr\u00f3prio calor de seu corpo.<\/p>\n<p>No dia seguinte, Helen encontrou-se com as crian\u00e7as do orfanato, para o momento regular de ora\u00e7\u00e3o. Ela lhes contou sobre o beb\u00ea que precisava ficar aquecido e sobre a irm\u00e3zinha, que chorava porque sua m\u00e3e tinha morrido. <strong>Helen registrou a ora\u00e7\u00e3o de Ruth, com dez anos de idade, e sua pr\u00f3pria resposta \u00e0quela ora\u00e7\u00e3o \u201cimposs\u00edvel\u201d.<\/strong><\/p>\n<p>Deus, por favor&#8230; envie-nos uma bolsa de \u00e1gua quente. N\u00e3o ser\u00e1 bom amanh\u00e3, Deus, porque o beb\u00ea j\u00e1 estar\u00e1 morto, ent\u00e3o, por favor, mande uma nessa tarde&#8230; E enquanto se encarrega disso, o Senhor, por favor, enviaria uma boneca para a menininha? Assim ela saber\u00e1 que o Senhor realmente a ama\u201d&#8230;<\/p>\n<p>Poderia eu sinceramente dizer \u201cAm\u00e9m\u201d? Eu apenas n\u00e3o acreditava que Deus faria isso&#8230; O \u00fanico modo como Deus poderia responder a esta ora\u00e7\u00e3o t\u00e3o espec\u00edfica seria enviando-me um pacote da minha terra. Eu estava na \u00c1frica h\u00e1 quatro anos, e at\u00e9 aquele momento n\u00e3o tinha recebido nada de casa&#8230;<\/p>\n<p><strong>Quando cheguei em casa&#8230; l\u00e1, na varanda, estava um pacote de dez quilos<\/strong>&#8230; com selos do Reino Unido&#8230; Levei-o para o orfanato&#8230; Cerca de trinta ou quarenta pares de olhos focalizavam-se na grande caixa de papel\u00e3o.<\/p>\n<p>[Depois de tirar muitos itens], quando coloquei minha m\u00e3o dentro da caixa novamente, senti a&#8230; Ser\u00e1 que era? Agarrei e puxei para fora \u2013 sim, uma bolsa de borracha para \u00e1gua quente, novinha! Eu chorei&#8230;<\/p>\n<p>Ruth&#8230; correu em minha dire\u00e7\u00e3o, gritando: \u201cSe Deus enviou a bolsa, Ele deve ter mandado tamb\u00e9m a bonequinha!\u201d Ao rebuscar at\u00e9 o fundo da caixa, ela puxou para fora a pequena boneca vestida com uma linda roupinha. Os olhos de Ruth brilharam! Ela nunca duvidara&#8230;<\/p>\n<p>Aquele pacote tinha sido enviado cinco meses antes&#8230; em resposta \u00e0 ora\u00e7\u00e3o de f\u00e9 daquela menina de dez anos, para que chegasse \u201cnaquela tarde\u201d.<\/p>\n<p>Algumas outras li\u00e7\u00f5es sobre a ora\u00e7\u00e3o foram relacionadas a ora\u00e7\u00f5es que pareciam n\u00e3o ser respondidas. Ao menos, n\u00e3o foram respondidas do modo como Helen desejou.<\/p>\n<p>Helen fora treinada para ser m\u00e9dica, mas n\u00e3o para ser cirurgi\u00e3. Era uma coisa assustadora pensar em aprender a operar atrav\u00e9s da pr\u00f3pria pr\u00e1tica, quando a vida de algu\u00e9m dependia de sua profici\u00eancia. Ela se recusou a fazer cirurgias at\u00e9 que foi confrontada pela realidade. Algumas pessoas morreriam sem a cirurgia, e se ela n\u00e3o a fizesse, quem faria? Durante todo o restante do tempo que passou no Congo, ela orou para que Deus tirasse aquele medo dela, mas este n\u00e3o foi o modo que Deus escolheu para manter sua mente alerta e sua m\u00e3o firme.[\/vc_column_text][vc_cta h2=&#8221;Mulheres Fi\u00e9is e Seu Deus Maravilhoso&#8221; h4=&#8221;Hist\u00f3rias de cinco mulheres de f\u00e9&#8221;]<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-50403 alignleft\" src=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/mulheres_Fieis_amp.jpg?resize=200%2C300&#038;ssl=1\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/mulheres_Fieis_amp.jpg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/mulheres_Fieis_amp.jpg?w=300&amp;ssl=1 300w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Estas s\u00e3o hist\u00f3rias de cinco mulheres comuns &#8211; Sarah Edwards, Lilias Trotter, Gladys Aylward, Esther Ahn Kim e Helen Roseveare &#8211; que creram em seu Deus maravilhoso, enquanto Ele as conduzia a fazerem grandes coisas em favor de Seu reino. No\u00ebl Piper apresenta suas vidas e realiza\u00e7\u00f5es como exemplos do que significa ser verdadeiramente fiel. Conhecer essas mulheres desafiar\u00e1 o leitor a fazer diferen\u00e7a por Cristo no seu lar, na igreja e em todo o mundo.<\/p>\n<p><a class=\"btn btn-default btn-md\" href=\"https:\/\/fiel.in\/2ENbPDY\">Confira<\/a>[\/vc_cta][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: N\u00f6el Piper. \u00a9 Editora Fiel. Website: <a href=\"https:\/\/www.editorafiel.com.br\">editorafiel.com.br<\/a>. Trecho retirado com permiss\u00e3o do livro: <a href=\"https:\/\/fiel.in\/2ENbPDY\" target=\"_blank\" rel=\"noopener noreferrer\">Mulheres Fi\u00e9is e seu Deus Maravilhoso<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/\" target=\"_blank\" rel=\"noopener noreferrer\">Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel<\/a>. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\" target=\"_blank\" rel=\"noopener noreferrer\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Helen n\u00e3o podia esquecer que sentia o chamado para miss\u00e3o m\u00e9dica, mas os v\u00e1rios outros pap\u00e9is continuavam a pressionar, competindo pela prioridade nas limitadas horas do dia.<\/p>\n","protected":false},"author":266,"featured_media":50402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[507],"tags":[592,2750],"class_list":["post-50399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-da-igreja","tag-desiring-god","tag-trechos-de-livros","tema-biografia-crista","tema-historia-e-biografia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel\" \/>\n<meta property=\"og:description\" content=\"Helen n\u00e3o podia esquecer que sentia o chamado para miss\u00e3o m\u00e9dica, mas os v\u00e1rios outros pap\u00e9is continuavam a pressionar, competindo pela prioridade nas limitadas horas do dia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-10T19:24:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-11T18:52:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Helen-Roseveare-me\u0301dica-missiona\u0301ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noel Piper\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noel Piper\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/\"},\"author\":{\"name\":\"Noel Piper\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/be7ebbc5b739a2c687cceec62202a427\"},\"headline\":\"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel\",\"datePublished\":\"2019-09-10T19:24:40+00:00\",\"dateModified\":\"2020-02-11T18:52:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/\"},\"wordCount\":2291,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1\",\"keywords\":[\"Desiring God Portugu\u00eas\",\"Trechos de livros\"],\"articleSection\":[\"Hist\u00f3ria da Igreja\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/\",\"name\":\"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2019-09-10T19:24:40+00:00\",\"dateModified\":\"2020-02-11T18:52:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/helen-roseveare-medica-missionaria-e-serva-fiel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/be7ebbc5b739a2c687cceec62202a427\",\"name\":\"Noel Piper\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Noel-Piper-96x96.jpeg\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Noel-Piper-96x96.jpeg\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Noel-Piper-96x96.jpeg\",\"caption\":\"Noel Piper\"},\"description\":\"No\u00ebl Piper \u00e9 esposa de John Piper, m\u00e3e de cinco filhos e av\u00f3 de doze. Ela \u00e9 autora de \\\"Mulheres e Seu Deus Maravilhoso\\\", da Editora Fiel.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/noel-piper\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/","og_locale":"pt_BR","og_type":"article","og_title":"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel","og_description":"Helen n\u00e3o podia esquecer que sentia o chamado para miss\u00e3o m\u00e9dica, mas os v\u00e1rios outros pap\u00e9is continuavam a pressionar, competindo pela prioridade nas limitadas horas do dia.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2019-09-10T19:24:40+00:00","article_modified_time":"2020-02-11T18:52:40+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Helen-Roseveare-me\u0301dica-missiona\u0301ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Noel Piper","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Noel Piper","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/"},"author":{"name":"Noel Piper","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/be7ebbc5b739a2c687cceec62202a427"},"headline":"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel","datePublished":"2019-09-10T19:24:40+00:00","dateModified":"2020-02-11T18:52:40+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/"},"wordCount":2291,"commentCount":1,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1","keywords":["Desiring God Portugu\u00eas","Trechos de livros"],"articleSection":["Hist\u00f3ria da Igreja"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/","name":"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1","datePublished":"2019-09-10T19:24:40+00:00","dateModified":"2020-02-11T18:52:40+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/helen-roseveare-medica-missionaria-e-serva-fiel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Helen Roseveare: m\u00e9dica, mission\u00e1ria e serva fiel"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/be7ebbc5b739a2c687cceec62202a427","name":"Noel Piper","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/11\/Noel-Piper-96x96.jpeg","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/11\/Noel-Piper-96x96.jpeg","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/11\/Noel-Piper-96x96.jpeg","caption":"Noel Piper"},"description":"No\u00ebl Piper \u00e9 esposa de John Piper, m\u00e3e de cinco filhos e av\u00f3 de doze. Ela \u00e9 autora de \"Mulheres e Seu Deus Maravilhoso\", da Editora Fiel.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/noel-piper\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Helen-Roseveare-me%CC%81dica-missiona%CC%81ria-e-serva-fiel.jpg?fit=856%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-d6T","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/266"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=50399"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50399\/revisions"}],"predecessor-version":[{"id":50408,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50399\/revisions\/50408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/50402"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=50399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=50399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=50399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}