{"id":50523,"date":"2019-09-16T12:43:18","date_gmt":"2019-09-16T15:43:18","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=50523"},"modified":"2020-02-11T15:52:08","modified_gmt":"2020-02-11T18:52:08","slug":"aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/","title":{"rendered":"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<em>O trecho abaixo foi retirado com permiss\u00e3o do livro <a href=\"https:\/\/fiel.in\/2Jpr6zA\" target=\"_blank\" rel=\"noopener noreferrer\">Instruindo o Cora\u00e7\u00e3o da Crian\u00e7a<\/a>, de Tedd e Margy Tripp, Editora Fiel.<\/em><\/p>\n<p>As crian\u00e7as precisam de instru\u00e7\u00e3o para aplicarem as Escrituras a quest\u00f5es como autoridade, obedi\u00eancia, resolu\u00e7\u00e3o de conflitos e pap\u00e9is designados por Deus nos relacionamentos. <strong>A vida cotidiana propicia dezenas de oportunidades de relacionar as Escrituras \u00e0 vida<\/strong> \u2014 desde a perda de uma mochila escolar at\u00e9 o rompimento de amizades e notas baixas nas provas. In\u00fameras oportunidades de treinamento evaporam sem que as percebamos, enquanto estamos no corre-corre di\u00e1rio, pensando que o tempo de devo\u00e7\u00f5es com nossos filhos \u00e9 suficiente. <strong>As nossas rea\u00e7\u00f5es diante das circunst\u00e2ncias e crises do cotidiano tornam a nossa teologia real.<\/strong><\/p>\n<p>As hist\u00f3rias da B\u00edblia irradiam ilustra\u00e7\u00f5es de crian\u00e7as cujo conhecimento das Escrituras se traduziu em obedi\u00eancia, coragem e a\u00e7\u00e3o. As palavras de Davi a Saul pareciam ing\u00eanuas e infantis diante do ex\u00e9rcito filisteu e das amea\u00e7as aterrorizantes de Golias: <em>\u201cN\u00e3o desfale\u00e7a o cora\u00e7\u00e3o de ningu\u00e9m por causa dele; teu servo ir\u00e1 e pelejar\u00e1 contra o filisteu\u201d (1Sm 17.32).<\/em> Mas a vida espiritual de Davi e a sua experi\u00eancia como jovem pastor de ovelhas ressoaram com seu direito de falar. <em>\u201cRespondeu Davi a Saul: Teu servo apascentava as ovelhas de seu pai; quando veio um le\u00e3o ou um urso e tomou um cordeiro do rebanho, eu sa\u00ed ap\u00f3s ele, e o feri, e livrei o cordeiro da sua boca; levantando-se ele contra mim, agarrei-o pela barba, e o feri, e o matei. O teu servo matou tanto o le\u00e3o como o urso; este incircunciso filisteu ser\u00e1 como um deles, porquanto afrontou os ex\u00e9rcitos do Deus vivo. Disse mais Davi: O Senhor me livrou das garras do le\u00e3o e das do urso; ele me livrar\u00e1 das m\u00e3os deste filisteu\u201d (1Sm 17.34-37).<\/em><\/p>\n<p>O discurso corajoso que Davi fez a Saul e o subsequente desafio a Golias n\u00e3o surgiram da aud\u00e1cia de uma fantasia da adolesc\u00eancia. <strong>Davi acreditava no poder e na autoridade de Deus.<\/strong> O Deus que libertara a Israel do Egito era o mesmo que o havia livrado do urso e do le\u00e3o. Sua confian\u00e7a veio do fato de que ele enfrentara o urso, clamara ao Senhor por socorro e <strong>experimentara o livramento de Deus<\/strong>. Saul olhou para Golias, que lhe pareceu grande; Deus e Suas promessas lhe pareceram pequenos. Davi olhou para Golias e para a multid\u00e3o de filisteus considerando em sua mente a hist\u00f3ria de Israel e o seu duelo perigoso. <strong>Ele aplicou aquilo que acreditava ser verdade a respeito de Deus e de Suas promessas.<\/strong> Em consequ\u00eancia, Deus lhe pareceu grande em face do gigante terreno e finito. \u201c<em>Tu vens contra mim com espada, e com lan\u00e7a, e com escudo; eu, por\u00e9m, vou contra ti em nome do Senhor dos Ex\u00e9rcitos, o Deus dos ex\u00e9rcitos de Israel, a quem tens afrontado. Hoje mesmo, o Senhor te entregar\u00e1 nas minhas m\u00e3os&#8230; Saber\u00e1 toda esta multid\u00e3o que o Senhor salva, n\u00e3o com espada, nem com lan\u00e7a; porque do Senhor \u00e9 a guerra, e ele vos entregar\u00e1 nas nossas m\u00e3os\u201d (1 Sm 17.45-47).<\/em><\/p>\n<h2>Seja um modelo de vitalidade espiritual para seus filhos<\/h2>\n<p><strong>Ser um modelo para os filhos<\/strong> <strong>\u00e9 a maneira mais segura de ensin\u00e1-los a aplicar a verdade de Deus \u00e0s circunst\u00e2ncias da vida.<\/strong> A paternidade que exibe um relacionamento vital com Deus em todas as alegrias e tempestades da vida \u00e9 irresist\u00edvel tanto para as crian\u00e7as como para os jovens. Em contrapartida, ter a <em>\u201cforma de piedade, negando-lhe, entretanto, o poder\u201d (2Tm 3.5)<\/em>, \u00e9 a maneira mais segura de <strong>endurecer o cora\u00e7\u00e3o de nossos filhos em rela\u00e7\u00e3o a Deus.<\/strong><\/p>\n<p><strong>Nossos lares s\u00e3o o laborat\u00f3rio de vida para nossos filhos<\/strong>. Eles acreditar\u00e3o que o cristianismo \u00e9 genu\u00edno se conhecemos a Deus \u2014 e n\u00e3o apenas sabemos fatos a respeito de Deus. \u00c0 medida que os filhos se tornam adultos em nossas igrejas, eles buscam desesperadamente uma f\u00e9 que possua o fervor e a vitalidade de um <strong>relacionamento \u00edntimo com o Deus vivo<\/strong> e o apoio seguro da s\u00e3 doutrina que resiste \u00e0s tempestades da vida. O relacionamento com Deus \u00e9 a garantia de que o Deus da B\u00edblia pode ser conhecido pelo seu povo em todas as experi\u00eancias da vida. O nosso relacionamento com Deus <strong>induzir\u00e1 os nossos filhos a se aproximarem de Deus<\/strong> como sua fonte de conforto e descanso.<\/p>\n<h2>Desenvolva um relacionamento maduro com seus filhos<\/h2>\n<p>Empenhe-se por desenvolver um relacionamento m\u00fatuo de vida e de trabalho pelo reino de Deus, com seus filhos. A vida crist\u00e3 \u00e9 vivida em comunidade. Em toda a hist\u00f3ria da reden\u00e7\u00e3o, os filhos de Deus t\u00eam testemunhado as obras impressionantes de Deus e se gloriado, uns com os outros, na prote\u00e7\u00e3o e na provis\u00e3o de Deus. Tamb\u00e9m precisamos ter em vista as gera\u00e7\u00f5es futuras. Ao falarmos sobre a fidelidade e a provis\u00e3o de Deus para a fam\u00edlia f\u00edsica e a fam\u00edlia espiritual, devemos manter a mesma perspectiva \u2014 a de que trabalharemos juntos para proclamar o reino de Cristo at\u00e9 que Ele venha. Josu\u00e9 declarou esta perspectiva: \u201cEu e a minha casa serviremos ao Senhor\u201d (Js. 24.15).<\/p>\n<p>Esse mesmo tema encontra-se no Livro dos Salmos. Salmos 48.12-14 nos diz: <em>\u201cPercorrei a Si\u00e3o, rodeai-a toda, contai-lhe as torres; notai bem os seus baluartes, observai os seus pal\u00e1cios, para narrardes \u00e0s gera\u00e7\u00f5es vindouras que este \u00e9 Deus, o nosso Deus para todo o sempre; ele ser\u00e1 nosso guia at\u00e9 \u00e0 morte\u201d<\/em><\/p>\n<p>Salmos 78.3-7 nos recorda: <em>\u201cO que ouvimos e aprendemos, o que nos contaram nossos pais, n\u00e3o o encobriremos a seus filhos; contaremos \u00e0 vindoura gera\u00e7\u00e3o os louvores do Senhor, e o seu poder, e as maravilhas que fez. Ele estabeleceu um testemunho em Jac\u00f3, e instituiu uma lei em Israel, e ordenou a nossos pais que os transmitissem a seus filhos, a fim de que a nova gera\u00e7\u00e3o os conhecesse, filhos que ainda h\u00e3o de nascer se levantassem e por sua vez os referissem aos seus descendentes; para que pusessem em Deus a sua confian\u00e7a e n\u00e3o se esquecessem dos feitos de Deus, mas lhe observassem os mandamentos\u201d.<\/em>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Tedd e Margy Tripp. \u00a9 Editora Fiel. Website: <a href=\"https:\/\/www.editorafiel.com.br\" target=\"_blank\" rel=\"noopener noreferrer\">editorafiel.com.br<\/a>. Trecho retirado com permiss\u00e3o do livro: <a class=\"external\" href=\"https:\/\/fiel.in\/2Jpr6zA\" target=\"_blank\" rel=\"noopener noreferrer\">Instruindo o Cora\u00e7\u00e3o da Crian\u00e7a<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Aplique as Escrituras \u00e0 vida cotidiana de seus filhos<\/a>. \u00a9 Voltemos ao Evangelho. Website: <a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A vida cotidiana propicia dezenas de oportunidades de relacionar as Escrituras \u00e0 vida.<\/p>\n","protected":false},"author":320,"featured_media":50525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3065,624,409],"tags":[2750],"class_list":["post-50523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casamento-e-familia","category-mulheres","category-vida-crista","tag-trechos-de-livros","tema-criacao-de-filhos","tema-filhos","tema-mulheres","tema-teologia-pratica","tema-vida-crista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aplique as Escrituras \u00e0 vida cotidiana de seus filhos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos\" \/>\n<meta property=\"og:description\" content=\"A vida cotidiana propicia dezenas de oportunidades de relacionar as Escrituras \u00e0 vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-16T15:43:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-11T18:52:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Aplique-as-Escrituras-a\u0300-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tedd Tripp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tedd Tripp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/\"},\"author\":{\"name\":\"Tedd Tripp\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/93e72abb8c8b7d88d1619b7771669c73\"},\"headline\":\"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos\",\"datePublished\":\"2019-09-16T15:43:18+00:00\",\"dateModified\":\"2020-02-11T18:52:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/\"},\"wordCount\":1162,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1\",\"keywords\":[\"Trechos de livros\"],\"articleSection\":[\"Casamento e fam\u00edlia\",\"Mulheres\",\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/\",\"name\":\"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2019-09-16T15:43:18+00:00\",\"dateModified\":\"2020-02-11T18:52:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/09\\\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/93e72abb8c8b7d88d1619b7771669c73\",\"name\":\"Tedd Tripp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Tedd-Tripp_avatar_1410895050-96x96.jpg\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Tedd-Tripp_avatar_1410895050-96x96.jpg\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Tedd-Tripp_avatar_1410895050-96x96.jpg\",\"caption\":\"Tedd Tripp\"},\"description\":\"Tedd Tripp \u00e9 pastor da Grace Fellowship Church, em Hazleton, Pensilv\u00e2nia, desde 1983. Dr. Tedd \u00e9 graduado pelo Geneva College (BA em Hist\u00f3ria), pelo Philadelphia Theological Seminary (MDiv) e pelo Westminster Theological Seminary (DMin), com \u00eanfase em Aconselhamento Pastoral.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/tedd-tripp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/","og_locale":"pt_BR","og_type":"article","og_title":"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos","og_description":"A vida cotidiana propicia dezenas de oportunidades de relacionar as Escrituras \u00e0 vida.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2019-09-16T15:43:18+00:00","article_modified_time":"2020-02-11T18:52:08+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Aplique-as-Escrituras-a\u0300-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Tedd Tripp","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Tedd Tripp","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/"},"author":{"name":"Tedd Tripp","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/93e72abb8c8b7d88d1619b7771669c73"},"headline":"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos","datePublished":"2019-09-16T15:43:18+00:00","dateModified":"2020-02-11T18:52:08+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/"},"wordCount":1162,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1","keywords":["Trechos de livros"],"articleSection":["Casamento e fam\u00edlia","Mulheres","Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/","name":"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1","datePublished":"2019-09-16T15:43:18+00:00","dateModified":"2020-02-11T18:52:08+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/09\/aplique-as-escrituras-a-vida-cotidiana-de-seus-filhos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Aplique as Escrituras \u00e0 vida cotidiana de seus filhos"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/93e72abb8c8b7d88d1619b7771669c73","name":"Tedd Tripp","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Tedd-Tripp_avatar_1410895050-96x96.jpg","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Tedd-Tripp_avatar_1410895050-96x96.jpg","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Tedd-Tripp_avatar_1410895050-96x96.jpg","caption":"Tedd Tripp"},"description":"Tedd Tripp \u00e9 pastor da Grace Fellowship Church, em Hazleton, Pensilv\u00e2nia, desde 1983. Dr. Tedd \u00e9 graduado pelo Geneva College (BA em Hist\u00f3ria), pelo Philadelphia Theological Seminary (MDiv) e pelo Westminster Theological Seminary (DMin), com \u00eanfase em Aconselhamento Pastoral.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/tedd-tripp\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/09\/Aplique-as-Escrituras-a%CC%80-vida-cotidiana-de-seus-filhos.jpg?fit=856%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-d8T","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/320"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=50523"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50523\/revisions"}],"predecessor-version":[{"id":50529,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50523\/revisions\/50529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/50525"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=50523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=50523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=50523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}