{"id":50813,"date":"2019-10-07T16:30:23","date_gmt":"2019-10-07T19:30:23","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=50813"},"modified":"2021-01-28T13:53:14","modified_gmt":"2021-01-28T16:53:14","slug":"coringa-um-filme-genial-e-perturbador","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/","title":{"rendered":"Coringa, um filme genial e perturbador"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Tenho dificuldades em encontrar um t\u00edtulo para este post. O novo filme do Coringa \u00e9 daqueles que levamos para casa, dormimos com ele e acordamos com ele. Ou melhor, ele \u00e9 que vai para casa conosco, dorme e acorda connosco. Vou tentar n\u00e3o dar spoilers.<\/p>\n<p>A cr\u00edtica divide-se entre extremos, mas \u00e9 compreens\u00edvel. \u00c9 um filme pesado, denso, dark, perturbador. J\u00e1 explico em poucas palavras porqu\u00ea. A interpreta\u00e7\u00e3o de Joaquin Phoenix \u00e9 genial, a banda sonora \u00e9 de outro mundo e a fotografia em todos os aspetos \u00e9 perfeita. O filme prende do in\u00edcio at\u00e9 ao fim. H\u00e1 cr\u00edticos que apontam repetitividade e excesso em algumas cenas, mas acho que esse excesso funciona bem na medida em que nos quer fazer infrutiferamente avan\u00e7ar naquilo que \u00e9 perturbador mas n\u00e3o pode ser evitado. Faz parte porque \u00e9 a realidade.<\/p>\n<p>E esse \u00e9 um dos pontos que podemos sentir at\u00e9 \u00e0 nossa alma: a realidade crua e fria da natureza humana e da sociedade. O filme \u00e9 niilista, existencialista; uma espiral descendente e assustadora do caos, tanto do Coringa quanto de Gotham, tanto do indiv\u00edduo quanto do coletivo.<\/p>\n<p>Coringa, Arthur Fleck, no in\u00edcio cuida exaustivamente da m\u00e3e, tem um trabalho como palha\u00e7o, mas aquilo que era uma estabilidade a caminhar sob a corda bamba, torna-se gradativamente em uma queda vertiginosa de circunst\u00e2ncias aliadas \u00e0s perturba\u00e7\u00f5es mentais j\u00e1 presentes que terminam com a\u00e7\u00f5es hediondas destitu\u00eddas de qualquer senso de certo e errado, de tristeza ou remorso. E isto reconhecemos no \u00faltimo Coringa que tivemos em \u201cBatman: O Cavaleiro das Trevas\u201d. (N\u00e3o vou dar detalhes para n\u00e3o dar spoiler).<\/p>\n<p>A pr\u00f3pria Gotham j\u00e1 no in\u00edcio n\u00e3o est\u00e1 bem, mas deteriora-se a uma velocidade vertiginosa tamb\u00e9m e Coringa acaba por ser o s\u00edmbolo que se torna inspira\u00e7\u00e3o para a maldade na cidade. Ao mesmo tempo podemos dizer que mesmo daqueles que esper\u00e1vamos alguma bondade n\u00e3o encontramos. E este \u00e9 o ponto perturbador do filme: n\u00e3o existe bondade no filme. N\u00e3o existe esperan\u00e7a, n\u00e3o h\u00e1 beleza, n\u00e3o h\u00e1 um her\u00f3i, n\u00e3o h\u00e1 reden\u00e7\u00e3o. N\u00e3o h\u00e1 um motivo pela qual ter uma cara feliz (\u201cPut on a happy face\u201d, frase que surge no filme), n\u00e3o h\u00e1 motivo pelo qual ser Happy (apelido que a m\u00e3e de Coringa lhe d\u00e1).<\/p>\n<p>Temos um vil\u00e3o que cria empatia nos habitantes revoltados com o sistema presente em Gotham e cria empatia com os espectadores da sala de cinema. O contexto, as circunst\u00e2ncias, a educa\u00e7\u00e3o levam Coringa a se tornar quem \u00e9. N\u00e3o sabemos o que sentir quanto a Coringa. A relativiza\u00e7\u00e3o do mal que ele apregoa \u00e9 o que o personagem e a sua hist\u00f3ria e contexto nos fazem sentir em rela\u00e7\u00e3o a ele. Somos sedutora e subtilmente levados a entrar na mente de Coringa.<\/p>\n<p>A \u00fanica ponta, quase invis\u00edvel, de esperan\u00e7a e reden\u00e7\u00e3o que surge no filme \u00e9 o pequeno Bruce Wayne (futuro Batman), o personagem em volta de quem, em escassos minutos, \u00e9 apresentado em inoc\u00eancia. A esperan\u00e7a s\u00f3 \u00e9 associada a ele porque temos no\u00e7\u00e3o de em quem ele se tornar\u00e1, caso contr\u00e1rio passar-nos-ia completamente desapercebido.<\/p>\n<p>Este filme n\u00e3o retrata a vit\u00f3ria do bem contra o mal, nem sequer a luta existente entre eles, mas o mal como um beco sem sa\u00edda, onde todos s\u00e3o v\u00edtimas e perpetradores do mal. E de fato essa \u00e9 a triste e crua realidade da humanidade sem um Redentor. \u00c9 por isso que eu n\u00e3o tenho problema com este tipo de filmes, muito pelo contr\u00e1rio, \u00e9 uma apologia da Deprava\u00e7\u00e3o Radical, embora creia na Gra\u00e7a Comum, na imagem de Deus no homem e na transforma\u00e7\u00e3o que o Her\u00f3i dos her\u00f3is pode produzir no indiv\u00edduo e no coletivo, mas esse \u00e9 exatamente o ponto: sem uma interven\u00e7\u00e3o externa da Gra\u00e7a Comum e da Gra\u00e7a Salv\u00edfica, todos somos Coringa, todos estamos em Gotham e nem sequer h\u00e1 uma no\u00e7\u00e3o de certo e errado. N\u00e3o h\u00e1 absolutos. O mal e o bem s\u00e3o relativizados. O mal \u00e9 um total beco sem sa\u00edda. Todos se tornam v\u00edtimas e perpetradores do mal.<\/p>\n<p>Artisticamente e filosoficamente o filme \u00e9 excelente por retratar esta realidade t\u00e3o bem. Podia ter di\u00e1logos melhores, mas posso dizer que \u00e9 um filme genial. \u00c9 um filme genialmente feio, retrata coisas feias e faz-nos sentir coisas feias, mas isso n\u00e3o \u00e9 necessariamente mau, pelo contr\u00e1rio, \u00e9 curativo, pois leva-nos ao anseio por beleza, por esperan\u00e7a, por salva\u00e7\u00e3o, por reden\u00e7\u00e3o, por paz, por harmonia, por bondade; e esse \u00e9 o caminho que nos leva \u00e0 fonte da beleza, esperan\u00e7a, salva\u00e7\u00e3o, reden\u00e7\u00e3o, paz, harmonia e bondade &#8211; o Deus Tri\u00fano, Pai, Filho e Esp\u00edrito Santo, que nos pode tirar do beco sem sa\u00edda do mal, aquele que de fato coloca em n\u00f3s um rosto genuinamente feliz.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Joel Bueche Lopes. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/era-uma-vez-em-hollywood-e-o-poder-dos-filmes\/\">Coringa, um filme genial e perturbador<\/a>.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Sem uma interven\u00e7\u00e3o externa da Gra\u00e7a Comum e da Gra\u00e7a Salv\u00edfica, todos somos Coringa, todos estamos em Gotham e nem sequer h\u00e1 uma no\u00e7\u00e3o de certo e errado<\/p>\n","protected":false},"author":742,"featured_media":50815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3063],"tags":[2693],"class_list":["post-50813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosmovisao-e-cultura","tag-teoportugal","tema-artes-e-cultura","tema-coringa","tema-filmes-e-series","tema-joker"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coringa, um filme genial e perturbador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coringa, um filme genial e perturbador\" \/>\n<meta property=\"og:description\" content=\"Sem uma interven\u00e7\u00e3o externa da Gra\u00e7a Comum e da Gra\u00e7a Salv\u00edfica, todos somos Coringa, todos estamos em Gotham e nem sequer h\u00e1 uma no\u00e7\u00e3o de certo e errado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-07T19:30:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-28T16:53:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/10\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joel Bueche Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joel Bueche Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/\"},\"author\":{\"name\":\"Joel Bueche Lopes\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/92e8457a746f308b9589ad90b585d387\"},\"headline\":\"Coringa, um filme genial e perturbador\",\"datePublished\":\"2019-10-07T19:30:23+00:00\",\"dateModified\":\"2021-01-28T16:53:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/\"},\"wordCount\":910,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1\",\"keywords\":[\"TeoPortugal\"],\"articleSection\":[\"Cosmovis\u00e3o e cultura\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/\",\"name\":\"Coringa, um filme genial e perturbador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2019-10-07T19:30:23+00:00\",\"dateModified\":\"2021-01-28T16:53:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2019\\\/10\\\/coringa-um-filme-genial-e-perturbador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coringa, um filme genial e perturbador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/92e8457a746f308b9589ad90b585d387\",\"name\":\"Joel Bueche Lopes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2940c9a716cd425f61857939c017e37e061cad7baf2059eec8f0bd8e816ec3f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2940c9a716cd425f61857939c017e37e061cad7baf2059eec8f0bd8e816ec3f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b2940c9a716cd425f61857939c017e37e061cad7baf2059eec8f0bd8e816ec3f?s=96&d=mm&r=g\",\"caption\":\"Joel Bueche Lopes\"},\"description\":\"Joel Bueche Lopes \u00e9 pastor na Igreja Ac\u00e7\u00e3o B\u00edblica, em Faro, Portugal e Diretor Pastoral do Semin\u00e1rio Martin Bucer Portugal. \u00c9 formado em Psicologia Cl\u00ednica pela Universidade do Algarve e em Teologia pelo Semin\u00e1rio Teol\u00f3gico Baptista de Queluz. \u00c9 casado com Talita Lopes e pai do Rafael, Gabriel e Daniel.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/joel-bueche-lopes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coringa, um filme genial e perturbador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/","og_locale":"pt_BR","og_type":"article","og_title":"Coringa, um filme genial e perturbador","og_description":"Sem uma interven\u00e7\u00e3o externa da Gra\u00e7a Comum e da Gra\u00e7a Salv\u00edfica, todos somos Coringa, todos estamos em Gotham e nem sequer h\u00e1 uma no\u00e7\u00e3o de certo e errado","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2019-10-07T19:30:23+00:00","article_modified_time":"2021-01-28T16:53:14+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/10\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Joel Bueche Lopes","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Joel Bueche Lopes","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/"},"author":{"name":"Joel Bueche Lopes","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/92e8457a746f308b9589ad90b585d387"},"headline":"Coringa, um filme genial e perturbador","datePublished":"2019-10-07T19:30:23+00:00","dateModified":"2021-01-28T16:53:14+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/"},"wordCount":910,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/10\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1","keywords":["TeoPortugal"],"articleSection":["Cosmovis\u00e3o e cultura"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/","name":"Coringa, um filme genial e perturbador","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/10\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1","datePublished":"2019-10-07T19:30:23+00:00","dateModified":"2021-01-28T16:53:14+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/10\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/10\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2019\/10\/coringa-um-filme-genial-e-perturbador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Coringa, um filme genial e perturbador"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/92e8457a746f308b9589ad90b585d387","name":"Joel Bueche Lopes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b2940c9a716cd425f61857939c017e37e061cad7baf2059eec8f0bd8e816ec3f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b2940c9a716cd425f61857939c017e37e061cad7baf2059eec8f0bd8e816ec3f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b2940c9a716cd425f61857939c017e37e061cad7baf2059eec8f0bd8e816ec3f?s=96&d=mm&r=g","caption":"Joel Bueche Lopes"},"description":"Joel Bueche Lopes \u00e9 pastor na Igreja Ac\u00e7\u00e3o B\u00edblica, em Faro, Portugal e Diretor Pastoral do Semin\u00e1rio Martin Bucer Portugal. \u00c9 formado em Psicologia Cl\u00ednica pela Universidade do Algarve e em Teologia pelo Semin\u00e1rio Teol\u00f3gico Baptista de Queluz. \u00c9 casado com Talita Lopes e pai do Rafael, Gabriel e Daniel.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/joel-bueche-lopes\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/10\/Coringa-um-filme-genial-e-perturbador.jpg?fit=856%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-ddz","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/742"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=50813"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50813\/revisions"}],"predecessor-version":[{"id":50862,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/50813\/revisions\/50862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/50815"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=50813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=50813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=50813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}