{"id":51846,"date":"2020-01-10T09:00:48","date_gmt":"2020-01-10T12:00:48","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=51846"},"modified":"2020-01-09T18:41:23","modified_gmt":"2020-01-09T21:41:23","slug":"os-dedos-falam-do-que-esta-cheio-o-coracao","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/","title":{"rendered":"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p id=\"ae36\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">Voc\u00ea j\u00e1 cansou de ver pessoas criticando a internet e como nos portamos nela? J\u00e1 cansou de ver pessoas dando um tempo da internet e j\u00e1 fez isso? Eu tamb\u00e9m. Se voc\u00ea conhece um pouco dos meus textos e tweets, hoje eu gosto \u00e9 de falar de luz. Eu n\u00e3o quero que voc\u00ea saia das redes sociais, quero que voc\u00ea brilhe a luz de Cristo nelas. Claro, vamos falhar. Iremos, entretanto, iluminar tamb\u00e9m, mesmo com luz fraquejante.<\/p>\n<p id=\"a8b2\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">Para come\u00e7ar, quero te agradecer por seus posts com vers\u00edculos, com trechos de livros e can\u00e7\u00f5es, com sua simples alegria em comer e ver seu cachorrinho feliz para uma foto. Sou grata por tantas lembran\u00e7as do que pode dar esperan\u00e7a e que brilharam muitas vezes na tela do meu computador e celular enquanto eu precisava lidar com coisas dif\u00edceis fora da tela. Quando eu me converti e estava trabalhando em um ambiente complicado, foram in\u00fameros posts de irm\u00e3os no Facebook que me ajudavam a respirar (o que voc\u00ea estava fazendo em rede social no trabalho, Ana? \u00c9 meu trabalho h\u00e1 12 anos, colega!). Eu estava sozinha ali no emprego ouvindo diariamente pessoas falarem mal do meu Senhor, mas no meu feed havia v\u00e1rias luzinhas brilhando. Foram muitas as vezes que voc\u00ea me deu um sorriso ao compartilhar uma flor que achou bonita, o sorriso da priminha, uma frase do C.S Lewis, uma enquete criativa ou uma piadinha sem\/com gra\u00e7a (espero que o Rev. Emilio e o Galdino leiam isso). Eu poderia e deveria abrir a B\u00edblia numa aba ou colocar uma m\u00fasica no meu fone? Poderia. N\u00f3s fazemos isso intencionalmente sempre? N\u00e3o. Lembre isso.<\/p>\n<p id=\"888a\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">Imagine que a internet seja uma pequena cesta de frutos. O que voc\u00ea est\u00e1 colhendo dela? O que voc\u00ea coloca nela? Quem voc\u00ea \u00e9? \u201cA rede social \u00e9 minha, nela eu escrevo o que eu quiser\u201d. \u00c9 mesmo? Quem \u00e9 voc\u00ea nos seus coment\u00e1rios, respostas, imagens e nos 280 caracteres? Como voc\u00ea est\u00e1 se sentindo quando v\u00ea seus irm\u00e3os postando coisas felizes? Voc\u00ea se alegra com os que se alegram ou isso est\u00e1 te fazendo mal? Voc\u00ea est\u00e1 gostando de passar uma imagem de resmung\u00e3o, reclam\u00e3o, em que voc\u00ea cr\u00ea que todo mundo \u00e9 idiota menos voc\u00ea? \u00c9 poss\u00edvel ser uma pessoa na vida real e outra na internet sim, pro bem e pro mal, s\u00f3 n\u00e3o \u00e9 nem um pouco coerente. N\u00e3o se pode falar coisas boas sendo maus e nem tanta coisa ruim sendo bons.\u00a0<em class=\"hq\">\u201cPorque a boca fala do que est\u00e1 cheio o cora\u00e7\u00e3o\u201d Mateus 12.34.<\/em><\/p>\n<p id=\"ef5c\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">\u00c9 muito f\u00e1cil ser contaminado pela negatividade de not\u00edcias sensacionalistas, reclama\u00e7\u00f5es di\u00e1rias de conhecidos, milit\u00e2ncias irritantes e tretas que passam pelo feed. Isso acontece especialmente em redes sociais que nos fazem ver at\u00e9 o que n\u00e3o queremos pelo \u201cfulano curtiu, fulano seguiu\u201d. \u00c9 claro que nos nossos dias passam nuvens sobrecarregadas que nos causam raiva, tristeza e desesperan\u00e7a. Essas emo\u00e7\u00f5es podem sim virar poesia dolorida, mas com luz, vide Salmos. \u00c9 \u00fatil acompanhar coisas como \u201cEu passei por isso hoje e Deus me ajudou a agir de tal forma\u201d, sou grata a voc\u00ea por isso. Podemos compartilhar nossas experi\u00eancias ruins com maturidade e amor, amor a Deus, amor conosco e para com os outros. N\u00e3o imagino uma internet s\u00f3 com positividade e v\u00eddeos de gatinhos, longe de mim. Mas algo estranho ocorre na mente da pessoa ao entrar em algumas redes sociais, como se uma chave negativa se virasse, pois a p\u00e1gina da pessoa vira um verdadeiro muro de lamenta\u00e7\u00f5es e tretas que trazem tudo de ruim \u00e0 mem\u00f3ria, menos esperan\u00e7a (aconteceu comigo tamb\u00e9m, todas as minhas irrita\u00e7\u00f5es com chefes viravam desabafo p\u00fablico. Nunca melhorou em nada meus sentimentos). Vai dizer que voc\u00ea nunca passou alguns minutos no twitter e n\u00e3o se pegou respirando fundo, pesado e carregado. Eu n\u00e3o gosto disso.\u00a0<strong class=\"he hr\">Existe um recurso chamado silenciar, em todas as redes sociais. Faz bem.<\/strong><\/p>\n<h2 id=\"ea89\" class=\"ie if co at as ig eg ih ei ii ij ik il im in io ip\"><strong class=\"bw\">Ser\u00e1 que voc\u00ea se silenciaria?<\/strong><\/h2>\n<p id=\"0ae4\" class=\"hc hd co at he b hf iq hh ir hj is hl it hn iu hp\" data-selectable-paragraph=\"\">Examine seus pequenos frutos digitais. Examine seu cora\u00e7\u00e3o toda vez que entra na internet e s\u00f3 consegue escrever (ou pensar em) indireta, murmura\u00e7\u00e3o e cr\u00edticas. Eu tamb\u00e9m cansei de pessoas dizendo como nos portar na internet.<strong class=\"he hr\">\u00a0Mas voc\u00ea sabe que a B\u00edblia tem o nosso padr\u00e3o de comportamento em todo lugar, o tempo todo.<\/strong>\u00a0Algu\u00e9m pode estar tendo que respirar fundo toda vez que v\u00ea o que voc\u00ea escreve, mas o mais prov\u00e1vel \u00e9 que seja voc\u00ea mesmo.\u00a0Vamos ver?<\/p>\n<p id=\"cede\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">1- Se tem algo te incomodando em algu\u00e9m, a B\u00edblia te manda ir at\u00e9 a pessoa e exortar, tentar resolver, depois disso existem v\u00e1rios passos, ver Mateus 18, e\u00a0<strong class=\"he hr\">nenhum deles envolve indiretas nas redes sociais ou fofocas.<\/strong>\u00a0Se voc\u00ea tem capacidade de colocar em alguns caracteres e imagens uma \u00e1cida indireta contra seu irm\u00e3o, imagina a capacidade boa que voc\u00ea ter\u00e1 em dizer isso pra ele em amor. Ore a Deus por isso.<\/p>\n<p id=\"0e0f\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">2- Se h\u00e1 algo dif\u00edcil acontecendo em sua vida, e sei que tem (comigo tamb\u00e9m), lembre que<strong class=\"he hr\">\u00a0murmurar \u00e9 pecado saindo da sua boca ou dos seus dedos<\/strong>. Se s\u00f3 o que voc\u00ea consegue digitar \u00e9 reclama\u00e7\u00e3o de tudo, talvez voc\u00ea esteja acostumado a fazer isso no seu dia a dia o tempo todo. Deve estar dif\u00edcil conviver com voc\u00ea. O digital tamb\u00e9m \u00e9 o real, mesmo que apenas uma parte dele. Pense de que formas brandas e gratas a Deus voc\u00ea pode dizer a mesma coisa sem fazer mal para voc\u00ea e para quem te l\u00ea (e ouve). N\u00e3o \u00e9 s\u00f3 uma postura digital, voc\u00ea est\u00e1 treinando seu cora\u00e7\u00e3o com isso.<\/p>\n<p id=\"6df0\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">3- Voc\u00ea est\u00e1 precisando de ajuda?\u00a0<strong class=\"he hr\">Pe\u00e7a ajuda<\/strong>! Envie intencionalmente mensagem para irm\u00e3os da igreja e clame por socorro, jogar reclama\u00e7\u00f5es na web n\u00e3o vai alcan\u00e7ar a ajuda que voc\u00ea deseja encontrar. Deixe seus irm\u00e3os saberem da sua necessidade e d\u00ea a oportunidade de te servirem.\u00a0<a class=\"bq de iv iw ix iy\" href=\"https:\/\/fiel.in\/2t2Aeno\" rel=\"noopener\">Somos inconstantes e Deus colocou a igreja para ajudar.<\/a><\/p>\n<p id=\"4581\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">4- \u00c9 claro que as pessoas v\u00e3o publicar momentos felizes em seus perfis de imagens. Ningu\u00e9m tira foto quando est\u00e1 chorando.\u00a0<strong class=\"he hr\">N\u00e3o se alegrar com os que se alegram tem nome, \u00e9 inveja.\u00a0<\/strong>Acontece, infelizmente. Mas analise seu cora\u00e7\u00e3o e assuma isso para Deus em arrependimento, Ele vai te ajudar. O que voc\u00ea n\u00e3o pode \u00e9 culpar a felicidade dos outros pelo seu sentimento de insatisfa\u00e7\u00e3o e ingratid\u00e3o.<\/p>\n<p id=\"89aa\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">5- Pol\u00eamica ganha n\u00fameros, \u00e9 verdade, mas dificilmente produz bom fruto.<strong class=\"he hr\">\u00a0O que nos marca como crist\u00e3os \u00e9 sermos pacificadores, e n\u00e3o torcida de briga<\/strong>. E leve a s\u00e9rio o que Paulo disse a Tito sobre nos apartarmos de pessoas facciosas (Tito 3.10).\u00a0Treta por causa de uva passas \u00e9 engra\u00e7ado, fora isso voc\u00ea n\u00e3o vai convencer ningu\u00e9m a tirar uva passas ou evangelizar por brigas em postagens.\u00a0Precisando exortar um irm\u00e3o por algo que ele se passou al\u00ed numa postagem, fale, no m\u00ednimo, com ele no privado em amor.<\/p>\n<p id=\"606f\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">6- Na falta do que dizer,<strong class=\"he hr\">\u00a0n\u00e3o digite nada<\/strong>. Deveria estar na defini\u00e7\u00e3o de maturidade digital a capacidade de reler o que escreveu, apagar tudo antes de postar (em coment\u00e1rios e publica\u00e7\u00f5es) e reescrever, se necess\u00e1rio. Releia o que escreveu antes de apertar aquele bot\u00e3ozinho que joga suas letras pro mundo.<\/p>\n<p id=\"b311\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\">7- Vamos falhar, mas n\u00e3o precisa tamb\u00e9m ser o tempo todo.\u00a0<strong class=\"he hr\">Deus \u00e9 misericordioso, paciente e long\u00e2nimo, isso \u00e9 alento e n\u00e3o desculpa<\/strong>. Viver\u00a0<em class=\"hq\">Coram Deo<\/em>\u00a0\u00e9 viver Diante de Deus em todo o tempo, inclusive na internet. Somos imperfeitos e erramos. H\u00e1 boas novas. Aquele que \u00e9 a luz do mundo, diz que somos tamb\u00e9m.\u00a0<strong class=\"he hr\">E ele \u00e9 especialista em usar dias maus para o bem, como uma certa tumba vazia bem atesta.<\/strong> \u00c0s vezes, \u00e9 justamente nos dias escuros em que nos lembramos do livro que \u00e9 l\u00e2mpada. Por vezes, \u00e9 quando as luzes artificiais da cidade se v\u00e3o num apag\u00e3o que melhor contemplamos as estrelas. Sim, ele usa mesmo nossas tristezas pra iluminar o caminho. Pode acontecer de quando mais estamos doloridos \u00e9 que melhor escrevamos sobre ele. Poesia, muitas vezes, \u00e9 feita de l\u00e1grimas mesmo. Confiemos que a luz do mundo sabe o que est\u00e1 fazendo. As trevas n\u00e3o prevalecem contra ele.<\/p>\n<p id=\"a17f\" class=\"hc hd co at he b hf hg hh hi hj hk hl hm hn ho hp\" data-selectable-paragraph=\"\"><strong class=\"he hr\">Eu n\u00e3o quero que voc\u00ea saia da internet, quero que voc\u00ea seja luz nela.<\/strong>\u00a0Mas pode ser que sua luz esteja fraquinha ou, pior, que voc\u00ea esteja sendo trevas. Eu te aconselho a sair da internet por um tempo sim,<strong class=\"he hr\">\u00a0caso voc\u00ea n\u00e3o consiga utiliza-la sem cair no pecado.<\/strong>\u00a0Parar por um tempo pode ser bom. Cuidar do seu cora\u00e7\u00e3o, dedicar o tempo que est\u00e1 dedicando a invejar e reclamar a ler mais a B\u00edblia e orar. Depois, voc\u00ea volta e espelha essa luz com seus olhos, dedos e cora\u00e7\u00e3o.<\/p>\n<blockquote class=\"jb jc jd\">\n<p id=\"cbca\" class=\"hc hd co hq he b hf hg hh hi hj hk hl hm hn ho hp\" style=\"text-align: left;\" data-selectable-paragraph=\"\">Seja sal e luz onde estiver, inclusive na internet.<\/p>\n<\/blockquote>\n<hr \/>\n<p data-selectable-paragraph=\"\"><em>Texto cedido gentilmente pela autora. Voc\u00ea pode ler outros textos da autora\u00a0<a class=\"external\" href=\"https:\/\/medium.com\/@AnaPaulaNunes\/\" target=\"_blank\" rel=\"noopener noreferrer\">neste link<\/a>.<\/em><\/p>\n<p>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Ana Paula Nunes. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\/\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/\">Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o<\/a>.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Releia o que escreveu antes de apertar aquele bot\u00e3ozinho que joga suas letras pro mundo.<\/p>\n","protected":false},"author":688,"featured_media":51847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[409],"tags":[],"class_list":["post-51846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-crista","tema-redes-sociais","tema-redes-sociais-dup","tema-tecnologia","tema-tecnologia-dup","tema-vida-crista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Releia o que escreveu antes de apertar aquele bot\u00e3ozinho que joga suas letras pro mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-10T12:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Os-dedos-falam-do-que-esta\u0301-cheio-o-corac\u0327a\u0303o.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Paula Nunes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Paula Nunes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/\"},\"author\":{\"name\":\"Ana Paula Nunes\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/71bb672513980c61228855008ff61521\"},\"headline\":\"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o\",\"datePublished\":\"2020-01-10T12:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/\"},\"wordCount\":1599,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1\",\"articleSection\":[\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/\",\"name\":\"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2020-01-10T12:00:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/os-dedos-falam-do-que-esta-cheio-o-coracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/71bb672513980c61228855008ff61521\",\"name\":\"Ana Paula Nunes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fd5c12f412d1a8463401df41cf5590db7b353f44d2459f0c0afddc59bf3a7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fd5c12f412d1a8463401df41cf5590db7b353f44d2459f0c0afddc59bf3a7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fd5c12f412d1a8463401df41cf5590db7b353f44d2459f0c0afddc59bf3a7c?s=96&d=mm&r=g\",\"caption\":\"Ana Paula Nunes\"},\"description\":\"Ana Paula Nunes \u00e9 formada em Comunica\u00e7\u00e3o Social e p\u00f3s-graduada em Pol\u00edtica e Estrat\u00e9gia. Em teologia \u00e9 p\u00f3s graduada em Teologia B\u00edblica pelo CPAJ e possui cursos em Apolog\u00e9tica e Cosmovis\u00e3o Reformada no Semin\u00e1rio Presbiteriano de Bras\u00edlia. Congrega na Igreja Presbiteriana e \u00e9 editora do Literatura &amp; Reden\u00e7\u00e3o e Sherlocka Holmes. Costuma escrever outros textos em sherlockaholmes.medium.com.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/ana-paula-nunes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/","og_locale":"pt_BR","og_type":"article","og_title":"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o","og_description":"Releia o que escreveu antes de apertar aquele bot\u00e3ozinho que joga suas letras pro mundo.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-01-10T12:00:48+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Os-dedos-falam-do-que-esta\u0301-cheio-o-corac\u0327a\u0303o.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Ana Paula Nunes","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Ana Paula Nunes","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/"},"author":{"name":"Ana Paula Nunes","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/71bb672513980c61228855008ff61521"},"headline":"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o","datePublished":"2020-01-10T12:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/"},"wordCount":1599,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1","articleSection":["Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/","name":"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1","datePublished":"2020-01-10T12:00:48+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/os-dedos-falam-do-que-esta-cheio-o-coracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Os dedos falam do que est\u00e1 cheio o cora\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/71bb672513980c61228855008ff61521","name":"Ana Paula Nunes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6fd5c12f412d1a8463401df41cf5590db7b353f44d2459f0c0afddc59bf3a7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6fd5c12f412d1a8463401df41cf5590db7b353f44d2459f0c0afddc59bf3a7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6fd5c12f412d1a8463401df41cf5590db7b353f44d2459f0c0afddc59bf3a7c?s=96&d=mm&r=g","caption":"Ana Paula Nunes"},"description":"Ana Paula Nunes \u00e9 formada em Comunica\u00e7\u00e3o Social e p\u00f3s-graduada em Pol\u00edtica e Estrat\u00e9gia. Em teologia \u00e9 p\u00f3s graduada em Teologia B\u00edblica pelo CPAJ e possui cursos em Apolog\u00e9tica e Cosmovis\u00e3o Reformada no Semin\u00e1rio Presbiteriano de Bras\u00edlia. Congrega na Igreja Presbiteriana e \u00e9 editora do Literatura &amp; Reden\u00e7\u00e3o e Sherlocka Holmes. Costuma escrever outros textos em sherlockaholmes.medium.com.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/ana-paula-nunes\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/Os-dedos-falam-do-que-esta%CC%81-cheio-o-corac%CC%A7a%CC%83o.jpg?fit=856%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-due","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/51846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/688"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=51846"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/51846\/revisions"}],"predecessor-version":[{"id":51851,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/51846\/revisions\/51851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/51847"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=51846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=51846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=51846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}