{"id":52081,"date":"2020-01-27T12:04:57","date_gmt":"2020-01-27T15:04:57","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=52081"},"modified":"2020-01-27T12:07:02","modified_gmt":"2020-01-27T15:07:02","slug":"a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/","title":{"rendered":"A morte de um \u00edcone dos esportes e o resto de nossas vidas"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<blockquote>\n<p style=\"text-align: left;\">Atendei, agora, v\u00f3s que dizeis: Hoje ou amanh\u00e3, iremos para a cidade tal, e l\u00e1 passaremos um ano, e negociaremos, e teremos lucros. V\u00f3s n\u00e3o sabeis o que suceder\u00e1 amanh\u00e3. Que \u00e9 a vossa vida? Sois, apenas, como neblina que aparece por instante e logo se dissipa. <strong>Tiago 4.13,14<\/strong><\/p>\n<\/blockquote>\n<p>Pai Celestial, a morte de Kobe Bryant ontem atordoou, entristeceu e deixou muitos de n\u00f3s s\u00f3brios. Com apenas 41 anos de idade, j\u00e1 possuindo 1000 vezes mais do que a maioria possuir\u00e1 na vida.<\/p>\n<p>No entanto, a Escritura nos lembra que nossa vida n\u00e3o \u00e9 muito longa. Somos mais como uma breve n\u00e9voa do que um carvalho envelhecido. Voc\u00ea numerou os nossos dias; como quer ent\u00e3o que vivamos o resto das nossas vidas, Pai?<\/p>\n<p>\u00c0 luz do Evangelho, o que dever\u00edamos passar mais tempo fazendo, e menos tempo desperdi\u00e7ando? Mudar os nossos pre\u00e7os &#8211; fixar os nossos valores. O que temos adiado que realmente importa para voc\u00ea? Em que parte da hist\u00f3ria da reden\u00e7\u00e3o e da restaura\u00e7\u00e3o de Jesus voc\u00ea nos faria investir mais de n\u00f3s mesmos?<\/p>\n<p>Onde dever\u00edamos passar mais dos nossos dias, e menos das nossas preocupa\u00e7\u00f5es? Com quem devemos passar o tempo cara a cara e de cora\u00e7\u00e3o a cora\u00e7\u00e3o? Que rela\u00e7\u00f5es permitimos erroneamente que nos reivindicassem e nos drenassem mental e emocionalmente?<\/p>\n<p>Com quem ainda somos ref\u00e9ns pelo nossa falta de perd\u00e3o e dor? Pai, sabemos que n\u00e3o \u00e9 por fazer um trabalho melhor em qualquer uma dessas coisas que iremos merecer mais do seu afeto. Nenhuma destas perguntas tem um cart\u00e3o de pontua\u00e7\u00e3o anexado. \u00c9 no desempenho e recorde de Jesus que nos vangloriamos.<\/p>\n<p>MAS sua gra\u00e7a nos liberta para fazer as perguntas certas e viver uma vida que honre mais a Jesus, declare mais o Evangelho e revele mais da real liberdade. Ajude-nos, Pai, e esteja com aqueles mais diretamente impactados pela morte de Kobe Bryant. Portanto, am\u00e9m e am\u00e9m, n\u00f3s oramos, no nome incompar\u00e1vel e magn\u00edfico de Jesus.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Scotty Smith. \u00a9 The Gospel Coalition. Website: <a href=\"https:\/\/www.thegospelcoalition.org\/\">thegospelcoalition.org<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/www.thegospelcoalition.org\/blogs\/scotty-smith\/the-death-of-a-sports-icon-and-the-rest-of-our-lives\/\">The Death of a Sports Icon and the Rest of Our Lives<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/\">A morte de um \u00edcone dos esportes e o resto de nossas vidas<\/a>. \u00a9 Minist\u00e9rio Fiel. Website: <a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">MinisterioFiel.com.br<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Que \u00e9 a vossa vida? Sois, apenas, como neblina que aparece por instante e logo se dissipa.<\/p>\n","protected":false},"author":308,"featured_media":52083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-52081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A morte de um \u00edcone dos esportes e o resto de nossas vidas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A morte de um \u00edcone dos esportes e o resto de nossas vidas\" \/>\n<meta property=\"og:description\" content=\"Que \u00e9 a vossa vida? Sois, apenas, como neblina que aparece por instante e logo se dissipa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-27T15:04:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-27T15:07:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/A-morte-de-um-i\u0301cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Scotty Smith\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Scotty Smith\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/\"},\"author\":{\"name\":\"Scotty Smith\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/dda1aca516a5b3df052110db225a6ad6\"},\"headline\":\"A morte de um \u00edcone dos esportes e o resto de nossas vidas\",\"datePublished\":\"2020-01-27T15:04:57+00:00\",\"dateModified\":\"2020-01-27T15:07:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/\"},\"wordCount\":461,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1\",\"articleSection\":[\"...\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/\",\"name\":\"A morte de um \u00edcone dos esportes e o resto de nossas vidas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2020-01-27T15:04:57+00:00\",\"dateModified\":\"2020-01-27T15:07:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/01\\\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A morte de um \u00edcone dos esportes e o resto de nossas vidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/dda1aca516a5b3df052110db225a6ad6\",\"name\":\"Scotty Smith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Scotty-Smith_avatar_1410893498.jpg\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Scotty-Smith_avatar_1410893498.jpg\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Scotty-Smith_avatar_1410893498.jpg\",\"caption\":\"Scotty Smith\"},\"description\":\"Rev. Scotty Smith \u00e9 o pastor fundador da Christ Community Church em Franklin, Tennessee, e \u00e9 autor de Everyday Prayers: 365 Days to a Gospel-Centered Faith.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/scotty-smith\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A morte de um \u00edcone dos esportes e o resto de nossas vidas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/","og_locale":"pt_BR","og_type":"article","og_title":"A morte de um \u00edcone dos esportes e o resto de nossas vidas","og_description":"Que \u00e9 a vossa vida? Sois, apenas, como neblina que aparece por instante e logo se dissipa.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-01-27T15:04:57+00:00","article_modified_time":"2020-01-27T15:07:02+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/A-morte-de-um-i\u0301cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Scotty Smith","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Scotty Smith","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/"},"author":{"name":"Scotty Smith","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/dda1aca516a5b3df052110db225a6ad6"},"headline":"A morte de um \u00edcone dos esportes e o resto de nossas vidas","datePublished":"2020-01-27T15:04:57+00:00","dateModified":"2020-01-27T15:07:02+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/"},"wordCount":461,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1","articleSection":["..."],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/","name":"A morte de um \u00edcone dos esportes e o resto de nossas vidas","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1","datePublished":"2020-01-27T15:04:57+00:00","dateModified":"2020-01-27T15:07:02+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/01\/a-morte-de-um-icone-dos-esportes-e-o-resto-de-nossas-vidas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"A morte de um \u00edcone dos esportes e o resto de nossas vidas"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/dda1aca516a5b3df052110db225a6ad6","name":"Scotty Smith","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Scotty-Smith_avatar_1410893498.jpg","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Scotty-Smith_avatar_1410893498.jpg","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Scotty-Smith_avatar_1410893498.jpg","caption":"Scotty Smith"},"description":"Rev. Scotty Smith \u00e9 o pastor fundador da Christ Community Church em Franklin, Tennessee, e \u00e9 autor de Everyday Prayers: 365 Days to a Gospel-Centered Faith.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/scotty-smith\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-dy1","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/01\/A-morte-de-um-i%CC%81cone-dos-esportes-e-o-resto-de-nossas-vidas.jpg?fit=856%2C394&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/308"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=52081"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52081\/revisions"}],"predecessor-version":[{"id":52086,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52081\/revisions\/52086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/52083"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=52081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=52081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=52081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}