{"id":52296,"date":"2020-02-05T10:46:38","date_gmt":"2020-02-05T13:46:38","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=52296"},"modified":"2020-02-05T10:47:11","modified_gmt":"2020-02-05T13:47:11","slug":"dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/","title":{"rendered":"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Existem todos os tipos de modelos e debates sobre como, por que e quando devemos plantar e \/ ou lan\u00e7ar novas igrejas. Algumas pessoas preferem o modelo de pequenos grupos \/ igrejas dom\u00e9sticas \/ grupos comunit\u00e1rios, que certamente \u00e9 uma maneira j\u00e1 experimentada, testada e comprovada de plantar novas congrega\u00e7\u00f5es em certos contextos culturais.<\/p>\n<p>Eu, por exemplo, n\u00e3o estou convencido de que essa seja uma estrat\u00e9gia vitoriosa nos bairros de moradias sociais (isso n\u00e3o quer dizer, a prop\u00f3sito, que esses grupos n\u00e3o tenham m\u00e9rito pastoral em nosso contexto). Temos o modelo \u201ccair de paraquedas\u201d, no qual um grupo de pessoas de fora salta para dentro de uma comunidade para aprender sua cultura e come\u00e7ar a construir uma comunidade evang\u00e9lica. Temos a abordagem de \u201cnave m\u00e3e\u201d, a mais favorecida no Reino Unido, onde uma congrega\u00e7\u00e3o maior e mais rica financia um novo trabalho em uma ou mais \u00e1reas. Depois, h\u00e1 aqueles que preferem a revitaliza\u00e7\u00e3o de igrejas. E isso, apenas para citar algumas das muitas metodologias dispon\u00edveis.<\/p>\n<p>Na 20schemes, queremos trabalhar de forma confessional, dentro de uma estrutura evang\u00e9lica conservadora, em uma variedade de contextos. Portanto, n\u00e3o defendemos um modelo em detrimento de outro. Nossa vis\u00e3o \u00e9 resolver o problema de alcan\u00e7ar as comunidades habitacionais carentes n\u00e3o alcan\u00e7adas da Esc\u00f3cia, revitalizando e \/ ou plantando igrejas centradas no evangelho. N\u00e3o acreditamos necessariamente que um \u201ctamanho \u00fanico\u201d sirva para todos.<\/p>\n<p>No entanto, recomendamos algumas considera\u00e7\u00f5es b\u00e1sicas para aqueles que pensam em fazer parceria conosco neste tipo de minist\u00e9rio.<\/p>\n<h2>1. Re\u00fana uma equipe de \u201ctempo integral\u201d<\/h2>\n<p>Penso que precisamos ter um grupo de 10 a 15 crist\u00e3os comprometidos, que vivam na \u00e1rea que pretendem plantar \/ revitalizar, a fim de iniciar um novo trabalho em uma comunidade. De prefer\u00eancia, pelo menos duas dessas pessoas trabalhar\u00e3o em tempo integral no minist\u00e9rio, se quisermos ver algum tipo de aceita\u00e7\u00e3o na comunidade nos primeiros dias. Precisamos que os principais membros de nossa equipe estejam em outro emprego de per\u00edodo integral (por raz\u00f5es \u00f3bvias), mas precisamos ter alguma presen\u00e7a em tempo integral em todo o local, se quisermos criar algum tipo de in\u00e9rcia.<\/p>\n<p>Agora, essa equipe n\u00e3o precisa estar no local, totalmente pronta, desde o in\u00edcio, mas devemos trabalhar em dire\u00e7\u00e3o essa configura\u00e7\u00e3o dentro dos primeiros cinco anos (sim, voc\u00ea leu o termo \u201cconfigura\u00e7\u00e3o\u201d corretamente). Isso significa que, aqui, precisamos ter cuidado com os tipos de l\u00edderes que colocamos no campo. Considera\u00e7\u00f5es espirituais e de car\u00e1ter \u00e0 parte, eles dever\u00e3o ser l\u00edderes fortes, pensadores positivos, ter um verdadeiro esp\u00edrito empreendedor e ser perseverante. Personagens sossegados e descontra\u00eddos, que s\u00e3o facilmente desencorajados, n\u00e3o ser\u00e3o \u201cboas not\u00edcias\u201d para esse tipo de trabalho nos primeiros anos. Algu\u00e9m que constr\u00f3i uma equipe e uma igreja do zero ter\u00e1 que ter um olhar muito diferente de outro que assume um trabalho moribundo e tem que pastorear uma comunidade atrav\u00e9s de sua morte e renascimento.<\/p>\n<h2>2. \u201cViver dentro\u201d<\/h2>\n<p>Muitos \u201cpensamentos mission\u00e1rios\u201d trabalham com a premissa de buscar construir relacionamentos de longo prazo, mas, pelo menos nas comunidades habitacionais carentes, o \u201ctrabalho\u201d de estabelecer suas \u201ccredenciais\u201d acontece muito cedo. Aqui, as pessoas v\u00e3o querer saber quem voc\u00ea \u00e9 e sobre suas inten\u00e7\u00f5es desde o in\u00edcio. Eles v\u00e3o querer saber o que voc\u00ea est\u00e1 fazendo na \u00e1rea deles, mesmo porque as pessoas (principalmente as que tem alguma qualifica\u00e7\u00e3o e educa\u00e7\u00e3o formal) sonham em se mudar para fora e n\u00e3o para dentro da comunidade. Portanto, se entenderem os l\u00edderes chaves como \u201cseguros \/ legais \/ tudo bem\u201d, ent\u00e3o geralmente aceitam o restante do grupo, mesmo aqueles que n\u00e3o conhecem t\u00e3o bem. Estar vis\u00edvel durante o dia e ter uma rotina (papelaria, pub, caf\u00e9 local, etc.) permitir\u00e1 que voc\u00ea obtenha sinergia mais rapidamente.<\/p>\n<p>Eu continuo batendo nessa tecla porque conhe\u00e7o muitos que pensam que podem fazer o trabalho apenas indo diariamente \u00e0 comunidade. Eles podem at\u00e9 fazer contatos e desenvolver amizades, mas \u00e9 muito dif\u00edcil vender a vis\u00e3o da comunidade crist\u00e3 quando n\u00f3s mesmos n\u00e3o estamos dispostos a viver essa comunidade dentro do terreno deles. N\u00e3o conhe\u00e7o nenhum trabalho em comunidades carentes ou conjuntos habitacionais em que a abordagem da \u201cvisita di\u00e1ria\u201d tenha funcionado com algum grau de sucesso. Os l\u00edderes que vivem na comunidade ter\u00e3o um trabalho muito mais f\u00e1cil em \u201cvender\u201d a vis\u00e3o do que aqueles que vivem fora. Por que as pessoas devem investir em uma \u201cigreja\u201d quando os l\u00edderes nem vivem na comunidade?<\/p>\n<h2>3. Ter uma \u201ctrabalhadora\u201d em per\u00edodo integral<\/h2>\n<p>Qualquer que seja a abordagem adotada para o plantio de igrejas em comunidades habitacionais, devemos ter uma trabalhadora em per\u00edodo integral (que n\u00e3o precisa, necessariamente, ser a esposa do plantador). Sem isso, acho que temos pouca ou nenhuma chance de desenvolver um minist\u00e9rio hol\u00edstico e entrar no que costuma ser um sistema muito matriarcal (m\u00e3es e av\u00f3s governam nesses locais!) Muitas vezes, elas podem ser a chave para o resto da fam\u00edlia.<\/p>\n<h2>4. N\u00e3o v\u00e1 sozinho e nem envie um \u201ccontratado em p\u00e2nico\u201d<\/h2>\n<p>Tenho aconselhado pessoas, que est\u00e3o participando de trabalhos nessas comunidades uma vez por semana, em um encontro infantil ou um estudo b\u00edblico, e percebo que elas ficam desanimadas com a falta de frutos e progresso. Outros, desiludidos com a igreja local, se mudaram para ser uma \u201cpresen\u00e7a\u201d na comunidade. Mas esse tipo de minist\u00e9rio n\u00e3o \u00e9 um empreendimento solo.<\/p>\n<p>Da mesma forma, tenho conversado com igrejas idosas e \/ ou moribundas, nessas comunidades, que pensam que a chave para resolver seus problemas nessas \u00e1reas \u00e9 contratar alguns \u201cjovens\u201d e jog\u00e1-los aos lobos. Geralmente, \u00e9 um graduado na Escola B\u00edblica, com 20 anos e de olhos arregalados, que ser\u00e1 devorado por qualquer pessoa da comunidade com mais de oito anos de idade! Repito, sem uma estrat\u00e9gia mais ampla e um sistema de suporte \u00e0 equipe, isso, quase certamente, resultar\u00e1 em um desastre.<\/p>\n<p>Pior que isso, conhe\u00e7o igrejas que empregaram homens entre os 50 e os 60 anos para mudar suas igrejas ou replantar \/ revitaliz\u00e1-las. Essa \u00e9 uma pol\u00edtica desastrosa se eles n\u00e3o conseguirem reunir rapidamente uma equipe jovem. Mesmo agora, aos 40 anos, percebo que o futuro do meu minist\u00e9rio estar\u00e1 cada vez mais no treinamento de jovens para fazer o trabalho. A diversidade \u00e9 fundamental, mas acho que plantar igrejas em comunidades carentes \u00e9 trabalho para jovens, devido ao tempo e esfor\u00e7o envolvidos no estabelecimento de contatos o quanto antes.<\/p>\n<h2>5. Estabele\u00e7a onde voc\u00ea se re\u00fane<\/h2>\n<p>Agora, acho que isso talvez seja mais importante do que qualquer outra considera\u00e7\u00e3o. Nas comunidades habitacionais carentes, as pessoas consideram, com grande suspeita, as reuni\u00f5es religiosas feitas em locais que n\u00e3o se parecem com um pr\u00e9dio de igreja. Qualquer coisa que n\u00e3o seja considerada uma \u201cigreja\u201d \u00e9 visto como \u201cseita\u201d e extremamente suspeito. E n\u00e3o estou exagerando nesse ponto.<\/p>\n<p>Por exemplo, em minha primeira igreja, que se reunia em um antigo sal\u00e3o da comunidade, meu pai ficou muito desconfort\u00e1vel e, a certa altura, me questionou se era mesmo uma igreja \u201creal\u201d. No entanto, em minha segunda igreja, que se reunia em um pr\u00e9dio recuperado da Igreja da Inglaterra, ele e minha madrasta eram (relativamente) felizes, desfrutavam do culto e se sentiam muito relaxados. Ambas as comunidades eram evang\u00e9licas e tinham praticamente o mesmo estilo de adora\u00e7\u00e3o, e ainda assim foi o edif\u00edcio que acalmou seus medos e preconceitos. H\u00e1 muita conversa sobre a igreja \u201cser as pessoas\u201d e n\u00e3o o edif\u00edcio, e eu entendo que isso tenha sido (em grande parte) uma resposta. Mas n\u00e3o subestime o \u201clocal\u201d de uma nova igreja ao trabalhar nessas comunidades.<\/p>\n<p>Al\u00e9m disso, a reputa\u00e7\u00e3o conta muito nessas comunidades. Em Niddrie, por exemplo, nos encontramos em um pr\u00e9dio novinho em folha que se parece mais com um centro comunit\u00e1rio, que parece ir contra tudo o que escrevi acima. No entanto, as pessoas da comunidade \u201cconfiam\u201d nele (mesmo que n\u00e3o venham \u00e0 igreja) por causa dos cem anos de hist\u00f3ria associados \u00e0 \u201cmiss\u00e3o\u201d que foi executada naquele pr\u00e9dio. O interessante \u00e9 que alguns plantadores de igrejas vieram e foram embora em Niddrie na \u00faltima d\u00e9cada. Onde sempre foi o local de encontro deles? O centro comunit\u00e1rio local. Na minha opini\u00e3o, uma das (muitas) raz\u00f5es para o fracasso foi que as pessoas aqui n\u00e3o associam esse lugar \u00e0 \u201cigreja\u201d e, portanto, n\u00e3o levam a iniciativa a s\u00e9rio.<\/p>\n<p>Esses s\u00e3o alguns pontos iniciais a serem considerados ao pensarmos mais sobre o minist\u00e9rio em comunidades habitacionais carentes em todo o pa\u00eds.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Mez McConnell. \u00a9 20schemes. Website: <a href=\"https:\/\/20schemes.com\/pt-br\/\" target=\"_blank\" rel=\"noopener noreferrer\">20schemes.com<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/20schemesequip.com\/tips-for-church-planting-in-areas-of-urban-deprivation\/\">Tips for Church Planting in Areas of Urban Deprivation<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/\">Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes<\/a>. \u00a9 Minist\u00e9rio Fiel. Website:\u00a0<a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">MinisterioFiel.com.br<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Paulo Reiss Junior. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Alguns pontos iniciais a serem considerados ao pensarmos mais sobre planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes.<\/p>\n","protected":false},"author":422,"featured_media":52298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[897],"class_list":["post-52296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-igreja-para-a-periferia-20schemes","tema-evangelizacao-e-missoes","tema-evangelizacao-e-missoes-dup","tema-plantacao-de-igrejas","tema-plantacao-de-igrejas-dup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes\" \/>\n<meta property=\"og:description\" content=\"Alguns pontos iniciais a serem considerados ao pensarmos mais sobre planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-05T13:46:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-05T13:47:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Dicas-para-plantac\u0327a\u0303o-de-igrejas-em-a\u0301reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mez McConnell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mez McConnell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/\"},\"author\":{\"name\":\"Mez McConnell\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/16ed25e9425ec13faec54df31da35da1\"},\"headline\":\"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes\",\"datePublished\":\"2020-02-05T13:46:38+00:00\",\"dateModified\":\"2020-02-05T13:47:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/\"},\"wordCount\":1590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1\",\"keywords\":[\"Igreja para a Periferia - 20schemes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/\",\"name\":\"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2020-02-05T13:46:38+00:00\",\"dateModified\":\"2020-02-05T13:47:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/16ed25e9425ec13faec54df31da35da1\",\"name\":\"Mez McConnell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"caption\":\"Mez McConnell\"},\"description\":\"\u00c9 pastor s\u00eanior da Niddrie Community Church, Edimburgo, Esc\u00f3cia. \u00c9 fundador do 20schemes, um minist\u00e9rio voltado para planta\u00e7\u00e3o de igrejas nos lugares mais dif\u00edceis da Esc\u00f3cia. Desde 1999, McConnell tem se envolvido com o minist\u00e9rio pastoral, tanto em planta\u00e7\u00e3o quanto revitaliza\u00e7\u00e3o.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/mez-mcconnell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/","og_locale":"pt_BR","og_type":"article","og_title":"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes","og_description":"Alguns pontos iniciais a serem considerados ao pensarmos mais sobre planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-02-05T13:46:38+00:00","article_modified_time":"2020-02-05T13:47:11+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Dicas-para-plantac\u0327a\u0303o-de-igrejas-em-a\u0301reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Mez McConnell","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Mez McConnell","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/"},"author":{"name":"Mez McConnell","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/16ed25e9425ec13faec54df31da35da1"},"headline":"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes","datePublished":"2020-02-05T13:46:38+00:00","dateModified":"2020-02-05T13:47:11+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/"},"wordCount":1590,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1","keywords":["Igreja para a Periferia - 20schemes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/","name":"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1","datePublished":"2020-02-05T13:46:38+00:00","dateModified":"2020-02-05T13:47:11+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/dicas-para-plantacao-de-igrejas-em-areas-urbanas-carentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Dicas para planta\u00e7\u00e3o de igrejas em \u00e1reas urbanas carentes"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/16ed25e9425ec13faec54df31da35da1","name":"Mez McConnell","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","caption":"Mez McConnell"},"description":"\u00c9 pastor s\u00eanior da Niddrie Community Church, Edimburgo, Esc\u00f3cia. \u00c9 fundador do 20schemes, um minist\u00e9rio voltado para planta\u00e7\u00e3o de igrejas nos lugares mais dif\u00edceis da Esc\u00f3cia. Desde 1999, McConnell tem se envolvido com o minist\u00e9rio pastoral, tanto em planta\u00e7\u00e3o quanto revitaliza\u00e7\u00e3o.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/mez-mcconnell\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Dicas-para-plantac%CC%A7a%CC%83o-de-igrejas-em-a%CC%81reas-urbanas-carentes.jpg?fit=856%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-dBu","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/422"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=52296"}],"version-history":[{"count":3,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52296\/revisions"}],"predecessor-version":[{"id":52301,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52296\/revisions\/52301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/52298"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=52296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=52296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=52296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}