{"id":52500,"date":"2020-02-20T17:04:01","date_gmt":"2020-02-20T20:04:01","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=52500"},"modified":"2020-02-20T17:04:32","modified_gmt":"2020-02-20T20:04:32","slug":"com-que-roupa-eu-vou","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/","title":{"rendered":"Com que roupa eu vou?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Quem nunca se pegou em frente ao seu guarda-roupa pensando \u201cN\u00e3o tenho nada pra vestir! Preciso de roupas novas! Cansei destas pe\u00e7as!\u201d? Ou quem nunca sonhou em frente a TV, desejando participar daqueles shows de transforma\u00e7\u00e3o de estilo, com profissionais do ramo da moda que mudam seu guarda roupa, maquiagem, cabelo&#8230; quem nunca?<\/p>\n<p>Ent\u00e3o, j\u00e1 pensaram se esta nossa vontade de mudan\u00e7a fosse refletida em nosso interior? Vontade ansiosa de colocar pra fora do arm\u00e1rio tudo o que n\u00e3o te representa mais, todos aqueles costumes que n\u00e3o te servem mais. Pois lhes digo que esta deveria ser a nossa vontade a partir do momento que somos remidas por Cristo, colocar fora tudo o que representa o velho eu.<\/p>\n<p>Paulo escreve exortando os Ef\u00e9sios para que n\u00e3o sejam mais como os gentios, pois eles aprenderam um novo modo de viver em Cristo:<\/p>\n<p><em>Ef\u00e9sios 4.17-24<\/em><\/p>\n<p><em>17 Isto, portanto, digo e no Senhor testifico que n\u00e3o mais andeis como tamb\u00e9m andam os gentios, na vaidade dos seus pr\u00f3prios pensamentos,<\/em><\/p>\n<p><em>18 obscurecidos de entendimento, alheios \u00e0 vida de Deus por causa da ignor\u00e2ncia em que vivem, pela dureza do seu cora\u00e7\u00e3o,<\/em><\/p>\n<p><em>19 os quais, tendo-se tornado insens\u00edveis, se entregaram \u00e0 dissolu\u00e7\u00e3o para, com avidez, cometerem toda sorte de impureza.<\/em><\/p>\n<p><em>20 Mas n\u00e3o foi assim que aprendestes a Cristo,<\/em><\/p>\n<p><em>21 se \u00e9 que, de fato, o tendes ouvido e nele fostes instru\u00eddos, segundo \u00e9 a verdade em Jesus,<\/em><\/p>\n<p><em>22 no sentido de que, quanto ao trato passado, vos despojeis do velho homem, que se corrompe segundo as concupisc\u00eancias do engano,<\/em><\/p>\n<p><em>23 e vos renoveis no esp\u00edrito do vosso entendimento,<\/em><\/p>\n<p><em>24 e vos revistais do novo homem, criado segundo Deus, em justi\u00e7a e retid\u00e3o procedentes da verdade.<\/em><\/p>\n<h2>1. O que n\u00e3o vestir<\/h2>\n<p>No verso 17, quando Paulo exorta os Ef\u00e9sios para que ajam reverentemente de acordo com a justa vontade de Deus. Eles precisariam ter uma vida diferente, agora que se tornaram disc\u00edpulos de Cristo. E ele lhes d\u00e1 uma lista de como os \u00edmpios agem.<\/p>\n<p>E n\u00f3s? Ser\u00e1 que agimos como \u00edmpios?<\/p>\n<p>Os \u00edmpios s\u00e3o vaidosos em seus pr\u00f3prios pensamentos e se enganam achando que v\u00e3o encontrar felicidade longe de Deus. E n\u00e3o pense que isto n\u00e3o acontece com voc\u00ea e comigo, pois as concupisc\u00eancias do engano (vs 22), os desejos desenfreados, desmedidos e enganosos est\u00e3o mais pr\u00f3ximos de n\u00f3s do que pensamos. Por muitas vezes n\u00f3s ca\u00edmos nestas mentiras e as tomamos por verdades, em:<\/p>\n<h3>Emprego<\/h3>\n<p>H\u00e1 mulheres que acham que precisam de um emprego fora de casa, e que somente assim elas ter\u00e3o seu papel na sociedade e ser\u00e3o propriamente valorizadas. Elas precisam se levantar logo cedo, se maquiar, colocar seus saltos e sair mundo afora, pois somente assim elas se sentir\u00e3o \u201calgu\u00e9m\u201d. Elas creem que somente assim elas far\u00e3o algo de importante e relevante neste mundo. Vejam, n\u00e3o estou dizendo que \u00e9 errado mulher trabalhar fora de casa, mas se \u00e9 esta a fonte do seu contentamento, ent\u00e3o \u00e9 pecaminoso, pois n\u00e3o \u00e9 isto que vai definir ou valorizar a mulher.<\/p>\n<h3>Compras<\/h3>\n<p>Outras creem que ter coisas, roupas, sapatos, etc, \u00e9 muito importante, ent\u00e3o elas compram, adquirem, gastam mesmo sem precisar. S\u00e3o movidas pela vaidade e temor de homens. Pois pensam que sem \u201cter\u201d elas n\u00e3o \u201cs\u00e3o ningu\u00e9m\u201d.<\/p>\n<h3>Relacionamentos impuros:<\/h3>\n<p>\u00c0s vezes parece que na igreja o mar n\u00e3o est\u00e1 para peixe. Os homens s\u00e3o escassos, desinteressantes, e \u00e0s vezes nem s\u00e3o t\u00e3o \u201chomens\u201d quanto gostar\u00edamos que fossem. Ent\u00e3o, o que a mo\u00e7a solteira faz? Vai pescar em outro aqu\u00e1rio, no oceano a\u00ed de fora, ou seja, no mundo. Namoro mission\u00e1rio (jugo desigual) n\u00e3o \u00e9 recomendado em nenhum lugar na B\u00edblia, portanto cuidado com mais este engano.<\/p>\n<p>Poder\u00edamos aqui pensar em muitos outros exemplos de como n\u00f3s podemos cair na tenta\u00e7\u00e3o de ir atr\u00e1s de nossos pr\u00f3prios pensamentos vaidosos e de \u201ccorrer atr\u00e1s do vento\u201d. Portanto, pe\u00e7a ao Senhor que lhe ajude a identificar enganos em sua vida que voc\u00ea tem tomado por verdades.<\/p>\n<p>O verso 18 fala de os gentios estarem obscurecidos de entendimento, que \u00e9 o mesmo que uma cegueira espiritual (n\u00e3o \u00e9 uma defici\u00eancia visual), \u00e9 uma falta de capacidade de raciocinar equilibradamente. Geralmente o homem que \u00e9 cego espiritualmente \u00e9 incapacidade de perceber sua cegueira, n\u00e3o percebe que \u201cele habita nas trevas e as pr\u00f3prias trevas tamb\u00e9m habitam nele\u201d (Willian Hendriksen).<\/p>\n<p>Infelizmente por mais que estas pessoas se julguem do bem e pr\u00f3ximas de Deus, na verdade elas est\u00e3o afastadas, alienadas do Senhor, mortas em seus delitos e pecados. Al\u00e9m disto, a falta de sensibilidade do cora\u00e7\u00e3o faz com elas permane\u00e7am na carne e se entreguem aos seus pr\u00f3prios prazeres desenfreadamente com avidez, sem limite (vs 19).<\/p>\n<p>Estes homens e mulheres, em \u00c9feso, n\u00e3o faziam esfor\u00e7o para sufocar seus desejos, n\u00e3o tinham dom\u00ednio pr\u00f3prio sobre seus v\u00edcios e pecados. Estavam sempre desejando mais, muito mais al\u00e9m do que lhes era devido e apropriado.<\/p>\n<p>Conseguem pensar em exemplos atuais? Exemplos de exibicionismo, lasc\u00edvia e imoralidade que s\u00e3o publicados sem vergonha, sem receio nas redes sociais, para que muitos curtam e apreciem? Exibicionismo, lasc\u00edvia e imoralidade aconteciam naquela \u00e9poca entre os gentios (\u00c9feso, Sodoma e Gomorra) e acontecem hoje tamb\u00e9m (at\u00e9 entre os crentes), por\u00e9m n\u00e3o podem permanecer em nosso meio. N\u00f3s que somos de Cristo n\u00e3o podemos aprovar este tipo de comportamento, ele tem de ser despido, despojado, n\u00e3o pode ficar em nosso guarda-roupa, pois o velho homem nascido de Ad\u00e3o foi crucificado com Cristo e n\u00e3o podemos mais servir ao pecado como escravos (Rm 6.6).<\/p>\n<p>As caracter\u00edsticas dos gentios que Paulo lista neste texto, tem a finalidade de mostrar a condi\u00e7\u00e3o miser\u00e1vel que eles se encontravam, a fim de incitar uma mudan\u00e7a de disposi\u00e7\u00e3o naqueles que s\u00e3o nascidos de novo.<\/p>\n<p>Pois, assim como os crentes de \u00c9feso, Cristo passou a ser o principal sujeito em nossas vidas, ele passou a ser a verdade que nos guia (ele mesmo diz em Jo\u00e3o 14.6 \u201cEu sou o caminho, e a verdade, e a vida.\u201d) ent\u00e3o, deste ponto em diante, temos que andar em novidade de vida, tirando do nosso guarda-roupa as pe\u00e7as que n\u00e3o nos representam mais como crist\u00e3s, experimentando arrependimento de nossos pecados e renunciando nossa natureza corrupta.<\/p>\n<p>Aquele que conhece a Cristo, mas tem uma vida semelhante aos incr\u00e9dulos, nada aprendeu do Senhor, pois conhecer a Cristo est\u00e1 intimamente ligado \u00e0 mortifica\u00e7\u00e3o da carne (Calvino).<\/p>\n<h2>2. Siga as dicas do Personal Stylist<\/h2>\n<p>Lembram que eu mencionei os profissionais de moda que s\u00e3o especialistas em transformar as pessoas? Pois \u00e9, hoje em dia os Personal Stylists est\u00e3o em alta. Eles analisam que cores ficam melhores com seu tom de pele, que corte de roupa combina com o formato do seu corpo, seu tipo de cabelo, etc. Eles montam um guarda roupa coordenado com um cat\u00e1logo de fotos dos looks que voc\u00ea pode consultar para montar as combina\u00e7\u00f5es, assim voc\u00ea sai sempre bem vestida, com tudo combinando.<\/p>\n<p>Aqui o ap\u00f3stolo Paulo \u00e9 nosso Personal Stylist, nos apontando o que tirar do guarda roupa e o que incluir nele.<\/p>\n<p>N\u00e3o adianta apenas despir-se do velho, pois ao mesmo tempo em que o velho tem de ser despojado e rejeitado, h\u00e1 um novo que tem de ser revestido. Uma nova mulher segundo o padr\u00e3o de santidade e pureza de Deus, uma nova mulher que \u00e9 procedente da verdade, criada por Deus em justi\u00e7a e retid\u00e3o (vs 24). A nova mulher espelha a Cristo.<\/p>\n<p><em>Revesti-vos, pois, como eleitos de Deus, santos e amados, de ternos afetos de miseric\u00f3rdia, de bondade, de humildade, de mansid\u00e3o, de longanimidade. (Cl 3.12)<\/em><\/p>\n<p>Em contraste com os gentios que s\u00e3o obscurecidos em seus entendimentos, crentes precisam fugir da futilidade de seus pensamentos e ter uma nova atitude em suas mentes. Isto pode dizer muito a respeito de como utilizamos nosso tempo diariamente, como falamos com aqueles mais pr\u00f3ximos, como servimos, como honramos ao Senhor com nossas roupas externas e conversas, etc.<\/p>\n<h2>3. Com que roupa eu vou ent\u00e3o?<\/h2>\n<p>Somos agora iluminadas pela doutrina da salva\u00e7\u00e3o. N\u00e3o somos mais ignorantes quanto a Deus, quanto a sua cria\u00e7\u00e3o, quanto a tudo o que ele fez por n\u00f3s. Pois temos agora a verdade habitando em n\u00f3s. Portanto, os nossos frutos precisam ser diferentes agora que temos o Esp\u00edrito de Deus habitando em n\u00f3s.<\/p>\n<p>Em G\u00e1latas 5.22, 23 Paulo escreve sobre o Fruto do Esp\u00edrito:<\/p>\n<p><em>Mas o fruto do Esp\u00edrito \u00e9: amor, alegria, paz, longanimidade, benignidade, bondade, fidelidade, mansid\u00e3o, dom\u00ednio pr\u00f3prio. Contra estas coisas n\u00e3o h\u00e1 lei.\u201d<\/em><\/p>\n<p>Este \u00e9 o fruto que temos que produzir revestidas da nova mulher com uma nova mente.<\/p>\n<p>E em Filipenses 4.8, o ap\u00f3stolo nos d\u00e1 uma lista que nos ajuda a preencher nossas mentes com o que \u00e9 santo:<\/p>\n<p><em>\u201cFinalmente irm\u00e3os, tudo o que \u00e9 verdadeiro, tudo o que \u00e9 respeit\u00e1vel, tudo o que \u00e9 justo, tudo o que \u00e9 puro, tudo o que \u00e9 am\u00e1vel, tudo o que \u00e9 de boa fama, se alguma virtude h\u00e1 e se algum louvor existe, seja isso o que ocupe o vosso pensamento.\u201d<\/em><\/p>\n<p>Por\u00e9m, a santifica\u00e7\u00e3o, que \u00e9 este processo de limpeza e mudan\u00e7a, n\u00e3o \u00e9 algo que acontece 100% de uma vez, \u00e9 algo que acontece progressivamente. N\u00f3s n\u00e3o estamos mais sob as amarras do pecado, ele n\u00e3o nos domina mais. Mas, ainda vivemos em um mundo corrompido, sofrendo as consequ\u00eancias que a queda trouxe sobre todos n\u00f3s.<\/p>\n<p><em>\u201cTirou-me de um po\u00e7o de perdi\u00e7\u00e3o, de um tremedal de lama; colocou-me os p\u00e9s sobre uma rocha e me firmou os passos.\u201d Salmo 40.2<\/em><\/p>\n<p>J\u00e1 ouvi v\u00e1rias vezes que, primeiro Deus nos tira da lama, depois ele come\u00e7a a tirar a lama de dentro de n\u00f3s. Este \u00e9 o processo de santifica\u00e7\u00e3o.<\/p>\n<p>Nossa santifica\u00e7\u00e3o tem de gerar mentes que aprendem em Cristo (vs 20) como servir e amar, como ser submissa e conselheira, e como ser auxiliadora e entusiasta. Isto temos que fazer com aqueles os quais Deus colocou em nossas vidas para cuidarmos e apoiarmos (pais, filhos, esposos, irm\u00e3s e irm\u00e3os na f\u00e9). Isto pode ser considerado como uma renova\u00e7\u00e3o do esp\u00edrito do nosso entendimento (vs 23), ter uma mente que aprende em Cristo e o tem como seu modelo.<\/p>\n<p>Deus \u00e9 quem nos d\u00e1 uma nova roupa que espelha o car\u00e1ter de Cristo, a certeza de uma renova\u00e7\u00e3o satisfat\u00f3ria, uma vida de contentamento pleno, pois, em Cristo somos novas criaturas (2Co 5.17), nascidas de novo.<\/p>\n<p>Em Cristo somos RENOVADAS! Temos uma nova mente, novas vestes e podemos nos alegrar nesta certeza, n\u00e3o por sermos fortes, invenc\u00edveis e empoderadas (como o mundo prega a\u00ed fora!), mas porque nosso Deus n\u00e3o mente, ele \u00e9 um Deus reto, justo e verdadeiro e ele mesmo come\u00e7ou a boa obra em n\u00f3s e h\u00e1 de termin\u00e1-la.<\/p>\n<p>Firmadas nesta certeza podemos nos alegrar em nos revestir com a nova roupa de Cristo e sermos mais parecidas com ele diariamente.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Natalie Campos. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\/\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/\">Com que roupa eu vou?<\/a>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Temos que andar em novidade de vida, tirando do nosso guarda-roupa as pe\u00e7as que n\u00e3o nos representam mais como crist\u00e3s, experimentando arrependimento de nossos pecados e renunciando nossa natureza corrupta.<\/p>\n","protected":false},"author":758,"featured_media":52504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3065,624],"tags":[],"class_list":["post-52500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casamento-e-familia","category-mulheres","tema-despojar-e-revestir","tema-mulheres","tema-santificacao","tema-santificacao-e-crescimento","tema-vida-crista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Com que roupa eu vou?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com que roupa eu vou?\" \/>\n<meta property=\"og:description\" content=\"Temos que andar em novidade de vida, tirando do nosso guarda-roupa as pe\u00e7as que n\u00e3o nos representam mais como crist\u00e3s, experimentando arrependimento de nossos pecados e renunciando nossa natureza corrupta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-20T20:04:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-20T20:04:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalie Campos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalie Campos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/\"},\"author\":{\"name\":\"Natalie Campos\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/580fa1bfb29d56da67937441e2298939\"},\"headline\":\"Com que roupa eu vou?\",\"datePublished\":\"2020-02-20T20:04:01+00:00\",\"dateModified\":\"2020-02-20T20:04:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/\"},\"wordCount\":1967,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1\",\"articleSection\":[\"Casamento e fam\u00edlia\",\"Mulheres\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/\",\"name\":\"Com que roupa eu vou?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2020-02-20T20:04:01+00:00\",\"dateModified\":\"2020-02-20T20:04:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/02\\\/com-que-roupa-eu-vou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Com que roupa eu vou?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/580fa1bfb29d56da67937441e2298939\",\"name\":\"Natalie Campos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3155274eef5f63d6247b16f338d24e306fd64e35e494e8c843e9dc0c20157aba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3155274eef5f63d6247b16f338d24e306fd64e35e494e8c843e9dc0c20157aba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3155274eef5f63d6247b16f338d24e306fd64e35e494e8c843e9dc0c20157aba?s=96&d=mm&r=g\",\"caption\":\"Natalie Campos\"},\"description\":\"Natalie Campos \u00e9 formada em Publicidade e Propaganda, mas tem o privil\u00e9gio e escolha de ser dona de casa em tempo integral. Desenvolve um trabalho, juntamente com outras mulheres, voltado para esposas de seminaristas no Semin\u00e1rio Presbiteriano em SP. Natalie \u00e9 esposa de Heber Campos Jr., com quem tem tr\u00eas filhos: Bianca, Samuel e Nicole.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/natalie-campos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com que roupa eu vou?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/","og_locale":"pt_BR","og_type":"article","og_title":"Com que roupa eu vou?","og_description":"Temos que andar em novidade de vida, tirando do nosso guarda-roupa as pe\u00e7as que n\u00e3o nos representam mais como crist\u00e3s, experimentando arrependimento de nossos pecados e renunciando nossa natureza corrupta.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-02-20T20:04:01+00:00","article_modified_time":"2020-02-20T20:04:32+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Natalie Campos","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Natalie Campos","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/"},"author":{"name":"Natalie Campos","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/580fa1bfb29d56da67937441e2298939"},"headline":"Com que roupa eu vou?","datePublished":"2020-02-20T20:04:01+00:00","dateModified":"2020-02-20T20:04:32+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/"},"wordCount":1967,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1","articleSection":["Casamento e fam\u00edlia","Mulheres"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/","name":"Com que roupa eu vou?","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1","datePublished":"2020-02-20T20:04:01+00:00","dateModified":"2020-02-20T20:04:32+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/02\/com-que-roupa-eu-vou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Com que roupa eu vou?"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/580fa1bfb29d56da67937441e2298939","name":"Natalie Campos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3155274eef5f63d6247b16f338d24e306fd64e35e494e8c843e9dc0c20157aba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3155274eef5f63d6247b16f338d24e306fd64e35e494e8c843e9dc0c20157aba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3155274eef5f63d6247b16f338d24e306fd64e35e494e8c843e9dc0c20157aba?s=96&d=mm&r=g","caption":"Natalie Campos"},"description":"Natalie Campos \u00e9 formada em Publicidade e Propaganda, mas tem o privil\u00e9gio e escolha de ser dona de casa em tempo integral. Desenvolve um trabalho, juntamente com outras mulheres, voltado para esposas de seminaristas no Semin\u00e1rio Presbiteriano em SP. Natalie \u00e9 esposa de Heber Campos Jr., com quem tem tr\u00eas filhos: Bianca, Samuel e Nicole.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/natalie-campos\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-dEM","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/02\/Com-que-roupa-eu-vou.jpg?fit=856%2C394&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/758"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=52500"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52500\/revisions"}],"predecessor-version":[{"id":52505,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52500\/revisions\/52505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/52504"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=52500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=52500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=52500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}