{"id":52936,"date":"2020-03-23T16:00:06","date_gmt":"2020-03-23T19:00:06","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=52936"},"modified":"2020-05-13T22:17:29","modified_gmt":"2020-05-14T01:17:29","slug":"10-mandamentos-para-sobreviver-ao-coronavirus","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/","title":{"rendered":"10 mandamentos para sobreviver ao Coronav\u00edrus"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>1. N\u00e3o entrar\u00e1s em p\u00e2nico:<\/strong> A crise que estamos vivendo n\u00e3o \u00e9 a primeira e, muito provavelmente, n\u00e3o ser\u00e1 a \u00faltima. \u00c9 um momento de calamidade, mas n\u00e3o \u00e9 o fim do mundo. Vai passar. Mantenha a calma e aja com prud\u00eancia.<\/p>\n<p><strong>2. N\u00e3o sair\u00e1s de casa:<\/strong> O momento exige que n\u00f3s deixemos nossas casas apenas para atendermos necessidades b\u00e1sicas para sobreviv\u00eancia (mercado, farm\u00e1cia, hospitais, etc.). Reaprenda a interagir com sua fam\u00edlia de uma forma criativa, afinal, eles s\u00e3o o nosso bem mais precioso aqui nesta terra.<\/p>\n<p><strong>3. N\u00e3o entrar\u00e1s em embates pol\u00edticos:<\/strong> As briguinhas entre esquerdas e direitas nas redes precisam parar. A circunst\u00e2ncia a qual estamos submetidos exige a uni\u00e3o da na\u00e7\u00e3o. Temos muito mais cren\u00e7as que nos unem do que nos separam. Somos todos os seres humanos, criados \u00e0 imagem e semelhan\u00e7a do Criador, com a mesma dignidade e, portanto, devemos focar no bem do pr\u00f3ximo acima de qualquer coisa.<\/p>\n<p><strong>4. N\u00e3o deixar\u00e1s a generosidade:<\/strong> Embora o momento seja de reclus\u00e3o, ele tamb\u00e9m nos compele \u00e0 solidariedade aos mais afetados por essa pandemia. Pessoas de maior idade precisam de nosso tempo, esfor\u00e7os e recursos. Doe alimentos, itens de higiene e outros recursos para quem n\u00e3o tem. Coloque-se a disposi\u00e7\u00e3o das pessoas ao seu redor e tome como sua a causa dos que no momento n\u00e3o podem defender-se contra o v\u00edrus.<\/p>\n<p><strong>5. N\u00e3o ficar\u00e1s sem dialogar:<\/strong> Estamos distantes fisicamente, mas n\u00e3o virtualmente. Mantenha contato com seus amigos, familiares e colegas de trabalho por meio das redes sociais, chamadas de v\u00eddeo, \u00e1udio, entre outros. Cheque se todos ao seu redor est\u00e3o bem, ore por eles, conforte-os, mantenha o sorriso e leve esperan\u00e7a por onde voc\u00ea for.<\/p>\n<p><strong>6. N\u00e3o cair\u00e1s na ociosidade:<\/strong> Tome cuidado com o mal uso do tempo. Aproveite esse intervalo de confinamento para ler bons livros, estudar as Escrituras, ouvir palestras, e divertir-se com sua fam\u00edlia. \u00c9 tempo de redimir o tempo, \u201cpois os dias s\u00e3o maus\u201d (Ef 5.16).<\/p>\n<p><strong>7. N\u00e3o esquecer\u00e1s o teu Deus:<\/strong> Lembre-se das palavras do salmista, \u201cDeus \u00e9 o nosso ref\u00fagio e fortaleza, socorro bem-presente nas tribula\u00e7\u00f5es\u201d (Sl 46.1) N\u00e3o pare de cultuar a Deus, seja com sua fam\u00edlia, nas redes sociais e individualmente. Intensifique suas ora\u00e7\u00f5es. Renove seu fervor espiritual. Guarde o seu cora\u00e7\u00e3o de cair no desespero. Fa\u00e7a com que este tempo de medo seja inundado pela paz do Eterno, pois \u201cO Senhor dos Ex\u00e9rcitos est\u00e1 conosco; o Deus de Jac\u00f3 \u00e9 o nosso ref\u00fagio\u201d (Sl 46.11).<\/p>\n<p><strong>8. N\u00e3o adivinhar\u00e1s o futuro:<\/strong> N\u00e3o sabemos direito ainda o que nos espera. Pode ser que em poucos meses a situa\u00e7\u00e3o esteja controlada, pode ser que demore um pouco mais. Cada pa\u00eds tem seu pr\u00f3prio modo de enfrentar pandemias. Oro para que o Brasil leve a situa\u00e7\u00e3o a s\u00e9rio e que Deus nos livre disso o mais r\u00e1pido poss\u00edvel. Por hora, o mais prudente \u00e9 evitar falat\u00f3rios in\u00fateis, teorias de conspira\u00e7\u00e3o e sermos realistas.<\/p>\n<p><strong>9. N\u00e3o abandonar\u00e1s a miss\u00e3o:<\/strong> Crises como essa nos ensinam mais que qualquer serm\u00e3o que algo est\u00e1 errado com a humanidade. Por causa de um s\u00f3 homem, milhares e, possivelmente, milh\u00f5es est\u00e3o sendo infectadas pelo v\u00edrus. Essa situa\u00e7\u00e3o ecoa de certa forma a narrativa do evangelho, como o ap\u00f3stolo Paulo afirmou, \u201cpor uma s\u00f3 ofensa, veio o ju\u00edzo sobre todos os homens para condena\u00e7\u00e3o, assim tamb\u00e9m, por um s\u00f3 ato de justi\u00e7a, veio a gra\u00e7a sobre todos os homens para a justifica\u00e7\u00e3o que d\u00e1 vida\u201d (Rm 5.18). Uma pandemia como essa tamb\u00e9m \u00e9 uma oportunidade de proclamar o evangelho que nos salva de um perigo muito maior que o coronav\u00edrus (COVID-19), o de permanecer morto espiritualmente para sempre.<\/p>\n<p><strong>10. N\u00e3o perder\u00e1s a esperan\u00e7a:<\/strong> Finalmente, precisamos reafirmar em meio \u00e0s turbul\u00eancias que Deus n\u00e3o perdeu o controle da hist\u00f3ria. O mundo parece um caos porque s\u00f3 o vemos como num quebra-cabe\u00e7as. A maioria das \u201cpe\u00e7as\u201d n\u00e3o fazem sentido. Por\u00e9m, um dia veremos o quebra-cabe\u00e7as pronto e diremos que Deus \u00e9 verdadeiramente s\u00e1bio em tudo o que faz. Deus n\u00e3o est\u00e1 sentado em uma cadeira, comendo pipoca, vendo o mundo ser destru\u00eddo pelo sofrimento, pelo mal e pela injusti\u00e7a. Deus est\u00e1 consertando o mundo. Ele j\u00e1 come\u00e7ou a consertar esse mundo, porque em Cristo j\u00e1 come\u00e7ou a consertar voc\u00ea e eu. N\u00e3o perca a esperan\u00e7a, a pandemia n\u00e3o \u00e9 a \u00faltima palavra.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Jean Francesco. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\/\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/\">10 mandamentos para sobreviver ao Coronav\u00edrus<\/a>.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Deus n\u00e3o est\u00e1 sentado em uma cadeira, comendo pipoca, vendo o mundo ser destru\u00eddo pelo sofrimento, pelo mal e pela injusti\u00e7a. Deus est\u00e1 consertando o mundo. Ele j\u00e1 come\u00e7ou a consertar esse mundo, porque em Cristo j\u00e1 come\u00e7ou a consertar voc\u00ea e eu.<\/p>\n","protected":false},"author":790,"featured_media":52939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[410],"tags":[2090],"class_list":["post-52936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-problemas-da-vida","tag-teobrasil","tema-coronavirus-covid-19","tema-doencas-dup","tema-problemas-da-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 mandamentos para sobreviver ao Coronav\u00edrus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 mandamentos para sobreviver ao Coronav\u00edrus\" \/>\n<meta property=\"og:description\" content=\"Deus n\u00e3o est\u00e1 sentado em uma cadeira, comendo pipoca, vendo o mundo ser destru\u00eddo pelo sofrimento, pelo mal e pela injusti\u00e7a. Deus est\u00e1 consertando o mundo. Ele j\u00e1 come\u00e7ou a consertar esse mundo, porque em Cristo j\u00e1 come\u00e7ou a consertar voc\u00ea e eu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T19:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T01:17:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/03\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Francesco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Francesco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/\"},\"author\":{\"name\":\"Jean Francesco\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/29ce68bcb627a93202389af9ed17560f\"},\"headline\":\"10 mandamentos para sobreviver ao Coronav\u00edrus\",\"datePublished\":\"2020-03-23T19:00:06+00:00\",\"dateModified\":\"2020-05-14T01:17:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/\"},\"wordCount\":859,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1\",\"keywords\":[\"TeoBrasil\"],\"articleSection\":[\"Problemas da Vida\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/\",\"name\":\"10 mandamentos para sobreviver ao Coronav\u00edrus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2020-03-23T19:00:06+00:00\",\"dateModified\":\"2020-05-14T01:17:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/03\\\/10-mandamentos-para-sobreviver-ao-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 mandamentos para sobreviver ao Coronav\u00edrus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/29ce68bcb627a93202389af9ed17560f\",\"name\":\"Jean Francesco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2522aec5588ddd9ca05ff9c290efa1f624e36364b2c9f355f1acbdd22831699?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2522aec5588ddd9ca05ff9c290efa1f624e36364b2c9f355f1acbdd22831699?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2522aec5588ddd9ca05ff9c290efa1f624e36364b2c9f355f1acbdd22831699?s=96&d=mm&r=g\",\"caption\":\"Jean Francesco\"},\"description\":\"Jean Francesco \u00e9 pastor presbiteriano, bacharel em Teologia pelo Semin\u00e1rio Presbiteriano do Sul (2009) e pela Universidade Presbiteriana Mackenzie (2016). Mestre em Teologia pelo Centro de P\u00f3s-Gradua\u00e7\u00e3o Andrew Jumper, CPAJ (2017) e doutorando em Teologia Sistem\u00e1tica pelo Calvin Theological Seminary. Autor do livro \u201cO Significado do Namoro\u201d. Integra a equipe pastoral da Igreja Presbiteriana da Penha como ministro ordenado desde 2013. Jean \u00e9 casado com Gesi\u00ea e pai do Valentim.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/jean-francesco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 mandamentos para sobreviver ao Coronav\u00edrus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/","og_locale":"pt_BR","og_type":"article","og_title":"10 mandamentos para sobreviver ao Coronav\u00edrus","og_description":"Deus n\u00e3o est\u00e1 sentado em uma cadeira, comendo pipoca, vendo o mundo ser destru\u00eddo pelo sofrimento, pelo mal e pela injusti\u00e7a. Deus est\u00e1 consertando o mundo. Ele j\u00e1 come\u00e7ou a consertar esse mundo, porque em Cristo j\u00e1 come\u00e7ou a consertar voc\u00ea e eu.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-03-23T19:00:06+00:00","article_modified_time":"2020-05-14T01:17:29+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/03\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Jean Francesco","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Jean Francesco","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/"},"author":{"name":"Jean Francesco","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/29ce68bcb627a93202389af9ed17560f"},"headline":"10 mandamentos para sobreviver ao Coronav\u00edrus","datePublished":"2020-03-23T19:00:06+00:00","dateModified":"2020-05-14T01:17:29+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/"},"wordCount":859,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/03\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1","keywords":["TeoBrasil"],"articleSection":["Problemas da Vida"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/","name":"10 mandamentos para sobreviver ao Coronav\u00edrus","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/03\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1","datePublished":"2020-03-23T19:00:06+00:00","dateModified":"2020-05-14T01:17:29+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/03\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/03\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/03\/10-mandamentos-para-sobreviver-ao-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"10 mandamentos para sobreviver ao Coronav\u00edrus"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/29ce68bcb627a93202389af9ed17560f","name":"Jean Francesco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e2522aec5588ddd9ca05ff9c290efa1f624e36364b2c9f355f1acbdd22831699?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e2522aec5588ddd9ca05ff9c290efa1f624e36364b2c9f355f1acbdd22831699?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2522aec5588ddd9ca05ff9c290efa1f624e36364b2c9f355f1acbdd22831699?s=96&d=mm&r=g","caption":"Jean Francesco"},"description":"Jean Francesco \u00e9 pastor presbiteriano, bacharel em Teologia pelo Semin\u00e1rio Presbiteriano do Sul (2009) e pela Universidade Presbiteriana Mackenzie (2016). Mestre em Teologia pelo Centro de P\u00f3s-Gradua\u00e7\u00e3o Andrew Jumper, CPAJ (2017) e doutorando em Teologia Sistem\u00e1tica pelo Calvin Theological Seminary. Autor do livro \u201cO Significado do Namoro\u201d. Integra a equipe pastoral da Igreja Presbiteriana da Penha como ministro ordenado desde 2013. Jean \u00e9 casado com Gesi\u00ea e pai do Valentim.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/jean-francesco\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/03\/10-mandamentos-para-sobriviver-ao-coronavirus.jpg?fit=856%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-dLO","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/790"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=52936"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52936\/revisions"}],"predecessor-version":[{"id":52942,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/52936\/revisions\/52942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/52939"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=52936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=52936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=52936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}