{"id":53327,"date":"2020-04-15T19:28:55","date_gmt":"2020-04-15T22:28:55","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=53327"},"modified":"2020-04-15T19:38:19","modified_gmt":"2020-04-15T22:38:19","slug":"caminhar-e-crer","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/","title":{"rendered":"Caminhar \u00e9 crer"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_btn title=&#8221;S\u00e9rie &#8220;Seguindo a Jesus&#8220; | Clique e veja os outros artigos&#8221; size=&#8221;sm&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffiel.in%2F2tfVINy|title:S%C3%A9rie%20%22Seguindo%20a%20Jesus%22%20%7C%20Clique%20e%20veja%20os%20outros%20artigos||&#8221;][vc_column_text]Leitura B\u00edblica: Marcos 5.21-6.6<\/p>\n<hr \/>\n<p><em>Ambas as hist\u00f3rias s\u00e3o sobre medo e f\u00e9, e o poder de Jesus de levar as pessoas de um para o outro. Ambas, individualmente e juntas, valem o investimento de tempo, no sentido de meditar nelas, imaginando que voc\u00ea est\u00e1 na multid\u00e3o assistindo tudo isso acontecer. Ent\u00e3o, se voc\u00ea tiver coragem, voc\u00ea pode se identificar com v\u00e1rios personagens desse drama. <strong>Essa \u00e9 uma maneira maravilhosa de transformar as escrituras em ora\u00e7\u00e3o &#8211; e hoje, como nos dias de Jesus, transformar o medo em f\u00e9.<\/strong>\u201d \u2013 Tom Wright<\/em><\/p>\n<p>Em nossa \u00faltima reflex\u00e3o observamos que as hist\u00f3rias narradas em Marcos 4:25-5:43 apontam para a triunfante a\u00e7\u00e3o de Cristo contra os mais amedrontadores poderes de oposi\u00e7\u00e3o: o mar e o vento (4:35-41), os dem\u00f4nios (5:1-20), a doen\u00e7a (5:25-34) e a morte (5:21-24; 35-43). Vimos que essas hist\u00f3rias est\u00e3o claramente associadas e descrevem a superioridade de Cristo sobre todos os diferentes poderes associados \u00e0 morte e ao mal.<\/p>\n<p>Al\u00e9m disso, observamos que existe entre as duas primeiras hit\u00f3rias uma rela\u00e7\u00e3o muito interessante com o primeiro exorcismo de Jesus no Evangelho de Marcos. Ao descrever a primeira miss\u00e3o de Cristo em territ\u00f3rio n\u00e3o judaico, o autor deixa muito claro o tipo de cen\u00e1rio repulsivo que o Mestre passaria a enfrentar: um mar de comportamento demon\u00edaco (4:37-39), um homem possesso por um esp\u00edrito imundo (5:2-5), numa terra gent\u00edlica (5:1), cercado por uma multid\u00e3o de criadores de porcos (5:14-17). Marcos n\u00e3o mede esfor\u00e7os para dizer que Jesus entrava em um novo territ\u00f3rio e simbolicamente ultrapassava um novo limite moral.<\/p>\n<p>Agora, do mesmo modo que vimos nas duas primeiras hist\u00f3rias contadas por Marcos aqui, as duas \u00faltimas hist\u00f3rias tamb\u00e9m est\u00e3o intimamente conectadas. N\u00e3o apenas as duas hist\u00f3rias s\u00e3o contadas ao mesmo tempo, como tamb\u00e9m s\u00e3o emolduradas pelo mesmo modelo: Ambas as hist\u00f3rias contam a respeito um homem (5:22) e uma mulher (5:26) em situa\u00e7\u00e3o de desespero (5:23, 35; 5:25-26); enquanto Jairo v\u00ea a Jesus (5:22), a mulher ouve falar a seu respeito (5:27); ambos caem aos p\u00e9s de Jesus (<strong>\u03c0\u1f77\u03c0\u03c4\u03c9<\/strong><strong>, <em>pipto\u0304; <\/em><\/strong>5:22; <strong>\u03c0\u03c1\u03bf\u03c3\u03c0\u1f77\u03c0\u03c4\u03c9<\/strong><strong>, <em>prospipto\u0304; <\/em><\/strong>5:33) e manifestam medo (<strong>\u03c6\u03bf\u03b2\u1f73\u03c9<\/strong><strong>, <em>fobeo\u0304; <\/em><\/strong>5:36; 5:33) e f\u00e9 (<strong>\u03c0\u1f77\u03c3\u03c4\u03b9\u03c2<\/strong><strong>, <em>pistis; <\/em><\/strong>5:36; 5:34); al\u00e9m disso, Jairo intercede por sua filha de doze anos (<strong>\u03b4\u1f7d\u03b4\u03b5\u03ba\u03b1<\/strong><strong>, <em>do\u0304deka; <\/em><\/strong>5:42), ao passo que a mulher intercede por si mesma, que a doze anos sofria com sua enfermidade (<strong>\u03b4\u1f7d\u03b4\u03b5\u03ba\u03b1<\/strong><strong>, <em>do\u0304deka; <\/em><\/strong>5:25). Em ambas as hist\u00f3rias, embora Jesus n\u00e3o seja compreendido pela multid\u00e3o (5:31; 5:40), Ele oferece salva\u00e7\u00e3o tanto para a menina (<strong>\u03c3\u1ff4\u03b6\u03c9<\/strong><strong>, <em>so\u0304zo\u0304<\/em>;<\/strong> 5:23, <em>cf. <\/em>v. 42) como para a mulher (<strong>\u03c3\u1ff4\u03b6\u03c9<\/strong><strong>, <em>so\u0304zo\u0304<\/em>;<\/strong> 5:28, 34). Na verdade, essas duas hist\u00f3rias est\u00e3o t\u00e3o conectadas que poderiam ser reconhecidas como uma hist\u00f3rias s\u00f3.<\/p>\n<p>Em outras palavras, essas duas hist\u00f3rias culminam um movimento liter\u00e1rio de Marcos em demonstrar acrescente manifesta\u00e7\u00e3o da autoridade de Cristo: (1) sobre uma situa\u00e7\u00e3o de <strong>quase morte<\/strong> no mar (4:35-41), (2) sobre uma <strong>vida entre a morte<\/strong> nos sepulcros (5:1-20), (3) sobre uma experi\u00eancia de <strong>morte em vida<\/strong> (5:25-34) e por fim (4) sobre a pr\u00f3pria <strong>morte<\/strong> (5:21-24; 35-43). E ao entender a narrativa nesses termos, algu\u00e9m esperaria um final triunfante para tais eventos: quem sabe uma grande convers\u00e3o em massa, e uma multid\u00e3o ainda maior de disc\u00edpulos; ou quem sabe ainda o reconhecimento de Jesus como o Filho de Deus.<\/p>\n<p>Entretanto, Marcos demonstra exatamente o contr\u00e1rio, e frustra quase que completamente as expectativas do leitor atento. A hist\u00f3rias que finaliza essa sequencia de hist\u00f3rias de triunfo do nosso Mestre \u00e9 uma inesperada narrativa da <strong>rejei\u00e7\u00e3o de Jesus em sua pr\u00f3pria cidade<\/strong> (6:1-6). Ou seja, depois de realizar grande feitos reconhecidos pelos seus conterr\u00e2neos (6:2), Jesus \u00e9 novamente rejeitado na sinagoga (6:3; <em>cf. <\/em>2:6; 3:6). Ao que parece, Marcos parece ensinar que a crescente manifesta\u00e7\u00e3o da autoridade de Cristo por meio de milagres \u00a0surpreendentes n\u00e3o produzia uma resposta positiva de f\u00e9 das pessoas que o assistiam.<\/p>\n<p>Ao contr\u00e1rio da opini\u00e3o popular, <strong>milagres n\u00e3o aumentam a possibilidade de uma resposta positiva de f\u00e9 daqueles que os testemunham<\/strong>. E isso, n\u00f3s j\u00e1 vimos acontecer outras vezes nesse Evangelho: quando Jesus manifestou seu poder para perdoar pecados ao curar um paral\u00edtico, Ele foi chamado de blasfemo (2:1-12) e quando ele curou um homem de m\u00e3o ressequida, as autoridades judaicas passaram a conspirar para mata-lo (3:1-6). Al\u00e9m disso, as autoridades teol\u00f3gicas sabiam explicar os milagres muito bem: para eles os atos de Cristo eram operados por Satan\u00e1s (3:22, 30). Mas, tal conclus\u00e3o n\u00e3o era restrita apenas \u00e0s autoridades judaicas, pois os pr\u00f3prios criadores de porcos esposavam similar opini\u00e3o (5:17; <em>cf.<\/em> v.10). Ou seja, os milagres realizados por Cristo, da perspectiva daqueles que se op\u00f5em a Ele, s\u00e3o nada mais nada menos do que motivos para o esc\u00e2ndalo: \u201c\u2019De onde lhe vem estas coisas? Que sabedoria \u00e9 esta que lhe foi dada<strong>? E estes milagres que Ele faz?<\/strong> N\u00e3o \u00e9 este o carpinteiro, filho de Maria e irm\u00e3o de Tiago, Jos\u00e9, Judas e Sim\u00e3o? N\u00e3o est\u00e3o aqui conosco as suas irm\u00e3s?\u2019 <strong>E ficavam escandalizados por causa dele<\/strong>\u201d (Mc 6:2-3). Ao inv\u00e9s de funcionar como um elemento de convencimento da verdadeira identidade de Jesus como Filho de Deus, as pessoas o viam como uma farsa, apesar da incontest\u00e1vel manifesta\u00e7\u00e3o de sua autoridade.<\/p>\n<p>Testemunhar os milagres, ou ouvir a respeito deles n\u00e3o provocava uma f\u00e9 naqueles que eram contr\u00e1rios a Cristo. Essas a\u00e7\u00f5es de Cristo s\u00e3o apenas reconhecidas em sua realidade atrav\u00e9s do olhar da f\u00e9. Quando Jesus resolve curar o paral\u00edtico, o que Ele v\u00ea antes de mais nada \u00e9 uma <strong>atitude de f\u00e9<\/strong> dele e dos seus amigos (2:5). E \u00e9 exatamente aqui que encontramos o elemento liter\u00e1rio que unifica a mensagem de Marcos 4:35-6:6: a f\u00e9. Do in\u00edcio ao fim das hist\u00f3rias narradas nesse intervalo, foi a f\u00e9 o <em>fio teol\u00f3gico<\/em> que costura todas as hist\u00f3rias: Foi a f\u00e9 que faltou aos disc\u00edpulos em alto mar (4:4); foi f\u00e9 que o ex-endemoninhado manifestou quando curado (5:18); foi a f\u00e9 que Jairo teve que aprender a desenvolver (5:23; 36); foi a f\u00e9 movimentou a mulher an\u00f4nima em dire\u00e7\u00e3o \u00e0 Cristo (5:25-27; 33-34); e por fim, foi a f\u00e9 que n\u00e3o se encontrou em toda Nazar\u00e9 (6:6).<\/p>\n<p>Em outras palavras, <strong>a f\u00e9 que faltou aos disc\u00edpulos no mar, tamb\u00e9m n\u00e3o foi encontrada na cidade onde Jesus cresceu<\/strong>. Aqueles que aparentemente deveriam ter manifestado f\u00e9 em Cristo, s\u00e3o os que s\u00e3o encontrados faltosos nessas hist\u00f3rias. Por outro lado, <strong>s\u00e3o as personagens mais improv\u00e1veis que manifestam a f\u00e9 esperada dos verdadeiros disc\u00edpulos<\/strong>: um ex-endemoninhado gentio (5:1-5; 18), um importante l\u00edder religioso (5:22), algu\u00e9m que pertencia ao ambiente de oposi\u00e7\u00e3o a Jesus (3:1, 6; <em>cf.<\/em> 6:2, 3) e uma mulher cerimonialmente impura (5:25-26) que pertence \u00e0 multid\u00e3o (5:27). Ou seja, mais uma vez Marcos nos ensina que seguir a Cristo n\u00e3o tem nada a ver com proximidade, amizade, nem se quer la\u00e7os familiares. <strong>O que \u00e9 realmente necess\u00e1rio \u00e9 a f\u00e9!<\/strong><\/p>\n<p>Mas que tipo de f\u00e9 \u00e9 essa que Marcos nos ensina aqui? Eu acredito que existem algumas dicas deixadas pelo autor nessas hist\u00f3rias que podem nos ajudar a entender melhor o que ele nos ensina sobre a f\u00e9 verdadeira.<\/p>\n<h2>F\u00e9 como Confian\u00e7a<\/h2>\n<p>Nos nossos dias, uma das primeiras palavras que associamos ao conceito de f\u00e9 \u00e9 a palavra credo. Quando falamos sobre a defesa da f\u00e9, ou falamos sobre a f\u00e9 crist\u00e3, normalmente associamos esses conceitos \u00e0 um conjunto de cren\u00e7as que definem o cristianismo. E tal conceito n\u00e3o est\u00e1 errado (<em>cf.<\/em> Ef.4:5; 1Tim 4:1). Entretanto, tal conceito n\u00e3o aparece de modo expl\u00edcito no Evangelho de Marcos (<em>cf.<\/em> 1:1; 15:39). O que vemos, desde o in\u00edcio \u00e9 uma <em>atitude de confian\u00e7a<\/em> que Jesus tem poder para libertar pessoas em sofrimento de suas situa\u00e7\u00f5es de mis\u00e9ria. Esse conceito \u00e9 claramente visto na hist\u00f3ria do homem paral\u00edtico perdoado e curado por Cristo (2:1-12): existia a clara confian\u00e7a de que Jesus poderia salvar esse homem de sua situa\u00e7\u00e3o deplor\u00e1vel.<\/p>\n<p>E \u00e9 exatamente essa confian\u00e7a que Jesus n\u00e3o encontrou nos disc\u00edpulos durante a tempestade no mar (4:35-41): \u201cPor que voc\u00eas est\u00e3o com tanto medo? <strong>Ainda n\u00e3o tem f\u00e9<\/strong>?\u201d (4:40). Embora tivessem testemunhado a manifesta\u00e7\u00e3o do seu poder, os disc\u00edpulos ainda n\u00e3o tinham manifestado a mesma confian\u00e7a que o paral\u00edtico e seus amigos tinham depositado em Jesus.<\/p>\n<p>Al\u00edas, parece que \u00e9 exatamente essa a f\u00e9 que Jairo tem a respeito de Jesus: diante de uma situa\u00e7\u00e3o de profundo desespero, ele \u00e9 capaz de deixar para tr\u00e1s seus conceitos sobre quem Jesus \u00e9, seu orgulho e sua dignidade para pedir que Jesus cure sua filha. Marcos o descreve como o presidente da sinagoga (\u1f00\u03c1\u03c7\u03b9\u03c3\u03c5\u03bd\u1f71\u03b3\u03c9\u03b3\u03bf\u03c2, <em>archisunago\u0304gos; <\/em>5:22), algu\u00e9m que participava do grupo de oposi\u00e7\u00e3o de Jesus. Ele pertencia ao alto escal\u00e3o da religi\u00e3o judaica e dificilmente gostaria de ver seu nome associado ao de Jesus. Sendo um oficial da religi\u00e3o judaica, Jairo dificilmente se jogaria diante de outra pessoa ou seria visto suplicando por ajuda de algu\u00e9m como Jesus.<\/p>\n<p>Mas a situa\u00e7\u00e3o de poss\u00edvel morte de sua filha mudou todo o cen\u00e1rio. Talvez sua vis\u00e3o de Jesus n\u00e3o fosse das melhores, mas ele j\u00e1 tinha ouvido sobre suas curas. Talvez essa fosse sua \u00fanica chance de ver sua filha reestabelecida. E num momento de profundo desespero, ele abandona seus conceitos sobre Jesus, seu orgulho pessoal e sua dignidade e se lan\u00e7a aos p\u00e9s de Jesus. Naquele momento, Jesus \u00e9 sua \u00fanica esperan\u00e7a, \u00e9 o \u00fanico que o pode ajudar. O \u00fanico.<\/p>\n<p>\u00c9 nesse momento que Jairo manifesta sua confian\u00e7a no poder de Jesus: \u201cMinha filhinha est\u00e1 morrendo. Vem, por favor, e imp\u00f5e as m\u00e3os sobre ela, para que seja curada e viva\u201d (5:23). A express\u00e3o usada por Marcos aqui para descrever a expectativa de Jairo, isto \u00e9, que Jesus impusesse sua m\u00e3o sobre sua filha, era um claro sinal de sua confian\u00e7a que Jesus poderia cur\u00e1-la (<em>cf.<\/em> 6:5; 7:32; 8:23, 25). Tal confian\u00e7a \u00e9 vista de modo ainda mais claro quando observamos o fim da frase: para que seja curada e viva (\u1f35\u03bd\u03b1 \u03c3\u03c9\u03b8\u1fc7 \u03ba\u03b1\u1f76 \u03b6\u1f75\u03c3\u1fc3; hina s\u014dth\u0113 kai z\u0113s\u0113). Nesse momento, Jairo parece transparecer que confia plenamente no poder de Jesus: Se ele impor suas m\u00e3os ela ser\u00e1 curada. Essa \u00e9 a f\u00e9 que Jairo deposita em Jesus. Uma confian\u00e7a que persiste mesmo em meio \u00e0 dor e ao sofrimento, e se mostra verdadeira diante da morte (5:35-36). Diferente dos disc\u00edpulos que titubearam perante uma situa\u00e7\u00e3o de perigo, Jairo seguiu confiante no poder de Jesus. Para Marcos, Jairo manifesta uma f\u00e9 como confian\u00e7a.<\/p>\n<h2>F\u00e9 como Convic\u00e7\u00e3o<\/h2>\n<p>De modo similar, Marcos nos conta a hist\u00f3rias de uma mulher an\u00f4nima que certamente n\u00e3o pertencia ao alto escal\u00e3o da religi\u00e3o judaica. Ao contr\u00e1rio de Jairo, essa personagem era uma mulher, sem nome, sem dinheiro e sem contato social. Em fun\u00e7\u00e3o de sua enfermidade ela teria sido rotulada como cerimonialmente impura e teria sido socialmente ostracizada pelos seus conterr\u00e2neos.<\/p>\n<p>Entretanto, em sua situa\u00e7\u00e3o de profundo desespero (5:25-26), ela decide enfrentar a multid\u00e3o diante do perigo de ser descoberta, somente para poder tocar em Jesus (5:5:27). O que a moveu do ostracismos social para a presen\u00e7a de Jesus foi a convic\u00e7\u00e3o de que Ele poderia fazer alguma coisa por ela: \u201c<strong>Se eu t\u00e3o somente tocar em seu manto, ficarei curada<\/strong>\u201d (5:28). Essa mulher era movida por uma convic\u00e7\u00e3o inabal\u00e1vel: ela sabia que seria curada! E Marcos nos conta que foi exatamente isso que aconteceu: \u201c<strong>Imediatamente cessou sua hemorragia<\/strong> e ela sentiu em seu corpo que estava livre do seu sofrimento\u201d (5:29).<\/p>\n<p>Em uma cena marcada por suspense, Marcos nos conta que Jesus pergunta em alta voz sobre quem o havia tocado (5:30) em meio a uma multid\u00e3o que o comprimia (5:24). Sua pergunta pareceu t\u00e3o fora de lugar que at\u00e9 mesmo os disc\u00edpulos achavam que o Mestre n\u00e3o estava bem: \u201cV\u00eas a multid\u00e3o aglomerada ao teu redor e <strong>ainda perguntas<\/strong>: \u2018Quem tocou em mim?\u201d (5:31). Ao que parece, os disc\u00edpulos sem saber o que estava acontecendo, tratam de modo r\u00edspido nosso Senhor mais uma vez (<em>cf.<\/em> 4:38).<\/p>\n<p>A grande ironia dessa hist\u00f3rias \u00e9 que enquanto os disc\u00edpulos n\u00e3o sabem o que est\u00e1 acontecendo, a mulher sabe exatamente o que aconteceu: ela foi curada (5:29); Jesus sabia exatamente o que aconteceu: dele saiu poder (5:30); e o leitor sabe exatamente o que aconteceu: Deus curou uma mulher de seu sofrimento por meio do Seu poder que operava em Cristo, em um movimento de resoluta f\u00e9 que a mulher deposita sobre Jesus. \u00c9 somente dessa perspectiva liter\u00e1ria que conseguimos entender o incomodo dos disc\u00edpulos com a pergunta de Jesus: eles n\u00e3o sabem o que est\u00e1 acontecendo.<\/p>\n<p>Mas, embora Jesus soubesse exatamente o que tinha acabado de acontecer, ele precisava encontrar a pessoa que o tinha tocado (5:32). E cheia de medo, a mulher coloca-se diante de Jesus prostrando-se publicamente diante dele e contou <em>toda a verdade<\/em> (5:33). Diante de uma multid\u00e3o que buscava a Cristo, provavelmente pela mesma raz\u00e3o que ela, essa mulher an\u00f4nima testemunha sobre o milagre que se operou nela. E para isso, teve que contar a respeito do seu sofrimento e enfermidade. Ele teve que declarar publicamente a respeito de sua convic\u00e7\u00e3o a respeito do que Cristo poderia fazer por ela em meio a uma situa\u00e7\u00e3o de profundo desespero. Ela teve que declarar <em>toda a verdade<\/em>.<\/p>\n<p>E ao fazer isso, ela provavelmente verbalizou sobre sua cren\u00e7a de que o <em>tocar<\/em> em Cristo seria suficiente para ser curada (5:28). Mas, em meio a uma multid\u00e3o que n\u00e3o apenas o tocava, mas o comprimia (5:24; 31), Jesus pode corrigir a convic\u00e7\u00e3o dessa mulher: N\u00e3o era o toque, era a f\u00e9 que a levou \u00e0 cura: \u201c<strong>Filha, a sua f\u00e9 a curou!<\/strong> V\u00e1 em paz e fique livre do seu sofrimento\u201d (5:34). Tocar, uma multid\u00e3o tinha tocado em Jesus, mas somente ela foi curada. A f\u00e9 foi o diferencial. E ela estava convencida de que Jesus a curaria. E movida por f\u00e9 ela viu o Senhor a salvar de sua situa\u00e7\u00e3o miser\u00e1vel.<\/p>\n<h2>F\u00e9 como Aceita\u00e7\u00e3o<\/h2>\n<p>Por fim, a \u00faltima hist\u00f3rias de Marcos nessa per\u00edcope aponta para mais um elemento que descreve a f\u00e9 de sua perspectiva. Jesus volta para sua cidade (6:1) e no s\u00e1bado volta a ensinar na sinagoga (6:2), um ambiente que at\u00e9 aqui tem se mostrado hostil ao nosso Senhor (<em>cf.<\/em> 2:1-12; 3:1-6). Mas, quem sabe agora que a not\u00edcia da cura da filha de um importante membro da sinagoga (5:22) possa mudar esse cen\u00e1rio de oposi\u00e7\u00e3o.<\/p>\n<p>Infelizmente esse n\u00e3o era o caso. Embora ensinasse com autoridade (1:22), Jesus n\u00e3o tinha as credenciais necess\u00e1rias para tal. Al\u00e9m disso, sua <em>fama<\/em> nem sempre se espalhava de maneira positiva (1:45; 3:7-10; 33:22, 30; 4:14-17). Em outras palavras, \u00e9 bem poss\u00edvel que as not\u00edcias a respeito de Jesus fossem marcadas por um <em>misto<\/em> de elogios e cr\u00edticas de tal forma que a recep\u00e7\u00e3o de Jesus em sua pr\u00f3pria cidade experimentasse um r\u00e1pido momento de maravilhamento seguido de profunda rejei\u00e7\u00e3o: \u201c\u2019De onde lhe vem estas coisas?\u2019, perguntavam eles. \u2018Que sabedoria \u00e9 esta que lhe foi dada? E estes milagres que Ele faz? <strong>N\u00e3o \u00e9 este o carpinteiro, filho de Maria<\/strong> e irm\u00e3o de Tiago, Jos\u00e9, Judas e Sim\u00e3o? N\u00e3o est\u00e3o aqui conosco as suas irm\u00e3s?\u2019 <strong>E ficavam escandalizados por causa dele<\/strong>\u201d (6:2-3).<\/p>\n<p>Conhecendo melhor sua origem familiar, as pessoas de Nazar\u00e9 foram incapazes de aceitar sua filia\u00e7\u00e3o divina (<em>cf.<\/em> 1:1). Esse homem era apenas um carpinteiro, o filho de Maria. Mesmo que tivessem recebido o testemunho a respeito de seus milagres e tivessem ouvido o seu ensino a ponto de reconhecer sua sabedoria (6:2), eles n\u00e3o podiam aceitar a verdadeira identidade de Cristo. Ao que parece, o semeador havia lan\u00e7ado sua semente, e \u201cvisto que n\u00e3o tem raiz em si mesmas, permanecem por pouco tempo. Quando surge alguma tribula\u00e7\u00e3o ou persegui\u00e7\u00e3o por causa da palavra, <strong>logo se escandalizam<\/strong>\u201d (4:17).<\/p>\n<p>Se associar com Jesus significaria se indispor com as autoridades judaica (2:1-3:6, 22, 30). Se associar com Jesus significa sofrer persegui\u00e7\u00e3o, e ainda que existisse em Jesus suficiente evid\u00eancia para o maravilhamento das multid\u00f5es (6:2; <em>cf. <\/em>1:22, 27, 28, 33-34, 45; 2:12; 4:31; 5:42), existia tamb\u00e9m suficiente sugest\u00e3o de que talvez ele fosse apenas um carpinteiro iletrado (6:3), movido pelo poder de Satan\u00e1s (3:22, 30; 5:14-17), algu\u00e9m que era blasfemo (2:7), sem respeito pelos costumes religiosos (2:15), que n\u00e3o observa as leis da santidade do juda\u00edsmo (2:18), que viola o s\u00e1bado (2:24) e que da perspectiva das autoridades judaicas, deveria morrer (3:6). E diante de tal testemunho divido, as pessoas da sinagoga de Nazar\u00e9 n\u00e3o aceitou a verdadeira identidade de Jesus, e encontrou nele um objeto de trope\u00e7o. Era como se dissessem: \u201c<em>\u00c9 imposs\u00edvel que algu\u00e9m t\u00e3o simples quanto esse carpinteiro seja t\u00e3o grande quanto suas obras.<\/em>\u201d E por isso, em Jesus viam apenas o filho de Maria, e n\u00e3o o Filho de Deus.<\/p>\n<p>N\u00e3o \u00e9 \u00e0 toa que Marcos descreve esse cen\u00e1rio como marcado por falta de f\u00e9: \u201cE ficou admirado com a <strong>incredulidade deles<\/strong>\u201d (6:6). E mais interessante, Marcos tamb\u00e9m nos conta que diante dessa incredulidade, Jesus n\u00e3o realizou em Nazar\u00e9 quase nenhum milagre: \u201c<strong>E n\u00e3o p\u00f4de fazer ali nenhum milagre<\/strong>, exceto impor as m\u00e3os sobre alguns doentes e cur\u00e1-los\u201d (6:5). Diante de um ambiente hostil, Jesus nega-se a manifestar sua autoridade! E isso veremos com ainda clareza em sua crucifica\u00e7\u00e3o. Mas, por ora, Marcos nos ensina que diante da falta de f\u00e9 das pessoas, Jesus n\u00e3o manifesta sua autoridade. E tal aparente <em>impossibilidade<\/em> de realizar milagres em Nazar\u00e9 (6:5), n\u00e3o deve ser entendida como <em>incapacidade<\/em> do Mestre, como se estivesse com as m\u00e3os atadas diante da incredulidade das pessoas. Trata-se apenas de <em>indisposi\u00e7\u00e3o<\/em> (<em>cf. <\/em>Mt 13:58) em manifestar sua autoridade diante de um ambiente que os usar\u00e1 como evid\u00eancia de seu \u201ccharlatanismo.\u201d<\/p>\n<p>Diante dessas hist\u00f3rias, Marcos parece nos ensinar que f\u00e9 n\u00e3o \u00e9 apenas afirmar um conjunto de conceitos teol\u00f3gicos; \u00e9 antes de mais nada uma atitude de confiar em Cristo em meio \u00e0s tempestades da vida, como n\u00e3o fizeram os disc\u00edpulos (4:40); \u00e9 uma atitude confiante de que apenas Jesus Cristo pode resolver nossa situa\u00e7\u00e3o de mis\u00e9ria, como fez Jairo (5:23, 36); \u00e9 uma atitude convicta de que apenas Jesus pode nos salvar do nosso sofrimento, como fez a mulher an\u00f4nima (5:28, 34); \u00e9 uma atitude de aceitar quem Jesus Cristo \u00e9, pelo o que Ele ensina e faz, como as pessoas da sinagoga de Nazar\u00e9 n\u00e3o fizeram (6:6).<\/p>\n<p>E mais interessante, ao contr\u00e1rio da opini\u00e3o popular, a f\u00e9 nem sempre acontece depois do milagre (<em>cf.<\/em> 1:30; 3:5), como se Jesus fizesse milagres para que as pessoas pudessem crer (<em>cf.<\/em> 6:5), mas muitas vezes \u00e9 o milagre que segue a f\u00e9: a cura do leproso foi antecedida por uma declara\u00e7\u00e3o de confian\u00e7a no poder de Cristo (1:40); a cura do paral\u00edtico aconteceu depois que Cristo viu sua f\u00e9 e a dos seus amigos (2:5); a cura da mulher seguiu sua firme convic\u00e7\u00e3o de que Jesus poderia cur\u00e1-la (5:28); e mais impressionante, a cura da filha de Jairo aconteceu apenas depois que seu pai manifestou f\u00e9 em Cristo (5:23; 36).<\/p>\n<p>A pergunta que fica para n\u00f3s, ent\u00e3o \u00e9: Que tipo de f\u00e9 voc\u00ea tem manifestado em Cristo? Sua f\u00e9 \u00e9 resoluta como a de Jairo? Convicta como a da mulher an\u00f4nima? Ou voc\u00ea se parece com as pessoas da cidade de Nazar\u00e9, que diante da persegui\u00e7\u00e3o se acovarda? Que diante do medo da oposi\u00e7\u00e3o, prefere o abandonar? Que tipo de compromisso voc\u00ea tem assumido com Cristo? Se for apenas um compromisso intelectual de recitar alguns conceitos sobre Ele, entenda que isso \u00e9 muito bom, mas insuficiente para segu\u00ed-lo. N\u00f3s precisamos aprender a confiar desesperadamente Nele em meio \u00e0 nossa Jornada com Ele. Que Jairo e essa mulher an\u00f4nima modelem essa atitude para n\u00f3s.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Marcelo Berti. \u00a9 Voltemos ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\/\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer.\">Caminhar \u00e9 crer<\/a>.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Milagres n\u00e3o aumentam a possibilidade de uma resposta positiva de f\u00e9 daqueles que os testemunham<\/p>\n","protected":false},"author":631,"featured_media":53332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[409],"tags":[2506,2499,2090],"class_list":["post-53327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-crista","tag-exegese-publica","tag-seguindo-a-jesus","tag-teobrasil","tema-discipulado","tema-discipulado-dup-2","tema-vida-crista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caminhar \u00e9 crer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caminhar \u00e9 crer\" \/>\n<meta property=\"og:description\" content=\"Milagres n\u00e3o aumentam a possibilidade de uma resposta positiva de f\u00e9 daqueles que os testemunham\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T22:28:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-15T22:38:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/caminhar-e\u0301-crer.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Berti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Berti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/\"},\"author\":{\"name\":\"Marcelo Berti\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/d4b9fa6c01a54ad00a057885af0be3df\"},\"headline\":\"Caminhar \u00e9 crer\",\"datePublished\":\"2020-04-15T22:28:55+00:00\",\"dateModified\":\"2020-04-15T22:38:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/\"},\"wordCount\":3486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1\",\"keywords\":[\"Exegese P\u00fablica\",\"Seguindo a Jesus\",\"TeoBrasil\"],\"articleSection\":[\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/\",\"name\":\"Caminhar \u00e9 crer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2020-04-15T22:28:55+00:00\",\"dateModified\":\"2020-04-15T22:38:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/caminhar-e-crer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caminhar \u00e9 crer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/d4b9fa6c01a54ad00a057885af0be3df\",\"name\":\"Marcelo Berti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46d5d9f0f0e6147629a849e14a244842cde24fbb5f9075127f7c16480a62accb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46d5d9f0f0e6147629a849e14a244842cde24fbb5f9075127f7c16480a62accb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46d5d9f0f0e6147629a849e14a244842cde24fbb5f9075127f7c16480a62accb?s=96&d=mm&r=g\",\"caption\":\"Marcelo Berti\"},\"description\":\"Marcelo Berti \u00e9 Bacharel em Miss\u00f5es pelo Semin\u00e1rio B\u00edblico Palavra da Vida e Mestre em Teologia pelo Dallas Theological Seminary. \u00c9 editor do Teologando e atualmente est\u00e1 iniciando um processo de planta\u00e7\u00e3o da Igreja Batista Fonte SP na cidade de S\u00e3o Paulo. Berti \u00e9 casado com a Gabriela Sachi e pai do Nathan e da Melissa.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/marcelo-berti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caminhar \u00e9 crer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/","og_locale":"pt_BR","og_type":"article","og_title":"Caminhar \u00e9 crer","og_description":"Milagres n\u00e3o aumentam a possibilidade de uma resposta positiva de f\u00e9 daqueles que os testemunham","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-04-15T22:28:55+00:00","article_modified_time":"2020-04-15T22:38:19+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/caminhar-e\u0301-crer.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Marcelo Berti","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Marcelo Berti","Est. tempo de leitura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/"},"author":{"name":"Marcelo Berti","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/d4b9fa6c01a54ad00a057885af0be3df"},"headline":"Caminhar \u00e9 crer","datePublished":"2020-04-15T22:28:55+00:00","dateModified":"2020-04-15T22:38:19+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/"},"wordCount":3486,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1","keywords":["Exegese P\u00fablica","Seguindo a Jesus","TeoBrasil"],"articleSection":["Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/","name":"Caminhar \u00e9 crer","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1","datePublished":"2020-04-15T22:28:55+00:00","dateModified":"2020-04-15T22:38:19+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/caminhar-e-crer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Caminhar \u00e9 crer"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/d4b9fa6c01a54ad00a057885af0be3df","name":"Marcelo Berti","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/46d5d9f0f0e6147629a849e14a244842cde24fbb5f9075127f7c16480a62accb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/46d5d9f0f0e6147629a849e14a244842cde24fbb5f9075127f7c16480a62accb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/46d5d9f0f0e6147629a849e14a244842cde24fbb5f9075127f7c16480a62accb?s=96&d=mm&r=g","caption":"Marcelo Berti"},"description":"Marcelo Berti \u00e9 Bacharel em Miss\u00f5es pelo Semin\u00e1rio B\u00edblico Palavra da Vida e Mestre em Teologia pelo Dallas Theological Seminary. \u00c9 editor do Teologando e atualmente est\u00e1 iniciando um processo de planta\u00e7\u00e3o da Igreja Batista Fonte SP na cidade de S\u00e3o Paulo. Berti \u00e9 casado com a Gabriela Sachi e pai do Nathan e da Melissa.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/marcelo-berti\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/caminhar-e%CC%81-crer.jpg?fit=856%2C394&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-dS7","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/53327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/631"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=53327"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/53327\/revisions"}],"predecessor-version":[{"id":53334,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/53327\/revisions\/53334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/53332"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=53327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=53327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=53327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}