{"id":53467,"date":"2020-04-28T17:04:47","date_gmt":"2020-04-28T20:04:47","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=53467"},"modified":"2020-04-28T20:07:44","modified_gmt":"2020-04-28T23:07:44","slug":"salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/","title":{"rendered":"Salvo pela &#8216;lealdade&#8217; somente? Sobre uma nova tentativa de revisar a reforma"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p id=\"88fb\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Este ano marca o 500\u00ba anivers\u00e1rio da afixa\u00e7\u00e3o das Noventa e Cinco Teses de Martinho Lutero na cidade de Wittenberg. Uma pergunta que surge \u00e9 se os Cinco Solas \u2014 que corretamente captura algumas das maiores \u00eanfases da Reforma \u2014 deveriam ser matizados ap\u00f3s 500 anos de reflex\u00e3o e estudo.<\/p>\n<p id=\"ccc5\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Matthew Bates, um jovem estudioso e talentoso que ensina na Quincy University, acredita que um ajustamento seria saud\u00e1vel, sugerindo que revisemos \u201cf\u00e9 somente\u201d e reformul\u00e1ssemos com o slogan \u201clealdade somente\u201d. Como aqueles que creem na Escritura somente, dever\u00edamos estar abertos para reformar e reformular o que nos sustentamos no passado, em Bates nos desafia a olhar para B\u00edblia novamente<\/p>\n<h2 id=\"cb80\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\"><strong class=\"gv hn\">Lealdade e o Evangelho<\/strong><\/h2>\n<p id=\"07da\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Em seu livro, <em class=\"hx\">Salvation by Allegiance Alone: Rethinking Faith, Works, and the Gospel of Jesus the King<\/em> (Salva\u00e7\u00e3o por Lealdade Somente: Repensando F\u00e9, Obras e o Evangelho de Jesus o Rei \u2014 em tradu\u00e7\u00e3o livre), Bates considera novamente a natureza da salva\u00e7\u00e3o e do evangelho. Ele argumenta que \u201cf\u00e9\u201d e \u201ccren\u00e7a\u201d nem sempre s\u00e3o os melhores termos para traduzir \u201cpiste\u201d e \u201cpisteuo\u201d no Novo Testamento. Em vez disso, quando se trata de salva\u00e7\u00e3o, seria melhor falar em <em>lealdade<\/em> a Jesus como Rei. Assim, essa f\u00e9 tem a ideia de <em>fidelidade<\/em>. A vantagem de lealdade \u00e9 que ela inclui a ideia de que as boas obras s\u00e3o necess\u00e1rias para a salva\u00e7\u00e3o final. Bates corretamente mant\u00e9m que a f\u00e9 n\u00e3o pode ser definida como um simples assentimento intelectual, um salto no escuro, ou um pensamento positivo.<\/p>\n<p id=\"047b\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">A no\u00e7\u00e3o de que f\u00e9 \u00e9 melhor traduzido por \u201clealdade\u201d \u00e9 apoiada, segundo Bates, quando se olha as evid\u00eancias na literatura judaica do Segundo Templo. Ent\u00e3o, ele argumenta em favor desse significado nos textos paulinos principais, dizendo que as no\u00e7\u00f5es de assentimento mental, \u201clealdade professada\u201d e \u201clealdade encarnada\u201d representam melhor o que se entende por salva\u00e7\u00e3o ou justifica\u00e7\u00e3o pela <em class=\"hx\">pistis<\/em>. Portanto, Paulo ensina \u201clealdade encarnada\u201d a Jesus com Rei. Bates prefers \u201clealdade\u201d \u00e0 \u201cconfian\u00e7a\u201d uma vez que ele pensa que essa \u00faltima n\u00e3o captura suficientemente a lealdade a Jesus como Rei entronizado. Segundo Bates, seremos julgados no \u00faltimo dia sobre se fomos ou n\u00e3o genuinamente leais Jesus, n\u00e3o se mantivemos uma lista detalhada de mandamentos.<\/p>\n<p id=\"6003\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Segundo Bates argumenta, o evangelho n\u00e3o pode ser reduzido \u00e0 f\u00f3rmula \u201cJesus morreu por nossos pecados\u201d, j\u00e1 que o centro do evangelho \u00e9 a verdade de que Jesus \u00e9 Rei. Ele \u00e9 o Senhor ressuscitado e entronizado acima de tudo, e somos chamados a expressar nossa lealdade a ele como nosso Senhor. De acordo com Bates, existem oito elementos no Evangelho:<\/p>\n<p id=\"bad0\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">1. Jesus preexistiu com o Pai;<\/p>\n<p id=\"c77d\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">2. Ele encarnou e cumpriu a promessa de Davi;<\/p>\n<p id=\"69f0\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">3. Ele morreu por nossos pecados segundo as Escrituras;<\/p>\n<p id=\"1ec7\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">4. Ele foi sepultado;<\/p>\n<p id=\"1c58\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">5. Ele ressuscitou ao terceiro dia segundo as Escrituras;<\/p>\n<p id=\"3d17\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">6. Ele apareceu a muito, mostrando que ressuscitara dentre os mortos<\/p>\n<p id=\"c10a\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Particularmente, Bates enfatiza que Jesus est\u00e1 entronizado como Rei e Messias sobre todo o mundo.<\/p>\n<h2 id=\"40d7\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\"><strong class=\"gv hn\">Salva\u00e7\u00e3o como um dom e a Nova Cria\u00e7\u00e3o<\/strong><\/h2>\n<p id=\"76aa\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Bates enfatiza que n\u00e3o podemos ganhar a salva\u00e7\u00e3o. Ela \u00e9 um dom de Deus. Ao mesmo tempo, todavia, ele rejeita a elei\u00e7\u00e3o individual e afirma que a elei\u00e7\u00e3o corporativa captura o testemunho com mais precis\u00e3o. Em todo caso, a gra\u00e7a \u00e9 efetiva e transforma nossas vidas. Embora os protestantes frequentemente digam que nossas obras s\u00e3o a evid\u00eancia e frutos necess\u00e1rios de nossa f\u00e9, \u00e9 melhor, diz Bates, falar de lealdade a Jesus como rei entronizado e reinando e, assim, as obras s\u00e3o \u201cessenciais para a salva\u00e7\u00e3o final\u201d (p. 110).<\/p>\n<p id=\"05e2\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Bates discorda da no\u00e7\u00e3o de que os crist\u00e3os simplesmente v\u00e3o para o c\u00e9u ap\u00f3s a morte. A imagem do Novo Testamento tem mais vigor e for\u00e7a que a concep\u00e7\u00e3o popular de c\u00e9u. Os crentes ser\u00e3o levantados dentre os mortos e viver\u00e3o como cidad\u00e3os na nova cria\u00e7\u00e3o. N\u00f3s aguardamos um universo transformado e esperamos reinar com o Rei Jesus para cumprir o prop\u00f3sito para o qual Deus originalmente criou os seres humanos. N\u00f3s n\u00e3o seremos criaturas et\u00e9reas flutuando nas nuvens, mas pessoas com corpos transformados e imortais residindo em um novo universo.<\/p>\n<p id=\"9110\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Bates v\u00ea corretamente como a entroniza\u00e7\u00e3o com Rei antecipando o novo universo onde reinaremos com ele e submisso a ele. Bates tamb\u00e9m sugere que toda verdade e bem que temos feito nesse mundo ser\u00e1 preservado na nova cria\u00e7\u00e3o vindoura. Como aqueles criados \u00e0 imagem de Deus, mesmo agora temos prop\u00f3sito em nossa vida. Se seguirmos o caminho da idolatria \u2014 se deixarmos de viver do modo que fomos designados como feitos \u00e0 imagem de Deus \u2014 desfiguraremos o mundo e causaremos danos a outros seres humanos. Jesus \u00e9 completa imagem de Deus, e seremos conformados \u00e0 sua imagem que haja alguma descontinuidade entre n\u00f3s como seres humanos, desde que Jesus \u00e9 o rei exaltado e entronizado.<\/p>\n<h2 id=\"3d94\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\"><strong class=\"gv hn\">Justifica\u00e7\u00e3o<\/strong><\/h2>\n<p id=\"5556\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Quando se trata da justifica\u00e7\u00e3o, Bates a fundamenta na vindica\u00e7\u00e3o de Jesus. Jesus foi condenado como um messi\u00e2nico escolhido, e sua morte na cruz significa para os l\u00edderes religiosos judeus que ele foi amaldi\u00e7oado por Deus. No entanto, Deus reverteu o julgamento daqueles que condenaram Jesus e demonstrou sua vindica\u00e7\u00e3o (justifica\u00e7\u00e3o) ao ressuscit\u00e1-lo de entre os mortos. Os crist\u00e3os s\u00e3o tamb\u00e9m justificados (justos com Deus) quando eles s\u00e3o incorporados em Cristo. Aqueles que pertencem a Cristo atrav\u00e9s da uni\u00e3o com ele s\u00e3o declarados estar justos com Deus, por causa da vindica\u00e7\u00e3o de Jesus \u00e9 que eles tamb\u00e9m s\u00e3o.<\/p>\n<p id=\"f50b\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Bates tamb\u00e9m questiona a ordem da salva\u00e7\u00e3o (<em class=\"hx\">ordo salutis<\/em>), assunto comum nos c\u00edrculos reformados, questionando que ela \u00e9 mais devedora da teologia sistem\u00e1tica do que da teologia b\u00edblica. Ele defende a imputa\u00e7\u00e3o no sentido de que os crentes est\u00e3o unidos com Cristo como nosso Rei entronizado. Embora Bates concorde com a imputa\u00e7\u00e3o, ele tamb\u00e9m sugere que a imputa\u00e7\u00e3o pode ser perdida, assim, alguns daqueles que s\u00e3o agora justificados, segundo Bates, pode realmente perder a condi\u00e7\u00e3o de justificado e acabar sofrendo a condena\u00e7\u00e3o eterna. Ele diz que a justifica\u00e7\u00e3o \u00e9 forense, mas tamb\u00e9m diz que a justi\u00e7a \u00e9 infundida (embora a infus\u00e3o n\u00e3o seja gradual, mas instant\u00e2nea ap\u00f3s a declara\u00e7\u00e3o de lealdade).<\/p>\n<h2 id=\"29f2\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\"><strong class=\"gv hn\">Mantendo os Antigos Caminhos<\/strong><\/h2>\n<p id=\"8445\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\"><em class=\"hx\">Salvation by Allegiance<\/em>\u00a0<em class=\"hx\">Alone<\/em> \u00e9 cheio de informa\u00e7\u00f5es \u00fateis, e falta espa\u00e7o para interagir com todos os escritos de Bates. Sua \u00eanfase sobre a submiss\u00e3o a Jesus como Rei, o entronizado Senhor do universo, capta bem a \u00eanfase do Novo Testamento sobre o que significa ser um crist\u00e3o. Ele tamb\u00e9m nos relembra que nossas vidas interessam nesse mundo, e que a idolatria n\u00e3o \u00e9 uma abstra\u00e7\u00e3o, mas aparece no modo como vivemos nossas vidas. N\u00f3s n\u00e3o somos criaturas incorp\u00f3reas; somos criaturas de carne e sangue que antecipam a vida na nova cria\u00e7\u00e3o. Bates tamb\u00e9m diz, com raz\u00e3o, que o evangelho \u00e9 mais amplo do que simplesmente \u201creceber Jesus como Salvador\u201d, e ele enfatiza a gra\u00e7a de Deus em nos salvar. Eu tamb\u00e9m simpatizo com sua \u00eanfase sobre lealdade; muitos protestantes reduzem a f\u00e9 a simples acordo verbal. Muitos est\u00e3o equivocadamente seguros de que gozar\u00e3o da vida eterna sem qualquer obedi\u00eancia se eles aceitarem Jesus como Salvador. Bates, de modo convincente, demonstra que tal leitura n\u00e3o est\u00e1 de acordo com a \u00eanfase do Novo Testamento sobre as obras, pois as obras s\u00e3o claramente essenciais para recebimento da vida eterna. Devemos manter nossa f\u00e9 at\u00e9 o fim para sermos salvos.<\/p>\n<p id=\"55e3\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Apesar das vantagens da palavra \u201clealdade\u201d, contudo, ainda acredito que \u201cconfian\u00e7a\u201d ou \u201cf\u00e9\u201d \u00e9 muito melhor, j\u00e1 que \u201clealdade\u201d coloca a \u00eanfase diretamente o agente humano \u2014 sobre o que fazemos, sobre nosso compromisso. \u201cLealdade\u201d capta a import\u00e2ncia das boas obras subsequentes, mas tamb\u00e9m deixa algo de fora, pois a f\u00e9 \u00e9 fundamentalmente receptiva. Recebemos o dom da justi\u00e7a com as m\u00e3os vazias, e essa concep\u00e7\u00e3o est\u00e1 ausente quando colocamos \u201clealdade\u201d no lugar da \u201cf\u00e9\u201d. Da mesma fora, a no\u00e7\u00e3o de que a verdadeira f\u00e9 ou confian\u00e7a inevitavelmente conduz \u00e0s boas obras \u00e9 tratada de uma maneira adequada com o testemunho do Novo Testamento.<\/p>\n<p id=\"592a\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Eu tamb\u00e9m argumentaria que Bates erroneamente separa a elei\u00e7\u00e3o corporativa da elei\u00e7\u00e3o individual. A tentativa de criar um lugar para a elei\u00e7\u00e3o corporativa al\u00e9m da elei\u00e7\u00e3o individual,\u00a0<a class=\"cu dw hy hz ia ib\" href=\"https:\/\/amzn.to\/2Shn3bB\" target=\"_blank\" rel=\"noopener nofollow noreferrer\">com argumentei em outro lugar<\/a>, \u00e9 logicamente falha e sem fundamentos b\u00edblicos. Bates diz que nem um \u00fanico vers\u00edculo apoia a elei\u00e7\u00e3o individual. Essa afirma\u00e7\u00e3o \u00e9 surpreendente, especialmente quando consideramos conceitos e n\u00e3o palavras. Eu indicaria Jo\u00e3o 6.35\u201344 como um exemplo claro. E, apesar de Bates dizer [o contr\u00e1rio], Romanos 9.6\u201323 \u2014 com suas muitas formas singulares e contextos soteriol\u00f3gicos \u2014 tamb\u00e9m apoia a elei\u00e7\u00e3o individual. Certamente que a elei\u00e7\u00e3o corporativa tem um longo legado nos c\u00edrculos evang\u00e9licos, mas todas as autoridades reformadas creem na elei\u00e7\u00e3o individual.<\/p>\n<p id=\"fc75\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Al\u00e9m disso, julgo que a no\u00e7\u00e3o de uma\u00a0<em class=\"hx\">ordo<\/em>\u00a0<em class=\"hx\">salutis<\/em> tem mais m\u00e9rito do que Bates afirma (veja Romanos 8.29,30). Corretamente ele nos lembra que precisamos fundamentar nossa perspectiva na Escritura, embora bem aqui eu sugeriria o t\u00edpico entendimento reformado. Em termos de justifica\u00e7\u00e3o, eu n\u00e3o creio que Bates ofere\u00e7a a clareza que precisamos. De acordo com ele, justifica\u00e7\u00e3o \u00e9 forense e transformativa, incluindo imputa\u00e7\u00e3o e infus\u00e3o, e a justi\u00e7a que temos pode acabar se perdendo. Aprecio profundamente a afirma\u00e7\u00e3o de Bates de que precisamos viver vidas transformadas como disc\u00edpulos do Rei Jesus, mas a sua perspectiva de justifica\u00e7\u00e3o e obras unidas afasta-se do testemunho da Escritura. Apesar de muitas ideias excelentes no livro, o velho caminho \u00e9 mais claro e, creio, biblicamente justificado.<\/p>\n<h2 id=\"492f\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\"><strong class=\"gv hn\">F\u00e9 somente e os Cinco Solas<\/strong><\/h2>\n<p id=\"86b5\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Embora a verdade de que somos justificados pela f\u00e9 somente n\u00e3o possa ser defendida aqui em detalhes, talvez ajudar\u00e1 refletir acerca de um ou dois textos e algumas implica\u00e7\u00f5es teol\u00f3gicas. Considere, por exemplo, Ef\u00e9sios 2.8\u201310, que apreende a famosa Soteriologia de Paulo e onde claramente ensina que somos salvos pela gra\u00e7a por meio da f\u00e9. Eu sugeriria que \u201cf\u00e9\u201d apreende mais adequadamente o significado de \u201c<em class=\"hx\">pistis<\/em>\u201d (que Paulo usa) que \u201clealdade\u201d, porque \u201cf\u00e9\u201d \u00e9 oposta a \u201cobras\u201d no texto. As obras s\u00e3o exclu\u00eddas porque, se a salva\u00e7\u00e3o vem por meio delas, estar\u00edamos propensos a nos gloriar. Vemos aqui um contraste entre agir e descansar. Assim, o termo \u201clealdade\u201d n\u00e3o funciona t\u00e3o bem porque, novamente, ele coloca a \u00eanfase no compromisso humano, enquanto \u201cf\u00e9\u201d transmite confian\u00e7a no que Deus tem feito por n\u00f3s em Jesus Cristo.<\/p>\n<p id=\"3054\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Mas a no\u00e7\u00e3o de confiar e receber anula a import\u00e2ncia das boas obras, as quais Bates t\u00e3o prestativamente enfatiza? Como Paulo diz, certamente que n\u00e3o! Ef\u00e9sios 2.10 mostra as boas obras que os crentes far\u00e3o. Tais obras n\u00e3o nos qualificam para salva\u00e7\u00e3o, mas s\u00e3o frutos de sermos uma criatura em Cristo Jesus. As m\u00e3os vazias com as quais recebemos Jesus como Senhor e Salvador n\u00e3o permanecem vazias. Em virtude de estarmos em Cristo, somos capacitados a viver uma nova vida que agrada a Deus. A genu\u00edna confian\u00e7a em Deus \u2014 f\u00e9 salvadora em Cristo \u2014 inevitavelmente conduz \u00e0 nova vida manifestando o fruto do Esp\u00edrito.<\/p>\n<p id=\"094a\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">A hist\u00f3ria da mulher pecadora em Lucas 7.36\u201350 ilustra a mesma verdade. N\u00e3o sabemos exatamente qual era o seu pecado, mas ele era p\u00fablico e, provavelmente sexual. Ela demonstra seu amor por Jesus chorando aos seus p\u00e9s, enxugando-os com seus cabelos, e derramando perfume. Jesus proclama que seus pecados est\u00e3o perdoados (Lucas 7.47), e a hist\u00f3ria termina com as seguintes palavras: \u201ctua f\u00e9 te salvou; v\u00e1 em paz\u201d (Lucas 7.50). Novamente, penso que a palavra \u201cf\u00e9\u201d \u00e9 melhor que \u201clealdade\u201d. Sim, ela foi dedicada a Jesus como seu Rei. Ainda assim, o ponto principal da hist\u00f3ria \u00e9 que ela confiou em Jesus para perd\u00e3o de seus pecados. Ela veio a ele com as m\u00e3os vazias, e o amor e devo\u00e7\u00e3o que se seguiram dela foram um resultado do perd\u00e3o que ela havia recebido.<\/p>\n<p id=\"5e2b\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Somente a f\u00e9, como vimos em Ef\u00e9sios 2, real\u00e7a a gra\u00e7a somente. A gra\u00e7a e bondade de Deus nos salva por meio da obra expiat\u00f3ria de Jesus como nosso Senhor crucificado e ressurreto. Mas, como nossa f\u00e9 nos salva? N\u00e3o somos salvos por nossa f\u00e9\u00a0<em class=\"hx\">per si<\/em>. A f\u00e9 nos salva por causa de seu objeto \u2014 porque por meio da f\u00e9 estamos unidos a Jesus Cristo, e sua justi\u00e7a torna-se nossa.<\/p>\n<p id=\"9bb1\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">Em outras palavras, a f\u00e9 somente implica Cristo somente! E se, pela gra\u00e7a, as m\u00e3os da f\u00e9 recebem Cristo para justi\u00e7a, ent\u00e3o toda a gl\u00f3ria \u00e9 dada a Deus pela salva\u00e7\u00e3o. Somos salvos pela gra\u00e7a somente por meio da f\u00e9 somente com base na obra de Cristo somente para gl\u00f3ria de Deus somente. E, claro, derivamos essas verdades das Escrituras somente.<\/p>\n<p id=\"b6da\" class=\"gt hh ap by gv b gw gx hi gy gz hj ha hb hk hc hd hl he hf hm hg fv\" data-selectable-paragraph=\"\">O termo \u201clealdade\u201d, portanto, embora \u00fatil em alguns aspectos, coloca o \u00eanfase no lugar errado e, assim, eu creio que \u201csomente a f\u00e9\u201d passa no teste do tempo em representar fielmente o ensinamento das Escrituras.<\/p>\n<p>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Thomas Schreiner. \u00a9 The Gospel Coalition. Website: <a href=\"https:\/\/www.thegospelcoalition.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">thegospelcoalition.org<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/www.thegospelcoalition.org\/reviews\/salvation-by-allegiance-alone\/\">Salvo pela \u201clealdade\u201d somente? Sobre uma nova tentativa de revisar a reforma<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/\">Salvo pela &#8216;lealdade&#8217; somente? Sobre uma nova tentativa de revisar a reforma<\/a>. \u00a9 Minist\u00e9rio Fiel. Website:\u00a0<a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">MinisterioFiel.com.br<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Gaspar de Souza. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Somos salvos pela gra\u00e7a somente por meio da f\u00e9 somente com base na obra de Cristo somente para gl\u00f3ria de Deus somente. E, claro, derivamos essas verdades das Escrituras somente.<\/p>\n","protected":false},"author":324,"featured_media":53469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[507,611],"tags":[],"class_list":["post-53467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-da-igreja","category-teologia-reformada","tema-fe","tema-fe-dup","tema-reforma","tema-teologia-reformada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salvo pela &#039;lealdade&#039; somente? Sobre uma nova tentativa de revisar a reforma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salvo pela &#039;lealdade&#039; somente? Sobre uma nova tentativa de revisar a reforma\" \/>\n<meta property=\"og:description\" content=\"Somos salvos pela gra\u00e7a somente por meio da f\u00e9 somente com base na obra de Cristo somente para gl\u00f3ria de Deus somente. E, claro, derivamos essas verdades das Escrituras somente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-28T20:04:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-28T23:07:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas R. Schreiner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas R. Schreiner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/\"},\"author\":{\"name\":\"Thomas R. Schreiner\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/5e803f88aa999e155a28c393d6688828\"},\"headline\":\"Salvo pela &#8216;lealdade&#8217; somente? Sobre uma nova tentativa de revisar a reforma\",\"datePublished\":\"2020-04-28T20:04:47+00:00\",\"dateModified\":\"2020-04-28T23:07:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/\"},\"wordCount\":2364,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1\",\"articleSection\":[\"Hist\u00f3ria da Igreja\",\"Teologia Reformada\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/\",\"name\":\"Salvo pela 'lealdade' somente? Sobre uma nova tentativa de revisar a reforma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1\",\"datePublished\":\"2020-04-28T20:04:47+00:00\",\"dateModified\":\"2020-04-28T23:07:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1\",\"width\":856,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/04\\\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salvo pela &#8216;lealdade&#8217; somente? Sobre uma nova tentativa de revisar a reforma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/5e803f88aa999e155a28c393d6688828\",\"name\":\"Thomas R. Schreiner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g\",\"caption\":\"Thomas R. Schreiner\"},\"description\":\"Thomas R. Schreiner serve como pastor de prega\u00e7\u00e3o na Clifton Baptist Church em Louisville, Kentucky. Ele \u00e9 tamb\u00e9m professor de Novo Testamento no Southern Baptist Theological Seminary e escreveu Romans (Baker, 1998) e Paul, Apostle of God\u2019s Glory in Christ: A Pauline Theology (InterVarsity, 2001), entre muitos outros t\u00edtulos.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/thomas-r-schreiner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salvo pela 'lealdade' somente? Sobre uma nova tentativa de revisar a reforma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/","og_locale":"pt_BR","og_type":"article","og_title":"Salvo pela 'lealdade' somente? Sobre uma nova tentativa de revisar a reforma","og_description":"Somos salvos pela gra\u00e7a somente por meio da f\u00e9 somente com base na obra de Cristo somente para gl\u00f3ria de Deus somente. E, claro, derivamos essas verdades das Escrituras somente.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-04-28T20:04:47+00:00","article_modified_time":"2020-04-28T23:07:44+00:00","og_image":[{"width":856,"height":394,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1","type":"image\/jpeg"}],"author":"Thomas R. Schreiner","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Thomas R. Schreiner","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/"},"author":{"name":"Thomas R. Schreiner","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/5e803f88aa999e155a28c393d6688828"},"headline":"Salvo pela &#8216;lealdade&#8217; somente? Sobre uma nova tentativa de revisar a reforma","datePublished":"2020-04-28T20:04:47+00:00","dateModified":"2020-04-28T23:07:44+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/"},"wordCount":2364,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1","articleSection":["Hist\u00f3ria da Igreja","Teologia Reformada"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/","name":"Salvo pela 'lealdade' somente? Sobre uma nova tentativa de revisar a reforma","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1","datePublished":"2020-04-28T20:04:47+00:00","dateModified":"2020-04-28T23:07:44+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1","width":856,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/04\/salvo-pela-lealdade-somente-sobre-uma-nova-tentativa-de-revisar-a-reforma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Salvo pela &#8216;lealdade&#8217; somente? Sobre uma nova tentativa de revisar a reforma"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/5e803f88aa999e155a28c393d6688828","name":"Thomas R. Schreiner","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f9492528356c7a33bbb7e420fbe896a769477fa30b1fb63b3cc61a4f5c53dbc?s=96&d=mm&r=g","caption":"Thomas R. Schreiner"},"description":"Thomas R. Schreiner serve como pastor de prega\u00e7\u00e3o na Clifton Baptist Church em Louisville, Kentucky. Ele \u00e9 tamb\u00e9m professor de Novo Testamento no Southern Baptist Theological Seminary e escreveu Romans (Baker, 1998) e Paul, Apostle of God\u2019s Glory in Christ: A Pauline Theology (InterVarsity, 2001), entre muitos outros t\u00edtulos.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/thomas-r-schreiner\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-dUn","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/04\/Salvo-pela-lealdade-somente-Sobre-uma-nova-tentativa-de-revisar-a-reforma.jpg?fit=856%2C394&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/53467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/324"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=53467"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/53467\/revisions"}],"predecessor-version":[{"id":53472,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/53467\/revisions\/53472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/53469"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=53467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=53467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=53467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}