{"id":54844,"date":"2020-08-10T17:09:45","date_gmt":"2020-08-10T20:09:45","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=54844"},"modified":"2020-08-10T17:09:45","modified_gmt":"2020-08-10T20:09:45","slug":"planos-em-tempos-de-incerteza","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/","title":{"rendered":"Planos em tempos de incerteza"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Voc\u00ea j\u00e1 teve medo de assumir publicamente um compromisso por receio de n\u00e3o conseguir cumpri-lo ou lev\u00e1-lo adiante? Quem nunca temeu anunciar o in\u00edcio de um relacionamento por ser \u201crecente demais\u201d? Quem nunca temeu anunciar uma mudan\u00e7a movida pelo medo de n\u00e3o dar certo? Quantas m\u00e3es n\u00e3o deixaram de anunciar a gesta\u00e7\u00e3o logo no in\u00edcio por medo de perderem o beb\u00ea? Quantos projetos ficaram engavetados pelo medo de n\u00e3o irem adiante? Tememos o fracasso, tememos afirmar que faremos algo e n\u00e3o conseguirmos. Tememos que nossos planos n\u00e3o ocorram conforme planejamos e anunciamos; tememos compartilhar nossas iniciativas, sonhos, ideias e decis\u00f5es, porque, no fim das contas, tememos o fracasso. <em>FRACASSO<\/em>: falta de \u00eaxito; malogro; derrota. Certamente, todas n\u00f3s j\u00e1 sentimos esse gosto amargo.<\/p>\n<p>Em tempos de crise nossos temores tendem a se tornar ainda maiores, a incerteza e a inseguran\u00e7a insistem em nos assombrar. Tememos assumir qualquer compromisso ou fazer planos pois o cen\u00e1rio n\u00e3o \u00e9 prop\u00edcio. E se n\u00e3o der certo? Ah, como \u00e9 dif\u00edcil ser um pouco otimista quando os ventos sopram em outra dire\u00e7\u00e3o.<\/p>\n<p>Enquanto escrevo estas palavras, escrevo-as na condi\u00e7\u00e3o de uma noiva que fez planos, promessas, assumiu compromissos e hoje se v\u00ea diante de um cen\u00e1rio incerto. Definitivamente, mesmo em nossos planos mais pessimistas, n\u00e3o cont\u00e1vamos com uma pandemia; em nossa fr\u00e1gil exist\u00eancia fomos pegos de surpresa.<\/p>\n<p>O ano de 2020 tem nos mostrado qu\u00e3o fr\u00e1geis s\u00e3o os nossos planos. Esperamos sair daqui com algumas li\u00e7\u00f5es aprendidas, se nada der certo, que pelo menos tenhamos a humildade de reconhecer que nossos planos nunca foram soberanos em absolutamente nada. Sem que a boa m\u00e3o de Deus n\u00e3o os conduza a \u00eaxito eles est\u00e3o fadados ao fracasso. Contudo, isso n\u00e3o deve nos desencorajar, de forma alguma. A B\u00edblia nos encoraja a perseverar em tempos de crise; a florescer mesmo em solos n\u00e3o t\u00e3o f\u00e9rteis [Coragem!].<\/p>\n<p>Lembro-me das palavras do profeta Jeremias anunciadas ao povo cativo na Babil\u00f4nia, no caso deles a \u201cquarentena\u201d duraria setenta anos e para esse tempo Deus ordenou: \u201cEdificai casas e habitai nelas; plantai pomares e comei o seu fruto. Tomai esposas e gerai filhos e filhas, tomai esposas para vossos filhos e dai vossas filhas a maridos, para que tenham filhos e filhas; multiplicai-vos a\u00ed e n\u00e3o vos diminuais\u201d (Jeremias 29:5,6). Em outras palavras: sigam em frente, s\u00e3o tempos dif\u00edceis, mas voc\u00eas n\u00e3o est\u00e3o autorizados a parar [sigam em frente].<\/p>\n<p>Mas, seguir em frente n\u00e3o \u00e9 f\u00e1cil, requer coragem, e, acima de tudo f\u00e9. <em>CORAGEM: 1. <\/em>bravura, intrepidez. 2. firmeza de esp\u00edrito para enfrentar situa\u00e7\u00e3o emocional ou moralmente dif\u00edcil. <strong><em>F\u00c9: <\/em><\/strong>a certeza das coisas que se esperam, a convic\u00e7\u00e3o de fatos eu n\u00e3o se veem (Hb 11:1). A coragem e a f\u00e9 n\u00e3o excluem o medo, mas o dominam; elas o colocam em seu devido lugar e seguem em frente; amparadas pela verdade de que o Senhor \u00e9 conosco precisamos encarar nossos ex\u00edlios e quarentenas com coragem.<\/p>\n<p>N\u00e3o seja dominada pelo medo. Embora ex\u00edlios e quarentenas n\u00e3o sejam cen\u00e1rios muito animadores, \u00e9 preciso seguir em frente. N\u00e3o desanime, a gra\u00e7a de Deus tamb\u00e9m se manifesta no ex\u00edlio; ela se manifesta para al\u00e9m da f\u00f4rma que a colocamos. O lugar e as circunst\u00e2ncias em que estamos n\u00e3o nos definem; nossa identidade est\u00e1 em Deus e Ele nos diz: somos povo, apesar do p\u00f3 e das correntes em nossos p\u00e9s. H\u00e1 caos no mundo, mas olhe para o c\u00e9u l\u00e1 fora, veja seu espet\u00e1culo ao entardecer. A gra\u00e7a de Deus continua brilhando.<\/p>\n<h2>Fa\u00e7a planos<\/h2>\n<p>Apesar do cen\u00e1rio desencorajador h\u00e1 uma raz\u00e3o boa o suficiente para que continuemos a fazer planos: Deus tem um plano; e esse plano, minhas caras, n\u00e3o pode ser frustrado, nem pelos c\u00e9us nem pela terra. Sim, o nosso Deus \u00e9 um Deus de planos, Ele n\u00e3o \u00e9 o relojoeiro que deu corda no mundo e simplesmente o abandonou; Ele tem um plano para este mundo e tem um plano para mim e para voc\u00ea e, embora n\u00f3s n\u00e3o saibamos ao certo como esse plano est\u00e1 sendo executado em nosso mundo, uma coisa \u00e9 certa: Ele est\u00e1 nos conduzindo para l\u00e1. Tendo sido criados \u00e0 sua imagem, Ele nos convida a juntarmo-nos a Ele em sua obra criativa, fazendo planos, criando, construindo e cultivando a terra que Ele nos deu.<\/p>\n<p>Portanto, se diante desse cen\u00e1rio incerto Deus te diz \u201csiga em frente!\u201d, ent\u00e3o v\u00e1, inicie algo novo, abrace esse relacionamento promissor com f\u00e9 \u2013 n\u00e3o no relacionamento, mas em Cristo \u2013 case-se, tenha filhos, estude, ensine, compartilhe, reinvente-se. Se isso que est\u00e1 no seu cora\u00e7\u00e3o glorifica a Deus, ponha para fora! N\u00e3o tenha medo. Conquanto n\u00e3o saibamos quais os planos de Deus para os pr\u00f3ximos dias, ele sabe e isso basta.<\/p>\n<p>Fa\u00e7a planos. Ter f\u00e9 n\u00e3o \u00e9 viver ao acaso, mas confiar que Deus controla tudo, inclusive os nossos planos. Ore a Deus, busque a sabedoria e o discernindo do alto e das pessoas que est\u00e3o pr\u00f3ximas a voc\u00ea. Seja s\u00e1bio, pois de nada valem os planos se n\u00e3o houver neles sensatez. Fa\u00e7a aquilo que estiver ao seu alcance, conforme as tuas for\u00e7as.<\/p>\n<p><em>\u201cTudo quanto te vier \u00e0 m\u00e3o para fazer, faze-o conforme as tuas for\u00e7as, porque na sepultura, para onde tu vais, n\u00e3o h\u00e1 obra nem projeto, nem conhecimento, nem sabedoria alguma.\u201d Eclesiastes 9.10<\/em><\/p>\n<p>Minha ora\u00e7\u00e3o \u00e9 para que n\u00e3o sejamos guiadas pelo medo, mas pela coragem, afirmando com convic\u00e7\u00e3o e paz no esp\u00edrito: \u201cse Deus quiser, faremos isto ou aquilo\u201d (Tg 4:15). Quero te encorajar a n\u00e3o paralisar sua vida por causa da pandemia. Se h\u00e1 planos a serem feitos, fa\u00e7a-os; se h\u00e1 sonhos a serem sonhados, sonhe-os; se h\u00e1 noivados a serem realizados, realize-os (com toda a seguran\u00e7a!); se h\u00e1 beb\u00eas a serem concebidos, conceba-os; se h\u00e1 servi\u00e7os a serem prestados, preste-os da melhor forma poss\u00edvel, mas n\u00e3o se deixe desanimar pelas circunst\u00e2ncias. N\u00e3o se deixe paralisar pelo medo. O povo da cruz \u00e9 um povo corajoso, n\u00e3o porque n\u00e3o sinta medo, mas porque sabe onde coloc\u00e1-lo enquanto avan\u00e7a pelas \u00edngremes montanhas da jornada rumo \u00e0 Cidade Celestial.<\/p>\n<h2>Esteja preparada para as frustra\u00e7\u00f5es<\/h2>\n<p>Sei que a essa altura esta frase definitivamente n\u00e3o \u00e9 o que esperamos ler, mas doses de realidade s\u00e3o sempre necess\u00e1rias, para o nosso bem. As frustra\u00e7\u00f5es vir\u00e3o, esteja preparada para elas. Pode ser que no final das contas nossos planos n\u00e3o deem certo e voltemos \u00e0 frustra\u00e7\u00e3o do primeiro par\u00e1grafo deste texto. E se isso acontecer, o que faremos? Como reagiremos? E se o projeto n\u00e3o for adiante? E se o relacionamento for rompido? E se a gesta\u00e7\u00e3o for interrompida ou sequer acontecer? Como responderemos? Eu n\u00e3o sei, e talvez voc\u00ea tamb\u00e9m n\u00e3o saiba, \u00e9 dif\u00edcil encarar o fracasso, ainda mais quando nossos olhos est\u00e3o fitos no sucesso. Mas, uma coisa \u00e9 certa, ao longo da caminhada crist\u00e3 tenho aprendido que Deus sempre ser\u00e1 suficiente, mesmo diante das maiores frustra\u00e7\u00f5es que a vida tenha a oferecer. Ele sempre ser\u00e1 suficiente.<\/p>\n<p>Nossos planos podem falhar, mas os planos de Deus jamais falhar\u00e3o, Ele sabe para onde est\u00e1 nos guiando. Podemos nos gloriar nas nossas frustra\u00e7\u00f5es porque \u00e9 na nossa fraqueza que o poder de Deus se aperfei\u00e7oa. Deus tem um plano que n\u00e3o falhar\u00e1, e a luz desse plano encobre todas as nossas frustra\u00e7\u00f5es. Isso \u00e9 suficiente.<\/p>\n<h2>Voc\u00ea n\u00e3o precisa dar conta de tudo<\/h2>\n<p>Por incr\u00edvel que pare\u00e7a Deus n\u00e3o est\u00e1 nos pedindo para darmos conta de tudo. Sei que \u00e9 dif\u00edcil, mas precisamos aceitar que n\u00f3s definitivamente n\u00e3o conseguiremos dar conta de tudo \u2013 de todos os cursos, de todas as \u201cLives\u201d, de todos os conte\u00fados, de todas as leituras ou de todos os projetos; e se tentarmos fazer isso ficaremos saturadas e doentes, e n\u00e3o \u00e9 essa a vontade de Deus para n\u00f3s. Tenha compaix\u00e3o da sua mente, do seu corpo, d\u00ea uma tr\u00e9gua, tome f\u00f4lego. Permita-se n\u00e3o fazer nada, permita-se n\u00e3o processar tantas informa\u00e7\u00f5es. Permita-se.<\/p>\n<p>Fa\u00e7a segundo as tuas for\u00e7as, nem mais, nem menos. Que esse tempo n\u00e3o seja de sobrecarga mental, emocional e espiritual, precisamos nos manter s\u00e3s e confiantes no Plano que Deus est\u00e1 executando em nosso mundo, as tarefas n\u00e3o podem ser uma fuga da realidade. Se Cristo n\u00e3o est\u00e1 sendo glorificado todo o nosso trabalho \u00e9 in\u00fatil. N\u00e3o precisamos nos comparar com o que os outros est\u00e3o fazendo, precisamos nos comparar com base naquilo que Deus quer que fa\u00e7amos.<\/p>\n<p>Mas aqui vai um alerta: em contrapartida, n\u00e3o devemos ceder \u00e0 de procrastina\u00e7\u00e3o e a pregui\u00e7a, devemos organizar nossas vidas para que possamos ser bons mordomos do tempo que Deus tem nos concedido \u2013 quem sabe o que nos espera adiante? Quem sabe esses dias n\u00e3o s\u00e3o o f\u00f4lego que precisamos tomar para os tempos dif\u00edceis que nos esperam adiante?! Quem sabe essa \u201cpausa\u201d n\u00e3o \u00e9 o intervalo entre o encher das lamparinas e o an\u00fancio da vinda do noivo (Mt 25.1-13)?! Estaremos preparadas? Cansadas demais? Ou pregui\u00e7osas demais? Como estaremos?<\/p>\n<p>N\u00e3o podemos dar conta de tudo, mas podemos dar conta de alguma coisa, talvez de apenas um punhado, aquilo que est\u00e1 ao nosso alcance nesse momento, mas isso, certamente, \u00e9 o bastante. N\u00e3o deixe que a produtividade se torne um \u00eddolo nesses dias, n\u00e3o deixe que a compara\u00e7\u00e3o te impe\u00e7a de enxergar os seus avan\u00e7os e, por favor, n\u00e3o assuma um fardo que Deus n\u00e3o colocou sobre voc\u00ea.<\/p>\n<h2>Seja encorajadora<\/h2>\n<p>Falamos sobre coragem, mas vale lembrar que a coragem nem sempre vem quando nossos joelhos est\u00e3o dobrados, muitas vezes ela vem por meio de uma palavra amiga, um encorajamento, um \u201csiga em frente\u201d aud\u00edvel. Seja uma encorajadora. N\u00e3o seja aquela que ir\u00e1 desmotivar aqueles que est\u00e3o ao seu redor. Seja aquela que ir\u00e1 dizer: \u201cOlhe, sei que s\u00e3o tempos dif\u00edceis aos nossos olhos, mas Deus est\u00e1 no controle. Eu vou orar por voc\u00ea, conte comigo.\u201d Compartilhar sonhos e planos j\u00e1 \u00e9 algo bem dif\u00edcil de se fazer diante do medo do fracasso, ent\u00e3o sejamos sens\u00edveis para com as pessoas que tomam a coragem de compartilhar aquilo que est\u00e1 em seus cora\u00e7\u00f5es. Ao inv\u00e9s de apontarmos tudo o que pode dar errado \u2013 ou, maldosamente, torcer para que isso ocorra \u2013 devemos ser aquelas que ir\u00e3o encorajar e dar suporte, animar e n\u00e3o desanimar. Seja uma encorajadora, os c\u00e9us se alegram.<\/p>\n<p>Por fim, deixo aqui o meu encorajamento: KEEP CALM, Deus tem um plano \u2013 e ele n\u00e3o pode ser frustrado!<a href=\"#_ednref1\" name=\"_edn1\"><\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Deus tem um plano; e esse plano, minhas caras, n\u00e3o pode ser frustrado, nem pelos c\u00e9us nem pela terra. Sim, o nosso Deus \u00e9 um Deus de planos, Ele n\u00e3o \u00e9 o relojoeiro que deu corda no mundo e simplesmente o abandonou.<\/p>\n","protected":false},"author":704,"featured_media":54847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[624,409],"tags":[],"class_list":["post-54844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mulheres","category-vida-crista","tema-mulheres","tema-planos","tema-tempo","tema-vida-crista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Planos em tempos de incerteza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planos em tempos de incerteza\" \/>\n<meta property=\"og:description\" content=\"Deus tem um plano; e esse plano, minhas caras, n\u00e3o pode ser frustrado, nem pelos c\u00e9us nem pela terra. Sim, o nosso Deus \u00e9 um Deus de planos, Ele n\u00e3o \u00e9 o relojoeiro que deu corda no mundo e simplesmente o abandonou.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-10T20:09:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prisca Lessa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prisca Lessa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/\"},\"author\":{\"name\":\"Prisca Lessa\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/ceb18fc6a87d03660cfef50dd1bdb8bf\"},\"headline\":\"Planos em tempos de incerteza\",\"datePublished\":\"2020-08-10T20:09:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/\"},\"wordCount\":1883,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1\",\"articleSection\":[\"Mulheres\",\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/\",\"name\":\"Planos em tempos de incerteza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2020-08-10T20:09:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/planos-em-tempos-de-incerteza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Planos em tempos de incerteza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/ceb18fc6a87d03660cfef50dd1bdb8bf\",\"name\":\"Prisca Lessa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Prisca-Lessa-96x96.jpg\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Prisca-Lessa-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Prisca-Lessa-96x96.jpg\",\"caption\":\"Prisca Lessa\"},\"description\":\"Prisca Lessa \u00e9 angolana, membro da Igreja Presbiteriana do Brasil, tem se dedicado ao minist\u00e9rio de mulheres e ao aconselhamento de jovens e adolescentes. \u00c9 formada em Teologia e escreve em seu blog pessoal Teologia para Mulheres.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/prisca-lessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planos em tempos de incerteza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/","og_locale":"pt_BR","og_type":"article","og_title":"Planos em tempos de incerteza","og_description":"Deus tem um plano; e esse plano, minhas caras, n\u00e3o pode ser frustrado, nem pelos c\u00e9us nem pela terra. Sim, o nosso Deus \u00e9 um Deus de planos, Ele n\u00e3o \u00e9 o relojoeiro que deu corda no mundo e simplesmente o abandonou.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-08-10T20:09:45+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Prisca Lessa","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Prisca Lessa","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/"},"author":{"name":"Prisca Lessa","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/ceb18fc6a87d03660cfef50dd1bdb8bf"},"headline":"Planos em tempos de incerteza","datePublished":"2020-08-10T20:09:45+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/"},"wordCount":1883,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1","articleSection":["Mulheres","Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/","name":"Planos em tempos de incerteza","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1","datePublished":"2020-08-10T20:09:45+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/planos-em-tempos-de-incerteza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Planos em tempos de incerteza"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/ceb18fc6a87d03660cfef50dd1bdb8bf","name":"Prisca Lessa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/05\/Prisca-Lessa-96x96.jpg","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/05\/Prisca-Lessa-96x96.jpg","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2019\/05\/Prisca-Lessa-96x96.jpg","caption":"Prisca Lessa"},"description":"Prisca Lessa \u00e9 angolana, membro da Igreja Presbiteriana do Brasil, tem se dedicado ao minist\u00e9rio de mulheres e ao aconselhamento de jovens e adolescentes. \u00c9 formada em Teologia e escreve em seu blog pessoal Teologia para Mulheres.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/prisca-lessa\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-egA","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Planos-em-tempos-de-incerteza.jpg?fit=750%2C395&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/54844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/704"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=54844"}],"version-history":[{"count":3,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/54844\/revisions"}],"predecessor-version":[{"id":54848,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/54844\/revisions\/54848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/54847"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=54844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=54844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=54844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}