{"id":54860,"date":"2020-08-11T13:49:18","date_gmt":"2020-08-11T16:49:18","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=54860"},"modified":"2020-08-11T20:13:39","modified_gmt":"2020-08-11T23:13:39","slug":"como-sobreviver-em-uma-era-de-ansiedade","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/","title":{"rendered":"Como sobreviver em uma era de ansiedade"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]A ansiedade pode ser esmagadora. Ela pode nos imobilizar e espremer at\u00e9 a \u00faltima gota de alegria de nossas vidas. Tamb\u00e9m pode ter um enorme impacto sobre n\u00f3s, f\u00edsica e emocionalmente. Algu\u00e9m que sofre de ansiedade cont\u00ednua pode ter que lidar com sintomas como altera\u00e7\u00f5es de humor, irritabilidade, raiva, sudorese, batimento card\u00edaco acelerado, dores no peito, exaust\u00e3o, falta de concentra\u00e7\u00e3o, perda de cabelo, ganho ou perda de peso, ataques de p\u00e2nico, ins\u00f4nia e press\u00e3o alta. E isso para citar apenas alguns.<\/p>\n<p>Um escritor coloca assim: \u201cA ansiedade esmagadora acontece quando eu acredito em mentiras. Voc\u00ea pode pensar em suas preocupa\u00e7\u00f5es como falsos profetas. Eles est\u00e3o lhe dizendo que Deus n\u00e3o \u00e9 bom, soberano e s\u00e1bio\u201d.<\/p>\n<p>Em todo o mundo, as pessoas est\u00e3o sendo esmagadas por esse tipo de ansiedade. Est\u00e1 acontecendo diariamente. Eu sei que \u00e9 mais f\u00e1cil falar do que fazer, mas precisamos parar de ouvir essas mentiras. A ansiedade \u00e9 uma quest\u00e3o enorme em nossa sociedade e, como crist\u00e3os, precisamos saber como combater esse pecado.<\/p>\n<h2>A ansiedade \u00e9 real<\/h2>\n<p>Paulo instrui os filipenses sobre a ansiedade: \u201cN\u00e3o andeis ansiosos de coisa alguma; em tudo, por\u00e9m, sejam conhecidas, diante de Deus, as vossas peti\u00e7\u00f5es, pela ora\u00e7\u00e3o e pela s\u00faplica, com a\u00e7\u00f5es de gra\u00e7as.\u201d (Fl 4.6). Agora, voc\u00ea pode ler isso e pensar: O que? Voc\u00ea est\u00e1 falando s\u00e9rio Paulo? Voc\u00ea realmente espera que eu passe pela vida sem nunca ficar ansioso?<\/p>\n<p>Quero dizer, toda m\u00e3e do planeta conhece esse sentimento &#8211; \u00e9 o pesadelo de toda m\u00e3e &#8211; naquele momento em que voc\u00ea percebe que n\u00e3o tem ideia de onde est\u00e1 seu filho. Isso aconteceu comigo uma vez quando eu estava fazendo compras no centro da cidade. De repente, meu filho de quatro anos, Bobby, desapareceu. Fiz o que qualquer m\u00e3e faz: chamei o nome dele, procurei em meio a todos os cabides de roupas, olhei embaixo das mesas e atr\u00e1s dos caixas. Com o passar do tempo e sem encontr\u00e1-lo, percebi que aquilo estava ficando s\u00e9rio. Envolvi a equipe da loja na busca. Meu cora\u00e7\u00e3o estava batendo forte, todos os m\u00fasculos do meu corpo estavam tensos, eu estava gritando por dentro e tentando conter as l\u00e1grimas. Minha ansiedade estava no teto.<\/p>\n<p>Ent\u00e3o minha mente come\u00e7ou a disparar em todas as dire\u00e7\u00f5es &#8211; ele foi sequestrado? Posso realmente me lembrar o que ele estava vestindo hoje? Eu deveria chamar a pol\u00edcia? Talvez voc\u00ea tenha tido um momento como este. Ou talvez voc\u00ea nunca tenha perdido um filho momentaneamente, mas j\u00e1 tenha se relacionado com a ansiedade avassaladora que estou descrevendo. Ent\u00e3o, tenho certeza de que voc\u00ea pode imaginar a sensa\u00e7\u00e3o de al\u00edvio e alegria absolutas &#8211; que logo se tornaram em raiva &#8211; quando encontrei meu filho encolhido na vitrine com os manequins.<\/p>\n<p>Aqui est\u00e1 o problema da ansiedade: parece perfeitamente natural. Naquele momento, parecia que eu n\u00e3o poderia ter outra resposta sen\u00e3o ser totalmente consumida pela ansiedade pelo meu filho desaparecido. Mas aqui est\u00e1 Paulo, em Filipenses 4, nos dizendo claramente para n\u00e3o ficarmos ansiosos por nada. Como devemos entender isso?<\/p>\n<h2>A Ansiedade \u00e9 ativa<\/h2>\n<p>Em um n\u00edvel, o estado de ansiedade pode ser uma resposta humana natural e normal a uma situa\u00e7\u00e3o assustadora. Mas Paulo est\u00e1 falando sobre estar ansioso, o que \u00e9 ativo. \u00c9 algo que escolhemos fazer. Ent\u00e3o, como combatemos esse tipo de ansiedade?<\/p>\n<p>A resposta de Paulo \u00e9 simples: ore (Fl 4.6). D. A. Carson disse uma vez: \u201cAinda tenho que encontrar um preocupado cr\u00f4nico que desfrute de uma excelente vida de ora\u00e7\u00e3o\u201d.<\/p>\n<p>Agora, eu sei que isso \u00e9 mais f\u00e1cil dizer do que fazer. Especialmente com as grandes coisas. Alguns anos atr\u00e1s, eu estava em uma confer\u00eancia, falando de um assunto que conhecia muito bem. Eu estava no palco quando, no meio da minha palestra, de repente eu n\u00e3o sabia o que deveria dizer. N\u00e3o era que eu simplesmente havia esquecido. Na verdade, eu n\u00e3o tinha ideia de qual era o meu ponto, qual era a pr\u00f3xima palavra e percebi que n\u00e3o conseguia nem ler as palavras na minha folha, quanto mais lembrar onde estava. Todo mundo pensou que eu tinha parado para dar algum efeito. Mas, naquele momento \u2013 enquanto eu lutava com o que estava acontecendo &#8211; percebi que havia algo seriamente errado comigo. Parecia que havia durado uma eternidade, mas, felizmente, n\u00e3o durou, e eu consegui terminar minha palestra.<\/p>\n<p>A partir da\u00ed, passei por um longo processo de testes neurol\u00f3gicos, exames de resson\u00e2ncia magn\u00e9tica e outros exames. Demorou s\u00e9culos para que eles descobrissem a causa do problema. N\u00e3o vou mentir para voc\u00ea: houve momentos de ansiedade. Mas, pela gra\u00e7a de Deus, isso me levou de volta a ele em ora\u00e7\u00e3o. Eu tinha que confiar que ele sabia o que estava acontecendo, que estava soberanamente no controle. Eu n\u00e3o estava com medo e n\u00e3o fiquei pesquisando ansiosamente no <em>Google<\/em> todos os sintomas que experimentei. Eu realmente estava contente em deixar isso com Deus. \u00c9 sobre isso que Paulo est\u00e1 falando em Filipenses 4 &#8211; que em todas as situa\u00e7\u00f5es, podemos confiar em Deus e saber que ele as tem em suas m\u00e3os.<\/p>\n<p>Kent Hughes basicamente vai direto ao cerne da quest\u00e3o quando diz: \u201cDescanse na gra\u00e7a de Deus e pare de surtar como algu\u00e9m que n\u00e3o conhece a Deus\u201d. Quando oramos &#8211; n\u00e3o importa a situa\u00e7\u00e3o &#8211; estamos reconhecendo que precisamos de Deus. Citando Hughes novamente: \u201cQuando oramos, apresentamos nossos pedidos, que refletem todos os casos poss\u00edveis de ansiedade &#8230;, estamos lan\u00e7ando todos os nossos cuidados em Deus e declarando nossa absoluta depend\u00eancia dele\u201d.<\/p>\n<h2>A ansiedade deve ser combatida<\/h2>\n<p>Ent\u00e3o, aqui est\u00e3o algumas verdades pr\u00e1ticas a serem lembradas enquanto voc\u00ea luta contra a ansiedade pecaminosa.<\/p>\n<ol>\n<li><strong> Preocupar-se \u00e9 in\u00fatil.<\/strong> Rouba nossa alegria e paz. Falando sobre essa passagem, Tony Merida diz que Paulo deixou claro que \u201ca paz vem somente atrav\u00e9s da ora\u00e7\u00e3o e peti\u00e7\u00e3o com a\u00e7\u00e3o de gra\u00e7as. . ..\u201d A ora\u00e7\u00e3o \u00e9 a ferramenta que empunhamos na luta contra a ansiedade. Isso nos lembra que podemos ter a paz de Deus, mesmo quando nossas circunst\u00e2ncias n\u00e3o fazem sentido para n\u00f3s. Deus \u00e9 a fonte da nossa paz.<\/li>\n<\/ol>\n<p>\u201cQual de v\u00f3s, por ansioso que esteja, pode acrescentar um c\u00f4vado ao curso da sua vida?\u201d (Mateus 6:27).<\/p>\n<ol start=\"2\">\n<li><strong> Deus est\u00e1 conosco.<\/strong> N\u00f3s realmente acreditamos nisso? O Deus que criou o universo, que varreu a terra com um dil\u00favio, que reteve o mar para Mois\u00e9s, que derrubou os muros de Jeric\u00f3, que providenciou um marido para Rute, que protegeu Davi de Saul, que manteve Jonas vivo em um peixe, que enviou seu Filho para morrer por voc\u00ea na cruz. Este Deus, esse mesmo Deus, est\u00e1 com voc\u00ea e nunca o abandonar\u00e1. Esse Deus \u00e9 confi\u00e1vel.<\/li>\n<\/ol>\n<p>Como um outro escritor disse: \u201cEm vez de esgotar sua energia mental na f\u00fatil esteira do &#8216;e se&#8217;, concentre seus pensamentos no verdadeiro, honrado, justo, puro, am\u00e1vel, louv\u00e1vel, excelente e digno de gl\u00f3ria Filho de Deus, que o amou e deu a si mesmo por voc\u00ea \u201d. . . e seja feliz em confiar nele.<\/p>\n<ol start=\"3\">\n<li><strong> Ele \u00e9 todo poderoso.<\/strong> John Frame explica desta maneira: \u201cEle criou e providenciou todas as coisas; nada acontece sem o seu poder\u201d. Este \u00e9 o Deus em cuja presen\u00e7a habitamos.<\/li>\n<li><strong> Deus prov\u00ea.<\/strong> A provis\u00e3o suprema de Deus j\u00e1 nos foi dada no Evangelho, e precisamos nos lembrar disso &#8211; ele nos proporcionou um lar eterno. Deus atende \u00e0 nossa maior necessidade em Cristo.<\/li>\n<\/ol>\n<p>Tony Merida diz muito bem: \u201cSua d\u00e1diva de salva\u00e7\u00e3o nos d\u00e1 motivos para nos alegrarmos. Ele remove nosso maior medo e alivia nossa mais profunda ansiedade atrav\u00e9s de sua vitoriosa morte e ressurrei\u00e7\u00e3o. Ele pagou a penalidade por n\u00f3s.<\/p>\n<p>Podemos pensar que nossa maior necessidade \u00e9 ter uma barriga cheia, um marido, filhos, uma nova casa, um emprego melhor, mas a realidade \u00e9 que nossa maior e mais premente necessidade \u00e9 mais de Deus. Com demasiada frequ\u00eancia, pensamos que sabemos o que precisamos melhor do que Deus nesses momentos. Precisamos correr, correr, correr para Deus e encontrar satisfa\u00e7\u00e3o ao confiarmos e descansarmos nele.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Sharon Dickens. \u00a9 20schemes. Website: <a href=\"https:\/\/20schemes.com\/pt-br\/\" target=\"_blank\" rel=\"noopener noreferrer\">20schemes.com<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/20schemesequip.com\/how-survive-age-anxiety\/\">How to Survive in an Age of Anxiety<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/wp.me\/p4MFiq-egQ\">Como sobreviver em uma era de ansiedade<\/a>. \u00a9 Minist\u00e9rio Fiel. Website:\u00a0<a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">MinisterioFiel.com.br<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Paulo Reiss Junior. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A ansiedade pode ser esmagadora. Ela pode nos imobilizar e espremer at\u00e9 a \u00faltima gota de alegria de nossas vidas. Tamb\u00e9m pode ter um enorme impacto sobre n\u00f3s, f\u00edsica e emocionalmente.<\/p>\n","protected":false},"author":479,"featured_media":54861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[624],"tags":[897],"class_list":["post-54860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mulheres","tag-igreja-para-a-periferia-20schemes","tema-medo-e-ansiedade","tema-medo-e-ansiedade-dup","tema-mulheres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como sobreviver em uma era de ansiedade<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como sobreviver em uma era de ansiedade\" \/>\n<meta property=\"og:description\" content=\"A ansiedade pode ser esmagadora. Ela pode nos imobilizar e espremer at\u00e9 a \u00faltima gota de alegria de nossas vidas. Tamb\u00e9m pode ter um enorme impacto sobre n\u00f3s, f\u00edsica e emocionalmente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-11T16:49:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-11T23:13:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sharon Dickens\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sharon Dickens\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/\"},\"author\":{\"name\":\"Sharon Dickens\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/ccd20b23ad76d536902db5f49f7d2649\"},\"headline\":\"Como sobreviver em uma era de ansiedade\",\"datePublished\":\"2020-08-11T16:49:18+00:00\",\"dateModified\":\"2020-08-11T23:13:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/\"},\"wordCount\":1504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"Igreja para a Periferia - 20schemes\"],\"articleSection\":[\"Mulheres\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/\",\"name\":\"Como sobreviver em uma era de ansiedade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2020-08-11T16:49:18+00:00\",\"dateModified\":\"2020-08-11T23:13:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/como-sobreviver-em-uma-era-de-ansiedade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como sobreviver em uma era de ansiedade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/ccd20b23ad76d536902db5f49f7d2649\",\"name\":\"Sharon Dickens\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Sharon-Dickens2-96x96.jpg\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Sharon-Dickens2-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Sharon-Dickens2-96x96.jpg\",\"caption\":\"Sharon Dickens\"},\"description\":\"Sharon \u00e9 a Diretora de Opera\u00e7\u00f5es e l\u00edder do minist\u00e9rio com mulheres no 20schemes. Ela tem mais de 26 anos de experi\u00eancia trabalhando na comunidade principalmente com fam\u00edlias e pessoas que estiveram ou est\u00e3o em risco de ficarem desabrigadas.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/sharon-dickens\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como sobreviver em uma era de ansiedade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/","og_locale":"pt_BR","og_type":"article","og_title":"Como sobreviver em uma era de ansiedade","og_description":"A ansiedade pode ser esmagadora. Ela pode nos imobilizar e espremer at\u00e9 a \u00faltima gota de alegria de nossas vidas. Tamb\u00e9m pode ter um enorme impacto sobre n\u00f3s, f\u00edsica e emocionalmente.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-08-11T16:49:18+00:00","article_modified_time":"2020-08-11T23:13:39+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Sharon Dickens","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Sharon Dickens","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/"},"author":{"name":"Sharon Dickens","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/ccd20b23ad76d536902db5f49f7d2649"},"headline":"Como sobreviver em uma era de ansiedade","datePublished":"2020-08-11T16:49:18+00:00","dateModified":"2020-08-11T23:13:39+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/"},"wordCount":1504,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1","keywords":["Igreja para a Periferia - 20schemes"],"articleSection":["Mulheres"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/","name":"Como sobreviver em uma era de ansiedade","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1","datePublished":"2020-08-11T16:49:18+00:00","dateModified":"2020-08-11T23:13:39+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/como-sobreviver-em-uma-era-de-ansiedade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Como sobreviver em uma era de ansiedade"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/ccd20b23ad76d536902db5f49f7d2649","name":"Sharon Dickens","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/11\/Sharon-Dickens2-96x96.jpg","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/11\/Sharon-Dickens2-96x96.jpg","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/11\/Sharon-Dickens2-96x96.jpg","caption":"Sharon Dickens"},"description":"Sharon \u00e9 a Diretora de Opera\u00e7\u00f5es e l\u00edder do minist\u00e9rio com mulheres no 20schemes. Ela tem mais de 26 anos de experi\u00eancia trabalhando na comunidade principalmente com fam\u00edlias e pessoas que estiveram ou est\u00e3o em risco de ficarem desabrigadas.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/sharon-dickens\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Como-sobreviver-em-uma-era-de-ansiedade.jpg?fit=750%2C395&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-egQ","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/54860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/479"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=54860"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/54860\/revisions"}],"predecessor-version":[{"id":54866,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/54860\/revisions\/54866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/54861"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=54860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=54860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=54860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}