{"id":55003,"date":"2020-08-19T06:00:28","date_gmt":"2020-08-19T09:00:28","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=55003"},"modified":"2020-08-18T22:46:26","modified_gmt":"2020-08-19T01:46:26","slug":"quando-voce-pastor-duvida-da-eternidade","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/","title":{"rendered":"Quando voc\u00ea, pastor, duvida da eternidade"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Se voc\u00ea \u00e9 crist\u00e3o, as palavras de Apocalipse 21 nunca devem envelhecer: \u201cE lhes enxugar\u00e1 dos olhos toda l\u00e1grima, e a morte j\u00e1 n\u00e3o existir\u00e1, j\u00e1 n\u00e3o haver\u00e1 luto, nem pranto, nem dor, porque as primeiras coisas passaram.\u201d (Ap 21.4) N\u00e3o importa em que \u00e9poca da vida voc\u00ea se encontre, essa grande promessa \u00e9 extremamente relevante.<\/p>\n<p>Recentemente li essas palavras com uma nova crente que eu pastoreava em seus est\u00e1gios finais de vida. Quando terminei de ler, orei e disse a ela: \u201cN\u00e3o se preocupe Carol, n\u00e3o vai demorar muito at\u00e9 que esse curto per\u00edodo de sofrimento seja substitu\u00eddo por uma eternidade de alegria, adorando Jesus.\u201d<\/p>\n<p>N\u00e3o muito depois disso, Carol voltou para a gl\u00f3ria. Ao olhar para ela, lembrei-me das quatro semanas anteriores. Pensei em como n\u00f3s, como igreja, passamos um tempo ao lado de sua cama &#8211; orando com ela, lendo a B\u00edblia para ela, conversando, rindo e chorando com ela. Fiquei triste por ela ter ido embora, mas feliz por seu sofrimento ter cessado. Confortei a mim mesmo e a sua fam\u00edlia dizendo: \u201cCarol est\u00e1 com Jesus agora. Ela realmente est\u00e1 em um lugar melhor\u201d.<\/p>\n<h2>A Realidade da Eternidade<\/h2>\n<p>Quase imediatamente ap\u00f3s dizer isso, d\u00favidas inundaram meus pensamentos interiores: <em>Carol est\u00e1, realmente l\u00e1? \u00c9 realmente nisso que voc\u00ea acredita? Voc\u00ea realmente acha que existe algo mais al\u00e9m desta vida?<\/em><\/p>\n<p>Como pastor, prego sobre a realidade da eternidade todas as semanas. Eu mantenho a esperan\u00e7a da salva\u00e7\u00e3o eterna e advirto as pessoas da condena\u00e7\u00e3o eterna. Eu sei que cada pessoa vai passar a eternidade na presen\u00e7a de Deus ou separada dele. \u00c9 a realidade mais importante do mundo. E o pensamento da salva\u00e7\u00e3o \u2013 passar a eternidade em alegria sem fim com meu Salvador &#8211; \u00e9 t\u00e3o real para mim que muitas vezes me leva \u00e0s l\u00e1grimas.<\/p>\n<p>Ent\u00e3o, depois desse encontro cara a cara com a morte, tive que me perguntar: <em>Por que a d\u00favida repentina?<\/em><\/p>\n<h2>Tesouro na Terra<\/h2>\n<p>Enquanto orava e refletia sobre isso, nas semanas ap\u00f3s a morte de Carol, fiquei convencido de que estava fazendo exatamente o que Jesus disse para n\u00e3o fazer em Mateus 6.<\/p>\n<p>\u201cN\u00e3o acumuleis para v\u00f3s outros tesouros sobre a terra, onde a tra\u00e7a e a ferrugem corroem e onde ladr\u00f5es escavam e roubam;\u00a0mas ajuntai para v\u00f3s outros tesouros no c\u00e9u, onde tra\u00e7a nem ferrugem corr\u00f3i, e onde ladr\u00f5es n\u00e3o escavam, nem roubam; porque, onde est\u00e1 o teu tesouro, a\u00ed estar\u00e1 tamb\u00e9m o teu cora\u00e7\u00e3o.\u201d (Mt 6.19-21).<\/p>\n<p>Fui pastor de um estado municipal em Middlesbrough por muitos anos, ent\u00e3o sei que &#8211; na melhor das hip\u00f3teses &#8211; ministrar em lugares dif\u00edceis pode ser dif\u00edcil, decepcionante e desanimador. Podemos ser tentados a parar de buscar encorajamento e consolo do Senhor e, em vez disso, busc\u00e1-los no mundo. Isso \u00e9 seriamente perigoso, mas \u00e9 exatamente o que eu estava fazendo.<\/p>\n<p>A ironia disso \u00e9 que achei que minha caminhada com Deus estava indo bem. Era consistente com minha vida devocional e pessoal de ora\u00e7\u00e3o. Meu estudo das Escrituras aumentou e minha prepara\u00e7\u00e3o para o serm\u00e3o era muito mais profunda do que nos \u00faltimos tempos.<\/p>\n<p>No entanto, quantidade nem sempre \u00e9 igual a qualidade. Apesar de minha carga de trabalho ter aumentado, minha alegria n\u00e3o. Por causa disso, eu estava buscando recompensas e conforto no tempor\u00e1rio, ao inv\u00e9s de no eterno.<\/p>\n<p>Um cora\u00e7\u00e3o errante \u00e9 um grande perigo para qualquer pessoa envolvida no minist\u00e9rio. Gostamos de pensar que merecemos recompensas por todo o trabalho \u00e1rduo que fazemos. \u00c9 quando come\u00e7amos a pensar em recompensas tempor\u00e1rias que nossos cora\u00e7\u00f5es geralmente v\u00e3o para coisas como comida, bebida, sexo ou dinheiro. E para quem j\u00e1 viu o tamanho da minha cintura, sabe onde \u00e9 minha primeira escala!<\/p>\n<h2>Olhos no Presente<\/h2>\n<p>Al\u00e9m de distra\u00e7\u00f5es pessoais, tamb\u00e9m estava distra\u00eddo pelo meu minist\u00e9rio. Passei o ano viajando pelo pa\u00eds procurando construir parcerias evang\u00e9licas. Eu estava tentando levantar finan\u00e7as e reunir apoio para ora\u00e7\u00e3o, sonhando e esperando que a Igreja New Life Church, em Middlesbrough, pudesse comprar o pr\u00e9dio que est\u00e1vamos alugando, contratar nossa pr\u00f3pria equipe e construir uma igreja saud\u00e1vel.<\/p>\n<p>Todas essas coisas s\u00e3o desejos s\u00e1bios e piedosos, at\u00e9 que sua alegria dependa deles. Comecei a perceber que toda vez que uma parceria n\u00e3o acontecia, ou pedidos de financiamento eram rejeitados (tornando a compra do pr\u00e9dio da igreja muito improv\u00e1vel), minha alegria e motiva\u00e7\u00e3o para o minist\u00e9rio eram diminu\u00eddas.<\/p>\n<p>Eu estava procurando valida\u00e7\u00e3o, como plantador de igrejas, nas coisas tempor\u00e1rias que estava tentando construir. Achei que a igreja e meu papel seriam validados por tijolos e argamassa, um site chamativo e uma grande equipe de funcion\u00e1rios. Todas essas coisas s\u00e3o boas e \u00fateis, mas s\u00e3o tempor\u00e1rias. E eu tinha me esquecido disso.<\/p>\n<h2>Esperan\u00e7a Eterna<\/h2>\n<p>Ao sentar-me com a fam\u00edlia de Carol &#8211; seu marido, filhos, sua m\u00e3e e seu pai &#8211; percebi que eles n\u00e3o se importavam com nossa constru\u00e7\u00e3o, parcerias evang\u00e9licas, equipe ou site. O que importava para eles era a eternidade. Eles estavam preocupados com o Evangelho Eterno e um Salvador Eterno, Aquele que salvou Carol da condena\u00e7\u00e3o eterna e agora estava lhes dando esperan\u00e7a e conforto.<\/p>\n<p>Foi neste momento que Deus me lembrou que quase todas as minhas decep\u00e7\u00f5es com a implanta\u00e7\u00e3o de igrejas aconteceram quando coloquei meu foco e entreguei meu cora\u00e7\u00e3o \u00e0s coisas tempor\u00e1rias deste mundo. A f\u00e9 de Carol em seu leito de morte me ensinou que, independentemente da situa\u00e7\u00e3o tempor\u00e1ria em que nos encontramos e quaisquer finan\u00e7as e recursos que possamos ou n\u00e3o ter, nossa alegria n\u00e3o vem do tempor\u00e1rio, mas do eterno.<\/p>\n<p>Se quisermos perseverar no minist\u00e9rio, precisamos compreender a alegria que s\u00f3 pode ser encontrada direcionando nossos cora\u00e7\u00f5es e olhos para o c\u00e9u. Devemos fixar nossos olhos na eternidade &#8211; o Evangelho Eterno que aponta para um Salvador Eterno. Afinal, quando nossa curta carreira na terra terminar, a eternidade ser\u00e1 o que mais importa.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Ian Williamson. \u00a9 20schemes. Website: <a href=\"https:\/\/20schemes.com\/pt-br\/\" target=\"_blank\" rel=\"noopener noreferrer\">20schemes.com<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/20schemesequip.com\/doubt-eternity-pastor\/\">When You Doubt Eternity as a Pastor<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/wp.me\/p4MFiq-ej9\">Quando voc\u00ea, pastor, duvida da eternidade<\/a>. \u00a9 Minist\u00e9rio Fiel. Website: <a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">MinisterioFiel.com.br<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Paulo Reiss Junior. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Se quisermos perseverar no minist\u00e9rio, precisamos compreender a alegria que s\u00f3 pode ser encontrada direcionando nossos cora\u00e7\u00f5es e olhos para o c\u00e9u.<\/p>\n","protected":false},"author":831,"featured_media":55006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[467],"tags":[897],"class_list":["post-55003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ministerio-pastoral","tag-igreja-para-a-periferia-20schemes","tema-lideranca-da-igreja","tema-lideranca-da-igreja-dup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quando voc\u00ea, pastor, duvida da eternidade<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando voc\u00ea, pastor, duvida da eternidade\" \/>\n<meta property=\"og:description\" content=\"Se quisermos perseverar no minist\u00e9rio, precisamos compreender a alegria que s\u00f3 pode ser encontrada direcionando nossos cora\u00e7\u00f5es e olhos para o c\u00e9u.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-19T09:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Quando-voce\u0302-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ian Williamson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ian Williamson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/\"},\"author\":{\"name\":\"Ian Williamson\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/57107e8b1642dd9fe038101221b69644\"},\"headline\":\"Quando voc\u00ea, pastor, duvida da eternidade\",\"datePublished\":\"2020-08-19T09:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/\"},\"wordCount\":1152,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"Igreja para a Periferia - 20schemes\"],\"articleSection\":[\"Minist\u00e9rio Pastoral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/\",\"name\":\"Quando voc\u00ea, pastor, duvida da eternidade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2020-08-19T09:00:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2020\\\/08\\\/quando-voce-pastor-duvida-da-eternidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quando voc\u00ea, pastor, duvida da eternidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/57107e8b1642dd9fe038101221b69644\",\"name\":\"Ian Williamson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ea028c16aec2f9244444688358d43d69952d3379cb7b6ff4502c7782bff0de7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ea028c16aec2f9244444688358d43d69952d3379cb7b6ff4502c7782bff0de7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ea028c16aec2f9244444688358d43d69952d3379cb7b6ff4502c7782bff0de7?s=96&d=mm&r=g\",\"caption\":\"Ian Williamson\"},\"description\":\"Ian Williamson \u00e9 pastor da New Life Church em Middlesbrough, Inglaterra.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/ian-williamson\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando voc\u00ea, pastor, duvida da eternidade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Quando voc\u00ea, pastor, duvida da eternidade","og_description":"Se quisermos perseverar no minist\u00e9rio, precisamos compreender a alegria que s\u00f3 pode ser encontrada direcionando nossos cora\u00e7\u00f5es e olhos para o c\u00e9u.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2020-08-19T09:00:28+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Quando-voce\u0302-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Ian Williamson","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Ian Williamson","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/"},"author":{"name":"Ian Williamson","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/57107e8b1642dd9fe038101221b69644"},"headline":"Quando voc\u00ea, pastor, duvida da eternidade","datePublished":"2020-08-19T09:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/"},"wordCount":1152,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1","keywords":["Igreja para a Periferia - 20schemes"],"articleSection":["Minist\u00e9rio Pastoral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/","name":"Quando voc\u00ea, pastor, duvida da eternidade","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1","datePublished":"2020-08-19T09:00:28+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2020\/08\/quando-voce-pastor-duvida-da-eternidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quando voc\u00ea, pastor, duvida da eternidade"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/57107e8b1642dd9fe038101221b69644","name":"Ian Williamson","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6ea028c16aec2f9244444688358d43d69952d3379cb7b6ff4502c7782bff0de7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ea028c16aec2f9244444688358d43d69952d3379cb7b6ff4502c7782bff0de7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ea028c16aec2f9244444688358d43d69952d3379cb7b6ff4502c7782bff0de7?s=96&d=mm&r=g","caption":"Ian Williamson"},"description":"Ian Williamson \u00e9 pastor da New Life Church em Middlesbrough, Inglaterra.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/ian-williamson\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2020\/08\/Quando-voce%CC%82-pastor-duvida-da-eternidade.jpg?fit=750%2C395&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-ej9","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/55003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/831"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=55003"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/55003\/revisions"}],"predecessor-version":[{"id":55009,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/55003\/revisions\/55009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/55006"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=55003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=55003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=55003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}