{"id":58120,"date":"2021-04-28T16:12:43","date_gmt":"2021-04-28T19:12:43","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=58120"},"modified":"2025-12-16T12:05:51","modified_gmt":"2025-12-16T15:05:51","slug":"uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/","title":{"rendered":"Uma igreja que n\u00e3o ajuda precisa ser ajudada"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Gostaria de reflectir, em primeiro lugar, sobre os direitos e os deveres de um membro de igreja (aquele que foi baptizado e que congrega uma igreja).<\/p>\n<p>Vamos partir de duas afirma\u00e7\u00f5es: os direitos s\u00e3o os benef\u00edcios aos quais as pessoas t\u00eam direito e os deveres s\u00e3o as responsabilidades.<\/p>\n<p>De certa forma, quando algu\u00e9m na igreja cumpre os seus deveres, outro ir\u00e1 receber os seus direitos.<\/p>\n<p>No pacto das Igrejas Baptistas h\u00e1 alguns aspectos que gostaria de salientar sobre os nossos deveres (algo que se espera que os membros fa\u00e7am para que outros recebam). Irei apenas mencionar os que est\u00e3o ligados ao texto b\u00edblico de Atos 11.27-30 (texto que abordarei de forma mais demorada posteriormente).<\/p>\n<p>Assim, no pacto das Igrejas Baptistas podemos ler que devemos contribuir liberal ou generosamente para:<\/p>\n<ul>\n<li>Sustento mission\u00e1rio;<\/li>\n<li>Despesas da Igreja;<\/li>\n<li>Aux\u00edlio aos pobres;<\/li>\n<li>Propaga\u00e7\u00e3o do Evangelho;<\/li>\n<\/ul>\n<p>Nas nossas rela\u00e7\u00f5es, devemos:<\/p>\n<ul>\n<li>Ter cuidado uns com os outros;<\/li>\n<li>Lembrarmo-nos uns dos outros nas nossas ora\u00e7\u00f5es;<\/li>\n<li>Ajudar mutuamente nas enfermidades e necessidades;<\/li>\n<li>Cultivar rela\u00e7\u00f5es francas e a delicadeza no trato;<\/li>\n<li>Estar prontos a perdoar as ofensas;<\/li>\n<li>Buscar a paz;<\/li>\n<\/ul>\n<p>Ser\u00e1 que pensamos nestes aspectos?<\/p>\n<p>Normalmente, quando ou\u00e7o algumas pessoas, e estou a generalizar, falam mais nos direitos do que nos deveres. Isto acontece, em grande parte, porque vivemos tempos em que queremos mais coisas dos outros do que aquilo que queremos dar aos outros.<\/p>\n<p>Em Atos 11.27-30 percebemos algumas coisas bastante interessantes.<\/p>\n<p>Se olharmos para os vers\u00edculos anteriores, veremos que \u201cUma Igreja com Miss\u00e3o\u201d deseja tanto alcan\u00e7ar pessoas para Cristo como \u00a0buscar a ovelha perdida. N\u00e3o h\u00e1 um desejo maior por uma parte e menor por outra.<\/p>\n<p>Devemos lutar para n\u00e3o sermos uma Igreja de acomodados, mas sim uma Igreja de cora\u00e7\u00f5es transformados e apaixonados por miss\u00f5es.<\/p>\n<p>Se temos cora\u00e7\u00f5es transformados, isso \u00e9 sinal de que Deus nos concedeu a f\u00e9.<\/p>\n<p>Se h\u00e1 f\u00e9 verdadeira, vinda de Deus, essa f\u00e9 produzir\u00e1 boas obras que se traduzir\u00e3o em nada mais do que actos de compaix\u00e3o pelas pessoas.<\/p>\n<p>Se a f\u00e9 n\u00e3o produzir nada, como diz em Tiago 2.20, \u00e9 morta, v\u00e3, sem valor.<\/p>\n<p>Pergunto ent\u00e3o como \u00e9 que essa f\u00e9 deve ser vis\u00edvel? Qual \u00e9 o impacto que deve ter na vida dos outros?<\/p>\n<p>Vamos olhar com maior aten\u00e7\u00e3o para o texto b\u00edblico j\u00e1 referido, este \u00e9 muito pertinente, principalmente nestes tempos t\u00e3o duros que vivemos e que iremos viver.<\/p>\n<p><em>27Naqueles dias, desceram alguns profetas de Jerusal\u00e9m para Antioquia, 28 e, apresentando-se um deles, chamado \u00c1gabo, dava a entender (indicava claramente), pelo Esp\u00edrito, que estava para vir grande fome por todo o mundo, a qual sobreveio nos dias de Cl\u00e1udio. 29Os disc\u00edpulos, cada um conforme as suas posses (ideia da proporcionalidade), resolveram enviar socorro (ajuda) aos irm\u00e3os que moravam na Judeia; 30 O que eles, com efeito, fizeram, enviando-o aos presb\u00edteros por interm\u00e9dio de Barnab\u00e9 e de Saulo.<\/em><\/p>\n<p>\u00c9 importante recordar que a Igreja de Jerusal\u00e9m tinha enviado Barnab\u00e9 para Antioquia para consolidar o que Deus estava a fazer com a convers\u00e3o de muitas vidas.<\/p>\n<p>Nestes tempos, era muito comum haver pessoas que profetizavam sobre o futuro precisamente porque a revela\u00e7\u00e3o b\u00edblica ainda n\u00e3o estava terminada. Era a forma que Deus tinha para comunicar com o Seu povo al\u00e9m do Antigo Testamento.<\/p>\n<p>O profeta \u00c1gabo, por revela\u00e7\u00e3o do Esp\u00edrito Santo, avisou a Igreja em Antioquia que viria uma grande fome no mundo nos dias do imperador Cla\u00fadio. A hist\u00f3ria comprova que, realmente, veio uma fome assoladora entre o ano 45 e 47.<\/p>\n<p>Quando algo vem de Deus, cumpre-se. O resto s\u00e3o suposi\u00e7\u00f5es.<\/p>\n<p>Por exemplo, em Dezembro de 2019 ouvimos dizer que 2020 ia ser um ano fant\u00e1stico \u00a0e foi o que foi. Alguns ainda ca\u00edram no erro de tentar adivinhar como ser\u00e1 este ano, estamos em meados de mar\u00e7o e j\u00e1 percebemos que ningu\u00e9m tem como saber o que ir\u00e1 acontecer (como em todos os anos que vivemos, sejam eles de pandemia, ou n\u00e3o).<\/p>\n<p>As \u00fanicas coisas que sabemos s\u00e3o:<\/p>\n<ul>\n<li><em>Deus \u00e9 soberano<\/em>: \u00e9 imposs\u00edvel que algo aconte\u00e7a fora da Sua vontade;<\/li>\n<li><em>O ser humano \u00e9 respons\u00e1vel pelas suas escolhas<\/em>: ainda que n\u00e3o consiga ir mais longe do que a Soberania de Deus permite.<\/li>\n<li><em>Deus \u00e9 bom<\/em>: qualquer que seja a Sua escolha;<\/li>\n<li><em>Deus \u00e9 justo<\/em>: nada do que Ele faz \u00e9 injusto;<\/li>\n<\/ul>\n<p>Como \u00e9 que a Igreja reagiu a esta profecia feita por \u00c1gabo?<\/p>\n<p>Ser\u00e1 que a Igreja esperou pela sua concretiza\u00e7\u00e3o ou come\u00e7ou logo a pensar em como ajudar aquelas pessoas?<\/p>\n<p>Lembro que estes crist\u00e3os n\u00e3o conheciam os crist\u00e3os em Jerusal\u00e9m.<\/p>\n<p>Vemos v\u00e1rios aspectos importantes no vers\u00edculo 29:<\/p>\n<p>Quem contribui? Cada crist\u00e3o. Todos quiseram ter a oportunidade de ajudar quem estava a precisar.<\/p>\n<p>Ser\u00e1 que todos tinham as mesmas condi\u00e7\u00f5es? Claro que n\u00e3o. No entanto, cada um contribuiu conforme as suas posses ao ponto de todos participarem nesta ajuda.<\/p>\n<p><em>Esta sempre foi a ideia b\u00edblica: todos somos chamados a praticar obras de compaix\u00e3o ao ajudarmos as pessoas, principalmente aos nossos irm\u00e3os na f\u00e9 (G\u00e1latas 6.10)<\/em><\/p>\n<p>Na segunda carta aos Cor\u00edntios 8.1-5 vemos outro exemplo incr\u00edvel:<\/p>\n<p>Os irm\u00e3os da Igreja na Maced\u00f3nia viviam na pobreza e ajudavam o pr\u00f3ximo, valorizavam mais o Reino do que as suas coisas e o seu reino pessoal, valorizavam mais os irm\u00e3os na f\u00e9 do que a realiza\u00e7\u00e3o de gostos pessoais.<\/p>\n<p>A quest\u00e3o \u00e9: j\u00e1 deix\u00e1mos de fazer alguma coisa que quer\u00edamos ou at\u00e9 ach\u00e1vamos que merec\u00edamos para ajudar outras pessoas?<\/p>\n<p>Deus usa muitas vezes o que temos para suprir as necessidades b\u00e1sicas de outros.<\/p>\n<p>A Igreja ajudou sem haver um pedido de ajuda e sem a fome ter chegado.<\/p>\n<p>Este \u00e9 um aspecto importante: as pessoas n\u00e3o precisam de pedir ajuda para as ajudarmos. Se sabemos ou imaginamos que pode haver uma dificuldade, ajudemos de imediato.<\/p>\n<p>Vemos tamb\u00e9m no vers\u00edculo 29 de Atos que os gentios ajudaram os judeus.<\/p>\n<p>Na Igreja somos um s\u00f3 corpo, n\u00e3o h\u00e1 diferen\u00e7as, somos todos iguais.<\/p>\n<p>Agora, como fizeram chegar as ofertas \u00e0s Igrejas?<\/p>\n<p>As pessoas da Igreja deram \u00e0 Igreja para que esta fosse o ve\u00edculo dessas mesmas ofertas, conferimos isso no vers\u00edculo 30.<\/p>\n<p>H\u00e1 sempre muito mais transpar\u00eancia nesta forma de agir e \u00e9 uma pr\u00e1tica b\u00edblica.<\/p>\n<p>A pr\u00e1tica das contribui\u00e7\u00f5es, d\u00edzimos e ofertas, sempre foi na l\u00f3gica de: entregar na Igreja para aben\u00e7oar a pr\u00f3pria Igreja e outras Igrejas, institui\u00e7\u00f5es ou pessoas.<\/p>\n<p>\u00c9 uma b\u00ean\u00e7\u00e3o honrarmos o compromisso de membresia e o pacto da Igreja e, consequentemente, devemos sentir alegria por podermos ajudar quem passa por dificuldades.<\/p>\n<p>Sendo assim, devemos desejar ser crist\u00e3os que contribuem com os seus d\u00edzimos e que d\u00e3o as ofertas, mediante as suas posses, sabendo que h\u00e1 sempre alguma coisa que podemos fazer ou dar.<\/p>\n<p>Deixar de contribuir para a Igreja com os d\u00edzimos e ofertas \u00e9 n\u00e3o compreender o princ\u00edpio b\u00edblico.<\/p>\n<p>Muitas vezes as Igrejas n\u00e3o fazem mais porque as pessoas n\u00e3o se envolvem. N\u00e3o \u00e9 por dificuldades financeiras, se fosse, ou quando \u00e9, \u00e9 completamente compreens\u00edvel, mas, na maior parte das vezes, \u00e9 falta de compromisso com a Palavra e com a Igreja.<\/p>\n<p>N\u00e3o devemos dar apenas o que sobeja, devemos dar tamb\u00e9m algo que nos custe, como deixar de ter um pequeno luxo durante algum tempo.<\/p>\n<p>Ressalvo que n\u00e3o devemos ajudar porque amanh\u00e3 podemos ser n\u00f3s a precisar. Queremos ajudar para que o nome de Deus seja glorificado e as pessoas sejam auxiliadas.<\/p>\n<p>Devemos at\u00e9 ajudar os nossos inimigos e aqueles que nos fazem mal: \u201cSe o teu inimigo tiver fome, d\u00e1-lhe de comer. Se tiver sede, d\u00e1-lhe de beber\u201d (Pv. 25.21)<\/p>\n<p>Tudo isto ser\u00e1 sempre um pequeno reflexo do que Deus fez por n\u00f3s devido \u00e0 nossa mis\u00e9ria espiritual: Romanos 5.8.<\/p>\n<p>A Deus seja sempre dada toda a gl\u00f3ria.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Devemos lutar para n\u00e3o sermos uma Igreja de acomodados, mas sim uma Igreja de cora\u00e7\u00f5es transformados e apaixonados por miss\u00f5es.<\/p>\n","protected":false},"author":864,"featured_media":58121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Devemos lutar para n\u00e3o sermos uma Igreja de acomodados, mas sim uma Igreja de cora\u00e7\u00f5es transformados e apaixonados por miss\u00f5es. #TeoPortugal","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[2693],"class_list":["post-58120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-teoportugal","tema-igreja","tema-missao-da-igreja","tema-questoes-da-igreja"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uma igreja que n\u00e3o ajuda precisa ser ajudada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uma igreja que n\u00e3o ajuda precisa ser ajudada\" \/>\n<meta property=\"og:description\" content=\"Devemos lutar para n\u00e3o sermos uma Igreja de acomodados, mas sim uma Igreja de cora\u00e7\u00f5es transformados e apaixonados por miss\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-28T19:12:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T15:05:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/04\/Uma-igreja-que-na\u0303o-ajuda-precisa-de-ser-ajudada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00f3natas Rafael Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00f3natas Rafael Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/\"},\"author\":{\"name\":\"J\u00f3natas Rafael Lopes\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/a653ae2ca6666b76a66bec88d6d51f35\"},\"headline\":\"Uma igreja que n\u00e3o ajuda precisa ser ajudada\",\"datePublished\":\"2021-04-28T19:12:43+00:00\",\"dateModified\":\"2025-12-16T15:05:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/\"},\"wordCount\":1376,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"TeoPortugal\"],\"articleSection\":[\"...\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/\",\"name\":\"Uma igreja que n\u00e3o ajuda precisa ser ajudada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2021-04-28T19:12:43+00:00\",\"dateModified\":\"2025-12-16T15:05:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uma igreja que n\u00e3o ajuda precisa ser ajudada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/a653ae2ca6666b76a66bec88d6d51f35\",\"name\":\"J\u00f3natas Rafael Lopes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280e8096ece069fb2d379f6fc8ef3ecadfc41513b3aa447a8c49bd4435d956eb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280e8096ece069fb2d379f6fc8ef3ecadfc41513b3aa447a8c49bd4435d956eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280e8096ece069fb2d379f6fc8ef3ecadfc41513b3aa447a8c49bd4435d956eb?s=96&d=mm&r=g\",\"caption\":\"J\u00f3natas Rafael Lopes\"},\"description\":\"Jonatas Rafael Lopes \u00e9 pastor na Igreja Baptista da Gra\u00e7a, em Lisboa, e p\u00f3s-graduado em estudos b\u00edblicos. \u00c9 membro da dire\u00e7\u00e3o da Conven\u00e7\u00e3o Baptista Portuguesa respons\u00e1vel por Apoio a Igrejas. Jonatas \u00e9 casado com a Filipa Lopes, e eles t\u00eam quatro filhos: Raquel, Samuel, Gabriel e Isabel.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/jonatas-rafael-lopes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uma igreja que n\u00e3o ajuda precisa ser ajudada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/","og_locale":"pt_BR","og_type":"article","og_title":"Uma igreja que n\u00e3o ajuda precisa ser ajudada","og_description":"Devemos lutar para n\u00e3o sermos uma Igreja de acomodados, mas sim uma Igreja de cora\u00e7\u00f5es transformados e apaixonados por miss\u00f5es.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2021-04-28T19:12:43+00:00","article_modified_time":"2025-12-16T15:05:51+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/04\/Uma-igreja-que-na\u0303o-ajuda-precisa-de-ser-ajudada.jpg","type":"image\/jpeg"}],"author":"J\u00f3natas Rafael Lopes","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"J\u00f3natas Rafael Lopes","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/"},"author":{"name":"J\u00f3natas Rafael Lopes","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/a653ae2ca6666b76a66bec88d6d51f35"},"headline":"Uma igreja que n\u00e3o ajuda precisa ser ajudada","datePublished":"2021-04-28T19:12:43+00:00","dateModified":"2025-12-16T15:05:51+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/"},"wordCount":1376,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/04\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1","keywords":["TeoPortugal"],"articleSection":["..."],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/","name":"Uma igreja que n\u00e3o ajuda precisa ser ajudada","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/04\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1","datePublished":"2021-04-28T19:12:43+00:00","dateModified":"2025-12-16T15:05:51+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/04\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/04\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/uma-igreja-que-nao-ajuda-precisa-de-ser-ajudada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Uma igreja que n\u00e3o ajuda precisa ser ajudada"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/a653ae2ca6666b76a66bec88d6d51f35","name":"J\u00f3natas Rafael Lopes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/280e8096ece069fb2d379f6fc8ef3ecadfc41513b3aa447a8c49bd4435d956eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/280e8096ece069fb2d379f6fc8ef3ecadfc41513b3aa447a8c49bd4435d956eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/280e8096ece069fb2d379f6fc8ef3ecadfc41513b3aa447a8c49bd4435d956eb?s=96&d=mm&r=g","caption":"J\u00f3natas Rafael Lopes"},"description":"Jonatas Rafael Lopes \u00e9 pastor na Igreja Baptista da Gra\u00e7a, em Lisboa, e p\u00f3s-graduado em estudos b\u00edblicos. \u00c9 membro da dire\u00e7\u00e3o da Conven\u00e7\u00e3o Baptista Portuguesa respons\u00e1vel por Apoio a Igrejas. Jonatas \u00e9 casado com a Filipa Lopes, e eles t\u00eam quatro filhos: Raquel, Samuel, Gabriel e Isabel.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/jonatas-rafael-lopes\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/04\/Uma-igreja-que-na%CC%83o-ajuda-precisa-de-ser-ajudada.jpg?fit=750%2C395&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-f7q","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/864"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=58120"}],"version-history":[{"count":4,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58120\/revisions"}],"predecessor-version":[{"id":58136,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58120\/revisions\/58136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/58121"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=58120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=58120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=58120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}