{"id":58450,"date":"2021-05-27T17:00:29","date_gmt":"2021-05-27T20:00:29","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=58450"},"modified":"2021-05-27T16:09:23","modified_gmt":"2021-05-27T19:09:23","slug":"praticantes-nao-somente-ouvintes","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/","title":{"rendered":"Praticantes, n\u00e3o somente ouvintes"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Como pastor de uma igreja local, eu tenho conhecido muitas pessoas ao longo dos anos que n\u00e3o cresceram indo \u00e0 igreja e que nunca estudaram a Escritura ou a teologia da Escritura. Eu tamb\u00e9m conheci pessoas que cresceram indo \u00e0 igreja, mas que nunca foram ensinadas como estudar a Escritura e sua teologia. No entanto, como o Dr. R.C. Sproul disse, <strong><a href=\"https:\/\/fiel.in\/2TrNFu5\" target=\"_blank\" rel=\"noopener\">somos todos te\u00f3logos<\/a><\/strong> \u2014 a quest\u00e3o \u00e9 se somos ou n\u00e3o bons te\u00f3logos. O problema fundamental no nosso tempo \u00e9 que muitos crist\u00e3os professantes n\u00e3o pensam que eles precisam estudar teologia, enquanto muitos outros n\u00e3o parecem se importar com teologia ou s\u00e3o simplesmente muito pregui\u00e7osos para estud\u00e1-la.\u00a0 Crist\u00e3os, entretanto, deveriam se importar com teologia. Como poder\u00edamos n\u00e3o nos importar, quando ela nos fala sobre aquele que salva nossas almas?<\/p>\n<p>Muitos crist\u00e3os, particularmente crist\u00e3os jovens e rec\u00e9m convertidos, n\u00e3o sabem por onde come\u00e7ar os seus estudos de teologia, e n\u00e3o sabem como dar conta disso. Eu descobri que alguns crist\u00e3os acham que teologia \u00e9 apenas para pastores ou acad\u00eamicos, e pior, alguns pastores e acad\u00eamicos fazem leigos pensarem que eles s\u00f3 podem de fato estudar teologia se eles se esfor\u00e7arem em dire\u00e7\u00e3o a um diploma teol\u00f3gico avan\u00e7ado.\u00a0 Eu tamb\u00e9m descobri que alguns crist\u00e3os pensam que precisam desenvolver sua pr\u00f3pria teologia. Mas Deus n\u00e3o nos chama a desenvolver nossa pr\u00f3pria teologia \u2014 esta j\u00e1 est\u00e1 desenvolvida na Escritura. N\u00f3s somos chamados a estud\u00e1-la, entend\u00ea-la, e a sermos praticantes, n\u00e3o somente ouvintes. Al\u00e9m disso, n\u00e3o \u00e9 a nossa pr\u00f3pria teologia; \u00e9 a teologia da igreja una, santa, cat\u00f3lica e apost\u00f3lica. Quando pessoas desenvolvem sua pr\u00f3pria teologia, elas inevitavelmente desenvolvem sua pr\u00f3pria heresia.<\/p>\n<p>Fazer teologia significa estudar a Escritura e estudar as palavras dos nossos fi\u00e9is antepassados que fielmente estudaram a Escritura. Significa estudar credos hist\u00f3ricos e confiss\u00f5es da igreja, que servem como \u00fateis sum\u00e1rios e explica\u00e7\u00f5es do que a Escritura ensina. Significa estudar n\u00e3o apenas livros de teologia sistem\u00e1tica, mas tamb\u00e9m coment\u00e1rios b\u00edblicos, e ainda livros de hermen\u00eautica (o m\u00e9todo de interpretar a Escritura), hist\u00f3ria da igreja, teologia hist\u00f3rica, e at\u00e9 sobre vida crist\u00e3 (como aplicar a teologia a toda a vida), porque teologia entendida corretamente \u00e9 teologia corretamente aplicada \u00e0 vida. Tamb\u00e9m significa estudar teologia enquanto sentamos debaixo do minist\u00e9rio da Palavra em nossas igrejas locais, semana ap\u00f3s semana, por meio da adora\u00e7\u00e3o, can\u00e7\u00e3o, e sacramentos. Porque quando n\u00f3s estudamos teologia, n\u00f3s estudamos Deus, para que possamos corretamente conhecer, amar, adorar e proclamar o Deus triuno da Escritura, n\u00e3o um deus criado por n\u00f3s.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Burk Parsons. \u00a9 Ligonier Ministries. Website: <a href=\"http:\/\/www.ligonier.org\/\" target=\"_blank\" rel=\"noopener\">ligonier.org<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/tabletalkmagazine.com\/article\/2018\/02\/doers-not-hearers\/\">Doers, Not Hearers Only<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/wp.me\/p4MFiq-fcK\">Praticantes, n\u00e3o somente ouvintes<\/a>. \u00a9 Minist\u00e9rio Fiel. Website:\u00a0<a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener\">MinisterioFiel.com.br<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Alex Motta. Revis\u00e3o: Pedro Henrique Lima de Oliveira.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Deus n\u00e3o nos chama a desenvolver nossa pr\u00f3pria teologia \u2014 esta j\u00e1 est\u00e1 desenvolvida na Escritura. N\u00f3s somos chamados a estud\u00e1-la, entend\u00ea-la, e a sermos praticantes, n\u00e3o somente ouvintes.<\/p>\n","protected":false},"author":44,"featured_media":58451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Deus n\u00e3o nos chama a desenvolver nossa pr\u00f3pria teologia \u2014 esta j\u00e1 est\u00e1 desenvolvida na Escritura. N\u00f3s somos chamados a estud\u00e1-la, entend\u00ea-la, e a sermos praticantes, n\u00e3o somente ouvintes.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[409],"tags":[2756,480],"class_list":["post-58450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-crista","tag-fazendo-teologia","tag-ligonier","tema-vida-crista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Praticantes, n\u00e3o somente ouvintes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Praticantes, n\u00e3o somente ouvintes\" \/>\n<meta property=\"og:description\" content=\"Deus n\u00e3o nos chama a desenvolver nossa pr\u00f3pria teologia \u2014 esta j\u00e1 est\u00e1 desenvolvida na Escritura. N\u00f3s somos chamados a estud\u00e1-la, entend\u00ea-la, e a sermos praticantes, n\u00e3o somente ouvintes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-27T20:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/05\/Praticantes-na\u0303o-somente-ouvintes.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Burk Parsons\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Burk Parsons\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/\"},\"author\":{\"name\":\"Burk Parsons\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/c29938440a404a2b117d1edbcdff8ecf\"},\"headline\":\"Praticantes, n\u00e3o somente ouvintes\",\"datePublished\":\"2021-05-27T20:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/\"},\"wordCount\":565,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"Fazendo Teologia\",\"Minist\u00e9rio Ligonier\"],\"articleSection\":[\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/\",\"name\":\"Praticantes, n\u00e3o somente ouvintes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2021-05-27T20:00:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/05\\\/praticantes-nao-somente-ouvintes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Praticantes, n\u00e3o somente ouvintes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/c29938440a404a2b117d1edbcdff8ecf\",\"name\":\"Burk Parsons\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Burk-Parsons_avatar_1410793123.jpg\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Burk-Parsons_avatar_1410793123.jpg\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/Burk-Parsons_avatar_1410793123.jpg\",\"caption\":\"Burk Parsons\"},\"description\":\"Burk Parsons \u00e9 pastor na Saint Andrew\u2019s Chapel, em Sanford (Fl\u00f3rida), e editor da revista mensal Tabletalk, publicada por Ligonier Ministries.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/burk-parsons\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Praticantes, n\u00e3o somente ouvintes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/","og_locale":"pt_BR","og_type":"article","og_title":"Praticantes, n\u00e3o somente ouvintes","og_description":"Deus n\u00e3o nos chama a desenvolver nossa pr\u00f3pria teologia \u2014 esta j\u00e1 est\u00e1 desenvolvida na Escritura. N\u00f3s somos chamados a estud\u00e1-la, entend\u00ea-la, e a sermos praticantes, n\u00e3o somente ouvintes.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2021-05-27T20:00:29+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/05\/Praticantes-na\u0303o-somente-ouvintes.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Burk Parsons","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Burk Parsons","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/"},"author":{"name":"Burk Parsons","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/c29938440a404a2b117d1edbcdff8ecf"},"headline":"Praticantes, n\u00e3o somente ouvintes","datePublished":"2021-05-27T20:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/"},"wordCount":565,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/05\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1","keywords":["Fazendo Teologia","Minist\u00e9rio Ligonier"],"articleSection":["Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/","name":"Praticantes, n\u00e3o somente ouvintes","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/05\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1","datePublished":"2021-05-27T20:00:29+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/05\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/05\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/05\/praticantes-nao-somente-ouvintes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Praticantes, n\u00e3o somente ouvintes"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/c29938440a404a2b117d1edbcdff8ecf","name":"Burk Parsons","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Burk-Parsons_avatar_1410793123.jpg","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Burk-Parsons_avatar_1410793123.jpg","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2014\/09\/Burk-Parsons_avatar_1410793123.jpg","caption":"Burk Parsons"},"description":"Burk Parsons \u00e9 pastor na Saint Andrew\u2019s Chapel, em Sanford (Fl\u00f3rida), e editor da revista mensal Tabletalk, publicada por Ligonier Ministries.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/burk-parsons\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-fcK","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/05\/Praticantes-na%CC%83o-somente-ouvintes.jpg?fit=750%2C395&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=58450"}],"version-history":[{"count":3,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58450\/revisions"}],"predecessor-version":[{"id":58454,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58450\/revisions\/58454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/58451"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=58450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=58450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=58450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}