{"id":58936,"date":"2021-04-28T16:00:19","date_gmt":"2021-04-28T19:00:19","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=58936"},"modified":"2021-06-23T16:42:04","modified_gmt":"2021-06-23T19:42:04","slug":"onde-estava-jesus-em-meu-sofrimento","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/","title":{"rendered":"Onde estava Jesus em meu sofrimento?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<em>Este \u00e9 um trecho adaptado do novo livro de Mez McConnell, The Creaking on the Stairs: Finding Faith in God through Childhood Abuse. Encomende o livro atrav\u00e9s da 10ofThose. Cada compra feita atrav\u00e9s da 10ofthose ajuda a apoiar o trabalho do 20schemes.<\/em><\/p>\n<p>Eu ou\u00e7o o primeiro baque antes de ouvir sua voz. \u201cMexa-se, sua espasm\u00f3dica est\u00fapida!\u201d. Mais baques se seguem. Baque! Baque! Baque! Eu me esgueiro at\u00e9 o topo do patamar e espreito minha cabe\u00e7a escada abaixo. Minha irm\u00e3 deficiente est\u00e1 sendo arrastada pelos cabelos pelo corredor abaixo. Quem sabe o que ela fez para incorrer em sua ira desta vez.<\/p>\n<p>Estou feliz por n\u00e3o ser eu.<\/p>\n<p>Ela chuta a porta da sala e arrasta minha irm\u00e3 por ela. Minha irm\u00e3 n\u00e3o est\u00e1 lutando. N\u00e3o faz sentido lutar. Isso s\u00f3 iria piorar a dor, ent\u00e3o ela apenas tenta se mover o mais r\u00e1pido que pode para n\u00e3o perder muitos tufos de cabelo. N\u00f3s dois nos tornamos profissionais, ao longo dos anos, em tentar minimizar a dor tanto quanto podemos.<\/p>\n<p>\u00c9 o choramingo que nunca esquecerei. Como um animal ferido \u00e0 beira da estrada. N\u00e3o gritando. N\u00e3o chorando. Apenas choramingando de mis\u00e9ria, confus\u00e3o e dor.<\/p>\n<p>Eu as sigo pela porta a uma dist\u00e2ncia segura. Eu n\u00e3o quero me colocar na linha de fogo. Elas est\u00e3o na cozinha agora e minha irm\u00e3 foi arrastada para a pia. \u201cComo voc\u00ea chama isso?\u201d Minha irm\u00e3 n\u00e3o diz nada. Apenas solu\u00e7os, \u201cResponda-me!\u201d, Ela grita, com saliva escorrendo de seu queixo. \u201cUma . . . uma . . . uma colher?\u201d minha irm\u00e3 consegue dizer. \u201cBem, o que isso est\u00e1 fazendo a\u00ed?\u201d . . . Eu . . . n\u00e3o sei. \u201cSem aviso, ela bate a cabe\u00e7a de minha irm\u00e3 na beirada da pia ela desliza para o ch\u00e3o atordoada. \u201cVoc\u00ea n\u00e3o passa de uma espasm\u00f3dica pregui\u00e7osa!\u201d Ela a acerta no est\u00f4mago. \u201cLevante-se do ch\u00e3o e lave-a.\u201d<\/p>\n<p>Ela se vira em dire\u00e7\u00e3o \u00e0 sala de estar e ent\u00e3o eu corro o mais r\u00e1pido que posso para o meu quarto e fecho a porta silenciosamente. Poucos minutos depois, ou\u00e7o os passos da minha irm\u00e3, mancando de volta para o quarto. Eu ou\u00e7o a porta dela fechar e ent\u00e3o ou\u00e7o o som familiar de choro abafado. Ela n\u00e3o ousa chorar muito alto, pois isso pode deix\u00e1-la ainda mais irritada. Eu quero ir at\u00e9 l\u00e1 e dizer a ela que vai ficar tudo bem. Mas eu sei que n\u00e3o vai. E eu sei que em algum momento hoje ser\u00e1 a minha vez de enfrentar a raiva e sentir a dor de qualquer tortura que ela queira me infligir.<\/p>\n<p>Portanto, n\u00e3o fa\u00e7o nada. Sento-me na cama, me sentindo mal por minha irm\u00e3 sofrer tanto, tremendo de terror, chorando baixinho comigo mesmo.<\/p>\n<p>Esperando minha vez. Esperando ouvir aquele som familiar do rangido na escada.<\/p>\n<h2>Jesus e sofrimento<\/h2>\n<p>No final de sua vida, Jesus conheceu bem a dor. Realmente n\u00e3o entendemos a dor que ele passou na cruz. Lembro-me de quando <em>A Paix\u00e3o de Cristo<\/em> foi lan\u00e7ado no cinema e muitas pessoas sa\u00edram, incomodadas com a natureza gr\u00e1fica da viol\u00eancia. A crucifica\u00e7\u00e3o era uma maneira terr\u00edvel de morrer. Foi uma das piores e mais malignas formas de tortura inventadas pela ra\u00e7a humana. Na \u00e9poca dos romanos, a crucifica\u00e7\u00e3o era reservada para o pior dos criminosos: traidores e assassinos.<\/p>\n<p>Mas, antes de chegarmos \u00e0 cruz, lemos, em Jo\u00e3o 19.1 que Pilatos entregou Jesus para ser a\u00e7oitado. Nos dias de Jesus, a\u00e7oites eram uma coisa comum. At\u00e9 os judeus tinham uma lei que limitava o n\u00famero de vezes que uma pessoa poderia ser a\u00e7oitada. Para eles, era no m\u00e1ximo 39 vezes. Mas os romanos levaram o a\u00e7oite a um n\u00edvel totalmente novo. Chamaram isso de flagelo e foi planejado propositalmente para ser o mais doloroso poss\u00edvel. Os chicotes usados \u200b\u200btinham pelo menos tr\u00eas tiras, cada uma com pesos de bolas de chumbo ou ossos de animais. Eles foram projetados especificamente para rasgar a pele com o contato. Eles teriam tirado a roupa de Jesus, amarrado e chicoteado sem piedade at\u00e9 que ele se transformasse em uma polpa de sangue.<\/p>\n<p>Novamente, a coisa toda era controlada e deliberada. Pessoas eram conhecidas por morrer de a\u00e7oite ao longo dos anos, ent\u00e3o os romanos aperfei\u00e7oaram a arte de infligir dor apenas o suficiente para garantir que uma pessoa sofresse, mas n\u00e3o morresse imediatamente. Em outras palavras, eles sabiam como prolongar o sofrimento.<\/p>\n<p>Lemos em Mateus 27.26 que depois que Jesus foi a\u00e7oitado, ele foi entregue para ser crucificado. N\u00e3o teria havido dignidade nisso, quando Jesus se encaminhou para o local da crucifica\u00e7\u00e3o. Espancado e sangrando, cercado por multid\u00f5es zombeteiras por todos os lados. Pobre Maria sendo obrigada a v\u00ea-lo sofrer. Uma coroa de espinhos foi cravada em sua cabe\u00e7a, causando ainda mais dor e tormento.<\/p>\n<p>E quando chegou ao Calv\u00e1rio, ele foi lan\u00e7ado em cima de uma estaca de madeira, e pregos de quinze cent\u00edmetros foram cravados em Suas m\u00e3os. A dor disso teria percorrido seu corpo ensanguentado. Os p\u00e9s v\u00eam em seguida, a dor sem d\u00favida \u00e9 excruciante. Qualquer leve movimento agora teria causado uma agonia indescrit\u00edvel para Jesus. Quando a cruz \u00e9 levantada e plantada no ch\u00e3o, o trauma disso causaria ondas de choque em seu corpo ferido.<\/p>\n<p>O peso de seu corpo e a terr\u00edvel perda de sangue teriam feito seu corpo ceder. Isso, por sua vez, teria rasgado suas m\u00e3os. Ao mover-se para tirar a press\u00e3o de suas m\u00e3os, ele teria colocado mais press\u00e3o em seus p\u00e9s. Os pregos agora rasgam os m\u00fasculos de seus p\u00e9s. Inevitavelmente, ele se cansa e come\u00e7a a ceder novamente. Agora h\u00e1 press\u00e3o no peito e nos pulm\u00f5es. \u00c9 dif\u00edcil respirar. Mas n\u00e3o h\u00e1 nada que ele possa fazer para aliviar sua dor e sofrimento. Qualquer movimento agora significa agonia indescrit\u00edvel.<\/p>\n<p>Depois de tr\u00eas horas nesse estado, a B\u00edblia registra que Jesus deu seu \u00faltimo suspiro.<\/p>\n<p>Agora, neste ponto da hist\u00f3ria, podemos ser perdoados por sentir pena de Jesus. Pela injusti\u00e7a de um homem inocente ter que passar por tudo isso. Se esse fosse o fim da hist\u00f3ria, sim, seria triste, mas n\u00e3o seria \u00fanico. N\u00e3o seria especial. Afinal, muitos homens e mulheres foram mortos ilegalmente ao longo dos anos. Muitas pessoas inocentes foram para a morte. Muitos deles foram torturados e assassinados de forma igualmente horr\u00edvel. Eles foram mortos de fome, fervidos at\u00e9 a morte, servindo de alimento para animais selvagens, decapitados, usados \u200b\u200bcomo tochas humanas, queimados at\u00e9 a morte. Tudo pelo crime de ser crist\u00e3o. Na verdade, o solo de nosso planeta est\u00e1 encharcado com o sangue de m\u00e1rtires crist\u00e3os ao longo dos tempos.<\/p>\n<p>Mas havia algo diferente nessa morte. Algo not\u00e1vel.<\/p>\n<p>Jesus <em>voluntariamente<\/em> se ofereceu para morrer dessa forma cruel e b\u00e1rbara.[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Mez McConnell. \u00a9 20schemes. Website: <a href=\"https:\/\/20schemes.com\/pt-br\/\" target=\"_blank\" rel=\"noopener\">20schemes.com<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/20schemesequip.com\/where-jesus-in-my-suffering\/\">Where Was Jesus in My Suffering?<\/a><\/p>\n<p>Original: Onde estava Jesus em meu sofrimento? \u00a9 Minist\u00e9rio Fiel. Website: <a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener\">MinisterioFiel.com.br<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Paulo Reiss Junior. Revis\u00e3o: Filipe Castelo Branco.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>O solo de nosso planeta est\u00e1 encharcado com o sangue de m\u00e1rtires crist\u00e3os ao longo dos tempos.<\/p>\n","protected":false},"author":422,"featured_media":58937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"\"O solo de nosso planeta est\u00e1 encharcado com o sangue de m\u00e1rtires crist\u00e3os ao longo dos tempos.\" \u2014Mez McConnell","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[409],"tags":[897],"class_list":["post-58936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-crista","tag-igreja-para-a-periferia-20schemes","tema-sofrimento","tema-sofrimento-dup","tema-vida-crista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Onde estava Jesus em meu sofrimento?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Onde estava Jesus em meu sofrimento?\" \/>\n<meta property=\"og:description\" content=\"O solo de nosso planeta est\u00e1 encharcado com o sangue de m\u00e1rtires crist\u00e3os ao longo dos tempos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-28T19:00:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-23T19:42:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/06\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mez McConnell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mez McConnell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/\"},\"author\":{\"name\":\"Mez McConnell\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/16ed25e9425ec13faec54df31da35da1\"},\"headline\":\"Onde estava Jesus em meu sofrimento?\",\"datePublished\":\"2021-04-28T19:00:19+00:00\",\"dateModified\":\"2021-06-23T19:42:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/\"},\"wordCount\":1289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"Igreja para a Periferia - 20schemes\"],\"articleSection\":[\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/\",\"name\":\"Onde estava Jesus em meu sofrimento?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2021-04-28T19:00:19+00:00\",\"dateModified\":\"2021-06-23T19:42:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/04\\\/onde-estava-jesus-em-meu-sofrimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onde estava Jesus em meu sofrimento?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/16ed25e9425ec13faec54df31da35da1\",\"name\":\"Mez McConnell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"url\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"contentUrl\":\"http:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Mez-McConnell_avatar_1522880470-96x96.jpg\",\"caption\":\"Mez McConnell\"},\"description\":\"\u00c9 pastor s\u00eanior da Niddrie Community Church, Edimburgo, Esc\u00f3cia. \u00c9 fundador do 20schemes, um minist\u00e9rio voltado para planta\u00e7\u00e3o de igrejas nos lugares mais dif\u00edceis da Esc\u00f3cia. Desde 1999, McConnell tem se envolvido com o minist\u00e9rio pastoral, tanto em planta\u00e7\u00e3o quanto revitaliza\u00e7\u00e3o.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/mez-mcconnell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Onde estava Jesus em meu sofrimento?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/","og_locale":"pt_BR","og_type":"article","og_title":"Onde estava Jesus em meu sofrimento?","og_description":"O solo de nosso planeta est\u00e1 encharcado com o sangue de m\u00e1rtires crist\u00e3os ao longo dos tempos.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2021-04-28T19:00:19+00:00","article_modified_time":"2021-06-23T19:42:04+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/06\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Mez McConnell","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Mez McConnell","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/"},"author":{"name":"Mez McConnell","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/16ed25e9425ec13faec54df31da35da1"},"headline":"Onde estava Jesus em meu sofrimento?","datePublished":"2021-04-28T19:00:19+00:00","dateModified":"2021-06-23T19:42:04+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/"},"wordCount":1289,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/06\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1","keywords":["Igreja para a Periferia - 20schemes"],"articleSection":["Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/","name":"Onde estava Jesus em meu sofrimento?","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/06\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1","datePublished":"2021-04-28T19:00:19+00:00","dateModified":"2021-06-23T19:42:04+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/06\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/06\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/04\/onde-estava-jesus-em-meu-sofrimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Onde estava Jesus em meu sofrimento?"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/16ed25e9425ec13faec54df31da35da1","name":"Mez McConnell","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","url":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","contentUrl":"http:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/04\/Mez-McConnell_avatar_1522880470-96x96.jpg","caption":"Mez McConnell"},"description":"\u00c9 pastor s\u00eanior da Niddrie Community Church, Edimburgo, Esc\u00f3cia. \u00c9 fundador do 20schemes, um minist\u00e9rio voltado para planta\u00e7\u00e3o de igrejas nos lugares mais dif\u00edceis da Esc\u00f3cia. Desde 1999, McConnell tem se envolvido com o minist\u00e9rio pastoral, tanto em planta\u00e7\u00e3o quanto revitaliza\u00e7\u00e3o.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/mez-mcconnell\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/06\/Onde-estava-Jesus-em-meu-sofrimento.jpg?fit=750%2C395&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-fkA","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/422"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=58936"}],"version-history":[{"count":3,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58936\/revisions"}],"predecessor-version":[{"id":58940,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/58936\/revisions\/58940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/58937"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=58936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=58936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=58936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}