{"id":59174,"date":"2021-07-08T21:30:21","date_gmt":"2021-07-09T00:30:21","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=59174"},"modified":"2021-07-08T16:19:05","modified_gmt":"2021-07-08T19:19:05","slug":"uma-oracao-pela-igreja-galatas-5-16-26","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/","title":{"rendered":"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<article id=\"post-16205\" class=\"entry post-16205 post type-post status-publish format-standard has-post-thumbnail hentry\">\n<div class=\"row\">\n<div class=\"col-sm-10 col-sm-offset-1\">\n<div class=\"entry-content\">\n<p>Pai nosso que est\u00e1s no c\u00e9u, nos alegramos em recordar que, guardados na santidade de Cristo, voc\u00ea nos considera santos aos teus olhos. N\u00e3o apenas quando oramos \u2013 mas sempre \u2013 o Senhor nos enxerga como santos, separados por nosso Salvador e para nosso Salvador.<\/p>\n<p>Por\u00e9m, vivemos esperan\u00e7osos que aquilo que vemos pela f\u00e9, um dia veremos com nossos pr\u00f3prios olhos. Certamente voc\u00ea nos entender\u00e1, Pai, se pedirmos, hoje, um vislumbre daquilo que veremos no futuro. Seguramente, o Senhor ignorar\u00e1 nossa impaci\u00eancia se suplicarmos que o Senhor continue a trabalhar em nossa vida a justi\u00e7a e a poderosa ressurrei\u00e7\u00e3o que temos em Cristo.<\/p>\n<p>Pai, sabemos que aquilo que seremos, de fato \u00e9 o que dever\u00edamos ser. Entretanto, em nossas conversas, somos mordazes e destru\u00edmos uns aos outros \u2013 nos inquietamos que na neglig\u00eancia com nossas palavras nos consumiremos. Sonhamos andar pelo Esp\u00edrito. Acordamos e, mais uma vez, satisfazemos os desejos da carne.<\/p>\n<p>Pedimos, ent\u00e3o, tua dire\u00e7\u00e3o. Leva-nos para longe dos p\u00e2ntanos da imoralidade sexual, sensualidade e impureza. Por mais doloroso que seja, exponha nossas inclina\u00e7\u00f5es \u00e0 idolatria, nossa fraqueza secreta e as nossas supersti\u00e7\u00f5es tolas. Nos fortifica contra pecados expostos e escandalosos, contra a embriaguez e at\u00e9 mesmo orgias e coisas semelhantes. Proteja-nos em nossas amizades e mantenha nossa fam\u00edlia longe do mal, das inimizades, disc\u00f3rdias e ataques de ira. Queremos tua ajuda enquanto lutamos com esp\u00edritos invejosos, ci\u00fames e dissens\u00f5es. Retenha o mal, n\u00f3s clamamos; nos refreia: atenta para nossa incredulidade, nossas ambi\u00e7\u00f5es rebeldes, nossos pensamentos amargos.<\/p>\n<p>O que n\u00f3s oramos por n\u00f3s mesmos e por nossos entes queridos, tamb\u00e9m oramos por tua Igreja. Defende tua noiva e protege-a do ataque de seus inimigos. Mant\u00e9m-na longe das horr\u00edveis dissens\u00f5es e das deformidades que v\u00eam das divis\u00f5es. Torna-a t\u00e3o santa quanto as pessoas que h\u00e3o de herdar o teu reino possam ser.<\/p>\n<p>Pai, n\u00f3s pedimos todas essas coisas. Ousamos pedir ainda mais? Voc\u00ea nos permitir\u00e1 ver uma \u00e9poca em nossas vidas quando o fruto do Esp\u00edrito ser\u00e1 evidente a todos? Voc\u00ea far\u00e1 de sua igreja um lugar onde o amor leva \u00e0 a\u00e7\u00e3o, onde a alegria \u00e9 profunda, onde cora\u00e7\u00f5es pac\u00edficos produzem pessoas pacientes? O Senhor nos dar\u00e1 o prazer de ver a bondade entre as crian\u00e7as crist\u00e3s? Voc\u00ea nos possibilitar\u00e1 ver um dia em que a busca pela verdadeira bondade ser\u00e1 tipificada em nossos jovens, homens e mulheres? Onde a fidelidade marcar\u00e1 nossos casamentos, onde a gentileza e o dom\u00ednio pr\u00f3prio ser\u00e3o as caracter\u00edsticas proeminentes de nossos pais e de nossos pastores?<\/p>\n<p>Se pertencemos a Cristo Jesus, por favor, crucifique nossa carne, com suas paix\u00f5es e concupisc\u00eancias. Se vivemos pelo Esp\u00edrito, por favor, mantenha-nos em sintonia com o seu Esp\u00edrito. N\u00e3o nos deixe ser convencidos, provocando um ao outro, tendo inveja um do outro. Deixe-nos contentes, promovendo e elevando o outro.<\/p>\n<p>Chegamos a ti com esses pedidos, porque n\u00e3o h\u00e1 mais ningu\u00e9m que possa fazer as maravilhas que desejamos testemunhar. N\u00f3s viemos a ti, porque o Senhor nos redimiu para que possamos dar o fruto do seu Esp\u00edrito. Negar esses pedidos seria negar seus santos e pr\u00f3prios prop\u00f3sitos, at\u00e9 mesmo negar a si mesmo! Portanto, nos ou\u00e7a e nos responda pelo seu pr\u00f3prio nome, n\u00f3s te confessamos \u00fanico Deus, Pai, Filho e Esp\u00edrito Santo. Am\u00e9m.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<p>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Chad Van Dixhoorn. \u00a9 Alliance of Confessing Evangelicals. Website: <a href=\"https:\/\/www.reformation21.org\/\">reformation21.org<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/www.reformation21.org\/blogs\/a-prayer-for-the-church-galati.php\">A Prayer for the Church (Galatians 5:16-26)<\/a>.<\/p>\n<p>Original: <a href=\"https:\/\/wp.me\/p4MFiq-foq\">Uma ora\u00e7\u00e3o pela Igreja (G\u00e1latas 5.16-26)<\/a>. \u00a9 Minist\u00e9rio Fiel. Website:\u00a0<a href=\"http:\/\/www.ministeriofiel.com.br\/\" target=\"_blank\" rel=\"noopener\">MinisterioFiel.com.br<\/a>. Todos os direitos reservados.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Pai nosso que est\u00e1s no c\u00e9u, nos alegramos em recordar que, guardados na santidade de Cristo, voc\u00ea nos considera santos aos teus olhos.<\/p>\n","protected":false},"author":806,"featured_media":59175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Pai nosso que est\u00e1s no c\u00e9u, nos alegramos em recordar que, guardados na santidade de Cristo, voc\u00ea nos considera santos aos teus olhos.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3062],"tags":[2531],"class_list":["post-59174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-igreja-eclesiologia","tag-alliance-of-confessing-evangelicals","tema-igreja-e-ministerio","tema-a-oracao","tema-oracao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)\" \/>\n<meta property=\"og:description\" content=\"Pai nosso que est\u00e1s no c\u00e9u, nos alegramos em recordar que, guardados na santidade de Cristo, voc\u00ea nos considera santos aos teus olhos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-09T00:30:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/07\/Uma-orac\u0327a\u0303o-pela-igreja.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chad Van Dixhoorn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chad Van Dixhoorn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/\"},\"author\":{\"name\":\"Chad Van Dixhoorn\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/d2ce73064edacb71d6cc2d4586faf932\"},\"headline\":\"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)\",\"datePublished\":\"2021-07-09T00:30:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/\"},\"wordCount\":687,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"Alliance of Confessing Evangelicals\"],\"articleSection\":[\"Igreja (eclesiologia)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/\",\"name\":\"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2021-07-09T00:30:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/uma-oracao-pela-igreja-galatas-5-16-26\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/d2ce73064edacb71d6cc2d4586faf932\",\"name\":\"Chad Van Dixhoorn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9ddeea7408aa5ba2861e272cb643977d51e0d68e82e91207ebe2f8f496fd2e4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9ddeea7408aa5ba2861e272cb643977d51e0d68e82e91207ebe2f8f496fd2e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9ddeea7408aa5ba2861e272cb643977d51e0d68e82e91207ebe2f8f496fd2e4?s=96&d=mm&r=g\",\"caption\":\"Chad Van Dixhoorn\"},\"description\":\"Chad Van Dixhoorn \u00e9 pastor associado da Grace Presbyterian Church em Viena, Virg\u00ednia, e pesquisador s\u00eanior do Wolfson College em Cambridge, Reino Unido.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/chad-van-dixhoorn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/","og_locale":"pt_BR","og_type":"article","og_title":"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)","og_description":"Pai nosso que est\u00e1s no c\u00e9u, nos alegramos em recordar que, guardados na santidade de Cristo, voc\u00ea nos considera santos aos teus olhos.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2021-07-09T00:30:21+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/07\/Uma-orac\u0327a\u0303o-pela-igreja.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Chad Van Dixhoorn","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Chad Van Dixhoorn","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/"},"author":{"name":"Chad Van Dixhoorn","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/d2ce73064edacb71d6cc2d4586faf932"},"headline":"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)","datePublished":"2021-07-09T00:30:21+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/"},"wordCount":687,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/07\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1","keywords":["Alliance of Confessing Evangelicals"],"articleSection":["Igreja (eclesiologia)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/","name":"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/07\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1","datePublished":"2021-07-09T00:30:21+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/07\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/07\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/uma-oracao-pela-igreja-galatas-5-16-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Uma ora\u00e7\u00e3o pela igreja (G\u00e1latas 5.16-26)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/d2ce73064edacb71d6cc2d4586faf932","name":"Chad Van Dixhoorn","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d9ddeea7408aa5ba2861e272cb643977d51e0d68e82e91207ebe2f8f496fd2e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9ddeea7408aa5ba2861e272cb643977d51e0d68e82e91207ebe2f8f496fd2e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9ddeea7408aa5ba2861e272cb643977d51e0d68e82e91207ebe2f8f496fd2e4?s=96&d=mm&r=g","caption":"Chad Van Dixhoorn"},"description":"Chad Van Dixhoorn \u00e9 pastor associado da Grace Presbyterian Church em Viena, Virg\u00ednia, e pesquisador s\u00eanior do Wolfson College em Cambridge, Reino Unido.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/chad-van-dixhoorn\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/07\/Uma-orac%CC%A7a%CC%83o-pela-igreja.jpg?fit=750%2C395&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-foq","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/59174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/806"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=59174"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/59174\/revisions"}],"predecessor-version":[{"id":59177,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/59174\/revisions\/59177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/59175"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=59174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=59174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=59174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}