{"id":60092,"date":"2021-10-13T17:00:49","date_gmt":"2021-10-13T20:00:49","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=60092"},"modified":"2021-10-04T17:42:45","modified_gmt":"2021-10-04T20:42:45","slug":"o-pensamento-grego-e-a-igreja-crista-parte-32","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/","title":{"rendered":"O pensamento grego e a igreja crist\u00e3 (Parte 32)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_btn title=&#8221;S\u00e9rie &#8220; O pensamento grego e a igreja crist\u00e3&#8220; | Clique para ler os outros artigos&#8221; size=&#8221;sm&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Ffiel.in%2F3aJBHzG|||&#8221;][vc_column_text]<\/p>\n<h3>Armas poderosas em Deus<\/h3>\n<p>Retornando \u00e0 quest\u00e3o tratada por Paulo, perguntamos: as armas que temos s\u00e3o poderosas em Deus para qu\u00ea? Analisemos a progress\u00e3o do seu pensamento:<\/p>\n<p>a) <em>\u201cPara destruir<\/em><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> <em>fortalezas\u201d<\/em> (* o)xu\/rwma)<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> (2Co 10.4<em>).<\/em> A palavra \u201cfortaleza\u201d, s\u00f3 ocorre aqui no NT, e tem um emprego secular de fortaleza de palavras, de argumentos presumivelmente considerados fortes e indestrut\u00edveis. Metaforicamente, a express\u00e3o indica conceitos especulativos que se erguem contra a cruz de Cristo. O Esp\u00edrito, por meio da Palavra, destr\u00f3i a nossa forma viciada de pensar que obstaculizava a compreens\u00e3o do Evangelho.<\/p>\n<p>b) <em>\u201cAnulando sofismas\u201d<\/em> (logismo\/j):<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a> Toda a sabedoria carnal em oposi\u00e7\u00e3o ao saber espiritual.<\/p>\n<p>c) <em>\u201cE toda altivez que se levante contra o conhecimento de Deus\u201d <\/em>(2Co 10.5). As fortalezas geralmente eram constru\u00eddas em lugares altos, sendo, portanto, mais dif\u00edcil combat\u00ea-las. Normalmente as coisas que exaltamos como sendo fundamentais e essenciais para a sua exist\u00eancia podem se constituir em fortalezas contra o conhecimento de Deus. As pessoas tendem a se julgar seguras dentro das \u201cfortalezas\u201d de seus argumentos contra o Evangelho, no entanto, os limites de pedra da raz\u00e3o e do cora\u00e7\u00e3o humano n\u00e3o servem de empecilho absoluto contra o Evangelho.<\/p>\n<p>d) <em>\u201cLevando cativo todo <u>pensamento<\/u> <\/em>(no\/hma)<em> \u00e0 obedi\u00eancia de Cristo\u201d<\/em> (2Co 10.5):<\/p>\n<p>Kruse interpreta:<\/p>\n<blockquote>\n<p style=\"text-align: left;\">Esta imagem \u00e9 a de uma fortaleza rompida; os que ali dentro se abrigavam, por detr\u00e1s de muralhas, est\u00e3o sendo levados em cativeiro. Assim \u00e9 que o prop\u00f3sito do ap\u00f3stolo n\u00e3o \u00e9 apenas demolir os falsos argumentos, como tamb\u00e9m conduzir os pensamentos das pessoas sob o senhorio de Cristo. Seu apelo como ap\u00f3stolo era implantar \u2018a obedi\u00eancia por f\u00e9, entre todos os gentios\u2019 (Rm 1.5).<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a><\/p>\n<\/blockquote>\n<p>Somente desse modo \u2212 por interm\u00e9dio do crescimento espiritual que consiste na obedi\u00eancia a Deus \u2212 \u00e9 poss\u00edvel, como diz Paulo aos ef\u00e9sios, <em>\u201cque n\u00e3o mais andeis como tamb\u00e9m andam os gentios na <u>vaidade<\/u> <\/em>(mataio\/thj)<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a> <em>dos seus pr\u00f3prios <u>pensamentos<\/u> <\/em>(nou=j),<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a> <em>obscurecidos de <u>entendimento<\/u><\/em> (dia\/noia),<a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a> <em>alheios \u00e0 vida de Deus por causa da <u>ignor\u00e2ncia<\/u><\/em> (a)\/gnoia)<em> em que vivem, pela dureza dos seus cora\u00e7\u00f5es&#8230;\u201d<\/em> (Ef 4.17-18).<\/p>\n<p>Se Deus desconsiderou a nossa antiga ignor\u00e2ncia (At 17.30); agora que Ele nos deu a conhecer a sua Palavra, tornando-nos \u201cfilhos da obedi\u00eancia\u201d, n\u00e3o deseja que tornemos \u00e0s nossas pr\u00e1ticas antigas, dominadas pelas paix\u00f5es. \u00c9 isso que escreve Pedro \u00e0s igrejas: <em>\u201cComo filhos da obedi\u00eancia, n\u00e3o vos amoldeis \u00e0s paix\u00f5es que t\u00ednheis anteriormente na vossa <u>ignor\u00e2ncia<\/u> <\/em>(a)\/gnoia)<em>\u201d<\/em> (1Pe 1.14).<\/p>\n<p>Portanto, podemos inferir que n\u00e3o h\u00e1 o que temer diante da oposi\u00e7\u00e3o erguida contra o ensino da f\u00e9 crist\u00e3. A sabedoria carnal \u00e9 oposta \u00e0 sabedoria espiritual e esta a sobrepuja.<\/p>\n<p>Na Palavra, temos todos os recursos necess\u00e1rios para combater o erro e apresentar a mensagem crist\u00e3 de forma clara e objetiva. A verdade b\u00edblica \u00e9 capaz de apresentar de forma coerente a f\u00e9 crist\u00e3 e sobrepujar toda forma de racioc\u00ednio que lhe \u00e9 hostil. Deste modo, a Igreja se alimenta da Palavra e nela encontra o discernimento de Deus para entender e avaliar todas as coisas.<\/p>\n<p>Assim sendo, devemos ressaltar que o Evangelho n\u00e3o \u00e9 irracional nem obscurantista, no sentido de que nega o saber, antes aponta na dire\u00e7\u00e3o de uma mente submissa a Cristo, que procura interpretar a realidade a partir da mente de Cristo, n\u00e3o da \u201cmente\u201d de Satan\u00e1s. Por isso, a prega\u00e7\u00e3o do evangelho envolve racioc\u00ednios e argumentos: Lucas registra que em Corinto: <em>\u201cTodos os s\u00e1bados (Paulo) <u>discorria<\/u> <\/em>(diale\/gomai) <em>na sinagoga, persuadindo tanto judeus como gregos\u201d<\/em> (At 18.4). Este era o m\u00e9todo habitual de Paulo.<\/p>\n<p>Ele usou do mesmo recurso na sinagoga de Tessal\u00f4nica (At 17.2); na sinagoga e na pra\u00e7a de Atenas (At 17.17); na sinagoga de \u00c9feso e na escola de Tirano durante dois anos (At 18.19; 19.8-10), na igreja em Tr\u00f4ade (At 20.7,9) e diante de violento Procurador F\u00e9lix (At 24.25).<\/p>\n<p>Ap\u00f3s a ressurrei\u00e7\u00e3o de Cristo os disc\u00edpulos ainda n\u00e3o entendiam adequadamente as Escrituras em rela\u00e7\u00e3o ao Messias, Jesus Cristo. Com dois deles, no caminho de Ema\u00fas, o Senhor abriu-lhes os olhos para que a compreendessem e cressem por meio da exposi\u00e7\u00e3o das Escrituras. Foi esta a percep\u00e7\u00e3o deles.<\/p>\n<p>Narra Lucas:<\/p>\n<p><em>E aconteceu que, quando estavam \u00e0 mesa, tomando ele o p\u00e3o, aben\u00e7oou-o e, tendo-o partido, lhes deu; ent\u00e3o, se lhes <u>abriram<\/u> (dianoi\/gw) os olhos, e o reconheceram; mas ele desapareceu da presen\u00e7a deles. E disseram um ao outro: Porventura, n\u00e3o nos ardia o cora\u00e7\u00e3o, quando ele, pelo caminho, nos falava, quando nos <u>expunha<\/u> (dianoi\/gw) as Escrituras? (Lc 24.30-32).<\/em><\/p>\n<p>Agora, com os demais disc\u00edpulos, Jesus mostra como as Escrituras se cumpriram em seu minist\u00e9rio, vida, morte e ressurrei\u00e7\u00e3o. Lucas resume: <em>\u201cEnt\u00e3o, lhes <u>abriu<\/u> <\/em>(dianoi\/gw) <em>o <u>entendimento<\/u> <\/em>(nou=j) <em>para <u>compreenderem<\/u> <\/em>(suni\/hmi) <em>as Escrituras\u201d<\/em> (Lc 24.45).<\/p>\n<p>De passagem, podemos observar que o caminho para atingir a mente e o cora\u00e7\u00e3o das pessoas \u00e9 a exposi\u00e7\u00e3o da Palavra. O Esp\u00edrito que opera por meio dela n\u00e3o for\u00e7a as evid\u00eancias, nem nos obriga a diminuir a nossa capacidade de pensar, antes, nos faz enxergar e crer nas evid\u00eancias (At 3.16; 16.14; 18.27; Rm 4.16; 1Co 3.5; Fp 1.29).<\/p>\n<p>Lucas relata:<\/p>\n<p><em>Paulo, segundo o seu costume, foi procur\u00e1-los e, por tr\u00eas s\u00e1bados, <u>arrazoou<\/u> (diale\/gomai) com eles acerca das Escrituras, <u>expondo<\/u> (dianoi\/gw = \u201cexplicando\u201d, \u201cinterpretando\u201d) e demonstrando ter sido necess\u00e1rio que o Cristo padecesse e ressurgisse dentre os mortos, e este, dizia ele, \u00e9 o Cristo, Jesus, que eu vos anuncio\u201d (At 17.3).\u00a0<\/em><\/p>\n<p>Devemos entender que Deus age ordinariamente por meio da Palavra. Pela Palavra ouvimos, cremos, recebemos e acolhemos a mensagem de Deus (Jo 17.6-8). N\u00e3o h\u00e1 experi\u00eancia mais significativa do que esta.<\/p>\n<p>LLoyd-Jones\u00a0 (1899-1981) \u00e9 bastante enf\u00e1tico neste ponto:<\/p>\n<blockquote>\n<p style=\"text-align: left;\">O Esp\u00edrito Santo n\u00e3o produz mera experi\u00eancia, o Esp\u00edrito Santo usa a Palavra. Ele \u00e9 o Esp\u00edrito da verdade, o Esp\u00edrito que ilumina, Ele \u00e9 o Esp\u00edrito que leva-nos ao entendimento. Jamais devemos lan\u00e7ar fora o intelecto que Deus nos deu. N\u00e3o \u00e9 preciso fazer isso. O Esp\u00edrito Santo pode operar no nosso c\u00e9rebro como em qualquer outra parte de n\u00f3s. \u00c9 falso o ensino que concita as pessoas a se soltarem. Se voc\u00ea fizer isso, ir\u00e1 cair numa libertinagem da imagina\u00e7\u00e3o e dos sentimentos, estar\u00e1 indo aos maus esp\u00edritos e maus poderes que est\u00e3o ao seu redor e que est\u00e3o sempre prontos para tomar posse de voc\u00ea e para fazer voc\u00ea de bobo.<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a><\/p>\n<\/blockquote>\n<p>Paulo sabia, n\u00f3s sabemos, que as armas devem ser usadas de acordo com o inimigo e o tipo de guerra. A ignor\u00e2ncia a respeito de nossos verdadeiros alvos pode nos conduzir a uma exaust\u00e3o frustrante.<\/p>\n<p>Temos de aprender a identificar, por exemplo, como o pensamento secular assume caracter\u00edsticas pr\u00f3prias em nossa gera\u00e7\u00e3o a fim de pod\u00ea-lo combater de forma eficiente.<a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a><\/p>\n<p>Davi, por exemplo, quando foi lutar contra o gigante Golias escolheu, criteriosamente, as pedras para usar em sua funda: <em>\u201cTomou o seu cajado na m\u00e3o, e <u>escolheu<\/u> <\/em>(rAhfB [B\u00e3har])<a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a><em> para si cinco pedras lisas do ribeiro&#8230;\u201d<\/em> (1Sm 17.40). Davi confiava em Deus e usou dos recursos de que dispunha e, neste caso, com os quais estava bem familiarizado.<\/p>\n<p>Tornando a Paulo, notemos que, uma vez que a sua luta era espiritual, as suas armas deveriam ser tamb\u00e9m espirituais (2Co 10.4-5). Paulo apresenta neste texto o caminho que seguiu e que caracterizava o seu Minist\u00e9rio: colocar todo o seu saber, todo o seu pensar, todo o seu sentir sob o dom\u00ednio de Cristo, mantendo assim a sua mente aprisionada ao saber, conhecer e sentir de Cristo.<a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a> Paulo demonstra como fez isso. Destaco apenas a aplica\u00e7\u00e3o desse princ\u00edpio na prega\u00e7\u00e3o da Palavra.<\/p>\n<p>Como vimos, Paulo admite que anda na carne, ou seja, participa de todas as limita\u00e7\u00f5es humanas, contudo o seu minist\u00e9rio n\u00e3o \u00e9 caracterizado por aus\u00eancia de recursos espirituais, antes todo ele \u00e9 realizado no poder de Deus (2Co 10.4). Ele n\u00e3o andava com ast\u00facia, nem adulterando a Palavra de Deus (2Co 4.2).<a href=\"#_ftn12\" name=\"_ftnref12\">[12]<\/a> As suas armas consistiam no an\u00fancio fiel das Escrituras, por meio delas Deus opera (Rm 1.16).<a href=\"#_ftn13\" name=\"_ftnref13\">[13]<\/a><\/p>\n<p>Todo <em>pensamento<\/em> deve ser levado cativo a Cristo, contrastando com a situa\u00e7\u00e3o antiga de dom\u00ednio do pecado sobre n\u00f3s: <em>\u201c&#8230; Vejo nos meus membros outra lei que, guerreando contra a lei da minha mente, me faz <u>prisioneiro<\/u><\/em> (ai)xmalwti\/zw)<a href=\"#_ftn14\" name=\"_ftnref14\">[14]<\/a><em> da lei do pecado que est\u00e1 nos meus membros\u201d<\/em> (Rm 7.23).<\/p>\n<p>Um dos perigos para n\u00f3s crist\u00e3os \u00e9 simplesmente n\u00e3o usar a nossa mente. A nossa convers\u00e3o a Deus envolve tamb\u00e9m uma nova mente, uma nova maneira de perceber a realidade, vendo o real como de fato \u00e9. Nosso cora\u00e7\u00e3o e mente precisam ser convertidos ao Senhor.<a href=\"#_ftn15\" name=\"_ftnref15\">[15]<\/a><\/p>\n<p>Usando uma figura do te\u00f3logo luterano de Johann C. Blumhardt (1805-1880), citada por Bavinck (1854-1921), podemos dizer que o crist\u00e3o precisa passar basicamente por duas convers\u00f5es: converter-se da vida natural para a vida espiritual e depois, da vida espiritual para a vida natural. Isso pode ser ilustrado no salmo: <em>\u201cQuem mais tenho eu no c\u00e9u? N\u00e3o h\u00e1 outro em quem eu me compraza na terra\u201d <\/em>(Sl 73.25).<a href=\"#_ftn16\" name=\"_ftnref16\">[16]<\/a><\/p>\n<p>Devemos aprender a entender a vontade de Deus em todas as circunst\u00e2ncias e submetermo-nos a ela. A nossa mente deve ser t\u00e3o devotada a Deus como o nosso cora\u00e7\u00e3o. Exclu\u00ed-la, significa n\u00e3o amar a Deus como ele requer. Deus deseja que o amemos e o sirvamos tamb\u00e9m com nossa intelig\u00eancia: <em>\u201cRespondeu-lhe Jesus: Amar\u00e1s o Senhor, teu Deus, de todo o teu <u>cora\u00e7\u00e3o<\/u> <\/em>(kardi\/a)<em>, de toda a tua <u>alma<\/u> <\/em>(yuxh\/\/)<em> e de todo o teu <u>entendimento<\/u> <\/em>(dia\/noia)<em>. Este \u00e9 o grande e primeiro mandamento\u201d<\/em> (Mt 22.37-38).<\/p>\n<p>O nosso testemunho exige o uso abalizado de nossa intelig\u00eancia, a viv\u00eancia de nossa f\u00e9 na hist\u00f3ria, dentro das circunst\u00e2ncias nas quais vivemos. A rejei\u00e7\u00e3o de um racionalismo aut\u00f4nomo cuja \u00fanica refer\u00eancia seria o <em>eu<\/em> pensante, uma egorrefer\u00eancia apelidada de \u201cmaioridade\u201d, t\u00e3o sonhada pelo iluminismo, n\u00e3o significa o abandono da racionalidade na compreens\u00e3o e transmiss\u00e3o da mensagem do evangelho.<\/p>\n<p>Indicando a responsabilidade que temos de consagrar as nossas mentes ao servi\u00e7o de Deus, em 1980, Malik (1906-1987), fil\u00f3sofo e diplomata crist\u00e3o de origem libanesa, declarou na inaugura\u00e7\u00e3o do Billy Graham Center no <em>campus <\/em>do Wheaton College:<\/p>\n<blockquote>\n<p style=\"text-align: left;\">Devo ser franco com voc\u00eas: o maior perigo que o cristianismo evang\u00e9lico americano enfrenta \u00e9 o anti-intelectualismo. A mente, compreendida em suas maiores e mais profundas faculdades, n\u00e3o tem recebido suficiente aten\u00e7\u00e3o. No entanto, a educa\u00e7\u00e3o intelectual n\u00e3o ocorre sem uma profunda imers\u00e3o por alguns anos na hist\u00f3ria do pensamento e do esp\u00edrito. Aqueles que est\u00e3o com pressa de sa\u00edrem da faculdade e come\u00e7arem a ganhar dinheiro ou a servir na igreja ou a pregar o evangelho n\u00e3o t\u00eam ideia do valor infinito de se gastar anos conversando com as maiores mentes e almas do passado, desenvolvendo, afiando e ampliando seu poder de pensamento. O resultado \u00e9 que a arena do pensamento criativo \u00e9 abandonada e entregue ao inimigo. Quem, entre os acad\u00eamicos evang\u00e9licos, pode enfrentar os grandes pensadores seculares em seus pr\u00f3prios termos acad\u00eamicos? Quem, entre os acad\u00eamicos evang\u00e9licos, \u00e9 citado pelas maiores autoridades seculares como fonte normativa em hist\u00f3ria, filosofia, psicologia, sociologia ou pol\u00edtica? O modo evang\u00e9lico de pensar teria a menor chance de se tornar dominante nas grandes universidades da Europa e Am\u00e9rica que moldam toda nossa civiliza\u00e7\u00e3o com seu esp\u00edrito e suas ideias? Por uma maior efic\u00e1cia no testemunho de Jesus Cristo, assim como pela sua pr\u00f3pria causa, os evang\u00e9licos n\u00e3o podem se dar ao luxo de viver na periferia da exist\u00eancia intelectual respons\u00e1vel.<a href=\"#_ftn17\" name=\"_ftnref17\">[17]<\/a><\/p>\n<\/blockquote>\n<p>Cerca de 20 anos antes desse pronunciamento, Blamires (1916-2017), em sua obra cl\u00e1ssica, <em>A mente Crist\u00e3,<\/em> constatava com tristeza (1963):<\/p>\n<blockquote>\n<p style=\"text-align: left;\">N\u00e3o existe mais uma mente crist\u00e3. Existe ainda, naturalmente, uma \u00e9tica crist\u00e3, uma pr\u00e1tica crist\u00e3 e uma espiritualidade crist\u00e3. O crist\u00e3o moderno, como ser moral, subscreve a um c\u00f3digo diferente daquele do n\u00e3o crist\u00e3o. Como membro da igreja, ele assume obriga\u00e7\u00f5es e observ\u00e2ncias ignoradas pelo n\u00e3o-crist\u00e3o. Como ser espiritual, em ora\u00e7\u00e3o e medita\u00e7\u00e3o, ele se esfor\u00e7a para cultivar uma dimens\u00e3o de vida inexplorada pelo n\u00e3o-crist\u00e3o. Mas como um ser <em>pensante, <\/em>o crist\u00e3o moderno j\u00e1 sucumbiu \u00e0 seculariza\u00e7\u00e3o.<a href=\"#_ftn18\" name=\"_ftnref18\">[18]<\/a><\/p>\n<\/blockquote>\n<hr \/>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> kaqai\/resij = destrui\u00e7\u00e3o (* 2Co 10.4,8; 13.10). O verbo, kaqaire\/w tem o sentido de fazer descer, vencer, derrubar, destruir (Mc 15.36, 46; Lc 1.52; 12.18; 23.53; At 13.19, 29; 2Co 10.4).<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Nos papiros significa tamb\u00e9m pris\u00e3o.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a>Logismo\/j significa \u201ccomputar\u201d, \u201crefletir\u201d, \u201ccogitar\u201d, \u201cconceber\u201d, \u201craciocinar\u201d. A palavra \u00e9 proveniente de lo\/goj. O termo pode ter tamb\u00e9m o sentido de argumento falso e sofisma (* Rm 2.15 (<em>\u201cpensamentos\u201d<\/em>); 2Co 10.4). (Sentido negativo \u00e9 usado tamb\u00e9m em Pv 6.18) (logismo\/j kakoi\/).<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Colin Kruse, <em>2 Cor\u00edntios: Introdu\u00e7\u00e3o e Coment\u00e1rio,<\/em> S\u00e3o Paulo: Vida Nova; Mundo Crist\u00e3o, 1994, (2Co 10.5), p. 186.<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a>mataio\/thj (= <em>Vaidade, futilidade, vacuidade<\/em>) apresenta a ideia de aus\u00eancia de objetivos (* Rm 8.20; Ef 4.17; 2Pe 2.18). Ma\/taioj = <em>V\u00e3o, f\u00fatil, tolo, sem valor<\/em>. (*At 14.15; 1Co 3.20; 15.17; Tt 3.9; Tg 1.26; 1Pe 1.18). \u201cNa literatura grega, <em>mataios<\/em> e seus cognatos t\u00eam como pano de fundo certos valores estabelecidos, padr\u00f5es morais, realidades religiosas, verdades e fatos reconhecidos. A conduta de qualquer pessoa que os deixa passar despercebidos, deliberadamente ou sem ser consciente disso, cai sob o julgamento de ser <em>mataios<\/em>\u201d (E. Tiedtke, Vazio: In: Colin Brown, ed. ger.<em> O Novo Dicion\u00e1rio Internacional de Teologia do Novo Testamento,<\/em> v. 4, p, 692).<\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a>nou=j, da mesma raiz de no\/hma, indica a mente, pensamento, modo de pensar, atitude e a faculdade de raciocinar.<\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> dia\/noia, pensamento, disposi\u00e7\u00e3o, entendimento, intelig\u00eancia, a mente como o \u00f3rg\u00e3o do pensamento, de interpreta\u00e7\u00e3o. No texto de Ef\u00e9sios, Calvino interpreta a palavra como sendo a pr\u00f3pria capacidade de pensar (Jo\u00e3o Calvino, <em>Ef\u00e9sios,<\/em> (Ef 4.17), p. 134). (Deus deseja que O amemos com toda a nossa dia\/noia (Mt 22.37; Mc 12.30; Lc 10.27); \u00e9 Deus quem ilumina os olhos de nosso cora\u00e7\u00e3o para que possamos ter a dia\/noia (compreens\u00e3o) espiritual (Ef 1.18\/1Jo 5.20); antes disso \u00e9ramos inimigos de Deus em nossa dia\/noia (Cl 1.21); no entanto, Deus imprimiu, conforme a profecia cumprida em Cristo, a sua lei em nossa dia\/noia (Hb 8.10; 10.16). A nossa dia\/noia, portanto, deve ser revestida com a Palavra a fim de permanecer esclarecida (2Pe 3.1\/1Pe 1.13).<\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a>David Martyn Lloyd-Jones, <em>Cristianismo Aut\u00eantico: Serm\u00f5es nos Atos dos ap\u00f3stolos<\/em>, S\u00e3o Paulo: Publica\u00e7\u00f5es Evang\u00e9licas Selecionadas, 2006, v. 2, p. 260.<\/p>\n<p><a href=\"#_ftnref9\" name=\"_ftn9\">[9]<\/a>Veja-se: Francis A. Schaeffer, <em>O Deus que Interv\u00e9m, <\/em>2. ed. S\u00e3o Paulo: Cultura Crist\u00e3, 2009, p. 29-31.<\/p>\n<p><a href=\"#_ftnref10\" name=\"_ftn10\">[10]<\/a>rAhfB (\u201cB\u00e3har\u201d) significa \u201cescolher\u201d, \u201celeger\u201d, \u201cdecidir por\u201d, etc. O verbo e os seus derivados ocorrem 198 vezes no Antigo Testamento, havendo o predom\u00ednio do seu emprego na modalidade \u201c<em>qal<\/em>\u201d, (146 vezes) que indica uma a\u00e7\u00e3o completa. O verbo \u00e9 usado cerca de 100 vezes referindo-se a Deus como sujeito da a\u00e7\u00e3o.<\/p>\n<p>\u201cB\u00e3har\u201d, apesar de n\u00e3o ser necessariamente teol\u00f3gico, apresenta sempre a ideia de uma escolha criteriosa, bem pensada \u2013\u2013 da\u00ed, tamb\u00e9m o seu sentido de \u201ctestar\u201d, \u201cexaminar\u201d (Is 48.10; Pv 10.20) \u2212, levando em considera\u00e7\u00e3o as op\u00e7\u00f5es (1Sm 17.40; 1Rs 18.25; Is 1.29; 40.20). (Para um estudo mais detalhado do uso da palavra no Antigo Testamento, veja-se: Hermisten M.P. Costa, <em>Jo\u00e3o <\/em><em>Calvino 500 anos, <\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2009).<\/p>\n<p><a href=\"#_ftnref11\" name=\"_ftn11\">[11]<\/a>Aqui temos um princ\u00edpio: n\u00e3o descansar simplesmente em nossas experi\u00eancias. \u201c&#8230;. sempre que descansamos contentes com as nossas pr\u00f3prias experi\u00eancias e somos s\u00e1bios aos nossos pr\u00f3prios olhos, nos mantemos distanciados de toda e qualquer aproxima\u00e7\u00e3o da doutrina de Cristo\u201d (Jo\u00e3o Calvino, <em>Exposi\u00e7\u00e3o de 2 Cor\u00edntios, <\/em>S\u00e3o Paulo: Edi\u00e7\u00f5es Paracletos, 1995, (2Co 10.5), p. 203). Veja-se: Abraham Kuyper, <em>\u00a0A Obra do Esp\u00edrito Santo, <\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2010, p. 44.<\/p>\n<p><a href=\"#_ftnref12\" name=\"_ftn12\">[12]<\/a><em> \u201c&#8230;. rejeitamos as coisas que, por vergonhosas, se ocultam, n\u00e3o andando com ast\u00facia, nem adulterando a palavra de Deus; antes, nos recomendamos \u00e0 consci\u00eancia de todo homem, na presen\u00e7a de Deus, pela manifesta\u00e7\u00e3o da verdade\u201d<\/em> (2Co 4.2).<\/p>\n<p><a href=\"#_ftnref13\" name=\"_ftn13\">[13]<\/a> <em>\u201cPois n\u00e3o me envergonho do evangelho, porque \u00e9 o poder de Deus para a salva\u00e7\u00e3o de todo aquele que cr\u00ea, primeiro do judeu e tamb\u00e9m do grego\u201d<\/em> (Rm 1.16).<\/p>\n<p><a href=\"#_ftnref14\" name=\"_ftn14\">[14]<\/a> ai)xmalwti\/zw (* Lc 21.24; Rm 7.23; 2Co 10.5).<\/p>\n<p><a href=\"#_ftnref15\" name=\"_ftn15\">[15]<\/a> Ver: Oliver Barclay, <em>Developing a Christian Mind, <\/em>Great Britain: Christian Focus, 2006, p. 16-17; Gene Edward Veith, Jr., <em>De Todo o Teu Entendimento<\/em>, S\u00e3o Paulo: Cultura Crist\u00e3, 2006, p. 133-138.<\/p>\n<p><a href=\"#_ftnref16\" name=\"_ftn16\">[16]<\/a>H. Bavinck, <em>The philosophy of revelation, <\/em>New York: Longmans, Green, and Co., 1909, p. 242.<\/p>\n<p><a href=\"#_ftnref17\" name=\"_ftn17\">[17]<\/a><em>Apud <\/em>Garrett J. DeWeese; J.P. Moreland, <em>Filosofia Concisa: uma introdu\u00e7\u00e3o aos principais temas filos\u00f3ficos, <\/em>S\u00e3o Paulo: Vida Nova, 2011, p. 154-155. (Do mesmo modo em: J.P. Moreland; William L. Craig, <em>Filosofia e Cosmovis\u00e3o Crist\u00e3<\/em>, S\u00e3o Paulo: Vida Nova, 2005, p. 15; William L. Craig, <em>Apolog\u00e9tica Crist\u00e3 para Quest\u00f5es dif\u00edceis da vida, <\/em>S\u00e3o Paulo: Vida Nova, 2010, p. 14-15).<\/p>\n<p><a href=\"#_ftnref18\" name=\"_ftn18\">[18]<\/a>Harry Blamires, <em>A Mente Crist\u00e3: como um crist\u00e3o deve pensar? <\/em>S\u00e3o Paulo: Shedd Publica\u00e7\u00f5es, 2006, p. 15-16.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Na Palavra, temos todos os recursos necess\u00e1rios para combater o erro e apresentar a mensagem crist\u00e3 de forma clara e objetiva.<\/p>\n","protected":false},"author":133,"featured_media":60094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"\"Na Palavra, temos todos os recursos necess\u00e1rios para combater o erro e apresentar a mensagem crist\u00e3 de forma clara e objetiva.\" \u2013Hermisten Maia","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3063],"tags":[2533,2532,2090],"class_list":["post-60092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosmovisao-e-cultura","tag-o-pensamento-grego-e-a-igreja-crista","tag-reflexoes-comprometidas","tag-teobrasil","tema-intelecto","tema-intelecto-dup","tema-pensamento-cristao","tema-verdade","tema-verdade-dup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O pensamento grego e a igreja crist\u00e3 (Parte 32)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O pensamento grego e a igreja crist\u00e3 (Parte 32)\" \/>\n<meta property=\"og:description\" content=\"Na Palavra, temos todos os recursos necess\u00e1rios para combater o erro e apresentar a mensagem crist\u00e3 de forma clara e objetiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-13T20:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/10\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hermisten Maia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hermisten Maia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/\"},\"author\":{\"name\":\"Hermisten Maia\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/cf905e2261780bfba3cda58932d1b22b\"},\"headline\":\"O pensamento grego e a igreja crist\u00e3 (Parte 32)\",\"datePublished\":\"2021-10-13T20:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/\"},\"wordCount\":2957,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"O pensamento grego e a igreja crist\u00e3\",\"Reflex\u00f5es Comprometidas\",\"TeoBrasil\"],\"articleSection\":[\"Cosmovis\u00e3o e cultura\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/\",\"name\":\"O pensamento grego e a igreja crist\u00e3 (Parte 32)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2021-10-13T20:00:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/10\\\/o-pensamento-grego-e-a-igreja-crista-parte-32\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O pensamento grego e a igreja crist\u00e3 (Parte 32)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/cf905e2261780bfba3cda58932d1b22b\",\"name\":\"Hermisten Maia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"caption\":\"Hermisten Maia\"},\"description\":\"Hermisten Maia \u00e9 ministro da Igreja Presbiteriana do Brasil, integrando a Equipe de Pastores da Primeira IP de S\u00e3o Bernardo do Campo, SP. \u00c9 formado em Teologia, Filosofia e Pedagogia. \u00c9 Mestre e Doutor em Ci\u00eancias da Religi\u00e3o. Leciona em diversos Semin\u00e1rios ininterruptamente desde 1980. Tem experi\u00eancia na \u00e1rea de Teologia Sistem\u00e1tica, lecionando h\u00e1 40 anos, e Hist\u00f3ria da Reforma Protestante, atuando principalmente nos seguintes temas: Jo\u00e3o Calvino e Teologia Reformada e Cosmovis\u00e3o Reformada. Faz parte de diversos Conselhos Editoriais de Revistas de Teologia e de Ci\u00eancias da Religi\u00e3o. Tem 40 livros escritos e mais de 1.500 artigos publicados. Leciona em diversas Institui\u00e7\u00f5es de Ensino Superior no Brasil. Publica diariamente em suas redes sociais um artigo e um v\u00eddeo.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/hermisten-maia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O pensamento grego e a igreja crist\u00e3 (Parte 32)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/","og_locale":"pt_BR","og_type":"article","og_title":"O pensamento grego e a igreja crist\u00e3 (Parte 32)","og_description":"Na Palavra, temos todos os recursos necess\u00e1rios para combater o erro e apresentar a mensagem crist\u00e3 de forma clara e objetiva.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2021-10-13T20:00:49+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/10\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Hermisten Maia","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Hermisten Maia","Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/"},"author":{"name":"Hermisten Maia","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/cf905e2261780bfba3cda58932d1b22b"},"headline":"O pensamento grego e a igreja crist\u00e3 (Parte 32)","datePublished":"2021-10-13T20:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/"},"wordCount":2957,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/10\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1","keywords":["O pensamento grego e a igreja crist\u00e3","Reflex\u00f5es Comprometidas","TeoBrasil"],"articleSection":["Cosmovis\u00e3o e cultura"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/","name":"O pensamento grego e a igreja crist\u00e3 (Parte 32)","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/10\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1","datePublished":"2021-10-13T20:00:49+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/10\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/10\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/10\/o-pensamento-grego-e-a-igreja-crista-parte-32\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"O pensamento grego e a igreja crist\u00e3 (Parte 32)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/cf905e2261780bfba3cda58932d1b22b","name":"Hermisten Maia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","caption":"Hermisten Maia"},"description":"Hermisten Maia \u00e9 ministro da Igreja Presbiteriana do Brasil, integrando a Equipe de Pastores da Primeira IP de S\u00e3o Bernardo do Campo, SP. \u00c9 formado em Teologia, Filosofia e Pedagogia. \u00c9 Mestre e Doutor em Ci\u00eancias da Religi\u00e3o. Leciona em diversos Semin\u00e1rios ininterruptamente desde 1980. Tem experi\u00eancia na \u00e1rea de Teologia Sistem\u00e1tica, lecionando h\u00e1 40 anos, e Hist\u00f3ria da Reforma Protestante, atuando principalmente nos seguintes temas: Jo\u00e3o Calvino e Teologia Reformada e Cosmovis\u00e3o Reformada. Faz parte de diversos Conselhos Editoriais de Revistas de Teologia e de Ci\u00eancias da Religi\u00e3o. Tem 40 livros escritos e mais de 1.500 artigos publicados. Leciona em diversas Institui\u00e7\u00f5es de Ensino Superior no Brasil. Publica diariamente em suas redes sociais um artigo e um v\u00eddeo.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/hermisten-maia\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/10\/O-pensamento-grego-e-a-igreja-crista-Parte-32.jpg?fit=750%2C395&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-fDe","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/60092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=60092"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/60092\/revisions"}],"predecessor-version":[{"id":60095,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/60092\/revisions\/60095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/60094"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=60092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=60092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=60092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}