{"id":60623,"date":"2021-07-15T10:00:39","date_gmt":"2021-07-15T13:00:39","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=60623"},"modified":"2021-12-02T16:00:27","modified_gmt":"2021-12-02T19:00:27","slug":"mulheres-no-trabalho","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/","title":{"rendered":"Mulheres no trabalho"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_btn title=&#8221;S\u00e9rie &#8220;O Minist\u00e9rio de Mulheres na Igreja Local&#8220; | Clique aqui e leia os outros artigos&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fvoltemosaoevangelho.com%2Fblog%2Fserie%2Fo-ministerio-de-mulheres-na-igreja-local%2F&#8221;][vc_column_text]<\/p>\n<h2>Mulher no trabalho<\/h2>\n<p>Por defini\u00e7\u00e3o, segundo Maria Cec\u00edlia Alfano, trabalho \u00e9 um conjunto de atividades produtivas e criativas que exercemos. Ele faz parte do plano de Deus desde a cria\u00e7\u00e3o. A mulher deve desenvolver e usar suas habilidades, seus dons e talentos para cumprir a obra que Deus lhe confiar em cada etapa da vida.<\/p>\n<p>Podem ser atividades remuneradas, mas vai al\u00e9m delas. Algumas pessoas gostam das tarefas que tem para desempenhar e sentem-se motivadas para realiz\u00e1-las, enquanto outras simplesmente toleram o trabalho para sobreviver. A autora descreve algumas verdades fundamentais relacionadas ao trabalho, a saber:<\/p>\n<ol>\n<li>a) O trabalho n\u00e3o \u00e9 um castigo ou maldi\u00e7\u00e3o resultante do pecado de Ad\u00e3o e Eva. Ele estava presente antes da Queda e serviremos a Deus na eternidade.<\/li>\n<li>b) A atividade que antes era prazerosa, foi afetada pelo pecado e tornou-se penosa, embora continue digna. O trabalho requer um esfor\u00e7o cansativo, al\u00e9m de que a terra produz \u201cespinhos e ervas daninhas\u201d, o que dificulta a tarefa (G\u00eanesis 3.17, 19).<\/li>\n<li>c) Trabalharemos na eternidade com o privil\u00e9gio de servir a Deus (Apocalipse 3).<\/li>\n<\/ol>\n<p>O trabalho, quando feito em temor a homens, ou para satisfazer a n\u00f3s mesmas, pode se tornar um deus que adoramos, em busca de riqueza, posi\u00e7\u00e3o, prest\u00edgio e elogios, ou mesmo como um escape de outras responsabilidades menos agrad\u00e1veis e atraentes. Nesse contexto, qualquer trabalho n\u00e3o passa de uma fadiga in\u00fatil, \u201cdebaixo do sol\u201d e sem valor eterno (Eclesiastes 1.3).<\/p>\n<p>Muitas mulheres precisam decidir seguirem (ou n\u00e3o) uma carreira profissional. N\u00e3o \u00e9 pecado, mas o fato \u00e9 que nosso conceito moderno de carreira \u00e9 egoc\u00eantrico. Em ess\u00eancia, diz respeito \u00e0 realiza\u00e7\u00e3o e identidade pessoal \u2013 voc\u00ea \u00e9 definida por aquilo que voc\u00ea faz. O que as mulheres devem fazer em vez disso? Tornarem-se boas investidoras daquilo que receberam. \u00c9 Deus quem nos d\u00e1 os relacionamentos, filhos, tempo, talentos, interesses e tarefas que enchem os nossos dias e os anos. N\u00e3o podemos for\u00e7ar que estas coisas aconte\u00e7am, e elas n\u00e3o s\u00e3o a verdadeira identidade. Podemos trabalhar em profiss\u00f5es altamente valorizadas ou podemos fazer trabalhos di\u00e1rios n\u00e3o remunerados. Esses pap\u00e9is n\u00e3o s\u00e3o nossa identidade. S\u00e3o oportunidades para a gl\u00f3ria de Deus.<\/p>\n<p>Nossa atitude fala a respeito de quem servimos: a n\u00f3s mesmas ou a Deus. O sucesso no trabalho n\u00e3o est\u00e1 condicionado aos resultados vis\u00edveis, \u00e0 posi\u00e7\u00e3o social ou aos ganhos materiais. Vem da fidelidade a Deus e \u00e9 ele quem nos recompensar\u00e1. Um bom exerc\u00edcio \u00e9 pensar e avaliar o seu trabalho, a luz de Romanos 11.36.<\/p>\n<p>\u00c9 necess\u00e1rio pensar e avaliar se o seu trabalho \u00e9 de Deus: Ele \u00e9 quem a chamou para executar suas responsabilidades? por meio de Deus? Ele a capacita e voc\u00ea atua em depend\u00eancia dele; \u00e9 para Deus? Tudo quanto voc\u00ea faz \u00e9 para ele e deve honrar e refletir a Deus diante de outros.<\/p>\n<p>Podemos ser esposas ou m\u00e3es, mas, por mais importantes que sejam essas condi\u00e7\u00f5es, s\u00e3o papeis que terminam nesta vida. Continuamos por toda a eternidade como filhas de Deus e irm\u00e3s daqueles que foram resgatados por Cristo.<\/p>\n<h2>Mulher na igreja<\/h2>\n<p>Para homens e mulheres que possuem um cora\u00e7\u00e3o para ministrar, salvar almas, restaurar vidas arruinadas, resistir ao mal e atender pessoas necessitadas, sempre existem campos infinitos de oportunidades para trabalho na igreja. Deus quer que toda a igreja esteja envolvida no minist\u00e9rio: homem e mulher.<\/p>\n<p>Muitas mulheres querem servir na igreja, mas n\u00e3o sabem como. Sentem que as regras excluem as mulheres do pastorado e do presbiterato de forma injusta, e quando est\u00e3o ouvindo os serm\u00f5es at\u00e9 pensam que elas mesmas pregariam melhor que o pastor.<\/p>\n<p>O que \u00e9 a igreja? Nielson relata que \u00e0s vezes, ao falarmos da igreja em rela\u00e7\u00e3o aos pap\u00e9is das mulheres e dos homens, tendemos a pensar nela como a organiza\u00e7\u00e3o em que temos de encontrar nosso lugar por um tempo, assim como uma empresa, na qual as pessoas trabalham como funcion\u00e1rias.<\/p>\n<p>A B\u00edblia, contudo, mostra a igreja como um organismo vivo: o corpo de Cristo ligado a Cristo, nosso cabe\u00e7a (Colossenses 1.18; Ef\u00e9sios 5.23); a casa espiritual de pedras vivas, tendo Jesus como pedra fundamental (1Pedro2.4-6); e, como sabemos, a noiva de Cristo, aquela que ama, como nosso noivo, a Igreja (Lucas 5.33-35; Ef\u00e9sios 25-33). Tais figuras, segundo a autora, iluminam a hist\u00f3ria em que vivemos como povo de Deus. Se somos crentes, nossa identidade muda para sempre, e fazemos parte desse povo de pessoas eternamente redimidas chamadas \u201cIgreja\u201d.<\/p>\n<p>Para mulheres crist\u00e3s, portanto, a quest\u00e3o n\u00e3o \u00e9 se conseguimos encontrar um lugar na igreja. A quest\u00e3o \u00e9 como vivenciaremos nosso lugar dentro do corpo de Cristo \u2013 e como os homens e as mulheres de nossas igrejas podem, juntos, mostrar Cristo ao mundo.<\/p>\n<p>Observa-se exemplos e descri\u00e7\u00f5es de mulheres mencionadas nas ep\u00edstolas do Novo Testamento, as cartas inspiradas pelo Esp\u00edrito, escritas pelos ap\u00f3stolos a diversos pastores e igrejas. O panorama da igreja inclui uma grande diversidade de seres humanos, homens e mulheres, jovens e velhos, que juntos, fazem parte do corpo de Cristo. O Novo Testamento \u00e9 pleno de ensinamentos e encorajamento, os quais aplicam-se, igualmente, a homens e mulheres. Paulo d\u00e1 uma ordem a todos, juntos: \u201cHabite, ricamente, em v\u00f3s a palavra de Cristo; instrui-vos e aconselhai-vos mutuamente em toda a sabedoria, louvando a Deus, com salmos, e hinos, e c\u00e2nticos espirituais, com gratid\u00e3o, em vosso cora\u00e7\u00e3o\u201d (Colossenses 3.16).<\/p>\n<p>As mulheres tamb\u00e9m s\u00e3o conclamadas a aprender e ensinar. Vemos o exemplo de Priscila, que tem encorajado muitas pessoas; ela partilhava tanto do fazer tendas como do ensino do evangelho com seu marido \u00c1quila. (Atos 18.1-3, 18-26). Os dois sempre s\u00e3o mencionados juntos, tr\u00eas vezes com o nome de Priscila primeiro e tr\u00eas vezes com o nome de \u00c1quila primeiro. Esse equil\u00edbrio agrad\u00e1vel parece representar sua parceria de vida e minist\u00e9rio. O casal era anfitri\u00e3o de uma igreja em sua casa, mas os dois tamb\u00e9m viajaram com Paulo, que relata a respeito de ambos: \u201cos quais pela minha vida arriscaram a sua pr\u00f3pria cabe\u00e7a; e isto lhes agrade\u00e7o, n\u00e3o somente eu, mas tamb\u00e9m todas as igrejas dos gentios. Saudai igualmente a igreja que se re\u00fane na casa deles\u201d (Romanos 16.4-5).<\/p>\n<p>Priscila parecia combinar a hospitalidade e humildade com o ensino, que obviamente atingiu muitas vidas.O ensino das mulheres, mencionado em Tito 2, tamb\u00e9m envolvia ambientes informais e relacionamentos pessoais.No entanto, nas Escrituras, as mulheres n\u00e3o s\u00e3o estimuladas a serem mestras formais da igreja, do modo como Paulo encoraja Tito e Tim\u00f3teo nas ep\u00edstolas pastorais.<\/p>\n<p>\u00c9 necess\u00e1rio pensar no Minist\u00e9rio de Mulheres n\u00e3o como um programa que realiza um evento evangel\u00edstico de tempos em tempos, mas sim, como uma rede de relacionamentos que est\u00e1 sempre alcan\u00e7ando por meio da palavra viva \u2013 em nossos estudos b\u00edblicos, nossas amizades e aconselhamentos, em todas as nossas reuni\u00f5es \u2013 sempre chegando para ajudar outros a receber a Palavra que d\u00e1 vida, da qual todas n\u00f3s estar\u00edamos separadas se ela n\u00e3o tivesse vindo at\u00e9 n\u00f3s. Se um minist\u00e9rio est\u00e1 repleto de estudo e ensino focado na Palavra, ent\u00e3o realmente \u00e9 dif\u00edcil isso n\u00e3o acontecer, porque a Palavra de Deus \u00e9 tanto suficiente quanto eficaz para a nossa salva\u00e7\u00e3o e santifica\u00e7\u00e3o.<\/p>\n<p>Nosso minist\u00e9rio n\u00e3o pode existir simplesmente com a finalidade de ajudar as pessoas a viverem bem agora; os nossos minist\u00e9rios, bem como toda a nossa vida, devem apontar para o fim, quando veremos Jesus face a face. As imagens gloriosas em Isaias 55 t\u00eam o seu cl\u00edmax em um \u00fanico fim: \u201cser\u00e1 isto gl\u00f3ria para o Senhor e memorial eterno, que jamais ser\u00e1 extinto\u201d (v.13) Esse nome \u00e9 o nome de Jesus, a quem \u201cdeu o nome que est\u00e1 acima de todo nome, para que ao nome de Jesus se dobre todo joelho, nos c\u00e9us, na terra e debaixo da terra\u201d (Filipenses 2.9, 10).[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>O sucesso no trabalho n\u00e3o est\u00e1 condicionado aos resultados vis\u00edveis, \u00e0 posi\u00e7\u00e3o social ou aos ganhos materiais. Vem da fidelidade a Deus e \u00e9 ele quem nos recompensar\u00e1.<\/p>\n","protected":false},"author":895,"featured_media":60625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"O sucesso no trabalho n\u00e3o est\u00e1 condicionado aos resultados vis\u00edveis, \u00e0 posi\u00e7\u00e3o social ou aos ganhos materiais. Vem da fidelidade a Deus e \u00e9 ele quem nos recompensar\u00e1.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[406,3065,624],"tags":[2765,2090],"class_list":{"0":"post-60623","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-aconselhamento","8":"category-casamento-e-familia","9":"category-mulheres","10":"tag-o-ministerio-de-mulheres-na-igreja-local","11":"tag-teobrasil","12":"tema-discipulado","13":"tema-discipulado-dup-2","14":"tema-ministerio-de-mulheres","16":"tema-mulheres","17":"tema-mutualidade"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mulheres no trabalho<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mulheres no trabalho\" \/>\n<meta property=\"og:description\" content=\"O sucesso no trabalho n\u00e3o est\u00e1 condicionado aos resultados vis\u00edveis, \u00e0 posi\u00e7\u00e3o social ou aos ganhos materiais. Vem da fidelidade a Deus e \u00e9 ele quem nos recompensar\u00e1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-15T13:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T19:00:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/12\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luciana Sborowski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luciana Sborowski\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/\"},\"author\":{\"name\":\"Luciana Sborowski\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/de0038b007363f8c31f365a4a7b1c504\"},\"headline\":\"Mulheres no trabalho\",\"datePublished\":\"2021-07-15T13:00:39+00:00\",\"dateModified\":\"2021-12-02T19:00:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/\"},\"wordCount\":1416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"O Minist\u00e9rio de Mulheres na Igreja Local\",\"TeoBrasil\"],\"articleSection\":[\"Aconselhamento\",\"Casamento e fam\u00edlia\",\"Mulheres\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/\",\"name\":\"Mulheres no trabalho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2021-07-15T13:00:39+00:00\",\"dateModified\":\"2021-12-02T19:00:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2021\\\/07\\\/mulheres-no-trabalho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mulheres no trabalho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/de0038b007363f8c31f365a4a7b1c504\",\"name\":\"Luciana Sborowski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ed20f54205697267695b4de6a7070746667feac82ac5577c4fe23c22dd501ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ed20f54205697267695b4de6a7070746667feac82ac5577c4fe23c22dd501ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ed20f54205697267695b4de6a7070746667feac82ac5577c4fe23c22dd501ea?s=96&d=mm&r=g\",\"caption\":\"Luciana Sborowski\"},\"description\":\"Luciana Sborowski \u00e9 graduada em Fonoaudiologia e possui Mestrado em Minist\u00e9rios (Semin\u00e1rio B\u00edblico Palavra da Vida). Envolvida com Minist\u00e9rio de Aconselhamento B\u00edblico e Discipulado com mulheres na igreja local. Luciana \u00e9 casada com Douglas Sborowski (pastor da Igreja Presbiteriana de Ribeir\u00e3o Preto) e m\u00e3e de Pedro (que se casou com Ana Luiza), Andr\u00e9 e Lia.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/luciana-sborowski\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mulheres no trabalho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/","og_locale":"pt_BR","og_type":"article","og_title":"Mulheres no trabalho","og_description":"O sucesso no trabalho n\u00e3o est\u00e1 condicionado aos resultados vis\u00edveis, \u00e0 posi\u00e7\u00e3o social ou aos ganhos materiais. Vem da fidelidade a Deus e \u00e9 ele quem nos recompensar\u00e1.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2021-07-15T13:00:39+00:00","article_modified_time":"2021-12-02T19:00:27+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/12\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1","type":"image\/jpeg"}],"author":"Luciana Sborowski","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Luciana Sborowski","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/"},"author":{"name":"Luciana Sborowski","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/de0038b007363f8c31f365a4a7b1c504"},"headline":"Mulheres no trabalho","datePublished":"2021-07-15T13:00:39+00:00","dateModified":"2021-12-02T19:00:27+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/"},"wordCount":1416,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/12\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1","keywords":["O Minist\u00e9rio de Mulheres na Igreja Local","TeoBrasil"],"articleSection":["Aconselhamento","Casamento e fam\u00edlia","Mulheres"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/","name":"Mulheres no trabalho","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/12\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1","datePublished":"2021-07-15T13:00:39+00:00","dateModified":"2021-12-02T19:00:27+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/12\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/12\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2021\/07\/mulheres-no-trabalho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Mulheres no trabalho"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/de0038b007363f8c31f365a4a7b1c504","name":"Luciana Sborowski","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1ed20f54205697267695b4de6a7070746667feac82ac5577c4fe23c22dd501ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ed20f54205697267695b4de6a7070746667feac82ac5577c4fe23c22dd501ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ed20f54205697267695b4de6a7070746667feac82ac5577c4fe23c22dd501ea?s=96&d=mm&r=g","caption":"Luciana Sborowski"},"description":"Luciana Sborowski \u00e9 graduada em Fonoaudiologia e possui Mestrado em Minist\u00e9rios (Semin\u00e1rio B\u00edblico Palavra da Vida). Envolvida com Minist\u00e9rio de Aconselhamento B\u00edblico e Discipulado com mulheres na igreja local. Luciana \u00e9 casada com Douglas Sborowski (pastor da Igreja Presbiteriana de Ribeir\u00e3o Preto) e m\u00e3e de Pedro (que se casou com Ana Luiza), Andr\u00e9 e Lia.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/luciana-sborowski\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2021\/12\/Mulheres-no-trabalho.jpg?fit=750%2C395&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-fLN","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/60623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/895"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=60623"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/60623\/revisions"}],"predecessor-version":[{"id":60626,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/60623\/revisions\/60626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/60625"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=60623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=60623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=60623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}