{"id":61125,"date":"2022-03-05T10:00:06","date_gmt":"2022-03-05T13:00:06","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=61125"},"modified":"2022-08-25T15:05:10","modified_gmt":"2022-08-25T18:05:10","slug":"salmo-32-a-misericordia-que-nos-assiste","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/","title":{"rendered":"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_message message_box_style=&#8221;solid&#8221; style=&#8221;square&#8221; message_box_color=&#8221;grey&#8221; icon_type=&#8221;openiconic&#8221; icon_openiconic=&#8221;vc-oi vc-oi-book&#8221;]<\/p>\n<h5><em>Este post faz parte da s\u00e9rie\u00a0<a href=\"https:\/\/voltemosaoevangelho.com\/blog\/serie\/salmo-32\/\" target=\"_blank\" rel=\"noopener\"><strong>Salmo 32<\/strong><\/a><\/em>.<\/h5>\n<p>[\/vc_message][vc_column_text]O Antigo Testamento emprega duas palavras que mais especificamente se ad\u00e9quam aos conceitos de \u201c<em>gra\u00e7a<\/em>\u201d e \u201c<em>miseric\u00f3rdia\u201d<\/em> expressos no Novo Testamento. As palavras s\u00e3o: (hesed) e\u00a0 (hen). Aqui nos ateremos \u00e0 primeira palavra.<\/p>\n<p>Hesed, cuja etimologia \u00e9 obscura,<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> pode ser traduzida por \u201c<em>bondade<\/em>\u201d, \u201c<em>gra\u00e7a<\/em>\u201d, \u201c<em>benevol\u00eancia<\/em>\u201d, \u201c<em>benignidade<\/em>\u201d, \u201c<em>clem\u00eancia<\/em>\u201d, \u201c<em>benefic\u00eancia<\/em>\u201d, \u201c<em>humanidade<\/em>\u201d (ARA. 2Sm 2.5), \u201c<em>fidelidade<\/em>\u201d (ARA. 2Sm 16.17) e \u201c<em>miseric\u00f3rdia<\/em>\u201d. Ocorre cerca de 250 vezes no Antigo Testamento, principalmente nos Salmos (127 vezes).<\/p>\n<p>Figuradamente, Deus \u00e9 chamado de \u201c<em>Miseric\u00f3rdia<\/em>\u201d por Davi: <em>\u201cMinha <u>miseric\u00f3rdia<\/u> <\/em>(hesed) <em>e fortaleza minha, meu alto ref\u00fagio e meu libertador, meu escudo, aquele em quem confio e quem me submete o meu povo\u201d <\/em>(Sl 144.2).<\/p>\n<p><em>Hesed<\/em> pode ser empregada acerca de Deus e acerca do homem. Quando a palavra se refere ao homem, reflete o seu amor para com o seu pr\u00f3ximo e para com Deus. Quando a palavra \u00e9 aplicada a Deus, denota a sua gra\u00e7a, envolvendo dois elementos importantes:<\/p>\n<h3>A autoentrega de Deus a Israel na rela\u00e7\u00e3o de um pacto<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a><\/h3>\n<p><strong>\u00a0<\/strong>A ideia principal \u00e9 a de que Deus manifesta o seu amor ativamente na forma de uma rela\u00e7\u00e3o pactual; \u00e9 um \u201camor consistente\u201d.<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a><\/p>\n<p><em>Hesed<\/em> \u00e9 um \u201camor de Pacto\u201d (Dt 7.9,12; Jr 31.3);<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a> \u201c<em>Hesed <\/em>da alian\u00e7a\u201d;<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a> \u201ccomportamento correto segundo a alian\u00e7a\u201d.<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a><\/p>\n<p>O Pacto de Deus \u00e9 unilateral no que concerne \u00e0s suas demandas e provis\u00f5es. Compete ao homem aceit\u00e1-lo ou n\u00e3o; por\u00e9m, n\u00e3o pode modificar os seus termos. O <em>Hesed<\/em> \u00e9 a causa e o efeito do Pacto. Deus fez o Pacto por miseric\u00f3rdia; ele revela a sua miseric\u00f3rdia de acordo com o Pacto (1Rs 8.23<a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a> [2Cr 6.14]; Ne 1.5; 9.32; Is 55.3; Dn 9.4).<\/p>\n<h3>Est\u00e1 associada \u00e0 justi\u00e7a de Deus<\/h3>\n<p>O <em>Hesed<\/em> de Deus n\u00e3o \u00e9 barato. Deus n\u00e3o age movido por um sentimento incontrol\u00e1vel e incoerente; antes, encontra um justo caminho para estabelecer uma rela\u00e7\u00e3o s\u00f3lida com o homem pecador sem omitir a condi\u00e7\u00e3o pecaminosa do homem nem, baratear a sua justi\u00e7a.<\/p>\n<p>O fundamento desta nova rela\u00e7\u00e3o \u00e9 o pr\u00f3prio Cristo. A manifesta\u00e7\u00e3o da justi\u00e7a \u00e9, concomitantemente, a express\u00e3o da sua gra\u00e7a.<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a> A gra\u00e7a de Deus nunca \u00e9 barata nem inconsequente.<\/p>\n<p>Devido ao seu <em>Hesed<\/em>, Deus voluntariamente elege o seu povo, mantendo-se fiel nesta rela\u00e7\u00e3o independentemente da fidelidade circunstancial dos seus eleitos (Dt 7.6-11;<a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a> 2Sm 2.6; Sl 36.5; 57.3; 89.49; Is 54.10; 55.3).<\/p>\n<h2>Mis\u00e9ria e Miseric\u00f3rdia operante<\/h2>\n<p>Deus se relaciona conosco em miseric\u00f3rdia. Ele \u00e9 pleno de seus atributos; portanto, rico em miseric\u00f3rdia por causa do seu grande amor (Ef 2.4).<a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a><\/p>\n<p>Tiago alegra-se na miseric\u00f3rdia de Deus: <em>\u201cEis que temos por felizes os que perseveraram firmes. Tendes ouvido da paci\u00eancia de J\u00f3 e vistes que fim o Senhor lhe deu; porque o Senhor \u00e9 <u>cheio de terna miseric\u00f3rdia<\/u><\/em>(\u03c0\u03bf\u03bb\u03cd\u03c3\u03c0\u03bb\u03b1\u03b3\u03c7\u03bd\u03cc\u03c2 &#8211; polysplanchnos) <em>e <u>compassivo<\/u> <\/em>(\u03bf\u1f30\u03ba\u03c4\u03af\u03c1\u03bc\u03c9\u03bd &#8211; oiktirm\u014dn)<em>\u201d<\/em> (Tg 5.11).<\/p>\n<p>A miseric\u00f3rdia de Deus, por sua vez revela tamb\u00e9m a nossa mis\u00e9ria. S\u00f3 pode haver miseric\u00f3rdia \u2013 justamente por carecer dela \u2013, para com os miser\u00e1veis.<\/p>\n<p>O salmista atento \u00e0 obra de Deus, conclama: <em>\u201cRendei gra\u00e7as ao Senhor, porque ele \u00e9 bom, porque a sua <u>miseric\u00f3rdia<\/u><\/em> (hesed) <em>dura para sempre\u201d<\/em> (Sl 118.1 = Sl 106.1; 107.1, etc.).<\/p>\n<h3>Relacionamento por miseric\u00f3rdia<\/h3>\n<p>Aqui h\u00e1 a compreens\u00e3o de que toda a nossa rela\u00e7\u00e3o com Deus se baseia em sua miseric\u00f3rdia.<\/p>\n<p>Ap\u00f3s a destrui\u00e7\u00e3o de Jerusal\u00e9m, Jeremias escreve: <em>\u201cAs <u>miseric\u00f3rdias<\/u><\/em> (hesed) <em>do Senhor s\u00e3o a causa de n\u00e3o sermos consumidos porque as suas miseric\u00f3rdias n\u00e3o t\u00eam fim\u201d<\/em> (Lm 3.22).<\/p>\n<p>Tudo que somos e temos pode ser resumido na \u201cmiseric\u00f3rdia eterna de Deus\u201d, que se compadece de n\u00f3s e propicia a nossa salva\u00e7\u00e3o.<\/p>\n<p>No salmo 130 encontramos o salmista em uma situa\u00e7\u00e3o extrema. Ele n\u00e3o se ilude com solu\u00e7\u00f5es humanas. Nenhuma metodologia de autoajuda o pode socorrer. Por isso, pode dizer do mais profundo de seu cora\u00e7\u00e3o, das \u201cprofundezas\u201d de sua situa\u00e7\u00e3o: <em>\u201cClamo a ti, Senhor\u201d<\/em> (Sl 130.1).<\/p>\n<p>Ele sabe perfeitamente a quem se dirige. A sua experi\u00eancia compartilhada \u00e9 de esperar em Deus visto que ele \u00e9 o Deus misericordioso: <em>\u201c<\/em><em>A minha alma anseia pelo Senhor mais do que os guardas pelo romper da manh\u00e3. Mais do que os guardas pelo romper da manh\u00e3, espere Israel no Senhor, pois no Senhor h\u00e1 <u>miseric\u00f3rdia<\/u> <\/em>(hesed)<em>; nele, copiosa reden\u00e7\u00e3o\u201d<\/em> (Sl 130.6-7).<\/p>\n<p>Nas Escrituras fica evidente que os servos de Deus sempre tiveram um conceito claro e abrangente de alguns importantes aspectos da sua miseric\u00f3rdia. Vejamos alguns testemunhos:<\/p>\n<p><strong>a) A bondade do Senhor est\u00e1 espalhada por toda Terra.<\/strong><\/p>\n<p><em>\u201cEle ama a justi\u00e7a e o direito; a terra est\u00e1 cheia da <u>bondade<\/u><\/em> (hesed) <em>do SENHOR\u201d<\/em> (Sl 33.5). (Do mesmo modo: Sl 119.64).<\/p>\n<h4><strong>b) A miseric\u00f3rdia de Deus \u00e9 eterna. <\/strong><\/h4>\n<p>O salmista pede a Deus que em sua lembran\u00e7a olhe para Ele com miseric\u00f3rdia, n\u00e3o considerando os pecados de sua juventude.<\/p>\n<p><em>\u201cLembra-te, SENHOR, das tuas <u>miseric\u00f3rdias<\/u> <\/em>(racham) <em>e das tuas <u>bondades<\/u><\/em> (hesed)<em>, que s\u00e3o desde a eternidade. N\u00e3o te lembres dos meus pecados da mocidade, nem das minhas transgress\u00f5es. Lembra-te de mim, segundo a tua <u>miseric\u00f3rdia<\/u><\/em> (hesed)<em>, por causa da tua <u>bondade<\/u> <\/em>(tub)<em>, \u00f3 SENHOR\u201d<\/em> (Sl 25.6-7).<\/p>\n<p><em>\u201cAo \u00fanico que opera <u>grandes<\/u> <\/em>(gadol) <em><u>maravilhas<\/u> <\/em>(pala)<em>, porque a sua <u>miseric\u00f3rdia<\/u> <\/em>(hesed) <em>dura para sempre\u201d <\/em>(Sl 136.4).<\/p>\n<p>No Salmo 31, Davi p\u00f4de expressar a Deus o seu contentamento reconhecendo a bondade de Deus: <em>\u201cComo \u00e9 grande a tua <u>bondade<\/u> <\/em>(tub)<em>, que reservaste aos que te temem, da qual usas, perante os filhos dos homens, para com os que em ti se refugiam!\u201d<\/em> (Sl 31.19)<\/p>\n<h4><strong>c)<\/strong> <strong>Davi pede a Deus que o livre, o salve pela sua miseric\u00f3rdia<\/strong><\/h4>\n<p><em>\u201c&#8230;. salva-me por tua <u>gra\u00e7a<\/u><\/em> (hesed)<em>\u201d<\/em> (Sl 6.4). (Do mesmo modo: Sl 31.16).<\/p>\n<h4><strong>d) O salmista reconhece como a miseric\u00f3rdia de Deus nos acompanha<\/strong><\/h4>\n<p>Por isso, expressa o desejo de que assim permane\u00e7a. Em \u00faltima inst\u00e2ncia a nossa confian\u00e7a deve estar sempre em Deus n\u00e3o em nossas supostas habilidades ou circunst\u00e2ncias favor\u00e1veis. Deus \u00e9 o Senhor do tempo, das circunst\u00e2ncias e da eternidade. Faremos muito bem se aprendermos a confiar nele, aquela que nos acompanha sempre (Sl 33.12-17).<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><em><sup>18<\/sup><\/em><em> Eis que os olhos do SENHOR est\u00e3o sobre os que o temem, sobre os que esperam na sua <u>miseric\u00f3rdia<\/u> <\/em>(hesed)<em>,\u00a0 <sup>19<\/sup> para livrar-lhes a alma da morte, e, no tempo da fome, conservar-lhes a vida.\u00a0 <sup>20<\/sup> Nossa alma espera no SENHOR, nosso aux\u00edlio e escudo.\u00a0 <sup>21<\/sup> Nele, o nosso cora\u00e7\u00e3o se alegra, pois confiamos no seu santo nome.\u00a0 <sup>22<\/sup> Seja sobre n\u00f3s, SENHOR, a tua <u>miseric\u00f3rdia<\/u> <\/em>(hesed)<em>, como de ti esperamos. <\/em>\u00a0(Sl 33-18-22).<\/p>\n<p style=\"text-align: left;\"><em>\u201cBondade e <u>miseric\u00f3rdia<\/u><\/em> (hesed) <em>certamente me seguir\u00e3o todos os dias da minha vida; e habitarei na Casa do SENHOR para todo o sempre <\/em>(Sl 23.6).<\/p>\n<\/blockquote>\n<h4><strong>e)<\/strong> <strong>A miseric\u00f3rdia de Deus \u00e9 preciosa e, aqueles que a reconhecem, refugiam-se em Deus<\/strong><\/h4>\n<p><em>\u201cComo \u00e9 preciosa, \u00f3 Deus, a tua <u>benignidade<\/u>! <\/em>(hesed) <em>Por isso, os filhos dos homens se acolhem \u00e0 sombra das tuas asas\u201d<\/em> (Sl 36.7).<\/p>\n<h4><strong>f) Davi sabe que o seu culto a Deus \u00e9 resultante da riqueza da miseric\u00f3rdia de Deus.<\/strong><\/h4>\n<p><em>\u201c&#8230;. eu, pela riqueza da tua <u>miseric\u00f3rdia<\/u><\/em> (hesed)<em>, entrarei na tua casa e me prostrarei diante do teu santo templo, no teu temor\u201d<\/em> (Sl 5.7).<\/p>\n<p>O nosso culto a Deus \u00e9 sempre uma express\u00e3o da gra\u00e7a de Deus. Deus se d\u00e1 a conhecer e nos capacita a nos relacionar com Ele em amor, fidelidade e obedi\u00eancia.<\/p>\n<p>No Novo Testamento Paulo roga aos irm\u00e3os que, considerando as miseric\u00f3rdias de Deus, se ofere\u00e7am integralmente como um culto agrad\u00e1vel a Deus: <em>\u201c<u>Rogo<\/u>-vos <\/em>(parakale\/w) (suplicar, exortar, solicitar, chamar)<em>, pois, irm\u00e3os, pelas miseric\u00f3rdias de Deus, que apresenteis o vosso corpo por sacrif\u00edcio vivo, santo e agrad\u00e1vel a Deus, que \u00e9 o vosso culto racional\u201d\u00a0 <\/em>(Rm 12.1).<\/p>\n<h4><strong>g) Deus responde as nossas ora\u00e7\u00f5es devido \u00e0 sua miseric\u00f3rdia.<\/strong><\/h4>\n<p><em>Quanto a mim, por\u00e9m, SENHOR, fa\u00e7o a ti, em tempo favor\u00e1vel, a minha ora\u00e7\u00e3o. Responde-me, \u00f3 Deus, pela riqueza da tua <u>gra\u00e7a<\/u><\/em>\u00a0 (hesed)<em>; pela tua fidelidade em socorrer (&#8230;). Responde-me, SENHOR, pois <u>compassiva<\/u> <\/em>(t\u00f4b)<a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a> <em>\u00e9 a tua <u>gra\u00e7a<\/u> <\/em>(hesed)<em>; volta-te para mim segundo a riqueza das tuas <u>miseric\u00f3rdias<\/u> <\/em>(racham). (Sl 69.13,16).<\/p>\n<h4><strong>h) O salmista rende gra\u00e7as a Deus considerando as suas maravilhosas obras fruto de sua miseric\u00f3rdia:<\/strong><\/h4>\n<p><em>\u201cAo \u00fanico que opera <u>grandes<\/u> <\/em>(gadol)<a href=\"#_ftn12\" name=\"_ftnref12\">[12]<\/a> <em><u>maravilhas<\/u> <\/em>(pala) (<em>admir\u00e1veis, <\/em>extraordin\u00e1rias)<em>, porque a sua <u>miseric\u00f3rdia<\/u><\/em>\u00a0(hesed) <em>dura para sempre\u201d <\/em>(Sl 136.4).<\/p>\n<p>Davi canta com alegria a magnificente miseric\u00f3rdia de Deus que se manifestou em seu livramento e alento de sua alma:<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><em>Render-te-ei gra\u00e7as, SENHOR, de todo o meu cora\u00e7\u00e3o; na presen\u00e7a dos poderosos te cantarei louvores.\u00a0 <sup>2<\/sup> Prostrar-me-ei para o teu santo templo e louvarei o teu nome, por causa da tua <\/em><em><u>miseric\u00f3rdia<\/u><\/em> (hesed) <em>e da tua verdade, pois <u>magnificaste<\/u> <\/em>(gadal) <em>acima de tudo o teu nome e a tua palavra.\u00a0 <sup>3<\/sup> No dia em que eu clamei, tu me acudiste e alentaste a for\u00e7a de minha alma. <\/em>(Sl 138-1-3).<\/p>\n<\/blockquote>\n<p>O povo de Deus, deve tamb\u00e9m faz\u00ea-lo, inclusive considerando o cuidado de Deus para com a sua Igreja conforme o seu pacto de miseric\u00f3rdia que preserva o seu povo ao longo da hist\u00f3ria:<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><em>Cantarei para sempre as tuas <u>miseric\u00f3rdias<\/u><\/em>\u00a0(hesed)<em>, \u00f3 SENHOR; os meus l\u00e1bios proclamar\u00e3o a todas as gera\u00e7\u00f5es a tua fidelidade.\u00a0 <sup>2<\/sup> Pois disse eu: a benignidade est\u00e1 fundada para sempre; a tua fidelidade, tu a confirmar\u00e1s nos c\u00e9us, dizendo:\u00a0 <sup>3<\/sup> Fiz alian\u00e7a com o meu escolhido e jurei a Davi, meu servo:\u00a0 <sup>4<\/sup> Para sempre estabelecerei a tua posteridade e firmarei o teu trono de gera\u00e7\u00e3o em gera\u00e7\u00e3o. <\/em>(Sl 89.1-4).<\/p>\n<\/blockquote>\n<h4><strong>i) Deus nos guarda e protege com a sua miseric\u00f3rdia.<\/strong><\/h4>\n<p>Davi escreve<em>: \u201cMuito sofrimento ter\u00e1 de curtir o \u00edmpio, mas o que confia no Senhor, a <u>miseric\u00f3rdia<\/u><\/em> (hesed) <em>o <u>assistir\u00e1<\/u><\/em>\u00a0 (sabab)\u201d (Sl 32.10).<\/p>\n<p>A palavra assistir, que tem um amplo sentido literal e figurado, significa envolver, cercar, contornar. Apenas para ilustrar, mencionamos que esta \u00e9 a palavra usada para descrever as voltas que o ex\u00e9rcito de Israel deu sobre Jeric\u00f3 durante sete dias (Js 6.3,4,7,11,14,15). A ideia expressa \u00e9 a de que Deus nos cerca, nos envolve por todos os lados com a sua miseric\u00f3rdia.<\/p>\n<p>O <em>hesed<\/em> de Deus \u00e9 o seu incans\u00e1vel, fiel e misericordioso amor pactual que se revela em sua rela\u00e7\u00e3o com o Seu povo. Ele pode ser esperado, desejado e suplicado, por\u00e9m, n\u00e3o pode ser exigido.<a href=\"#_ftn13\" name=\"_ftnref13\">[13]<\/a> A miseric\u00f3rdia de Deus se manifesta de forma boa e agrad\u00e1vel a fim de nos restaurar. Ela se relaciona com a profundidade de seu amor que se revela em atos concretos de compaix\u00e3o.<\/p>\n<h3>O esquecimento dos atos de Deus<\/h3>\n<p>No entanto, mesmo sendo evidente a miseric\u00f3rdia de Deus em sua rela\u00e7\u00e3o com o seu povo, a desconsidera\u00e7\u00e3o leviana da bondade de Deus caracterizou a vida de Israel em diversas e cont\u00ednuas situa\u00e7\u00f5es.<\/p>\n<p>O esquecimento dos atos de Deus contribui para o nosso afastamento dele e de sua Palavra. Esse \u00e9 o diagn\u00f3stico que faz o salmista ao considerar a rebeldia de Israel: <em>\u201cNossos pais, no Egito, n\u00e3o <u>atentaram<\/u> <\/em>(sakal) <em>\u00e0s tuas <u>maravilhas<\/u> <\/em>(pala)<em>; n\u00e3o se <u>lembraram<\/u> <\/em>(zakar) <em>da multid\u00e3o das tuas <u>miseric\u00f3rdias<\/u> <\/em>(hesed) <em>e foram rebeldes junto ao mar, o mar Vermelho\u201d<\/em> (Sl 106.7).<\/p>\n<p>O povo se manteve indiferente a Deus. N\u00e3o considerou a Palavra de Deus, seus atos e a alian\u00e7a feita.<\/p>\n<p>Creio que essa experi\u00eancia n\u00e3o \u00e9 estranha a muitos de n\u00f3s. Em alguns momentos, sob o impacto de um grande livramento, a concretiza\u00e7\u00e3o de um desejo intensamente acalentado, o restabelecimento de uma enfermidade, a conquista de um emprego depois de meses sem sucesso&#8230;. Quem sabe, louvamos a Deus com sinceridade e integridade. Assumimos compromissos santos diante de Deus, e confessamos as nossas falhas&#8230; Mas, em seguida, passados os primeiros momentos de j\u00fabilo, gradativamente podemos incorrer no esquecimento de Deus, dos seus atos e de nossas promessas. Foi o que aconteceu com o povo de Israel:<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><em><sup>11<\/sup><\/em><em> As \u00e1guas cobriram os seus opressores; nem um deles escapou.\u00a0 <sup>12<\/sup> Ent\u00e3o, creram nas suas palavras e lhe cantaram louvor.\u00a0 <sup>13<\/sup> Cedo, por\u00e9m, <u>se esqueceram<\/u> <\/em>(shakach) <em>\u00a0das suas obras e n\u00e3o lhe aguardaram os des\u00edgnios (\u2026)\u00a0\u00a0 <sup>21<\/sup> <u>Esqueceram-se<\/u> <\/em>(shakach) <em>\u00a0de Deus, seu Salvador, que, no Egito, fizera <u>coisas portentosas<\/u> <\/em>(gadol)<em>. <\/em>(Sl 106.11-13, 21).<\/p>\n<\/blockquote>\n<p>As maravilhas de Deus envolvem a sua Palavra. Por isso, devemos consider\u00e1-la com sinceridade e louvor.<\/p>\n<h3>Considerar os feitos de Deus em louvor e adora\u00e7\u00e3o<\/h3>\n<p>No Salmo 105, o salmista considerando as obras maravilhosas de Deus na hist\u00f3ria de Israel, instrui: <em>\u201c<u>Lembrai<\/u>-vos <\/em>(zakar) <em>das maravilhas<\/em> <em>que fez, dos seus prod\u00edgios e dos <u>ju\u00edzos<\/u> <\/em>(mishpat)<a href=\"#_ftn14\" name=\"_ftnref14\">[14]<\/a> <em>de seus l\u00e1bios\u201d<\/em> (Sl 105.5).<\/p>\n<p>Asafe em profunda ang\u00fastia, se reanima na considera\u00e7\u00e3o dos feitos de Deus:<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><em><sup>2<\/sup><\/em><em> No dia da minha ang\u00fastia, procuro o Senhor; erguem-se as minhas m\u00e3os durante a noite e n\u00e3o se cansam; a minha alma recusa consolar-se.\u00a0 <sup>3<\/sup> Lembro-me de Deus e passo a gemer; medito, e me desfalece o esp\u00edrito.\u00a0 <sup>4<\/sup> N\u00e3o me deixas pregar os olhos; t\u00e3o perturbado estou, que nem posso falar.\u00a0 <sup>5<\/sup>Penso nos dias de outrora, trago \u00e0 lembran\u00e7a os anos de passados tempos.\u00a0 <sup>6<\/sup>De noite indago o meu \u00edntimo, e o meu esp\u00edrito perscruta.\u00a0 <sup>7<\/sup>Rejeita o Senhor para sempre? Acaso, n\u00e3o torna a ser prop\u00edcio?\u00a0 <sup>8<\/sup> Cessou perpetuamente a sua <u>gra\u00e7a<\/u><\/em>\u00a0(hesed)<em>? <\/em><em>Caducou<\/em><em> a sua promessa para todas as gera\u00e7\u00f5es?\u00a0 <sup>9<\/sup>Esqueceu-se Deus de ser benigno? Ou, na sua ira, ter\u00e1 ele reprimido as suas miseric\u00f3rdias?\u00a0 <sup>10<\/sup> Ent\u00e3o, disse eu: isto \u00e9 a minha afli\u00e7\u00e3o; mudou-se a destra do Alt\u00edssimo.\u00a0 <sup>11<\/sup> Recordo os feitos do SENHOR, pois me lembro das tuas <u>maravilhas<\/u><\/em>\u00a0(<em>pele<\/em>) <em>da antiguidade.\u00a0 <sup>12<\/sup> Considero tamb\u00e9m nas tuas obras todas e cogito dos teus prod\u00edgios.\u00a0 <sup>13<\/sup> O teu caminho, \u00f3 Deus, \u00e9 de santidade. Que deus \u00e9 t\u00e3o grande como o nosso Deus?\u00a0 <sup>14<\/sup> Tu \u00e9s o Deus que operas <u>maravilhas<\/u> <\/em>(<em>pele<\/em>) <em>e, entre os povos, tens feito not\u00f3rio o teu poder. <\/em>(Sl 77.2-14).<\/p>\n<\/blockquote>\n<p>Asafe canta: <em>\u201cGra\u00e7as te rendemos, \u00f3 Deus; gra\u00e7as te rendemos, e invocamos o teu nome, e declaramos as tuas <u>maravilhas<\/u> <\/em>\u00a0(pala)<em>\u201d<\/em> (Sl 75.1).<\/p>\n<p>O salmista rememorando os feitos \u00a0misericordiosos de Deus na hist\u00f3ria de seu povo, escreve: <em>\u201c<\/em><em>Rendam gra\u00e7as ao SENHOR por sua <u>bondade <\/u><\/em>(hesed) <em>e por suas <u>maravilhas<\/u> <\/em>(pala) <em>para com os filhos dos homens!<\/em>\u201d (Sl 107.8).<\/p>\n<p>O salmista assume um compromisso pessoal: <em>\u201cLouvar-te-ei, SENHOR, de todo o meu cora\u00e7\u00e3o; contarei todas as tuas <u>maravilhas<\/u><\/em>\u00a0(pala)<em>\u201d<\/em> (Sl 9.1).<\/p>\n<h3>Apolog\u00e9tico, Missional e pedag\u00f3gico<\/h3>\n<p>Os feitos maravilhosos de Deus ultrapassam os limites de Israel. Isso tem tamb\u00e9m um prop\u00f3sito apolog\u00e9tico e mission\u00e1rio. A igreja por sua vez, deve narrar os feitos de Deus com prop\u00f3sitos adoracionais e pedag\u00f3gicos.<\/p>\n<p>No testemunho de Asafe vemos o prop\u00f3sito apolog\u00e9tico-missional:<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><em><sup>13<\/sup><\/em><em> O teu caminho, \u00f3 Deus, \u00e9 de santidade. Que deus \u00e9 t\u00e3o grande como o nosso Deus?\u00a0 <sup>14<\/sup> Tu \u00e9s o Deus que operas <u>maravilhas<\/u> <\/em>(pele) <em>e, entre os povos, tens feito not\u00f3rio o teu poder. <sup>15<\/sup> Com o teu bra\u00e7o remiste o teu povo, os filhos de Jac\u00f3 e de Jos\u00e9.\u00a0 <sup>16<\/sup> Viram-te as \u00e1guas, \u00f3 Deus; as \u00e1guas te viram e temeram, at\u00e9 os abismos se abalaram.\u00a0 <sup>17<\/sup> Grossas nuvens se desfizeram em \u00e1gua; houve trov\u00f5es nos espa\u00e7os; tamb\u00e9m as suas setas cruzaram de uma parte para outra.\u00a0 <sup>18<\/sup> O ribombar do teu trov\u00e3o ecoou na redondeza; os rel\u00e2mpagos alumiaram o mundo; a terra se abalou e tremeu.\u00a0 <sup>19<\/sup> Pelo mar foi o teu caminho; as tuas veredas, pelas grandes \u00e1guas; e n\u00e3o se descobrem os teus vest\u00edgios.\u00a0 <sup>20<\/sup> O teu povo, tu o conduziste, como rebanho, pelas m\u00e3os de Mois\u00e9s e de Ar\u00e3o. <\/em>(Sl 77.13-20).<\/p>\n<\/blockquote>\n<p>Em outro lugar o salmista conclama o povo a anunciar entre os povos a gl\u00f3ria e as maravilhas de Deus: <em>\u201cAnunciai entre as na\u00e7\u00f5es a sua gl\u00f3ria, entre todos os povos, as suas <u>maravilhas<\/u> <\/em>(pala)<em>\u201d<\/em> (Sl 96.3).<\/p>\n<p>O mesmo Asafe, estabelece a necessidade de educar seus filhos e as futuras gera\u00e7\u00f5es contando as maravilhas de Deus na hist\u00f3ria:<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><em><sup>3<\/sup><\/em><em> O que ouvimos e aprendemos, o que nos contaram nossos pais,\u00a0 <sup>4<\/sup> n\u00e3o o encobriremos a seus filhos; contaremos \u00e0 vindoura gera\u00e7\u00e3o os louvores do SENHOR, e o seu poder, e as <u>maravilhas<\/u><\/em>\u00a0(pala) <em>que fez.\u00a0 <sup>5<\/sup> Ele estabeleceu um testemunho em Jac\u00f3, e instituiu uma lei em Israel, e ordenou a nossos pais que os transmitissem a seus filhos,\u00a0 <sup>6<\/sup> a fim de que a nova gera\u00e7\u00e3o os conhecesse, filhos que ainda h\u00e3o de nascer se levantassem e por sua vez os referissem aos seus descendentes;\u00a0 <sup>7<\/sup> para que pusessem em Deus a sua confian\u00e7a e n\u00e3o se esquecessem dos feitos de Deus, mas lhe observassem os mandamentos;\u00a0 <sup>8<\/sup> e que n\u00e3o fossem, como seus pais, gera\u00e7\u00e3o obstinada e rebelde, gera\u00e7\u00e3o de cora\u00e7\u00e3o inconstante, e cujo esp\u00edrito n\u00e3o foi fiel a Deus. <\/em>(Sl 78.3-8).<\/p>\n<\/blockquote>\n<p>O nosso Deus de miseric\u00f3rdia tem operado maravilhas em nossa cotidianidade. Os seus atos na hist\u00f3ria devem ser objeto de nossa reflex\u00e3o e gratid\u00e3o. Sei que \u00e9 muito dif\u00edcil para n\u00f3s ultrapassarmos os limites do que \u00e9 apenas imediatamente percebido, contudo, amparados da certeza de quem \u00e9 o nosso Senhor, ainda que com mod\u00e9stia epistemol\u00f3gica,<a href=\"#_ftn15\" name=\"_ftnref15\">[15]<\/a> podemos vislumbrar aspectos da grandeza de sua dire\u00e7\u00e3o em nossa vida. O Senhor deve ser louvado. Devemos instruir nossos filhos nesse caminho e proclamar a todas as pessoas os seus feitos.<\/p>\n<p>A miseric\u00f3rdia de Deus \u00e9 uma realidade cont\u00ednua em nossa exist\u00eancia. Contudo, ela se torna mais eloquente para n\u00f3s quando tomamos consci\u00eancia do nosso pecado e do perd\u00e3o de Deus.<\/p>\n<p>No Salmo 6, o salmista Davi, tendo pecado, arrependido, suplica a Deus: <em>\u201cVolta-te, SENHOR, e livra a minha alma; salva-me por tua <u>gra\u00e7a <\/u><\/em>(hesed)<em>\u201d <\/em>(Sl 6.4).<a href=\"#_ftn16\" name=\"_ftnref16\">[16]<\/a><\/p>\n<p>Por maiores que sejam os nossos pecados, exponhamos a Deus em ora\u00e7\u00e3o. N\u00e3o tenhamos vergonha de colocar diante de Deus as nossas angustias, temores e ansiedades. Tenhamos vergonha de pecar. Lamentavelmente tendo feito isto, arrependidos, n\u00e3o tenhamos vergonha de confessar a Deus a nossa transgress\u00e3o rogando-lhe a gra\u00e7a do perd\u00e3o.<\/p>\n<p>Devemos ter sempre presente diante de nossos olhos que a restaura\u00e7\u00e3o concedida por Deus \u00e0 nossa vida \u00e9 unicamente amparada em sua miseric\u00f3rdia e gra\u00e7a, cujo fundamento \u00e9 a obra redentora de Cristo.<\/p>\n<p>Esse Deus misericordioso \u00e9 o nosso Pastor, que nos acompanha sempre com sua miseric\u00f3rdia em todos os lugares e circunst\u00e2ncias.<\/p>\n<p>Foi nesse contexto de ang\u00fastia que Davi escreveu o Salmo 51. O salmo 32 parece ter sido composto depois, quando o salmista recuperou a sua paz com Deus e p\u00f4de refletir mais demoradamente sobre a sua teologia e experi\u00eancia que ilustra aquela.<\/p>\n<p>Este salmo retrata de forma did\u00e1tica, sens\u00edvel e intensa a bem-aventuran\u00e7a do perd\u00e3o de Deus resultante de Sua miseric\u00f3rdia que nos assiste. Ali\u00e1s, \u201cS\u00f3 ser\u00e3o bem-aventurados aqueles que p\u00f5em sua confian\u00e7a na miseric\u00f3rdia de Deus\u201d.<a href=\"#_ftn17\" name=\"_ftnref1\">[17]<\/a><\/p>\n<hr \/>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a>H.J. Stoebe, desex: In: Ernst Jenni; Claus Westermann, eds. <em>Diccionario Teologico Manual del Antiguo Testamento,<\/em> Madrid: Ediciones Cristiandad, 1978, v. 1, p. 832.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Vejam-se: W. Zimmerli, et. al. Xa\/rij: In: G. Friedrich; G. Kittel, eds. <em>Theological Dictionary of the New Testament,<\/em> Grand Rapids, Michigan: Eerdmans, 1982, v. 9, p. 383ss.; Walther Eichrodt, <em>Teologia del Antiguo Testamento,<\/em> Madrid: Ediciones Cristiandad, 1975, v. 1, p. 213ss.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a>C.E. Armerding, Miseric\u00f3rdia: In: Merrill C. Tenney, org. ger., <em>Enciclop\u00e9dia da B\u00edblia, <\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2008, v. 4, p. 296.<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a>Van Groningen, comentando o Salmo 111.1, chama a express\u00e3o de \u201cfidelidade pactual\u201d; no Salmo 118.1, designa de \u201camor pactual\u201d (Gerard Van Groningen, <em>Revela\u00e7\u00e3o Messi\u00e2nica no Velho Testamento, <\/em>Campinas, SP.: Luz para o Caminho, 1995, p. 351, 363). Packer, a traduz por \u201cAmor constante\u201d (J.I. Packer, <em>Voc\u00e1bulos de Deus, <\/em>S\u00e3o Jos\u00e9 dos Campos, SP.: Fiel, 1994, p. 88); \u201cAmor imut\u00e1vel\u201d, traduzem Baer e Gordon (D.A. Baer; R.P. Gordon, Hsd: In: Willem A. VanGemeren, org., <em>Novo Dicion\u00e1rio Internacional de Teologia e Exegese do Antigo Testamento, <\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2011, v. 2, p. 209). Eichrodt, chama de \u201camor sol\u00edcito\u201d (Walther Eichrodt, <em>Teologia del Antiguo Testamento,<\/em> v. 1, p. 213). Harris seguindo a vers\u00e3o King James, cr\u00ea que uma boa tradu\u00e7\u00e3o \u00e9 \u201cbondade amorosa\u201d (R. Laird Harris, hsd: In: R. Laird Harris, et. al., eds. <em>Dicion\u00e1rio Internacional de Teologia do Antigo Testamento,<\/em> S\u00e3o Paulo: Vida Nova, 1998, p. 503).<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a>R. Laird Harris, <strong>i<\/strong>hsd: In: R. Laird Harris, et. al., eds. <em>Dicion\u00e1rio Internacional de Teologia do Antigo Testamento,<\/em> p. 501.<\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a>H.H. Esser, Miseric\u00f3rdia: In: Colin Brown, ed. ger. <em>O Novo Dicion\u00e1rio Internacional de Teologia do Novo Testamento,<\/em> S\u00e3o Paulo: Vida Nova, 1981-1983, v. 3, p. 177.<\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a><em>\u201c<sup>22<\/sup> P\u00f4s-se Salom\u00e3o diante do altar do Senhor, na presen\u00e7a de toda a congrega\u00e7\u00e3o de Israel; e estendeu as m\u00e3os para os c\u00e9us <sup>23<\/sup> e disse: \u00d3 Senhor, Deus de Israel, n\u00e3o h\u00e1 Deus como tu, em cima nos c\u00e9us nem embaixo na terra, como tu que guardas a alian\u00e7a e a <u>miseric\u00f3rdia<\/u><\/em>\u00a0(hesed) <em>a teus servos que de todo o cora\u00e7\u00e3o andam diante de ti\u201d<\/em> (1Rs 8.22-23).<\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a>Cf. Herman Bavinck, <em>Dogm\u00e1tica Reformada, <\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2012, v. 2, p. 230.<\/p>\n<p><a href=\"#_ftnref9\" name=\"_ftn9\">[9]<\/a><em>\u201c<sup>6<\/sup> Porque tu \u00e9s povo santo ao Senhor, teu Deus; o Senhor, teu Deus, te escolheu, para que lhe fosses o seu povo pr\u00f3prio, de todos os povos que h\u00e1 sobre a terra. <sup>7<\/sup> N\u00e3o vos teve o Senhor afei\u00e7\u00e3o, nem vos escolheu porque f\u00f4sseis mais numerosos do que qualquer povo, pois \u00e9reis o menor de todos os povos, <sup>8<\/sup> mas porque o Senhor vos amava e, para guardar o juramento que fizera a vossos pais, o Senhor vos tirou com m\u00e3o poderosa e vos resgatou da casa da servid\u00e3o, do poder de Fara\u00f3, rei do Egito. <sup>9<\/sup> Saber\u00e1s, pois, que o Senhor, teu Deus, \u00e9 Deus, o Deus fiel, que guarda a alian\u00e7a e a <u>miseric\u00f3rdia<\/u><\/em>\u00a0(hesed)<em> at\u00e9 mil gera\u00e7\u00f5es aos que o amam e cumprem os seus mandamentos; <sup>10<\/sup> e d\u00e1 o pago diretamente aos que o odeiam, fazendo-os perecer; n\u00e3o ser\u00e1 demorado para com o que o odeia; prontamente, lho retribuir\u00e1. <sup>11<\/sup>Guarda, pois, os mandamentos, e os estatutos, e os ju\u00edzos que hoje te mando cumprir\u201d<\/em> (Dt 7.6-11).<\/p>\n<p><a href=\"#_ftnref10\" name=\"_ftn10\">[10]<\/a><em>\u201c<\/em><em>Mas Deus, sendo rico em <u>miseric\u00f3rdia<\/u><\/em><em>, por causa do grande amor com que nos amou\u201d<\/em> (Ef 2.4).<\/p>\n<p><a href=\"#_ftnref11\" name=\"_ftn11\">[11]<\/a>A palavra hebraica \u00e9 traduzida de forma variada no AT.: <em>Bondade<\/em> (Sl 21.3; 23.6); <em>bom<\/em> (Sl 25.8; 34.9,15); <em>bem<\/em> (Sl 34.11,12; 37.3); <em>melhor<\/em> (Sl 63.3; 118.8,9); <em>vale mais<\/em> (Sl 84.10); bens (Sl 107.9). A Cria\u00e7\u00e3o \u00e9, em seu estado original, avaliada por Deus como sendo boa (Gn 1.4,10,12,18,21,25,31).\u00a0 \u00a0Por vezes a palavra tem o sentido est\u00e9tico (belo, agrad\u00e1vel) ainda que n\u00e3o indique necessariamente algo bom, mas, o caminho adequado para se conseguir o que deseja ou, na mesma linha de subjetividade, o que parece bom aos nossos olhos (Gn 19.8; Js 9.25; Et 3.11; 2Rs 20.3). Tipo o \u201cImperativo Hipot\u00e9tico\u201d de Kant, associo eu. (Para um estudo mais exaustivo do termo, vejam-se: Alan Richardson, ed. <em>A Theological Word Book of the Bible, <\/em>London: SCM Press, 13. impression, 1975, p. 99; Andrew Bowling, T\u00f4b: In: R. Laird Harris; Gleason L. Archer, Jr.; Bruce K. Waltke, orgs. <em>Dicion\u00e1rio Internacional de Teologia do Antigo Testamento, <\/em>S\u00e3o Paulo: Vida Nova, 1998, p. 564-566 (Artigo bastante did\u00e1tico). Robert P. Gordon, Twb: In: Willem A. VanGemeren, org., <em>Novo Dicion\u00e1rio Internacional de Teologia e Exegese do Antigo Testamento, <\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2011, v. 2, p. 352-356; E. Beyreuther, Bom: In: \u00a0Colin Brown, ed. ger. <em>O<\/em> <em>Novo Dicion\u00e1rio Internacional de Teologia do Novo Testamento, <\/em>S\u00e3o Paulo: Vida Nova, 1981-1983, v. 1, p. 319-327; W. Grundmann, A)gaqo\/j: In: G. Kittel; G. Friedrich, eds. <em>Theological Dictionary of the New Testament,<\/em> Grand Rapids, Michigan: Eerdmans, 1983 (Reprinted), v. 1, p. 10-18; W. Grundmann, Kalo\/j: G. Kittel; G. Friedrich, eds. <em>Theological Dictionary of the New Testament, <\/em>v. 3, p. 536-550; I. H\u00f6ver-Johag, bOs: In: G. Johannes Botterweck; Helmer Ringgren, eds., <em>Theological Dictionary of the Old Testament, <\/em>Grand Rapids, MI.: Eerdmans, 1980 (Revised edition), v. 5, p. 296-317; Bom: W.E. Vine; Merril F. Unger; William White Jr., <em>Dicion\u00e1rio Vine: o significado exeg\u00e9tico e expositivo das palavras do Antigo e do Novo Testamento, <\/em>Rio de Janeiro: Casa Publicadora das Assembleias de Deus, 2002, p. 55-56 (Pequeno, por\u00e9m, significativo artigo).<\/p>\n<p><a href=\"#_ftnref12\" name=\"_ftn12\">[12]<\/a> Para um estudo mais exaustivo do uso da palavra e de suas variantes, vejam-se: M.G. Abegg, Jr., Gdl: In: Willem A. VanGemeren, org., <em>Novo Dicion\u00e1rio Internacional de Teologia e Exegese do Antigo Testamento, <\/em>S\u00e3o Paulo: Cultura Crist\u00e3, 2011, v. 1, p. 798-801; Jan Bergman, et. al., G\u00e2dhal: In: G.J. Botterweck, Helmer Ringgren, eds., <em>Theological Dictionary of the Old Testament, <\/em>Grand Rapids, MI.: Eerdmans, 1977 (Revised edition), v. 2, p. 390-416. (Para os nossos objetivos, especialmente, as p\u00e1ginas 406-412).<\/p>\n<p><a href=\"#_ftnref13\" name=\"_ftn13\">[13]<\/a>Veja-se: R. Bultmann, E)\/leoj: In: G. Kittel; G. Friedrich, eds. <em>Theological Dictionary of the New Testament,<\/em> Grand Rapids, Michigan: Eerdmans, 1982 (Reprinted), v. 2, p. 479-482.<\/p>\n<p><a href=\"#_ftnref14\" name=\"_ftn14\">[14]<\/a> \u201cJu\u00edzos\u201d, enfatizam a suprema autoridade de Deus em nos prescrever as leis que devem regular as nossas rela\u00e7\u00f5es e exigir que as cumpramos. <em>\u201cAgora, pois, \u00f3 Israel, ouve os estatutos e os <u>ju\u00edzos<\/u> <\/em>(mishpat) <em>que eu vos ensino, para os cumprirdes, para que vivais, e entreis, e possuais a terra que o SENHOR, Deus de vossos pais, vos d\u00e1. (&#8230;)<\/em> <em><sup>5<\/sup> Eis que vos tenho ensinado estatutos e <u>ju\u00edzos<\/u><\/em>\u00a0(mishpat)<em>, como me mandou o SENHOR, meu Deus, para que assim fa\u00e7ais no meio da terra que passais a possuir.\u00a0 (&#8230;)\u00a0 <sup>8<\/sup> E que grande na\u00e7\u00e3o h\u00e1 que tenha estatutos e <u>ju\u00edzos<\/u><\/em>\u00a0(mishpat) <em>t\u00e3o justos como toda esta lei que eu hoje vos proponho? (&#8230;) <sup>14<\/sup>Tamb\u00e9m o SENHOR me ordenou, ao mesmo tempo, que vos ensinasse estatutos e <u>ju\u00edzos<\/u><\/em>\u00a0(mishpat)<em>, para que os cumpr\u00edsseis na terra a qual passais a possuir\u201d <\/em>(Dt 4.1,5,8,14). <em>\u201cChamou Mois\u00e9s a todo o Israel e disse-lhe: Ouvi, \u00f3 Israel, os estatutos e <u>ju\u00edzos<\/u> <\/em>(mishpat)<em> que hoje vos falo aos ouvidos, para que os aprendais e cuideis em os cumprirdes\u201d <\/em>(Dt 5.1). <em>\u201cEstes, pois, s\u00e3o os mandamentos<\/em>,<em> os estatutos e os <u>ju\u00edzos<\/u> <\/em>(mishpat) <em>que mandou o SENHOR, teu Deus, se te ensinassem, para que os cumprisses na terra a que passas para a possuir\u201d <\/em>(Dt 6.1).<\/p>\n<p><a href=\"#_ftnref15\" name=\"_ftn15\">[15]<\/a> \u201cA f\u00e9 reformada incentiva a humildade epistemol\u00f3gica ao tentar dizer o que Deus est\u00e1 fazendo na hist\u00f3ria. (&#8230;) A hist\u00f3ria de uma perspectiva calvinista \u00e9, na verdade, cheia de mist\u00e9rio\u201d (Darryl G. Hart, 1929 e tudo aquilo, ou o que o calvinismo diz aos historiadores em busca de significado?: In: David W. Hall, <em>Calvino em pra\u00e7a p\u00fablica, <\/em>\u00a0S\u00e3o Paulo: Cultura Crist\u00e3, 2017, p. 21).<\/p>\n<p><a href=\"#_ftnref16\" name=\"_ftn16\">[16]<\/a>Para um estudo mais detalhado do Salmo 6, veja-se: Hermisten M.P. Costa, <em>O Homem no Teatro de Deus: Provid\u00eancia, Tempo, Hist\u00f3ria e Circunst\u00e2ncia, <\/em>\u00a0Eus\u00e9bio, CE.: Peregrino, 2019, p. 367-382.<\/p>\n<p><a href=\"#_ftnref17\" name=\"_ftn1\">[17]<\/a> Jo\u00e3o Calvino, <em>O Livro dos Salmos,<\/em> S\u00e3o Paulo: Paracletos, 1999, v. 2, (Sl 32.1), p. 40.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Devemos ter sempre diante de nossos olhos que a restaura\u00e7\u00e3o concedida por Deus \u00e0 nossa vida \u00e9 unicamente amparada em sua miseric\u00f3rdia e gra\u00e7a, cujo fundamento \u00e9 a obra redentora de Cristo.<\/p>\n","protected":false},"author":133,"featured_media":61128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Devemos ter sempre diante de nossos olhos que a restaura\u00e7\u00e3o concedida por Deus \u00e9 unicamente amparada em sua miseric\u00f3rdia e gra\u00e7a, cujo fundamento \u00e9 a obra redentora de Cristo.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[700],"tags":[2532,2811,2090],"class_list":["post-61125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudos-biblicos","tag-reflexoes-comprometidas","tag-salmo-32","tag-teobrasil","tema-escritura","tema-escritura-dup","tema-estudos-biblicos","tema-misericordia-de-deus","tema-relacionamento","tema-salmos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)\" \/>\n<meta property=\"og:description\" content=\"Devemos ter sempre diante de nossos olhos que a restaura\u00e7\u00e3o concedida por Deus \u00e0 nossa vida \u00e9 unicamente amparada em sua miseric\u00f3rdia e gra\u00e7a, cujo fundamento \u00e9 a obra redentora de Cristo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-05T13:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-25T18:05:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/02\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hermisten Maia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hermisten Maia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/\"},\"author\":{\"name\":\"Hermisten Maia\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/cf905e2261780bfba3cda58932d1b22b\"},\"headline\":\"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)\",\"datePublished\":\"2022-03-05T13:00:06+00:00\",\"dateModified\":\"2022-08-25T18:05:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/\"},\"wordCount\":4530,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1\",\"keywords\":[\"Reflex\u00f5es Comprometidas\",\"Salmo 32\",\"TeoBrasil\"],\"articleSection\":[\"Estudos B\u00edblicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/\",\"name\":\"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1\",\"datePublished\":\"2022-03-05T13:00:06+00:00\",\"dateModified\":\"2022-08-25T18:05:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1\",\"width\":750,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/03\\\/salmo-32-a-misericordia-que-nos-assiste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/cf905e2261780bfba3cda58932d1b22b\",\"name\":\"Hermisten Maia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"caption\":\"Hermisten Maia\"},\"description\":\"Hermisten Maia \u00e9 ministro da Igreja Presbiteriana do Brasil, integrando a Equipe de Pastores da Primeira IP de S\u00e3o Bernardo do Campo, SP. \u00c9 formado em Teologia, Filosofia e Pedagogia. \u00c9 Mestre e Doutor em Ci\u00eancias da Religi\u00e3o. Leciona em diversos Semin\u00e1rios ininterruptamente desde 1980. Tem experi\u00eancia na \u00e1rea de Teologia Sistem\u00e1tica, lecionando h\u00e1 40 anos, e Hist\u00f3ria da Reforma Protestante, atuando principalmente nos seguintes temas: Jo\u00e3o Calvino e Teologia Reformada e Cosmovis\u00e3o Reformada. Faz parte de diversos Conselhos Editoriais de Revistas de Teologia e de Ci\u00eancias da Religi\u00e3o. Tem 40 livros escritos e mais de 1.500 artigos publicados. Leciona em diversas Institui\u00e7\u00f5es de Ensino Superior no Brasil. Publica diariamente em suas redes sociais um artigo e um v\u00eddeo.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/hermisten-maia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/","og_locale":"pt_BR","og_type":"article","og_title":"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)","og_description":"Devemos ter sempre diante de nossos olhos que a restaura\u00e7\u00e3o concedida por Deus \u00e0 nossa vida \u00e9 unicamente amparada em sua miseric\u00f3rdia e gra\u00e7a, cujo fundamento \u00e9 a obra redentora de Cristo.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2022-03-05T13:00:06+00:00","article_modified_time":"2022-08-25T18:05:10+00:00","og_image":[{"width":750,"height":395,"url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/02\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg","type":"image\/jpeg"}],"author":"Hermisten Maia","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Hermisten Maia","Est. tempo de leitura":"25 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/"},"author":{"name":"Hermisten Maia","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/cf905e2261780bfba3cda58932d1b22b"},"headline":"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)","datePublished":"2022-03-05T13:00:06+00:00","dateModified":"2022-08-25T18:05:10+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/"},"wordCount":4530,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/02\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1","keywords":["Reflex\u00f5es Comprometidas","Salmo 32","TeoBrasil"],"articleSection":["Estudos B\u00edblicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/","name":"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/02\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1","datePublished":"2022-03-05T13:00:06+00:00","dateModified":"2022-08-25T18:05:10+00:00","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/02\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/02\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1","width":750,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/03\/salmo-32-a-misericordia-que-nos-assiste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Salmo 32: A Miseric\u00f3rdia que nos assiste (Parte 1)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/cf905e2261780bfba3cda58932d1b22b","name":"Hermisten Maia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","caption":"Hermisten Maia"},"description":"Hermisten Maia \u00e9 ministro da Igreja Presbiteriana do Brasil, integrando a Equipe de Pastores da Primeira IP de S\u00e3o Bernardo do Campo, SP. \u00c9 formado em Teologia, Filosofia e Pedagogia. \u00c9 Mestre e Doutor em Ci\u00eancias da Religi\u00e3o. Leciona em diversos Semin\u00e1rios ininterruptamente desde 1980. Tem experi\u00eancia na \u00e1rea de Teologia Sistem\u00e1tica, lecionando h\u00e1 40 anos, e Hist\u00f3ria da Reforma Protestante, atuando principalmente nos seguintes temas: Jo\u00e3o Calvino e Teologia Reformada e Cosmovis\u00e3o Reformada. Faz parte de diversos Conselhos Editoriais de Revistas de Teologia e de Ci\u00eancias da Religi\u00e3o. Tem 40 livros escritos e mais de 1.500 artigos publicados. Leciona em diversas Institui\u00e7\u00f5es de Ensino Superior no Brasil. Publica diariamente em suas redes sociais um artigo e um v\u00eddeo.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/hermisten-maia\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/02\/salmo-32-a-misericordia-que-nos-assiste-parte-1.jpg?fit=750%2C395&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-fTT","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/61125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=61125"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/61125\/revisions"}],"predecessor-version":[{"id":62299,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/61125\/revisions\/62299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/61128"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=61125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=61125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=61125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}