{"id":63603,"date":"2022-12-07T16:23:51","date_gmt":"2022-12-07T19:23:51","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=63603"},"modified":"2022-12-14T10:34:12","modified_gmt":"2022-12-14T13:34:12","slug":"salmo-32-a-misericordia-que-nos-assiste-parte-26","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/","title":{"rendered":"Salmo 32: A Miseric\u00f3rdia que nos assiste &#8211; (parte 26)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1><b>5. Na Instru\u00e7\u00e3o (8-9)\u00a0 (Continua\u00e7\u00e3o)<\/b><\/h1>\n<p><b>6)<\/b> <i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><span style=\"font-weight: 400;\">Por meio da medita\u00e7\u00e3o e pr\u00e1tica da Palavra, Deus em sua miseric\u00f3rdia nos concede discernimento com clareza. Este \u00e9 o testemunho do salmista: <\/span><i><span style=\"font-weight: 400;\">\u201cA revela\u00e7\u00e3o das tuas palavras <\/span><\/i><i><span style=\"font-weight: 400;\">esclarece<\/span><\/i> <span style=\"font-weight: 400;\">(&#8216;o\u0302r) <\/span><i><span style=\"font-weight: 400;\">e d\u00e1 <\/span><\/i><i><span style=\"font-weight: 400;\">entendimento<\/span><\/i> <span style=\"font-weight: 400;\">(bi\u0302yn) <\/span><i><span style=\"font-weight: 400;\">aos <\/span><\/i><i><span style=\"font-weight: 400;\">simples<\/span><\/i><span style=\"font-weight: 400;\"> (pethiy) (= ing\u00eanuo, tolo, mente aberta)<\/span><i><span style=\"font-weight: 400;\">\u201d<\/span><\/i> <span style=\"font-weight: 400;\">(Sl 119.130).<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para que possamos viver com discernimento, nos instrui Prov\u00e9rbios: <\/span><i><span style=\"font-weight: 400;\">\u201cDeixai os <\/span><\/i><i><span style=\"font-weight: 400;\">insensatos<\/span><\/i><span style=\"font-weight: 400;\"> (pethiy) <\/span><i><span style=\"font-weight: 400;\">e vivei; andai pelo caminho do <\/span><\/i><i><span style=\"font-weight: 400;\">entendimento<\/span><\/i> <span style=\"font-weight: 400;\">(biynah)<\/span><i><span style=\"font-weight: 400;\">\u201d<\/span><\/i> <span style=\"font-weight: 400;\">(Pv 9.6).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span> <span style=\"font-weight: 400;\">Deus deseja que exercitemos o senso cr\u00edtico (Pv 1.4; 14.15) deixando a paix\u00e3o pela \u201c<\/span><i><span style=\"font-weight: 400;\">necedade<\/span><\/i><span style=\"font-weight: 400;\">\u201d (Pv 1.22).<\/span><span style=\"font-weight: 400;\"> MacArthur, pontua:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Um indiv\u00edduo simples \u00e9 como uma porta aberta \u2013 ele n\u00e3o tem discernimento sobre o que pode sair ou entrar. Tudo entra porque ele \u00e9 ignorante, inexperiente, ing\u00eanuo e n\u00e3o sabe discernir as coisas. Pode ser at\u00e9 que tenha orgulho de ter uma \u2018mente aberta\u2019, apesar de ser verdadeiramente um tolo. Mas a Palavra de Deus faz com que essa pessoa seja \u201cs\u00e1bia\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span> <span style=\"font-weight: 400;\"> O escritor de Hebreus\u00a0 exorta a alguns de seus imaturos leitores que n\u00e3o entendiam a superioridade de Cristo sobre todas as coisas:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">11<\/span><\/i><i><span style=\"font-weight: 400;\">A esse respeito temos muitas coisas que dizer e dif\u00edceis de explicar, porquanto vos tendes tornado tardios em <\/span><\/i><i><span style=\"font-weight: 400;\">ouvir<\/span><\/i><i><span style=\"font-weight: 400;\">. <\/span><\/i><i><span style=\"font-weight: 400;\">12<\/span><\/i><i><span style=\"font-weight: 400;\">Pois, com efeito, quando dev\u00edeis ser mestres, atendendo ao tempo decorrido, tendes, novamente, necessidade de algu\u00e9m que vos ensine, de novo, quais s\u00e3o os princ\u00edpios elementares dos or\u00e1culos de Deus; assim, vos tornastes como necessitados de leite e n\u00e3o de alimento s\u00f3lido. <\/span><\/i><span style=\"font-weight: 400;\">(Hb 5.11-12).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O salmista cantando as maravilhas da Lei de Deus, escreve: <\/span><i><span style=\"font-weight: 400;\">\u201c&#8230;. o testemunho do SENHOR \u00e9 fiel e d\u00e1 <\/span><\/i><i><span style=\"font-weight: 400;\">sabedoria<\/span><\/i><span style=\"font-weight: 400;\"> (chakam)<\/span> <i><span style=\"font-weight: 400;\">aos <\/span><\/i><i><span style=\"font-weight: 400;\">s\u00edmplices<\/span><\/i><span style=\"font-weight: 400;\"> (pethiy)<\/span><i><span style=\"font-weight: 400;\">\u201d<\/span><\/i><span style=\"font-weight: 400;\"> (Sl 19.7).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O simples por n\u00e3o perceber o mal do qual se aproxima, conduz-se perigosamente: <\/span><i><span style=\"font-weight: 400;\">\u201cO prudente v\u00ea o mal e esconde-se; mas os <\/span><\/i><i><span style=\"font-weight: 400;\">simples<\/span><\/i><span style=\"font-weight: 400;\"> (pethiy) <\/span><i><span style=\"font-weight: 400;\">passam adiante e sofrem a pena\u201d <\/span><\/i><span style=\"font-weight: 400;\">(Pv 22.3).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Deus deseja produzir em seus servos aspectos do seu car\u00e1ter. A sabedoria consiste em subordinar a nossa vontade aos preceitos de Deus, reconhecendo neles o caminho de uma vida com s\u00e1bio discernimento na presen\u00e7a de Deus. \u201cSer s\u00e1bio \u00e9 dominar a arte do viver di\u00e1rio por interm\u00e9dio do conhecimento da Palavra de Deus e sabendo aplic\u00e1-la em toda situa\u00e7\u00e3o\u201d, conclui MacArthur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Deus concede este discernimento <\/span><i><span style=\"font-weight: 400;\">\u201caos <\/span><\/i><i><span style=\"font-weight: 400;\">s\u00edmplices<\/span><\/i><span style=\"font-weight: 400;\"> (pethiy) (= ing\u00eanuo, tolo, mente aberta)<\/span><i><span style=\"font-weight: 400;\">\u201d<\/span><\/i><span style=\"font-weight: 400;\">, sendo aqui aplicada a palavra \u00e0s pessoas ing\u00eanuas que por n\u00e3o terem desenvolvido uma mente discernidora, \u00e9 aberta a qualquer conceito,<\/span><span style=\"font-weight: 400;\"> n\u00e3o percebendo as armadilhas e contradi\u00e7\u00f5es do seu mosaico inconsistente de pensamento.\u00a0<\/span><\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A Palavra nos conduz \u00e0 maturidade, ao discernimento para que n\u00e3o mais tenhamos uma \u201cmente aberta\u201d onde tudo passe sem fronteira, sendo suscet\u00edvel a todo tipo de sedu\u00e7\u00e3o e engano.<\/span><span style=\"font-weight: 400;\"> Faz-se necess\u00e1rio que pensemos e, como nosso pensamento tamb\u00e9m foi afetado pelo pecado, pensemos sobre o nosso pensamento, rogando o Esp\u00edrito de sabedoria concedido por Deus (Ef 1.17).<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span> <span style=\"font-weight: 400;\">Deus, por interm\u00e9dio da sua Palavra,\u00a0 d\u00e1-nos sabedoria espiritual e discernimento para que possamos reconhecer nos seus testemunhos &#8211; a Palavra de vida eterna a fim de que vejamos com clareza os sinais dos tempos, sem nos deixar levar por falsas doutrinas engenhosamente criadas pelos homens, seguindo sabiamente o caminho de Deus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como escreve Piper, \u201cpensar intensamente sobre a verdade b\u00edblica \u00e9 o meio pelo qual o Esp\u00edrito nos mostra a verdade\u201d.<\/span><span style=\"font-weight: 400;\">\u00a0 Devemos, portanto, aprender a refletir sobre o ensino b\u00edblico, suplicando o discernimento do Esp\u00edrito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Paulo, escrevendo ao jovem Tim\u00f3teo, recorda o aprendizado que ele recebeu nas Escrituras: <\/span><i><span style=\"font-weight: 400;\">\u201c&#8230;. desde a inf\u00e2ncia sabes as sagradas letras que podem tornar-te s\u00e1bio para a salva\u00e7\u00e3o pela f\u00e9 em Cristo Jesus\u201d<\/span><\/i><span style=\"font-weight: 400;\"> (2Tm 3.15).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quem anda em sabedoria n\u00e3o caminha de forma cambaleante (Sl 107.27).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Paradoxalmente, o que tem faltado \u00e0 Igreja \u00e9 sabedoria para discernir, por interm\u00e9dio da Palavra de Deus, o que est\u00e1 acontecendo.\u00a0 Muitas vezes, temos sido iludidos, enganados e espoliados espiritualmente, justamente porque nos tem faltado a medita\u00e7\u00e3o na Palavra de Deus, acompanhada pela ora\u00e7\u00e3o para que Deus nos d\u00ea a compreens\u00e3o dos fatos, da sua vontade para o nosso momento presente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Diz o salmista:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">98<\/span><\/i><i><span style=\"font-weight: 400;\">Os teus mandamentos me fazem mais <\/span><\/i><i><span style=\"font-weight: 400;\">s\u00e1bio<\/span><\/i> <span style=\"font-weight: 400;\">(chakam)<\/span> <i><span style=\"font-weight: 400;\">que os meus inimigos; porque, aqueles, eu os tenho sempre comigo. <\/span><\/i><i><span style=\"font-weight: 400;\">99<\/span><\/i><i><span style=\"font-weight: 400;\">Compreendo mais do que todos os meus mestres, porque medito nos teus testemunhos.\u00a0 <\/span><\/i><i><span style=\"font-weight: 400;\">100<\/span><\/i><i><span style=\"font-weight: 400;\"> Sou mais <\/span><\/i><i><span style=\"font-weight: 400;\">prudente<\/span><\/i><span style=\"font-weight: 400;\"> (biyn) <\/span><i><span style=\"font-weight: 400;\">que os idosos, porque guardo os teus preceitos.\u00a0 <\/span><\/i><i><span style=\"font-weight: 400;\">101<\/span><\/i><i><span style=\"font-weight: 400;\"> De todo mau caminho desvio os p\u00e9s, para observar a tua palavra.<\/span><\/i><span style=\"font-weight: 400;\"> (Sl 119. 98-101).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0\u00a0<\/span> <span style=\"font-weight: 400;\">Deus n\u00e3o deseja um povo ing\u00eanuo, imaturo quanto \u00e0 interpreta\u00e7\u00e3o da realidade. Ele quer que sejamos maduros, aptos para discernir, interpretar os acontecimentos e que, sem titubear, sigamos os seus preceitos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A sabedoria propiciada por Deus\u00a0 d\u00e1-nos discernimento para que possamos nos valer do que for \u00fatil em todos os conhecimentos sem nos perder em meio \u00e0s suas contradi\u00e7\u00f5es, tendo como elemento avaliador a Palavra de Deus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0\u00a0<\/span> <span style=\"font-weight: 400;\">A sabedoria divina oferece-nos um quadro de refer\u00eancia que nos conduz cada vez \u00e0 gratid\u00e3o a Deus por t\u00e3o grandiosa b\u00ean\u00e7\u00e3o. Para que possamos emitir um ju\u00edzo de valor \u00e9 preciso ter valores e um quadro coerente de interpreta\u00e7\u00e3o a partir de determinado valor ou de um conjunto de valores. Notemos, portanto, que pensar com clareza \u00e9 uma grande b\u00ean\u00e7\u00e3o de Deus.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span> <span style=\"font-weight: 400;\">A Palavra de Deus propicia uma revolu\u00e7\u00e3o epistemol\u00f3gica em nossa vida jamais alcan\u00e7ada de outro modo: Ela ilumina o nosso caminho e os nossos passos, ou seja: o que est\u00e1 diante de n\u00f3s. Mas, al\u00e9m disso, ilumina os nossos olhos para poder enxergar isso, o que se configura \u00e0 nossa frente precisando ser avaliado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A realidade pode estar clara diante de n\u00f3s, por\u00e9m, nossos olhos tamb\u00e9m podem estar obscurecidos por v\u00e1rios impedimentos tais como: preconceito, m\u00e1 vontade, falta de esclarecimento do assunto, paix\u00f5es, etc. Por sua vez, nossos olhos podem estar em perfeitas condi\u00e7\u00f5es, por\u00e9m, a pouca luminosidade e a falta de clareza dos fatos podem n\u00e3o nos ajudar. Digamos assim: Deus opera no sujeito e no objeto por meio de sua Palavra.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Calvino comenta sobre isso:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada homem \u00e9 cego, at\u00e9 que Deus tamb\u00e9m ilumine os olhos do entendimento do homem. Admitindo que Deus nos prov\u00ea luz por meio de Sua Palavra, o profeta tem em mente que somos cegos em meio \u00e0 mais clara luz, enquanto Deus n\u00e3o remove o v\u00e9u de nossos olhos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O entendimento proveniente de Deus faz com que tenhamos discernimento em todas as coisas: <\/span><i><span style=\"font-weight: 400;\">\u201cOs homens maus n\u00e3o <\/span><\/i><i><span style=\"font-weight: 400;\">entendem<\/span><\/i><span style=\"font-weight: 400;\"> (bi\u0302yn) <\/span><i><span style=\"font-weight: 400;\">o que \u00e9 justo, mas os que buscam o SENHOR <\/span><\/i><i><span style=\"font-weight: 400;\">entendem<\/span><\/i> <span style=\"font-weight: 400;\">(bi\u0302yn) <\/span><i><span style=\"font-weight: 400;\">tudo\u201d<\/span><\/i><span style=\"font-weight: 400;\"> (Pv 28.5). <\/span><i><span style=\"font-weight: 400;\">\u201cSou mais <\/span><\/i><i><span style=\"font-weight: 400;\">prudente<\/span><\/i> <span style=\"font-weight: 400;\">(bi\u0302yn) <\/span><i><span style=\"font-weight: 400;\">que os idosos, porque <\/span><\/i><i><span style=\"font-weight: 400;\">guardo<\/span><\/i> <span style=\"font-weight: 400;\">(na\u0302tsar)<\/span><i><span style=\"font-weight: 400;\"> os teus preceitos\u201d<\/span><\/i> <span style=\"font-weight: 400;\">(Sl 119.100).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este discernimento, contudo, n\u00e3o \u00e9 apenas para uma satisfa\u00e7\u00e3o intelectual, antes tem um efeito pr\u00e1tico. Ele \u00e9, de certa forma, profil\u00e1tico: <\/span><i><span style=\"font-weight: 400;\">\u201cPor meio dos teus preceitos, consigo <\/span><\/i><i><span style=\"font-weight: 400;\">entendimento<\/span><\/i> <span style=\"font-weight: 400;\">(bi\u0302yn)<\/span><i><span style=\"font-weight: 400;\">; por isso, detesto todo caminho de falsidade\u201d<\/span><\/i> <span style=\"font-weight: 400;\">(Sl 119.104).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, \u00e0 pergunta de J\u00f3 sobre onde encontrar a sabedoria e o entendimento, ele mesmo apresenta a resposta:\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Mas onde se achar\u00e1 a sabedoria? E onde est\u00e1 o lugar do <\/span><\/i><i><span style=\"font-weight: 400;\">entendimento<\/span><\/i> <span style=\"font-weight: 400;\">(bi\u0302yna\u0302h)<\/span><i><span style=\"font-weight: 400;\">?<\/span><\/i> <span style=\"font-weight: 400;\">(J\u00f3 28.12). <\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Donde, pois, vem a sabedoria, e onde est\u00e1 o lugar do <\/span><\/i><i><span style=\"font-weight: 400;\">entendimento<\/span><\/i> <span style=\"font-weight: 400;\">(bi\u0302yna\u0302h)?<\/span> <span style=\"font-weight: 400;\">(J\u00f3 12.20).\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">E disse ao homem: Eis que o temor do Senhor \u00e9 a sabedoria, e o apartar-se do mal \u00e9 o <\/span><\/i><i><span style=\"font-weight: 400;\">entendimento<\/span><\/i><span style=\"font-weight: 400;\"> (bi\u0302yna\u0302h)<\/span><i><span style=\"font-weight: 400;\">. <\/span><\/i><span style=\"font-weight: 400;\">(J\u00f3 28.28).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O nosso discernimento revela-se em nos apartar do mal seguindo a Lei de Deus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span> <span style=\"font-weight: 400;\">Jesus Cristo afirma que aquele que deseja fazer a vontade de Deus deve examinar a doutrina: <\/span><i><span style=\"font-weight: 400;\">\u201cSe algu\u00e9m quiser fazer a <\/span><\/i><i><span style=\"font-weight: 400;\">vontade<\/span><\/i><i><span style=\"font-weight: 400;\"> dele (Deus), <\/span><\/i><i><span style=\"font-weight: 400;\">conhecer\u00e1<\/span><\/i><i><span style=\"font-weight: 400;\"> a respeito da <\/span><\/i><i><span style=\"font-weight: 400;\">doutrina<\/span><\/i><i><span style=\"font-weight: 400;\">, se ela \u00e9 de Deus\u201d <\/span><\/i><span style=\"font-weight: 400;\">(Jo 7.17).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 necess\u00e1rio discernimento para interpretar as doutrinas que nos s\u00e3o transmitidas a fim de saber se s\u00e3o de Deus ou n\u00e3o. Portanto, devemos desejar conhecer a vontade de Deus (Ef 5.17).\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O falso mestre \u00e9 aquele que ensina a mentira, o engano: cria imagens que nada s\u00e3o para corromper seus ouvintes, conduzindo-os a negar o pr\u00f3prio Senhor Jesus Cristo e, tamb\u00e9m, \u00e0 viverem libertinamente, ou seja, de modo dissoluto e lascivo.<\/span><span style=\"font-weight: 400;\"> Por causa disso, o caminho do Evangelho seria caluniado, reprovado, \u201cblasfemado\u201d. A mensagem desses falsos mestres consiste numa corrup\u00e7\u00e3o do Evangelho.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">(Plast\u00f3s) parece ter o sentido aqui de palavras artisticamente elaboradas, moldadas, sugestivas, por\u00e9m, falsas, forjadas em seu pr\u00f3prio proveito, e, que por isso mesmo est\u00e3o em oposi\u00e7\u00e3o \u00e0 verdade. Curiosamente este \u00e9 o termo de onde vem a nossa palavra \u201cpl\u00e1stico\u201d.<\/span><span style=\"font-weight: 400;\"> O ensino crist\u00e3o envolve arte, mas n\u00e3o \u201carte pl\u00e1stica\u201d para com a verdade.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00f3s crist\u00e3os, precisamos treinar os nossos ouvidos: <\/span><i><span style=\"font-weight: 400;\">\u201cPorque o ouvido <\/span><\/i><i><span style=\"font-weight: 400;\">prova<\/span><\/i> <span style=\"font-weight: 400;\">(bahan)(<\/span><i><span style=\"font-weight: 400;\">examina, testa<\/span><\/i><span style=\"font-weight: 400;\">) <\/span><i><span style=\"font-weight: 400;\">as palavras, como o paladar, a comida\u201d <\/span><\/i><span style=\"font-weight: 400;\">(J\u00f3 34.3\/J\u00f3 12.11).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O caminho da sabedoria \u00e9 o caminho da santidade. Se n\u00f3s queremos ser santos, devemos buscar na Palavra de Deus a coragem para cumprir os seus decretos, o \u00e2nimo para n\u00e3o nos abatermos com as ciladas do diabo, e o discernimento e sabedoria para que possamos interpretar a Palavra de Deus, avaliando os fatos, e aplicando os princ\u00edpios eternos de Deus \u00e0 nossa realidade cotidiana.<\/span><\/p>\n<p>&#8212;&#8212;<\/p>\n<p>[1] <span style=\"font-weight: 400;\">Por isso mesmo Deus nos convida a um exame de Sua Palavra. Nela temos os Seus ensinamentos e promessas que, de fato, podem iluminar os nossos olhos, apontando e nos capacitando a seguir o Seu caminho<\/span><i><span style=\"font-weight: 400;\">. \u201cPorque o mandamento \u00e9 l\u00e2mpada, e a instru\u00e7\u00e3o, <\/span><\/i><i><span style=\"font-weight: 400;\">luz<\/span><\/i> <span style=\"font-weight: 400;\">(&#8216;o\u0302r)&#8230;.\u201d<\/span> <span style=\"font-weight: 400;\">(Pv 6.23). Esta \u00e9 a experi\u00eancia do salmista: <\/span><i><span style=\"font-weight: 400;\">\u201cOs preceitos do SENHOR s\u00e3o retos e alegram o cora\u00e7\u00e3o; o mandamento do SENHOR \u00e9 puro e <\/span><\/i><i><span style=\"font-weight: 400;\">ilumina<\/span><\/i><span style=\"font-weight: 400;\"> (&#8216;o\u0302r) <\/span><i><span style=\"font-weight: 400;\">os olhos\u201d<\/span><\/i> <span style=\"font-weight: 400;\">(Sl 19.8).<\/span><i><span style=\"font-weight: 400;\"> \u201cL\u00e2mpada para os meus p\u00e9s \u00e9 a tua palavra e, <\/span><\/i><i><span style=\"font-weight: 400;\">luz<\/span><\/i> <span style=\"font-weight: 400;\">(&#8216;o\u0302r) <\/span><i><span style=\"font-weight: 400;\">para os meus caminhos\u201d<\/span><\/i> <span style=\"font-weight: 400;\">(Sl 119.105). Nas Escrituras, seguir a instru\u00e7\u00e3o de Deus \u00e9 o mesmo que andar na luz: <\/span><i><span style=\"font-weight: 400;\">\u201cIr\u00e3o muitas na\u00e7\u00f5es e dir\u00e3o: Vinde, e subamos ao monte do SENHOR e \u00e0 casa do Deus de Jac\u00f3, para que nos ensine os seus caminhos, e andemos pelas suas veredas; porque de Si\u00e3o sair\u00e1 a lei, e a palavra do SENHOR, de Jerusal\u00e9m (&#8230;) Vinde, \u00f3 casa de Jac\u00f3, e andemos na <\/span><\/i><i><span style=\"font-weight: 400;\">luz<\/span><\/i><span style=\"font-weight: 400;\"> (<\/span><span style=\"font-weight: 400;\">rAa<\/span><span style=\"font-weight: 400;\">) (&#8216;o\u0302r) <\/span><i><span style=\"font-weight: 400;\">do SENHOR\u201d <\/span><\/i><span style=\"font-weight: 400;\">(Is 2.3,5).<\/span><i><span style=\"font-weight: 400;\"> \u201cAtendei-me, povo meu, e escutai-me, na\u00e7\u00e3o minha; porque de mim sair\u00e1 a lei, e estabelecerei o meu direito como <\/span><\/i><i><span style=\"font-weight: 400;\">luz<\/span><\/i><span style=\"font-weight: 400;\"> (&#8216;o\u0302r) <\/span><i><span style=\"font-weight: 400;\">dos povos\u201d <\/span><\/i><span style=\"font-weight: 400;\">(Is 51.4). (Para um estudo mais pormenorizado do emprego da palavra no Antigo Testamento, vejam-se: H. Wolf, \u2018\u00f4r: In: L. Harris, et. al., eds.,<\/span><i><span style=\"font-weight: 400;\"> Dicion\u00e1rio Internacional de Teologia do Antigo Testamento, <\/span><\/i><span style=\"font-weight: 400;\">S\u00e3o Paulo: Vida Nova, 1998, p. 38-42; William Gesenius, <\/span><i><span style=\"font-weight: 400;\">Hebrew-Chaldee Lexicon to the Old Testament<\/span><\/i><span style=\"font-weight: 400;\">,<\/span> <span style=\"font-weight: 400;\">3. ed. Michigan: WM. Eerdmans Publishing Co. 1978, p. 23).<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p>[2] <i><span style=\"font-weight: 400;\">\u201cAt\u00e9 quando, \u00f3 <\/span><\/i><i><span style=\"font-weight: 400;\">n\u00e9scios<\/span><\/i> <span style=\"font-weight: 400;\">(pethiy)<\/span><i><span style=\"font-weight: 400;\">, amareis a <\/span><\/i><i><span style=\"font-weight: 400;\">necedade<\/span><\/i> <span style=\"font-weight: 400;\">(pethiy)<\/span><i><span style=\"font-weight: 400;\">? E v\u00f3s, escarnecedores, desejareis o esc\u00e1rnio? E v\u00f3s, loucos, aborrecereis o conhecimento?\u201d<\/span><\/i><span style=\"font-weight: 400;\"> (Pv 1.22).<\/span><\/p>\n<p>[3] <span style=\"font-weight: 400;\">John F. MacArthur Jr., Adotando a Autoridade e a Sufici\u00eancia das Escrituras: In: J.F. MacArthur Jr., ed. ger., <\/span><i><span style=\"font-weight: 400;\">Pense Biblicamente!: recuperando a vis\u00e3o crist\u00e3 do mundo, <\/span><\/i><span style=\"font-weight: 400;\">S\u00e3o Paulo: Hagnos, 2005, p. 39. Veja-se tamb\u00e9m: J.F. MacArthur, Jr., <\/span><i><span style=\"font-weight: 400;\">Nossa Sufici\u00eancia em Cristo, <\/span><\/i><span style=\"font-weight: 400;\">S\u00e3o Jos\u00e9 dos Campos, SP.: Fiel, 1995, p. 68.<\/span><\/p>\n<p>[4] <span style=\"font-weight: 400;\">John MacArthur, Adotando a Autoridade e a Sufici\u00eancia das Escrituras. In: John MacArthur, ed. ger., <\/span><i><span style=\"font-weight: 400;\">Pense Biblicamente!: recuperando a vis\u00e3o crist\u00e3 do mundo, <\/span><\/i><span style=\"font-weight: 400;\">S\u00e3o Paulo: Hagnos, 2005, p. 39.<\/span><\/p>\n<p>[5] <i><span style=\"font-weight: 400;\">O <\/span><\/i><i><span style=\"font-weight: 400;\">simples<\/span><\/i><span style=\"font-weight: 400;\"> (pethiy) <\/span><i><span style=\"font-weight: 400;\">d\u00e1 cr\u00e9dito a toda palavra, mas o prudente <\/span><\/i><i><span style=\"font-weight: 400;\">atenta<\/span><\/i><span style=\"font-weight: 400;\"> (biyn) <\/span><i><span style=\"font-weight: 400;\">para os seus passos\u201d<\/span><\/i><span style=\"font-weight: 400;\"> (Pv 14.15).<\/span><\/p>\n<p>[6] <span style=\"font-weight: 400;\">Cf. Louis Goldberg, Pet\u00ee: In: R. Laird Harris, et. al., eds. <\/span><i><span style=\"font-weight: 400;\">Dicion\u00e1rio Internacional de Teologia do Antigo Testamento,<\/span><\/i> <span style=\"font-weight: 400;\">S\u00e3o Paulo: Vida Nova, 1998, p. 1249. Para um estudo mais detalhado da palavra, veja-se: M. Saebo, Pth: In: E. Jenni; C. Westermann, eds., <\/span><i><span style=\"font-weight: 400;\">Diccionario Teologico Manual del Antiguo Testamento, <\/span><\/i><span style=\"font-weight: 400;\">Madrid: Ediciones Cristiandad, 1985, v. 2, p. 624-628. <\/span><\/p>\n<p>[7] <span style=\"font-weight: 400;\">\u201cOs crist\u00e3os precisam pensar sobre o pensamento. (&#8230;) A maioria dos seres humanos, contudo, nunca pensa profundamente sobre o ato de pensar. (&#8230;) Devido \u00e0 devasta\u00e7\u00e3o intelectual causada pela queda, temos a obriga\u00e7\u00e3o de pensar sobre o ato de pensar. Essa \u00e9 a raz\u00e3o pela qual o discipulado crist\u00e3o \u00e9, tamb\u00e9m, uma atividade intelectual\u201d (R. Albert Mohler Jr., O modo como o mundo pensa: Um encontro com a mente natural no espelho e no mercado. In: John Piper; David Mathis, orgs. <\/span><i><span style=\"font-weight: 400;\">Pensar \u2013 Amar \u2013 Fazer, <\/span><\/i><span style=\"font-weight: 400;\">S\u00e3o Paulo: Cultura Crist\u00e3, 2013, p. 44,45,54).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cVoc\u00ea n\u00e3o precisa acreditar em tudo o que pensa, e a raz\u00e3o \u00e9 simples: n\u00f3s vemos o que queremos ver. (&#8230;) O nervo \u00f3ptico, o \u00fanico nervo com liga\u00e7\u00e3o direta com o c\u00e9rebro, na verdade transmite mais impulsos do c\u00e9rebro para o olho do que vice-versa. Isto significa que se c\u00e9rebro determina o que o olho v\u00ea. Voc\u00ea j\u00e1 est\u00e1 precondicionado. \u00c9 por isso que, se quatro pessoas presenciarem um acidente, cada uma vai relatar algo diferente. Precisamos nos lembrar, e ensinar aos outros, que n\u00e3o devemos acreditar em tudo o que pensamos\u201d (Rick Waren, A batalha pela sua mente. In: John Piper; David Mathis, orgs. <\/span><i><span style=\"font-weight: 400;\">Pensar \u2013 Amar \u2013 Fazer<\/span><\/i><span style=\"font-weight: 400;\">, S\u00e3o Paulo: Cultura Crist\u00e3, 2013, p. 27). <\/span><\/p>\n<p>[8] <span style=\"font-weight: 400;\">John Piper: In: John Piper; D.A. Carson, <\/span><i><span style=\"font-weight: 400;\">O Pastor Mestre e O Mestre Pastor, <\/span><\/i><span style=\"font-weight: 400;\">S\u00e3o Jos\u00e9 dos Campos, SP.: Fiel, 2011, p. 64.<\/span><\/p>\n<p>[9] <span style=\"font-weight: 400;\">Veja-se: John MacArthur Jr., <\/span><i><span style=\"font-weight: 400;\">Abaixo a Ansiedade<\/span><\/i><b>, <\/b><span style=\"font-weight: 400;\">S\u00e3o Paulo: Editora Cultura Crist\u00e3, 2001, p. 32.<\/span><\/p>\n<p>[10] <span style=\"font-weight: 400;\">Jo\u00e3o Calvino, <\/span><i><span style=\"font-weight: 400;\">Salmos, <\/span><\/i><span style=\"font-weight: 400;\">S\u00e3o Jos\u00e9 dos Campos, SP.: Fiel, 2009, v. 4, (Sl 119.18), p. 184.<\/span><\/p>\n<p>[11] <span style=\"font-weight: 400;\">Este termo<\/span><span style=\"font-weight: 400;\"> ocorre nos seguintes textos do Novo Testamento: Mc 7.22; Rm 13.13; 2Co 12.21; Gl 5.19; Ef 4.19; 1Pe 4.3; 2Pe 2.2,7,18; Jd 4.<\/span>[\/vc_column_text][vc_message message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;grey&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Autor: Hermisten Maia. \u00a9 Voltemos ao Evangelho. Website: voltemosaoevangelho.com. Todos os direitos reservados. Editor e Revisor: Vinicius Lima.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00c9 necess\u00e1rio discernimento para interpretar as doutrinas que nos s\u00e3o transmitidas a fim de saber se s\u00e3o de Deus ou n\u00e3o. Portanto, devemos desejar conhecer a vontade de Deus.<\/p>\n","protected":false},"author":133,"featured_media":63606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[700,371],"tags":[2532,2811,2090],"class_list":["post-63603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudos-biblicos","category-teologia-biblica","tag-reflexoes-comprometidas","tag-salmo-32","tag-teobrasil","tema-atributos-de-deus-dup","tema-estudos-biblicos","tema-pecado-hamartiologia","tema-perdao","tema-soberania-de-deus","tema-teologia","categoria-artigo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salmo 32: A Miseric\u00f3rdia que nos assiste - (parte 26)<\/title>\n<meta name=\"description\" content=\"\u00c9 necess\u00e1rio discernimento para interpretar as doutrinas que nos s\u00e3o transmitidas a fim de saber se s\u00e3o de Deus ou n\u00e3o. Portanto, devemos desejar conhecer a vontade de Deus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salmo 32: A Miseric\u00f3rdia que nos assiste - (parte 26)\" \/>\n<meta property=\"og:description\" content=\"\u00c9 necess\u00e1rio discernimento para interpretar as doutrinas que nos s\u00e3o transmitidas a fim de saber se s\u00e3o de Deus ou n\u00e3o. Portanto, devemos desejar conhecer a vontade de Deus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-07T19:23:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T13:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/12\/aaron-burden-535Npq1wFG8-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hermisten Maia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hermisten Maia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/\"},\"author\":{\"name\":\"Hermisten Maia\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/cf905e2261780bfba3cda58932d1b22b\"},\"headline\":\"Salmo 32: A Miseric\u00f3rdia que nos assiste &#8211; (parte 26)\",\"datePublished\":\"2022-12-07T19:23:51+00:00\",\"dateModified\":\"2022-12-14T13:34:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/\"},\"wordCount\":2329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1\",\"keywords\":[\"Reflex\u00f5es Comprometidas\",\"Salmo 32\",\"TeoBrasil\"],\"articleSection\":[\"Estudos B\u00edblicos\",\"Teologia B\u00edblica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/\",\"name\":\"Salmo 32: A Miseric\u00f3rdia que nos assiste - (parte 26)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1\",\"datePublished\":\"2022-12-07T19:23:51+00:00\",\"dateModified\":\"2022-12-14T13:34:12+00:00\",\"description\":\"\u00c9 necess\u00e1rio discernimento para interpretar as doutrinas que nos s\u00e3o transmitidas a fim de saber se s\u00e3o de Deus ou n\u00e3o. Portanto, devemos desejar conhecer a vontade de Deus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1\",\"width\":750,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2022\\\/12\\\/salmo-32-a-misericordia-que-nos-assiste-parte-26\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salmo 32: A Miseric\u00f3rdia que nos assiste &#8211; (parte 26)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/cf905e2261780bfba3cda58932d1b22b\",\"name\":\"Hermisten Maia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g\",\"caption\":\"Hermisten Maia\"},\"description\":\"Hermisten Maia \u00e9 ministro da Igreja Presbiteriana do Brasil, integrando a Equipe de Pastores da Primeira IP de S\u00e3o Bernardo do Campo, SP. \u00c9 formado em Teologia, Filosofia e Pedagogia. \u00c9 Mestre e Doutor em Ci\u00eancias da Religi\u00e3o. Leciona em diversos Semin\u00e1rios ininterruptamente desde 1980. Tem experi\u00eancia na \u00e1rea de Teologia Sistem\u00e1tica, lecionando h\u00e1 40 anos, e Hist\u00f3ria da Reforma Protestante, atuando principalmente nos seguintes temas: Jo\u00e3o Calvino e Teologia Reformada e Cosmovis\u00e3o Reformada. Faz parte de diversos Conselhos Editoriais de Revistas de Teologia e de Ci\u00eancias da Religi\u00e3o. Tem 40 livros escritos e mais de 1.500 artigos publicados. Leciona em diversas Institui\u00e7\u00f5es de Ensino Superior no Brasil. Publica diariamente em suas redes sociais um artigo e um v\u00eddeo.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/hermisten-maia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salmo 32: A Miseric\u00f3rdia que nos assiste - (parte 26)","description":"\u00c9 necess\u00e1rio discernimento para interpretar as doutrinas que nos s\u00e3o transmitidas a fim de saber se s\u00e3o de Deus ou n\u00e3o. Portanto, devemos desejar conhecer a vontade de Deus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/","og_locale":"pt_BR","og_type":"article","og_title":"Salmo 32: A Miseric\u00f3rdia que nos assiste - (parte 26)","og_description":"\u00c9 necess\u00e1rio discernimento para interpretar as doutrinas que nos s\u00e3o transmitidas a fim de saber se s\u00e3o de Deus ou n\u00e3o. Portanto, devemos desejar conhecer a vontade de Deus.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2022-12-07T19:23:51+00:00","article_modified_time":"2022-12-14T13:34:12+00:00","og_image":[{"width":750,"height":563,"url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/12\/aaron-burden-535Npq1wFG8-unsplash.jpg","type":"image\/jpeg"}],"author":"Hermisten Maia","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Hermisten Maia","Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/"},"author":{"name":"Hermisten Maia","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/cf905e2261780bfba3cda58932d1b22b"},"headline":"Salmo 32: A Miseric\u00f3rdia que nos assiste &#8211; (parte 26)","datePublished":"2022-12-07T19:23:51+00:00","dateModified":"2022-12-14T13:34:12+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/"},"wordCount":2329,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/12\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1","keywords":["Reflex\u00f5es Comprometidas","Salmo 32","TeoBrasil"],"articleSection":["Estudos B\u00edblicos","Teologia B\u00edblica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/","name":"Salmo 32: A Miseric\u00f3rdia que nos assiste - (parte 26)","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/12\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1","datePublished":"2022-12-07T19:23:51+00:00","dateModified":"2022-12-14T13:34:12+00:00","description":"\u00c9 necess\u00e1rio discernimento para interpretar as doutrinas que nos s\u00e3o transmitidas a fim de saber se s\u00e3o de Deus ou n\u00e3o. Portanto, devemos desejar conhecer a vontade de Deus.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/12\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/12\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1","width":750,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2022\/12\/salmo-32-a-misericordia-que-nos-assiste-parte-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Salmo 32: A Miseric\u00f3rdia que nos assiste &#8211; (parte 26)"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/cf905e2261780bfba3cda58932d1b22b","name":"Hermisten Maia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20a122e67798d4049bc4cbbf17df84dc5c06ef0e060afe4bb9b31e081200eff7?s=96&d=mm&r=g","caption":"Hermisten Maia"},"description":"Hermisten Maia \u00e9 ministro da Igreja Presbiteriana do Brasil, integrando a Equipe de Pastores da Primeira IP de S\u00e3o Bernardo do Campo, SP. \u00c9 formado em Teologia, Filosofia e Pedagogia. \u00c9 Mestre e Doutor em Ci\u00eancias da Religi\u00e3o. Leciona em diversos Semin\u00e1rios ininterruptamente desde 1980. Tem experi\u00eancia na \u00e1rea de Teologia Sistem\u00e1tica, lecionando h\u00e1 40 anos, e Hist\u00f3ria da Reforma Protestante, atuando principalmente nos seguintes temas: Jo\u00e3o Calvino e Teologia Reformada e Cosmovis\u00e3o Reformada. Faz parte de diversos Conselhos Editoriais de Revistas de Teologia e de Ci\u00eancias da Religi\u00e3o. Tem 40 livros escritos e mais de 1.500 artigos publicados. Leciona em diversas Institui\u00e7\u00f5es de Ensino Superior no Brasil. Publica diariamente em suas redes sociais um artigo e um v\u00eddeo.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/hermisten-maia\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2022\/12\/aaron-burden-535Npq1wFG8-unsplash.jpg?fit=750%2C563&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-gxR","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/63603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=63603"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/63603\/revisions"}],"predecessor-version":[{"id":63607,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/63603\/revisions\/63607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/63606"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=63603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=63603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=63603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}