{"id":64748,"date":"2023-05-01T08:00:20","date_gmt":"2023-05-01T11:00:20","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=64748"},"modified":"2023-04-27T15:20:16","modified_gmt":"2023-04-27T18:20:16","slug":"a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/","title":{"rendered":"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<span style=\"font-weight: 400;\">Perto da virada do s\u00e9culo, h\u00e1 uns 20 anos atr\u00e1s, quando a internet ainda n\u00e3o era t\u00e3o difundida, cidad\u00e3os bem informados poderiam ter 20 poss\u00edveis fontes de not\u00edcias. Eles assistiam a um notici\u00e1rio local e a um nacional, escolhiam um ou dois jornais para serem entregues todas as manh\u00e3s em suas casas, esperavam cada semana ou m\u00eas por uma revista de assinatura, encaminhavam alguns e-mails com amea\u00e7as bizarras e ouviam a uma ou duas esta\u00e7\u00f5es de r\u00e1dio de entrevistas nos trajetos di\u00e1rios.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Contudo, nos \u00faltimos 20 anos o n\u00famero de fontes expandiu para 200 \u2026 2.000 \u2026 200.000 \u2026 2 milh\u00f5es \u2026 200 milh\u00f5es \u2026 2 bilh\u00f5es e assim por diante para qualquer pessoa ao redor do mundo que possa criar um perfil no facebook, contas privadas no Twitter, uma conta p\u00fablica no Instagram e outra escondida dos pais, e muito mais.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa revolu\u00e7\u00e3o gera implica\u00e7\u00f5es em cada canto de nossas vidas, mas talvez a maior consequ\u00eancia seja vista na forma\u00e7\u00e3o crist\u00e3 e no discipulado.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Da imprensa para o algoritmo<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Quando os pastores subiam no p\u00falpito 20 anos atr\u00e1s, eles tinham uma vantagem intelectual sobre a maior parte dos membros da igreja. Eles sabiam mais sobre a B\u00edblia, sobre outros crist\u00e3os ao redor do mundo, mais sobre hist\u00f3ria e teologia. Isso n\u00e3o significava que as congrega\u00e7\u00f5es sempre concordavam com eles. Eles podiam ler a B\u00edblia por si mesmos. Poderiam comprar livros sobre a hist\u00f3ria da igreja em uma livraria ou na <\/span><i><span style=\"font-weight: 400;\">Amazon<\/span><\/i><span style=\"font-weight: 400;\">. Eles poderiam assinar a revista <\/span><i><span style=\"font-weight: 400;\">Christianity Today<\/span><\/i><span style=\"font-weight: 400;\">. Contudo, esse estudo requer tempo, dinheiro e esfor\u00e7o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na \u00e9poca, o mundo era controlado por editores e produtores. Como os pastores, esses guardi\u00f5es se beneficiavam de um acordo geral. Programas de TV e revistas podiam vender mais propagandas dessa forma. Os pastores podiam se concentrar em estudar e pastorear suas ovelhas apenas assistindo aos notici\u00e1rios da TV aberta e <\/span><i><span style=\"font-weight: 400;\">talk shows<\/span><\/i><span style=\"font-weight: 400;\"> mais populares entre sua congrega\u00e7\u00e3o<\/span><i><span style=\"font-weight: 400;\">.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Em grande parte, o mundo comandado pela imprensa desapareceu. O editor ordin\u00e1rio foi substitu\u00eddo pelo algoritmo opaco. O algoritmo sabe mais sobre n\u00f3s do que qualquer pastor ou editor jamais poderia saber. Ele nos d\u00e1 o que talvez nem admitamos que queremos. Os l\u00edderes da Igreja s\u00f3 podem nos dar o que eles acham que precisamos.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Crist\u00e3os formados pela internet<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Comparando com 20 anos atr\u00e1s, hoje a internet &#8211; n\u00e3o a igreja local &#8211; se tornou o principal local onde crist\u00e3os s\u00e3o formados. Antes que seus l\u00edderes falem, os membros da igreja j\u00e1 sabem no que acreditam. E, eles esperam que seus l\u00edderes se conformem &#8211; porque sen\u00e3o\u2026 N\u00e3o \u00e9 de se admirar que tantos l\u00edderes de igrejas sintam que perderam sua fun\u00e7\u00e3o nos \u00faltimos dois anos.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">Hoje a internet &#8211; n\u00e3o a igreja local &#8211; se tornou o principal local onde crist\u00e3os s\u00e3o formados.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Cada pastor, claro, \u00e9 levado a acreditar que sua situa\u00e7\u00e3o \u00e9 \u00fanica. L\u00edderes se afastam de seus cargos por acusa\u00e7\u00f5es de erros teol\u00f3gicos. Membros jovens saem por frustra\u00e7\u00e3o, porque seus pastores n\u00e3o mudaram seu serm\u00e3o para falar sobre o \u00faltimo v\u00eddeo que viralizou na internet. Di\u00e1conos rompem amizades de d\u00e9cadas depois que descobrem um novo canal favorito no YouTube.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como consequ\u00eancia, os pastores refletem sobre o que fizeram de errado. Eles ofenderam algu\u00e9m involuntariamente? Deveriam ter desenvolvido uma nova pol\u00edtica para quando rever a ora\u00e7\u00e3o pastoral? A pessoa que eles mais gostam de citar fez realmente todas as coisas terr\u00edveis que algum <\/span><i><span style=\"font-weight: 400;\">podcast<\/span><\/i><span style=\"font-weight: 400;\"> sugeriu?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Enquanto isso acontece com um pastor, \u00e9 bom analisarmos nossa pr\u00f3pria situa\u00e7\u00e3o. Quando est\u00e1 acontecendo com toda uma denomina\u00e7\u00e3o, \u00e9 melhor olharmos para a cultura de treinamento de l\u00edderes. Mas, quando est\u00e1 acontecendo em todas as igrejas, \u00e9 uma revolu\u00e7\u00e3o.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">A Reforma (tecnol\u00f3gica)<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A revolu\u00e7\u00e3o n\u00e3o \u00e9 necessariamente algo ruim.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Martinho Lutero viveu durante uma revolu\u00e7\u00e3o. Mais de um s\u00e9culo antes de Lutero involuntariamente iniciar a Reforma Protestante, Jan Hus levantou muitas das mesmas quest\u00f5es em rela\u00e7\u00e3o \u00e0s ofensas \u00e9tnicas produzidas pela Igreja Cat\u00f3lica medieval. Hus tamb\u00e9m tinha o suporte de poderosos l\u00edderes pol\u00edticos da regi\u00e3o em que ele nascera na Europa. Entretanto, ele foi executado como um m\u00e1rtir em 1415 no Conc\u00edlio de Constan\u00e7a. Lutero morreu de forma natural em 1546 depois de causar um cisma em Roma. Sob a provis\u00e3o de Deus, em que se deu a diferen\u00e7a entre os dois?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lutero se utilizou da revolu\u00e7\u00e3o da imprensa no in\u00edcio do s\u00e9culo dezesseis. E, segundo o bi\u00f3grafo Andrew Pettegree em <\/span><i><span style=\"font-weight: 400;\">Brand Luther<\/span><\/i><span style=\"font-weight: 400;\">, ele efetivamente inventou o tratado teol\u00f3gico popular. Ele n\u00e3o colocou sua esperan\u00e7a sobre a hierarquia da igreja. Ele n\u00e3o escreveu somente em latim acad\u00eamico. Ele\u00a0 tirou seu caso diretamente da B\u00edblia, e entregou diretamente para o povo. Essa revolu\u00e7\u00e3o de gra\u00e7a prevaleceu em grande parte da Europa e agora continua a se espalhar em todos os continentes habitados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hoje, estamos vivendo o in\u00edcio de uma revolu\u00e7\u00e3o da mesma escala, mas com um desfecho incerto.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Temor para o mal ou para o bem?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Lutero e Hus continuam sendo her\u00f3is para <\/span><i><span style=\"font-weight: 400;\">youtubers <\/span><\/i><span style=\"font-weight: 400;\">e criadores de podcasts que denunciam l\u00edderes corruptos de nossos dias. Se alguma figura da hist\u00f3ria da igreja tivesse se destacado na onda inconstante do Twitter, seria Lutero. Hus s\u00f3 gostaria que o TikTok tivesse estado dispon\u00edvel no caminho para Constance. Se voc\u00ea j\u00e1 foi ferido ou desprezado por l\u00edderes denominacionais corruptos, a Internet \u00e9 o seu lugar seguro. Voc\u00ea n\u00e3o precisa de um editor de revista ou produtor de TV para investigar sua hist\u00f3ria. Eles ficar\u00e3o em casa e far\u00e3o reportagens em seus Espa\u00e7os do Twitter. Voc\u00ea tem o poder.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa revolu\u00e7\u00e3o \u00e9 uma espada de dois gumes. \u00c9 um terror \u00e0 m\u00e1 conduta. Mas, por vezes, tamb\u00e9m corta o que \u00e9 bom. Como podemos, ent\u00e3o, aproveitar essa revolu\u00e7\u00e3o para a gl\u00f3ria de Deus?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lutero n\u00e3o explorou a cultura crescente da celebridade e da imprensa por causa da revolu\u00e7\u00e3o. Sua revolu\u00e7\u00e3o reconduziu\u00a0 os crist\u00e3os \u00e0 autoridade m\u00e1xima da Palavra de Deus, que \u00e9 &#8220;viva, e eficaz, e mais cortante do que qualquer espada de dois gumes, e penetra at\u00e9 ao ponto de dividir alma e esp\u00edrito, juntas e medulas, e \u00e9 apta para discernir os pensamentos e prop\u00f3sitos do cora\u00e7\u00e3o&#8221; (Hebreus 4.12; ARA). Esta palavra de Deus condena todos os que negam o dom gratuito do Evangelho (G\u00e1latas 5.12). Esta palavra de Deus extermina a ra\u00e7a de v\u00edboras que falam sobre o bem, mas praticam o mal (Mateus 12.34).<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u00a0 \u00a0 \u00a0 \u00a0Qualquer revolu\u00e7\u00e3o tecnol\u00f3gica que retorne com a Palavra de Deus para o centro da vida e pr\u00e1tica crist\u00e3s ser\u00e1 aben\u00e7oada por Deus.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Qualquer revolu\u00e7\u00e3o tecnol\u00f3gica que retorne com a Palavra de Deus para o centro da vida e pr\u00e1tica crist\u00e3s ser\u00e1 aben\u00e7oada por Deus. Todo l\u00edder verdadeiro \u00e9 agradecido pela autoridade da Palavra de Deus.\u00a0 Damos gra\u00e7as pelos v\u00eddeos do <\/span><i><span style=\"font-weight: 400;\">BibleProject<\/span><\/i><span style=\"font-weight: 400;\">, serm\u00f5es do John Piper e pelos pequenos grupos feitos pelo <\/span><i><span style=\"font-weight: 400;\">Zoom<\/span><\/i><span style=\"font-weight: 400;\"> durante a pandemia. Por causa da ordem de Paulo para que o nosso discurso seja &#8220;sempre gracioso, temperado com sal&#8221; (Colossenses 4:6), somos gratos &#8211; e pedimos a Deus por dedos mais lentos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Onde quer que a Palavra governe, ningu\u00e9m que pertence a Deus deve temer.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Trope\u00e7ando em dire\u00e7\u00e3o \u00e0 sobriedade<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Este \u00e9 o dia que o Senhor fez. Em \u00faltima an\u00e1lise, a Internet n\u00e3o se mant\u00e9m por causa de torres de sat\u00e9lite na Calif\u00f3rnia, mas pelo poder da palavra de Deus. E, no entanto, os l\u00edderes da igreja\u00a0 de hoje em dia n\u00e3o podem ignorar a internet, assim como o papa n\u00e3o p\u00f4de ignorar Lutero como um javali alem\u00e3o selvagem.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, qual \u00e9 a solu\u00e7\u00e3o para a crise da lideran\u00e7a da igreja no alvorecer da revolu\u00e7\u00e3o da Internet?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Transferir todo o nosso minist\u00e9rio para a Internet pioraria o problema. Na verdade, os l\u00edderes de igrejas fariam bem ao ter cuidado e at\u00e9 considerar a possibilidade de se afastar das redes sociais. Voc\u00ea n\u00e3o passa mais uma cerveja para o glut\u00e3o e espera que ele v\u00e1 cambaleando em dire\u00e7\u00e3o \u00e0 sobriedade. \u00c0s vezes, a melhor defesa contra as intermin\u00e1veis pseudo-pol\u00eamicas da Internet \u00e9 a ignor\u00e2ncia. Talvez n\u00e3o seja poss\u00edvel ignorar a Internet, mas voc\u00ea provavelmente deveria ignorar a maior parte das brigas do Twitter.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como a Internet expandiu nossos horizontes para o mundo todo, a maioria dos l\u00edderes de igrejas deveria se sentir liberada para se concentrar em seu minist\u00e9rio local. Minist\u00e9rios como Desiring God e Coaliz\u00e3o pelo Evangelho cresceram nos \u00faltimos 20 anos para ajudar a preencher o vazio do discipulado digital e combater as mensagens anti evang\u00e9licas a partir da verdade b\u00edblica. Mas o melhor que nossa equipe pode fazer \u00e9 ajudar a apoiar os l\u00edderes da igreja local &#8211; aqueles que conhecem o seu verdadeiro eu, n\u00e3o a selfie do Instagram. N\u00e3o podemos e n\u00e3o vamos ministrar a Ceia do Senhor para que voc\u00ea possa relembrar a bondade de Deus por meio do perd\u00e3o dos pecados. Quando voc\u00ea se desvia da Palavra, n\u00e3o podemos bater \u00e0 sua porta e oferecer incentivo e ora\u00e7\u00e3o. N\u00e3o podemos pregar a Palavra com poder depois de nos sentarmos ao lado de sua cama quando voc\u00ea estiver sofrendo.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">A melhor defesa para nossas almas<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A internet exp\u00f5e os falsos mestres na mesma medida que permite que eles espalhem suas heresias destrutivas (2 Pedro 2.1). Em toda revolu\u00e7\u00e3o, pessoas boas sofrem por causa de lobos vestidos de cordeiros (2 Cor\u00edntios 11.4). A melhor defesa ou discernimento na era digital \u00e9 um l\u00edder de uma igreja local que se submeta \u00e0 Palavra de Deus, <\/span>que saiba quem voc\u00ea \u00e9, conhe\u00e7a suas fraquezas e que ame a todos do mesmo modo.<\/p>\n<p><span style=\"font-weight: 400;\">Quando nos voltamos para a igreja local, a revolu\u00e7\u00e3o da Internet refor\u00e7ar\u00e1 &#8211; n\u00e3o ofuscar\u00e1 &#8211; o minist\u00e9rio da palavra. Uma outra Reforma, em que o povo de Deus l\u00ea e d\u00e1 ouvidos a sua Palavra, pode desdobrar-se em tempo real. E o nome de Deus ser\u00e1 louvado na nossa unidade espiritual, em vez de ser insultado em toda a divis\u00e3o feita pelo homem.<\/span>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Collin Hansen. \u00a9 Desiring God Foundation. Website: <a class=\"external\" href=\"http:\/\/desiringgod.org\/\" target=\"_blank\" rel=\"noopener\">desiringGod.org<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/www.desiringgod.org\/articles\/discipled-by-everyone-and-no-one\"><span style=\"font-weight: 400;\">Discipled By Everyone And No One Is The Internet Good For The Church?<\/span><\/a>\u00a0\u00a9 Voltemos ao Evangelho. Website:\u00a0<a href=\"http:\/\/voltemosaoevangelho.com\/\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados. Tradu\u00e7\u00e3o: Luise Massa Santos. Revis\u00e3o e Edi\u00e7\u00e3o: Vinicius Lima.[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00c9 fato que a internet se tornou um ambiente onde muitos crist\u00e3os s\u00e3o formados. Veja neste artigo de Collin Hansen considera\u00e7\u00f5es sobre isso.<\/p>\n","protected":false},"author":642,"featured_media":64751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3063,467,726,409],"tags":[592],"class_list":["post-64748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosmovisao-e-cultura","category-ministerio-pastoral","category-relacionamentos","category-vida-crista","tag-desiring-god","tema-internet","tema-perigos-da-internet","tema-redes-sociais","tema-unidade-da-igreja","tema-vida-da-igreja","categoria-artigo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?<\/title>\n<meta name=\"description\" content=\"\u00c9 fato que a internet se tornou um ambiente onde muitos crist\u00e3os s\u00e3o formados. Veja neste artigo de Collin Hansen considera\u00e7\u00f5es sobre isso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?\" \/>\n<meta property=\"og:description\" content=\"\u00c9 fato que a internet se tornou um ambiente onde muitos crist\u00e3os s\u00e3o formados. Veja neste artigo de Collin Hansen considera\u00e7\u00f5es sobre isso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-01T11:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/internet-1.png?fit=837%2C470&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Collin Hansen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Collin Hansen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/\"},\"author\":{\"name\":\"Collin Hansen\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/70c4b8af48e642f4205d7ab2e1f12bff\"},\"headline\":\"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?\",\"datePublished\":\"2023-05-01T11:00:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/\"},\"wordCount\":1879,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/internet-1.png?fit=837%2C470&ssl=1\",\"keywords\":[\"Desiring God Portugu\u00eas\"],\"articleSection\":[\"Cosmovis\u00e3o e cultura\",\"Minist\u00e9rio Pastoral\",\"Relacionamentos\",\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/\",\"name\":\"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/internet-1.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2023-05-01T11:00:20+00:00\",\"description\":\"\u00c9 fato que a internet se tornou um ambiente onde muitos crist\u00e3os s\u00e3o formados. Veja neste artigo de Collin Hansen considera\u00e7\u00f5es sobre isso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/internet-1.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/internet-1.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470,\"caption\":\"internet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/70c4b8af48e642f4205d7ab2e1f12bff\",\"name\":\"Collin Hansen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Collin-Hansen_avatar_1537830018-96x96.jpg\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Collin-Hansen_avatar_1537830018-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Collin-Hansen_avatar_1537830018-96x96.jpg\",\"caption\":\"Collin Hansen\"},\"description\":\"Editor associado da revista Christianity Today, Collin Hansen atua como diretor editorial do The Gospel Coalition e \u00e9 autor de \u201cYoung, Restless, Reformed: A Journalist\u2019s Journey with the New Calvinists\u201d \u00e9 co-autor com John Woodbridge de \u201cA God-Sized Vision: Revival Stories That Stretch and Stir\u201d.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/collin-hansen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?","description":"\u00c9 fato que a internet se tornou um ambiente onde muitos crist\u00e3os s\u00e3o formados. Veja neste artigo de Collin Hansen considera\u00e7\u00f5es sobre isso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/","og_locale":"pt_BR","og_type":"article","og_title":"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?","og_description":"\u00c9 fato que a internet se tornou um ambiente onde muitos crist\u00e3os s\u00e3o formados. Veja neste artigo de Collin Hansen considera\u00e7\u00f5es sobre isso.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2023-05-01T11:00:20+00:00","og_image":[{"width":837,"height":470,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/internet-1.png?fit=837%2C470&ssl=1","type":"image\/png"}],"author":"Collin Hansen","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Collin Hansen","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/"},"author":{"name":"Collin Hansen","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/70c4b8af48e642f4205d7ab2e1f12bff"},"headline":"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?","datePublished":"2023-05-01T11:00:20+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/"},"wordCount":1879,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/internet-1.png?fit=837%2C470&ssl=1","keywords":["Desiring God Portugu\u00eas"],"articleSection":["Cosmovis\u00e3o e cultura","Minist\u00e9rio Pastoral","Relacionamentos","Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/","name":"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/internet-1.png?fit=837%2C470&ssl=1","datePublished":"2023-05-01T11:00:20+00:00","description":"\u00c9 fato que a internet se tornou um ambiente onde muitos crist\u00e3os s\u00e3o formados. Veja neste artigo de Collin Hansen considera\u00e7\u00f5es sobre isso.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/internet-1.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/internet-1.png?fit=837%2C470&ssl=1","width":837,"height":470,"caption":"internet"},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/a-internet-esta-revolucionando-a-vida-crista-e-a-vida-da-igreja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"A internet est\u00e1 revolucionando a vida crist\u00e3 e a vida da igreja?"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/70c4b8af48e642f4205d7ab2e1f12bff","name":"Collin Hansen","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/09\/Collin-Hansen_avatar_1537830018-96x96.jpg","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/09\/Collin-Hansen_avatar_1537830018-96x96.jpg","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2018\/09\/Collin-Hansen_avatar_1537830018-96x96.jpg","caption":"Collin Hansen"},"description":"Editor associado da revista Christianity Today, Collin Hansen atua como diretor editorial do The Gospel Coalition e \u00e9 autor de \u201cYoung, Restless, Reformed: A Journalist\u2019s Journey with the New Calvinists\u201d \u00e9 co-autor com John Woodbridge de \u201cA God-Sized Vision: Revival Stories That Stretch and Stir\u201d.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/collin-hansen\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-gQk","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/internet-1.png?fit=837%2C470&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/64748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/642"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=64748"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/64748\/revisions"}],"predecessor-version":[{"id":64754,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/64748\/revisions\/64754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/64751"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=64748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=64748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=64748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}