{"id":64862,"date":"2023-05-18T08:00:03","date_gmt":"2023-05-18T11:00:03","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=64862"},"modified":"2023-05-31T10:33:51","modified_gmt":"2023-05-31T13:33:51","slug":"o-que-voce-faz-quando-as-circunstancias-te-contrariam","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/","title":{"rendered":"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_btn title=&#8221;Artigo 1 da s\u00e9rie Rute e o amor benevolente de Deus | clique aqui para ver os demais artigos desta s\u00e9rie&#8221; align=&#8221;center&#8221; link=&#8221;url:https%3A%2F%2Fvoltemosaoevangelho.com%2Fblog%2Fserie%2Frute-e-o-amor-benevolente-de-deus%2F&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<span style=\"font-weight: 400;\">O livro de Rute, embora curto, demonstra a provid\u00eancia abundante de Deus em meio a circunst\u00e2ncias adversas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assim como, em um quadro, as pinceladas de luz s\u00e3o mais vis\u00edveis quando colocadas sobre um fundo escuro; para n\u00f3s, o agir de Deus pode se tornar mais evidente em meio a circunst\u00e2ncias e dias que parecem sombrios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, antes de nos maravilharmos com a gra\u00e7a e fidelidade do Senhor narradas nesse livro, precisamos entender qual era o pano de fundo de Israel, tanto nas quest\u00f5es pol\u00edticas, quanto em rela\u00e7\u00e3o ao cora\u00e7\u00e3o do povo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O livro de Rute \u00e9 posicionado no c\u00e2non b\u00edblico de uma forma que representa o momento em que a narrativa acontece: entre os dias dos ju\u00edzes e o primeiro reinado de Israel. Eram dias escuros para o povo de Deus, cada um fazia o que era certo aos seus pr\u00f3prios olhos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ironicamente, Bel\u00e9m, cidade cujo nome significa \u201ccasa do p\u00e3o\u201d ou \u201ccasa de alimento\u201d, estava sofrendo com a fome. Consequ\u00eancia do pr\u00f3prio pecado dos habitantes da Terra Prometida (Lv 26.18-20, Dt 28.15).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Naquele tempo, mudar-se de cidade n\u00e3o se tratava apenas de uma quest\u00e3o geogr\u00e1fica. O povo escolhido de Deus estava, finalmente, na terra da promessa. Aquele lugar simbolizava a alian\u00e7a do Senhor com o povo, onde os sacrif\u00edcios eram oferecidos e as festas, celebradas. A identidade do povo como parte da alian\u00e7a estava ligada ao lugar em que estavam habitando. O culto ao Senhor estava intimamente relacionado com a terra prometida, sair de l\u00e1 n\u00e3o era uma simples mudan\u00e7a de endere\u00e7o, mas uma demonstra\u00e7\u00e3o de neglig\u00eancia com rela\u00e7\u00e3o \u00e0 adora\u00e7\u00e3o a Deus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os moabitas eram conhecidos por sua idolatria e, desde o seu princ\u00edpio em G\u00eanesis, s\u00e3o sin\u00f4nimos de rebeldia e desobedi\u00eancia. Em Moabe, n\u00e3o havia adora\u00e7\u00e3o ao Deus de Israel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com isso em mente, podemos iniciar a leitura do livro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os cinco primeiros vers\u00edculos narram parte da hist\u00f3ria de uma fam\u00edlia:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nos dias em que os ju\u00edzes julgavam, n\u00e3o havia p\u00e3o na casa do p\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Elimeleque, ent\u00e3o, decide sair da terra prometida com sua fam\u00edlia em busca de uma aparente seguran\u00e7a, fugindo da fome. Eles saem da tribo de Jud\u00e1 e ficam em Moabe por uma d\u00e9cada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Malom e Quiliom, seus filhos, casam-se com mulheres moabitas: Orfa e Rute.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em algum momento nesses 10 anos, em per\u00edodos distintos, morre o pai e os dois filhos, deixando Noemi, Orfa e Rute vi\u00favas.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Situa\u00e7\u00f5es dif\u00edceis tendem a nos mostrar o que est\u00e1 em nosso cora\u00e7\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Existe uma famosa frase que diz: \u201c\u00c9 mais f\u00e1cil ir para Moabe do que perguntar para Deus por que h\u00e1 fome em Israel\u201d. A escassez em Bel\u00e9m mostrou o que estava no cora\u00e7\u00e3o desse chefe de fam\u00edlia. Mesmo sabendo que aquele per\u00edodo dif\u00edcil era disciplina de Deus para fazer o povo olhar para o alto, preferiu fugir a se arrepender e clamar por miseric\u00f3rdia.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Tentamos resolver as coisas dif\u00edceis da vida pelas nossas pr\u00f3prias for\u00e7as<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Parece muito l\u00f3gico sair de um lugar onde h\u00e1 fome para ir a um lugar com abund\u00e2ncia, por\u00e9m, como vimos na introdu\u00e7\u00e3o, essa n\u00e3o era uma mudan\u00e7a qualquer. Elimeleque preferiu o conforto material longe do Senhor ao sofrimento perto dele.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Nosso pecado impacta as pessoas \u00e0 nossa volta<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Elimeleque havia decidido levar sua mulher e seus dois filhos para uma terra imoral e longe de Deus, ignorando o fato de que estava expondo a si mesmo e sua fam\u00edlia a um contexto perverso. Ele n\u00e3o se preocupou com a possibilidade de que seus filhos jovens se casariam com mulheres de fora da alian\u00e7a do Senhor (Dt 7.1-4).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o sabemos se houve relut\u00e2ncia da parte da fam\u00edlia ou n\u00e3o, mas a decis\u00e3o de Elimeleque mudou o rumo e os padr\u00f5es morais das pessoas de sua casa. Em busca de seguran\u00e7a, encontrou a morte. Em busca de conforto, trouxe dor \u00e0s pessoas que deixou.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Dias escuros exigem f\u00e9<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Focar nas circunst\u00e2ncias nos levar\u00e1 a tomar m\u00e1s decis\u00f5es, focar no Senhor nos conduzir\u00e1 \u00e0 fidelidade. Se essa fome era para mostrar algo para o povo, a resposta deveria ser cair de joelhos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Elimeleque se guia pelo que est\u00e1 vendo, pelas circunst\u00e2ncias. No caminho, \u00e9 bem prov\u00e1vel que essa fam\u00edlia tenha visto uma prova f\u00edsica do agir de Deus em favor do povo, num momento em que o cen\u00e1rio parecia improv\u00e1vel. A rota mais r\u00e1pida de Bel\u00e9m at\u00e9 Moabe passava pela antiga Jeric\u00f3, ainda em ru\u00ednas, cidade cujos muros foram derrubados pelo Senhor. Passar por essa cidade j\u00e1 seria mais do que o necess\u00e1rio para lembr\u00e1-los dos feitos de Deus, mas eles continuam o caminho.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nas dificuldades da vida, devemos ser fi\u00e9is ao que Deus nos manda fazer, mesmo que nossas a\u00e7\u00f5es possam parecer in\u00fateis, pois nossa for\u00e7a n\u00e3o mudar\u00e1 a situa\u00e7\u00e3o. Nosso papel n\u00e3o \u00e9 o de consertar algo, ou \u201cfazer acontecer\u201d, mas o de sermos fi\u00e9is.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Como voc\u00ea acha que o povo se sentia ao dar voltas ao redor de Jeric\u00f3?\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Era fisicamente imposs\u00edvel que aquelas muralhas ca\u00edssem simplesmente pelo barulho das trombetas ou pelo caminhar das pessoas. N\u00e3o foi a a\u00e7\u00e3o em si, mas a obedi\u00eancia e f\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Elimeleque respondeu com orgulho e autonomia. O que voc\u00ea faz quando coisas desagrad\u00e1veis acontecem? Lembre-se: Situa\u00e7\u00f5es dif\u00edceis revelam nosso cora\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por que n\u00f3s, como povo de Deus, insistimos em fazer as coisas com nossas pr\u00f3prias m\u00e3os? Por que achamos que cabe a n\u00f3s resolver algo do qual Deus \u201cn\u00e3o cuidou\u201d? Nem mesmo Jesus tomou a situa\u00e7\u00e3o nas suas pr\u00f3prias m\u00e3os quando foi tentado.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">No que voc\u00ea tem fixado os seus olhos?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Como voc\u00ea tem sido chamado a demonstrar obedi\u00eancia e f\u00e9? O que pode te ajudar a lembrar que fidelidade \u00e9 mais importante do que tentar resolver \u00e0 sua maneira?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Que o Senhor desvie nossos olhos das circunst\u00e2ncias e nos renove por meio de Sua Palavra.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">\u201cn\u00e3o atentando n\u00f3s nas coisas que se veem, mas nas que se n\u00e3o veem; porque as que se veem s\u00e3o temporais e as que se n\u00e3o veem s\u00e3o eternas.\u201d<\/span><\/i><\/p>\n<p style=\"text-align: center;\"><i><span style=\"font-weight: 400;\">2 Cor\u00edntios 4.18<\/span><\/i><\/p>\n<p>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Lara Sayuri. \u00a9 Voltemos Ao Evangelho. Website: <a href=\"https:\/\/voltemosaoevangelho.com\/\">voltemosaoevangelho.com<\/a>. Todos os direitos reservados.\u00a0<em>Revis\u00e3o e Edi\u00e7\u00e3o Vinicius Lima e Renata Gandolfo<\/em><em>.<\/em>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Situa\u00e7\u00f5es dif\u00edceis tendem a nos mostrar o que est\u00e1 em nosso cora\u00e7\u00e3o. Focar nas circunst\u00e2ncias nos levar\u00e1 a tomar m\u00e1s decis\u00f5es, focar no Senhor nos conduzir\u00e1 \u00e0 fidelidade.<\/p>\n","protected":false},"author":981,"featured_media":64865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[624,409],"tags":[156,3271],"class_list":["post-64862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mulheres","category-vida-crista","tag-mulheres","tag-rute-e-o-amor-benevolente-de-deus","tema-mulheres","tema-vida-crista","categoria-artigo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?<\/title>\n<meta name=\"description\" content=\"Circunst\u00e2ncias tendem a mostrar o que est\u00e1 no cora\u00e7\u00e3o. Focar nelas nos levar\u00e1 para m\u00e1s decis\u00f5es, focar no Senhor nos conduzir\u00e1 \u00e0 fidelidade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?\" \/>\n<meta property=\"og:description\" content=\"Circunst\u00e2ncias tendem a mostrar o que est\u00e1 no cora\u00e7\u00e3o. Focar nelas nos levar\u00e1 para m\u00e1s decis\u00f5es, focar no Senhor nos conduzir\u00e1 \u00e0 fidelidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-18T11:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T13:33:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/circunstancias-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lara Sayuri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lara Sayuri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/\"},\"author\":{\"name\":\"Lara Sayuri\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/7003869ccb0f896cdcc96f532b4ee8f0\"},\"headline\":\"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?\",\"datePublished\":\"2023-05-18T11:00:03+00:00\",\"dateModified\":\"2023-05-31T13:33:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/\"},\"wordCount\":1227,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/circunstancias-1.png?fit=837%2C470&ssl=1\",\"keywords\":[\"Mulheres\",\"Rute e o amor benevolente de Deus\"],\"articleSection\":[\"Mulheres\",\"Vida Crist\u00e3\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/\",\"name\":\"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/circunstancias-1.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2023-05-18T11:00:03+00:00\",\"dateModified\":\"2023-05-31T13:33:51+00:00\",\"description\":\"Circunst\u00e2ncias tendem a mostrar o que est\u00e1 no cora\u00e7\u00e3o. Focar nelas nos levar\u00e1 para m\u00e1s decis\u00f5es, focar no Senhor nos conduzir\u00e1 \u00e0 fidelidade\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/circunstancias-1.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/circunstancias-1.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470,\"caption\":\"arrependimento\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2023\\\/05\\\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/7003869ccb0f896cdcc96f532b4ee8f0\",\"name\":\"Lara Sayuri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-WhatsApp-Image-2023-01-05-at-14.27.13-96x96.jpeg\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-WhatsApp-Image-2023-01-05-at-14.27.13-96x96.jpeg\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-WhatsApp-Image-2023-01-05-at-14.27.13-96x96.jpeg\",\"caption\":\"Lara Sayuri\"},\"description\":\"Lara estudou no Semin\u00e1rio B\u00edblico Palavra da Vida e atualmente serve na Igreja Batista Maranata em S\u00e3o Jos\u00e9 dos Campos como l\u00edder de jovens mo\u00e7as.\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/larasayuri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?","description":"Circunst\u00e2ncias tendem a mostrar o que est\u00e1 no cora\u00e7\u00e3o. Focar nelas nos levar\u00e1 para m\u00e1s decis\u00f5es, focar no Senhor nos conduzir\u00e1 \u00e0 fidelidade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/","og_locale":"pt_BR","og_type":"article","og_title":"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?","og_description":"Circunst\u00e2ncias tendem a mostrar o que est\u00e1 no cora\u00e7\u00e3o. Focar nelas nos levar\u00e1 para m\u00e1s decis\u00f5es, focar no Senhor nos conduzir\u00e1 \u00e0 fidelidade","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2023-05-18T11:00:03+00:00","article_modified_time":"2023-05-31T13:33:51+00:00","og_image":[{"width":837,"height":470,"url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/circunstancias-1.png","type":"image\/png"}],"author":"Lara Sayuri","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Lara Sayuri","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/"},"author":{"name":"Lara Sayuri","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/7003869ccb0f896cdcc96f532b4ee8f0"},"headline":"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?","datePublished":"2023-05-18T11:00:03+00:00","dateModified":"2023-05-31T13:33:51+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/"},"wordCount":1227,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/circunstancias-1.png?fit=837%2C470&ssl=1","keywords":["Mulheres","Rute e o amor benevolente de Deus"],"articleSection":["Mulheres","Vida Crist\u00e3"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/","name":"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/circunstancias-1.png?fit=837%2C470&ssl=1","datePublished":"2023-05-18T11:00:03+00:00","dateModified":"2023-05-31T13:33:51+00:00","description":"Circunst\u00e2ncias tendem a mostrar o que est\u00e1 no cora\u00e7\u00e3o. Focar nelas nos levar\u00e1 para m\u00e1s decis\u00f5es, focar no Senhor nos conduzir\u00e1 \u00e0 fidelidade","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/circunstancias-1.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/circunstancias-1.png?fit=837%2C470&ssl=1","width":837,"height":470,"caption":"arrependimento"},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2023\/05\/o-que-voce-faz-quando-as-circunstancias-te-contrariam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"O que voc\u00ea faz quando as circunst\u00e2ncias te contrariam?"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/7003869ccb0f896cdcc96f532b4ee8f0","name":"Lara Sayuri","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/cropped-WhatsApp-Image-2023-01-05-at-14.27.13-96x96.jpeg","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/cropped-WhatsApp-Image-2023-01-05-at-14.27.13-96x96.jpeg","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/01\/cropped-WhatsApp-Image-2023-01-05-at-14.27.13-96x96.jpeg","caption":"Lara Sayuri"},"description":"Lara estudou no Semin\u00e1rio B\u00edblico Palavra da Vida e atualmente serve na Igreja Batista Maranata em S\u00e3o Jos\u00e9 dos Campos como l\u00edder de jovens mo\u00e7as.","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/larasayuri\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2023\/05\/circunstancias-1.png?fit=837%2C470&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-gSa","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/64862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/981"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=64862"}],"version-history":[{"count":5,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/64862\/revisions"}],"predecessor-version":[{"id":64998,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/64862\/revisions\/64998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/64865"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=64862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=64862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=64862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}