{"id":70899,"date":"2025-03-25T08:00:10","date_gmt":"2025-03-25T11:00:10","guid":{"rendered":"https:\/\/voltemosaoevangelho.com\/blog\/?p=70899"},"modified":"2025-03-14T15:14:58","modified_gmt":"2025-03-14T18:14:58","slug":"a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado","status":"publish","type":"post","link":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/","title":{"rendered":"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<p class=\"has-drop-cap\" style=\"text-align: justify;\">Todos os crist\u00e3os est\u00e3o bem cientes do incompar\u00e1vel significado hist\u00f3rico-redentor da encarna\u00e7\u00e3o, crucifica\u00e7\u00e3o, ressurrei\u00e7\u00e3o e ascens\u00e3o de Cristo. Estamos igualmente informados de Seu vitorioso derramamento do Esp\u00edrito Santo sobre a igreja no Pentecostes. Mas poucos crist\u00e3os percebem o significado do derramamento da santa ira de Cristo sobre Jerusal\u00e9m no ano 70 d. C.<\/p>\n<p style=\"text-align: justify;\">No entanto, os eventos do ano 70 s\u00e3o muito importantes na profecia do Novo Testamento, ao servir como uma dram\u00e1tica consequ\u00eancia da primeira vinda. Ao considerar apenas o Evangelho de Lucas, o holocausto do ano 70 nos \u00e9 apontado em v\u00e1rias profecias: Lucas 13:32-35; 19:41-44; 21:20-40; e 23:28-31. Al\u00e9m disso, esse evento n\u00e3o \u00e9 somente tema de muitas par\u00e1bolas (por exemplo, Mt 21:33-45; 22:1-14), tamb\u00e9m \u00e9 motivo do triste lamento de Cristo sobre Jerusal\u00e9m (Mt 23:38). Tal lamento introduz um dos mais longos discursos registrados de Cristo, um cujo in\u00edcio se concentra naquele ano lament\u00e1vel (Mt 24 \u2013 25).<\/p>\n<p style=\"text-align: justify;\">Consideremos o significado do ano 70 em quatro \u00e1reas.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Corrobora a autoridade de Cristo<\/strong><\/h3>\n<p style=\"text-align: justify;\">A cat\u00e1strofe de 70 d. C. resultou de uma palavra prof\u00e9tica de Cristo, o que corrobora Sua autoridade messi\u00e2nica de maneira dram\u00e1tica. O ano 70 prova que a profecia de Cristo n\u00e3o \u00e9 apenas verdadeira palavra divina (Dt 18:22), \u00e9 tamb\u00e9m uma palavra de \u201cjulgamento\u201d contra o povo de Deus.<\/p>\n<p style=\"text-align: justify;\">O pedido dos disc\u00edpulos por um \u201csinal\u201d que apontasse para o \u201cfim dos tempos\u201d (Mt 24:3) desencadeia o Serm\u00e3o das Oliveiras em Mateus 24 e 25. At\u00e9 o vers\u00edculo 34 do cap\u00edtulo 24, Jesus se concentra na destrui\u00e7\u00e3o de Jerusal\u00e9m: A devasta\u00e7\u00e3o da cidade santa e a conflagra\u00e7\u00e3o da casa santa tornam-se \u201cno c\u00e9u o sinal do Filho do Homem\u201d (24:30). Assim, quando o holocausto do primeiro s\u00e9culo ocorre em Israel, isso definitivamente significa a divina autoridade daquele que est\u00e1 agora no C\u00e9u (confira Mt 26:59-64; Lucas 23:20-31).<\/p>\n<p style=\"text-align: justify;\">Muitos crist\u00e3os n\u00e3o entendem o significado de \u201co Filho do Homem vindo sobre as nuvens do c\u00e9u\u201d, em Mateus 24:30, por duas raz\u00f5es. Primeiro, n\u00e3o est\u00e3o familiarizados com as passagens apocal\u00edpticas do Antigo Testamento nas quais os julgamentos divinos aparecem como nuvens que surgem (Is 19:1). Segundo, ignoram as pistas interpretativas em Mateus 24: a men\u00e7\u00e3o da destrui\u00e7\u00e3o do templo (v. 2), o foco na Judeia (v. 16) e a proximidade temporal de todos os eventos entre os versos 4 e 34 (v. 34). De fato, Jesus adverte \u201cos pr\u00f3prios homens\u201d que se sentam para julg\u00e1-lo: \u201c[\u2026] desde agora, vereis o Filho do Homem assentado \u00e0 direita do Todo-Poderoso e vindo sobre as nuvens do c\u00e9u\u201d (Mt 26:64b).<\/p>\n<p style=\"text-align: justify;\">Com certeza, \u00e9 assim que a igreja antiga lia Mateus 24. Referindo-se ao ano 70, Eus\u00e9bio destaca \u201ca infal\u00edvel previs\u00e3o do nosso Salvador pela qual Ele exp\u00f4s profeticamente essas mesmas coisas\u201d (<em>Hist\u00f3ria Eclesi\u00e1stica<\/em>, 3.7.1).<\/p>\n<h3 style=\"text-align: justify;\"><strong>Conclui a antiga economia<\/strong><\/h3>\n<p style=\"text-align: justify;\">O Antigo Testamento est\u00e1 repleto de sinais e s\u00edmbolos que prenunciam a obra de Cristo. No entanto, a pr\u00f3pria natureza dessa era tipol\u00f3gica exige que represente um passo tempor\u00e1rio em dire\u00e7\u00e3o \u00e0 plena conclus\u00e3o hist\u00f3rica e redentiva trazida por Cristo, um est\u00e1gio passageiro movendo-se em dire\u00e7\u00e3o ao grande cl\u00edmax. De fato, a vitalidade da nova alian\u00e7a n\u00e3o poderia ser contida dentro das restri\u00e7\u00f5es da antiga alian\u00e7a referente a uma etnia, a um espa\u00e7o geogr\u00e1fico e a um templo tipol\u00f3gico, pois n\u00e3o se pode colocar \u201cvinhos novos em odres velhos; do contr\u00e1rio, rompem-se os odres, derrama-se o vinho, e os odres se perdem\u201d (Mt 9:17a).<\/p>\n<p style=\"text-align: justify;\">O Novo Testamento com frequ\u00eancia indica essa iminente mudan\u00e7a de administra\u00e7\u00e3o pactual. Por exemplo, Hebreus 8:13 declara: \u201cQuando ele diz Nova, torna antiquada a primeira. Ora, aquilo que se torna antiquado e envelhecido est\u00e1 prestes a desaparecer.\u201d De fato, Hebreus adverte os judeus convertidos a n\u00e3o voltarem ao juda\u00edsmo, especialmente quando veem \u201cque o Dia [ano 70] se aproxima\u201d (Hb 10:25). Tal apostasia os faria retornar a uma c\u00f3pia material, prestes a desaparecer, da verdade, pois Cristo trouxe o povo de Deus ao \u201cmaior e mais perfeito tabern\u00e1culo, n\u00e3o feito por m\u00e3os\u201d (Hb 9:11; confira 9:24). Ao colocar de lado as estruturas da antiga alian\u00e7a, o ano 70 assegura o esquema final da nova alian\u00e7a.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Confirma o minist\u00e9rio aos gentios<\/strong><\/h3>\n<p style=\"text-align: justify;\">A igreja primitiva foi tentada a se contentar com a miss\u00e3o judaica (presencie a experi\u00eancia de Pedro em Atos 10 \u2013 11). Com o crescente minist\u00e9rio de Paulo, isso come\u00e7a a mudar. Essa not\u00e1vel mudan\u00e7a de foco de uma miss\u00e3o judaica palestina para uma miss\u00e3o gentia mundial \u00e9 definitivamente selada no ano 70.<\/p>\n<p style=\"text-align: justify;\">Se retornamos a Mateus 24, aprendemos que ap\u00f3s a derrubada do templo, Cristo enviar\u00e1 Seus \u201canjos\u201d (no grego\u00a0<em>angeloi<\/em>, aqui s\u00e3o mensageiros humanos) \u201ccom grande clangor de trombeta, os quais reunir\u00e3o os seus escolhidos, dos quatro ventos [\u2026]\u201d (Mt 24:31a). Dessa forma, na queda de Jerusal\u00e9m, o jubileu final (veja Lv 25) \u2014 a salva\u00e7\u00e3o eterna \u2014 ser\u00e1 declarada a todo o mundo. Agora que as restri\u00e7\u00f5es da antiga alian\u00e7a foram para sempre removidas, o mundo se torna o campo mission\u00e1rio da igreja.<\/p>\n<p style=\"text-align: justify;\">Certamente, Paulo de maneira prof\u00e9tica associa o sucesso final da miss\u00e3o aos gentis com a \u201cqueda\u201d de Israel, ou seja, seu trope\u00e7o sobre Cristo e a consequente destrui\u00e7\u00e3o do ano 70. Pois sua queda \u00e9 \u201criqueza para o mundo\u201d e seu fracasso \u00e9 \u201criqueza para os gentios\u201d (Rm 11:12). Na verdade, \u201co fato de terem sido eles rejeitados trouxe reconcilia\u00e7\u00e3o ao mundo\u201d (Rm 15:11a).<\/p>\n<h3 style=\"text-align: justify;\"><strong>Nos confronta com Sua severidade<\/strong><\/h3>\n<p style=\"text-align: justify;\">O ano 70 enfatiza a realidade n\u00e3o apenas da bondade de Deus, tamb\u00e9m destaca a Sua severidade. Paulo adverte aqueles que se autodenominam povo de Deus: \u201cConsiderai, pois, a bondade e a severidade de Deus: para com os que ca\u00edram, severidade; mas, para contigo, a bondade de Deus, se nela permaneceres; doutra sorte tamb\u00e9m tu ser\u00e1s cortado\u201d (Rm 11:22).<\/p>\n<p style=\"text-align: justify;\">A severidade que cai sobre os judeus no ano 70 exibe o julgamento divino sobre a incredulidade e a rebeli\u00e3o. Embora Israel tivesse uma heran\u00e7a gloriosa (Rm 9:3-5), embora sua raiz fosse santa (Rm 11:16), ilustra tragicamente as consequ\u00eancias em falhar em uma responsabilidade santa. Todos n\u00f3s devemos aprender a li\u00e7\u00e3o ali exposta, \u201c[\u2026] \u00e0quele a quem muito foi dado, muito lhe ser\u00e1 exigido\u201d (Lc 12:48b). O julgamento de Israel no ano 70 ressalta a sublime responsabilidade que resulta do chamado divino. No entanto, \u00e0 medida que Israel seca sob o calor abrasador da severa ira divina, os gentios florescem nas \u00e1guas frescas da boa miseric\u00f3rdia de Deus (Rm 11:12, 15; At 13:46-47). Tal \u00e9 a bondade de Deus. Entretanto, os gentios tamb\u00e9m devem levar a li\u00e7\u00e3o a s\u00e9rio: \u201cPorque, se Deus n\u00e3o poupou os ramos naturais, tamb\u00e9m n\u00e3o te poupar\u00e1\u201d (Rm 11:21).<\/p>\n<p style=\"text-align: justify;\">O \u201cfantasma\u201d do ano 70 persegue o registro do Novo Testamento (ao ser profetizado de forma frequente e vigorosa). Sua ocorr\u00eancia impacta dramaticamente a hist\u00f3ria do primeiro s\u00e9culo (sendo um dos seus eventos mais dat\u00e1veis e catastr\u00f3ficos). O ano 70 confirma importantes verdades hist\u00f3ricas da reden\u00e7\u00e3o (ainda confirma a suprema autoridade de Cristo, o t\u00e9rmino da economia da antiga alian\u00e7a, a natureza abrangente do evangelho e o julgamento de Israel) e nos transmite li\u00e7\u00f5es pr\u00e1ticas e significantes (nosso elevado chamado implica obriga\u00e7\u00f5es santas). Far\u00edamos bem em aprender sobre os caminhos de Deus entre os homens.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Aprofunde seu conhecimento sobre Hist\u00f3ria da Igreja por meio dos excelentes livros da Editora Fiel &#8211; <a href=\"https:\/\/www.editorafiel.com.br\/historia-da-igreja\">CLIQUE AQUI<\/a>.<\/p>\n<p>[\/vc_column_text][vc_message color=&#8221;alert-danger&#8221; message_box_style=&#8221;outline&#8221; style=&#8221;square&#8221; message_box_color=&#8221;alert-danger&#8221; icon_type=&#8221;pixelicons&#8221; css=&#8221;&#8221; el_class=&#8221;creditos_box&#8221; icon_pixelicons=&#8221;vc_pixel_icon vc_pixel_icon-explanation&#8221;]Por: Kenneth L. Gentry Jr. \u00a9 Ligonier Ministries. Website: <a href=\"http:\/\/www.ligonier.org\/\" target=\"_blank\" rel=\"noopener\">ligonier.org<\/a>. Traduzido com permiss\u00e3o. Fonte: <a href=\"https:\/\/pt.ligonier.org\/artigos\/como-o-relampago-sai-do-oriente\/\"><strong><em>Como o rel\u00e2mpago sai do oriente<\/em><\/strong><\/a> | <span style=\"font-weight: 400;\">Traduzido por <\/span><span style=\"font-weight: 400;\">Jo\u00e3o Costa. <\/span><span style=\"font-weight: 400;\">Revis\u00e3o por Renata Gandolfo<\/span><span style=\"font-weight: 400;\">. <\/span><span style=\"font-weight: 400;\">Editor: <em>Vinicius Lima<\/em>.<\/span>[\/vc_message][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>O mundo em que Cristo veio, e no qual o Seu evangelho espalhou-se, foi preparado de antem\u00e3o por Aquele que ergue e faz cair as na\u00e7\u00f5es de acordo com Sua boa vontade.<\/p>\n","protected":false},"author":1101,"featured_media":70905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[507],"tags":[480,3924],"class_list":["post-70899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-da-igreja","tag-ligonier","tag-reflexoes-a-historia-da-igreja-no-seculo-i","tema-historia-da-igreja","categoria-artigo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado<\/title>\n<meta name=\"description\" content=\"O mundo em que Cristo veio, e no qual o Seu evangelho espalhou-se, foi preparado de antem\u00e3o por Aquele que ergue e faz cair as na\u00e7\u00f5es de acordo com Sua boa vontade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado\" \/>\n<meta property=\"og:description\" content=\"O mundo em que Cristo veio, e no qual o Seu evangelho espalhou-se, foi preparado de antem\u00e3o por Aquele que ergue e faz cair as na\u00e7\u00f5es de acordo com Sua boa vontade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/\" \/>\n<meta property=\"og:site_name\" content=\"Voltemos Ao Evangelho\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/voltemosaoevangelho\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-25T11:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/nnjn.png?fit=837%2C470&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kenneth L. Gentry Jr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voltemos\" \/>\n<meta name=\"twitter:site\" content=\"@voltemos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kenneth L. Gentry Jr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/\"},\"author\":{\"name\":\"Kenneth L. Gentry Jr\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/6f7dcf9e281f54f971b992e39ae66b4c\"},\"headline\":\"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado\",\"datePublished\":\"2025-03-25T11:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/\"},\"wordCount\":1369,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/nnjn.png?fit=837%2C470&ssl=1\",\"keywords\":[\"Minist\u00e9rio Ligonier\",\"Reflex\u00f5es sobre a Hist\u00f3ria da Igreja no s\u00e9culo I\"],\"articleSection\":[\"Hist\u00f3ria da Igreja\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/\",\"name\":\"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/nnjn.png?fit=837%2C470&ssl=1\",\"datePublished\":\"2025-03-25T11:00:10+00:00\",\"description\":\"O mundo em que Cristo veio, e no qual o Seu evangelho espalhou-se, foi preparado de antem\u00e3o por Aquele que ergue e faz cair as na\u00e7\u00f5es de acordo com Sua boa vontade.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/nnjn.png?fit=837%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/nnjn.png?fit=837%2C470&ssl=1\",\"width\":837,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/2025\\\/03\\\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"name\":\"Voltemos Ao Evangelho\",\"description\":\"um site crist\u00e3o por Cristo e pelo Evangelho\",\"publisher\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#organization\",\"name\":\"Voltemos ao Evangelho\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/ve-cr.png?fit=644%2C805&ssl=1\",\"width\":644,\"height\":805,\"caption\":\"Voltemos ao Evangelho\"},\"image\":{\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/voltemosaoevangelho\",\"https:\\\/\\\/x.com\\\/voltemos\",\"https:\\\/\\\/www.instagram.com\\\/vevangelho\\\/\",\"https:\\\/\\\/pinterest.com\\\/voltemos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VoltemosAoEvangelho\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/#\\\/schema\\\/person\\\/6f7dcf9e281f54f971b992e39ae66b4c\",\"name\":\"Kenneth L. Gentry Jr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-61-XYNkMJ3L._SX300_CR00300300_-96x96.jpg\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-61-XYNkMJ3L._SX300_CR00300300_-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-61-XYNkMJ3L._SX300_CR00300300_-96x96.jpg\",\"caption\":\"Kenneth L. Gentry Jr\"},\"description\":\"Kenneth L. Gentry, Jr., Th.D. \u00e9 um ministro presbiteriano aposentado, autor de v\u00e1rios livros sobre teologia e estudos b\u00edblicos, e um palestrante de confer\u00eancias que falou por toda a Am\u00e9rica, no Caribe e na Austr\u00e1lia. Ele \u00e9 um crist\u00e3o conservador, evang\u00e9lico e reformado. Ele \u00e9 bacharel pela Tennessee Temple University (Estudos B\u00edblicos); mestre em Div. pelo Reformed Theological Seminary (Minist\u00e9rio Pastoral); e doutor em Th.M. e Th.D. pelo Whitefield Theological Seminary (Novo Testamento). Ele \u00e9 casado (desde 1971) e tem tr\u00eas filhos casados \u200b\u200b(e seis netos).\",\"url\":\"https:\\\/\\\/voltemosaoevangelho.com\\\/blog\\\/autor\\\/kenneth-l-gentry-jr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado","description":"O mundo em que Cristo veio, e no qual o Seu evangelho espalhou-se, foi preparado de antem\u00e3o por Aquele que ergue e faz cair as na\u00e7\u00f5es de acordo com Sua boa vontade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/","og_locale":"pt_BR","og_type":"article","og_title":"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado","og_description":"O mundo em que Cristo veio, e no qual o Seu evangelho espalhou-se, foi preparado de antem\u00e3o por Aquele que ergue e faz cair as na\u00e7\u00f5es de acordo com Sua boa vontade.","og_url":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/","og_site_name":"Voltemos Ao Evangelho","article_publisher":"https:\/\/facebook.com\/voltemosaoevangelho","article_published_time":"2025-03-25T11:00:10+00:00","og_image":[{"width":837,"height":470,"url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/nnjn.png?fit=837%2C470&ssl=1","type":"image\/png"}],"author":"Kenneth L. Gentry Jr","twitter_card":"summary_large_image","twitter_creator":"@voltemos","twitter_site":"@voltemos","twitter_misc":{"Escrito por":"Kenneth L. Gentry Jr","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/#article","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/"},"author":{"name":"Kenneth L. Gentry Jr","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/6f7dcf9e281f54f971b992e39ae66b4c"},"headline":"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado","datePublished":"2025-03-25T11:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/"},"wordCount":1369,"commentCount":0,"publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/nnjn.png?fit=837%2C470&ssl=1","keywords":["Minist\u00e9rio Ligonier","Reflex\u00f5es sobre a Hist\u00f3ria da Igreja no s\u00e9culo I"],"articleSection":["Hist\u00f3ria da Igreja"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/","url":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/","name":"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado","isPartOf":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/#primaryimage"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/nnjn.png?fit=837%2C470&ssl=1","datePublished":"2025-03-25T11:00:10+00:00","description":"O mundo em que Cristo veio, e no qual o Seu evangelho espalhou-se, foi preparado de antem\u00e3o por Aquele que ergue e faz cair as na\u00e7\u00f5es de acordo com Sua boa vontade.","breadcrumb":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/#primaryimage","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/nnjn.png?fit=837%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/nnjn.png?fit=837%2C470&ssl=1","width":837,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/voltemosaoevangelho.com\/blog\/2025\/03\/a-destruicao-de-jerusalem-em-70-d-c-e-seu-significado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/voltemosaoevangelho.com\/blog\/"},{"@type":"ListItem","position":2,"name":"A destrui\u00e7\u00e3o de Jerusal\u00e9m em 70 d.C e seu significado"}]},{"@type":"WebSite","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#website","url":"https:\/\/voltemosaoevangelho.com\/blog\/","name":"Voltemos Ao Evangelho","description":"um site crist\u00e3o por Cristo e pelo Evangelho","publisher":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voltemosaoevangelho.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#organization","name":"Voltemos ao Evangelho","url":"https:\/\/voltemosaoevangelho.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","contentUrl":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2015\/04\/ve-cr.png?fit=644%2C805&ssl=1","width":644,"height":805,"caption":"Voltemos ao Evangelho"},"image":{"@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/voltemosaoevangelho","https:\/\/x.com\/voltemos","https:\/\/www.instagram.com\/vevangelho\/","https:\/\/pinterest.com\/voltemos\/","https:\/\/www.youtube.com\/user\/VoltemosAoEvangelho"]},{"@type":"Person","@id":"https:\/\/voltemosaoevangelho.com\/blog\/#\/schema\/person\/6f7dcf9e281f54f971b992e39ae66b4c","name":"Kenneth L. Gentry Jr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/cropped-61-XYNkMJ3L._SX300_CR00300300_-96x96.jpg","url":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/cropped-61-XYNkMJ3L._SX300_CR00300300_-96x96.jpg","contentUrl":"https:\/\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/cropped-61-XYNkMJ3L._SX300_CR00300300_-96x96.jpg","caption":"Kenneth L. Gentry Jr"},"description":"Kenneth L. Gentry, Jr., Th.D. \u00e9 um ministro presbiteriano aposentado, autor de v\u00e1rios livros sobre teologia e estudos b\u00edblicos, e um palestrante de confer\u00eancias que falou por toda a Am\u00e9rica, no Caribe e na Austr\u00e1lia. Ele \u00e9 um crist\u00e3o conservador, evang\u00e9lico e reformado. Ele \u00e9 bacharel pela Tennessee Temple University (Estudos B\u00edblicos); mestre em Div. pelo Reformed Theological Seminary (Minist\u00e9rio Pastoral); e doutor em Th.M. e Th.D. pelo Whitefield Theological Seminary (Novo Testamento). Ele \u00e9 casado (desde 1971) e tem tr\u00eas filhos casados \u200b\u200b(e seis netos).","url":"https:\/\/voltemosaoevangelho.com\/blog\/autor\/kenneth-l-gentry-jr\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4MFiq-irx","jetpack_featured_media_url":"https:\/\/i0.wp.com\/voltemosaoevangelho.com\/blog\/wp-content\/uploads\/2025\/03\/nnjn.png?fit=837%2C470&ssl=1","_links":{"self":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/70899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/users\/1101"}],"replies":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/comments?post=70899"}],"version-history":[{"count":2,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/70899\/revisions"}],"predecessor-version":[{"id":70903,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/posts\/70899\/revisions\/70903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media\/70905"}],"wp:attachment":[{"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/media?parent=70899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/categories?post=70899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voltemosaoevangelho.com\/blog\/wp-json\/wp\/v2\/tags?post=70899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}